{"id":640848,"date":"2026-01-23T22:38:12","date_gmt":"2026-01-23T21:38:12","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=640848&#038;preview=true&#038;preview_id=640848"},"modified":"2026-01-23T23:03:37","modified_gmt":"2026-01-23T22:03:37","slug":"lasvel-chute-encore-en-euroligue-sous-la-folle-adresse-de-barcelone","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/lasvel-chute-encore-en-euroligue-sous-la-folle-adresse-de-barcelone\/","title":{"rendered":"L\u2019ASVEL chute encore en EuroLigue sous la folle adresse de Barcelone"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><strong>EUROLIGUE 2025\/2026 &#8211; Longtemps au contact de ses adversaires, l\u2019ASVEL a fini par chuter 98-91 sous la folle r\u00e9ussite des Barcelonais, notamment longue distance. Exercice dans lequel ils terminent \u00e0 12\/19 !<\/strong><\/em><\/p>\n<ul style=\"text-align: justify;\">\n<li><strong>\u00c0 lire aussi \u2013\u00a0<a href=\"https:\/\/dicodusport.fr\/blog\/classement-actualise-euroligue-masculine-2025-2026\/\">Classement actualis\u00e9 EuroLigue masculine 2025-2026<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Dommage pour l\u2019ASVEL qui a longtemps tenu t\u00eate aux Barcelonais avant de subir dans le dernier quart. Il n\u2019y avait pourtant pas grand-chose \u00e0 jeter dans les trois premiers. Mais les Barcelonais ont fait preuve d\u2019une incroyable r\u00e9ussite. De loin surtout, le cercle avait la taille d\u2019une bassine pour eux.<\/p>\n<h2 style=\"text-align: justify;\">L\u2019ASVEL tient la drag\u00e9e haute \u00e0 Barcelone<\/h2>\n<p style=\"text-align: justify;\">Lanc\u00e9 par <strong>Glynn Watson<\/strong>, tr\u00e8s vite dans son match avec 10 points en autant de minutes, les Villeurbannais ont suivi le mouvement. Ils ont fait preuve de beaucoup d\u2019agressivit\u00e9 pour s\u2019ouvrir les espaces vers le cercle et faire grimper le compteur. <strong>Braian<\/strong> <strong>Angola-Rodas<\/strong> a, de plus, sign\u00e9 une entr\u00e9e remarqu\u00e9e. \u00c0 passe pour le alley-oop d&rsquo;<strong>Eboua<\/strong>, <a href=\"https:\/\/dicodusport.fr\/blog\/encore-une-recrue-pour-lasvel-larriere-braian-angola-rodas-debarque-en-betclic-elite\/\">la nouvelle recrue<\/a>\u00a0a marqu\u00e9 des points. Efficace sur son 1<sup>er<\/sup> essai longue distance, il a ensuite distill\u00e9 un caviar \u00e0 <strong>Vautier<\/strong> sous le cercle, qui n\u2019avait plus qu\u2019\u00e0 conclure. La formation de <strong>Pierric Poupet<\/strong> a ainsi fait course en t\u00eate, port\u00e9e par une belle r\u00e9ussite.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">Braian Angola brilliant pass to Paul Eboua \ud83d\ude80 <a href=\"https:\/\/t.co\/oD8iYgNjTm\">pic.twitter.com\/oD8iYgNjTm<\/a><\/p>\n<p>\u2014 SKWEEK (@skweektv) <a href=\"https:\/\/twitter.com\/skweektv\/status\/2014796272754978822?ref_src=twsrc%5Etfw\">January 23, 2026<\/a><\/p><\/blockquote>\n<p style=\"text-align: justify;\"><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p style=\"text-align: justify;\">Seulement en face, le Bar\u00e7a n\u2019avait rien \u00e0 envier \u00e0 l\u2019adresse de leurs h\u00f4tes. <strong>Tornike Shengelia<\/strong> a facilement trouv\u00e9 ses marques poste bas, <strong>Satoransky<\/strong> a d\u00e9but\u00e9 avec un 2\/2 derri\u00e8re l\u2019arc et <strong>Kevin<\/strong> <strong>Punter<\/strong> a commenc\u00e9 \u00e0 r\u00e9pondre \u00e0 Glynn Watson. Jamais tr\u00e8s loin derri\u00e8re, parfois devant, les Espagnols ont r\u00e9alis\u00e9 eux aussi une premi\u00e8re p\u00e9riode empreinte d\u2019efficacit\u00e9 (16\/24 dont 5\/7 \u00e0 3 points). Le court avantage villeurbannais \u00e0 la pause se jouait sur les quelques chances suppl\u00e9mentaires r\u00e9cup\u00e9r\u00e9es aux rebonds offensifs. Mais la gagne \u00e9tait tr\u00e8s loin d\u2019\u00eatre act\u00e9e.<\/p>\n<h2 style=\"text-align: justify;\">Le Bar\u00e7a trop fort<\/h2>\n<p style=\"text-align: justify;\"><strong>Tornike Shengelia<\/strong> a repris son travail de sape dans le 3<sup>\u00e8me<\/sup> quart. Avec 8 points de rang, la tour de contr\u00f4le g\u00e9orgienne a plac\u00e9 Barcelone aux commandes. Heureusement, dans la tourmente ces derniers mois sur son tir \u00e0 3 points, <strong>Seljaas Zachary<\/strong> a retrouv\u00e9 un brin de r\u00e9ussite au bon moment pour \u00e9viter un trop gros \u00e9clat. Un tir prim\u00e9 aussit\u00f4t rendu par <strong>Punter<\/strong>, qui pris feu en inscrivant 11 points en 3 minutes, dont un 3\/3 longue distance qui a \u00e9loign\u00e9 l\u2019ASVEL de 8 longueurs (60-68). Cette derni\u00e8re n\u2019a rien l\u00e2ch\u00e9, trouvant quelques r\u00e9ponses par l\u2019interm\u00e9diaire d\u2019<strong>Ajinca<\/strong> et <strong>Vautier<\/strong> pour grignoter de moiti\u00e9 l\u2019\u00e9cart et ainsi rester au contact malgr\u00e9 l\u2019insolente adresse \u00e0 3 points des visiteurs \u00e0 cet instant (10\/17). Une folle r\u00e9ussite qui s\u2019est poursuivie.<\/p>\n<p style=\"text-align: justify;\">Revenus maintes fois \u00e0 deux petits points, les Villeurbannais ont eu les occasions pour reprendre le lead. Mais elles \u00e9taient toutes entach\u00e9es d\u2019une perte de balle suivie d\u2019une fl\u00e8che barcelonaise, \u00e0 l\u2019image du 3 points de <strong>Shengelia<\/strong> (22 points), encore lui, \u00e0 7 minutes du terme (76-81). Celui de <strong>Punter<\/strong> (30 points) dans la foul\u00e9e a mis un coup suppl\u00e9mentaire derri\u00e8re la t\u00eate de l\u2019ASVEL. Malgr\u00e9 les 23 unit\u00e9s de Glynn Watson et une partition collective globalement s\u00e9rieuse, l\u2019ASVEL doit composer avec une 18<sup>\u00e8me<\/sup> d\u00e9faite cette saison. Le Bar\u00e7a \u00e9tait tout simplement trop fort. Et trop adroit (34\/51 dont 12\/19 \u00e0 3 points).<\/p>\n<div id=\"gtx-trans\" style=\"position: absolute; left: -14px; top: 40.9091px;\">\n<div class=\"gtx-trans-icon\" style=\"text-align: justify;\"><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>EUROLIGUE 2025\/2026 &#8211; Longtemps au contact de ses adversaires, l\u2019ASVEL a fini par chuter 98-91 sous la folle r\u00e9ussite des Barcelonais, notamment longue distance (12\/19).<\/p>\n","protected":false},"author":18,"featured_media":640865,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[47001],"tags":[7864,16878,181],"class_list":["post-640848","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-euroligue","tag-asvel","tag-breve","tag-euroligue"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>L\u2019ASVEL chute encore en EuroLigue sous la folle adresse de Barcelone<\/title>\n<meta name=\"description\" content=\"EUROLIGUE 2025\/2026 - Longtemps au contact de ses adversaires, l\u2019ASVEL a fini par chuter 98-91 sous la folle r\u00e9ussite des Barcelonais.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/lasvel-chute-encore-en-euroligue-sous-la-folle-adresse-de-barcelone\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L\u2019ASVEL chute encore en EuroLigue sous la folle adresse de Barcelone\" \/>\n<meta property=\"og:description\" content=\"EUROLIGUE 2025\/2026 - Longtemps au contact de ses adversaires, l\u2019ASVEL a fini par chuter 98-91 sous la folle r\u00e9ussite des Barcelonais.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/lasvel-chute-encore-en-euroligue-sous-la-folle-adresse-de-barcelone\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/soocube\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-23T21:38:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-23T22:03:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/01\/LASVEL-chute-encore-en-EuroLigue-sous-la-folle-adresse-de-Barcelone.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Sophie Clapier\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"L\u2019ASVEL chute encore en EuroLigue sous la folle adresse de Barcelone\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/soocube\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/lasvel-chute-encore-en-euroligue-sous-la-folle-adresse-de-barcelone\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/lasvel-chute-encore-en-euroligue-sous-la-folle-adresse-de-barcelone\/\"},\"author\":{\"name\":\"Sophie Clapier\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/416c975648aca9da8839bdfe333a21c9\"},\"headline\":\"L\u2019ASVEL chute encore en EuroLigue sous la folle adresse de Barcelone\",\"datePublished\":\"2026-01-23T21:38:12+00:00\",\"dateModified\":\"2026-01-23T22:03:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/lasvel-chute-encore-en-euroligue-sous-la-folle-adresse-de-barcelone\/\"},\"wordCount\":581,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/lasvel-chute-encore-en-euroligue-sous-la-folle-adresse-de-barcelone\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/01\/LASVEL-chute-encore-en-EuroLigue-sous-la-folle-adresse-de-Barcelone.png\",\"keywords\":[\"ASVEL\",\"br\u00e8ve\",\"Euroligue\"],\"articleSection\":[\"EuroLigue\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/lasvel-chute-encore-en-euroligue-sous-la-folle-adresse-de-barcelone\/#respond\"]}],\"copyrightYear\":\"2026\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/lasvel-chute-encore-en-euroligue-sous-la-folle-adresse-de-barcelone\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/lasvel-chute-encore-en-euroligue-sous-la-folle-adresse-de-barcelone\/\",\"name\":\"L\u2019ASVEL chute encore en EuroLigue sous la folle adresse de Barcelone\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/lasvel-chute-encore-en-euroligue-sous-la-folle-adresse-de-barcelone\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/lasvel-chute-encore-en-euroligue-sous-la-folle-adresse-de-barcelone\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/01\/LASVEL-chute-encore-en-EuroLigue-sous-la-folle-adresse-de-Barcelone.png\",\"datePublished\":\"2026-01-23T21:38:12+00:00\",\"dateModified\":\"2026-01-23T22:03:37+00:00\",\"description\":\"EUROLIGUE 2025\/2026 - Longtemps au contact de ses adversaires, l\u2019ASVEL a fini par chuter 98-91 sous la folle r\u00e9ussite des Barcelonais.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/lasvel-chute-encore-en-euroligue-sous-la-folle-adresse-de-barcelone\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/lasvel-chute-encore-en-euroligue-sous-la-folle-adresse-de-barcelone\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/lasvel-chute-encore-en-euroligue-sous-la-folle-adresse-de-barcelone\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/01\/LASVEL-chute-encore-en-EuroLigue-sous-la-folle-adresse-de-Barcelone.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/01\/LASVEL-chute-encore-en-EuroLigue-sous-la-folle-adresse-de-Barcelone.png\",\"width\":1200,\"height\":674,\"caption\":\"L\u2019ASVEL chute encore en EuroLigue sous la folle adresse de Barcelone\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/lasvel-chute-encore-en-euroligue-sous-la-folle-adresse-de-barcelone\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L\u2019ASVEL chute encore en EuroLigue sous la folle adresse de Barcelone\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/416c975648aca9da8839bdfe333a21c9\",\"name\":\"Sophie Clapier\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Sophie-Clapier-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Sophie-Clapier-150x150.jpg\",\"caption\":\"Sophie Clapier\"},\"description\":\"Journaliste\/r\u00e9dactrice depuis janvier 2016 - Passionn\u00e9e de sport depuis toujours, j\u2019en ai pratiqu\u00e9 quelques-uns. Judo, football, handball ou encore tennis, je n\u2019ai jamais pu me mettre d\u2019accord sur un en particulier. Mais \u00e7a, c\u2019\u00e9tait avant de d\u00e9couvrir le basket, devenu mon sport de pr\u00e9dilection. Les actions NBA, le All-Star Week-end, la fureur des Game 7 pendant les playoffs ou mieux, lors des Finals, this is why we play. Team Spurs T.P, je m\u2019accroche encore \u00e0 Gregg Popovich (don\u2019t leave !). Team chef Curry, je souhaite qu\u2019il finisse aux Warriors (staaaay !). Non, il n\u2019y a pas qu\u2019eux, des petits nouveaux -et des petites nouvelles \u00e9videmment- arrivent chaque jour dans toutes les disciplines et cr\u00e9ent de nouveaux exploits. Alors pour les grands \u00e9v\u00e9nements et comp\u00e9titions internationales, vive les pulsations 240\/minutes et le d\u00e9fibrillateur pas loin, et allez les Bleu(e)s ! C\u2019est s\u00fbr, j\u2019aurai plus vu ma vie sur un terrain de sport, mais \u00e0 d\u00e9faut d\u2019en faire en haut niveau, je le partage avec vous.\",\"sameAs\":[\"https:\/\/www.facebook.com\/soocube\",\"https:\/\/x.com\/https:\/\/twitter.com\/soocube\",\"admin\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/sophie\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"L\u2019ASVEL chute encore en EuroLigue sous la folle adresse de Barcelone","description":"EUROLIGUE 2025\/2026 - Longtemps au contact de ses adversaires, l\u2019ASVEL a fini par chuter 98-91 sous la folle r\u00e9ussite des Barcelonais.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/lasvel-chute-encore-en-euroligue-sous-la-folle-adresse-de-barcelone\/","og_locale":"fr_FR","og_type":"article","og_title":"L\u2019ASVEL chute encore en EuroLigue sous la folle adresse de Barcelone","og_description":"EUROLIGUE 2025\/2026 - Longtemps au contact de ses adversaires, l\u2019ASVEL a fini par chuter 98-91 sous la folle r\u00e9ussite des Barcelonais.","og_url":"https:\/\/dicodusport.fr\/blog\/lasvel-chute-encore-en-euroligue-sous-la-folle-adresse-de-barcelone\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/soocube","article_published_time":"2026-01-23T21:38:12+00:00","article_modified_time":"2026-01-23T22:03:37+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/01\/LASVEL-chute-encore-en-EuroLigue-sous-la-folle-adresse-de-Barcelone.png","type":"image\/png"}],"author":"Sophie Clapier","twitter_card":"summary_large_image","twitter_title":"L\u2019ASVEL chute encore en EuroLigue sous la folle adresse de Barcelone","twitter_creator":"@https:\/\/twitter.com\/soocube","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/lasvel-chute-encore-en-euroligue-sous-la-folle-adresse-de-barcelone\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/lasvel-chute-encore-en-euroligue-sous-la-folle-adresse-de-barcelone\/"},"author":{"name":"Sophie Clapier","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/416c975648aca9da8839bdfe333a21c9"},"headline":"L\u2019ASVEL chute encore en EuroLigue sous la folle adresse de Barcelone","datePublished":"2026-01-23T21:38:12+00:00","dateModified":"2026-01-23T22:03:37+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/lasvel-chute-encore-en-euroligue-sous-la-folle-adresse-de-barcelone\/"},"wordCount":581,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/lasvel-chute-encore-en-euroligue-sous-la-folle-adresse-de-barcelone\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/01\/LASVEL-chute-encore-en-EuroLigue-sous-la-folle-adresse-de-Barcelone.png","keywords":["ASVEL","br\u00e8ve","Euroligue"],"articleSection":["EuroLigue"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/lasvel-chute-encore-en-euroligue-sous-la-folle-adresse-de-barcelone\/#respond"]}],"copyrightYear":"2026","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/lasvel-chute-encore-en-euroligue-sous-la-folle-adresse-de-barcelone\/","url":"https:\/\/dicodusport.fr\/blog\/lasvel-chute-encore-en-euroligue-sous-la-folle-adresse-de-barcelone\/","name":"L\u2019ASVEL chute encore en EuroLigue sous la folle adresse de Barcelone","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/lasvel-chute-encore-en-euroligue-sous-la-folle-adresse-de-barcelone\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/lasvel-chute-encore-en-euroligue-sous-la-folle-adresse-de-barcelone\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/01\/LASVEL-chute-encore-en-EuroLigue-sous-la-folle-adresse-de-Barcelone.png","datePublished":"2026-01-23T21:38:12+00:00","dateModified":"2026-01-23T22:03:37+00:00","description":"EUROLIGUE 2025\/2026 - Longtemps au contact de ses adversaires, l\u2019ASVEL a fini par chuter 98-91 sous la folle r\u00e9ussite des Barcelonais.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/lasvel-chute-encore-en-euroligue-sous-la-folle-adresse-de-barcelone\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/lasvel-chute-encore-en-euroligue-sous-la-folle-adresse-de-barcelone\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/lasvel-chute-encore-en-euroligue-sous-la-folle-adresse-de-barcelone\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/01\/LASVEL-chute-encore-en-EuroLigue-sous-la-folle-adresse-de-Barcelone.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/01\/LASVEL-chute-encore-en-EuroLigue-sous-la-folle-adresse-de-Barcelone.png","width":1200,"height":674,"caption":"L\u2019ASVEL chute encore en EuroLigue sous la folle adresse de Barcelone"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/lasvel-chute-encore-en-euroligue-sous-la-folle-adresse-de-barcelone\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"L\u2019ASVEL chute encore en EuroLigue sous la folle adresse de Barcelone"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/416c975648aca9da8839bdfe333a21c9","name":"Sophie Clapier","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Sophie-Clapier-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Sophie-Clapier-150x150.jpg","caption":"Sophie Clapier"},"description":"Journaliste\/r\u00e9dactrice depuis janvier 2016 - Passionn\u00e9e de sport depuis toujours, j\u2019en ai pratiqu\u00e9 quelques-uns. Judo, football, handball ou encore tennis, je n\u2019ai jamais pu me mettre d\u2019accord sur un en particulier. Mais \u00e7a, c\u2019\u00e9tait avant de d\u00e9couvrir le basket, devenu mon sport de pr\u00e9dilection. Les actions NBA, le All-Star Week-end, la fureur des Game 7 pendant les playoffs ou mieux, lors des Finals, this is why we play. Team Spurs T.P, je m\u2019accroche encore \u00e0 Gregg Popovich (don\u2019t leave !). Team chef Curry, je souhaite qu\u2019il finisse aux Warriors (staaaay !). Non, il n\u2019y a pas qu\u2019eux, des petits nouveaux -et des petites nouvelles \u00e9videmment- arrivent chaque jour dans toutes les disciplines et cr\u00e9ent de nouveaux exploits. Alors pour les grands \u00e9v\u00e9nements et comp\u00e9titions internationales, vive les pulsations 240\/minutes et le d\u00e9fibrillateur pas loin, et allez les Bleu(e)s ! C\u2019est s\u00fbr, j\u2019aurai plus vu ma vie sur un terrain de sport, mais \u00e0 d\u00e9faut d\u2019en faire en haut niveau, je le partage avec vous.","sameAs":["https:\/\/www.facebook.com\/soocube","https:\/\/x.com\/https:\/\/twitter.com\/soocube","admin"],"url":"https:\/\/dicodusport.fr\/blog\/author\/sophie\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/640848","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=640848"}],"version-history":[{"count":5,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/640848\/revisions"}],"predecessor-version":[{"id":640884,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/640848\/revisions\/640884"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/640865"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=640848"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=640848"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=640848"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}