{"id":644989,"date":"2026-02-07T16:11:39","date_gmt":"2026-02-07T15:11:39","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=644989&#038;preview=true&#038;preview_id=644989"},"modified":"2026-02-07T16:26:22","modified_gmt":"2026-02-07T15:26:22","slug":"matias-roche-et-timothe-sivignon-ratent-la-qualification-pour-la-finale-du-ski-slopestyle-aux-jo-2026","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/matias-roche-et-timothe-sivignon-ratent-la-qualification-pour-la-finale-du-ski-slopestyle-aux-jo-2026\/","title":{"rendered":"Matias Roche et Timoth\u00e9 Sivignon ratent la qualification pour la finale du ski slopestyle aux JO 2026"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>SKI FREESTYLE JO 2026 &#8211; Sans surprise, Matias Roche et Timoth\u00e9 Sivignon ont pris la porte d\u00e8s les qualifications en ski slopestyle.<\/em><\/strong><\/p>\n<ul style=\"text-align: justify;\">\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet \u2013\u00a0<a href=\"https:\/\/dicodusport.fr\/blog\/calendrier-jo-dhiver-2026-programme-complet-des-epreuves-jour-par-jour-milan-cortina\/\">Calendrier JO d\u2019hiver 2026 : programme complet des \u00e9preuves, jour par jour (Milan-Cortina)<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Quelques heures apr\u00e8s l&rsquo;\u00e9limination de <strong>Kim Dumont Zanella<\/strong>, le <strong>ski freestyle<\/strong> fran\u00e7ais comptait sur <strong>Matias Roche<\/strong> et <strong>Timoth\u00e9 Sivignon<\/strong> pour tenter de se frayer un chemin en finale du <strong>slopestyle<\/strong>. Pour les deux jeunes Tricolores, davantage habitu\u00e9s \u00e0 performer en big air, sortir des qualifications repr\u00e9sentait d\u00e9j\u00e0 une v\u00e9ritable montagne.<\/p>\n<div class=\"vlp-link-container vlp-layout-article\"><a href=\"https:\/\/dicodusport.fr\/blog\/kim-dumont-zanella-se-rate-deux-fois-et-nira-pas-en-finale-du-ski-slopestyle-aux-jo-2026\/\" class=\"vlp-link\" title=\"Kim Dumont Zanella se rate deux fois et n&#039;ira pas en finale du ski slopestyle aux JO 2026\"><\/a><div class=\"vlp-layout-zone-side\"><div class=\"vlp-block-4 vlp-link-image\"><img loading=\"lazy\" decoding=\"async\" style=\"max-width: 792px;\" width=\"792\" height=\"445\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/02\/Kim-Dumont-Zanella-se-rate-deux-fois-et-nira-pas-en-finale-du-ski-slopestyle-aux-JO-2026.png\" class=\"attachment-800x445 size-800x445\" alt=\"Kim Dumont Zanella se rate deux fois et n&#039;ira pas en finale du ski slopestyle aux JO 2026\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/02\/Kim-Dumont-Zanella-se-rate-deux-fois-et-nira-pas-en-finale-du-ski-slopestyle-aux-JO-2026.png 1200w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/02\/Kim-Dumont-Zanella-se-rate-deux-fois-et-nira-pas-en-finale-du-ski-slopestyle-aux-JO-2026-300x169.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/02\/Kim-Dumont-Zanella-se-rate-deux-fois-et-nira-pas-en-finale-du-ski-slopestyle-aux-JO-2026-1024x575.png 1024w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/02\/Kim-Dumont-Zanella-se-rate-deux-fois-et-nira-pas-en-finale-du-ski-slopestyle-aux-JO-2026-768x431.png 768w\" sizes=\"auto, (max-width: 792px) 100vw, 792px\" \/><\/div><\/div><div class=\"vlp-layout-zone-main\"><div class=\"vlp-block-0 vlp-link-title\">Kim Dumont Zanella se rate deux fois et n'ira pas en finale du ski slopestyle aux JO 2026<\/div><div class=\"vlp-block-1 vlp-link-summary\">SKI FREESTYLE JO 2026 - La Fran\u00e7aise Kim Dumont Zanella a chut\u00e9 par deux fois et est \u00e9limin\u00e9e d\u00e8s les qualifications du slopestyle.<\/div><div class=\"vlp-block-2 vlp-link-button\">Lire l'article<\/div><div class=\"vlp-block-3 vlp-link-url\">dicodusport.fr<\/div><\/div><\/div>\n<h2 style=\"text-align: justify;\">Matias Roche et Timoth\u00e9 Sivignon restent \u00e0 quai<\/h2>\n<p style=\"text-align: justify;\">Sans r\u00e9elle surprise, les deux Fran\u00e7ais n&rsquo;ont pas r\u00e9ussi \u00e0 franchir cet \u00e9norme cap. Pourtant, \u00e0 l&rsquo;issue des premiers runs, <strong>Matias Roche<\/strong> avait su tirer son \u00e9pingle du jeu pour se positionner aux portes du Top 12. Auteur de tricks propres avec une belle amplitude, il a en revanche pay\u00e9 sa rigidit\u00e9 et sa timidit\u00e9 sur les rails, ce qui lui a valu une note de <strong>54.50<\/strong>. De son c\u00f4t\u00e9, <strong>Timoth\u00e9 Sivignon<\/strong> a connu beaucoup de d\u00e9chet, et les deux Tricolores savaient qu&rsquo;ils devaient tout tenter sur leur deuxi\u00e8me run.<\/p>\n<ul style=\"text-align: justify;\">\n<li><strong>\u00c0 lire aussi \u2013 <a href=\"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-jo-2026-classement-mis-a-jour-en-temps-reel\/\">Tableau des m\u00e9dailles JO 2026 : classement mis \u00e0 jour en temps r\u00e9el<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">De nouveau le premier des deux \u00e0 s&rsquo;\u00e9lancer, <strong>Roche<\/strong> a propos\u00e9 un run malheureusement similaire au premier. Beaucoup trop prudent sur les rails, cela l&rsquo;a emp\u00each\u00e9 de viser le Top 12 en d\u00e9pit de tricks parfaitement pos\u00e9s. Il a ainsi l\u00e9g\u00e8rement am\u00e9lior\u00e9 sa note (<strong>57.96<\/strong>) pour finalement se classer \u00e0 une honorable <strong>15<sup>e<\/sup> place<\/strong>. \u00c0 l&rsquo;inverse, Sivignon a rat\u00e9 une r\u00e9ception, une erreur fatale. Avec une <strong>note trop faible (38.93)<\/strong>, il \u00e9choue en fond de classement, au <strong>23<sup>e<\/sup> rang<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Les deux Fran\u00e7ais ne verront donc pas la finale. En revanche, ils seront attendus au tournant en fin de semaine prochaine en <strong>big air<\/strong>, o\u00f9 une qualification en finale constituera cette fois un objectif r\u00e9el et atteignable.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">\u2744\ufe0f <a href=\"https:\/\/twitter.com\/hashtag\/MilanoCortina2026?src=hash&amp;ref_src=twsrc%5Etfw\">#MilanoCortina2026<\/a> | \ud83c\uddeb\ud83c\uddf7 Matias Roche am\u00e9liore son score sur son deuxi\u00e8me run, mais cela ne sera pas suffisant pour aller en finale&#8230;<\/p>\n<p>\u27a1\ufe0f Suivez les JO sur la cha\u00eene sport de France T\u00e9l\u00e9visions : <a href=\"https:\/\/t.co\/2YyyGIAfdo\">https:\/\/t.co\/2YyyGIAfdo<\/a> <a href=\"https:\/\/t.co\/29hN4eERNC\">pic.twitter.com\/29hN4eERNC<\/a><br \/>\n\u2014 francetvsport (@francetvsport) <a href=\"https:\/\/twitter.com\/francetvsport\/status\/2020152276258595032?ref_src=twsrc%5Etfw\">February 7, 2026<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 style=\"text-align: justify;\">Les favoris au rendez-vous<\/h2>\n<p style=\"text-align: justify;\">Parmi les candidats \u00e0 l&rsquo;or, cette journ\u00e9e \u00e9tait risqu\u00e9e. L&rsquo;Am\u00e9ricain <strong>Marc Forehand<\/strong>, vainqueur en Coupe du monde cet hiver, mais aussi le Su\u00e9dois <strong>Jesper Tj\u00e4der<\/strong>, m\u00e9daill\u00e9 de bronze aux derniers Jeux Olympiques, en ont fait les frais en chutant lors de leur premier run. Une frayeur finalement sans cons\u00e9quence, puisque les deux pr\u00e9tendants \u00e0 une m\u00e9daille ont r\u00e9agi sur le deuxi\u00e8me passage afin de s\u00e9curiser leur qualification.<\/p>\n<p style=\"text-align: justify;\">\u00c0 l&rsquo;inverse, le Norv\u00e9gien <strong>Birk Ruud<\/strong>, le champion olympique sortant <strong>Alex Hall<\/strong>, ainsi que le dernier vainqueur des X Games <strong>Luca Harrington<\/strong>, ont assur\u00e9 leur place d\u00e8s le premier run en d\u00e9passant la barre des 70 points. Une note largement suffisante au vu de la notation globalement basse des juges. Avec <strong>81.75<\/strong>, <strong>Birk Ruud<\/strong> a m\u00eame remport\u00e9 ces qualifications devant son compatriote <strong>Tormod Frostad<\/strong>, en \u00e9tant le seul \u00e0 franchir la barre des 80.<\/p>\n<div id=\"gtx-trans\" style=\"position: absolute; left: -14px; top: 40.9091px;\">\n<div class=\"gtx-trans-icon\" style=\"text-align: justify;\"><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>SKI FREESTYLE JO 2026 &#8211; Sans surprise, Matias Roche et Timoth\u00e9 Sivignon ont pris la porte d\u00e8s les qualifications en ski slopestyle.<\/p>\n","protected":false},"author":55,"featured_media":645104,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[44003,9217],"tags":[32415,16878,46887,46888,47094,15570],"class_list":["post-644989","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-jo-hiver-2026","category-ski","tag-actu","tag-breve","tag-jeux-olympiques-2026","tag-jo-2026","tag-jo-dhiver","tag-ski-slopestyle"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Matias Roche et Timoth\u00e9 Sivignon ratent la qualification pour la finale du ski slopestyle aux JO 2026<\/title>\n<meta name=\"description\" content=\"SKI FREESTYLE JO 2026 - Sans surprise, Matias Roche et Timoth\u00e9 Sivignon ont pris la porte d\u00e8s les qualifications en ski slopestyle.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/matias-roche-et-timothe-sivignon-ratent-la-qualification-pour-la-finale-du-ski-slopestyle-aux-jo-2026\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Matias Roche et Timoth\u00e9 Sivignon ratent la qualification pour la finale du ski slopestyle aux JO 2026\" \/>\n<meta property=\"og:description\" content=\"SKI FREESTYLE JO 2026 - Sans surprise, Matias Roche et Timoth\u00e9 Sivignon ont pris la porte d\u00e8s les qualifications en ski slopestyle.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/matias-roche-et-timothe-sivignon-ratent-la-qualification-pour-la-finale-du-ski-slopestyle-aux-jo-2026\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-07T15:11:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-07T15:26:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/02\/Matias-Roche-et-Timothe-Sivignon-ratent-la-qualification-pour-la-finale-du-ski-slopestyle-aux-JO-2026.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Maxime Cazenave\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Matias Roche et Timoth\u00e9 Sivignon ratent la qualification pour la finale du ski slopestyle aux JO 2026\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Maxime_Caze\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/matias-roche-et-timothe-sivignon-ratent-la-qualification-pour-la-finale-du-ski-slopestyle-aux-jo-2026\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/matias-roche-et-timothe-sivignon-ratent-la-qualification-pour-la-finale-du-ski-slopestyle-aux-jo-2026\\\/\"},\"author\":{\"name\":\"Maxime Cazenave\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/37def232098a7a5cbab3974a3690abb0\"},\"headline\":\"Matias Roche et Timoth\u00e9 Sivignon ratent la qualification pour la finale du ski slopestyle aux JO 2026\",\"datePublished\":\"2026-02-07T15:11:39+00:00\",\"dateModified\":\"2026-02-07T15:26:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/matias-roche-et-timothe-sivignon-ratent-la-qualification-pour-la-finale-du-ski-slopestyle-aux-jo-2026\\\/\"},\"wordCount\":635,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/matias-roche-et-timothe-sivignon-ratent-la-qualification-pour-la-finale-du-ski-slopestyle-aux-jo-2026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Matias-Roche-et-Timothe-Sivignon-ratent-la-qualification-pour-la-finale-du-ski-slopestyle-aux-JO-2026.png\",\"keywords\":[\"actu\",\"br\u00e8ve\",\"Jeux Olympiques 2026\",\"JO 2026\",\"JO d'hiver\",\"Ski slopestyle\"],\"articleSection\":[\"JO d'hiver 2026\",\"Ski\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/matias-roche-et-timothe-sivignon-ratent-la-qualification-pour-la-finale-du-ski-slopestyle-aux-jo-2026\\\/#respond\"]}],\"copyrightYear\":\"2026\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/matias-roche-et-timothe-sivignon-ratent-la-qualification-pour-la-finale-du-ski-slopestyle-aux-jo-2026\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/matias-roche-et-timothe-sivignon-ratent-la-qualification-pour-la-finale-du-ski-slopestyle-aux-jo-2026\\\/\",\"name\":\"Matias Roche et Timoth\u00e9 Sivignon ratent la qualification pour la finale du ski slopestyle aux JO 2026\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/matias-roche-et-timothe-sivignon-ratent-la-qualification-pour-la-finale-du-ski-slopestyle-aux-jo-2026\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/matias-roche-et-timothe-sivignon-ratent-la-qualification-pour-la-finale-du-ski-slopestyle-aux-jo-2026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Matias-Roche-et-Timothe-Sivignon-ratent-la-qualification-pour-la-finale-du-ski-slopestyle-aux-JO-2026.png\",\"datePublished\":\"2026-02-07T15:11:39+00:00\",\"dateModified\":\"2026-02-07T15:26:22+00:00\",\"description\":\"SKI FREESTYLE JO 2026 - Sans surprise, Matias Roche et Timoth\u00e9 Sivignon ont pris la porte d\u00e8s les qualifications en ski slopestyle.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/matias-roche-et-timothe-sivignon-ratent-la-qualification-pour-la-finale-du-ski-slopestyle-aux-jo-2026\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/matias-roche-et-timothe-sivignon-ratent-la-qualification-pour-la-finale-du-ski-slopestyle-aux-jo-2026\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/matias-roche-et-timothe-sivignon-ratent-la-qualification-pour-la-finale-du-ski-slopestyle-aux-jo-2026\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Matias-Roche-et-Timothe-Sivignon-ratent-la-qualification-pour-la-finale-du-ski-slopestyle-aux-JO-2026.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Matias-Roche-et-Timothe-Sivignon-ratent-la-qualification-pour-la-finale-du-ski-slopestyle-aux-JO-2026.png\",\"width\":1200,\"height\":674,\"caption\":\"Matias Roche et Timoth\u00e9 Sivignon ratent la qualification pour la finale du ski slopestyle aux JO 2026\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/matias-roche-et-timothe-sivignon-ratent-la-qualification-pour-la-finale-du-ski-slopestyle-aux-jo-2026\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Matias Roche et Timoth\u00e9 Sivignon ratent la qualification pour la finale du ski slopestyle aux JO 2026\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/37def232098a7a5cbab3974a3690abb0\",\"name\":\"Maxime Cazenave\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Maxime-Cazenave-150x150.jpg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Maxime-Cazenave-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Maxime-Cazenave-150x150.jpg\",\"caption\":\"Maxime Cazenave\"},\"description\":\"Journaliste\\\/R\u00e9dacteur depuis 2012 - Berc\u00e9 par l\u2019amour des Girondins de Bordeaux, les \u00e9checs de Christophe Moreau sur le Tour de France sous l'\u00e8re Lance Armstrong et le fade-away l\u00e9tal de Dirk Nowitzki, ma passion d\u00e9vorante pour le sport a toujours \u00e9t\u00e9 un pan incontournable de ma vie. Transmettre ma passion \u00e0 l\u2019\u00e9crit a \u00e9t\u00e9 une transition naturelle. Suiveur assidu de basket et de hockey sur glace, je garde toujours un peu de place pour suivre le cyclisme, le football et le maximum de performances fran\u00e7aises.\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/Maxime_Caze\"],\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/maximec\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Matias Roche et Timoth\u00e9 Sivignon ratent la qualification pour la finale du ski slopestyle aux JO 2026","description":"SKI FREESTYLE JO 2026 - Sans surprise, Matias Roche et Timoth\u00e9 Sivignon ont pris la porte d\u00e8s les qualifications en ski slopestyle.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/matias-roche-et-timothe-sivignon-ratent-la-qualification-pour-la-finale-du-ski-slopestyle-aux-jo-2026\/","og_locale":"fr_FR","og_type":"article","og_title":"Matias Roche et Timoth\u00e9 Sivignon ratent la qualification pour la finale du ski slopestyle aux JO 2026","og_description":"SKI FREESTYLE JO 2026 - Sans surprise, Matias Roche et Timoth\u00e9 Sivignon ont pris la porte d\u00e8s les qualifications en ski slopestyle.","og_url":"https:\/\/dicodusport.fr\/blog\/matias-roche-et-timothe-sivignon-ratent-la-qualification-pour-la-finale-du-ski-slopestyle-aux-jo-2026\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2026-02-07T15:11:39+00:00","article_modified_time":"2026-02-07T15:26:22+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/02\/Matias-Roche-et-Timothe-Sivignon-ratent-la-qualification-pour-la-finale-du-ski-slopestyle-aux-JO-2026.png","type":"image\/png"}],"author":"Maxime Cazenave","twitter_card":"summary_large_image","twitter_title":"Matias Roche et Timoth\u00e9 Sivignon ratent la qualification pour la finale du ski slopestyle aux JO 2026","twitter_creator":"@https:\/\/twitter.com\/Maxime_Caze","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/matias-roche-et-timothe-sivignon-ratent-la-qualification-pour-la-finale-du-ski-slopestyle-aux-jo-2026\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/matias-roche-et-timothe-sivignon-ratent-la-qualification-pour-la-finale-du-ski-slopestyle-aux-jo-2026\/"},"author":{"name":"Maxime Cazenave","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0"},"headline":"Matias Roche et Timoth\u00e9 Sivignon ratent la qualification pour la finale du ski slopestyle aux JO 2026","datePublished":"2026-02-07T15:11:39+00:00","dateModified":"2026-02-07T15:26:22+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/matias-roche-et-timothe-sivignon-ratent-la-qualification-pour-la-finale-du-ski-slopestyle-aux-jo-2026\/"},"wordCount":635,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/matias-roche-et-timothe-sivignon-ratent-la-qualification-pour-la-finale-du-ski-slopestyle-aux-jo-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/02\/Matias-Roche-et-Timothe-Sivignon-ratent-la-qualification-pour-la-finale-du-ski-slopestyle-aux-JO-2026.png","keywords":["actu","br\u00e8ve","Jeux Olympiques 2026","JO 2026","JO d'hiver","Ski slopestyle"],"articleSection":["JO d'hiver 2026","Ski"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/matias-roche-et-timothe-sivignon-ratent-la-qualification-pour-la-finale-du-ski-slopestyle-aux-jo-2026\/#respond"]}],"copyrightYear":"2026","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/matias-roche-et-timothe-sivignon-ratent-la-qualification-pour-la-finale-du-ski-slopestyle-aux-jo-2026\/","url":"https:\/\/dicodusport.fr\/blog\/matias-roche-et-timothe-sivignon-ratent-la-qualification-pour-la-finale-du-ski-slopestyle-aux-jo-2026\/","name":"Matias Roche et Timoth\u00e9 Sivignon ratent la qualification pour la finale du ski slopestyle aux JO 2026","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/matias-roche-et-timothe-sivignon-ratent-la-qualification-pour-la-finale-du-ski-slopestyle-aux-jo-2026\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/matias-roche-et-timothe-sivignon-ratent-la-qualification-pour-la-finale-du-ski-slopestyle-aux-jo-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/02\/Matias-Roche-et-Timothe-Sivignon-ratent-la-qualification-pour-la-finale-du-ski-slopestyle-aux-JO-2026.png","datePublished":"2026-02-07T15:11:39+00:00","dateModified":"2026-02-07T15:26:22+00:00","description":"SKI FREESTYLE JO 2026 - Sans surprise, Matias Roche et Timoth\u00e9 Sivignon ont pris la porte d\u00e8s les qualifications en ski slopestyle.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/matias-roche-et-timothe-sivignon-ratent-la-qualification-pour-la-finale-du-ski-slopestyle-aux-jo-2026\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/matias-roche-et-timothe-sivignon-ratent-la-qualification-pour-la-finale-du-ski-slopestyle-aux-jo-2026\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/matias-roche-et-timothe-sivignon-ratent-la-qualification-pour-la-finale-du-ski-slopestyle-aux-jo-2026\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/02\/Matias-Roche-et-Timothe-Sivignon-ratent-la-qualification-pour-la-finale-du-ski-slopestyle-aux-JO-2026.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/02\/Matias-Roche-et-Timothe-Sivignon-ratent-la-qualification-pour-la-finale-du-ski-slopestyle-aux-JO-2026.png","width":1200,"height":674,"caption":"Matias Roche et Timoth\u00e9 Sivignon ratent la qualification pour la finale du ski slopestyle aux JO 2026"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/matias-roche-et-timothe-sivignon-ratent-la-qualification-pour-la-finale-du-ski-slopestyle-aux-jo-2026\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Matias Roche et Timoth\u00e9 Sivignon ratent la qualification pour la finale du ski slopestyle aux JO 2026"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0","name":"Maxime Cazenave","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg","caption":"Maxime Cazenave"},"description":"Journaliste\/R\u00e9dacteur depuis 2012 - Berc\u00e9 par l\u2019amour des Girondins de Bordeaux, les \u00e9checs de Christophe Moreau sur le Tour de France sous l'\u00e8re Lance Armstrong et le fade-away l\u00e9tal de Dirk Nowitzki, ma passion d\u00e9vorante pour le sport a toujours \u00e9t\u00e9 un pan incontournable de ma vie. Transmettre ma passion \u00e0 l\u2019\u00e9crit a \u00e9t\u00e9 une transition naturelle. Suiveur assidu de basket et de hockey sur glace, je garde toujours un peu de place pour suivre le cyclisme, le football et le maximum de performances fran\u00e7aises.","sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/Maxime_Caze"],"url":"https:\/\/dicodusport.fr\/blog\/author\/maximec\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/644989","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=644989"}],"version-history":[{"count":5,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/644989\/revisions"}],"predecessor-version":[{"id":645119,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/644989\/revisions\/645119"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/645104"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=644989"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=644989"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=644989"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}