{"id":645296,"date":"2026-02-07T21:06:41","date_gmt":"2026-02-07T20:06:41","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=645296&#038;preview=true&#038;preview_id=645296"},"modified":"2026-02-07T21:28:48","modified_gmt":"2026-02-07T20:28:48","slug":"les-bleus-du-patinage-artistique-elimines-de-lepreuve-par-equipes-avant-la-finale-aux-jo-2026","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/les-bleus-du-patinage-artistique-elimines-de-lepreuve-par-equipes-avant-la-finale-aux-jo-2026\/","title":{"rendered":"Les Bleus du patinage artistique \u00e9limin\u00e9s de l\u2019\u00e9preuve par \u00e9quipes avant la finale aux JO 2026"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><strong>PATINAGE ARTISTIQUE JO 2026 &#8211; C\u2019en est fini des espoirs de la France dans l\u2019\u00e9preuve par \u00e9quipes. La 4\u00e8me place de Kevin Aymoz sur l&rsquo;individuel court n\u2019a pas suffi \u00e0 replacer le collectif tricolore dans le top 5 final.<\/strong><\/em><\/p>\n<ul style=\"text-align: justify;\">\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet \u2013\u00a0<a href=\"https:\/\/dicodusport.fr\/blog\/calendrier-jo-dhiver-2026-programme-complet-des-epreuves-jour-par-jour-milan-cortina\/\">Calendrier JO d\u2019hiver 2026 : programme complet des \u00e9preuves, jour par jour (Milan-Cortina)<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\"><strong>Guillaume Cizeron<\/strong> et <strong>Laurence Fournier Beaudry<\/strong> avaient bien lanc\u00e9 le clan fran\u00e7ais en prenant la 2<sup>\u00e8me<\/sup> place en danse sur glace. Le passage en couple de <strong>Camille<\/strong> et <strong>Pavel Kovalev<\/strong> avait ensuite rel\u00e9gu\u00e9 la France \u00e0 la limite. Dans le top 5 final avant le court de l\u2019individuel femmes, les Bleus se sont retrouv\u00e9s \u00e0 sa porte, \u00e0 la 6<sup>\u00e8me<\/sup> place. Deux points les s\u00e9paraient alors des Canadiens, 5<sup>\u00e8mes<\/sup>.<\/p>\n<div class=\"vlp-link-container vlp-layout-article\"><a href=\"https:\/\/dicodusport.fr\/blog\/la-france-sixieme-de-lepreuve-par-equipes-de-patinage-artistique-apres-la-premiere-journee\/\" class=\"vlp-link\" title=\"La France sixi\u00e8me de l&#039;\u00e9preuve par \u00e9quipes de patinage artistique apr\u00e8s la premi\u00e8re journ\u00e9e\"><\/a><div class=\"vlp-layout-zone-side\"><div class=\"vlp-block-4 vlp-link-image\"><img loading=\"lazy\" decoding=\"async\" style=\"max-width: 792px;\" width=\"792\" height=\"445\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/02\/La-France-sixieme-de-lepreuve-par-equipes-de-patinage-artistique-apres-la-premiere-journee.png\" class=\"attachment-800x445 size-800x445\" alt=\"La France sixi\u00e8me de l&#039;\u00e9preuve par \u00e9quipes de patinage artistique apr\u00e8s la premi\u00e8re journ\u00e9e\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/02\/La-France-sixieme-de-lepreuve-par-equipes-de-patinage-artistique-apres-la-premiere-journee.png 1200w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/02\/La-France-sixieme-de-lepreuve-par-equipes-de-patinage-artistique-apres-la-premiere-journee-300x169.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/02\/La-France-sixieme-de-lepreuve-par-equipes-de-patinage-artistique-apres-la-premiere-journee-1024x575.png 1024w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/02\/La-France-sixieme-de-lepreuve-par-equipes-de-patinage-artistique-apres-la-premiere-journee-768x431.png 768w\" sizes=\"auto, (max-width: 792px) 100vw, 792px\" \/><\/div><\/div><div class=\"vlp-layout-zone-main\"><div class=\"vlp-block-0 vlp-link-title\">La France sixi\u00e8me de l'\u00e9preuve par \u00e9quipes de patinage artistique apr\u00e8s la premi\u00e8re journ\u00e9e<\/div><div class=\"vlp-block-1 vlp-link-summary\">PATINAGE ARTISTIQUE JO 2026 \u2013 \u00c0 l'issue de la premi\u00e8re journ\u00e9e de qualifications, les Bleus pointent \u00e0 la 6\u00e8me position de l'\u00e9preuve par \u00e9quipes. Il restera le programme court masculin demain pour esp\u00e9rer rejoindre la finale.\u00a0<\/div><div class=\"vlp-block-2 vlp-link-button\">Lire l'article<\/div><div class=\"vlp-block-3 vlp-link-url\">dicodusport.fr<\/div><\/div><\/div>\n<h2 style=\"text-align: justify;\">La France s\u2019arr\u00eate aux portes du top 5 final<\/h2>\n<p style=\"text-align: justify;\"><strong>Kevin Aymoz<\/strong> avait donc une grosse responsabilit\u00e9. D\u2019autant que <strong>Stephen Gogolev<\/strong> ne lui a pas facilit\u00e9 le travail. Sur le rythme de \u00ab Hey ! Pachucho ! \u00bb (mais si vous savez, la musique du film The Mask), le Canadien a frapp\u00e9 fort. Des figures proprement ex\u00e9cut\u00e9es, des r\u00e9ceptions sans bavure, <strong>Gogolev<\/strong> r\u00e9alisait son meilleur total de la saison avec un score de 92.99 dont une grosse note technique de 53.63. Loin de subir la pression d\u2019une premi\u00e8re participation olympique, il l\u2019a mise en revanche sur les \u00e9paules de <strong>Kevin Aymoz<\/strong>. Le Fran\u00e7ais n\u2019avait pas le choix, il fallait sortir le programme parfait.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"en\">Kevin Aymoz sur du Lady Gaga : \ud835\udc0c.\ud835\udc00.\ud835\udc06.\ud835\udc08.\ud835\udc10.\ud835\udc14.\ud835\udc04 \ud83d\ude0d <a href=\"https:\/\/t.co\/jRtaev12LW\">pic.twitter.com\/jRtaev12LW<\/a><\/p>\n<p>\u2014 Eurosport France (@Eurosport_FR) <a href=\"https:\/\/twitter.com\/Eurosport_FR\/status\/2020226264615801203?ref_src=twsrc%5Etfw\">February 7, 2026<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p style=\"text-align: justify;\">\u00c7a ne d\u00e9marrait pourtant pas sous les meilleurs auspices pour lui, f\u00e9brile \u00e0 la r\u00e9ception du premier saut. S\u2019il se reprenait dans la foul\u00e9e et ambian\u00e7ait la Ice Skating Arena de Milan au moment de la transition sur \u00ab Judas \u00bb de Lady Gaga, il restait encore derri\u00e8re le Canada (88.05). Il fallait alors compter sur un petit d\u00e9r\u00e8glement de <strong>Nika Egadze<\/strong>. Loin d\u2019\u00eatre serein \u00e0 l\u2019entame de sa partition, le G\u00e9orgien retrouvait n\u00e9anmoins des couleurs au fil du temps. Deux rangs derri\u00e8re Aymoz, il affichait une note de 84.37, suffisante pour laisser l\u2019\u00e9quipe de France aux portes du top 5 final.<\/p>\n<p style=\"text-align: justify;\">Celui-ci est actuellement men\u00e9 par les USA (34 points) devant le Japon (33 points), l&rsquo;Italie (28 points), le Canada (27 points) et la G\u00e9orgie (20 points).<\/p>\n<h3>\u00c0 voir aussi<\/h3>\n<div class=\"vlp-link-container vlp-layout-article\"><a href=\"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-jo-2026-classement-mis-a-jour-en-temps-reel\/\" class=\"vlp-link\" title=\"Tableau des m\u00e9dailles JO 2026 : classement mis \u00e0 jour en temps r\u00e9el\"><\/a><div class=\"vlp-layout-zone-side\"><div class=\"vlp-block-4 vlp-link-image\"><img loading=\"lazy\" decoding=\"async\" style=\"max-width: 792px;\" width=\"792\" height=\"445\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/02\/Tableau-des-medailles-JO-2026-classement-mis-a-jour-en-temps-reel.png\" class=\"attachment-800x445 size-800x445\" alt=\"Tableau des m\u00e9dailles JO 2026 classement mis \u00e0 jour en temps r\u00e9el\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/02\/Tableau-des-medailles-JO-2026-classement-mis-a-jour-en-temps-reel.png 1200w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/02\/Tableau-des-medailles-JO-2026-classement-mis-a-jour-en-temps-reel-300x169.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/02\/Tableau-des-medailles-JO-2026-classement-mis-a-jour-en-temps-reel-1024x575.png 1024w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/02\/Tableau-des-medailles-JO-2026-classement-mis-a-jour-en-temps-reel-768x431.png 768w\" sizes=\"auto, (max-width: 792px) 100vw, 792px\" \/><\/div><\/div><div class=\"vlp-layout-zone-main\"><div class=\"vlp-block-0 vlp-link-title\">Tableau des m\u00e9dailles JO 2026 : classement mis \u00e0 jour en temps r\u00e9el<\/div><div class=\"vlp-block-1 vlp-link-summary\">D\u00e9couvrez le tableau des m\u00e9dailles des JO 2026 : classement par pays, m\u00e9dailles d\u2019or, d\u2019argent et de bronze, mis \u00e0 jour en temps r\u00e9el pendant les Jeux.<\/div><div class=\"vlp-block-2 vlp-link-button\">Lire l'article<\/div><div class=\"vlp-block-3 vlp-link-url\">dicodusport.fr<\/div><\/div><\/div>\n<div id=\"gtx-trans\" style=\"position: absolute; left: -14px; top: 40.9091px;\">\n<div class=\"gtx-trans-icon\" style=\"text-align: justify;\"><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>PATINAGE ARTISTIQUE JO 2026 &#8211; S\u2019en est termin\u00e9 des espoirs de la France dans l\u2019\u00e9preuve par \u00e9quipes. La 4\u00e8me place de Kevin Aymoz sur l&rsquo;individuel court n\u2019a pas suffi \u00e0 replacer le collectif tricolore dans le top 5 final.<\/p>\n","protected":false},"author":18,"featured_media":645321,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[44003],"tags":[32415,16878,46887,46888,47094],"class_list":["post-645296","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-jo-hiver-2026","tag-actu","tag-breve","tag-jeux-olympiques-2026","tag-jo-2026","tag-jo-dhiver"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Les Bleus du patinage artistique \u00e9limin\u00e9s de l\u2019\u00e9preuve par \u00e9quipes avant la finale aux JO 2026<\/title>\n<meta name=\"description\" content=\"PATINAGE ARTISTIQUE JO 2026 - La 4\u00e8me place de Kevin Aymoz n\u2019a pas suffi \u00e0 replacer la France dans le top 5 final de l&#039;\u00e9preuve par \u00e9quipes.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/les-bleus-du-patinage-artistique-elimines-de-lepreuve-par-equipes-avant-la-finale-aux-jo-2026\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les Bleus du patinage artistique \u00e9limin\u00e9s de l\u2019\u00e9preuve par \u00e9quipes avant la finale aux JO 2026\" \/>\n<meta property=\"og:description\" content=\"PATINAGE ARTISTIQUE JO 2026 - La 4\u00e8me place de Kevin Aymoz n\u2019a pas suffi \u00e0 replacer la France dans le top 5 final de l&#039;\u00e9preuve par \u00e9quipes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/les-bleus-du-patinage-artistique-elimines-de-lepreuve-par-equipes-avant-la-finale-aux-jo-2026\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/soocube\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-07T20:06:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-07T20:28:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/02\/Les-Bleus-du-patinage-artistique-elimines-de-lepreuve-par-equipes-avant-la-finale-aux-JO-2026.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Sophie Clapier\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Les Bleus du patinage artistique \u00e9limin\u00e9s de l\u2019\u00e9preuve par \u00e9quipes avant la finale aux JO 2026\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/soocube\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-bleus-du-patinage-artistique-elimines-de-lepreuve-par-equipes-avant-la-finale-aux-jo-2026\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-bleus-du-patinage-artistique-elimines-de-lepreuve-par-equipes-avant-la-finale-aux-jo-2026\\\/\"},\"author\":{\"name\":\"Sophie Clapier\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/416c975648aca9da8839bdfe333a21c9\"},\"headline\":\"Les Bleus du patinage artistique \u00e9limin\u00e9s de l\u2019\u00e9preuve par \u00e9quipes avant la finale aux JO 2026\",\"datePublished\":\"2026-02-07T20:06:41+00:00\",\"dateModified\":\"2026-02-07T20:28:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-bleus-du-patinage-artistique-elimines-de-lepreuve-par-equipes-avant-la-finale-aux-jo-2026\\\/\"},\"wordCount\":568,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-bleus-du-patinage-artistique-elimines-de-lepreuve-par-equipes-avant-la-finale-aux-jo-2026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Les-Bleus-du-patinage-artistique-elimines-de-lepreuve-par-equipes-avant-la-finale-aux-JO-2026.png\",\"keywords\":[\"actu\",\"br\u00e8ve\",\"Jeux Olympiques 2026\",\"JO 2026\",\"JO d'hiver\"],\"articleSection\":[\"JO d'hiver 2026\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-bleus-du-patinage-artistique-elimines-de-lepreuve-par-equipes-avant-la-finale-aux-jo-2026\\\/#respond\"]}],\"copyrightYear\":\"2026\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-bleus-du-patinage-artistique-elimines-de-lepreuve-par-equipes-avant-la-finale-aux-jo-2026\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-bleus-du-patinage-artistique-elimines-de-lepreuve-par-equipes-avant-la-finale-aux-jo-2026\\\/\",\"name\":\"Les Bleus du patinage artistique \u00e9limin\u00e9s de l\u2019\u00e9preuve par \u00e9quipes avant la finale aux JO 2026\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-bleus-du-patinage-artistique-elimines-de-lepreuve-par-equipes-avant-la-finale-aux-jo-2026\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-bleus-du-patinage-artistique-elimines-de-lepreuve-par-equipes-avant-la-finale-aux-jo-2026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Les-Bleus-du-patinage-artistique-elimines-de-lepreuve-par-equipes-avant-la-finale-aux-JO-2026.png\",\"datePublished\":\"2026-02-07T20:06:41+00:00\",\"dateModified\":\"2026-02-07T20:28:48+00:00\",\"description\":\"PATINAGE ARTISTIQUE JO 2026 - La 4\u00e8me place de Kevin Aymoz n\u2019a pas suffi \u00e0 replacer la France dans le top 5 final de l'\u00e9preuve par \u00e9quipes.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-bleus-du-patinage-artistique-elimines-de-lepreuve-par-equipes-avant-la-finale-aux-jo-2026\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-bleus-du-patinage-artistique-elimines-de-lepreuve-par-equipes-avant-la-finale-aux-jo-2026\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-bleus-du-patinage-artistique-elimines-de-lepreuve-par-equipes-avant-la-finale-aux-jo-2026\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Les-Bleus-du-patinage-artistique-elimines-de-lepreuve-par-equipes-avant-la-finale-aux-JO-2026.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Les-Bleus-du-patinage-artistique-elimines-de-lepreuve-par-equipes-avant-la-finale-aux-JO-2026.png\",\"width\":1200,\"height\":674,\"caption\":\"Les Bleus du patinage artistique \u00e9limin\u00e9s de l\u2019\u00e9preuve par \u00e9quipes avant la finale aux JO 2026\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-bleus-du-patinage-artistique-elimines-de-lepreuve-par-equipes-avant-la-finale-aux-jo-2026\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les Bleus du patinage artistique \u00e9limin\u00e9s de l\u2019\u00e9preuve par \u00e9quipes avant la finale aux JO 2026\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/416c975648aca9da8839bdfe333a21c9\",\"name\":\"Sophie Clapier\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Sophie-Clapier-150x150.jpg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Sophie-Clapier-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Sophie-Clapier-150x150.jpg\",\"caption\":\"Sophie Clapier\"},\"description\":\"Journaliste\\\/r\u00e9dactrice depuis janvier 2016 - Passionn\u00e9e de sport depuis toujours, j\u2019en ai pratiqu\u00e9 quelques-uns. Judo, football, handball ou encore tennis, je n\u2019ai jamais pu me mettre d\u2019accord sur un en particulier. Mais \u00e7a, c\u2019\u00e9tait avant de d\u00e9couvrir le basket, devenu mon sport de pr\u00e9dilection. Les actions NBA, le All-Star Week-end, la fureur des Game 7 pendant les playoffs ou mieux, lors des Finals, this is why we play. Team Spurs T.P, je m\u2019accroche encore \u00e0 Gregg Popovich (don\u2019t leave !). Team chef Curry, je souhaite qu\u2019il finisse aux Warriors (staaaay !). Non, il n\u2019y a pas qu\u2019eux, des petits nouveaux -et des petites nouvelles \u00e9videmment- arrivent chaque jour dans toutes les disciplines et cr\u00e9ent de nouveaux exploits. Alors pour les grands \u00e9v\u00e9nements et comp\u00e9titions internationales, vive les pulsations 240\\\/minutes et le d\u00e9fibrillateur pas loin, et allez les Bleu(e)s ! C\u2019est s\u00fbr, j\u2019aurai plus vu ma vie sur un terrain de sport, mais \u00e0 d\u00e9faut d\u2019en faire en haut niveau, je le partage avec vous.\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/soocube\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/soocube\",\"admin\"],\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/sophie\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Les Bleus du patinage artistique \u00e9limin\u00e9s de l\u2019\u00e9preuve par \u00e9quipes avant la finale aux JO 2026","description":"PATINAGE ARTISTIQUE JO 2026 - La 4\u00e8me place de Kevin Aymoz n\u2019a pas suffi \u00e0 replacer la France dans le top 5 final de l'\u00e9preuve par \u00e9quipes.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/les-bleus-du-patinage-artistique-elimines-de-lepreuve-par-equipes-avant-la-finale-aux-jo-2026\/","og_locale":"fr_FR","og_type":"article","og_title":"Les Bleus du patinage artistique \u00e9limin\u00e9s de l\u2019\u00e9preuve par \u00e9quipes avant la finale aux JO 2026","og_description":"PATINAGE ARTISTIQUE JO 2026 - La 4\u00e8me place de Kevin Aymoz n\u2019a pas suffi \u00e0 replacer la France dans le top 5 final de l'\u00e9preuve par \u00e9quipes.","og_url":"https:\/\/dicodusport.fr\/blog\/les-bleus-du-patinage-artistique-elimines-de-lepreuve-par-equipes-avant-la-finale-aux-jo-2026\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/soocube","article_published_time":"2026-02-07T20:06:41+00:00","article_modified_time":"2026-02-07T20:28:48+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/02\/Les-Bleus-du-patinage-artistique-elimines-de-lepreuve-par-equipes-avant-la-finale-aux-JO-2026.png","type":"image\/png"}],"author":"Sophie Clapier","twitter_card":"summary_large_image","twitter_title":"Les Bleus du patinage artistique \u00e9limin\u00e9s de l\u2019\u00e9preuve par \u00e9quipes avant la finale aux JO 2026","twitter_creator":"@https:\/\/twitter.com\/soocube","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/les-bleus-du-patinage-artistique-elimines-de-lepreuve-par-equipes-avant-la-finale-aux-jo-2026\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/les-bleus-du-patinage-artistique-elimines-de-lepreuve-par-equipes-avant-la-finale-aux-jo-2026\/"},"author":{"name":"Sophie Clapier","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/416c975648aca9da8839bdfe333a21c9"},"headline":"Les Bleus du patinage artistique \u00e9limin\u00e9s de l\u2019\u00e9preuve par \u00e9quipes avant la finale aux JO 2026","datePublished":"2026-02-07T20:06:41+00:00","dateModified":"2026-02-07T20:28:48+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/les-bleus-du-patinage-artistique-elimines-de-lepreuve-par-equipes-avant-la-finale-aux-jo-2026\/"},"wordCount":568,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/les-bleus-du-patinage-artistique-elimines-de-lepreuve-par-equipes-avant-la-finale-aux-jo-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/02\/Les-Bleus-du-patinage-artistique-elimines-de-lepreuve-par-equipes-avant-la-finale-aux-JO-2026.png","keywords":["actu","br\u00e8ve","Jeux Olympiques 2026","JO 2026","JO d'hiver"],"articleSection":["JO d'hiver 2026"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/les-bleus-du-patinage-artistique-elimines-de-lepreuve-par-equipes-avant-la-finale-aux-jo-2026\/#respond"]}],"copyrightYear":"2026","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/les-bleus-du-patinage-artistique-elimines-de-lepreuve-par-equipes-avant-la-finale-aux-jo-2026\/","url":"https:\/\/dicodusport.fr\/blog\/les-bleus-du-patinage-artistique-elimines-de-lepreuve-par-equipes-avant-la-finale-aux-jo-2026\/","name":"Les Bleus du patinage artistique \u00e9limin\u00e9s de l\u2019\u00e9preuve par \u00e9quipes avant la finale aux JO 2026","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/les-bleus-du-patinage-artistique-elimines-de-lepreuve-par-equipes-avant-la-finale-aux-jo-2026\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/les-bleus-du-patinage-artistique-elimines-de-lepreuve-par-equipes-avant-la-finale-aux-jo-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/02\/Les-Bleus-du-patinage-artistique-elimines-de-lepreuve-par-equipes-avant-la-finale-aux-JO-2026.png","datePublished":"2026-02-07T20:06:41+00:00","dateModified":"2026-02-07T20:28:48+00:00","description":"PATINAGE ARTISTIQUE JO 2026 - La 4\u00e8me place de Kevin Aymoz n\u2019a pas suffi \u00e0 replacer la France dans le top 5 final de l'\u00e9preuve par \u00e9quipes.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/les-bleus-du-patinage-artistique-elimines-de-lepreuve-par-equipes-avant-la-finale-aux-jo-2026\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/les-bleus-du-patinage-artistique-elimines-de-lepreuve-par-equipes-avant-la-finale-aux-jo-2026\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/les-bleus-du-patinage-artistique-elimines-de-lepreuve-par-equipes-avant-la-finale-aux-jo-2026\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/02\/Les-Bleus-du-patinage-artistique-elimines-de-lepreuve-par-equipes-avant-la-finale-aux-JO-2026.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/02\/Les-Bleus-du-patinage-artistique-elimines-de-lepreuve-par-equipes-avant-la-finale-aux-JO-2026.png","width":1200,"height":674,"caption":"Les Bleus du patinage artistique \u00e9limin\u00e9s de l\u2019\u00e9preuve par \u00e9quipes avant la finale aux JO 2026"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/les-bleus-du-patinage-artistique-elimines-de-lepreuve-par-equipes-avant-la-finale-aux-jo-2026\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Les Bleus du patinage artistique \u00e9limin\u00e9s de l\u2019\u00e9preuve par \u00e9quipes avant la finale aux JO 2026"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/416c975648aca9da8839bdfe333a21c9","name":"Sophie Clapier","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Sophie-Clapier-150x150.jpg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Sophie-Clapier-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Sophie-Clapier-150x150.jpg","caption":"Sophie Clapier"},"description":"Journaliste\/r\u00e9dactrice depuis janvier 2016 - Passionn\u00e9e de sport depuis toujours, j\u2019en ai pratiqu\u00e9 quelques-uns. Judo, football, handball ou encore tennis, je n\u2019ai jamais pu me mettre d\u2019accord sur un en particulier. Mais \u00e7a, c\u2019\u00e9tait avant de d\u00e9couvrir le basket, devenu mon sport de pr\u00e9dilection. Les actions NBA, le All-Star Week-end, la fureur des Game 7 pendant les playoffs ou mieux, lors des Finals, this is why we play. Team Spurs T.P, je m\u2019accroche encore \u00e0 Gregg Popovich (don\u2019t leave !). Team chef Curry, je souhaite qu\u2019il finisse aux Warriors (staaaay !). Non, il n\u2019y a pas qu\u2019eux, des petits nouveaux -et des petites nouvelles \u00e9videmment- arrivent chaque jour dans toutes les disciplines et cr\u00e9ent de nouveaux exploits. Alors pour les grands \u00e9v\u00e9nements et comp\u00e9titions internationales, vive les pulsations 240\/minutes et le d\u00e9fibrillateur pas loin, et allez les Bleu(e)s ! C\u2019est s\u00fbr, j\u2019aurai plus vu ma vie sur un terrain de sport, mais \u00e0 d\u00e9faut d\u2019en faire en haut niveau, je le partage avec vous.","sameAs":["https:\/\/www.facebook.com\/soocube","https:\/\/x.com\/https:\/\/twitter.com\/soocube","admin"],"url":"https:\/\/dicodusport.fr\/blog\/author\/sophie\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/645296","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=645296"}],"version-history":[{"count":6,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/645296\/revisions"}],"predecessor-version":[{"id":645335,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/645296\/revisions\/645335"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/645321"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=645296"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=645296"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=645296"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}