{"id":646073,"date":"2026-02-10T13:59:51","date_gmt":"2026-02-10T12:59:51","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=646073&#038;preview=true&#038;preview_id=646073"},"modified":"2026-02-10T17:11:47","modified_gmt":"2026-02-10T16:11:47","slug":"le-norvegien-birk-ruud-sacre-champion-olympique-de-ski-slopestyle","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/le-norvegien-birk-ruud-sacre-champion-olympique-de-ski-slopestyle\/","title":{"rendered":"Le Norv\u00e9gien Birk Ruud sacr\u00e9 champion olympique de ski slopestyle"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>SKI FREESTYLE JO 2026 &#8211; Solide d\u00e8s son premier run, le Norv\u00e9gien Birk Ruud a d\u00e9croch\u00e9 le titre olympique du slopestyle devant Alexander Hall et Luca Harrington.\u00a0<\/em><\/strong><\/p>\n<ul style=\"text-align: justify;\">\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet \u2013\u00a0<a href=\"https:\/\/dicodusport.fr\/blog\/calendrier-jo-dhiver-2026-programme-complet-des-epreuves-jour-par-jour-milan-cortina\/\">Calendrier JO d\u2019hiver 2026 : programme complet des \u00e9preuves, jour par jour (Milan-Cortina)<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Jour de finale du ski slopestyle masculin. Une finale sans tricolore, puisque <strong>Matias Roche<\/strong> et <strong>Timoth\u00e9 Sivignon<\/strong>, plus attendus sur le big air, ne sont pas parvenus \u00e0 se qualifier. Pour cette finale, trois runs par skieur \u00e9taient au programme, et le meilleur \u00e9tait conserv\u00e9.<\/p>\n<h2 style=\"text-align: justify;\">Ruud d\u00e9marre fort<\/h2>\n<p style=\"text-align: justify;\">\u00c0 l\u2019issue du 1er run, c\u2019est le Norv\u00e9gien <strong>Birk Ruud<\/strong>, champion du monde en titre, qui prenait assez largement la t\u00eate avec la note de 86,28. Un r\u00e9sultat coh\u00e9rent tant il a \u00e9t\u00e9 plus propre, que ce soit sur les rails ou sur les r\u00e9ceptions de ses sauts. Derri\u00e8re lui, son compatriote <strong>Tormod Frostad<\/strong> se retrouvait assez loin avec 78,65, tout comme le Su\u00e9dois <strong>Jesper Tj\u00e4der<\/strong> (77,21).<\/p>\n<ul>\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet \u2013\u00a0<a href=\"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-jo-2026-classement-mis-a-jour-en-temps-reel\/\">Tableau des m\u00e9dailles JO 2026 : classement mis \u00e0 jour en temps r\u00e9el<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Champion olympique en titre, <strong>Alexander Hall<\/strong> s\u2019est repris apr\u00e8s un premier passage manqu\u00e9. Solide sur les rails, et gr\u00e2ce \u00e0 une superbe amplitude sur les sauts, il obtenait 85,75 et occupait provisoirement la 2<sup>e<\/sup> place. Il lui faudra plaquer davantage sur les r\u00e9ceptions pour esp\u00e9rer mieux. La pression est importante sur cette finale olympique et cela se ressent, car les <em>riders<\/em> peinent \u00e0 sortir de gros runs. Pas de changement pour la premi\u00e8re place, avec toujours <strong>Birk Ruud<\/strong> en t\u00eate.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"en\">\ud83e\udd47 Birk RUUD [NOR] claims gold on the slopes in the freestyle skiing men&rsquo;s freeski slopestyle.<\/p>\n<p>The Beijing 2022 Big Air Olympic champion adds slopestyle gold after finishing 5th in this event four years ago \ud83d\udc4f<\/p>\n<p>What a performance \ud83d\udd25 <a href=\"https:\/\/twitter.com\/hashtag\/MilanoCortina2026?src=hash&amp;ref_src=twsrc%5Etfw\">#MilanoCortina2026<\/a> | <a href=\"https:\/\/twitter.com\/FISfreestyle?ref_src=twsrc%5Etfw\">@FISFreestyle<\/a> |\u2026 <a href=\"https:\/\/t.co\/HCL0rvriUB\">pic.twitter.com\/HCL0rvriUB<\/a><\/p>\n<p>\u2014 The Olympic Games (@Olympics) <a href=\"https:\/\/twitter.com\/Olympics\/status\/2021207767076266261?ref_src=twsrc%5Etfw\">February 10, 2026<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 style=\"text-align: justify;\">2<sup>e<\/sup> titre olympique pour Birk Ruud<\/h2>\n<p style=\"text-align: justify;\">Tout pouvait donc encore se jouer sur la derni\u00e8re manche. Avant-dernier \u00e0 l\u2019issue des deux premiers runs, le N\u00e9o-Z\u00e9landais <strong>Luca Harrington<\/strong> a encha\u00een\u00e9 les gros tricks sans erreurs pour venir se placer sur le si\u00e8ge \u00e9jectable, \u00e0 la 3<sup>e<\/sup> marche du podium (85,15), juste devant <strong>Andri Ragettli<\/strong> (78,65).<\/p>\n<p style=\"text-align: justify;\"><strong>Alexander Hall<\/strong> prenait ensuite le d\u00e9part pour tenter de d\u00e9loger Ruud. Mais d\u00e8s les rails, l\u2019Am\u00e9ricain se manquait. Avec un ultime run marqu\u00e9 par une petite chute, <strong>Birk Ruud<\/strong> d\u00e9crochait donc le titre olympique, son 2<sup>e<\/sup> apr\u00e8s celui obtenu en 2022 sur le big air. <strong>Alexander Hall<\/strong> prenait l\u2019argent, <strong>Luca Harrington<\/strong> le bronze.<\/p>\n<div id=\"gtx-trans\" style=\"position: absolute; left: -14px; top: 40.9091px;\">\n<div class=\"gtx-trans-icon\" style=\"text-align: justify;\"><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>SKI FREESTYLE JO 2026 &#8211; Solide d\u00e8s son premier run, le Norv\u00e9gien Birk Ruud a d\u00e9croch\u00e9 le titre olympique du slopestyle devant Alexander Hall et Luca Harrington.\u00a0<\/p>\n","protected":false},"author":89,"featured_media":646327,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[44003,9217],"tags":[32415,16878,46887,46888,47094,15570],"class_list":["post-646073","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-jo-hiver-2026","category-ski","tag-actu","tag-breve","tag-jeux-olympiques-2026","tag-jo-2026","tag-jo-dhiver","tag-ski-slopestyle"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Le Norv\u00e9gien Birk Ruud sacr\u00e9 champion olympique de ski slopestyle<\/title>\n<meta name=\"description\" content=\"SKI FREESTYLE JO 2026 - Solide d\u00e8s son premier run, le Norv\u00e9gien Birk Ruud a d\u00e9croch\u00e9 le titre olympique du slopestyle devant Alexander Hall et Luca Harrington.\u00a0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/le-norvegien-birk-ruud-sacre-champion-olympique-de-ski-slopestyle\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le Norv\u00e9gien Birk Ruud sacr\u00e9 champion olympique de ski slopestyle\" \/>\n<meta property=\"og:description\" content=\"SKI FREESTYLE JO 2026 - Solide d\u00e8s son premier run, le Norv\u00e9gien Birk Ruud a d\u00e9croch\u00e9 le titre olympique du slopestyle devant Alexander Hall et Luca Harrington.\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/le-norvegien-birk-ruud-sacre-champion-olympique-de-ski-slopestyle\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-10T12:59:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-10T16:11:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/02\/Le-Norvegien-Birk-Ruud-sacre-champion-olympique-de-ski-slopestyle-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Louka Lesueur\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Le Norv\u00e9gien Birk Ruud sacr\u00e9 champion olympique de ski slopestyle\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/LNewsSF\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/le-norvegien-birk-ruud-sacre-champion-olympique-de-ski-slopestyle\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/le-norvegien-birk-ruud-sacre-champion-olympique-de-ski-slopestyle\\\/\"},\"author\":{\"name\":\"Louka Lesueur\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/54b6cdccebdfcd5a1036c594aecffc2a\"},\"headline\":\"Le Norv\u00e9gien Birk Ruud sacr\u00e9 champion olympique de ski slopestyle\",\"datePublished\":\"2026-02-10T12:59:51+00:00\",\"dateModified\":\"2026-02-10T16:11:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/le-norvegien-birk-ruud-sacre-champion-olympique-de-ski-slopestyle\\\/\"},\"wordCount\":438,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/le-norvegien-birk-ruud-sacre-champion-olympique-de-ski-slopestyle\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Le-Norvegien-Birk-Ruud-sacre-champion-olympique-de-ski-slopestyle-1.png\",\"keywords\":[\"actu\",\"br\u00e8ve\",\"Jeux Olympiques 2026\",\"JO 2026\",\"JO d'hiver\",\"Ski slopestyle\"],\"articleSection\":[\"JO d'hiver 2026\",\"Ski\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/le-norvegien-birk-ruud-sacre-champion-olympique-de-ski-slopestyle\\\/#respond\"]}],\"copyrightYear\":\"2026\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/le-norvegien-birk-ruud-sacre-champion-olympique-de-ski-slopestyle\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/le-norvegien-birk-ruud-sacre-champion-olympique-de-ski-slopestyle\\\/\",\"name\":\"Le Norv\u00e9gien Birk Ruud sacr\u00e9 champion olympique de ski slopestyle\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/le-norvegien-birk-ruud-sacre-champion-olympique-de-ski-slopestyle\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/le-norvegien-birk-ruud-sacre-champion-olympique-de-ski-slopestyle\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Le-Norvegien-Birk-Ruud-sacre-champion-olympique-de-ski-slopestyle-1.png\",\"datePublished\":\"2026-02-10T12:59:51+00:00\",\"dateModified\":\"2026-02-10T16:11:47+00:00\",\"description\":\"SKI FREESTYLE JO 2026 - Solide d\u00e8s son premier run, le Norv\u00e9gien Birk Ruud a d\u00e9croch\u00e9 le titre olympique du slopestyle devant Alexander Hall et Luca Harrington.\u00a0\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/le-norvegien-birk-ruud-sacre-champion-olympique-de-ski-slopestyle\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/le-norvegien-birk-ruud-sacre-champion-olympique-de-ski-slopestyle\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/le-norvegien-birk-ruud-sacre-champion-olympique-de-ski-slopestyle\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Le-Norvegien-Birk-Ruud-sacre-champion-olympique-de-ski-slopestyle-1.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Le-Norvegien-Birk-Ruud-sacre-champion-olympique-de-ski-slopestyle-1.png\",\"width\":1200,\"height\":674,\"caption\":\"Le Norv\u00e9gien Birk Ruud sacr\u00e9 champion olympique de ski slopestyle\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/le-norvegien-birk-ruud-sacre-champion-olympique-de-ski-slopestyle\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le Norv\u00e9gien Birk Ruud sacr\u00e9 champion olympique de ski slopestyle\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/54b6cdccebdfcd5a1036c594aecffc2a\",\"name\":\"Louka Lesueur\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/IMG_2783-150x150.jpeg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/IMG_2783-150x150.jpeg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/IMG_2783-150x150.jpeg\",\"caption\":\"Louka Lesueur\"},\"description\":\"Passionn\u00e9 depuis tout petit par les exploits de Bolt, Fourcade, Riner, Lavillenie, Wilkinson, Hirscher. Les \u00e9motions provoqu\u00e9es par le sport ont berc\u00e9 mon enfance et continuent de le faire aujourd'hui. C'est ainsi qu'il m'est arriv\u00e9 de pleurer devant la d\u00e9faite des Bleus face aux Blacks en 2011, ou encore devant le titre olympique de Florent Manaudou \u00e0 Londres. Bien loin de ce milieu professionnel, j'ai os\u00e9 tenter ma chance pour rejoindre l'\u00e9quipe de r\u00e9daction de Dicodusport, et depuis septembre 2023, je tente de retransmettre au mieux les exploits des athl\u00e8tes, tous sports confondus. Grand chauvin, c'est bel et bien sur les sportifs tricolores que je pr\u00e9f\u00e8re \u00e9crire.\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/LNewsSF\"],\"gender\":\"Homme\",\"worksFor\":\"Louka LESUEUR\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/louka-lesueur\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Le Norv\u00e9gien Birk Ruud sacr\u00e9 champion olympique de ski slopestyle","description":"SKI FREESTYLE JO 2026 - Solide d\u00e8s son premier run, le Norv\u00e9gien Birk Ruud a d\u00e9croch\u00e9 le titre olympique du slopestyle devant Alexander Hall et Luca Harrington.\u00a0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/le-norvegien-birk-ruud-sacre-champion-olympique-de-ski-slopestyle\/","og_locale":"fr_FR","og_type":"article","og_title":"Le Norv\u00e9gien Birk Ruud sacr\u00e9 champion olympique de ski slopestyle","og_description":"SKI FREESTYLE JO 2026 - Solide d\u00e8s son premier run, le Norv\u00e9gien Birk Ruud a d\u00e9croch\u00e9 le titre olympique du slopestyle devant Alexander Hall et Luca Harrington.\u00a0","og_url":"https:\/\/dicodusport.fr\/blog\/le-norvegien-birk-ruud-sacre-champion-olympique-de-ski-slopestyle\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2026-02-10T12:59:51+00:00","article_modified_time":"2026-02-10T16:11:47+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/02\/Le-Norvegien-Birk-Ruud-sacre-champion-olympique-de-ski-slopestyle-1.png","type":"image\/png"}],"author":"Louka Lesueur","twitter_card":"summary_large_image","twitter_title":"Le Norv\u00e9gien Birk Ruud sacr\u00e9 champion olympique de ski slopestyle","twitter_creator":"@https:\/\/twitter.com\/LNewsSF","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/le-norvegien-birk-ruud-sacre-champion-olympique-de-ski-slopestyle\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/le-norvegien-birk-ruud-sacre-champion-olympique-de-ski-slopestyle\/"},"author":{"name":"Louka Lesueur","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/54b6cdccebdfcd5a1036c594aecffc2a"},"headline":"Le Norv\u00e9gien Birk Ruud sacr\u00e9 champion olympique de ski slopestyle","datePublished":"2026-02-10T12:59:51+00:00","dateModified":"2026-02-10T16:11:47+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/le-norvegien-birk-ruud-sacre-champion-olympique-de-ski-slopestyle\/"},"wordCount":438,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/le-norvegien-birk-ruud-sacre-champion-olympique-de-ski-slopestyle\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/02\/Le-Norvegien-Birk-Ruud-sacre-champion-olympique-de-ski-slopestyle-1.png","keywords":["actu","br\u00e8ve","Jeux Olympiques 2026","JO 2026","JO d'hiver","Ski slopestyle"],"articleSection":["JO d'hiver 2026","Ski"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/le-norvegien-birk-ruud-sacre-champion-olympique-de-ski-slopestyle\/#respond"]}],"copyrightYear":"2026","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/le-norvegien-birk-ruud-sacre-champion-olympique-de-ski-slopestyle\/","url":"https:\/\/dicodusport.fr\/blog\/le-norvegien-birk-ruud-sacre-champion-olympique-de-ski-slopestyle\/","name":"Le Norv\u00e9gien Birk Ruud sacr\u00e9 champion olympique de ski slopestyle","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/le-norvegien-birk-ruud-sacre-champion-olympique-de-ski-slopestyle\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/le-norvegien-birk-ruud-sacre-champion-olympique-de-ski-slopestyle\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/02\/Le-Norvegien-Birk-Ruud-sacre-champion-olympique-de-ski-slopestyle-1.png","datePublished":"2026-02-10T12:59:51+00:00","dateModified":"2026-02-10T16:11:47+00:00","description":"SKI FREESTYLE JO 2026 - Solide d\u00e8s son premier run, le Norv\u00e9gien Birk Ruud a d\u00e9croch\u00e9 le titre olympique du slopestyle devant Alexander Hall et Luca Harrington.\u00a0","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/le-norvegien-birk-ruud-sacre-champion-olympique-de-ski-slopestyle\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/le-norvegien-birk-ruud-sacre-champion-olympique-de-ski-slopestyle\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/le-norvegien-birk-ruud-sacre-champion-olympique-de-ski-slopestyle\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/02\/Le-Norvegien-Birk-Ruud-sacre-champion-olympique-de-ski-slopestyle-1.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/02\/Le-Norvegien-Birk-Ruud-sacre-champion-olympique-de-ski-slopestyle-1.png","width":1200,"height":674,"caption":"Le Norv\u00e9gien Birk Ruud sacr\u00e9 champion olympique de ski slopestyle"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/le-norvegien-birk-ruud-sacre-champion-olympique-de-ski-slopestyle\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Le Norv\u00e9gien Birk Ruud sacr\u00e9 champion olympique de ski slopestyle"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/54b6cdccebdfcd5a1036c594aecffc2a","name":"Louka Lesueur","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/09\/IMG_2783-150x150.jpeg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/09\/IMG_2783-150x150.jpeg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/09\/IMG_2783-150x150.jpeg","caption":"Louka Lesueur"},"description":"Passionn\u00e9 depuis tout petit par les exploits de Bolt, Fourcade, Riner, Lavillenie, Wilkinson, Hirscher. Les \u00e9motions provoqu\u00e9es par le sport ont berc\u00e9 mon enfance et continuent de le faire aujourd'hui. C'est ainsi qu'il m'est arriv\u00e9 de pleurer devant la d\u00e9faite des Bleus face aux Blacks en 2011, ou encore devant le titre olympique de Florent Manaudou \u00e0 Londres. Bien loin de ce milieu professionnel, j'ai os\u00e9 tenter ma chance pour rejoindre l'\u00e9quipe de r\u00e9daction de Dicodusport, et depuis septembre 2023, je tente de retransmettre au mieux les exploits des athl\u00e8tes, tous sports confondus. Grand chauvin, c'est bel et bien sur les sportifs tricolores que je pr\u00e9f\u00e8re \u00e9crire.","sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/LNewsSF"],"gender":"Homme","worksFor":"Louka LESUEUR","url":"https:\/\/dicodusport.fr\/blog\/author\/louka-lesueur\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/646073","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/89"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=646073"}],"version-history":[{"count":5,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/646073\/revisions"}],"predecessor-version":[{"id":646328,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/646073\/revisions\/646328"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/646327"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=646073"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=646073"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=646073"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}