{"id":646135,"date":"2026-02-10T13:19:14","date_gmt":"2026-02-10T12:19:14","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=646135&#038;preview=true&#038;preview_id=646135"},"modified":"2026-02-10T15:32:46","modified_gmt":"2026-02-10T14:32:46","slug":"litalie-championne-olympique-du-relais-mixte-de-short-track-a-domicile-les-belges-sur-le-podium","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/litalie-championne-olympique-du-relais-mixte-de-short-track-a-domicile-les-belges-sur-le-podium\/","title":{"rendered":"L&rsquo;Italie championne olympique du relais mixte de short-track \u00e0 domicile, les Belges sur le podium"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>SHORT-TRACK JO 2026 &#8211; L&rsquo;Italie a ma\u00eetris\u00e9 la finale A du relais mixte et s&rsquo;est offert le titre olympique devant le Canada et la Belgique. La France est 7\u00e8me.<\/em><\/strong><\/p>\n<ul style=\"text-align: justify;\">\n<li><strong><strong>\u00c0 ce sujet \u2013\u00a0<a href=\"https:\/\/dicodusport.fr\/blog\/calendrier-jo-dhiver-2026-programme-complet-des-epreuves-jour-par-jour-milan-cortina\/\">Calendrier JO d\u2019hiver 2026 : programme complet des \u00e9preuves, jour par jour (Milan-Cortina)<\/a><\/strong><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Nouveau triomphe \u00e0 domicile. L\u2019Italie a parfaitement g\u00e9r\u00e9 sa finale olympique et a remport\u00e9 l\u2019or lors du relais mixte de short-track. Les Transalpins ont profit\u00e9 d\u2019une erreur technique chinoise pour passer devant, sans jamais l\u00e2cher la t\u00eate. Le Canada est en argent, m\u00e9daille de bronze pour la Belgique, la premi\u00e8re dans ces JO 2026. La France (<\/span><b>Clo\u00e9 Ollivier<\/b><span style=\"font-weight: 400;\">, <\/span><b>B\u00e9r\u00e9nice Comby<\/b><span style=\"font-weight: 400;\">, <\/span><b>\u00c9tienne Bastier<\/b><span style=\"font-weight: 400;\"> et <\/span><b>Quentin Fercoq<\/b><span style=\"font-weight: 400;\">), rep\u00each\u00e9e pour les demi-finales, se classe finalement 7<sup>e<\/sup> de ce deuxi\u00e8me relais mixte de l\u2019histoire olympique.<\/span><\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"pt\">FESTA ITALIANA NO IN\u00cdCIO DO SHORT TRACK!<br \/>\nA \ud83e\udd47 It\u00e1lia \ud83c\uddee\ud83c\uddf9 vence revezamento misto da patina\u00e7\u00e3o de velocidade em pista curta, \u00e0 frente do \ud83e\udd48 Canad\u00e1 \ud83c\udde8\ud83c\udde6 e da improv\u00e1vel \ud83e\udd49 B\u00e9lgica \ud83c\udde7\ud83c\uddea, que conquista sua 1\u00aa medalha nesta edi\u00e7\u00e3o, apenas a 9\u00aa da hist\u00f3ria do pa\u00eds em <a href=\"https:\/\/twitter.com\/hashtag\/OlimpiadasDeInverno?src=hash&amp;ref_src=twsrc%5Etfw\">#OlimpiadasDeInverno<\/a>. <a href=\"https:\/\/t.co\/IcO7gRFHNv\">pic.twitter.com\/IcO7gRFHNv<\/a><\/p>\n<p>\u2014 M\u00e1rcio Melo &#8211; Olimp\u00edadas de Inverno (@marciohmmelo) <a href=\"https:\/\/twitter.com\/marciohmmelo\/status\/2021198199176954068?ref_src=twsrc%5Etfw\">February 10, 2026<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 style=\"text-align: justify;\">Les Pays-Bas sortis pr\u00e9matur\u00e9ment<\/h2>\n<p><span style=\"font-weight: 400;\">\u00c0 partir de midi pile, les quarts de finale se sont d\u00e9roul\u00e9s sans accroc pour les meilleures nations, sauf lors de la s\u00e9rie de l\u2019\u00e9quipe de France. Alors en 2<sup>e<\/sup> position, le patineur fran\u00e7ais a \u00e9t\u00e9 bouscul\u00e9 par son adversaire japonais. Les juges ont d\u00e9cid\u00e9 de p\u00e9naliser le Japon et de rep\u00eacher le quatuor tricolore. La Cor\u00e9e du Sud et les \u00c9tats-Unis se sont qualifi\u00e9s lors de cette course.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La France a donc int\u00e9gr\u00e9 le top 8 olympique, mais n\u2019a pas pu rejoindre la finale. L\u2019Italie et la Chine ont pris leur billet, laissant les Pays-Bas, num\u00e9ros un mondiaux, sur la touche. Ces derniers sont finalement all\u00e9s en finale B, qu\u2019ils ont remport\u00e9e, avec la Cor\u00e9e du Sud et les \u00c9tats-Unis. <\/span><b>Gilli Kim<\/b><span style=\"font-weight: 400;\"> a \u00e9t\u00e9 tacl\u00e9e par <\/span><b>Corinne Stoddard<\/b><span style=\"font-weight: 400;\"> lors de la seconde partie de cette demi-finale, \u00e9liminant les deux nations. Le Canada et la Belgique ont rejoint le dernier carr\u00e9 gr\u00e2ce \u00e0 cet accrochage.<\/span><\/p>\n<ul>\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet \u2013 <a href=\"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-jo-2026-classement-mis-a-jour-en-temps-reel\/\">Tableau des m\u00e9dailles JO 2026 : classement mis \u00e0 jour en temps r\u00e9el<\/a><\/strong><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">D\u2019abord en t\u00eate, la Chine n\u2019a fait que d\u00e9gringoler lors de la finale A. Les trois autres nations en ont profit\u00e9, l\u2019Italie en premi\u00e8re ligne. Le Canada et la Belgique ont compl\u00e9t\u00e9 ce podium, sans les Cor\u00e9ens ni les N\u00e9erlandais, pi\u00e9g\u00e9s plus t\u00f4t dans la comp\u00e9tition.<\/span><\/p>\n<div id=\"gtx-trans\" style=\"position: absolute; left: -14px; top: 40.9091px;\">\n<div class=\"gtx-trans-icon\" style=\"text-align: justify;\"><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>SHORT-TRACK JO 2026 &#8211; L&rsquo;Italie a ma\u00eetris\u00e9 la finale A du relais mixte et s&rsquo;est offert le titre olympique devant le Canada et la Belgique. La France est 7\u00e8me.<\/p>\n","protected":false},"author":61,"featured_media":646303,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[44003,2313],"tags":[32415,16878,46887,46888,47094,2646],"class_list":["post-646135","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-jo-hiver-2026","category-sports-dhiver","tag-actu","tag-breve","tag-jeux-olympiques-2026","tag-jo-2026","tag-jo-dhiver","tag-short-track"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>L&#039;Italie championne olympique du relais mixte de short-track \u00e0 domicile, les Belges sur le podium<\/title>\n<meta name=\"description\" content=\"SHORT-TRACK JO 2026 - L&#039;Italie a ma\u00eetris\u00e9 la finale A du relais mixte et s&#039;est offert le titre olympique devant le Canada et la Belgique. La France est 7\u00e8me.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/litalie-championne-olympique-du-relais-mixte-de-short-track-a-domicile-les-belges-sur-le-podium\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L&#039;Italie championne olympique du relais mixte de short-track \u00e0 domicile, les Belges sur le podium\" \/>\n<meta property=\"og:description\" content=\"SHORT-TRACK JO 2026 - L&#039;Italie a ma\u00eetris\u00e9 la finale A du relais mixte et s&#039;est offert le titre olympique devant le Canada et la Belgique. La France est 7\u00e8me.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/litalie-championne-olympique-du-relais-mixte-de-short-track-a-domicile-les-belges-sur-le-podium\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-10T12:19:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-10T14:32:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/02\/LItalie-championne-olympique-du-relais-mixte-de-short-track-a-domicile-les-Belges-sur-le-podium-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Pierre Gorce\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"L&#039;Italie championne olympique du relais mixte de short-track \u00e0 domicile, les Belges sur le podium\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/pierregorce12\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/litalie-championne-olympique-du-relais-mixte-de-short-track-a-domicile-les-belges-sur-le-podium\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/litalie-championne-olympique-du-relais-mixte-de-short-track-a-domicile-les-belges-sur-le-podium\\\/\"},\"author\":{\"name\":\"Pierre Gorce\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/0eaf70b33d703a1a66b1155ac1bda018\"},\"headline\":\"L&rsquo;Italie championne olympique du relais mixte de short-track \u00e0 domicile, les Belges sur le podium\",\"datePublished\":\"2026-02-10T12:19:14+00:00\",\"dateModified\":\"2026-02-10T14:32:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/litalie-championne-olympique-du-relais-mixte-de-short-track-a-domicile-les-belges-sur-le-podium\\\/\"},\"wordCount\":467,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/litalie-championne-olympique-du-relais-mixte-de-short-track-a-domicile-les-belges-sur-le-podium\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/LItalie-championne-olympique-du-relais-mixte-de-short-track-a-domicile-les-Belges-sur-le-podium-1.png\",\"keywords\":[\"actu\",\"br\u00e8ve\",\"Jeux Olympiques 2026\",\"JO 2026\",\"JO d'hiver\",\"short track\"],\"articleSection\":[\"JO d'hiver 2026\",\"Sports d'hiver\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/litalie-championne-olympique-du-relais-mixte-de-short-track-a-domicile-les-belges-sur-le-podium\\\/#respond\"]}],\"copyrightYear\":\"2026\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/litalie-championne-olympique-du-relais-mixte-de-short-track-a-domicile-les-belges-sur-le-podium\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/litalie-championne-olympique-du-relais-mixte-de-short-track-a-domicile-les-belges-sur-le-podium\\\/\",\"name\":\"L'Italie championne olympique du relais mixte de short-track \u00e0 domicile, les Belges sur le podium\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/litalie-championne-olympique-du-relais-mixte-de-short-track-a-domicile-les-belges-sur-le-podium\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/litalie-championne-olympique-du-relais-mixte-de-short-track-a-domicile-les-belges-sur-le-podium\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/LItalie-championne-olympique-du-relais-mixte-de-short-track-a-domicile-les-Belges-sur-le-podium-1.png\",\"datePublished\":\"2026-02-10T12:19:14+00:00\",\"dateModified\":\"2026-02-10T14:32:46+00:00\",\"description\":\"SHORT-TRACK JO 2026 - L'Italie a ma\u00eetris\u00e9 la finale A du relais mixte et s'est offert le titre olympique devant le Canada et la Belgique. La France est 7\u00e8me.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/litalie-championne-olympique-du-relais-mixte-de-short-track-a-domicile-les-belges-sur-le-podium\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/litalie-championne-olympique-du-relais-mixte-de-short-track-a-domicile-les-belges-sur-le-podium\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/litalie-championne-olympique-du-relais-mixte-de-short-track-a-domicile-les-belges-sur-le-podium\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/LItalie-championne-olympique-du-relais-mixte-de-short-track-a-domicile-les-Belges-sur-le-podium-1.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/LItalie-championne-olympique-du-relais-mixte-de-short-track-a-domicile-les-Belges-sur-le-podium-1.png\",\"width\":1200,\"height\":674,\"caption\":\"L'Italie championne olympique du relais mixte de short-track \u00e0 domicile, les Belges sur le podium\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/litalie-championne-olympique-du-relais-mixte-de-short-track-a-domicile-les-belges-sur-le-podium\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L&rsquo;Italie championne olympique du relais mixte de short-track \u00e0 domicile, les Belges sur le podium\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/0eaf70b33d703a1a66b1155ac1bda018\",\"name\":\"Pierre Gorce\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/IMG_20211214_233053_722-150x150.jpg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/IMG_20211214_233053_722-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/IMG_20211214_233053_722-150x150.jpg\",\"caption\":\"Pierre Gorce\"},\"description\":\"Couteau suisse venant tout droit de Haute-Savoie. Habitu\u00e9 \u00e0 regarder du sport depuis petit, j'en ai maintenant fait mon m\u00e9tier. Des sports d'hiver au surf, en passant par le tennis, la F1, le handball et l'athl\u00e9tisme, j'essaie d'avoir mes yeux sur l'enti\u00e8ret\u00e9 de l'actualit\u00e9. Jeune homme berc\u00e9 par les exploits de Jean-Baptiste Grange, Sebastian Vettel et des Experts. Membre de la g\u00e9n\u00e9ration 1999 comme Luka Doncic, Sydney McLaughlin, Lando Norris et Loana Lecomte, mais avec beaucoup moins de talent qu'eux.\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/pierregorce12\"],\"birthDate\":\"1999-08-29\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/pierreg\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"L'Italie championne olympique du relais mixte de short-track \u00e0 domicile, les Belges sur le podium","description":"SHORT-TRACK JO 2026 - L'Italie a ma\u00eetris\u00e9 la finale A du relais mixte et s'est offert le titre olympique devant le Canada et la Belgique. La France est 7\u00e8me.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/litalie-championne-olympique-du-relais-mixte-de-short-track-a-domicile-les-belges-sur-le-podium\/","og_locale":"fr_FR","og_type":"article","og_title":"L'Italie championne olympique du relais mixte de short-track \u00e0 domicile, les Belges sur le podium","og_description":"SHORT-TRACK JO 2026 - L'Italie a ma\u00eetris\u00e9 la finale A du relais mixte et s'est offert le titre olympique devant le Canada et la Belgique. La France est 7\u00e8me.","og_url":"https:\/\/dicodusport.fr\/blog\/litalie-championne-olympique-du-relais-mixte-de-short-track-a-domicile-les-belges-sur-le-podium\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2026-02-10T12:19:14+00:00","article_modified_time":"2026-02-10T14:32:46+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/02\/LItalie-championne-olympique-du-relais-mixte-de-short-track-a-domicile-les-Belges-sur-le-podium-1.png","type":"image\/png"}],"author":"Pierre Gorce","twitter_card":"summary_large_image","twitter_title":"L'Italie championne olympique du relais mixte de short-track \u00e0 domicile, les Belges sur le podium","twitter_creator":"@https:\/\/twitter.com\/pierregorce12","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/litalie-championne-olympique-du-relais-mixte-de-short-track-a-domicile-les-belges-sur-le-podium\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/litalie-championne-olympique-du-relais-mixte-de-short-track-a-domicile-les-belges-sur-le-podium\/"},"author":{"name":"Pierre Gorce","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/0eaf70b33d703a1a66b1155ac1bda018"},"headline":"L&rsquo;Italie championne olympique du relais mixte de short-track \u00e0 domicile, les Belges sur le podium","datePublished":"2026-02-10T12:19:14+00:00","dateModified":"2026-02-10T14:32:46+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/litalie-championne-olympique-du-relais-mixte-de-short-track-a-domicile-les-belges-sur-le-podium\/"},"wordCount":467,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/litalie-championne-olympique-du-relais-mixte-de-short-track-a-domicile-les-belges-sur-le-podium\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/02\/LItalie-championne-olympique-du-relais-mixte-de-short-track-a-domicile-les-Belges-sur-le-podium-1.png","keywords":["actu","br\u00e8ve","Jeux Olympiques 2026","JO 2026","JO d'hiver","short track"],"articleSection":["JO d'hiver 2026","Sports d'hiver"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/litalie-championne-olympique-du-relais-mixte-de-short-track-a-domicile-les-belges-sur-le-podium\/#respond"]}],"copyrightYear":"2026","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/litalie-championne-olympique-du-relais-mixte-de-short-track-a-domicile-les-belges-sur-le-podium\/","url":"https:\/\/dicodusport.fr\/blog\/litalie-championne-olympique-du-relais-mixte-de-short-track-a-domicile-les-belges-sur-le-podium\/","name":"L'Italie championne olympique du relais mixte de short-track \u00e0 domicile, les Belges sur le podium","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/litalie-championne-olympique-du-relais-mixte-de-short-track-a-domicile-les-belges-sur-le-podium\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/litalie-championne-olympique-du-relais-mixte-de-short-track-a-domicile-les-belges-sur-le-podium\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/02\/LItalie-championne-olympique-du-relais-mixte-de-short-track-a-domicile-les-Belges-sur-le-podium-1.png","datePublished":"2026-02-10T12:19:14+00:00","dateModified":"2026-02-10T14:32:46+00:00","description":"SHORT-TRACK JO 2026 - L'Italie a ma\u00eetris\u00e9 la finale A du relais mixte et s'est offert le titre olympique devant le Canada et la Belgique. La France est 7\u00e8me.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/litalie-championne-olympique-du-relais-mixte-de-short-track-a-domicile-les-belges-sur-le-podium\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/litalie-championne-olympique-du-relais-mixte-de-short-track-a-domicile-les-belges-sur-le-podium\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/litalie-championne-olympique-du-relais-mixte-de-short-track-a-domicile-les-belges-sur-le-podium\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/02\/LItalie-championne-olympique-du-relais-mixte-de-short-track-a-domicile-les-Belges-sur-le-podium-1.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/02\/LItalie-championne-olympique-du-relais-mixte-de-short-track-a-domicile-les-Belges-sur-le-podium-1.png","width":1200,"height":674,"caption":"L'Italie championne olympique du relais mixte de short-track \u00e0 domicile, les Belges sur le podium"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/litalie-championne-olympique-du-relais-mixte-de-short-track-a-domicile-les-belges-sur-le-podium\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"L&rsquo;Italie championne olympique du relais mixte de short-track \u00e0 domicile, les Belges sur le podium"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/0eaf70b33d703a1a66b1155ac1bda018","name":"Pierre Gorce","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/03\/IMG_20211214_233053_722-150x150.jpg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/03\/IMG_20211214_233053_722-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/03\/IMG_20211214_233053_722-150x150.jpg","caption":"Pierre Gorce"},"description":"Couteau suisse venant tout droit de Haute-Savoie. Habitu\u00e9 \u00e0 regarder du sport depuis petit, j'en ai maintenant fait mon m\u00e9tier. Des sports d'hiver au surf, en passant par le tennis, la F1, le handball et l'athl\u00e9tisme, j'essaie d'avoir mes yeux sur l'enti\u00e8ret\u00e9 de l'actualit\u00e9. Jeune homme berc\u00e9 par les exploits de Jean-Baptiste Grange, Sebastian Vettel et des Experts. Membre de la g\u00e9n\u00e9ration 1999 comme Luka Doncic, Sydney McLaughlin, Lando Norris et Loana Lecomte, mais avec beaucoup moins de talent qu'eux.","sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/pierregorce12"],"birthDate":"1999-08-29","url":"https:\/\/dicodusport.fr\/blog\/author\/pierreg\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/646135","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=646135"}],"version-history":[{"count":5,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/646135\/revisions"}],"predecessor-version":[{"id":646273,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/646135\/revisions\/646273"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/646303"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=646135"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=646135"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=646135"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}