{"id":646356,"date":"2026-02-10T19:16:06","date_gmt":"2026-02-10T18:16:06","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=646356&#038;preview=true&#038;preview_id=646356"},"modified":"2026-02-10T22:39:47","modified_gmt":"2026-02-10T21:39:47","slug":"seule-au-monde-julia-taubitz-est-sacree-championne-olympique-de-luge-individuelle-aux-jo-2026","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/seule-au-monde-julia-taubitz-est-sacree-championne-olympique-de-luge-individuelle-aux-jo-2026\/","title":{"rendered":"Seule au monde, Julia Taubitz est sacr\u00e9e championne olympique de luge individuelle aux JO 2026"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>LUGE JO &#8211; D&rsquo;une r\u00e9gularit\u00e9 folle, Julia Taubitz d\u00e9croche le sacre olympique sur l&rsquo;\u00e9preuve individuelle avec pr\u00e8s d&rsquo;une seconde d&rsquo;avance sur sa dauphine.<\/em><\/strong><\/p>\n<ul style=\"text-align: justify;\">\n<li><strong><strong>\u00c0 ce sujet \u2013\u00a0<a href=\"https:\/\/dicodusport.fr\/blog\/calendrier-jo-dhiver-2026-programme-complet-des-epreuves-jour-par-jour-milan-cortina\/\">Calendrier JO d\u2019hiver 2026 : programme complet des \u00e9preuves, jour par jour (Milan-Cortina)<\/a><\/strong><\/strong><\/li>\n<\/ul>\n<div id=\"mvp-content-main\" class=\"left relative\" style=\"text-align: justify;\">\n<h2 style=\"text-align: justify;\">Julia Taubitz en p\u00f4le avec une confortable avance, une grande bagarre derri\u00e8re elle en pr\u00e9vision<\/h2>\n<p style=\"text-align: justify;\">L&rsquo;identit\u00e9 de la championne olympique n&rsquo;\u00e9tait pas le plus grand d\u00e9bat avant cette derni\u00e8re manche ! <strong>Julia Taubitz<\/strong> a \u00e9t\u00e9 la plus r\u00e9guli\u00e8re, s&rsquo;adjugeant le record de la piste sur sa 2<sup>e<\/sup> manche (52.550). L&rsquo;Allemande, octuple championne du monde, n&rsquo;\u00e9tait qu&rsquo;\u00e0 une manche de d\u00e9crocher le plus beau des m\u00e9taux, pour sa toute premi\u00e8re m\u00e9daille olympique, la seule qui manquait \u00e0 son palmar\u00e8s. La seule sous les 2:38 au cumul des trois manches (2:37.918). En revanche, la bataille pour le podium promettait d&rsquo;\u00eatre folle, avec cinq femmes qui se tenaient en deux dixi\u00e8mes et m\u00eame une dizaine de concurrentes pour r\u00eaver au podium.<\/p>\n<p style=\"text-align: justify;\">Pourtant, \u00e0 l&rsquo;issue des deux premi\u00e8res manches, c&rsquo;est \u00e0 une autre Allemande que l&rsquo;on pensait pour le titre, au moins pour la bagarre. La jeune <strong>Merle Fr\u00e4bel<\/strong> (22 ans) avait r\u00e9ussi deux manches tr\u00e8s probantes ce lundi, avec le record de la piste d\u00e8s son premier run (52.590). Sa deuxi\u00e8me sortie confirmait sa forme (52.659), m\u00eame si sa compatriote lui a chip\u00e9 le record de la piste. Mais d\u00e8s la premi\u00e8re manche de ce mardi, la troisi\u00e8me des quatre runs, elle passe totalement \u00e0 c\u00f4t\u00e9. Un d\u00e9part catastrophique, un chrono qui sanctionne la prestation en 54.144. Elle recule au 10<sup>e<\/sup> rang. Si le podium n&rsquo;\u00e9tait pas infaisable.<\/p>\n<ul>\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet \u2013 <a href=\"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-jo-2026-classement-mis-a-jour-en-temps-reel\/\">Tableau des m\u00e9dailles JO 2026 : classement mis \u00e0 jour en temps r\u00e9el<\/a><\/strong><\/li>\n<\/ul>\n<h2 style=\"text-align: justify;\">Une derni\u00e8re manche qui n&rsquo;a fait que confirmer les positions<\/h2>\n<p style=\"text-align: justify;\">Pouvait-elle se remettre de ce coup du sort ? Premi\u00e8re des favorites \u00e0 s&rsquo;\u00e9lancer, l&rsquo;Allemande r\u00e9alise un run en 52.779. Il y a eu r\u00e9action, sans que le chrono soit aussi bon que celui de son premier run. Mais elle a montr\u00e9 que son 3<sup>e<\/sup> run n&rsquo;\u00e9tait qu&rsquo;une erreur. Pas suffisant pour aller chercher la m\u00e9daille. Elle pourra sans doute nourrir de tr\u00e8s gros regrets et termine \u00e0 la 8<sup>e<\/sup> place. Leader de la Coupe du monde, l&rsquo;Autrichienne <strong>Lisa Schulte<\/strong> n&rsquo;aura pas vraiment trouv\u00e9 le bon tempo et ne terminera pas dans le top 5.<\/p>\n<div class=\"QpPSMb\" style=\"text-align: justify;\">\n<div class=\"DoxwDb\">\n<div class=\"PZPZlf ssJ7i B5dxMb\" style=\"text-align: justify;\" role=\"heading\" aria-level=\"2\" data-attrid=\"title\">L&rsquo;Italienne <strong>Sandra Robatscher<\/strong> est la premi\u00e8re \u00e0 passer sous les 3:32 au cumul des quatre manches, en 3:31.732, apr\u00e8s un chrono de 52.905 sur son dernier run. Insuffisant l\u00e0 aussi pour le podium. Doubl\u00e9e par sa compatriote <strong>Verena Hofer<\/strong> (3:31.645), elle pouvait encore viser la m\u00e9daille, puisqu&rsquo;il ne restait que trois concurrentes derri\u00e8re elle. Elle sera finalement au pied du podium (4<sup>e<\/sup>). Elle a d&rsquo;abord \u00e9t\u00e9 doubl\u00e9e par l&rsquo;Am\u00e9ricaine <strong>Ashley Farquharson<\/strong>. Au terme d&rsquo;une manche monumentale, o\u00f9 elle est pass\u00e9e devant, derri\u00e8re, puis encore devant, elle sauve sa place sur la bo\u00eete. Puis par la Lettonne <strong>El\u012bna Ieva Bota<\/strong>, qui a su limiter la casse. Finalement, cette derni\u00e8re manche a \u00e9t\u00e9 intense, mais n&rsquo;a fait que confirmer les positions.<\/div>\n<\/div>\n<\/div>\n<div style=\"text-align: justify;\" role=\"heading\" aria-level=\"2\" data-attrid=\"title\"><\/div>\n<div style=\"text-align: justify;\" role=\"heading\" aria-level=\"2\" data-attrid=\"title\">Il ne restait que <strong>Julia Taubitz<\/strong>. Et quitte \u00e0 \u00eatre championne olympique, l&rsquo;Allemande a voulu montrer qu&rsquo;elle \u00e9tait la patronne. En 52.707, elle r\u00e9alise le meilleur temps de la derni\u00e8re manche. Si elle n&rsquo;a pas \u00e9t\u00e9 aussi rapide que le lundi, c&rsquo;est elle qui aura \u00e9t\u00e9 la plus forte, avec trois meilleurs temps sur les quatre manches. La seule sous les 3:31 (3:30.625), elle rel\u00e8gue <strong>El\u012bna Ieva Bota<\/strong> \u00e0 pr\u00e8s d&rsquo;une seconde. Elle \u00e9tait seule au monde.<\/div>\n<\/div>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"de\">\ud83c\udfc5 Olympia-Gold f\u00fcr Julia Taubitz! Die 29-J\u00e4hrige vom WSC Oberwiesenthal triumphiert im Rodel-Einsitzer \u2013 ein starkes Zeichen aus dem s\u00e4chsischen Wintersportzentrum. Gl\u00fcckwunsch!<a href=\"https:\/\/twitter.com\/hashtag\/milanocortina2026?src=hash&amp;ref_src=twsrc%5Etfw\">#milanocortina2026<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/deinsportunsereaufgabe?src=hash&amp;ref_src=twsrc%5Etfw\">#deinsportunsereaufgabe<\/a> <a href=\"https:\/\/t.co\/bucPBJOPHO\">pic.twitter.com\/bucPBJOPHO<\/a><\/p>\n<p>\u2014 Innenministerium Sachsen (@SMIsachsen) <a href=\"https:\/\/twitter.com\/SMIsachsen\/status\/2021286078141841798?ref_src=twsrc%5Etfw\">February 10, 2026<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h3 style=\"text-align: justify;\">Dicodusport vous conseille<\/h3>\n<div class=\"vlp-link-container vlp-layout-article\"><a href=\"https:\/\/dicodusport.fr\/blog\/en-demonstration-max-langenhan-sacre-en-luge-individuel-aux-jo-2026\/\" class=\"vlp-link\" title=\"En d\u00e9monstration, Max Langenhan sacr\u00e9 en luge individuelle aux JO 2026\"><\/a><div class=\"vlp-layout-zone-side\"><div class=\"vlp-block-4 vlp-link-image\"><img loading=\"lazy\" decoding=\"async\" style=\"max-width: 792px;\" width=\"792\" height=\"445\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/02\/En-demonstration-Max-Langenhan-sacre-en-luge-individuelle-aux-JO-2026.png\" class=\"attachment-800x445 size-800x445\" alt=\"En d\u00e9monstration, Max Langenhan sacr\u00e9 en luge individuelle aux JO 2026\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/02\/En-demonstration-Max-Langenhan-sacre-en-luge-individuelle-aux-JO-2026.png 1200w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/02\/En-demonstration-Max-Langenhan-sacre-en-luge-individuelle-aux-JO-2026-300x169.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/02\/En-demonstration-Max-Langenhan-sacre-en-luge-individuelle-aux-JO-2026-1024x575.png 1024w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/02\/En-demonstration-Max-Langenhan-sacre-en-luge-individuelle-aux-JO-2026-768x431.png 768w\" sizes=\"auto, (max-width: 792px) 100vw, 792px\" \/><\/div><\/div><div class=\"vlp-layout-zone-main\"><div class=\"vlp-block-0 vlp-link-title\">En d\u00e9monstration, Max Langenhan sacr\u00e9 en luge individuelle aux JO 2026<\/div><div class=\"vlp-block-1 vlp-link-summary\">L'Allemand Max Langenhan sacr\u00e9 en luge individuelle apr\u00e8s une d\u00e9monstration, avec quatre records olympiques en quatre manches.<\/div><div class=\"vlp-block-2 vlp-link-button\">Lire l'article<\/div><div class=\"vlp-block-3 vlp-link-url\">dicodusport.fr<\/div><\/div><\/div>\n<div id=\"gtx-trans\" style=\"position: absolute; left: -14px; top: 40.9091px;\">\n<div class=\"gtx-trans-icon\" style=\"text-align: justify;\"><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>LUGE JO &#8211; D&rsquo;une r\u00e9gularit\u00e9 folle, Julia Taubitz d\u00e9croche le sacre olympique sur l&rsquo;\u00e9preuve individuelle avec pr\u00e8s d&rsquo;une seconde d&rsquo;avance sur sa dauphine.<\/p>\n","protected":false},"author":83,"featured_media":646409,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[44003,2313],"tags":[32415,16878,46887,46888,47094],"class_list":["post-646356","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-jo-hiver-2026","category-sports-dhiver","tag-actu","tag-breve","tag-jeux-olympiques-2026","tag-jo-2026","tag-jo-dhiver"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Seule au monde, Julia Taubitz est sacr\u00e9e championne olympique de luge individuelle aux JO 2026<\/title>\n<meta name=\"description\" content=\"LUGE JO - D&#039;une r\u00e9gularit\u00e9 folle, Julia Taubitz d\u00e9croche le sacre olympique sur l&#039;\u00e9preuve individuelle avec pr\u00e8s d&#039;une seconde d&#039;avance sur sa dauphine.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/seule-au-monde-julia-taubitz-est-sacree-championne-olympique-de-luge-individuelle-aux-jo-2026\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Seule au monde, Julia Taubitz est sacr\u00e9e championne olympique de luge individuelle aux JO 2026\" \/>\n<meta property=\"og:description\" content=\"LUGE JO - D&#039;une r\u00e9gularit\u00e9 folle, Julia Taubitz d\u00e9croche le sacre olympique sur l&#039;\u00e9preuve individuelle avec pr\u00e8s d&#039;une seconde d&#039;avance sur sa dauphine.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/seule-au-monde-julia-taubitz-est-sacree-championne-olympique-de-luge-individuelle-aux-jo-2026\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-10T18:16:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-10T21:39:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/02\/Seule-au-monde-Julia-Taubitz-est-sacree-championne-olympique-de-luge-individuelle-aux-JO-2026-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Etienne Goursaud\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Seule au monde, Julia Taubitz est sacr\u00e9e championne olympique de luge individuelle aux JO 2026\" \/>\n<meta name=\"twitter:creator\" content=\"@dicodusport\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/seule-au-monde-julia-taubitz-est-sacree-championne-olympique-de-luge-individuelle-aux-jo-2026\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/seule-au-monde-julia-taubitz-est-sacree-championne-olympique-de-luge-individuelle-aux-jo-2026\\\/\"},\"author\":{\"name\":\"Etienne Goursaud\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/d603dd7da31fb2b46c82b9835a77ec13\"},\"headline\":\"Seule au monde, Julia Taubitz est sacr\u00e9e championne olympique de luge individuelle aux JO 2026\",\"datePublished\":\"2026-02-10T18:16:06+00:00\",\"dateModified\":\"2026-02-10T21:39:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/seule-au-monde-julia-taubitz-est-sacree-championne-olympique-de-luge-individuelle-aux-jo-2026\\\/\"},\"wordCount\":773,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/seule-au-monde-julia-taubitz-est-sacree-championne-olympique-de-luge-individuelle-aux-jo-2026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Seule-au-monde-Julia-Taubitz-est-sacree-championne-olympique-de-luge-individuelle-aux-JO-2026-1.png\",\"keywords\":[\"actu\",\"br\u00e8ve\",\"Jeux Olympiques 2026\",\"JO 2026\",\"JO d'hiver\"],\"articleSection\":[\"JO d'hiver 2026\",\"Sports d'hiver\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/seule-au-monde-julia-taubitz-est-sacree-championne-olympique-de-luge-individuelle-aux-jo-2026\\\/#respond\"]}],\"copyrightYear\":\"2026\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/seule-au-monde-julia-taubitz-est-sacree-championne-olympique-de-luge-individuelle-aux-jo-2026\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/seule-au-monde-julia-taubitz-est-sacree-championne-olympique-de-luge-individuelle-aux-jo-2026\\\/\",\"name\":\"Seule au monde, Julia Taubitz est sacr\u00e9e championne olympique de luge individuelle aux JO 2026\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/seule-au-monde-julia-taubitz-est-sacree-championne-olympique-de-luge-individuelle-aux-jo-2026\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/seule-au-monde-julia-taubitz-est-sacree-championne-olympique-de-luge-individuelle-aux-jo-2026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Seule-au-monde-Julia-Taubitz-est-sacree-championne-olympique-de-luge-individuelle-aux-JO-2026-1.png\",\"datePublished\":\"2026-02-10T18:16:06+00:00\",\"dateModified\":\"2026-02-10T21:39:47+00:00\",\"description\":\"LUGE JO - D'une r\u00e9gularit\u00e9 folle, Julia Taubitz d\u00e9croche le sacre olympique sur l'\u00e9preuve individuelle avec pr\u00e8s d'une seconde d'avance sur sa dauphine.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/seule-au-monde-julia-taubitz-est-sacree-championne-olympique-de-luge-individuelle-aux-jo-2026\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/seule-au-monde-julia-taubitz-est-sacree-championne-olympique-de-luge-individuelle-aux-jo-2026\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/seule-au-monde-julia-taubitz-est-sacree-championne-olympique-de-luge-individuelle-aux-jo-2026\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Seule-au-monde-Julia-Taubitz-est-sacree-championne-olympique-de-luge-individuelle-aux-JO-2026-1.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Seule-au-monde-Julia-Taubitz-est-sacree-championne-olympique-de-luge-individuelle-aux-JO-2026-1.png\",\"width\":1200,\"height\":674,\"caption\":\"Seule au monde, Julia Taubitz est sacr\u00e9e championne olympique de luge individuelle aux JO 2026\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/seule-au-monde-julia-taubitz-est-sacree-championne-olympique-de-luge-individuelle-aux-jo-2026\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Seule au monde, Julia Taubitz est sacr\u00e9e championne olympique de luge individuelle aux JO 2026\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/d603dd7da31fb2b46c82b9835a77ec13\",\"name\":\"Etienne Goursaud\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/410122264_10231602061736049_5565839791558026645_n-150x150.jpg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/410122264_10231602061736049_5565839791558026645_n-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/410122264_10231602061736049_5565839791558026645_n-150x150.jpg\",\"caption\":\"Etienne Goursaud\"},\"description\":\"Journaliste et amoureux de sport. Ancien footballeur reconverti athl\u00e8te quand ses muscles le laissent tranquille. \u00c9lev\u00e9 \u00e0 la sauce des exploits de Thomas Voeckler en 2004, du dernier essai de l\u00e9gende de Eunice Barber \u00e0 la longueur lors des championnats du monde d'athl\u00e9tisme de 2003 mais aussi Zidane, Omeyer et Titou Lamaison.\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/etienne-goursaud\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Seule au monde, Julia Taubitz est sacr\u00e9e championne olympique de luge individuelle aux JO 2026","description":"LUGE JO - D'une r\u00e9gularit\u00e9 folle, Julia Taubitz d\u00e9croche le sacre olympique sur l'\u00e9preuve individuelle avec pr\u00e8s d'une seconde d'avance sur sa dauphine.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/seule-au-monde-julia-taubitz-est-sacree-championne-olympique-de-luge-individuelle-aux-jo-2026\/","og_locale":"fr_FR","og_type":"article","og_title":"Seule au monde, Julia Taubitz est sacr\u00e9e championne olympique de luge individuelle aux JO 2026","og_description":"LUGE JO - D'une r\u00e9gularit\u00e9 folle, Julia Taubitz d\u00e9croche le sacre olympique sur l'\u00e9preuve individuelle avec pr\u00e8s d'une seconde d'avance sur sa dauphine.","og_url":"https:\/\/dicodusport.fr\/blog\/seule-au-monde-julia-taubitz-est-sacree-championne-olympique-de-luge-individuelle-aux-jo-2026\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2026-02-10T18:16:06+00:00","article_modified_time":"2026-02-10T21:39:47+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/02\/Seule-au-monde-Julia-Taubitz-est-sacree-championne-olympique-de-luge-individuelle-aux-JO-2026-1.png","type":"image\/png"}],"author":"Etienne Goursaud","twitter_card":"summary_large_image","twitter_title":"Seule au monde, Julia Taubitz est sacr\u00e9e championne olympique de luge individuelle aux JO 2026","twitter_creator":"@dicodusport","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/seule-au-monde-julia-taubitz-est-sacree-championne-olympique-de-luge-individuelle-aux-jo-2026\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/seule-au-monde-julia-taubitz-est-sacree-championne-olympique-de-luge-individuelle-aux-jo-2026\/"},"author":{"name":"Etienne Goursaud","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/d603dd7da31fb2b46c82b9835a77ec13"},"headline":"Seule au monde, Julia Taubitz est sacr\u00e9e championne olympique de luge individuelle aux JO 2026","datePublished":"2026-02-10T18:16:06+00:00","dateModified":"2026-02-10T21:39:47+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/seule-au-monde-julia-taubitz-est-sacree-championne-olympique-de-luge-individuelle-aux-jo-2026\/"},"wordCount":773,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/seule-au-monde-julia-taubitz-est-sacree-championne-olympique-de-luge-individuelle-aux-jo-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/02\/Seule-au-monde-Julia-Taubitz-est-sacree-championne-olympique-de-luge-individuelle-aux-JO-2026-1.png","keywords":["actu","br\u00e8ve","Jeux Olympiques 2026","JO 2026","JO d'hiver"],"articleSection":["JO d'hiver 2026","Sports d'hiver"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/seule-au-monde-julia-taubitz-est-sacree-championne-olympique-de-luge-individuelle-aux-jo-2026\/#respond"]}],"copyrightYear":"2026","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/seule-au-monde-julia-taubitz-est-sacree-championne-olympique-de-luge-individuelle-aux-jo-2026\/","url":"https:\/\/dicodusport.fr\/blog\/seule-au-monde-julia-taubitz-est-sacree-championne-olympique-de-luge-individuelle-aux-jo-2026\/","name":"Seule au monde, Julia Taubitz est sacr\u00e9e championne olympique de luge individuelle aux JO 2026","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/seule-au-monde-julia-taubitz-est-sacree-championne-olympique-de-luge-individuelle-aux-jo-2026\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/seule-au-monde-julia-taubitz-est-sacree-championne-olympique-de-luge-individuelle-aux-jo-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/02\/Seule-au-monde-Julia-Taubitz-est-sacree-championne-olympique-de-luge-individuelle-aux-JO-2026-1.png","datePublished":"2026-02-10T18:16:06+00:00","dateModified":"2026-02-10T21:39:47+00:00","description":"LUGE JO - D'une r\u00e9gularit\u00e9 folle, Julia Taubitz d\u00e9croche le sacre olympique sur l'\u00e9preuve individuelle avec pr\u00e8s d'une seconde d'avance sur sa dauphine.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/seule-au-monde-julia-taubitz-est-sacree-championne-olympique-de-luge-individuelle-aux-jo-2026\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/seule-au-monde-julia-taubitz-est-sacree-championne-olympique-de-luge-individuelle-aux-jo-2026\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/seule-au-monde-julia-taubitz-est-sacree-championne-olympique-de-luge-individuelle-aux-jo-2026\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/02\/Seule-au-monde-Julia-Taubitz-est-sacree-championne-olympique-de-luge-individuelle-aux-JO-2026-1.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/02\/Seule-au-monde-Julia-Taubitz-est-sacree-championne-olympique-de-luge-individuelle-aux-JO-2026-1.png","width":1200,"height":674,"caption":"Seule au monde, Julia Taubitz est sacr\u00e9e championne olympique de luge individuelle aux JO 2026"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/seule-au-monde-julia-taubitz-est-sacree-championne-olympique-de-luge-individuelle-aux-jo-2026\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Seule au monde, Julia Taubitz est sacr\u00e9e championne olympique de luge individuelle aux JO 2026"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/d603dd7da31fb2b46c82b9835a77ec13","name":"Etienne Goursaud","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/410122264_10231602061736049_5565839791558026645_n-150x150.jpg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/410122264_10231602061736049_5565839791558026645_n-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/410122264_10231602061736049_5565839791558026645_n-150x150.jpg","caption":"Etienne Goursaud"},"description":"Journaliste et amoureux de sport. Ancien footballeur reconverti athl\u00e8te quand ses muscles le laissent tranquille. \u00c9lev\u00e9 \u00e0 la sauce des exploits de Thomas Voeckler en 2004, du dernier essai de l\u00e9gende de Eunice Barber \u00e0 la longueur lors des championnats du monde d'athl\u00e9tisme de 2003 mais aussi Zidane, Omeyer et Titou Lamaison.","url":"https:\/\/dicodusport.fr\/blog\/author\/etienne-goursaud\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/646356","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/83"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=646356"}],"version-history":[{"count":5,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/646356\/revisions"}],"predecessor-version":[{"id":646376,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/646356\/revisions\/646376"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/646409"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=646356"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=646356"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=646356"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}