{"id":646708,"date":"2026-02-12T10:39:08","date_gmt":"2026-02-12T09:39:08","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=646708&#038;preview=true&#038;preview_id=646708"},"modified":"2026-02-12T12:00:02","modified_gmt":"2026-02-12T11:00:02","slug":"pas-dexploit-pour-paul-andrea-gay-et-arthur-offel-de-villaucourt-dans-la-deuxieme-manche-de-qualification-en-ski-de-bosses","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/pas-dexploit-pour-paul-andrea-gay-et-arthur-offel-de-villaucourt-dans-la-deuxieme-manche-de-qualification-en-ski-de-bosses\/","title":{"rendered":"Pas d&rsquo;exploit pour Paul Andr\u00e9a Gay et Arthur Offel de Villaucourt dans la deuxi\u00e8me manche de qualification en ski de bosses"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>SKI FREESTYLE JO 2026 &#8211; Arthur Offel de Villaucourt et Paul Andr\u00e9a Gay terminent 25\u00e8me et 26\u00e8me des qualifications en ski de bosses. Pas de finale pour les Bleus.<\/em><\/strong><\/p>\n<ul style=\"text-align: justify;\">\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet \u2013\u00a0<a href=\"https:\/\/dicodusport.fr\/blog\/calendrier-jo-dhiver-2026-programme-complet-des-epreuves-jour-par-jour-milan-cortina\/\">Calendrier JO d\u2019hiver 2026 : programme complet des \u00e9preuves, jour par jour (Milan-Cortina)<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Le compteur de Fran\u00e7ais qualifi\u00e9s en finale du ski de bosses restera bloqu\u00e9 \u00e0 deux, ce qui constitue d\u00e9j\u00e0 une belle performance. La marche \u00e9tait trop haute pour <strong>Paul Andr\u00e9a Gay<\/strong> et <strong>Arthur Offel de Villaucourt<\/strong>. Les deux Tricolores \u00e9taient engag\u00e9s ce jeudi matin dans la deuxi\u00e8me manche de qualification du ski de bosses, avec pour objectif de rejoindre leurs compatriotes <strong>Benjamin Cavet<\/strong> et <strong>Thibaud Mouille<\/strong>, qualifi\u00e9s directement pour la finale.<\/p>\n<div class=\"vlp-link-container vlp-layout-article\"><a href=\"https:\/\/dicodusport.fr\/blog\/benjamin-cavet-et-thibaud-mouille-qualifies-en-finale-de-ski-de-bosses-des-jo-2026\/\" class=\"vlp-link\" title=\"Benjamin Cavet et Thibaud Mouille qualifi\u00e9s en finale de ski de bosses des JO 2026\"><\/a><div class=\"vlp-layout-zone-side\"><div class=\"vlp-block-4 vlp-link-image\"><img loading=\"lazy\" decoding=\"async\" style=\"max-width: 792px;\" width=\"792\" height=\"445\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/02\/Benjamin-Cavet-et-Thibaud-Mouille-qualifies-en-finale-de-ski-de-bosses-des-JO-2026-1.png\" class=\"attachment-800x445 size-800x445\" alt=\"Benjamin Cavet et Thibaud Mouille qualifi\u00e9s en finale de ski de bosses des JO 2026\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/02\/Benjamin-Cavet-et-Thibaud-Mouille-qualifies-en-finale-de-ski-de-bosses-des-JO-2026-1.png 1200w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/02\/Benjamin-Cavet-et-Thibaud-Mouille-qualifies-en-finale-de-ski-de-bosses-des-JO-2026-1-300x169.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/02\/Benjamin-Cavet-et-Thibaud-Mouille-qualifies-en-finale-de-ski-de-bosses-des-JO-2026-1-1024x575.png 1024w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/02\/Benjamin-Cavet-et-Thibaud-Mouille-qualifies-en-finale-de-ski-de-bosses-des-JO-2026-1-768x431.png 768w\" sizes=\"auto, (max-width: 792px) 100vw, 792px\" \/><\/div><\/div><div class=\"vlp-layout-zone-main\"><div class=\"vlp-block-0 vlp-link-title\">Benjamin Cavet et Thibaud Mouille qualifi\u00e9s en finale de ski de bosses des JO 2026<\/div><div class=\"vlp-block-1 vlp-link-summary\">Les Fran\u00e7ais Benjamin Cavet et Thibaud Mouille se sont qualifi\u00e9s pour la finale de ski de bosses hommes.<\/div><div class=\"vlp-block-2 vlp-link-button\">Lire l'article<\/div><div class=\"vlp-block-3 vlp-link-url\">dicodusport.fr<\/div><\/div><\/div>\n<h2 style=\"text-align: justify;\">Les deux Tricolores en progr\u00e8s, mais la marche \u00e9tait trop haute<\/h2>\n<p style=\"text-align: justify;\"><strong>Arthur Offel de Villaucourt<\/strong> \u00e9tait le premier \u00e0 s&rsquo;\u00e9lancer. Il avait obtenu un score de <strong>68.32<\/strong> la veille. M\u00eame s&rsquo;il a parfois subi, il am\u00e9liore nettement son total avec <strong>73.02<\/strong> points. Une progression insuffisante pour int\u00e9grer la finale. Pour rappel, seule la meilleure note des deux runs est retenue pour entrer en finale. Il termine 25e des qualifications.<\/p>\n<p style=\"text-align: justify;\"><strong>Paul Andr\u00e9a Gay<\/strong>, qui s&rsquo;\u00e9lan\u00e7ait en dernier, \u00e9tait compl\u00e8tement pass\u00e9 \u00e0 c\u00f4t\u00e9 de sa premi\u00e8re manche avec <strong>35.39<\/strong> points. Son avantage r\u00e9sidait dans les nombreuses informations r\u00e9colt\u00e9es sur les runs pr\u00e9c\u00e9dents. Contrairement \u00e0 la veille, il a pu poser son run, mais l\u2019ensemble est rest\u00e9 insuffisant. Avec <strong>70.54<\/strong> points, il prend la 26e place.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">Ski freestyle \u26f7<\/p>\n<p>Ca ne passera pas en finale pour Arthur de Villaucourt et Paul Andr\u00e9a Gay qui finissent 25e et 26e des qualifications.<\/p>\n<p>Rendez-vous \u00e0 12h15 pour la finale avec Benjamin Cavet et Thibaud Mouille.<a href=\"https:\/\/twitter.com\/hashtag\/AllezLesBleus?src=hash&amp;ref_src=twsrc%5Etfw\">#AllezLesBleus<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/MilanoCortina2026?src=hash&amp;ref_src=twsrc%5Etfw\">#MilanoCortina2026<\/a><\/p>\n<p>\u2014 Equipe France (@EquipeFRA) <a href=\"https:\/\/twitter.com\/EquipeFRA\/status\/2021882946169307247?ref_src=twsrc%5Etfw\">February 12, 2026<\/a><\/p><\/blockquote>\n<p style=\"text-align: justify;\"><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 style=\"text-align: justify;\">Cooper Woods impressionne dans cette 2e manche<\/h2>\n<p style=\"text-align: justify;\">\u00c0 noter que le Japonais <strong>Takuya Shimakawa<\/strong> a r\u00e9alis\u00e9 un tr\u00e8s gros score de <strong>78.27<\/strong> lors de cette deuxi\u00e8me manche de qualification. Il s&rsquo;agit du 6e meilleur total parmi les qualifi\u00e9s. S&rsquo;il r\u00e9cup\u00e8re bien de son run matinal, il sera \u00e0 surveiller dans la course aux m\u00e9dailles. Pour rappel, chez les femmes, il fallait r\u00e9aliser 78.00 pour d\u00e9crocher le bronze, une m\u00e9daille obtenue par <strong>Perrine Laffont<\/strong> au bout du suspense.<\/p>\n<p style=\"text-align: justify;\">Mais le plus impressionnant reste <strong>Cooper Woods<\/strong>. L&rsquo;Australien a sign\u00e9 une manche \u00e0 plus de 80 points (<strong>80.46<\/strong>), soit le deuxi\u00e8me meilleur score des qualifi\u00e9s. S&rsquo;il reproduit cette performance en finale, il sera un s\u00e9rieux candidat \u00e0 la m\u00e9daille. Il efface ainsi la d\u00e9ception d&rsquo;un premier run l\u00e9g\u00e8rement manqu\u00e9 (<strong>73.67<\/strong>). M\u00eame enjeu que pour le Japonais : la r\u00e9cup\u00e9ration avant une finale qui arrive tr\u00e8s vite.<\/p>\n<ul style=\"text-align: justify;\">\n<li><strong>\u00c0 ce sujet \u2013\u00a0<a href=\"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-jo-2026-classement-mis-a-jour-en-temps-reel\/\">Tableau des m\u00e9dailles JO 2026 : classement mis \u00e0 jour en temps r\u00e9el<\/a><\/strong><\/li>\n<\/ul>\n<div id=\"gtx-trans\" style=\"position: absolute; left: -14px; top: 40.9091px;\">\n<div class=\"gtx-trans-icon\" style=\"text-align: justify;\"><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>SKI FREESTYLE JO 2026 &#8211; Arthur Offel de Villaucourt et Paul Andr\u00e9a Gay terminent 25\u00e8me et 26\u00e8me des qualifications en ski de bosses. Pas de finale pour les Bleus.<\/p>\n","protected":false},"author":83,"featured_media":646720,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[44003,9217],"tags":[32415,16878,46887,46888,47094],"class_list":["post-646708","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-jo-hiver-2026","category-ski","tag-actu","tag-breve","tag-jeux-olympiques-2026","tag-jo-2026","tag-jo-dhiver"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Pas d&#039;exploit pour Paul Andr\u00e9a Gay et Arthur Offel de Villaucourt dans la deuxi\u00e8me manche de qualification en ski de bosses<\/title>\n<meta name=\"description\" content=\"SKI FREESTYLE JO 2026 - Arthur Offel de Villaucourt et Paul Andr\u00e9a Gay terminent 25\u00e8me et 26\u00e8me des qualifications en ski de bosses. Pas de finale pour les Bleus.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/pas-dexploit-pour-paul-andrea-gay-et-arthur-offel-de-villaucourt-dans-la-deuxieme-manche-de-qualification-en-ski-de-bosses\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pas d&#039;exploit pour Paul Andr\u00e9a Gay et Arthur Offel de Villaucourt dans la deuxi\u00e8me manche de qualification en ski de bosses\" \/>\n<meta property=\"og:description\" content=\"SKI FREESTYLE JO 2026 - Arthur Offel de Villaucourt et Paul Andr\u00e9a Gay terminent 25\u00e8me et 26\u00e8me des qualifications en ski de bosses. Pas de finale pour les Bleus.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/pas-dexploit-pour-paul-andrea-gay-et-arthur-offel-de-villaucourt-dans-la-deuxieme-manche-de-qualification-en-ski-de-bosses\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-12T09:39:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-12T11:00:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/02\/Pas-dexploit-pour-Paul-Andrea-Gay-et-Arthur-Offel-de-Villaucourt-dans-la-2eme-manche-de-qualifications-en-ski-de-bosses.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Etienne Goursaud\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Pas d&#039;exploit pour Paul Andr\u00e9a Gay et Arthur Offel de Villaucourt dans la deuxi\u00e8me manche de qualification en ski de bosses\" \/>\n<meta name=\"twitter:creator\" content=\"@dicodusport\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/pas-dexploit-pour-paul-andrea-gay-et-arthur-offel-de-villaucourt-dans-la-deuxieme-manche-de-qualification-en-ski-de-bosses\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/pas-dexploit-pour-paul-andrea-gay-et-arthur-offel-de-villaucourt-dans-la-deuxieme-manche-de-qualification-en-ski-de-bosses\\\/\"},\"author\":{\"name\":\"Etienne Goursaud\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/d603dd7da31fb2b46c82b9835a77ec13\"},\"headline\":\"Pas d&rsquo;exploit pour Paul Andr\u00e9a Gay et Arthur Offel de Villaucourt dans la deuxi\u00e8me manche de qualification en ski de bosses\",\"datePublished\":\"2026-02-12T09:39:08+00:00\",\"dateModified\":\"2026-02-12T11:00:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/pas-dexploit-pour-paul-andrea-gay-et-arthur-offel-de-villaucourt-dans-la-deuxieme-manche-de-qualification-en-ski-de-bosses\\\/\"},\"wordCount\":578,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/pas-dexploit-pour-paul-andrea-gay-et-arthur-offel-de-villaucourt-dans-la-deuxieme-manche-de-qualification-en-ski-de-bosses\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Pas-dexploit-pour-Paul-Andrea-Gay-et-Arthur-Offel-de-Villaucourt-dans-la-2eme-manche-de-qualifications-en-ski-de-bosses.png\",\"keywords\":[\"actu\",\"br\u00e8ve\",\"Jeux Olympiques 2026\",\"JO 2026\",\"JO d'hiver\"],\"articleSection\":[\"JO d'hiver 2026\",\"Ski\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/pas-dexploit-pour-paul-andrea-gay-et-arthur-offel-de-villaucourt-dans-la-deuxieme-manche-de-qualification-en-ski-de-bosses\\\/#respond\"]}],\"copyrightYear\":\"2026\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/pas-dexploit-pour-paul-andrea-gay-et-arthur-offel-de-villaucourt-dans-la-deuxieme-manche-de-qualification-en-ski-de-bosses\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/pas-dexploit-pour-paul-andrea-gay-et-arthur-offel-de-villaucourt-dans-la-deuxieme-manche-de-qualification-en-ski-de-bosses\\\/\",\"name\":\"Pas d'exploit pour Paul Andr\u00e9a Gay et Arthur Offel de Villaucourt dans la deuxi\u00e8me manche de qualification en ski de bosses\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/pas-dexploit-pour-paul-andrea-gay-et-arthur-offel-de-villaucourt-dans-la-deuxieme-manche-de-qualification-en-ski-de-bosses\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/pas-dexploit-pour-paul-andrea-gay-et-arthur-offel-de-villaucourt-dans-la-deuxieme-manche-de-qualification-en-ski-de-bosses\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Pas-dexploit-pour-Paul-Andrea-Gay-et-Arthur-Offel-de-Villaucourt-dans-la-2eme-manche-de-qualifications-en-ski-de-bosses.png\",\"datePublished\":\"2026-02-12T09:39:08+00:00\",\"dateModified\":\"2026-02-12T11:00:02+00:00\",\"description\":\"SKI FREESTYLE JO 2026 - Arthur Offel de Villaucourt et Paul Andr\u00e9a Gay terminent 25\u00e8me et 26\u00e8me des qualifications en ski de bosses. Pas de finale pour les Bleus.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/pas-dexploit-pour-paul-andrea-gay-et-arthur-offel-de-villaucourt-dans-la-deuxieme-manche-de-qualification-en-ski-de-bosses\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/pas-dexploit-pour-paul-andrea-gay-et-arthur-offel-de-villaucourt-dans-la-deuxieme-manche-de-qualification-en-ski-de-bosses\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/pas-dexploit-pour-paul-andrea-gay-et-arthur-offel-de-villaucourt-dans-la-deuxieme-manche-de-qualification-en-ski-de-bosses\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Pas-dexploit-pour-Paul-Andrea-Gay-et-Arthur-Offel-de-Villaucourt-dans-la-2eme-manche-de-qualifications-en-ski-de-bosses.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Pas-dexploit-pour-Paul-Andrea-Gay-et-Arthur-Offel-de-Villaucourt-dans-la-2eme-manche-de-qualifications-en-ski-de-bosses.png\",\"width\":1200,\"height\":674,\"caption\":\"Pas d'exploit pour Paul Andr\u00e9a Gay et Arthur Offel de Villaucourt dans la 2\u00e8me manche de qualifications en ski de bosses\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/pas-dexploit-pour-paul-andrea-gay-et-arthur-offel-de-villaucourt-dans-la-deuxieme-manche-de-qualification-en-ski-de-bosses\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pas d&rsquo;exploit pour Paul Andr\u00e9a Gay et Arthur Offel de Villaucourt dans la deuxi\u00e8me manche de qualification en ski de bosses\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/d603dd7da31fb2b46c82b9835a77ec13\",\"name\":\"Etienne Goursaud\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/410122264_10231602061736049_5565839791558026645_n-150x150.jpg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/410122264_10231602061736049_5565839791558026645_n-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/410122264_10231602061736049_5565839791558026645_n-150x150.jpg\",\"caption\":\"Etienne Goursaud\"},\"description\":\"Journaliste et amoureux de sport. Ancien footballeur reconverti athl\u00e8te quand ses muscles le laissent tranquille. \u00c9lev\u00e9 \u00e0 la sauce des exploits de Thomas Voeckler en 2004, du dernier essai de l\u00e9gende de Eunice Barber \u00e0 la longueur lors des championnats du monde d'athl\u00e9tisme de 2003 mais aussi Zidane, Omeyer et Titou Lamaison.\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/etienne-goursaud\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Pas d'exploit pour Paul Andr\u00e9a Gay et Arthur Offel de Villaucourt dans la deuxi\u00e8me manche de qualification en ski de bosses","description":"SKI FREESTYLE JO 2026 - Arthur Offel de Villaucourt et Paul Andr\u00e9a Gay terminent 25\u00e8me et 26\u00e8me des qualifications en ski de bosses. Pas de finale pour les Bleus.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/pas-dexploit-pour-paul-andrea-gay-et-arthur-offel-de-villaucourt-dans-la-deuxieme-manche-de-qualification-en-ski-de-bosses\/","og_locale":"fr_FR","og_type":"article","og_title":"Pas d'exploit pour Paul Andr\u00e9a Gay et Arthur Offel de Villaucourt dans la deuxi\u00e8me manche de qualification en ski de bosses","og_description":"SKI FREESTYLE JO 2026 - Arthur Offel de Villaucourt et Paul Andr\u00e9a Gay terminent 25\u00e8me et 26\u00e8me des qualifications en ski de bosses. Pas de finale pour les Bleus.","og_url":"https:\/\/dicodusport.fr\/blog\/pas-dexploit-pour-paul-andrea-gay-et-arthur-offel-de-villaucourt-dans-la-deuxieme-manche-de-qualification-en-ski-de-bosses\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2026-02-12T09:39:08+00:00","article_modified_time":"2026-02-12T11:00:02+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/02\/Pas-dexploit-pour-Paul-Andrea-Gay-et-Arthur-Offel-de-Villaucourt-dans-la-2eme-manche-de-qualifications-en-ski-de-bosses.png","type":"image\/png"}],"author":"Etienne Goursaud","twitter_card":"summary_large_image","twitter_title":"Pas d'exploit pour Paul Andr\u00e9a Gay et Arthur Offel de Villaucourt dans la deuxi\u00e8me manche de qualification en ski de bosses","twitter_creator":"@dicodusport","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/pas-dexploit-pour-paul-andrea-gay-et-arthur-offel-de-villaucourt-dans-la-deuxieme-manche-de-qualification-en-ski-de-bosses\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/pas-dexploit-pour-paul-andrea-gay-et-arthur-offel-de-villaucourt-dans-la-deuxieme-manche-de-qualification-en-ski-de-bosses\/"},"author":{"name":"Etienne Goursaud","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/d603dd7da31fb2b46c82b9835a77ec13"},"headline":"Pas d&rsquo;exploit pour Paul Andr\u00e9a Gay et Arthur Offel de Villaucourt dans la deuxi\u00e8me manche de qualification en ski de bosses","datePublished":"2026-02-12T09:39:08+00:00","dateModified":"2026-02-12T11:00:02+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/pas-dexploit-pour-paul-andrea-gay-et-arthur-offel-de-villaucourt-dans-la-deuxieme-manche-de-qualification-en-ski-de-bosses\/"},"wordCount":578,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/pas-dexploit-pour-paul-andrea-gay-et-arthur-offel-de-villaucourt-dans-la-deuxieme-manche-de-qualification-en-ski-de-bosses\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/02\/Pas-dexploit-pour-Paul-Andrea-Gay-et-Arthur-Offel-de-Villaucourt-dans-la-2eme-manche-de-qualifications-en-ski-de-bosses.png","keywords":["actu","br\u00e8ve","Jeux Olympiques 2026","JO 2026","JO d'hiver"],"articleSection":["JO d'hiver 2026","Ski"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/pas-dexploit-pour-paul-andrea-gay-et-arthur-offel-de-villaucourt-dans-la-deuxieme-manche-de-qualification-en-ski-de-bosses\/#respond"]}],"copyrightYear":"2026","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/pas-dexploit-pour-paul-andrea-gay-et-arthur-offel-de-villaucourt-dans-la-deuxieme-manche-de-qualification-en-ski-de-bosses\/","url":"https:\/\/dicodusport.fr\/blog\/pas-dexploit-pour-paul-andrea-gay-et-arthur-offel-de-villaucourt-dans-la-deuxieme-manche-de-qualification-en-ski-de-bosses\/","name":"Pas d'exploit pour Paul Andr\u00e9a Gay et Arthur Offel de Villaucourt dans la deuxi\u00e8me manche de qualification en ski de bosses","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/pas-dexploit-pour-paul-andrea-gay-et-arthur-offel-de-villaucourt-dans-la-deuxieme-manche-de-qualification-en-ski-de-bosses\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/pas-dexploit-pour-paul-andrea-gay-et-arthur-offel-de-villaucourt-dans-la-deuxieme-manche-de-qualification-en-ski-de-bosses\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/02\/Pas-dexploit-pour-Paul-Andrea-Gay-et-Arthur-Offel-de-Villaucourt-dans-la-2eme-manche-de-qualifications-en-ski-de-bosses.png","datePublished":"2026-02-12T09:39:08+00:00","dateModified":"2026-02-12T11:00:02+00:00","description":"SKI FREESTYLE JO 2026 - Arthur Offel de Villaucourt et Paul Andr\u00e9a Gay terminent 25\u00e8me et 26\u00e8me des qualifications en ski de bosses. Pas de finale pour les Bleus.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/pas-dexploit-pour-paul-andrea-gay-et-arthur-offel-de-villaucourt-dans-la-deuxieme-manche-de-qualification-en-ski-de-bosses\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/pas-dexploit-pour-paul-andrea-gay-et-arthur-offel-de-villaucourt-dans-la-deuxieme-manche-de-qualification-en-ski-de-bosses\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/pas-dexploit-pour-paul-andrea-gay-et-arthur-offel-de-villaucourt-dans-la-deuxieme-manche-de-qualification-en-ski-de-bosses\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/02\/Pas-dexploit-pour-Paul-Andrea-Gay-et-Arthur-Offel-de-Villaucourt-dans-la-2eme-manche-de-qualifications-en-ski-de-bosses.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/02\/Pas-dexploit-pour-Paul-Andrea-Gay-et-Arthur-Offel-de-Villaucourt-dans-la-2eme-manche-de-qualifications-en-ski-de-bosses.png","width":1200,"height":674,"caption":"Pas d'exploit pour Paul Andr\u00e9a Gay et Arthur Offel de Villaucourt dans la 2\u00e8me manche de qualifications en ski de bosses"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/pas-dexploit-pour-paul-andrea-gay-et-arthur-offel-de-villaucourt-dans-la-deuxieme-manche-de-qualification-en-ski-de-bosses\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Pas d&rsquo;exploit pour Paul Andr\u00e9a Gay et Arthur Offel de Villaucourt dans la deuxi\u00e8me manche de qualification en ski de bosses"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/d603dd7da31fb2b46c82b9835a77ec13","name":"Etienne Goursaud","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/410122264_10231602061736049_5565839791558026645_n-150x150.jpg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/410122264_10231602061736049_5565839791558026645_n-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/410122264_10231602061736049_5565839791558026645_n-150x150.jpg","caption":"Etienne Goursaud"},"description":"Journaliste et amoureux de sport. Ancien footballeur reconverti athl\u00e8te quand ses muscles le laissent tranquille. \u00c9lev\u00e9 \u00e0 la sauce des exploits de Thomas Voeckler en 2004, du dernier essai de l\u00e9gende de Eunice Barber \u00e0 la longueur lors des championnats du monde d'athl\u00e9tisme de 2003 mais aussi Zidane, Omeyer et Titou Lamaison.","url":"https:\/\/dicodusport.fr\/blog\/author\/etienne-goursaud\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/646708","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/83"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=646708"}],"version-history":[{"count":5,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/646708\/revisions"}],"predecessor-version":[{"id":646758,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/646708\/revisions\/646758"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/646720"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=646708"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=646708"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=646708"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}