{"id":648164,"date":"2026-02-15T16:27:17","date_gmt":"2026-02-15T15:27:17","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=648164&#038;preview=true&#038;preview_id=648164"},"modified":"2026-02-15T16:48:52","modified_gmt":"2026-02-15T15:48:52","slug":"les-bleus-de-timothy-loubineaud-elimines-de-la-poursuite-par-equipes-aux-jo-2026","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/les-bleus-de-timothy-loubineaud-elimines-de-la-poursuite-par-equipes-aux-jo-2026\/","title":{"rendered":"Les Bleus de Timothy Loubineaud \u00e9limin\u00e9s de la poursuite par \u00e9quipes aux JO 2026"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><strong>PATINAGE DE VITESSE JO 2026 &#8211; Cinqui\u00e8me\u00a0temps de la poursuite par \u00e9quipes, le trio fran\u00e7ais compos\u00e9 de Timothy Loubineaud, Valentin Thiebault et Germain Deschamps est \u00e9limin\u00e9 en quarts de finale.<\/strong><\/em><\/p>\n<ul style=\"text-align: justify;\">\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet \u2013\u00a0<a href=\"https:\/\/dicodusport.fr\/blog\/calendrier-jo-dhiver-2026-programme-complet-des-epreuves-jour-par-jour-milan-cortina\/\">Calendrier JO d\u2019hiver 2026 : programme complet des \u00e9preuves, jour par jour (Milan-Cortina)<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Il restait de l\u2019espoir pour <strong>Timothy Loubineaud<\/strong> afin d\u2019effacer les d\u00e9ceptions du 5 000 et 10 000 m\u00e8tres. Mais \u00e0 peine commenc\u00e9e, la poursuite par \u00e9quipes a pris fin pour le trio tricolore, tomb\u00e9 en quarts de finale. Pour acc\u00e9der au dernier carr\u00e9, les Fran\u00e7ais devaient imp\u00e9rativement int\u00e9grer le top 4 au terme de ces s\u00e9ries.<\/p>\n<div class=\"vlp-link-container vlp-layout-article\"><a href=\"https:\/\/dicodusport.fr\/blog\/metodej-jilek-sacre-sur-le-10000-m-des-jo-2026-en-patinage-de-vitesse-timothy-loubineaud-au-pied-du-podium\/\" class=\"vlp-link\" title=\"Metod\u011bj J\u00edlek sacr\u00e9 sur le 10000 m des JO 2026 en patinage de vitesse, Timothy Loubineaud au pied du podium\"><\/a><div class=\"vlp-layout-zone-side\"><div class=\"vlp-block-4 vlp-link-image\"><img loading=\"lazy\" decoding=\"async\" style=\"max-width: 792px;\" width=\"792\" height=\"445\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/02\/Metodej-Jilek-sacre-sur-le-10000-m-des-JO-2026-en-patinage-de-vitesse-Timothy-Loubineaud-au-pied-du-podium.png\" class=\"attachment-800x445 size-800x445\" alt=\"Metod\u011bj J\u00edlek sacr\u00e9 sur le 10000 m des JO 2026 en patinage de vitesse, Timothy Loubineaud au pied du podium\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/02\/Metodej-Jilek-sacre-sur-le-10000-m-des-JO-2026-en-patinage-de-vitesse-Timothy-Loubineaud-au-pied-du-podium.png 1200w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/02\/Metodej-Jilek-sacre-sur-le-10000-m-des-JO-2026-en-patinage-de-vitesse-Timothy-Loubineaud-au-pied-du-podium-300x169.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/02\/Metodej-Jilek-sacre-sur-le-10000-m-des-JO-2026-en-patinage-de-vitesse-Timothy-Loubineaud-au-pied-du-podium-1024x575.png 1024w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/02\/Metodej-Jilek-sacre-sur-le-10000-m-des-JO-2026-en-patinage-de-vitesse-Timothy-Loubineaud-au-pied-du-podium-768x431.png 768w\" sizes=\"auto, (max-width: 792px) 100vw, 792px\" \/><\/div><\/div><div class=\"vlp-layout-zone-main\"><div class=\"vlp-block-0 vlp-link-title\">Metod\u011bj J\u00edlek sacr\u00e9 sur le 10000 m des JO 2026 en patinage de vitesse, Timothy Loubineaud au pied du podium<\/div><div class=\"vlp-block-1 vlp-link-summary\">PATINAGE DE VITESSE JO 2026 - Metod\u011bj J\u00edlek remporte le 10000 m. Quatri\u00e8me, Timothy Loubineaud \u00e9choue \u00e0 trois secondes du podium.<\/div><div class=\"vlp-block-2 vlp-link-button\">Lire l'article<\/div><div class=\"vlp-block-3 vlp-link-url\">dicodusport.fr<\/div><\/div><\/div>\n<h2 style=\"text-align: justify;\">Pas de demies pour les Bleus<\/h2>\n<p style=\"text-align: justify;\">Tandis que les h\u00f4tes frappaient un grand coup face aux Am\u00e9ricains, les Bleus \u00e9taient quant \u00e0 eux au d\u00e9part de la derni\u00e8re s\u00e9rie. Un long temps d\u2019attente mais qui leur permettait de savoir le temps \u00e0 r\u00e9aliser pour se placer parmi ces quatre meilleures nations et pr\u00e9tendantes au podium. Pour le leader tricolore et ses deux partenaires <strong>Valentin Thiebault<\/strong> et <strong>Germain Deschamps<\/strong>, la donne \u00e9tait simple au moment de s&rsquo;\u00e9lancer : terminer devant les Pays-Bas en moins de 3\u203244\u203336 ou acter l&rsquo;int\u00e9gralit\u00e9 des tours en moins de 3\u203241\u203366 et cela peu importe le chrono des N\u00e9erlandais.<\/p>\n<p style=\"text-align: justify;\">Longtemps \u00e0 la bagarre pour cette quatri\u00e8me et derni\u00e8re place qualificative, la fin de course pesait lourd. Notamment dans les jambes de <strong>Germain Deschamps<\/strong>, qui peinait \u00e0 rester au contact de ses partenaires. Malheureusement le temps final, pris en compte au passage du dernier patineur, ne permettait pas aux Fran\u00e7ais de prendre place en demies, il leur manque une seconde. Ils terminent ainsi aux portes du top 4, \u00e0 la 5<sup>\u00e8me<\/sup> place. Italie, USA, Chine et Pays-Bas se disputeront le titre.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">D\u00e9ception pour les Bleus \ud83c\uddeb\ud83c\uddf7 sur la poursuite par \u00e9quipes en patinage de vitesse : une cinqui\u00e8me place qui ne leur permet pas de valider leur ticket pour les demi-finales<\/p>\n<p>Les Jeux Olympiques de <a href=\"https:\/\/twitter.com\/hashtag\/MilanoCortina2026?src=hash&amp;ref_src=twsrc%5Etfw\">#MilanoCortina2026<\/a>, c&rsquo;est en int\u00e9gralit\u00e9 sur Eurosport et HBO Max <a href=\"https:\/\/t.co\/8zzOwO0TvM\">pic.twitter.com\/8zzOwO0TvM<\/a><\/p>\n<p>\u2014 Eurosport France (@Eurosport_FR) <a href=\"https:\/\/twitter.com\/Eurosport_FR\/status\/2023056084773007522?ref_src=twsrc%5Etfw\">February 15, 2026<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<div id=\"gtx-trans\" style=\"position: absolute; left: -14px; top: 40.9091px;\">\n<div class=\"gtx-trans-icon\" style=\"text-align: justify;\"><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>PATINAGE DE VITESSE JO 2026 &#8211; Cinqui\u00e8me\u00a0temps de la poursuite par \u00e9quipes, le trio fran\u00e7ais compos\u00e9 de Timothy Loubineaud, Valentin Thiebault et Germain Deschamps est \u00e9limin\u00e9 en quarts de finale.<\/p>\n","protected":false},"author":18,"featured_media":648188,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[44003,2313],"tags":[32415,16878,46887,46888,47094],"class_list":["post-648164","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-jo-hiver-2026","category-sports-dhiver","tag-actu","tag-breve","tag-jeux-olympiques-2026","tag-jo-2026","tag-jo-dhiver"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Les Bleus de Timothy Loubineaud \u00e9limin\u00e9s de la poursuite par \u00e9quipes aux JO 2026<\/title>\n<meta name=\"description\" content=\"PATINAGE DE VITESSE JO 2026 - Cinqui\u00e8me\u00a0temps de la poursuite par \u00e9quipes, le trio fran\u00e7ais est \u00e9limin\u00e9 en quarts de finale.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/les-bleus-de-timothy-loubineaud-elimines-de-la-poursuite-par-equipes-aux-jo-2026\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les Bleus de Timothy Loubineaud \u00e9limin\u00e9s de la poursuite par \u00e9quipes aux JO 2026\" \/>\n<meta property=\"og:description\" content=\"PATINAGE DE VITESSE JO 2026 - Cinqui\u00e8me\u00a0temps de la poursuite par \u00e9quipes, le trio fran\u00e7ais est \u00e9limin\u00e9 en quarts de finale.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/les-bleus-de-timothy-loubineaud-elimines-de-la-poursuite-par-equipes-aux-jo-2026\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/soocube\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-15T15:27:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-15T15:48:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/02\/Les-Bleus-de-Timothy-Loubineaud-elimines-de-la-poursuite-par-equipes-hommes-aux-JO-2026.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Sophie Clapier\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Les Bleus de Timothy Loubineaud \u00e9limin\u00e9s de la poursuite par \u00e9quipes aux JO 2026\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/soocube\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-bleus-de-timothy-loubineaud-elimines-de-la-poursuite-par-equipes-aux-jo-2026\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-bleus-de-timothy-loubineaud-elimines-de-la-poursuite-par-equipes-aux-jo-2026\\\/\"},\"author\":{\"name\":\"Sophie Clapier\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/416c975648aca9da8839bdfe333a21c9\"},\"headline\":\"Les Bleus de Timothy Loubineaud \u00e9limin\u00e9s de la poursuite par \u00e9quipes aux JO 2026\",\"datePublished\":\"2026-02-15T15:27:17+00:00\",\"dateModified\":\"2026-02-15T15:48:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-bleus-de-timothy-loubineaud-elimines-de-la-poursuite-par-equipes-aux-jo-2026\\\/\"},\"wordCount\":460,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-bleus-de-timothy-loubineaud-elimines-de-la-poursuite-par-equipes-aux-jo-2026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Les-Bleus-de-Timothy-Loubineaud-elimines-de-la-poursuite-par-equipes-hommes-aux-JO-2026.png\",\"keywords\":[\"actu\",\"br\u00e8ve\",\"Jeux Olympiques 2026\",\"JO 2026\",\"JO d'hiver\"],\"articleSection\":[\"JO d'hiver 2026\",\"Sports d'hiver\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-bleus-de-timothy-loubineaud-elimines-de-la-poursuite-par-equipes-aux-jo-2026\\\/#respond\"]}],\"copyrightYear\":\"2026\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-bleus-de-timothy-loubineaud-elimines-de-la-poursuite-par-equipes-aux-jo-2026\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-bleus-de-timothy-loubineaud-elimines-de-la-poursuite-par-equipes-aux-jo-2026\\\/\",\"name\":\"Les Bleus de Timothy Loubineaud \u00e9limin\u00e9s de la poursuite par \u00e9quipes aux JO 2026\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-bleus-de-timothy-loubineaud-elimines-de-la-poursuite-par-equipes-aux-jo-2026\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-bleus-de-timothy-loubineaud-elimines-de-la-poursuite-par-equipes-aux-jo-2026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Les-Bleus-de-Timothy-Loubineaud-elimines-de-la-poursuite-par-equipes-hommes-aux-JO-2026.png\",\"datePublished\":\"2026-02-15T15:27:17+00:00\",\"dateModified\":\"2026-02-15T15:48:52+00:00\",\"description\":\"PATINAGE DE VITESSE JO 2026 - Cinqui\u00e8me\u00a0temps de la poursuite par \u00e9quipes, le trio fran\u00e7ais est \u00e9limin\u00e9 en quarts de finale.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-bleus-de-timothy-loubineaud-elimines-de-la-poursuite-par-equipes-aux-jo-2026\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-bleus-de-timothy-loubineaud-elimines-de-la-poursuite-par-equipes-aux-jo-2026\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-bleus-de-timothy-loubineaud-elimines-de-la-poursuite-par-equipes-aux-jo-2026\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Les-Bleus-de-Timothy-Loubineaud-elimines-de-la-poursuite-par-equipes-hommes-aux-JO-2026.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Les-Bleus-de-Timothy-Loubineaud-elimines-de-la-poursuite-par-equipes-hommes-aux-JO-2026.png\",\"width\":1200,\"height\":674,\"caption\":\"Les Bleus de Timothy Loubineaud \u00e9limin\u00e9s de la poursuite par \u00e9quipes hommes aux JO 2026\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-bleus-de-timothy-loubineaud-elimines-de-la-poursuite-par-equipes-aux-jo-2026\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les Bleus de Timothy Loubineaud \u00e9limin\u00e9s de la poursuite par \u00e9quipes aux JO 2026\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/416c975648aca9da8839bdfe333a21c9\",\"name\":\"Sophie Clapier\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Sophie-Clapier-150x150.jpg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Sophie-Clapier-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Sophie-Clapier-150x150.jpg\",\"caption\":\"Sophie Clapier\"},\"description\":\"Journaliste\\\/r\u00e9dactrice depuis janvier 2016 - Passionn\u00e9e de sport depuis toujours, j\u2019en ai pratiqu\u00e9 quelques-uns. Judo, football, handball ou encore tennis, je n\u2019ai jamais pu me mettre d\u2019accord sur un en particulier. Mais \u00e7a, c\u2019\u00e9tait avant de d\u00e9couvrir le basket, devenu mon sport de pr\u00e9dilection. Les actions NBA, le All-Star Week-end, la fureur des Game 7 pendant les playoffs ou mieux, lors des Finals, this is why we play. Team Spurs T.P, je m\u2019accroche encore \u00e0 Gregg Popovich (don\u2019t leave !). Team chef Curry, je souhaite qu\u2019il finisse aux Warriors (staaaay !). Non, il n\u2019y a pas qu\u2019eux, des petits nouveaux -et des petites nouvelles \u00e9videmment- arrivent chaque jour dans toutes les disciplines et cr\u00e9ent de nouveaux exploits. Alors pour les grands \u00e9v\u00e9nements et comp\u00e9titions internationales, vive les pulsations 240\\\/minutes et le d\u00e9fibrillateur pas loin, et allez les Bleu(e)s ! C\u2019est s\u00fbr, j\u2019aurai plus vu ma vie sur un terrain de sport, mais \u00e0 d\u00e9faut d\u2019en faire en haut niveau, je le partage avec vous.\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/soocube\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/soocube\",\"admin\"],\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/sophie\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Les Bleus de Timothy Loubineaud \u00e9limin\u00e9s de la poursuite par \u00e9quipes aux JO 2026","description":"PATINAGE DE VITESSE JO 2026 - Cinqui\u00e8me\u00a0temps de la poursuite par \u00e9quipes, le trio fran\u00e7ais est \u00e9limin\u00e9 en quarts de finale.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/les-bleus-de-timothy-loubineaud-elimines-de-la-poursuite-par-equipes-aux-jo-2026\/","og_locale":"fr_FR","og_type":"article","og_title":"Les Bleus de Timothy Loubineaud \u00e9limin\u00e9s de la poursuite par \u00e9quipes aux JO 2026","og_description":"PATINAGE DE VITESSE JO 2026 - Cinqui\u00e8me\u00a0temps de la poursuite par \u00e9quipes, le trio fran\u00e7ais est \u00e9limin\u00e9 en quarts de finale.","og_url":"https:\/\/dicodusport.fr\/blog\/les-bleus-de-timothy-loubineaud-elimines-de-la-poursuite-par-equipes-aux-jo-2026\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/soocube","article_published_time":"2026-02-15T15:27:17+00:00","article_modified_time":"2026-02-15T15:48:52+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/02\/Les-Bleus-de-Timothy-Loubineaud-elimines-de-la-poursuite-par-equipes-hommes-aux-JO-2026.png","type":"image\/png"}],"author":"Sophie Clapier","twitter_card":"summary_large_image","twitter_title":"Les Bleus de Timothy Loubineaud \u00e9limin\u00e9s de la poursuite par \u00e9quipes aux JO 2026","twitter_creator":"@https:\/\/twitter.com\/soocube","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/les-bleus-de-timothy-loubineaud-elimines-de-la-poursuite-par-equipes-aux-jo-2026\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/les-bleus-de-timothy-loubineaud-elimines-de-la-poursuite-par-equipes-aux-jo-2026\/"},"author":{"name":"Sophie Clapier","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/416c975648aca9da8839bdfe333a21c9"},"headline":"Les Bleus de Timothy Loubineaud \u00e9limin\u00e9s de la poursuite par \u00e9quipes aux JO 2026","datePublished":"2026-02-15T15:27:17+00:00","dateModified":"2026-02-15T15:48:52+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/les-bleus-de-timothy-loubineaud-elimines-de-la-poursuite-par-equipes-aux-jo-2026\/"},"wordCount":460,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/les-bleus-de-timothy-loubineaud-elimines-de-la-poursuite-par-equipes-aux-jo-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/02\/Les-Bleus-de-Timothy-Loubineaud-elimines-de-la-poursuite-par-equipes-hommes-aux-JO-2026.png","keywords":["actu","br\u00e8ve","Jeux Olympiques 2026","JO 2026","JO d'hiver"],"articleSection":["JO d'hiver 2026","Sports d'hiver"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/les-bleus-de-timothy-loubineaud-elimines-de-la-poursuite-par-equipes-aux-jo-2026\/#respond"]}],"copyrightYear":"2026","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/les-bleus-de-timothy-loubineaud-elimines-de-la-poursuite-par-equipes-aux-jo-2026\/","url":"https:\/\/dicodusport.fr\/blog\/les-bleus-de-timothy-loubineaud-elimines-de-la-poursuite-par-equipes-aux-jo-2026\/","name":"Les Bleus de Timothy Loubineaud \u00e9limin\u00e9s de la poursuite par \u00e9quipes aux JO 2026","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/les-bleus-de-timothy-loubineaud-elimines-de-la-poursuite-par-equipes-aux-jo-2026\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/les-bleus-de-timothy-loubineaud-elimines-de-la-poursuite-par-equipes-aux-jo-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/02\/Les-Bleus-de-Timothy-Loubineaud-elimines-de-la-poursuite-par-equipes-hommes-aux-JO-2026.png","datePublished":"2026-02-15T15:27:17+00:00","dateModified":"2026-02-15T15:48:52+00:00","description":"PATINAGE DE VITESSE JO 2026 - Cinqui\u00e8me\u00a0temps de la poursuite par \u00e9quipes, le trio fran\u00e7ais est \u00e9limin\u00e9 en quarts de finale.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/les-bleus-de-timothy-loubineaud-elimines-de-la-poursuite-par-equipes-aux-jo-2026\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/les-bleus-de-timothy-loubineaud-elimines-de-la-poursuite-par-equipes-aux-jo-2026\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/les-bleus-de-timothy-loubineaud-elimines-de-la-poursuite-par-equipes-aux-jo-2026\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/02\/Les-Bleus-de-Timothy-Loubineaud-elimines-de-la-poursuite-par-equipes-hommes-aux-JO-2026.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/02\/Les-Bleus-de-Timothy-Loubineaud-elimines-de-la-poursuite-par-equipes-hommes-aux-JO-2026.png","width":1200,"height":674,"caption":"Les Bleus de Timothy Loubineaud \u00e9limin\u00e9s de la poursuite par \u00e9quipes hommes aux JO 2026"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/les-bleus-de-timothy-loubineaud-elimines-de-la-poursuite-par-equipes-aux-jo-2026\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Les Bleus de Timothy Loubineaud \u00e9limin\u00e9s de la poursuite par \u00e9quipes aux JO 2026"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/416c975648aca9da8839bdfe333a21c9","name":"Sophie Clapier","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Sophie-Clapier-150x150.jpg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Sophie-Clapier-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Sophie-Clapier-150x150.jpg","caption":"Sophie Clapier"},"description":"Journaliste\/r\u00e9dactrice depuis janvier 2016 - Passionn\u00e9e de sport depuis toujours, j\u2019en ai pratiqu\u00e9 quelques-uns. Judo, football, handball ou encore tennis, je n\u2019ai jamais pu me mettre d\u2019accord sur un en particulier. Mais \u00e7a, c\u2019\u00e9tait avant de d\u00e9couvrir le basket, devenu mon sport de pr\u00e9dilection. Les actions NBA, le All-Star Week-end, la fureur des Game 7 pendant les playoffs ou mieux, lors des Finals, this is why we play. Team Spurs T.P, je m\u2019accroche encore \u00e0 Gregg Popovich (don\u2019t leave !). Team chef Curry, je souhaite qu\u2019il finisse aux Warriors (staaaay !). Non, il n\u2019y a pas qu\u2019eux, des petits nouveaux -et des petites nouvelles \u00e9videmment- arrivent chaque jour dans toutes les disciplines et cr\u00e9ent de nouveaux exploits. Alors pour les grands \u00e9v\u00e9nements et comp\u00e9titions internationales, vive les pulsations 240\/minutes et le d\u00e9fibrillateur pas loin, et allez les Bleu(e)s ! C\u2019est s\u00fbr, j\u2019aurai plus vu ma vie sur un terrain de sport, mais \u00e0 d\u00e9faut d\u2019en faire en haut niveau, je le partage avec vous.","sameAs":["https:\/\/www.facebook.com\/soocube","https:\/\/x.com\/https:\/\/twitter.com\/soocube","admin"],"url":"https:\/\/dicodusport.fr\/blog\/author\/sophie\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/648164","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=648164"}],"version-history":[{"count":6,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/648164\/revisions"}],"predecessor-version":[{"id":648205,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/648164\/revisions\/648205"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/648188"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=648164"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=648164"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=648164"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}