{"id":649568,"date":"2026-02-21T15:20:28","date_gmt":"2026-02-21T14:20:28","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=649568&#038;preview=true&#038;preview_id=649568"},"modified":"2026-02-28T17:52:14","modified_gmt":"2026-02-28T16:52:14","slug":"atp-500-le-tableau-du-tournoi-de-dubai-2026","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/atp-500-le-tableau-du-tournoi-de-dubai-2026\/","title":{"rendered":"ATP 500 : Le tableau du tournoi de Duba\u00ef 2026"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>ATP 500 \u2013 Le tournoi de Duba\u00ef a lieu du 23 au 28 f\u00e9vrier. Qui succ\u00e9dera \u00e0 Stefanos Tsitsipas ? Voici le tableau du tournoi.<\/em><\/strong><\/p>\n<p><a href=\"https:\/\/www.atptour.com\/en\/scores\/current\/dubai\/495\/draws\" target=\"_blank\" rel=\"noopener\"><span style=\"font-size: 24px;\"><strong>Le tableau complet<\/strong><\/span><\/a><\/p>\n<h2>Finale<\/h2>\n<p><strong>Medvedev<\/strong> bat Griekspoor (forfait)<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ATP 500 \u2013 Le tournoi de Duba\u00ef a lieu du 23 au 28 f\u00e9vrier. Qui succ\u00e9dera \u00e0 Stefanos Tsitsipas ? Voici le tableau du tournoi.<\/p>\n","protected":false},"author":12,"featured_media":649851,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[2302],"tags":[16878],"class_list":["post-649568","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tennis","tag-breve"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>ATP 500 : Le tableau du tournoi de Duba\u00ef 2026<\/title>\n<meta name=\"description\" content=\"ATP 500 \u2013 Le tournoi de Duba\u00ef a lieu du 23 au 28 f\u00e9vrier. Qui succ\u00e9dera \u00e0 Stefanos Tsitsipas ? Voici le tableau du tournoi.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/atp-500-le-tableau-du-tournoi-de-dubai-2026\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ATP 500 : Le tableau du tournoi de Duba\u00ef 2026\" \/>\n<meta property=\"og:description\" content=\"ATP 500 \u2013 Le tournoi de Duba\u00ef a lieu du 23 au 28 f\u00e9vrier. Qui succ\u00e9dera \u00e0 Stefanos Tsitsipas ? Voici le tableau du tournoi.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/atp-500-le-tableau-du-tournoi-de-dubai-2026\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-21T14:20:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-28T16:52:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/02\/ATP-500-Le-tableau-du-tournoi-de-Dubai-2026.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Arlette Yeye\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"ATP 500 : Le tableau du tournoi de Duba\u00ef 2026\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Shiclette94\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/atp-500-le-tableau-du-tournoi-de-dubai-2026\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/atp-500-le-tableau-du-tournoi-de-dubai-2026\/\"},\"author\":{\"name\":\"Arlette Yeye\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cce96fa88785bd8573e3d43078ac8c79\"},\"headline\":\"ATP 500 : Le tableau du tournoi de Duba\u00ef 2026\",\"datePublished\":\"2026-02-21T14:20:28+00:00\",\"dateModified\":\"2026-02-28T16:52:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/atp-500-le-tableau-du-tournoi-de-dubai-2026\/\"},\"wordCount\":37,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/atp-500-le-tableau-du-tournoi-de-dubai-2026\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/02\/ATP-500-Le-tableau-du-tournoi-de-Dubai-2026.png\",\"keywords\":[\"br\u00e8ve\"],\"articleSection\":[\"Tennis\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/atp-500-le-tableau-du-tournoi-de-dubai-2026\/#respond\"]}],\"copyrightYear\":\"2026\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/atp-500-le-tableau-du-tournoi-de-dubai-2026\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/atp-500-le-tableau-du-tournoi-de-dubai-2026\/\",\"name\":\"ATP 500 : Le tableau du tournoi de Duba\u00ef 2026\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/atp-500-le-tableau-du-tournoi-de-dubai-2026\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/atp-500-le-tableau-du-tournoi-de-dubai-2026\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/02\/ATP-500-Le-tableau-du-tournoi-de-Dubai-2026.png\",\"datePublished\":\"2026-02-21T14:20:28+00:00\",\"dateModified\":\"2026-02-28T16:52:14+00:00\",\"description\":\"ATP 500 \u2013 Le tournoi de Duba\u00ef a lieu du 23 au 28 f\u00e9vrier. Qui succ\u00e9dera \u00e0 Stefanos Tsitsipas ? Voici le tableau du tournoi.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/atp-500-le-tableau-du-tournoi-de-dubai-2026\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/atp-500-le-tableau-du-tournoi-de-dubai-2026\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/atp-500-le-tableau-du-tournoi-de-dubai-2026\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/02\/ATP-500-Le-tableau-du-tournoi-de-Dubai-2026.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/02\/ATP-500-Le-tableau-du-tournoi-de-Dubai-2026.png\",\"width\":1200,\"height\":674,\"caption\":\"ATP 500 Le tableau du tournoi de Duba\u00ef 2026\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/atp-500-le-tableau-du-tournoi-de-dubai-2026\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ATP 500 : Le tableau du tournoi de Duba\u00ef 2026\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cce96fa88785bd8573e3d43078ac8c79\",\"name\":\"Arlette Yeye\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/dca4a6239e6d708e46c45d60e160de6c?s=96&d=wp_user_avatar&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/dca4a6239e6d708e46c45d60e160de6c?s=96&d=wp_user_avatar&r=g\",\"caption\":\"Arlette Yeye\"},\"description\":\"Journaliste\/r\u00e9dactrice depuis septembre 2015 - Supportrice de Chelsea, j'ai pour sports de pr\u00e9dilection le handball, l'athl\u00e9tisme et le tennis. Si je tweete plus vite que mon ombre, vous pouvez aussi me retrouver les week-ends sur les playgrounds de Bruxelles pour un petit foot ou basket entre potes. Parcourir la France, l'Europe et plus si affinit\u00e9s pour suivre mes sportifs pr\u00e9f\u00e9r\u00e9s ? Mon kif ! Et c'est avec plaisir que je partage les r\u00e9sultats des sports populaires mais \u00e9galement plus confidentiels pour Dicodusport.\",\"sameAs\":[\"https:\/\/x.com\/https:\/\/twitter.com\/Shiclette94\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/arlette\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"ATP 500 : Le tableau du tournoi de Duba\u00ef 2026","description":"ATP 500 \u2013 Le tournoi de Duba\u00ef a lieu du 23 au 28 f\u00e9vrier. Qui succ\u00e9dera \u00e0 Stefanos Tsitsipas ? Voici le tableau du tournoi.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/atp-500-le-tableau-du-tournoi-de-dubai-2026\/","og_locale":"fr_FR","og_type":"article","og_title":"ATP 500 : Le tableau du tournoi de Duba\u00ef 2026","og_description":"ATP 500 \u2013 Le tournoi de Duba\u00ef a lieu du 23 au 28 f\u00e9vrier. Qui succ\u00e9dera \u00e0 Stefanos Tsitsipas ? Voici le tableau du tournoi.","og_url":"https:\/\/dicodusport.fr\/blog\/atp-500-le-tableau-du-tournoi-de-dubai-2026\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2026-02-21T14:20:28+00:00","article_modified_time":"2026-02-28T16:52:14+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/02\/ATP-500-Le-tableau-du-tournoi-de-Dubai-2026.png","type":"image\/png"}],"author":"Arlette Yeye","twitter_card":"summary_large_image","twitter_title":"ATP 500 : Le tableau du tournoi de Duba\u00ef 2026","twitter_creator":"@https:\/\/twitter.com\/Shiclette94","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/atp-500-le-tableau-du-tournoi-de-dubai-2026\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/atp-500-le-tableau-du-tournoi-de-dubai-2026\/"},"author":{"name":"Arlette Yeye","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cce96fa88785bd8573e3d43078ac8c79"},"headline":"ATP 500 : Le tableau du tournoi de Duba\u00ef 2026","datePublished":"2026-02-21T14:20:28+00:00","dateModified":"2026-02-28T16:52:14+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/atp-500-le-tableau-du-tournoi-de-dubai-2026\/"},"wordCount":37,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/atp-500-le-tableau-du-tournoi-de-dubai-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/02\/ATP-500-Le-tableau-du-tournoi-de-Dubai-2026.png","keywords":["br\u00e8ve"],"articleSection":["Tennis"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/atp-500-le-tableau-du-tournoi-de-dubai-2026\/#respond"]}],"copyrightYear":"2026","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/atp-500-le-tableau-du-tournoi-de-dubai-2026\/","url":"https:\/\/dicodusport.fr\/blog\/atp-500-le-tableau-du-tournoi-de-dubai-2026\/","name":"ATP 500 : Le tableau du tournoi de Duba\u00ef 2026","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/atp-500-le-tableau-du-tournoi-de-dubai-2026\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/atp-500-le-tableau-du-tournoi-de-dubai-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/02\/ATP-500-Le-tableau-du-tournoi-de-Dubai-2026.png","datePublished":"2026-02-21T14:20:28+00:00","dateModified":"2026-02-28T16:52:14+00:00","description":"ATP 500 \u2013 Le tournoi de Duba\u00ef a lieu du 23 au 28 f\u00e9vrier. Qui succ\u00e9dera \u00e0 Stefanos Tsitsipas ? Voici le tableau du tournoi.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/atp-500-le-tableau-du-tournoi-de-dubai-2026\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/atp-500-le-tableau-du-tournoi-de-dubai-2026\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/atp-500-le-tableau-du-tournoi-de-dubai-2026\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/02\/ATP-500-Le-tableau-du-tournoi-de-Dubai-2026.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/02\/ATP-500-Le-tableau-du-tournoi-de-Dubai-2026.png","width":1200,"height":674,"caption":"ATP 500 Le tableau du tournoi de Duba\u00ef 2026"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/atp-500-le-tableau-du-tournoi-de-dubai-2026\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"ATP 500 : Le tableau du tournoi de Duba\u00ef 2026"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cce96fa88785bd8573e3d43078ac8c79","name":"Arlette Yeye","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/dca4a6239e6d708e46c45d60e160de6c?s=96&d=wp_user_avatar&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/dca4a6239e6d708e46c45d60e160de6c?s=96&d=wp_user_avatar&r=g","caption":"Arlette Yeye"},"description":"Journaliste\/r\u00e9dactrice depuis septembre 2015 - Supportrice de Chelsea, j'ai pour sports de pr\u00e9dilection le handball, l'athl\u00e9tisme et le tennis. Si je tweete plus vite que mon ombre, vous pouvez aussi me retrouver les week-ends sur les playgrounds de Bruxelles pour un petit foot ou basket entre potes. Parcourir la France, l'Europe et plus si affinit\u00e9s pour suivre mes sportifs pr\u00e9f\u00e9r\u00e9s ? Mon kif ! Et c'est avec plaisir que je partage les r\u00e9sultats des sports populaires mais \u00e9galement plus confidentiels pour Dicodusport.","sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/Shiclette94"],"url":"https:\/\/dicodusport.fr\/blog\/author\/arlette\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/649568","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=649568"}],"version-history":[{"count":5,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/649568\/revisions"}],"predecessor-version":[{"id":651606,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/649568\/revisions\/651606"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/649851"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=649568"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=649568"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=649568"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}