{"id":653260,"date":"2026-03-07T13:27:49","date_gmt":"2026-03-07T12:27:49","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=653260&#038;preview=true&#038;preview_id=653260"},"modified":"2026-03-07T13:55:36","modified_gmt":"2026-03-07T12:55:36","slug":"double-chinois-sur-le-sprint-categorie-debout-du-para-biathlon-pas-de-podium-pour-les-bleus","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/double-chinois-sur-le-sprint-categorie-debout-du-para-biathlon-pas-de-podium-pour-les-bleus\/","title":{"rendered":"Doubl\u00e9 chinois sur le sprint cat\u00e9gorie debout du para biathlon, pas de podium pour les Bleus"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>JEUX PARALYMPIQUES DE MILAN CORTINA 2026 &#8211; Le Chinois Jiayun Cai a remport\u00e9 la m\u00e9daille d&rsquo;or de l&rsquo;\u00e9preuve du sprint debout du para biathlon. Il m\u00e8ne un doubl\u00e9 chinois et les deux Fran\u00e7ais Benjamin Daviet et Karl Tabouret terminent 7\u00e8me et 12\u00e8me.<\/em><\/strong><\/p>\n<ul>\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/calendrier-des-jeux-paralympiques-dhiver-2026-programme-complet-des-epreuves-jour-par-jour-milan-cortina\/\">Calendrier des Jeux Paralympiques d&rsquo;hiver 2026 : Programme complet des \u00e9preuves jour par jour \u00e0 Milan-Cortina<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Lors de ce premier jour de finales des Jeux Paralympiques de Milan-Cortina 2026, avait lieu l\u2019\u00e9preuve de sprint cat\u00e9gorie debout de para biathlon. Les r\u00e8gles sont sensiblement les m\u00eames que celles que l\u2019on conna\u00eet dans le biathlon olympique \u00e0 quelques exceptions pr\u00e8s. Les deux tirs sont ici deux tirs couch\u00e9s et non un couch\u00e9 puis un debout.<\/p>\n<p style=\"text-align: justify;\">De plus, dans un souci d\u2019\u00e9quit\u00e9, les para-athl\u00e8tes poss\u00e8dent chacun un coefficient d\u00e9termin\u00e9 en fonction de leur niveau de handicap allant de 0,80 \u00e0 1. L\u2019\u00e9cart de temps est pond\u00e9r\u00e9 en direct, donc on peut se fier aux temps que l\u2019on voit sur les \u00e9crans. Enfin, les hommes partent sans carabine sur eux, celle-ci les attend directement sur le pas de tir.<\/p>\n<p style=\"text-align: justify;\">Aujourd\u2019hui, vingt para-biathl\u00e8tes prenaient le d\u00e9part de ce sprint cat\u00e9gorie debout. Parmi eux, deux Fran\u00e7ais tentaient leur chance : le jeune <strong>Karl Tabouret<\/strong> et l\u2019exp\u00e9riment\u00e9 <strong>Benjamin Daviet<\/strong>.<\/p>\n<div class=\"vlp-link-container vlp-layout-article\"><a href=\"https:\/\/dicodusport.fr\/blog\/hernandez-bauchet-daviet-les-chances-de-medailles-francaises-aux-jeux-paralympiques-2026\/\" class=\"vlp-link\" title=\"Hernandez, Bauchet, Daviet\u2026 les chances de m\u00e9dailles fran\u00e7aises aux Jeux Paralympiques 2026\"><\/a><div class=\"vlp-layout-zone-side\"><div class=\"vlp-block-4 vlp-link-image\"><img loading=\"lazy\" decoding=\"async\" style=\"max-width: 792px;\" width=\"792\" height=\"445\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/03\/Hernandez-Bauchet-Daviet-les-chances-de-medailles-francaises-aux-Jeux-Paralympiques-2026.png\" class=\"attachment-800x445 size-800x445\" alt=\"Hernandez, Bauchet, Daviet les chances de m\u00e9dailles fran\u00e7aises aux Jeux Paralympiques 2026\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/03\/Hernandez-Bauchet-Daviet-les-chances-de-medailles-francaises-aux-Jeux-Paralympiques-2026.png 1200w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/03\/Hernandez-Bauchet-Daviet-les-chances-de-medailles-francaises-aux-Jeux-Paralympiques-2026-300x169.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/03\/Hernandez-Bauchet-Daviet-les-chances-de-medailles-francaises-aux-Jeux-Paralympiques-2026-1024x575.png 1024w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/03\/Hernandez-Bauchet-Daviet-les-chances-de-medailles-francaises-aux-Jeux-Paralympiques-2026-768x431.png 768w\" sizes=\"auto, (max-width: 792px) 100vw, 792px\" \/><\/div><\/div><div class=\"vlp-layout-zone-main\"><div class=\"vlp-block-0 vlp-link-title\">Hernandez, Bauchet, Daviet\u2026 les chances de m\u00e9dailles fran\u00e7aises aux Jeux Paralympiques 2026<\/div><div class=\"vlp-block-1 vlp-link-summary\">Les Jeux Paralympiques de Milan-Cortina ouvrent leurs portes le 6 mars avec une petite d\u00e9l\u00e9gation tricolore. Petite\u2026 mais costaude ! Dicodusport vous pr\u00e9sente les chances de m\u00e9dailles fran\u00e7aises durant cette dizaine.<\/div><div class=\"vlp-block-2 vlp-link-button\">Lire l'article<\/div><div class=\"vlp-block-3 vlp-link-url\">dicodusport.fr<\/div><\/div><\/div>\n<h2>Jiayun Cai impressionnant, pas de podium pour les Bleus<\/h2>\n<p style=\"text-align: justify;\">Le premier Tricolore \u00e0 partir est <strong>Karl Tabouret<\/strong>, dossard 14. En forme sur les skis, il a commis une faute sur le premier tir mais, malgr\u00e9 \u00e7a, est rest\u00e9 tr\u00e8s bien plac\u00e9 \u00e0 l\u2019issue de celui-ci. Malheureusement, le Fran\u00e7ais ajoutera deux fautes suppl\u00e9mentaires et terminera 12<sup>\u00e8me<\/sup> de sa premi\u00e8re course paralympique. <strong>Benjamin Daviet<\/strong> avait le dernier dossard, le 20. Parti doucement sur les skis, il a n\u00e9anmoins r\u00e9ussi le plein sur le premier tir et est ressorti 7<sup>\u00e8me<\/sup> \u00e0 l\u2019issue de celui-ci. \u00c0 nouveau parfait sur le second tir, il a gard\u00e9 cette place jusqu\u2019\u00e0 la ligne d\u2019arriv\u00e9e.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">\u2744\ufe0f <a href=\"https:\/\/twitter.com\/hashtag\/MilanoCortina2026?src=hash&amp;ref_src=twsrc%5Etfw\">#MilanoCortina2026<\/a> | \u274c Pas de m\u00e9daille pour nos Fran\u00e7ais malheureusement sur le sprint en para biathlon debout : Benjamin Daviet est 7e, Karl Tabouret 11e.<\/p>\n<p>\ud83d\udcfa Suivez les Jeux en direct : <a href=\"https:\/\/t.co\/2YyyGIAfdo\">https:\/\/t.co\/2YyyGIAfdo<\/a> <a href=\"https:\/\/t.co\/h6rQ9xdgV9\">pic.twitter.com\/h6rQ9xdgV9<\/a><\/p>\n<p>\u2014 francetvsport (@francetvsport) <a href=\"https:\/\/twitter.com\/francetvsport\/status\/2030256538749653379?ref_src=twsrc%5Etfw\">March 7, 2026<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p style=\"text-align: justify;\">Parall\u00e8lement \u00e0 nos Bleus, le Chinois <strong>Jiayun Cai<\/strong> a \u00e9t\u00e9 impeccable ! Sans aucune faute au tir et sp\u00e9cialiste du ski de fond, il a su tout mettre en place pour remporter l\u2019or aujourd\u2019hui. Nous avons assist\u00e9 \u00e0 un doubl\u00e9 chinois puisque <strong>Xiaobin Liu<\/strong> (+21.8 secondes) se classe deuxi\u00e8me tandis que l\u2019Allemand <strong>Marco Maier<\/strong> (+28.8 secondes) compl\u00e8te le podium. L\u2019Ukrainien champion paralympique en titre, <strong>Grygorii Vovchynskyi<\/strong>, a \u00e9chou\u00e9 au pied du podium. C\u2019est une d\u00e9ception pour nos Bleus aujourd\u2019hui mais d\u2019autres \u00e9preuves de para biathlon arrivent tout au long de ces Jeux : ils pourront retenter leur chance.<\/p>\n<div id=\"gtx-trans\" style=\"position: absolute; left: -14px; top: 40.9091px;\">\n<div class=\"gtx-trans-icon\" style=\"text-align: justify;\"><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Le Chinois Jiayun Cai a remport\u00e9 la m\u00e9daille d&rsquo;or de l&rsquo;\u00e9preuve du sprint debout du para biathlon. Il m\u00e8ne un doubl\u00e9 chinois et les deux Fran\u00e7ais Benjamin Daviet et Karl Tabouret terminent 7\u00e8me et 12\u00e8me.<\/p>\n","protected":false},"author":54,"featured_media":653286,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[47401],"tags":[32415,16878,1964,20604,21269],"class_list":["post-653260","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-jeux-paralympiques-dhiver-2026","tag-actu","tag-breve","tag-jeux-paralympiques","tag-jeux-paralympiques-dhiver","tag-para-biathlon"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Doubl\u00e9 chinois sur le sprint cat\u00e9gorie debout du para biathlon, pas de podium pour les Bleus<\/title>\n<meta name=\"description\" content=\"Le Chinois Jiayun Cai a remport\u00e9 la m\u00e9daille d&#039;or de l&#039;\u00e9preuve du sprint debout du para biathlon. Il m\u00e8ne un doubl\u00e9 chinois et les deux Fran\u00e7ais Benjamin Daviet et Karl Tabouret terminent 7\u00e8me et 12\u00e8me.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/double-chinois-sur-le-sprint-categorie-debout-du-para-biathlon-pas-de-podium-pour-les-bleus\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Doubl\u00e9 chinois sur le sprint cat\u00e9gorie debout du para biathlon, pas de podium pour les Bleus\" \/>\n<meta property=\"og:description\" content=\"Le Chinois Jiayun Cai a remport\u00e9 la m\u00e9daille d&#039;or de l&#039;\u00e9preuve du sprint debout du para biathlon. Il m\u00e8ne un doubl\u00e9 chinois et les deux Fran\u00e7ais Benjamin Daviet et Karl Tabouret terminent 7\u00e8me et 12\u00e8me.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/double-chinois-sur-le-sprint-categorie-debout-du-para-biathlon-pas-de-podium-pour-les-bleus\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/roxane.lecacher\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-07T12:27:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-07T12:55:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/03\/Double-chinois-sur-le-sprint-categorie-debout-du-para-biathlon-pas-de-podium-pour-les-Bleus.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Roxane Lecacher\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Doubl\u00e9 chinois sur le sprint cat\u00e9gorie debout du para biathlon, pas de podium pour les Bleus\" \/>\n<meta name=\"twitter:creator\" content=\"@dicodusport\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/double-chinois-sur-le-sprint-categorie-debout-du-para-biathlon-pas-de-podium-pour-les-bleus\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/double-chinois-sur-le-sprint-categorie-debout-du-para-biathlon-pas-de-podium-pour-les-bleus\/\"},\"author\":{\"name\":\"Roxane Lecacher\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/819fb2545dd2715bd7c0580d6d4b411a\"},\"headline\":\"Doubl\u00e9 chinois sur le sprint cat\u00e9gorie debout du para biathlon, pas de podium pour les Bleus\",\"datePublished\":\"2026-03-07T12:27:49+00:00\",\"dateModified\":\"2026-03-07T12:55:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/double-chinois-sur-le-sprint-categorie-debout-du-para-biathlon-pas-de-podium-pour-les-bleus\/\"},\"wordCount\":591,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/double-chinois-sur-le-sprint-categorie-debout-du-para-biathlon-pas-de-podium-pour-les-bleus\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/03\/Double-chinois-sur-le-sprint-categorie-debout-du-para-biathlon-pas-de-podium-pour-les-Bleus.png\",\"keywords\":[\"actu\",\"br\u00e8ve\",\"jeux paralympiques\",\"Jeux Paralympiques d'hiver\",\"para biathlon\"],\"articleSection\":[\"Jeux Paralympiques d'hiver 2026\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/double-chinois-sur-le-sprint-categorie-debout-du-para-biathlon-pas-de-podium-pour-les-bleus\/#respond\"]}],\"copyrightYear\":\"2026\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/double-chinois-sur-le-sprint-categorie-debout-du-para-biathlon-pas-de-podium-pour-les-bleus\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/double-chinois-sur-le-sprint-categorie-debout-du-para-biathlon-pas-de-podium-pour-les-bleus\/\",\"name\":\"Doubl\u00e9 chinois sur le sprint cat\u00e9gorie debout du para biathlon, pas de podium pour les Bleus\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/double-chinois-sur-le-sprint-categorie-debout-du-para-biathlon-pas-de-podium-pour-les-bleus\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/double-chinois-sur-le-sprint-categorie-debout-du-para-biathlon-pas-de-podium-pour-les-bleus\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/03\/Double-chinois-sur-le-sprint-categorie-debout-du-para-biathlon-pas-de-podium-pour-les-Bleus.png\",\"datePublished\":\"2026-03-07T12:27:49+00:00\",\"dateModified\":\"2026-03-07T12:55:36+00:00\",\"description\":\"Le Chinois Jiayun Cai a remport\u00e9 la m\u00e9daille d'or de l'\u00e9preuve du sprint debout du para biathlon. Il m\u00e8ne un doubl\u00e9 chinois et les deux Fran\u00e7ais Benjamin Daviet et Karl Tabouret terminent 7\u00e8me et 12\u00e8me.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/double-chinois-sur-le-sprint-categorie-debout-du-para-biathlon-pas-de-podium-pour-les-bleus\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/double-chinois-sur-le-sprint-categorie-debout-du-para-biathlon-pas-de-podium-pour-les-bleus\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/double-chinois-sur-le-sprint-categorie-debout-du-para-biathlon-pas-de-podium-pour-les-bleus\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/03\/Double-chinois-sur-le-sprint-categorie-debout-du-para-biathlon-pas-de-podium-pour-les-Bleus.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/03\/Double-chinois-sur-le-sprint-categorie-debout-du-para-biathlon-pas-de-podium-pour-les-Bleus.png\",\"width\":1200,\"height\":674,\"caption\":\"Doubl\u00e9 chinois sur le sprint cat\u00e9gorie debout du para biathlon, pas de podium pour les Bleus\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/double-chinois-sur-le-sprint-categorie-debout-du-para-biathlon-pas-de-podium-pour-les-bleus\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Doubl\u00e9 chinois sur le sprint cat\u00e9gorie debout du para biathlon, pas de podium pour les Bleus\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/819fb2545dd2715bd7c0580d6d4b411a\",\"name\":\"Roxane Lecacher\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Roxane-Lecacher-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Roxane-Lecacher-150x150.jpg\",\"caption\":\"Roxane Lecacher\"},\"description\":\"Journaliste\/r\u00e9dactrice depuis janvier 2021 - N\u00e9e quelques jours avant la premi\u00e8re \u00e9toile des Bleus, je baigne dans une famille tr\u00e8s sportive. Je n\u2019ai eu d\u2019autres choix que de me passionner pour le sujet. Pratiquante de l\u2019athl\u00e9tisme depuis toute petite, j\u2019ai aussi un attrait tout particulier pour la Formule 1, le biathlon et le foot. Pendant les grands \u00e9v\u00e9nements, il est impossible de d\u00e9crocher de ma t\u00e9l\u00e9. C\u2019est \u00e0 travers Dicodusport que j\u2019aime d\u00e9sormais vous transmettre mes \u00e9motions et ma passion.\",\"sameAs\":[\"https:\/\/www.facebook.com\/roxane.lecacher\",\"https:\/\/fr.linkedin.com\/in\/roxane-lecacher-23368313b\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/roxanel\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Doubl\u00e9 chinois sur le sprint cat\u00e9gorie debout du para biathlon, pas de podium pour les Bleus","description":"Le Chinois Jiayun Cai a remport\u00e9 la m\u00e9daille d'or de l'\u00e9preuve du sprint debout du para biathlon. Il m\u00e8ne un doubl\u00e9 chinois et les deux Fran\u00e7ais Benjamin Daviet et Karl Tabouret terminent 7\u00e8me et 12\u00e8me.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/double-chinois-sur-le-sprint-categorie-debout-du-para-biathlon-pas-de-podium-pour-les-bleus\/","og_locale":"fr_FR","og_type":"article","og_title":"Doubl\u00e9 chinois sur le sprint cat\u00e9gorie debout du para biathlon, pas de podium pour les Bleus","og_description":"Le Chinois Jiayun Cai a remport\u00e9 la m\u00e9daille d'or de l'\u00e9preuve du sprint debout du para biathlon. Il m\u00e8ne un doubl\u00e9 chinois et les deux Fran\u00e7ais Benjamin Daviet et Karl Tabouret terminent 7\u00e8me et 12\u00e8me.","og_url":"https:\/\/dicodusport.fr\/blog\/double-chinois-sur-le-sprint-categorie-debout-du-para-biathlon-pas-de-podium-pour-les-bleus\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/roxane.lecacher","article_published_time":"2026-03-07T12:27:49+00:00","article_modified_time":"2026-03-07T12:55:36+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/03\/Double-chinois-sur-le-sprint-categorie-debout-du-para-biathlon-pas-de-podium-pour-les-Bleus.png","type":"image\/png"}],"author":"Roxane Lecacher","twitter_card":"summary_large_image","twitter_title":"Doubl\u00e9 chinois sur le sprint cat\u00e9gorie debout du para biathlon, pas de podium pour les Bleus","twitter_creator":"@dicodusport","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/double-chinois-sur-le-sprint-categorie-debout-du-para-biathlon-pas-de-podium-pour-les-bleus\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/double-chinois-sur-le-sprint-categorie-debout-du-para-biathlon-pas-de-podium-pour-les-bleus\/"},"author":{"name":"Roxane Lecacher","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/819fb2545dd2715bd7c0580d6d4b411a"},"headline":"Doubl\u00e9 chinois sur le sprint cat\u00e9gorie debout du para biathlon, pas de podium pour les Bleus","datePublished":"2026-03-07T12:27:49+00:00","dateModified":"2026-03-07T12:55:36+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/double-chinois-sur-le-sprint-categorie-debout-du-para-biathlon-pas-de-podium-pour-les-bleus\/"},"wordCount":591,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/double-chinois-sur-le-sprint-categorie-debout-du-para-biathlon-pas-de-podium-pour-les-bleus\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/03\/Double-chinois-sur-le-sprint-categorie-debout-du-para-biathlon-pas-de-podium-pour-les-Bleus.png","keywords":["actu","br\u00e8ve","jeux paralympiques","Jeux Paralympiques d'hiver","para biathlon"],"articleSection":["Jeux Paralympiques d'hiver 2026"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/double-chinois-sur-le-sprint-categorie-debout-du-para-biathlon-pas-de-podium-pour-les-bleus\/#respond"]}],"copyrightYear":"2026","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/double-chinois-sur-le-sprint-categorie-debout-du-para-biathlon-pas-de-podium-pour-les-bleus\/","url":"https:\/\/dicodusport.fr\/blog\/double-chinois-sur-le-sprint-categorie-debout-du-para-biathlon-pas-de-podium-pour-les-bleus\/","name":"Doubl\u00e9 chinois sur le sprint cat\u00e9gorie debout du para biathlon, pas de podium pour les Bleus","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/double-chinois-sur-le-sprint-categorie-debout-du-para-biathlon-pas-de-podium-pour-les-bleus\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/double-chinois-sur-le-sprint-categorie-debout-du-para-biathlon-pas-de-podium-pour-les-bleus\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/03\/Double-chinois-sur-le-sprint-categorie-debout-du-para-biathlon-pas-de-podium-pour-les-Bleus.png","datePublished":"2026-03-07T12:27:49+00:00","dateModified":"2026-03-07T12:55:36+00:00","description":"Le Chinois Jiayun Cai a remport\u00e9 la m\u00e9daille d'or de l'\u00e9preuve du sprint debout du para biathlon. Il m\u00e8ne un doubl\u00e9 chinois et les deux Fran\u00e7ais Benjamin Daviet et Karl Tabouret terminent 7\u00e8me et 12\u00e8me.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/double-chinois-sur-le-sprint-categorie-debout-du-para-biathlon-pas-de-podium-pour-les-bleus\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/double-chinois-sur-le-sprint-categorie-debout-du-para-biathlon-pas-de-podium-pour-les-bleus\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/double-chinois-sur-le-sprint-categorie-debout-du-para-biathlon-pas-de-podium-pour-les-bleus\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/03\/Double-chinois-sur-le-sprint-categorie-debout-du-para-biathlon-pas-de-podium-pour-les-Bleus.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/03\/Double-chinois-sur-le-sprint-categorie-debout-du-para-biathlon-pas-de-podium-pour-les-Bleus.png","width":1200,"height":674,"caption":"Doubl\u00e9 chinois sur le sprint cat\u00e9gorie debout du para biathlon, pas de podium pour les Bleus"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/double-chinois-sur-le-sprint-categorie-debout-du-para-biathlon-pas-de-podium-pour-les-bleus\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Doubl\u00e9 chinois sur le sprint cat\u00e9gorie debout du para biathlon, pas de podium pour les Bleus"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/819fb2545dd2715bd7c0580d6d4b411a","name":"Roxane Lecacher","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Roxane-Lecacher-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Roxane-Lecacher-150x150.jpg","caption":"Roxane Lecacher"},"description":"Journaliste\/r\u00e9dactrice depuis janvier 2021 - N\u00e9e quelques jours avant la premi\u00e8re \u00e9toile des Bleus, je baigne dans une famille tr\u00e8s sportive. Je n\u2019ai eu d\u2019autres choix que de me passionner pour le sujet. Pratiquante de l\u2019athl\u00e9tisme depuis toute petite, j\u2019ai aussi un attrait tout particulier pour la Formule 1, le biathlon et le foot. Pendant les grands \u00e9v\u00e9nements, il est impossible de d\u00e9crocher de ma t\u00e9l\u00e9. C\u2019est \u00e0 travers Dicodusport que j\u2019aime d\u00e9sormais vous transmettre mes \u00e9motions et ma passion.","sameAs":["https:\/\/www.facebook.com\/roxane.lecacher","https:\/\/fr.linkedin.com\/in\/roxane-lecacher-23368313b"],"url":"https:\/\/dicodusport.fr\/blog\/author\/roxanel\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/653260","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/54"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=653260"}],"version-history":[{"count":4,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/653260\/revisions"}],"predecessor-version":[{"id":653303,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/653260\/revisions\/653303"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/653286"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=653260"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=653260"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=653260"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}