{"id":654692,"date":"2026-03-13T12:30:38","date_gmt":"2026-03-13T11:30:38","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=654692&#038;preview=true&#038;preview_id=654692"},"modified":"2026-03-13T08:45:10","modified_gmt":"2026-03-13T07:45:10","slug":"mathis-desloges-un-retour-pour-me-faire-plaisir-sans-forcement-attendre-de-resultats","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/mathis-desloges-un-retour-pour-me-faire-plaisir-sans-forcement-attendre-de-resultats\/","title":{"rendered":"Mathis Desloges : \u00ab Un retour pour me faire plaisir, sans forc\u00e9ment attendre de r\u00e9sultats\u00a0\u00bb"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><strong>SKI DE FOND &#8211; Entretien avec Mathis Desloges \u00e0 quelques heures de son retour sur le circuit de la Coupe du monde de ski de fond.<\/strong><\/em><\/p>\n<p style=\"text-align: justify;\">L\u2019heure de la rentr\u00e9e a sonn\u00e9 pour <a href=\"https:\/\/dicodusport.fr\/blog\/qui-est-mathis-desloges-5-choses-a-savoir-sur-le-vice-champion-olympique-du-skiathlon\/\"><strong>Mathis Desloges<\/strong><\/a>. Trois semaines apr\u00e8s la fin des <strong>Jeux Olympiques<\/strong> de <strong>Milan-Cortina<\/strong> (Italie), le fondeur, triple m\u00e9daill\u00e9 d\u2019argent, s\u2019appr\u00eate \u00e0 retrouver le circuit de la <strong>Coupe du monde<\/strong>. Il sera engag\u00e9, ce samedi, \u00e0 <strong>Oslo-Holmenkollen<\/strong> (Norv\u00e8ge), sur la mass-start. Alors qu\u2019il s\u2019appr\u00eatait \u00e0 prendre l\u2019avion, il nous a accord\u00e9 une interview.<\/p>\n<h3 style=\"text-align: justify;\">Comment vous sentez-vous \u00e0 quelques jours de la reprise ?<\/h3>\n<p style=\"text-align: justify;\">C&rsquo;est difficile \u00e0 dire. Cela fait deux semaines que je m\u2019entra\u00eene moins, car je suis en tourn\u00e9e m\u00e9diatique. J\u2019ai peu d\u2019entra\u00eenement, donc on verra bien comment sera la forme.<\/p>\n<h3 style=\"text-align: justify;\">On conna\u00eet votre app\u00e9tence pour l\u2019entra\u00eenement. Comment avez-vous pu g\u00e9rer cette phase ?<\/h3>\n<p style=\"text-align: justify;\">Je n&rsquo;ai pas g\u00e9r\u00e9 grand-chose <i>(rires)<\/i>. C\u2019est vrai que ce qui me passionne, c&rsquo;est l\u2019entra\u00eenement, et l\u00e0, je n&rsquo;ai pas pu faire ce que je voulais. C&rsquo;est pour \u00e7a que j\u2019aborde cette fin de saison avec tr\u00e8s peu d&rsquo;ambition. Je sais tr\u00e8s bien que lorsque je pr\u00e9pare mal les choses, je ne sais pas trop \u00e0 quoi m&rsquo;attendre. On verra bien.<\/p>\n<h3 style=\"text-align: justify;\">Vous attendez-vous tout de m\u00eame \u00e0 \u00eatre davantage surveill\u00e9 ?<\/h3>\n<p style=\"text-align: justify;\">Oui, c&rsquo;est certain que je serai plus attendu dans le sens o\u00f9 j&rsquo;ai trois m\u00e9dailles. Aujourd&rsquo;hui, je fais un peu partie des skieurs \u00e0 surveiller sur le circuit de la <strong>Coupe du monde<\/strong>. Mais je sais que je n&rsquo;ai pas fait la pr\u00e9paration optimale pour ces prochaines courses. J&rsquo;y vais pour me faire plaisir. Ce sont des lieux qui vont \u00eatre sympas. <strong>Oslo<\/strong> est un stade magnifique. <strong>Lake Placid<\/strong>, aux <strong>\u00c9tats-Unis<\/strong>, va \u00eatre une superbe f\u00eate pour le ski de fond mondial. J&rsquo;y vais pour profiter sans forc\u00e9ment attendre de r\u00e9sultats.<\/p>\n<div class=\"vlp-link-container vlp-layout-article\"><a href=\"https:\/\/dicodusport.fr\/blog\/shaidorov-hristova-desloges-les-surprises-des-jo-2026-de-milan-cortina\/\" class=\"vlp-link\" title=\"Shaidorov, Hristova, Desloges\u2026 les surprises des JO 2026 de Milan-Cortina\"><\/a><div class=\"vlp-layout-zone-side\"><div class=\"vlp-block-4 vlp-link-image\"><img loading=\"lazy\" decoding=\"async\" style=\"max-width: 792px;\" width=\"792\" height=\"445\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/02\/Shaidorov-Hristova-Desloges-les-surprises-des-JO-2026-de-Milan-Cortina.png\" class=\"attachment-800x445 size-800x445\" alt=\"Shaidorov, Hristova, Desloges les surprises des JO 2026 de Milan-Cortina\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/02\/Shaidorov-Hristova-Desloges-les-surprises-des-JO-2026-de-Milan-Cortina.png 1200w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/02\/Shaidorov-Hristova-Desloges-les-surprises-des-JO-2026-de-Milan-Cortina-300x169.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/02\/Shaidorov-Hristova-Desloges-les-surprises-des-JO-2026-de-Milan-Cortina-1024x575.png 1024w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/02\/Shaidorov-Hristova-Desloges-les-surprises-des-JO-2026-de-Milan-Cortina-768x431.png 768w\" sizes=\"auto, (max-width: 792px) 100vw, 792px\" \/><\/div><\/div><div class=\"vlp-layout-zone-main\"><div class=\"vlp-block-0 vlp-link-title\">Shaidorov, Hristova, Desloges\u2026 les surprises des JO 2026 de Milan-Cortina<\/div><div class=\"vlp-block-1 vlp-link-summary\">JO 2026 - Entre les promesses faites avant les Jeux et la r\u00e9alit\u00e9 du terrain, il y a parfois un monde d\u2019\u00e9cart. Certains se sont \u00e9croul\u00e9s sous la pression, d\u2019autres sont arriv\u00e9s l\u00e0 o\u00f9 on ne les attendait pas. Voici quelques surprises de Milan-Cortina.<\/div><div class=\"vlp-block-2 vlp-link-button\">Lire l'article<\/div><div class=\"vlp-block-3 vlp-link-url\">dicodusport.fr<\/div><\/div><\/div>\n<h3 style=\"text-align: justify;\">Comment expliquez-vous vos performances lors des Jeux ?<\/h3>\n<p style=\"text-align: justify;\">Cela prendrait du temps \u00e0 expliquer <i>(rires)<\/i>. C&rsquo;est le fruit d\u2019un travail acharn\u00e9 avec une optimisation de tous les param\u00e8tres de la performance, sur toute une pr\u00e9paration et sur plusieurs ann\u00e9es. C\u2019\u00e9tait un r\u00eave d&rsquo;enfant et je me suis donn\u00e9 tous les moyens possibles pour y arriver. Aujourd&rsquo;hui, voir que le travail paye, \u00e7a fait plaisir.<\/p>\n<h3 style=\"text-align: justify;\">Regrettez-vous que les sites soient \u00e9clat\u00e9s et que l\u2019ambiance ressemble davantage \u00e0 celle d\u2019une Coupe du monde ?<\/h3>\n<p style=\"text-align: justify;\">Je l&rsquo;ai bien v\u00e9cu, parce que le seul objectif de ces Jeux \u00e9tait de ramener des m\u00e9dailles et d\u2019y aller pour la performance, pas pour l&rsquo;esprit olympique et tout le folklore qui va avec. Mais je comprends que certains athl\u00e8tes aient pu \u00eatre d\u00e9\u00e7us. Certains venaient davantage pour cet esprit olympique entre les athl\u00e8tes, toutes ces petites activit\u00e9s qu&rsquo;on peut faire dans un village olympique. Moi, je n\u2019y allais pas du tout pour \u00e7a, donc cela ne m\u2019a pas d\u00e9rang\u00e9.<\/p>\n<h3 style=\"text-align: justify;\">Vous avez \u00e9galement \u00e9t\u00e9 porte-drapeau lors de la c\u00e9r\u00e9monie de cl\u00f4ture. Est-ce un moment marquant de cette quinzaine ?<\/h3>\n<p style=\"text-align: justify;\">C&rsquo;\u00e9tait une superbe soir\u00e9e. En plus, accompagn\u00e9 de <strong>Lou Jeanmonnot<\/strong>, qui est une athl\u00e8te et une personne que j&rsquo;appr\u00e9cie vraiment. C&rsquo;\u00e9tait un bel honneur. Les ar\u00e8nes de <strong>V\u00e9rone<\/strong> \u00e9taient un cadre assez idyllique et magnifique. Avoir \u00e9t\u00e9 nomm\u00e9 porte-drapeau, c&rsquo;\u00e9tait vraiment un honneur.<\/p>\n<div class=\"vlp-link-container vlp-layout-article\"><a href=\"https:\/\/dicodusport.fr\/blog\/lou-jeanmonnot-et-mathis-desloges-seront-les-porte-drapeaux-de-la-france-pour-la-ceremonie-de-cloture-des-jo-2026\/\" class=\"vlp-link\" title=\"Lou Jeanmonnot et Mathis Desloges seront les porte-drapeaux de la France pour la C\u00e9r\u00e9monie de Cl\u00f4ture des JO 2026\"><\/a><div class=\"vlp-layout-zone-side\"><div class=\"vlp-block-4 vlp-link-image\"><img loading=\"lazy\" decoding=\"async\" style=\"max-width: 792px;\" width=\"792\" height=\"445\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/02\/Lou-Jeanmonnot-et-Mathis-Desloges-seront-les-porte-drapeaux-de-la-France-pour-la-Ceremonie-de-Cloture-des-JO-2026.png\" class=\"attachment-800x445 size-800x445\" alt=\"Lou Jeanmonnot et Mathis Desloges seront les porte-drapeaux de la France pour la C\u00e9r\u00e9monie de Cl\u00f4ture des JO 2026\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/02\/Lou-Jeanmonnot-et-Mathis-Desloges-seront-les-porte-drapeaux-de-la-France-pour-la-Ceremonie-de-Cloture-des-JO-2026.png 1200w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/02\/Lou-Jeanmonnot-et-Mathis-Desloges-seront-les-porte-drapeaux-de-la-France-pour-la-Ceremonie-de-Cloture-des-JO-2026-300x169.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/02\/Lou-Jeanmonnot-et-Mathis-Desloges-seront-les-porte-drapeaux-de-la-France-pour-la-Ceremonie-de-Cloture-des-JO-2026-1024x575.png 1024w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/02\/Lou-Jeanmonnot-et-Mathis-Desloges-seront-les-porte-drapeaux-de-la-France-pour-la-Ceremonie-de-Cloture-des-JO-2026-768x431.png 768w\" sizes=\"auto, (max-width: 792px) 100vw, 792px\" \/><\/div><\/div><div class=\"vlp-layout-zone-main\"><div class=\"vlp-block-0 vlp-link-title\">Lou Jeanmonnot et Mathis Desloges seront les porte-drapeaux de la France pour la C\u00e9r\u00e9monie de Cl\u00f4ture des JO 2026<\/div><div class=\"vlp-block-1 vlp-link-summary\">JO 2026 - Ce samedi apr\u00e8s-midi, Lou Jeanmonnot et Mathis Desloges ont \u00e9t\u00e9 nomm\u00e9s porte-drapeaux pour la c\u00e9r\u00e9monie de cl\u00f4ture des Jeux Olympiques.<\/div><div class=\"vlp-block-2 vlp-link-button\">Lire l'article<\/div><div class=\"vlp-block-3 vlp-link-url\">dicodusport.fr<\/div><\/div><\/div>\n<h3 style=\"text-align: justify;\">Le biathlon occupe beaucoup de place dans l\u2019espace m\u00e9diatique. Pensez-vous que votre performance puisse apporter davantage de visibilit\u00e9 au ski de fond ?<\/h3>\n<p style=\"text-align: justify;\">Je l&rsquo;esp\u00e8re. Apr\u00e8s, je n&rsquo;aime pas beaucoup la comparaison avec le biathlon. Ils pratiquent un sport qui est vraiment diff\u00e9rent du n\u00f4tre.<\/p>\n<p style=\"text-align: justify;\">Le biathlon laisse une place m\u00e9diatique assez importante dans la vie des athl\u00e8tes. Nous, on le fait un petit peu moins. Ce n&rsquo;est pas comparable d&rsquo;un sport \u00e0 l\u2019autre. En tout cas, j\u2019esp\u00e8re avoir pu montrer ce qu&rsquo;\u00e9tait le ski de fond aux Fran\u00e7ais et ce qu&rsquo;est l&rsquo;\u00e9quipe de France de ski de fond. On s&rsquo;entend vraiment super bien. On est une bande de copains avant d&rsquo;\u00eatre des athl\u00e8tes et j&rsquo;esp\u00e8re qu&rsquo;on l&rsquo;a vraiment montr\u00e9.<\/p>\n<h3 style=\"text-align: justify;\">Qu\u2019est-ce qui fait que vous formez une bande de copains au sein de l\u2019\u00e9quipe ?<\/h3>\n<p style=\"text-align: justify;\">Je dirais que c&rsquo;est aussi parce qu\u2019il y a tout \u00e0 \u00e9crire et que nous ne nous marchons pas du tout dessus. Un podium ou une victoire d&rsquo;un gars du groupe, on la ressent comme si c&rsquo;\u00e9tait la n\u00f4tre. C&rsquo;est vraiment ce qui fait la beaut\u00e9 de ce groupe. Pour l&rsquo;anecdote, quand je suis mont\u00e9 sur ma deuxi\u00e8me Coupe du monde, en Suisse \u00e0 <strong>Goms<\/strong>, <strong>Jules Lapierre<\/strong> a fait un <a href=\"https:\/\/dicodusport.fr\/blog\/ski-de-fond-jules-lapierre-monte-sur-le-podium-de-la-mass-start-de-goms\/\">podium sur la mass-start skate<\/a> <i>(28 janvier 2024)<\/i>. Et quand je suis rentr\u00e9, j&rsquo;ai dit \u00e0 ma m\u00e8re que j\u2019avais l&rsquo;impression que c&rsquo;\u00e9tait moi qui avais fait un podium. C&rsquo;est \u00e7a qui fait la force de cette \u00e9quipe. On aime c\u00e9l\u00e9brer et \u00eatre heureux pour les autres. On passe tellement de temps ensemble qu&rsquo;heureusement que c&rsquo;est comme \u00e7a.<\/p>\n<h3 style=\"text-align: justify;\">Que voulez-vous dire par \u00ab il y a tout \u00e0 \u00e9crire \u00bb ?<\/h3>\n<p style=\"text-align: justify;\">Le ski de fond n&rsquo;a pas remport\u00e9 beaucoup de m\u00e9dailles olympiques, surtout en individuel. J&rsquo;\u00e9tais la deuxi\u00e8me m\u00e9daille de l&rsquo;histoire du ski de fond fran\u00e7ais, 20 ans apr\u00e8s la premi\u00e8re <i>(<strong>Rodolphe Darragon<\/strong>, en argent \u00e0 <strong>Turin 2006<\/strong>)<\/i>. Cela signifie qu&rsquo;il faut tracer notre propre route. En France, nous n\u2019avons presque personne dont nous inspirer dans cette discipline. Si on fait le parall\u00e8le avec le biathlon, des biathl\u00e8tes fran\u00e7ais m\u00e9daill\u00e9s olympiques, il y en a beaucoup. Chez les fondeurs, c\u2019est beaucoup plus rare. L\u2019histoire reste encore \u00e0 \u00e9crire.<\/p>\n<h3 style=\"text-align: justify;\">Cette histoire peut-elle s\u2019\u00e9crire en 2030 avec les Jeux olympiques en France ? Comment comptez-vous construire cette olympiade \u00e0 venir ?<\/h3>\n<p style=\"text-align: justify;\">Je veux faire la meilleure pr\u00e9paration olympique possible pour 2030. J\u2019ai quatre ans pour essayer des choses et \u00eatre ambitieux. Cela me laisse du temps et c\u2019est vraiment positif. Ce qui m\u2019anime, c\u2019est de me dire que j\u2019ai quatre ans pour affiner tous les d\u00e9tails. Quatre ans, c\u2019est long, mais ce n\u2019est pas si long quand on veut vraiment bien faire les choses. Il va falloir rentabiliser au maximum ce temps.<\/p>\n<div id=\"gtx-trans\" style=\"position: absolute; left: -14px; top: 40.9091px;\">\n<div class=\"gtx-trans-icon\" style=\"text-align: justify;\"><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Entretien avec Mathis Desloges \u00e0 quelques heures de son retour sur le circuit de la Coupe du monde de ski de fond.<\/p>\n","protected":false},"author":80,"featured_media":654941,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[9217],"tags":[16878,47373,2819],"class_list":["post-654692","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ski","tag-breve","tag-jo-milan-cortina","tag-ski-de-fond"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Mathis Desloges : \u00ab Un retour pour me faire plaisir, sans forc\u00e9ment attendre de r\u00e9sultats\u00a0\u00bb<\/title>\n<meta name=\"description\" content=\"SKI DE FOND - Entretien avec Mathis Desloges \u00e0 quelques heures de son retour sur le circuit de la Coupe du monde de ski de fond.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/mathis-desloges-un-retour-pour-me-faire-plaisir-sans-forcement-attendre-de-resultats\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mathis Desloges : \u00ab Un retour pour me faire plaisir, sans forc\u00e9ment attendre de r\u00e9sultats\u00a0\u00bb\" \/>\n<meta property=\"og:description\" content=\"SKI DE FOND - Entretien avec Mathis Desloges \u00e0 quelques heures de son retour sur le circuit de la Coupe du monde de ski de fond.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/mathis-desloges-un-retour-pour-me-faire-plaisir-sans-forcement-attendre-de-resultats\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/profile.php?id=100009753662352\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-13T11:30:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/03\/Mathis-Desloges-Un-retour-pour-me-faire-plaisir-sans-forcement-attendre-de-resultats-.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Killian Tanguy\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Mathis Desloges : \u00ab Un retour pour me faire plaisir, sans forc\u00e9ment attendre de r\u00e9sultats\u00a0\u00bb\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/sport_ktanguy\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/mathis-desloges-un-retour-pour-me-faire-plaisir-sans-forcement-attendre-de-resultats\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/mathis-desloges-un-retour-pour-me-faire-plaisir-sans-forcement-attendre-de-resultats\\\/\"},\"author\":{\"name\":\"Killian Tanguy\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/ff2feeb71ea78ad31eeb3390ffe96b46\"},\"headline\":\"Mathis Desloges : \u00ab Un retour pour me faire plaisir, sans forc\u00e9ment attendre de r\u00e9sultats\u00a0\u00bb\",\"datePublished\":\"2026-03-13T11:30:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/mathis-desloges-un-retour-pour-me-faire-plaisir-sans-forcement-attendre-de-resultats\\\/\"},\"wordCount\":1329,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/mathis-desloges-un-retour-pour-me-faire-plaisir-sans-forcement-attendre-de-resultats\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Mathis-Desloges-Un-retour-pour-me-faire-plaisir-sans-forcement-attendre-de-resultats-.png\",\"keywords\":[\"br\u00e8ve\",\"JO Milan-Cortina\",\"Ski de fond\"],\"articleSection\":[\"Ski\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/mathis-desloges-un-retour-pour-me-faire-plaisir-sans-forcement-attendre-de-resultats\\\/#respond\"]}],\"copyrightYear\":\"2026\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/mathis-desloges-un-retour-pour-me-faire-plaisir-sans-forcement-attendre-de-resultats\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/mathis-desloges-un-retour-pour-me-faire-plaisir-sans-forcement-attendre-de-resultats\\\/\",\"name\":\"Mathis Desloges : \u00ab Un retour pour me faire plaisir, sans forc\u00e9ment attendre de r\u00e9sultats\u00a0\u00bb\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/mathis-desloges-un-retour-pour-me-faire-plaisir-sans-forcement-attendre-de-resultats\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/mathis-desloges-un-retour-pour-me-faire-plaisir-sans-forcement-attendre-de-resultats\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Mathis-Desloges-Un-retour-pour-me-faire-plaisir-sans-forcement-attendre-de-resultats-.png\",\"datePublished\":\"2026-03-13T11:30:38+00:00\",\"description\":\"SKI DE FOND - Entretien avec Mathis Desloges \u00e0 quelques heures de son retour sur le circuit de la Coupe du monde de ski de fond.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/mathis-desloges-un-retour-pour-me-faire-plaisir-sans-forcement-attendre-de-resultats\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/mathis-desloges-un-retour-pour-me-faire-plaisir-sans-forcement-attendre-de-resultats\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/mathis-desloges-un-retour-pour-me-faire-plaisir-sans-forcement-attendre-de-resultats\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Mathis-Desloges-Un-retour-pour-me-faire-plaisir-sans-forcement-attendre-de-resultats-.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Mathis-Desloges-Un-retour-pour-me-faire-plaisir-sans-forcement-attendre-de-resultats-.png\",\"width\":1200,\"height\":674,\"caption\":\"Mathis Desloges \u00ab Un retour pour me faire plaisir, sans forc\u00e9ment attendre de r\u00e9sultats\u00a0\u00bb\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/mathis-desloges-un-retour-pour-me-faire-plaisir-sans-forcement-attendre-de-resultats\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mathis Desloges : \u00ab Un retour pour me faire plaisir, sans forc\u00e9ment attendre de r\u00e9sultats\u00a0\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/ff2feeb71ea78ad31eeb3390ffe96b46\",\"name\":\"Killian Tanguy\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Killian-Tanguy-150x150.png\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Killian-Tanguy-150x150.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Killian-Tanguy-150x150.png\",\"caption\":\"Killian Tanguy\"},\"description\":\"Journaliste qui parle de tout et surtout de sport. Rugby, handball, sports d'hiver, football, cyclisme... Et ce que j'aime par-dessus tout : couvrir une discipline que je ne connais pas. Rien de mieux pour s'enrichir et apprendre.\",\"sameAs\":[\"https:\\\/\\\/killiantanguy.wixsite.com\\\/monsite\",\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=100009753662352\",\"https:\\\/\\\/www.instagram.com\\\/sport.killiantanguy\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/killiantanguy\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/sport_ktanguy\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCRfZkHKJL0wK7wvnJjCry-Q\"],\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/killian-tanguy\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Mathis Desloges : \u00ab Un retour pour me faire plaisir, sans forc\u00e9ment attendre de r\u00e9sultats\u00a0\u00bb","description":"SKI DE FOND - Entretien avec Mathis Desloges \u00e0 quelques heures de son retour sur le circuit de la Coupe du monde de ski de fond.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/mathis-desloges-un-retour-pour-me-faire-plaisir-sans-forcement-attendre-de-resultats\/","og_locale":"fr_FR","og_type":"article","og_title":"Mathis Desloges : \u00ab Un retour pour me faire plaisir, sans forc\u00e9ment attendre de r\u00e9sultats\u00a0\u00bb","og_description":"SKI DE FOND - Entretien avec Mathis Desloges \u00e0 quelques heures de son retour sur le circuit de la Coupe du monde de ski de fond.","og_url":"https:\/\/dicodusport.fr\/blog\/mathis-desloges-un-retour-pour-me-faire-plaisir-sans-forcement-attendre-de-resultats\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/profile.php?id=100009753662352","article_published_time":"2026-03-13T11:30:38+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/03\/Mathis-Desloges-Un-retour-pour-me-faire-plaisir-sans-forcement-attendre-de-resultats-.png","type":"image\/png"}],"author":"Killian Tanguy","twitter_card":"summary_large_image","twitter_title":"Mathis Desloges : \u00ab Un retour pour me faire plaisir, sans forc\u00e9ment attendre de r\u00e9sultats\u00a0\u00bb","twitter_creator":"@https:\/\/twitter.com\/sport_ktanguy","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/mathis-desloges-un-retour-pour-me-faire-plaisir-sans-forcement-attendre-de-resultats\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/mathis-desloges-un-retour-pour-me-faire-plaisir-sans-forcement-attendre-de-resultats\/"},"author":{"name":"Killian Tanguy","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/ff2feeb71ea78ad31eeb3390ffe96b46"},"headline":"Mathis Desloges : \u00ab Un retour pour me faire plaisir, sans forc\u00e9ment attendre de r\u00e9sultats\u00a0\u00bb","datePublished":"2026-03-13T11:30:38+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/mathis-desloges-un-retour-pour-me-faire-plaisir-sans-forcement-attendre-de-resultats\/"},"wordCount":1329,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/mathis-desloges-un-retour-pour-me-faire-plaisir-sans-forcement-attendre-de-resultats\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/03\/Mathis-Desloges-Un-retour-pour-me-faire-plaisir-sans-forcement-attendre-de-resultats-.png","keywords":["br\u00e8ve","JO Milan-Cortina","Ski de fond"],"articleSection":["Ski"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/mathis-desloges-un-retour-pour-me-faire-plaisir-sans-forcement-attendre-de-resultats\/#respond"]}],"copyrightYear":"2026","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/mathis-desloges-un-retour-pour-me-faire-plaisir-sans-forcement-attendre-de-resultats\/","url":"https:\/\/dicodusport.fr\/blog\/mathis-desloges-un-retour-pour-me-faire-plaisir-sans-forcement-attendre-de-resultats\/","name":"Mathis Desloges : \u00ab Un retour pour me faire plaisir, sans forc\u00e9ment attendre de r\u00e9sultats\u00a0\u00bb","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/mathis-desloges-un-retour-pour-me-faire-plaisir-sans-forcement-attendre-de-resultats\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/mathis-desloges-un-retour-pour-me-faire-plaisir-sans-forcement-attendre-de-resultats\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/03\/Mathis-Desloges-Un-retour-pour-me-faire-plaisir-sans-forcement-attendre-de-resultats-.png","datePublished":"2026-03-13T11:30:38+00:00","description":"SKI DE FOND - Entretien avec Mathis Desloges \u00e0 quelques heures de son retour sur le circuit de la Coupe du monde de ski de fond.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/mathis-desloges-un-retour-pour-me-faire-plaisir-sans-forcement-attendre-de-resultats\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/mathis-desloges-un-retour-pour-me-faire-plaisir-sans-forcement-attendre-de-resultats\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/mathis-desloges-un-retour-pour-me-faire-plaisir-sans-forcement-attendre-de-resultats\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/03\/Mathis-Desloges-Un-retour-pour-me-faire-plaisir-sans-forcement-attendre-de-resultats-.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/03\/Mathis-Desloges-Un-retour-pour-me-faire-plaisir-sans-forcement-attendre-de-resultats-.png","width":1200,"height":674,"caption":"Mathis Desloges \u00ab Un retour pour me faire plaisir, sans forc\u00e9ment attendre de r\u00e9sultats\u00a0\u00bb"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/mathis-desloges-un-retour-pour-me-faire-plaisir-sans-forcement-attendre-de-resultats\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Mathis Desloges : \u00ab Un retour pour me faire plaisir, sans forc\u00e9ment attendre de r\u00e9sultats\u00a0\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/ff2feeb71ea78ad31eeb3390ffe96b46","name":"Killian Tanguy","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/12\/Killian-Tanguy-150x150.png","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/12\/Killian-Tanguy-150x150.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/12\/Killian-Tanguy-150x150.png","caption":"Killian Tanguy"},"description":"Journaliste qui parle de tout et surtout de sport. Rugby, handball, sports d'hiver, football, cyclisme... Et ce que j'aime par-dessus tout : couvrir une discipline que je ne connais pas. Rien de mieux pour s'enrichir et apprendre.","sameAs":["https:\/\/killiantanguy.wixsite.com\/monsite","https:\/\/www.facebook.com\/profile.php?id=100009753662352","https:\/\/www.instagram.com\/sport.killiantanguy\/","https:\/\/www.linkedin.com\/in\/killiantanguy\/","https:\/\/x.com\/https:\/\/twitter.com\/sport_ktanguy","https:\/\/www.youtube.com\/channel\/UCRfZkHKJL0wK7wvnJjCry-Q"],"url":"https:\/\/dicodusport.fr\/blog\/author\/killian-tanguy\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/654692","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/80"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=654692"}],"version-history":[{"count":3,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/654692\/revisions"}],"predecessor-version":[{"id":654942,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/654692\/revisions\/654942"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/654941"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=654692"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=654692"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=654692"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}