{"id":656528,"date":"2026-03-19T13:11:37","date_gmt":"2026-03-19T12:11:37","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=656528&#038;preview=true&#038;preview_id=656528"},"modified":"2026-03-19T13:11:47","modified_gmt":"2026-03-19T12:11:47","slug":"sprint-femmes-oslo-2026-startlist-et-dossards-des-huit-francaises-engagees","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/sprint-femmes-oslo-2026-startlist-et-dossards-des-huit-francaises-engagees\/","title":{"rendered":"Sprint femmes Oslo 2026 \u2013 Startlist et dossards des huit Fran\u00e7aises engag\u00e9es"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>Retrouvez la startlist et les dossards des Fran\u00e7aises engag\u00e9es sur le sprint femmes d&rsquo;Oslo (Norv\u00e8ge), dont le d\u00e9part est pr\u00e9vu le jeudi 18 mars 2026 \u00e0 16h15.<\/em><\/strong><\/p>\n<ul style=\"text-align: justify;\">\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/biathlon-oslo-2026-programme-horaires-et-resultats\/\">Biathlon Oslo 2026 : Programme, Horaires et R\u00e9sultats<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Le <strong>sprint femmes d\u2019Oslo<\/strong>, disput\u00e9 ce jeudi 19 mars 2026 \u00e0 <strong>Holmenkollen<\/strong>, est perturb\u00e9 par des conditions m\u00e9t\u00e9orologiques d\u00e9licates, avec des temp\u00e9ratures tr\u00e8s \u00e9lev\u00e9es. Cons\u00e9quence, l&rsquo;IBU a d\u00e9cid\u00e9 de changer la startlist.<\/p>\n<p style=\"text-align: justify;\">L\u2019\u00e9quipe de France sera bien repr\u00e9sent\u00e9e,\u00a0avec huit Fran\u00e7aises engag\u00e9es au d\u00e9part de l\u2019\u00e9preuve. <strong>Camille Bened<\/strong> ouvrira la marche c\u00f4t\u00e9 tricolore avec le dossard 1, juste avant <strong>Lou Jeanmonnot <\/strong>(dossard 3), <strong>Julia Simon <\/strong>(dossard 5) et <strong>Justine Braisaz-Bouchet <\/strong>(dossard 7), toutes plac\u00e9es tr\u00e8s t\u00f4t dans l\u2019ordre de d\u00e9part.<\/p>\n<p style=\"text-align: justify;\">Plus loin, la France pourra \u00e9galement compter sur <strong>Oc\u00e9ane Michelon <\/strong>(dossard 21) et <strong>Sophie Chauveau <\/strong>(dossard 29), avant de retrouver <strong>Voldiya Galmace Paulin <\/strong>(dossard 56) puis <strong>Amandine Mengin <\/strong>(dossard 88). Une d\u00e9l\u00e9gation dense, m\u00ealant leaders confirm\u00e9es et jeunes talents, dans une course qui s\u2019annonce capitale \u00e0 Holmenkollen.<\/p>\n<ul>\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/lou-jeanmonnot-a-un-pas-du-gros-globe-de-cristal-les-scenarios-avant-le-sprint-doslo\/\">Lou Jeanmonnot \u00e0 un pas du gros globe de cristal : les sc\u00e9narios avant le sprint d\u2019Oslo<\/a><\/strong><\/li>\n<\/ul>\n<h3 style=\"text-align: justify;\"><strong>Les 8 Fran\u00e7aises au d\u00e9part :<\/strong><\/h3>\n<p style=\"text-align: justify;\">\u2022 <strong>Camille Bened<\/strong> : dossard 1<\/p>\n<p style=\"text-align: justify;\">\u2022 <strong>Lou Jeanmonnot<\/strong> : dossard 3<\/p>\n<p style=\"text-align: justify;\">\u2022 <strong>Julia Simon<\/strong> : dossard 5<\/p>\n<p style=\"text-align: justify;\">\u2022 <strong>Justine Braisaz-Bouchet<\/strong> : dossard 7<\/p>\n<p style=\"text-align: justify;\">\u2022 <strong>Oc\u00e9ane Michelon<\/strong> : dossard 21<\/p>\n<p style=\"text-align: justify;\">\u2022 <strong>Sophie Chauveau<\/strong> : dossard 29<\/p>\n<p style=\"text-align: justify;\">\u2022 <strong>Voldiya Galmace Paulin<\/strong> : dossard 56<\/p>\n<p style=\"text-align: justify;\">\u2022 <strong>Amandine Mengin<\/strong> : dossard 88<\/p>\n<ul style=\"text-align: justify;\">\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/biathlon-oslo-2026-pronostic-sprint-femmes\/\">Biathlon Oslo 2026 \u2013 Pronostic Sprint femmes<\/a><\/strong><\/li>\n<\/ul>\n<h2 style=\"text-align: justify;\" align=\"justify\">La startlist du sprint femmes d&rsquo;Oslo<\/h2>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/03\/Nouvelle-startlist-du-sprint-femmes-dOslo-2026.pdf\" class=\"pdfemb-viewer\" style=\"\" data-width=\"max\" data-height=\"max\"  data-toolbar=\"both\" data-toolbar-fixed=\"on\">Nouvelle startlist du sprint femmes d&#039;Oslo 2026<br\/><\/a>\n<h3 style=\"text-align: justify;\">Dicodusport vous conseille<\/h3>\n<ul style=\"text-align: justify;\">\n<li style=\"text-align: justify;\"><strong><a href=\"https:\/\/dicodusport.fr\/blog\/biathlon-coupe-du-monde-2025-2026-le-calendrier-complet\/\">Biathlon Coupe du monde 2025-2026 &#8211; Le calendrier complet<\/a><\/strong><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Retrouvez la startlist et les dossards des Fran\u00e7aises engag\u00e9es sur le sprint femmes d&rsquo;Oslo (Norv\u00e8ge), dont le d\u00e9part est pr\u00e9vu le jeudi 18 mars 2026 \u00e0 16h15.<\/p>\n","protected":false},"author":4,"featured_media":656530,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[47040],"tags":[32415,2427,22316,30329,16878,2695,6937],"class_list":["post-656528","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coupe-du-monde-de-biathlon","tag-actu","tag-biathlon","tag-biathlon-oslo","tag-biathlon-oslo-holmenkollen","tag-breve","tag-coupe-du-monde-de-biathlon","tag-sprint-femmes"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Sprint femmes Oslo 2026 \u2013 Startlist et dossards des huit Fran\u00e7aises engag\u00e9es<\/title>\n<meta name=\"description\" content=\"Retrouvez la startlist et les dossards des Fran\u00e7aises engag\u00e9es sur le sprint femmes d&#039;Oslo (Norv\u00e8ge), dont le d\u00e9part est pr\u00e9vu le jeudi 18 mars 2026 \u00e0 16h15.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/sprint-femmes-oslo-2026-startlist-et-dossards-des-huit-francaises-engagees\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sprint femmes Oslo 2026 \u2013 Startlist et dossards des huit Fran\u00e7aises engag\u00e9es\" \/>\n<meta property=\"og:description\" content=\"Retrouvez la startlist et les dossards des Fran\u00e7aises engag\u00e9es sur le sprint femmes d&#039;Oslo (Norv\u00e8ge), dont le d\u00e9part est pr\u00e9vu le jeudi 18 mars 2026 \u00e0 16h15.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/sprint-femmes-oslo-2026-startlist-et-dossards-des-huit-francaises-engagees\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/florent.ostermann\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-19T12:11:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-19T12:11:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/03\/Sprint-femmes-Oslo-2026-Startlist-et-dossards-des-huit-Francaises-engagees.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Flo Ostermann\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Sprint femmes Oslo 2026 \u2013 Startlist et dossards des huit Fran\u00e7aises engag\u00e9es\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/FlOstermann\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/sprint-femmes-oslo-2026-startlist-et-dossards-des-huit-francaises-engagees\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/sprint-femmes-oslo-2026-startlist-et-dossards-des-huit-francaises-engagees\/\"},\"author\":{\"name\":\"Flo Ostermann\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a\"},\"headline\":\"Sprint femmes Oslo 2026 \u2013 Startlist et dossards des huit Fran\u00e7aises engag\u00e9es\",\"datePublished\":\"2026-03-19T12:11:37+00:00\",\"dateModified\":\"2026-03-19T12:11:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/sprint-femmes-oslo-2026-startlist-et-dossards-des-huit-francaises-engagees\/\"},\"wordCount\":293,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/sprint-femmes-oslo-2026-startlist-et-dossards-des-huit-francaises-engagees\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/03\/Sprint-femmes-Oslo-2026-Startlist-et-dossards-des-huit-Francaises-engagees.png\",\"keywords\":[\"actu\",\"Biathlon\",\"biathlon oslo\",\"Biathlon Oslo-Holmenkollen\",\"br\u00e8ve\",\"Coupe du monde de Biathlon\",\"Sprint femmes\"],\"articleSection\":[\"Coupe du monde de biathlon\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/sprint-femmes-oslo-2026-startlist-et-dossards-des-huit-francaises-engagees\/#respond\"]}],\"copyrightYear\":\"2026\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/sprint-femmes-oslo-2026-startlist-et-dossards-des-huit-francaises-engagees\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/sprint-femmes-oslo-2026-startlist-et-dossards-des-huit-francaises-engagees\/\",\"name\":\"Sprint femmes Oslo 2026 \u2013 Startlist et dossards des huit Fran\u00e7aises engag\u00e9es\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/sprint-femmes-oslo-2026-startlist-et-dossards-des-huit-francaises-engagees\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/sprint-femmes-oslo-2026-startlist-et-dossards-des-huit-francaises-engagees\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/03\/Sprint-femmes-Oslo-2026-Startlist-et-dossards-des-huit-Francaises-engagees.png\",\"datePublished\":\"2026-03-19T12:11:37+00:00\",\"dateModified\":\"2026-03-19T12:11:47+00:00\",\"description\":\"Retrouvez la startlist et les dossards des Fran\u00e7aises engag\u00e9es sur le sprint femmes d'Oslo (Norv\u00e8ge), dont le d\u00e9part est pr\u00e9vu le jeudi 18 mars 2026 \u00e0 16h15.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/sprint-femmes-oslo-2026-startlist-et-dossards-des-huit-francaises-engagees\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/sprint-femmes-oslo-2026-startlist-et-dossards-des-huit-francaises-engagees\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/sprint-femmes-oslo-2026-startlist-et-dossards-des-huit-francaises-engagees\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/03\/Sprint-femmes-Oslo-2026-Startlist-et-dossards-des-huit-Francaises-engagees.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/03\/Sprint-femmes-Oslo-2026-Startlist-et-dossards-des-huit-Francaises-engagees.png\",\"width\":1200,\"height\":674,\"caption\":\"Sprint femmes Oslo 2026 Startlist et dossards des huit Fran\u00e7aises engag\u00e9es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/sprint-femmes-oslo-2026-startlist-et-dossards-des-huit-francaises-engagees\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sprint femmes Oslo 2026 \u2013 Startlist et dossards des huit Fran\u00e7aises engag\u00e9es\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a\",\"name\":\"Flo Ostermann\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg\",\"caption\":\"Flo Ostermann\"},\"description\":\"Journaliste\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !\",\"sameAs\":[\"https:\/\/www.facebook.com\/florent.ostermann\",\"https:\/\/x.com\/https:\/\/twitter.com\/FlOstermann\",\"admin\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/flo\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Sprint femmes Oslo 2026 \u2013 Startlist et dossards des huit Fran\u00e7aises engag\u00e9es","description":"Retrouvez la startlist et les dossards des Fran\u00e7aises engag\u00e9es sur le sprint femmes d'Oslo (Norv\u00e8ge), dont le d\u00e9part est pr\u00e9vu le jeudi 18 mars 2026 \u00e0 16h15.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/sprint-femmes-oslo-2026-startlist-et-dossards-des-huit-francaises-engagees\/","og_locale":"fr_FR","og_type":"article","og_title":"Sprint femmes Oslo 2026 \u2013 Startlist et dossards des huit Fran\u00e7aises engag\u00e9es","og_description":"Retrouvez la startlist et les dossards des Fran\u00e7aises engag\u00e9es sur le sprint femmes d'Oslo (Norv\u00e8ge), dont le d\u00e9part est pr\u00e9vu le jeudi 18 mars 2026 \u00e0 16h15.","og_url":"https:\/\/dicodusport.fr\/blog\/sprint-femmes-oslo-2026-startlist-et-dossards-des-huit-francaises-engagees\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/florent.ostermann","article_published_time":"2026-03-19T12:11:37+00:00","article_modified_time":"2026-03-19T12:11:47+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/03\/Sprint-femmes-Oslo-2026-Startlist-et-dossards-des-huit-Francaises-engagees.png","type":"image\/png"}],"author":"Flo Ostermann","twitter_card":"summary_large_image","twitter_title":"Sprint femmes Oslo 2026 \u2013 Startlist et dossards des huit Fran\u00e7aises engag\u00e9es","twitter_creator":"@https:\/\/twitter.com\/FlOstermann","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/sprint-femmes-oslo-2026-startlist-et-dossards-des-huit-francaises-engagees\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/sprint-femmes-oslo-2026-startlist-et-dossards-des-huit-francaises-engagees\/"},"author":{"name":"Flo Ostermann","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a"},"headline":"Sprint femmes Oslo 2026 \u2013 Startlist et dossards des huit Fran\u00e7aises engag\u00e9es","datePublished":"2026-03-19T12:11:37+00:00","dateModified":"2026-03-19T12:11:47+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/sprint-femmes-oslo-2026-startlist-et-dossards-des-huit-francaises-engagees\/"},"wordCount":293,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/sprint-femmes-oslo-2026-startlist-et-dossards-des-huit-francaises-engagees\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/03\/Sprint-femmes-Oslo-2026-Startlist-et-dossards-des-huit-Francaises-engagees.png","keywords":["actu","Biathlon","biathlon oslo","Biathlon Oslo-Holmenkollen","br\u00e8ve","Coupe du monde de Biathlon","Sprint femmes"],"articleSection":["Coupe du monde de biathlon"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/sprint-femmes-oslo-2026-startlist-et-dossards-des-huit-francaises-engagees\/#respond"]}],"copyrightYear":"2026","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/sprint-femmes-oslo-2026-startlist-et-dossards-des-huit-francaises-engagees\/","url":"https:\/\/dicodusport.fr\/blog\/sprint-femmes-oslo-2026-startlist-et-dossards-des-huit-francaises-engagees\/","name":"Sprint femmes Oslo 2026 \u2013 Startlist et dossards des huit Fran\u00e7aises engag\u00e9es","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/sprint-femmes-oslo-2026-startlist-et-dossards-des-huit-francaises-engagees\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/sprint-femmes-oslo-2026-startlist-et-dossards-des-huit-francaises-engagees\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/03\/Sprint-femmes-Oslo-2026-Startlist-et-dossards-des-huit-Francaises-engagees.png","datePublished":"2026-03-19T12:11:37+00:00","dateModified":"2026-03-19T12:11:47+00:00","description":"Retrouvez la startlist et les dossards des Fran\u00e7aises engag\u00e9es sur le sprint femmes d'Oslo (Norv\u00e8ge), dont le d\u00e9part est pr\u00e9vu le jeudi 18 mars 2026 \u00e0 16h15.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/sprint-femmes-oslo-2026-startlist-et-dossards-des-huit-francaises-engagees\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/sprint-femmes-oslo-2026-startlist-et-dossards-des-huit-francaises-engagees\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/sprint-femmes-oslo-2026-startlist-et-dossards-des-huit-francaises-engagees\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/03\/Sprint-femmes-Oslo-2026-Startlist-et-dossards-des-huit-Francaises-engagees.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/03\/Sprint-femmes-Oslo-2026-Startlist-et-dossards-des-huit-Francaises-engagees.png","width":1200,"height":674,"caption":"Sprint femmes Oslo 2026 Startlist et dossards des huit Fran\u00e7aises engag\u00e9es"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/sprint-femmes-oslo-2026-startlist-et-dossards-des-huit-francaises-engagees\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Sprint femmes Oslo 2026 \u2013 Startlist et dossards des huit Fran\u00e7aises engag\u00e9es"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a","name":"Flo Ostermann","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","caption":"Flo Ostermann"},"description":"Journaliste\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !","sameAs":["https:\/\/www.facebook.com\/florent.ostermann","https:\/\/x.com\/https:\/\/twitter.com\/FlOstermann","admin"],"url":"https:\/\/dicodusport.fr\/blog\/author\/flo\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/656528","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=656528"}],"version-history":[{"count":4,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/656528\/revisions"}],"predecessor-version":[{"id":656623,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/656528\/revisions\/656623"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/656530"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=656528"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=656528"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=656528"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}