{"id":661436,"date":"2026-04-09T12:35:00","date_gmt":"2026-04-09T10:35:00","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=661436&#038;preview=true&#038;preview_id=661436"},"modified":"2026-04-09T11:20:27","modified_gmt":"2026-04-09T09:20:27","slug":"ufc-327-liste-des-combats-diffusion-tv-cotes-date-et-heure","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/ufc-327-liste-des-combats-diffusion-tv-cotes-date-et-heure\/","title":{"rendered":"UFC 327 : Liste des combats, Diffusion TV, Cotes, Date et Heure"},"content":{"rendered":"<p style=\"text-align: justify;\" align=\"justify\"><strong><em>L&rsquo;UFC 327 se d\u00e9roule dans la nuit du samedi 11 au dimanche 12 avril aux \u00c9tats-Unis, \u00e0 Miami<\/em><em>. Programme et cha\u00eene TV.<\/em><\/strong><\/p>\n<ul style=\"text-align: justify;\">\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/combattants-francais-a-lufc-la-liste-complete-depuis-la-creation-de-lorganisation\/\">Combattants fran\u00e7ais \u00e0 l\u2019UFC : la liste compl\u00e8te depuis la cr\u00e9ation de l\u2019organisation<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Le <strong>327\u00e8me \u00e9v\u00e8nement num\u00e9rot\u00e9 de l&rsquo;UFC<\/strong> aura lieu dans la nuit de samedi \u00e0 dimanche au Kaseya Center de Miami, aux \u00c9tats-Unis. Avec en t\u00eate d&rsquo;affiche le combat pour la ceinture des poids mi-lourds entre <strong>Ji\u0159\u00ed Proch\u00e1zka<\/strong> et <strong>Carlos Ulberg<\/strong>.<\/p>\n<h2 style=\"text-align: justify;\">Proch\u00e1zka de retour au sommet ?<\/h2>\n<p style=\"text-align: justify;\">Depuis son arriv\u00e9e \u00e0 l&rsquo;UFC en 2020, <strong>Ji\u0159\u00ed Proch\u00e1zka<\/strong><strong>\u00a0<\/strong>est un acteur majeur de la cat\u00e9gorie des poids mi-lourds. Il avait d&rsquo;ailleurs d\u00e9croch\u00e9 la ceinture en 2022, avant d&rsquo;\u00eatre contraint de la rendre sur blessure, sans jamais pouvoir la d\u00e9fendre. Depuis, il a eu deux chances de la reconqu\u00e9rir, mais \u00e0 chaque fois, il a but\u00e9 sur\u00a0<strong>Alex Pereira<\/strong>, ses deux seules d\u00e9faites dans l&rsquo;organisation am\u00e9ricaine.<\/p>\n<div class=\"vlp-link-container vlp-layout-article\"><a href=\"https:\/\/dicodusport.fr\/blog\/ufc-303-pereira-eteint-prochazka-ghemmouri-se-rate-tous-les-resultats-du-ppv\/\" class=\"vlp-link\" title=\"UFC 303 : Pereira \u00e9teint Proch\u00e1zka, Ghemmouri se rate, tous les r\u00e9sultats du PPV\"><\/a><div class=\"vlp-layout-zone-side\"><div class=\"vlp-block-4 vlp-link-image\"><img loading=\"lazy\" decoding=\"async\" style=\"max-width: 792px;\" width=\"792\" height=\"445\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/06\/UFC-303-Pereira-eteint-Prochazka-Ghemmouri-se-rate-tous-les-resultats-du-PPV.png\" class=\"attachment-800x445 size-800x445\" alt=\"UFC 303 Pereira \u00e9teint Proch\u00e1zka, Ghemmouri se rate, tous les r\u00e9sultats du PPV\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/06\/UFC-303-Pereira-eteint-Prochazka-Ghemmouri-se-rate-tous-les-resultats-du-PPV.png 1200w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/06\/UFC-303-Pereira-eteint-Prochazka-Ghemmouri-se-rate-tous-les-resultats-du-PPV-300x169.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/06\/UFC-303-Pereira-eteint-Prochazka-Ghemmouri-se-rate-tous-les-resultats-du-PPV-1024x575.png 1024w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/06\/UFC-303-Pereira-eteint-Prochazka-Ghemmouri-se-rate-tous-les-resultats-du-PPV-768x431.png 768w\" sizes=\"auto, (max-width: 792px) 100vw, 792px\" \/><\/div><\/div><div class=\"vlp-layout-zone-main\"><div class=\"vlp-block-0 vlp-link-title\">UFC 303 : Pereira \u00e9teint Proch\u00e1zka, Ghemmouri se rate, tous les r\u00e9sultats du PPV<\/div><div class=\"vlp-block-1 vlp-link-summary\">Alex Pereira met KO Ji\u0159\u00ed Proch\u00e1zka dans la 2e reprise.<\/div><div class=\"vlp-block-2 vlp-link-button\">Lire l'article<\/div><div class=\"vlp-block-3 vlp-link-url\">dicodusport.fr<\/div><\/div><\/div>\n<p style=\"text-align: justify;\">\u00ab\u00a0<em>Poatan<\/em>\u00a0\u00bb parti conqu\u00e9rir la cat\u00e9gorie des poids lourds, le Tch\u00e8que se voit offrir une nouvelle chance de rafler la ceinture d\u00e9sormais vacante. Pour cela, il lui faudra dominer <strong>Carlos Ulberg<\/strong>, un combattant qui s&rsquo;\u00e9tait inclin\u00e9 lors de sa toute premi\u00e8re apparition \u00e0 l&rsquo;UFC, mais qui a remport\u00e9 ses neuf combats suivants, dominant au passage <strong>Jan B\u0142achowicz<\/strong> ou <strong>Dominick Reyes<\/strong>. De quoi promettre un bel affrontement dans la cage du Kesaya Center.<\/p>\n<h2 style=\"text-align: justify;\" align=\"justify\">Date, heure et cha\u00eene TV de l&rsquo;UFC 327<\/h2>\n<p style=\"text-align: justify;\">La soir\u00e9e de l&rsquo;<strong>UFC 327<\/strong> d\u00e9butera \u00e0 23h30 heure fran\u00e7aise, samedi, avec les combats pr\u00e9liminaires, mais la carte principale ne d\u00e9butera pas avant 03h00. Le combat pour la ceinture des poids mi-lourds sera au plus t\u00f4t \u00e0 5h00.<\/p>\n<p style=\"text-align: justify;\">C&rsquo;est <strong>RMC Sport<\/strong> qui diffusera la carte pr\u00e9liminaire et la carte principale, avec une soir\u00e9e sp\u00e9ciale \u00e0 partir de 1h00. La carte pr\u00e9-pr\u00e9liminaire sera elle retransmise sur la cha\u00eene Twitch de la cha\u00eene.<\/p>\n<p style=\"text-align: justify;\">La soir\u00e9e est \u00e9galement retransmise en int\u00e9gralit\u00e9 sur le UFC League Pass.<\/p>\n<h2 style=\"text-align: justify;\" align=\"justify\">Carte principale UFC 327 (3h00) :<\/h2>\n<ul style=\"text-align: justify;\">\n<li>Ji\u0159\u00ed Proch\u00e1zka vs. Carlos Ulberg &#8211; pour la ceinture des poids mi-lourds<\/li>\n<li>Azamat Murzakanov vs. Paulo Costa &#8211; poids mi-lourds<\/li>\n<li>Heavyweight Curtis Blaydes vs. Josh Hokit Light &#8211; poids lourds<\/li>\n<li>Heavyweight Dominick Reyes vs. Johnny Walker &#8211; poids mi-lourds<\/li>\n<li>Featherweight Cub Swanson vs. Nate Landwehr &#8211; poids plumes<\/li>\n<\/ul>\n<h2 style=\"text-align: justify;\" align=\"justify\">Carte pr\u00e9liminaire UFC 327 (1h00) :<\/h2>\n<ul style=\"text-align: justify;\">\n<li>Patr\u00edcio Pitbull vs. Aaron Pico &#8211; poids plumes<\/li>\n<li>Mateusz Gamrot vs. Esteban Ribovics &#8211; poids l\u00e9gers<\/li>\n<li>Kevin Holland vs. Randy Brown &#8211; poids mi-moyens<\/li>\n<li>Tatiana Suarez vs. Loopy Godinez &#8211; poids pailles<\/li>\n<\/ul>\n<h2 style=\"text-align: justify;\" align=\"justify\">Carte pr\u00e9-pr\u00e9liminaire UFC 327 (23h00) :<\/h2>\n<ul style=\"text-align: justify;\">\n<li>Chris Padilla vs. MarQuel Mederos &#8211; poids l\u00e9gers<\/li>\n<li>Kelvin Gastelum vs. Vicente Luque &#8211; poids moyens<\/li>\n<li>Charles Radtke vs. Francisco Prado &#8211; poids mi-moyens<\/li>\n<\/ul>\n<h2 style=\"text-align: justify;\">Les cotes de Ji\u0159\u00ed Proch\u00e1zka &#8211; Carlos Ulberg<\/h2>\n<table style=\"width: 840px;\">\n<tbody>\n<tr style=\"height: 16px;\">\n<td style=\"background-color: #404040; text-align: left; border-color: #ededed; width: 532px;\" colspan=\"2\"><span style=\"font-size: 12px; color: #ffffff;\">Dimanche 12 avril 5h00<\/span><\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"background-color: #ffffff; border-color: #ededed; vertical-align: middle; text-align: center; width: 400px;\"><span style=\"font-size: 10px;\"><span style=\"font-size: 14px;\"><strong>Ji\u0159\u00ed Proch\u00e1zka<\/strong><\/span><br \/>\n<a href=\"https:\/\/www.winamax.fr\/paris-sportifs\/match\/69446826?banid=33423\" class=\"su-button su-button-style-flat su-button-wide\" style=\"color:#fff;background-color:#013369;border-color:#012954;border-radius:5px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#fff;padding:0px 20px;font-size:16px;line-height:32px;border-color:#4e7196;border-radius:5px;text-shadow:none\"> 1.78<\/span><\/a><\/span><\/td>\n<td style=\"background-color: #ffffff; border-color: #ededed; vertical-align: middle; text-align: center; width: 400px;\"><span style=\"font-size: 10px;\"><span style=\"font-size: 14px;\"><strong>Carlos Ulberg<\/strong><\/span><br \/>\n<a href=\"https:\/\/www.winamax.fr\/paris-sportifs\/match\/69446826?banid=33423\" class=\"su-button su-button-style-flat su-button-wide\" style=\"color:#fff;background-color:#013369;border-color:#012954;border-radius:5px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#fff;padding:0px 20px;font-size:16px;line-height:32px;border-color:#4e7196;border-radius:5px;text-shadow:none\"> 1.90<\/span><\/a><\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p style=\"text-align: justify;\">Tentez votre chance en profitant de votre <a href=\"https:\/\/www.winamax.fr\/registration\/landing\/affiliation_Bonus100?banid=33423\">1er d\u00e9p\u00f4t doubl\u00e9 jusqu&rsquo;\u00e0 100 \u20ac<\/a> direct en paris gratuits sur Winamax !<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;UFC 327 se d\u00e9roule dans la nuit du samedi 11 au dimanche 12 avril aux \u00c9tats-Unis, \u00e0 Miami. Programme et cha\u00eene TV.<\/p>\n","protected":false},"author":59,"featured_media":661437,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[44295,10666],"tags":[16878,1222,1224],"class_list":["post-661436","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chaine-tv","category-mma","tag-breve","tag-mma","tag-ufc"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>UFC 327 : Liste des combats, Diffusion TV, Cotes, Date et Heure<\/title>\n<meta name=\"description\" content=\"L&#039;UFC 327 se d\u00e9roule dans la nuit du samedi 11 au dimanche 12 avril aux \u00c9tats-Unis, \u00e0 Miami. Programme et cha\u00eene TV.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/ufc-327-liste-des-combats-diffusion-tv-cotes-date-et-heure\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"UFC 327 : Liste des combats, Diffusion TV, Cotes, Date et Heure\" \/>\n<meta property=\"og:description\" content=\"L&#039;UFC 327 se d\u00e9roule dans la nuit du samedi 11 au dimanche 12 avril aux \u00c9tats-Unis, \u00e0 Miami. Programme et cha\u00eene TV.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/ufc-327-liste-des-combats-diffusion-tv-cotes-date-et-heure\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/sebastien.gente\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-09T10:35:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/04\/UFC-327-Liste-des-combats-Diffusion-TV-Cotes-Date-et-Heure.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"S\u00e9bastien Gente\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"UFC 327 : Liste des combats, Diffusion TV, Cotes, Date et Heure\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/globulo24\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/ufc-327-liste-des-combats-diffusion-tv-cotes-date-et-heure\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/ufc-327-liste-des-combats-diffusion-tv-cotes-date-et-heure\\\/\"},\"author\":{\"name\":\"S\u00e9bastien Gente\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/627966a6cde45dbd8c5e36ac85d783da\"},\"headline\":\"UFC 327 : Liste des combats, Diffusion TV, Cotes, Date et Heure\",\"datePublished\":\"2026-04-09T10:35:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/ufc-327-liste-des-combats-diffusion-tv-cotes-date-et-heure\\\/\"},\"wordCount\":644,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/ufc-327-liste-des-combats-diffusion-tv-cotes-date-et-heure\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/UFC-327-Liste-des-combats-Diffusion-TV-Cotes-Date-et-Heure.png\",\"keywords\":[\"br\u00e8ve\",\"MMA\",\"UFC\"],\"articleSection\":[\"Cha\u00eene TV\",\"MMA\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/ufc-327-liste-des-combats-diffusion-tv-cotes-date-et-heure\\\/#respond\"]}],\"copyrightYear\":\"2026\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/ufc-327-liste-des-combats-diffusion-tv-cotes-date-et-heure\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/ufc-327-liste-des-combats-diffusion-tv-cotes-date-et-heure\\\/\",\"name\":\"UFC 327 : Liste des combats, Diffusion TV, Cotes, Date et Heure\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/ufc-327-liste-des-combats-diffusion-tv-cotes-date-et-heure\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/ufc-327-liste-des-combats-diffusion-tv-cotes-date-et-heure\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/UFC-327-Liste-des-combats-Diffusion-TV-Cotes-Date-et-Heure.png\",\"datePublished\":\"2026-04-09T10:35:00+00:00\",\"description\":\"L'UFC 327 se d\u00e9roule dans la nuit du samedi 11 au dimanche 12 avril aux \u00c9tats-Unis, \u00e0 Miami. Programme et cha\u00eene TV.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/ufc-327-liste-des-combats-diffusion-tv-cotes-date-et-heure\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/ufc-327-liste-des-combats-diffusion-tv-cotes-date-et-heure\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/ufc-327-liste-des-combats-diffusion-tv-cotes-date-et-heure\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/UFC-327-Liste-des-combats-Diffusion-TV-Cotes-Date-et-Heure.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/UFC-327-Liste-des-combats-Diffusion-TV-Cotes-Date-et-Heure.png\",\"width\":1200,\"height\":674,\"caption\":\"UFC 327 Liste des combats, Diffusion TV, Cotes, Date et Heure\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/ufc-327-liste-des-combats-diffusion-tv-cotes-date-et-heure\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"UFC 327 : Liste des combats, Diffusion TV, Cotes, Date et Heure\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/627966a6cde45dbd8c5e36ac85d783da\",\"name\":\"S\u00e9bastien Gente\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"caption\":\"S\u00e9bastien Gente\"},\"description\":\"John Stockton, Gianni Bugno, Zinedine Zidane, Steffi Graf, Frode Andresen, St\u00e9phane Stoecklin, Davis Kamoga, Primoz Peterka, Werner Schlager et Aur\u00e9lien Rougerie. Point commun entre ces sportifs? Ils m'ont fait r\u00eaver et ont berc\u00e9 mon adolescence. Je suis un fondu de sports et j'essaie de retranscrire ma passion \u00e0 travers mes articles. Originaire du P\u00e9rigord, ma passion pour les Girondins, les Jaunards et les Jazzmen transpire dans mes \u00e9crits. \u00c0 Dicodusport depuis 2021, je d\u00e9niche les sports m\u00e9connus dans lesquels la France brille, et il y en a !\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/sebastien.gente\\\/\",\"https:\\\/\\\/www.instagram.com\\\/sebgente\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/sbastien-gente-a29583169\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/globulo24\",\"SebastienGente\"],\"worksFor\":\"S\u00e9bastien GENTE\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/sebastiengente\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"UFC 327 : Liste des combats, Diffusion TV, Cotes, Date et Heure","description":"L'UFC 327 se d\u00e9roule dans la nuit du samedi 11 au dimanche 12 avril aux \u00c9tats-Unis, \u00e0 Miami. Programme et cha\u00eene TV.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/ufc-327-liste-des-combats-diffusion-tv-cotes-date-et-heure\/","og_locale":"fr_FR","og_type":"article","og_title":"UFC 327 : Liste des combats, Diffusion TV, Cotes, Date et Heure","og_description":"L'UFC 327 se d\u00e9roule dans la nuit du samedi 11 au dimanche 12 avril aux \u00c9tats-Unis, \u00e0 Miami. Programme et cha\u00eene TV.","og_url":"https:\/\/dicodusport.fr\/blog\/ufc-327-liste-des-combats-diffusion-tv-cotes-date-et-heure\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/sebastien.gente\/","article_published_time":"2026-04-09T10:35:00+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/04\/UFC-327-Liste-des-combats-Diffusion-TV-Cotes-Date-et-Heure.png","type":"image\/png"}],"author":"S\u00e9bastien Gente","twitter_card":"summary_large_image","twitter_title":"UFC 327 : Liste des combats, Diffusion TV, Cotes, Date et Heure","twitter_creator":"@https:\/\/twitter.com\/globulo24","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/ufc-327-liste-des-combats-diffusion-tv-cotes-date-et-heure\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/ufc-327-liste-des-combats-diffusion-tv-cotes-date-et-heure\/"},"author":{"name":"S\u00e9bastien Gente","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da"},"headline":"UFC 327 : Liste des combats, Diffusion TV, Cotes, Date et Heure","datePublished":"2026-04-09T10:35:00+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/ufc-327-liste-des-combats-diffusion-tv-cotes-date-et-heure\/"},"wordCount":644,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/ufc-327-liste-des-combats-diffusion-tv-cotes-date-et-heure\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/04\/UFC-327-Liste-des-combats-Diffusion-TV-Cotes-Date-et-Heure.png","keywords":["br\u00e8ve","MMA","UFC"],"articleSection":["Cha\u00eene TV","MMA"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/ufc-327-liste-des-combats-diffusion-tv-cotes-date-et-heure\/#respond"]}],"copyrightYear":"2026","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/ufc-327-liste-des-combats-diffusion-tv-cotes-date-et-heure\/","url":"https:\/\/dicodusport.fr\/blog\/ufc-327-liste-des-combats-diffusion-tv-cotes-date-et-heure\/","name":"UFC 327 : Liste des combats, Diffusion TV, Cotes, Date et Heure","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/ufc-327-liste-des-combats-diffusion-tv-cotes-date-et-heure\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/ufc-327-liste-des-combats-diffusion-tv-cotes-date-et-heure\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/04\/UFC-327-Liste-des-combats-Diffusion-TV-Cotes-Date-et-Heure.png","datePublished":"2026-04-09T10:35:00+00:00","description":"L'UFC 327 se d\u00e9roule dans la nuit du samedi 11 au dimanche 12 avril aux \u00c9tats-Unis, \u00e0 Miami. Programme et cha\u00eene TV.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/ufc-327-liste-des-combats-diffusion-tv-cotes-date-et-heure\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/ufc-327-liste-des-combats-diffusion-tv-cotes-date-et-heure\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/ufc-327-liste-des-combats-diffusion-tv-cotes-date-et-heure\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/04\/UFC-327-Liste-des-combats-Diffusion-TV-Cotes-Date-et-Heure.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/04\/UFC-327-Liste-des-combats-Diffusion-TV-Cotes-Date-et-Heure.png","width":1200,"height":674,"caption":"UFC 327 Liste des combats, Diffusion TV, Cotes, Date et Heure"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/ufc-327-liste-des-combats-diffusion-tv-cotes-date-et-heure\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"UFC 327 : Liste des combats, Diffusion TV, Cotes, Date et Heure"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da","name":"S\u00e9bastien Gente","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","caption":"S\u00e9bastien Gente"},"description":"John Stockton, Gianni Bugno, Zinedine Zidane, Steffi Graf, Frode Andresen, St\u00e9phane Stoecklin, Davis Kamoga, Primoz Peterka, Werner Schlager et Aur\u00e9lien Rougerie. Point commun entre ces sportifs? Ils m'ont fait r\u00eaver et ont berc\u00e9 mon adolescence. Je suis un fondu de sports et j'essaie de retranscrire ma passion \u00e0 travers mes articles. Originaire du P\u00e9rigord, ma passion pour les Girondins, les Jaunards et les Jazzmen transpire dans mes \u00e9crits. \u00c0 Dicodusport depuis 2021, je d\u00e9niche les sports m\u00e9connus dans lesquels la France brille, et il y en a !","sameAs":["https:\/\/www.facebook.com\/sebastien.gente\/","https:\/\/www.instagram.com\/sebgente\/","https:\/\/www.linkedin.com\/in\/sbastien-gente-a29583169\/","https:\/\/x.com\/https:\/\/twitter.com\/globulo24","SebastienGente"],"worksFor":"S\u00e9bastien GENTE","url":"https:\/\/dicodusport.fr\/blog\/author\/sebastiengente\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/661436","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/59"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=661436"}],"version-history":[{"count":1,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/661436\/revisions"}],"predecessor-version":[{"id":661450,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/661436\/revisions\/661450"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/661437"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=661436"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=661436"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=661436"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}