{"id":661455,"date":"2026-04-10T20:15:04","date_gmt":"2026-04-10T18:15:04","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=661455&#038;preview=true&#038;preview_id=661455"},"modified":"2026-04-10T20:18:17","modified_gmt":"2026-04-10T18:18:17","slug":"marseille-metz-sur-quelle-chaine-tv-a-quelle-heure-et-avec-quelles-compositions-ligue-1-2025-2026","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/marseille-metz-sur-quelle-chaine-tv-a-quelle-heure-et-avec-quelles-compositions-ligue-1-2025-2026\/","title":{"rendered":"Marseille-Metz : sur quelle cha\u00eene TV, \u00e0 quelle heure et avec quelles compositions ?"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><strong><span class=\"html-span xdj266r x14z9mp xat24cr x1lziwak xexx8yu xyri2b x18d9i69 x1c1uobl x1hl2dhg x16tdsg8 x1vvkbs x4k7w5x x1h91t0o x1h9r5lt x1jfb8zj xv2umb2 x1beo9mf xaigb6o x12ejxvf x3igimt xarpa2k xedcshv x1lytzrv x1t2pt76 x7ja8zs x1qrby5j\"><span class=\"x193iq5w xeuugli x13faqbe x1vvkbs x1xmvt09 x1lliihq x1s928wv xhkezso x1gmr53x x1cpjm7i x1fgarty x1943h6x xudqn12 x3x7a5m x6prxxf xvq8zen xo1l8bm xzsf02u\" dir=\"auto\">D\u00e9couvrez l\u2019heure, la cha\u00eene TV et les compositions pour Marseille-Metz en Ligue 1. Toutes les infos essentielles pour suivre le match.<\/span><\/span><\/strong><\/em><\/p>\n<ul style=\"text-align: justify;\">\n<li><strong>\u00c0 ce sujet &#8211;\u00a0<a href=\"https:\/\/dicodusport.fr\/blog\/classement-ligue-1-2025-2026\/\">Classement Ligue 1 2025-2026<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">La rencontre entre l&rsquo;Olympique de Marseille et le FC Metz, comptant pour la 29\u00e8me journ\u00e9e de Ligue 1 2025\/2026, aura lieu vendredi 10 avril 2026 \u00e0 21h05, au Stade V\u00e9lodrome de Marseille.<\/p>\n<h2 style=\"text-align: justify;\">Victoire indispensable pour Marseille<\/h2>\n<p style=\"text-align: justify;\">\u00c0 sept journ\u00e9es de la fin de saison en Ligue 1, <strong>Marseille<\/strong> n&rsquo;est clairement pas assur\u00e9 de voir la Ligue des champions la saison prochaine. Cinq clubs peuvent encore pr\u00e9tendre \u00e0 la troisi\u00e8me place (et \u00e0 la quatri\u00e8me qui donne acc\u00e8s aux barrages), et en ce sens, l&rsquo;OM a fait une bien mauvaise op\u00e9ration en s&rsquo;inclinant dimanche soir \u00e0 Monaco, qui a rejoint les Phoc\u00e9ens au classement.<\/p>\n<div class=\"vlp-link-container vlp-layout-article\"><a href=\"https:\/\/dicodusport.fr\/blog\/monaco-renverse-marseille-et-relance-la-course-a-la-ligue-des-champions\/\" class=\"vlp-link\" title=\"Monaco renverse Marseille et relance la course \u00e0 la Ligue des Champions\"><\/a><div class=\"vlp-layout-zone-side\"><div class=\"vlp-block-4 vlp-link-image\"><img loading=\"lazy\" decoding=\"async\" style=\"max-width: 792px;\" width=\"792\" height=\"445\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/04\/Monaco-renverse-Marseille-et-relance-la-course-a-la-Ligue-des-Champions.png\" class=\"attachment-800x445 size-800x445\" alt=\"Monaco renverse Marseille et relance la course \u00e0 la Ligue des Champions\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/04\/Monaco-renverse-Marseille-et-relance-la-course-a-la-Ligue-des-Champions.png 1200w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/04\/Monaco-renverse-Marseille-et-relance-la-course-a-la-Ligue-des-Champions-300x169.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/04\/Monaco-renverse-Marseille-et-relance-la-course-a-la-Ligue-des-Champions-1024x575.png 1024w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/04\/Monaco-renverse-Marseille-et-relance-la-course-a-la-Ligue-des-Champions-768x431.png 768w\" sizes=\"auto, (max-width: 792px) 100vw, 792px\" \/><\/div><\/div><div class=\"vlp-layout-zone-main\"><div class=\"vlp-block-0 vlp-link-title\">Monaco renverse Marseille et relance la course \u00e0 la Ligue des Champions<\/div><div class=\"vlp-block-1 vlp-link-summary\">Dans un choc capital pour l\u2019Europe, l\u2019AS Monaco a pris le dessus sur l\u2019Olympique de Marseille (2-1) au terme d\u2019un match longtemps ferm\u00e9 mais totalement fou dans ses derni\u00e8res minutes.\u00a0<\/div><div class=\"vlp-block-2 vlp-link-button\">Lire l'article<\/div><div class=\"vlp-block-3 vlp-link-url\">dicodusport.fr<\/div><\/div><\/div>\n<p style=\"text-align: justify;\">Heureusement, le match de ce vendredi soir est plus qu&rsquo;abordable. Car c&rsquo;est la lanterne rouge qui se rend au V\u00e9lodrome. <strong>Metz<\/strong> n&rsquo;est pas officiellement rel\u00e9gu\u00e9 en Ligue 2, mais avec 12 points de retard sur la zone de s\u00e9curit\u00e9, c&rsquo;est probablement in\u00e9luctable. D&rsquo;autant que les Lorrains n&rsquo;ont plus gagn\u00e9 depuis novembre en Ligue 1, et il semble peu probable qu&rsquo;ils retrouvent le chemin de la victoire ce soir.<\/p>\n<p style=\"text-align: justify;\">Au match aller, \u00e0 Metz, Marseille \u00e9tait facilement venu s&rsquo;imposer <strong>0-3<\/strong> avec des buts de <strong>Paix\u00e3o<\/strong>, <strong>O&rsquo;Riley<\/strong> et <strong>Gouiri<\/strong>. Chez les bookmakers, l&rsquo;OM est grand favori de la rencontre.<\/p>\n<h2 style=\"text-align: justify;\">Ligue 1 : le programme TV de Marseille-Metz<\/h2>\n<h3 style=\"text-align: justify;\">Vendredi 10 avril 2026<\/h3>\n<p style=\"text-align: justify;\"><b>Match diffus\u00e9 sur Ligue 1+<\/b><b>\u00a0: <\/b>d\u00e9but du match \u00e0<strong> 21h05.<\/strong><\/p>\n<h2 style=\"text-align: justify;\">Les compositions officielles de Marseille-Metz<\/h2>\n<h3 style=\"text-align: justify;\">La composition de Marseille<\/h3>\n<p style=\"text-align: justify;\">Rulli, Medina, Balerdi, Pavard, Paixao, Timber, Hojbjerg, Weah, Gouiri, Greenwood, Aubameyang<\/p>\n<h3 style=\"text-align: justify;\">La composition de Metz<\/h3>\n<p style=\"text-align: justify;\">Sy, Colin, Toure, Sane, Kouao, Deminguet, Gbamin, Tsitaishvili, Hein, Sarr, Diallo<\/p>\n<h2 style=\"text-align: justify;\">Les cotes de Marseille-Metz<\/h2>\n<table style=\"width: 840px;\">\n<tbody>\n<tr style=\"height: 16px;\">\n<td style=\"background-color: #404040; border-color: #ededed; width: 840px; text-align: left;\" colspan=\"3\"><strong><span style=\"font-size: 12px; color: #ffffff;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-512842\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Logo-Winamax.png\" alt=\"\" width=\"14\" height=\"13\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Logo-Winamax.png 290w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Logo-Winamax-150x150.png 150w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Logo-Winamax-80x80.png 80w\" sizes=\"auto, (max-width: 14px) 100vw, 14px\" \/> Vendredi 10 avril 2026 21h05<\/span><\/strong><\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"background-color: #ffffff; border-color: #ededed; vertical-align: middle; text-align: center; width: 266px;\"><span style=\"font-size: 10px;\"><span style=\"font-size: 14px;\"><strong>Marseille<br \/>\n<\/strong><\/span><\/span><span style=\"font-size: 10px;\"><a href=\"https:\/\/www.winamax.fr\/paris-sportifs\/match\/61526494?banid=33423\" class=\"su-button su-button-style-flat su-button-wide\" style=\"color:#fff;background-color:#0860ff;border-color:#074dcc;border-radius:5px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#fff;padding:0px 20px;font-size:16px;line-height:32px;border-color:#5390ff;border-radius:5px;text-shadow:none\"> 1.21<\/span><\/a><\/span><\/td>\n<td style=\"background-color: #ffffff; border-color: #ededed; vertical-align: middle; text-align: center; width: 266px;\"><span style=\"font-size: 10px;\"><span style=\"font-size: 14px;\"><strong>Match nul<\/strong><\/span><br \/>\n<a href=\"https:\/\/www.winamax.fr\/paris-sportifs\/match\/61526494?banid=33423\" class=\"su-button su-button-style-flat su-button-wide\" style=\"color:#fff;background-color:#0860ff;border-color:#074dcc;border-radius:5px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#fff;padding:0px 20px;font-size:16px;line-height:32px;border-color:#5390ff;border-radius:5px;text-shadow:none\"> 6.50<\/span><\/a><\/span><\/td>\n<td style=\"background-color: #ffffff; border-color: #ededed; vertical-align: middle; text-align: center; width: 266px;\"><span style=\"font-size: 10px;\"><span style=\"font-size: 14px;\"><strong>Lille<\/strong><\/span><br \/>\n<a href=\"https:\/\/www.winamax.fr\/paris-sportifs\/match\/61526494?banid=33423\" class=\"su-button su-button-style-flat su-button-wide\" style=\"color:#fff;background-color:#0860ff;border-color:#074dcc;border-radius:5px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#fff;padding:0px 20px;font-size:16px;line-height:32px;border-color:#5390ff;border-radius:5px;text-shadow:none\"> 10<\/span><\/a><\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p style=\"text-align: justify;\">Tentez votre chance en profitant de votre <a href=\"https:\/\/www.winamax.fr\/registration\/landing\/affiliation_Bonus100?banid=33423\">1er d\u00e9p\u00f4t doubl\u00e9 jusqu&rsquo;\u00e0 100 \u20ac<\/a> direct en paris gratuits sur Winamax !<\/p>\n","protected":false},"excerpt":{"rendered":"<p>D\u00e9couvrez l\u2019heure, la cha\u00eene TV et les compositions pour Marseille-Metz en Ligue 1. Toutes les infos essentielles pour suivre le match.<\/p>\n","protected":false},"author":59,"featured_media":661475,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[44295,47045],"tags":[16878,5587,75,1554,446,8799],"class_list":["post-661455","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chaine-tv","category-ligue-1","tag-breve","tag-fc-metz","tag-football","tag-ligue-1","tag-marseille","tag-programme-tv"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Marseille-Metz : sur quelle cha\u00eene TV, \u00e0 quelle heure et avec quelles compositions ?<\/title>\n<meta name=\"description\" content=\"D\u00e9couvrez l\u2019heure, la cha\u00eene TV et les compositions pour Marseille-Metz en Ligue 1. Toutes les infos essentielles pour suivre le match.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/marseille-metz-sur-quelle-chaine-tv-a-quelle-heure-et-avec-quelles-compositions-ligue-1-2025-2026\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Marseille-Metz : sur quelle cha\u00eene TV, \u00e0 quelle heure et avec quelles compositions ?\" \/>\n<meta property=\"og:description\" content=\"D\u00e9couvrez l\u2019heure, la cha\u00eene TV et les compositions pour Marseille-Metz en Ligue 1. Toutes les infos essentielles pour suivre le match.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/marseille-metz-sur-quelle-chaine-tv-a-quelle-heure-et-avec-quelles-compositions-ligue-1-2025-2026\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/sebastien.gente\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-10T18:15:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-10T18:18:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/04\/Marseille-Metz-sur-quelle-chaine-TV-a-quelle-heure-et-avec-quelles-compositions.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"S\u00e9bastien Gente\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Marseille-Metz : sur quelle cha\u00eene TV, \u00e0 quelle heure et avec quelles compositions ?\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/globulo24\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/marseille-metz-sur-quelle-chaine-tv-a-quelle-heure-et-avec-quelles-compositions-ligue-1-2025-2026\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/marseille-metz-sur-quelle-chaine-tv-a-quelle-heure-et-avec-quelles-compositions-ligue-1-2025-2026\/\"},\"author\":{\"name\":\"S\u00e9bastien Gente\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da\"},\"headline\":\"Marseille-Metz : sur quelle cha\u00eene TV, \u00e0 quelle heure et avec quelles compositions ?\",\"datePublished\":\"2026-04-10T18:15:04+00:00\",\"dateModified\":\"2026-04-10T18:18:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/marseille-metz-sur-quelle-chaine-tv-a-quelle-heure-et-avec-quelles-compositions-ligue-1-2025-2026\/\"},\"wordCount\":507,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/marseille-metz-sur-quelle-chaine-tv-a-quelle-heure-et-avec-quelles-compositions-ligue-1-2025-2026\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/04\/Marseille-Metz-sur-quelle-chaine-TV-a-quelle-heure-et-avec-quelles-compositions.png\",\"keywords\":[\"br\u00e8ve\",\"FC Metz\",\"Football\",\"Ligue 1\",\"Marseille\",\"Programme TV\"],\"articleSection\":[\"Cha\u00eene TV\",\"Ligue 1\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/marseille-metz-sur-quelle-chaine-tv-a-quelle-heure-et-avec-quelles-compositions-ligue-1-2025-2026\/#respond\"]}],\"copyrightYear\":\"2026\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/marseille-metz-sur-quelle-chaine-tv-a-quelle-heure-et-avec-quelles-compositions-ligue-1-2025-2026\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/marseille-metz-sur-quelle-chaine-tv-a-quelle-heure-et-avec-quelles-compositions-ligue-1-2025-2026\/\",\"name\":\"Marseille-Metz : sur quelle cha\u00eene TV, \u00e0 quelle heure et avec quelles compositions ?\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/marseille-metz-sur-quelle-chaine-tv-a-quelle-heure-et-avec-quelles-compositions-ligue-1-2025-2026\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/marseille-metz-sur-quelle-chaine-tv-a-quelle-heure-et-avec-quelles-compositions-ligue-1-2025-2026\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/04\/Marseille-Metz-sur-quelle-chaine-TV-a-quelle-heure-et-avec-quelles-compositions.png\",\"datePublished\":\"2026-04-10T18:15:04+00:00\",\"dateModified\":\"2026-04-10T18:18:17+00:00\",\"description\":\"D\u00e9couvrez l\u2019heure, la cha\u00eene TV et les compositions pour Marseille-Metz en Ligue 1. Toutes les infos essentielles pour suivre le match.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/marseille-metz-sur-quelle-chaine-tv-a-quelle-heure-et-avec-quelles-compositions-ligue-1-2025-2026\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/marseille-metz-sur-quelle-chaine-tv-a-quelle-heure-et-avec-quelles-compositions-ligue-1-2025-2026\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/marseille-metz-sur-quelle-chaine-tv-a-quelle-heure-et-avec-quelles-compositions-ligue-1-2025-2026\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/04\/Marseille-Metz-sur-quelle-chaine-TV-a-quelle-heure-et-avec-quelles-compositions.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/04\/Marseille-Metz-sur-quelle-chaine-TV-a-quelle-heure-et-avec-quelles-compositions.png\",\"width\":1200,\"height\":674,\"caption\":\"Marseille-Metz sur quelle cha\u00eene TV, \u00e0 quelle heure et avec quelles compositions\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/marseille-metz-sur-quelle-chaine-tv-a-quelle-heure-et-avec-quelles-compositions-ligue-1-2025-2026\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Marseille-Metz : sur quelle cha\u00eene TV, \u00e0 quelle heure et avec quelles compositions ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da\",\"name\":\"S\u00e9bastien Gente\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"caption\":\"S\u00e9bastien Gente\"},\"description\":\"John Stockton, Gianni Bugno, Zinedine Zidane, Steffi Graf, Frode Andresen, St\u00e9phane Stoecklin, Davis Kamoga, Primoz Peterka, Werner Schlager et Aur\u00e9lien Rougerie. Point commun entre ces sportifs? Ils m'ont fait r\u00eaver et ont berc\u00e9 mon adolescence. Je suis un fondu de sports et j'essaie de retranscrire ma passion \u00e0 travers mes articles. Originaire du P\u00e9rigord, ma passion pour les Girondins, les Jaunards et les Jazzmen transpire dans mes \u00e9crits. \u00c0 Dicodusport depuis 2021, je d\u00e9niche les sports m\u00e9connus dans lesquels la France brille, et il y en a !\",\"sameAs\":[\"https:\/\/www.facebook.com\/sebastien.gente\/\",\"https:\/\/www.instagram.com\/sebgente\/\",\"https:\/\/www.linkedin.com\/in\/sbastien-gente-a29583169\/\",\"https:\/\/x.com\/https:\/\/twitter.com\/globulo24\",\"SebastienGente\"],\"worksFor\":\"S\u00e9bastien GENTE\",\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/sebastiengente\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Marseille-Metz : sur quelle cha\u00eene TV, \u00e0 quelle heure et avec quelles compositions ?","description":"D\u00e9couvrez l\u2019heure, la cha\u00eene TV et les compositions pour Marseille-Metz en Ligue 1. Toutes les infos essentielles pour suivre le match.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/marseille-metz-sur-quelle-chaine-tv-a-quelle-heure-et-avec-quelles-compositions-ligue-1-2025-2026\/","og_locale":"fr_FR","og_type":"article","og_title":"Marseille-Metz : sur quelle cha\u00eene TV, \u00e0 quelle heure et avec quelles compositions ?","og_description":"D\u00e9couvrez l\u2019heure, la cha\u00eene TV et les compositions pour Marseille-Metz en Ligue 1. Toutes les infos essentielles pour suivre le match.","og_url":"https:\/\/dicodusport.fr\/blog\/marseille-metz-sur-quelle-chaine-tv-a-quelle-heure-et-avec-quelles-compositions-ligue-1-2025-2026\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/sebastien.gente\/","article_published_time":"2026-04-10T18:15:04+00:00","article_modified_time":"2026-04-10T18:18:17+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/04\/Marseille-Metz-sur-quelle-chaine-TV-a-quelle-heure-et-avec-quelles-compositions.png","type":"image\/png"}],"author":"S\u00e9bastien Gente","twitter_card":"summary_large_image","twitter_title":"Marseille-Metz : sur quelle cha\u00eene TV, \u00e0 quelle heure et avec quelles compositions ?","twitter_creator":"@https:\/\/twitter.com\/globulo24","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/marseille-metz-sur-quelle-chaine-tv-a-quelle-heure-et-avec-quelles-compositions-ligue-1-2025-2026\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/marseille-metz-sur-quelle-chaine-tv-a-quelle-heure-et-avec-quelles-compositions-ligue-1-2025-2026\/"},"author":{"name":"S\u00e9bastien Gente","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da"},"headline":"Marseille-Metz : sur quelle cha\u00eene TV, \u00e0 quelle heure et avec quelles compositions ?","datePublished":"2026-04-10T18:15:04+00:00","dateModified":"2026-04-10T18:18:17+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/marseille-metz-sur-quelle-chaine-tv-a-quelle-heure-et-avec-quelles-compositions-ligue-1-2025-2026\/"},"wordCount":507,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/marseille-metz-sur-quelle-chaine-tv-a-quelle-heure-et-avec-quelles-compositions-ligue-1-2025-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/04\/Marseille-Metz-sur-quelle-chaine-TV-a-quelle-heure-et-avec-quelles-compositions.png","keywords":["br\u00e8ve","FC Metz","Football","Ligue 1","Marseille","Programme TV"],"articleSection":["Cha\u00eene TV","Ligue 1"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/marseille-metz-sur-quelle-chaine-tv-a-quelle-heure-et-avec-quelles-compositions-ligue-1-2025-2026\/#respond"]}],"copyrightYear":"2026","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/marseille-metz-sur-quelle-chaine-tv-a-quelle-heure-et-avec-quelles-compositions-ligue-1-2025-2026\/","url":"https:\/\/dicodusport.fr\/blog\/marseille-metz-sur-quelle-chaine-tv-a-quelle-heure-et-avec-quelles-compositions-ligue-1-2025-2026\/","name":"Marseille-Metz : sur quelle cha\u00eene TV, \u00e0 quelle heure et avec quelles compositions ?","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/marseille-metz-sur-quelle-chaine-tv-a-quelle-heure-et-avec-quelles-compositions-ligue-1-2025-2026\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/marseille-metz-sur-quelle-chaine-tv-a-quelle-heure-et-avec-quelles-compositions-ligue-1-2025-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/04\/Marseille-Metz-sur-quelle-chaine-TV-a-quelle-heure-et-avec-quelles-compositions.png","datePublished":"2026-04-10T18:15:04+00:00","dateModified":"2026-04-10T18:18:17+00:00","description":"D\u00e9couvrez l\u2019heure, la cha\u00eene TV et les compositions pour Marseille-Metz en Ligue 1. Toutes les infos essentielles pour suivre le match.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/marseille-metz-sur-quelle-chaine-tv-a-quelle-heure-et-avec-quelles-compositions-ligue-1-2025-2026\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/marseille-metz-sur-quelle-chaine-tv-a-quelle-heure-et-avec-quelles-compositions-ligue-1-2025-2026\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/marseille-metz-sur-quelle-chaine-tv-a-quelle-heure-et-avec-quelles-compositions-ligue-1-2025-2026\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/04\/Marseille-Metz-sur-quelle-chaine-TV-a-quelle-heure-et-avec-quelles-compositions.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/04\/Marseille-Metz-sur-quelle-chaine-TV-a-quelle-heure-et-avec-quelles-compositions.png","width":1200,"height":674,"caption":"Marseille-Metz sur quelle cha\u00eene TV, \u00e0 quelle heure et avec quelles compositions"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/marseille-metz-sur-quelle-chaine-tv-a-quelle-heure-et-avec-quelles-compositions-ligue-1-2025-2026\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Marseille-Metz : sur quelle cha\u00eene TV, \u00e0 quelle heure et avec quelles compositions ?"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da","name":"S\u00e9bastien Gente","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","caption":"S\u00e9bastien Gente"},"description":"John Stockton, Gianni Bugno, Zinedine Zidane, Steffi Graf, Frode Andresen, St\u00e9phane Stoecklin, Davis Kamoga, Primoz Peterka, Werner Schlager et Aur\u00e9lien Rougerie. Point commun entre ces sportifs? Ils m'ont fait r\u00eaver et ont berc\u00e9 mon adolescence. Je suis un fondu de sports et j'essaie de retranscrire ma passion \u00e0 travers mes articles. Originaire du P\u00e9rigord, ma passion pour les Girondins, les Jaunards et les Jazzmen transpire dans mes \u00e9crits. \u00c0 Dicodusport depuis 2021, je d\u00e9niche les sports m\u00e9connus dans lesquels la France brille, et il y en a !","sameAs":["https:\/\/www.facebook.com\/sebastien.gente\/","https:\/\/www.instagram.com\/sebgente\/","https:\/\/www.linkedin.com\/in\/sbastien-gente-a29583169\/","https:\/\/x.com\/https:\/\/twitter.com\/globulo24","SebastienGente"],"worksFor":"S\u00e9bastien GENTE","url":"https:\/\/dicodusport.fr\/blog\/author\/sebastiengente\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/661455","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/59"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=661455"}],"version-history":[{"count":3,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/661455\/revisions"}],"predecessor-version":[{"id":661895,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/661455\/revisions\/661895"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/661475"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=661455"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=661455"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=661455"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}