{"id":661483,"date":"2026-04-09T13:31:26","date_gmt":"2026-04-09T11:31:26","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=661483&#038;preview=true&#038;preview_id=661483"},"modified":"2026-04-09T14:15:25","modified_gmt":"2026-04-09T12:15:25","slug":"decathlon-cma-cgm-dement-la-rumeur-dun-passage-sous-pavillon-suisse","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/decathlon-cma-cgm-dement-la-rumeur-dun-passage-sous-pavillon-suisse\/","title":{"rendered":"Decathlon CMA CGM d\u00e9ment la rumeur d&rsquo;un passage sous pavillon suisse"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>CYCLISME SUR ROUTE &#8211; La formation Decathlon CMA CGM n&rsquo;a pas tard\u00e9 \u00e0 r\u00e9agir aux informations concernant le potentiel changement de nationalit\u00e9 de l&rsquo;\u00e9quipe.<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">Suite \u00e0 l&rsquo;information au sujet de son passage sous pavillon suisse \u00e0 partir de 2027, la formation <strong>Decathlon CMA CGM<\/strong> a rapidement apport\u00e9 une r\u00e9ponse.<\/p>\n<div class=\"vlp-link-container vlp-layout-article\"><a href=\"https:\/\/dicodusport.fr\/blog\/decathlon-cma-cgm-ne-sera-plus-une-equipe-francaise-en-2027\/\" class=\"vlp-link\" title=\"Decathlon CMA CGM ne sera plus une \u00e9quipe fran\u00e7aise en 2027\"><\/a><div class=\"vlp-layout-zone-side\"><div class=\"vlp-block-4 vlp-link-image\"><img loading=\"lazy\" decoding=\"async\" style=\"max-width: 792px;\" width=\"792\" height=\"445\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/04\/Decathlon-CMA-CGM-ne-sera-plus-une-equipe-francaise-en-2027.png\" class=\"attachment-800x445 size-800x445\" alt=\"Decathlon CMA CGM ne sera plus une \u00e9quipe fran\u00e7aise en 2027\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/04\/Decathlon-CMA-CGM-ne-sera-plus-une-equipe-francaise-en-2027.png 1200w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/04\/Decathlon-CMA-CGM-ne-sera-plus-une-equipe-francaise-en-2027-300x169.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/04\/Decathlon-CMA-CGM-ne-sera-plus-une-equipe-francaise-en-2027-1024x575.png 1024w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/04\/Decathlon-CMA-CGM-ne-sera-plus-une-equipe-francaise-en-2027-768x431.png 768w\" sizes=\"auto, (max-width: 792px) 100vw, 792px\" \/><\/div><\/div><div class=\"vlp-layout-zone-main\"><div class=\"vlp-block-0 vlp-link-title\">Decathlon CMA CGM ne sera plus une \u00e9quipe fran\u00e7aise en 2027<\/div><div class=\"vlp-block-1 vlp-link-summary\">CYCLISME SUR ROUTE - Selon WielerFlits, l'\u00e9quipe fran\u00e7aise Decathlon CMA CGM va passer sous pavillon suisse d\u00e8s l'ann\u00e9e prochaine.<\/div><div class=\"vlp-block-2 vlp-link-button\">Lire l'article<\/div><div class=\"vlp-block-3 vlp-link-url\">dicodusport.fr<\/div><\/div><\/div>\n<h2 style=\"text-align: justify;\">\u00ab\u00a0On confirme qu&rsquo;on restera une \u00e9quipe fran\u00e7aise\u00a0\u00bb<\/h2>\n<p style=\"text-align: justify;\">Au micro de <em>V\u00e9lo Fut\u00e9<\/em>, l&rsquo;\u00e9quipe fran\u00e7aise a souhait\u00e9 <strong>d\u00e9mentir<\/strong> fermement <strong>ce possible d\u00e9m\u00e9nagement<\/strong>.<\/p>\n<blockquote>\n<p style=\"text-align: justify;\">C&rsquo;est une p\u00e9riode o\u00f9 beaucoup de gens parlent \u00e0 notre place. Il y a beaucoup de rumeurs. L&rsquo;ann\u00e9e derni\u00e8re, on disait de nous qu&rsquo;on deviendrait une \u00e9quipe belge ou qu\u2019on d\u00e9m\u00e9nagerait \u00e0 Lille. On vous confirme qu&rsquo;on restera une \u00e9quipe fran\u00e7aise et que notre Centre de Performance restera \u00e0 Chamb\u00e9ry.<\/p>\n<\/blockquote>\n<p style=\"text-align: justify;\">Cette r\u00e9action est somme toute logique pour la formation fran\u00e7aise, qui a souhait\u00e9 rapidement \u00e9teindre le d\u00e9but d&rsquo;incendie que pouvait provoquer une telle nouvelle. D\u00e9sormais, seul l&rsquo;avenir nous dira si cela est seulement pour retarder l&rsquo;\u00e9ch\u00e9ance, ou si l&rsquo;\u00e9quipe cr\u00e9\u00e9e en 1992 poursuivra bien son chemin sous le pavillon tricolore \u00e0 l&rsquo;avenir.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">\ud83d\udea8D\u00e9cathlon CMA CGM\ud83c\uddeb\ud83c\uddf7 ne confirme pas cette information aupr\u00e8s de V\u00e9loFut\u00e9\ud83d\udc47\ud83c\udffb<\/p>\n<p>\ud83c\udf99\ufe0f\u00a0\u00bbC&rsquo;est une p\u00e9riode o\u00f9 beaucoup de gens parlent \u00e0 notre place. Il y a beaucoup de rumeurs. L&rsquo;ann\u00e9e derni\u00e8re, on disait de nous qu&rsquo;on deviendrait une \u00e9quipe belge ou qu\u2019on d\u00e9m\u00e9nagerait \u00e0 Lille. On vous\u2026 <a href=\"https:\/\/t.co\/B0ijdCc6Hm\">https:\/\/t.co\/B0ijdCc6Hm<\/a><\/p>\n<p>\u2014 V\u00e9lofut\u00e9 (@VeloFute) <a href=\"https:\/\/twitter.com\/VeloFute\/status\/2042197245508903171?ref_src=twsrc%5Etfw\">April 9, 2026<\/a><\/p><\/blockquote>\n<p style=\"text-align: justify;\"><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<div id=\"gtx-trans\" style=\"position: absolute; left: -14px; top: 40.9091px;\">\n<div class=\"gtx-trans-icon\" style=\"text-align: justify;\"><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>CYCLISME SUR ROUTE &#8211; La formation Decathlon CMA CGM n&rsquo;a pas tard\u00e9 \u00e0 r\u00e9agir aux informations concernant le potentiel changement de nationalit\u00e9 de l&rsquo;\u00e9quipe.<\/p>\n","protected":false},"author":55,"featured_media":661484,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[46994],"tags":[16878,47421,574,47429],"class_list":["post-661483","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cyclisme-sur-route","tag-breve","tag-cycisme-sur-route","tag-cyclisme","tag-decathlon-cma-cgm"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Decathlon CMA CGM d\u00e9ment la rumeur d&#039;un passage sous pavillon suisse<\/title>\n<meta name=\"description\" content=\"CYCLISME SUR ROUTE - La formation Decathlon CMA CGM n&#039;a pas tard\u00e9 \u00e0 r\u00e9agir aux informations concernant le potentiel changement de nationalit\u00e9 de l&#039;\u00e9quipe.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/decathlon-cma-cgm-dement-la-rumeur-dun-passage-sous-pavillon-suisse\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Decathlon CMA CGM d\u00e9ment la rumeur d&#039;un passage sous pavillon suisse\" \/>\n<meta property=\"og:description\" content=\"CYCLISME SUR ROUTE - La formation Decathlon CMA CGM n&#039;a pas tard\u00e9 \u00e0 r\u00e9agir aux informations concernant le potentiel changement de nationalit\u00e9 de l&#039;\u00e9quipe.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/decathlon-cma-cgm-dement-la-rumeur-dun-passage-sous-pavillon-suisse\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-09T11:31:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-09T12:15:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/04\/Decathlon-CMA-CGM-dement-la-rumeur-dun-passage-sous-pavillon-suisse.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Maxime Cazenave\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Decathlon CMA CGM d\u00e9ment la rumeur d&#039;un passage sous pavillon suisse\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Maxime_Caze\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/decathlon-cma-cgm-dement-la-rumeur-dun-passage-sous-pavillon-suisse\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/decathlon-cma-cgm-dement-la-rumeur-dun-passage-sous-pavillon-suisse\/\"},\"author\":{\"name\":\"Maxime Cazenave\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0\"},\"headline\":\"Decathlon CMA CGM d\u00e9ment la rumeur d&rsquo;un passage sous pavillon suisse\",\"datePublished\":\"2026-04-09T11:31:26+00:00\",\"dateModified\":\"2026-04-09T12:15:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/decathlon-cma-cgm-dement-la-rumeur-dun-passage-sous-pavillon-suisse\/\"},\"wordCount\":346,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/decathlon-cma-cgm-dement-la-rumeur-dun-passage-sous-pavillon-suisse\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/04\/Decathlon-CMA-CGM-dement-la-rumeur-dun-passage-sous-pavillon-suisse.png\",\"keywords\":[\"br\u00e8ve\",\"Cycisme sur route\",\"Cyclisme\",\"decathlon CMA CGM\"],\"articleSection\":[\"Cyclisme sur route\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/decathlon-cma-cgm-dement-la-rumeur-dun-passage-sous-pavillon-suisse\/#respond\"]}],\"copyrightYear\":\"2026\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/decathlon-cma-cgm-dement-la-rumeur-dun-passage-sous-pavillon-suisse\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/decathlon-cma-cgm-dement-la-rumeur-dun-passage-sous-pavillon-suisse\/\",\"name\":\"Decathlon CMA CGM d\u00e9ment la rumeur d'un passage sous pavillon suisse\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/decathlon-cma-cgm-dement-la-rumeur-dun-passage-sous-pavillon-suisse\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/decathlon-cma-cgm-dement-la-rumeur-dun-passage-sous-pavillon-suisse\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/04\/Decathlon-CMA-CGM-dement-la-rumeur-dun-passage-sous-pavillon-suisse.png\",\"datePublished\":\"2026-04-09T11:31:26+00:00\",\"dateModified\":\"2026-04-09T12:15:25+00:00\",\"description\":\"CYCLISME SUR ROUTE - La formation Decathlon CMA CGM n'a pas tard\u00e9 \u00e0 r\u00e9agir aux informations concernant le potentiel changement de nationalit\u00e9 de l'\u00e9quipe.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/decathlon-cma-cgm-dement-la-rumeur-dun-passage-sous-pavillon-suisse\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/decathlon-cma-cgm-dement-la-rumeur-dun-passage-sous-pavillon-suisse\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/decathlon-cma-cgm-dement-la-rumeur-dun-passage-sous-pavillon-suisse\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/04\/Decathlon-CMA-CGM-dement-la-rumeur-dun-passage-sous-pavillon-suisse.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/04\/Decathlon-CMA-CGM-dement-la-rumeur-dun-passage-sous-pavillon-suisse.png\",\"width\":1200,\"height\":674,\"caption\":\"Decathlon CMA CGM d\u00e9ment la rumeur d'un passage sous pavillon suisse\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/decathlon-cma-cgm-dement-la-rumeur-dun-passage-sous-pavillon-suisse\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Decathlon CMA CGM d\u00e9ment la rumeur d&rsquo;un passage sous pavillon suisse\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0\",\"name\":\"Maxime Cazenave\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg\",\"caption\":\"Maxime Cazenave\"},\"description\":\"Journaliste\/R\u00e9dacteur depuis 2012 - Berc\u00e9 par l\u2019amour des Girondins de Bordeaux, les \u00e9checs de Christophe Moreau sur le Tour de France sous l'\u00e8re Lance Armstrong et le fade-away l\u00e9tal de Dirk Nowitzki, ma passion d\u00e9vorante pour le sport a toujours \u00e9t\u00e9 un pan incontournable de ma vie. Transmettre ma passion \u00e0 l\u2019\u00e9crit a \u00e9t\u00e9 une transition naturelle. Suiveur assidu de basket et de hockey sur glace, je garde toujours un peu de place pour suivre le cyclisme, le football et le maximum de performances fran\u00e7aises.\",\"sameAs\":[\"https:\/\/x.com\/https:\/\/twitter.com\/Maxime_Caze\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/maximec\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Decathlon CMA CGM d\u00e9ment la rumeur d'un passage sous pavillon suisse","description":"CYCLISME SUR ROUTE - La formation Decathlon CMA CGM n'a pas tard\u00e9 \u00e0 r\u00e9agir aux informations concernant le potentiel changement de nationalit\u00e9 de l'\u00e9quipe.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/decathlon-cma-cgm-dement-la-rumeur-dun-passage-sous-pavillon-suisse\/","og_locale":"fr_FR","og_type":"article","og_title":"Decathlon CMA CGM d\u00e9ment la rumeur d'un passage sous pavillon suisse","og_description":"CYCLISME SUR ROUTE - La formation Decathlon CMA CGM n'a pas tard\u00e9 \u00e0 r\u00e9agir aux informations concernant le potentiel changement de nationalit\u00e9 de l'\u00e9quipe.","og_url":"https:\/\/dicodusport.fr\/blog\/decathlon-cma-cgm-dement-la-rumeur-dun-passage-sous-pavillon-suisse\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2026-04-09T11:31:26+00:00","article_modified_time":"2026-04-09T12:15:25+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/04\/Decathlon-CMA-CGM-dement-la-rumeur-dun-passage-sous-pavillon-suisse.png","type":"image\/png"}],"author":"Maxime Cazenave","twitter_card":"summary_large_image","twitter_title":"Decathlon CMA CGM d\u00e9ment la rumeur d'un passage sous pavillon suisse","twitter_creator":"@https:\/\/twitter.com\/Maxime_Caze","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/decathlon-cma-cgm-dement-la-rumeur-dun-passage-sous-pavillon-suisse\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/decathlon-cma-cgm-dement-la-rumeur-dun-passage-sous-pavillon-suisse\/"},"author":{"name":"Maxime Cazenave","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0"},"headline":"Decathlon CMA CGM d\u00e9ment la rumeur d&rsquo;un passage sous pavillon suisse","datePublished":"2026-04-09T11:31:26+00:00","dateModified":"2026-04-09T12:15:25+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/decathlon-cma-cgm-dement-la-rumeur-dun-passage-sous-pavillon-suisse\/"},"wordCount":346,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/decathlon-cma-cgm-dement-la-rumeur-dun-passage-sous-pavillon-suisse\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/04\/Decathlon-CMA-CGM-dement-la-rumeur-dun-passage-sous-pavillon-suisse.png","keywords":["br\u00e8ve","Cycisme sur route","Cyclisme","decathlon CMA CGM"],"articleSection":["Cyclisme sur route"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/decathlon-cma-cgm-dement-la-rumeur-dun-passage-sous-pavillon-suisse\/#respond"]}],"copyrightYear":"2026","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/decathlon-cma-cgm-dement-la-rumeur-dun-passage-sous-pavillon-suisse\/","url":"https:\/\/dicodusport.fr\/blog\/decathlon-cma-cgm-dement-la-rumeur-dun-passage-sous-pavillon-suisse\/","name":"Decathlon CMA CGM d\u00e9ment la rumeur d'un passage sous pavillon suisse","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/decathlon-cma-cgm-dement-la-rumeur-dun-passage-sous-pavillon-suisse\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/decathlon-cma-cgm-dement-la-rumeur-dun-passage-sous-pavillon-suisse\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/04\/Decathlon-CMA-CGM-dement-la-rumeur-dun-passage-sous-pavillon-suisse.png","datePublished":"2026-04-09T11:31:26+00:00","dateModified":"2026-04-09T12:15:25+00:00","description":"CYCLISME SUR ROUTE - La formation Decathlon CMA CGM n'a pas tard\u00e9 \u00e0 r\u00e9agir aux informations concernant le potentiel changement de nationalit\u00e9 de l'\u00e9quipe.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/decathlon-cma-cgm-dement-la-rumeur-dun-passage-sous-pavillon-suisse\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/decathlon-cma-cgm-dement-la-rumeur-dun-passage-sous-pavillon-suisse\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/decathlon-cma-cgm-dement-la-rumeur-dun-passage-sous-pavillon-suisse\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/04\/Decathlon-CMA-CGM-dement-la-rumeur-dun-passage-sous-pavillon-suisse.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/04\/Decathlon-CMA-CGM-dement-la-rumeur-dun-passage-sous-pavillon-suisse.png","width":1200,"height":674,"caption":"Decathlon CMA CGM d\u00e9ment la rumeur d'un passage sous pavillon suisse"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/decathlon-cma-cgm-dement-la-rumeur-dun-passage-sous-pavillon-suisse\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Decathlon CMA CGM d\u00e9ment la rumeur d&rsquo;un passage sous pavillon suisse"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0","name":"Maxime Cazenave","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg","caption":"Maxime Cazenave"},"description":"Journaliste\/R\u00e9dacteur depuis 2012 - Berc\u00e9 par l\u2019amour des Girondins de Bordeaux, les \u00e9checs de Christophe Moreau sur le Tour de France sous l'\u00e8re Lance Armstrong et le fade-away l\u00e9tal de Dirk Nowitzki, ma passion d\u00e9vorante pour le sport a toujours \u00e9t\u00e9 un pan incontournable de ma vie. Transmettre ma passion \u00e0 l\u2019\u00e9crit a \u00e9t\u00e9 une transition naturelle. Suiveur assidu de basket et de hockey sur glace, je garde toujours un peu de place pour suivre le cyclisme, le football et le maximum de performances fran\u00e7aises.","sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/Maxime_Caze"],"url":"https:\/\/dicodusport.fr\/blog\/author\/maximec\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/661483","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=661483"}],"version-history":[{"count":5,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/661483\/revisions"}],"predecessor-version":[{"id":661529,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/661483\/revisions\/661529"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/661484"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=661483"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=661483"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=661483"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}