{"id":661816,"date":"2026-04-10T18:59:37","date_gmt":"2026-04-10T16:59:37","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=661816&#038;preview=true&#038;preview_id=661816"},"modified":"2026-04-10T18:59:37","modified_gmt":"2026-04-10T16:59:37","slug":"les-bleuettes-roulent-sur-les-anglaises-et-remportent-le-festival-des-6-nations","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/les-bleuettes-roulent-sur-les-anglaises-et-remportent-le-festival-des-6-nations\/","title":{"rendered":"Les Bleuettes roulent sur les Anglaises et remportent le Festival des 6 Nations !"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>FESTIVAL DES SIX NATIONS F\u00c9MININ 2026 &#8211; Largement sup\u00e9rieures, les Bleuettes ont fait du petit bois avec les Anglaises et remportent la comp\u00e9tition.\u00a0<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">L&rsquo;<strong>\u00e9quipe de France U18 filles<\/strong> avait jusqu&rsquo;ici d\u00e9roul\u00e9 dans le Festival des Six Nations. Trois matchs (dont deux lundi sur un format d&rsquo;une mi-temps), trois victoires, du jeu, des essais en pagaille : les Bleuettes paraissaient impressionnantes. Mais restait \u00e0 passer le test ultime : l&rsquo;Angleterre, pour d\u00e9terminer qui remporterait la comp\u00e9tition.<\/p>\n<div class=\"vlp-link-container vlp-layout-article\"><a href=\"https:\/\/dicodusport.fr\/blog\/les-bleuettes-raflent-deux-victoires-daffilee-contre-les-italiennes-et-les-galloises-au-festival-des-6-nations\/\" class=\"vlp-link\" title=\"Les Bleuettes raflent deux victoires d&#039;affil\u00e9e contre les Italiennes et les Galloises au Festival des 6 Nations\"><\/a><div class=\"vlp-layout-zone-side\"><div class=\"vlp-block-4 vlp-link-image\"><img loading=\"lazy\" decoding=\"async\" style=\"max-width: 792px;\" width=\"792\" height=\"445\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/04\/Les-Bleuettes-raflent-deux-victoires-daffilee-contre-les-Italiennes-et-les-Galloises-au-Festival-des-6-Nations.png\" class=\"attachment-800x445 size-800x445\" alt=\"Les Bleuettes raflent deux victoires d&#039;affil\u00e9e contre les Italiennes et les Galloises au Festival des 6 Nations\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/04\/Les-Bleuettes-raflent-deux-victoires-daffilee-contre-les-Italiennes-et-les-Galloises-au-Festival-des-6-Nations.png 1200w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/04\/Les-Bleuettes-raflent-deux-victoires-daffilee-contre-les-Italiennes-et-les-Galloises-au-Festival-des-6-Nations-300x169.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/04\/Les-Bleuettes-raflent-deux-victoires-daffilee-contre-les-Italiennes-et-les-Galloises-au-Festival-des-6-Nations-1024x575.png 1024w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/04\/Les-Bleuettes-raflent-deux-victoires-daffilee-contre-les-Italiennes-et-les-Galloises-au-Festival-des-6-Nations-768x431.png 768w\" sizes=\"auto, (max-width: 792px) 100vw, 792px\" \/><\/div><\/div><div class=\"vlp-layout-zone-main\"><div class=\"vlp-block-0 vlp-link-title\">Les Bleuettes raflent deux victoires d'affil\u00e9e contre les Italiennes et les Galloises au Festival des 6 Nations<\/div><div class=\"vlp-block-1 vlp-link-summary\">FESTIVAL DES SIX NATIONS F\u00c9MININ 2026 - Deux matchs d'une mi-temps, deux victoires pour les Bleuettes, qui sont pr\u00eates pour d\u00e9fier les Anglaises.<\/div><div class=\"vlp-block-2 vlp-link-button\">Lire l'article<\/div><div class=\"vlp-block-3 vlp-link-url\">dicodusport.fr<\/div><\/div><\/div>\n<h2 style=\"text-align: justify;\">D\u00e9part canon<\/h2>\n<p style=\"text-align: justify;\">Les Bleuettes dominaient le d\u00e9but de match, et il ne leur fallait que 5 minutes pour voir <strong>Chlo\u00e9 Legoueix<\/strong> raffuter deux Anglaises sur son aile pour d\u00e9florer le planchot. Trois minutes plus tard, <strong>Louane Pichon<\/strong> d\u00e9chirait le rideau d\u00e9fensif adverse et envoyait<strong> Tonie Fior\u00e8se<\/strong> doubler la mise. Les Anglaises tentaient de mettre plus d&rsquo;intensit\u00e9, mais rien \u00e0 faire : <strong>Alexia Le Floc&rsquo;h<\/strong> bousculait la d\u00e9fense et allait signer le troisi\u00e8me essai fran\u00e7ais\u2026 apr\u00e8s 15 minutes !<br \/>\n<iframe loading=\"lazy\" title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/O8C2RUFMd4U?si=rt0wAkTha1L3NmIf\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><br \/>\nUne d\u00e9compression suivait logiquement, et les Anglaises pouvaient enfin sortir la t\u00eate de l&rsquo;eau, et faire parler leur paquet d&rsquo;avants. Les Bleuettes \u00e9taient domin\u00e9es dans ce secteur, multipliaient les fautes, et <strong>Laura Guez<\/strong> puis <strong>Chlo\u00e9 Legoueix\u00a0<\/strong>prenaient un jaune avant un essai de p\u00e9nalit\u00e9 logique (25\u00e8me). Mais pas de quoi effrayer les Bleuettes, et notamment<strong> Laura Guez<\/strong>, qui se faisait pardonner d&rsquo;une intervention tranchante dans la ligne pour le quatri\u00e8me essai. \u00c0 la pause, le match \u00e9tait d\u00e9j\u00e0 quasiment gagn\u00e9 (<strong>26-7<\/strong>).<\/p>\n<h2 style=\"text-align: justify;\">Une d\u00e9monstration<\/h2>\n<p style=\"text-align: justify;\">Difficile de garder un haut niveau d&rsquo;intensit\u00e9 n\u00e9anmoins. Le retour sur la pelouse \u00e9tait brouillon, les Bleuettes se mettaient encore \u00e0 la faute, ce qui valait un nouveau carton jaune pour<strong> Sarah Pegouri\u00e9<\/strong>, mais reprenaient rapidement leur domination. Et apr\u00e8s plusieurs minutes de maladresse\/fatigue, <strong>Alixe Valence<\/strong> trouvait <strong>Candice Barret<\/strong>, qui salait la note en force. Dans la foul\u00e9e, <strong>Tonie Fior\u00e8se<\/strong> s&rsquo;offrait un doubl\u00e9 d&rsquo;un d\u00e9boul\u00e9 sur son aile, confirmant son talent entrevu lors des matchs pr\u00e9c\u00e9dents : la rencontre \u00e9tait termin\u00e9e.<\/p>\n<p style=\"text-align: justify;\">Les Bleuettes ne voulaient n\u00e9anmoins pas ralentir, et <strong>Mathilde Closson<\/strong>, lanc\u00e9e \u00e0 quelques m\u00e8tres de la ligne, ajoutait un essai en force. Puis <strong>Aliz\u00e9e Durant<\/strong> cueillait les fruits d&rsquo;un travail monumental de <strong>Madeleine Sutton<\/strong> pour y aller de son essau. Mais les Bleuettes n&rsquo;avaient pas fini de r\u00e9galer et gratifiaient le public anglais d&rsquo;une action riche en offloads jusqu&rsquo;\u00e0 l&rsquo;essai de <strong>Ma\u00efsha Nasso<\/strong>. Puis le coup de gr\u00e2ce : interception de <strong>Sutton<\/strong>, et essai de<strong> Louane Pichon<\/strong>, qui allait derri\u00e8re s&rsquo;offrir un dernier exploit individuel apr\u00e8s la sir\u00e8ne pour donner au score une ampleur incroyable. Une d\u00e9monstration, rien de moins : victoire <strong>75-7<\/strong>, triomphe final dans le Festival des Six Nations. Cette \u00e9quipe a de l&rsquo;avenir, sans nul doute !<\/p>\n","protected":false},"excerpt":{"rendered":"<p>FESTIVAL DES SIX NATIONS F\u00c9MININ 2026 &#8211; Largement sup\u00e9rieures, les Bleuettes ont fait du petit bois avec les Anglaises et remportent la comp\u00e9tition.\u00a0<\/p>\n","protected":false},"author":59,"featured_media":661857,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[9129,47048,19951],"tags":[16878,47462],"class_list":["post-661816","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rugby-a-xv","category-tournoi-des-6-nations","category-xv-de-france","tag-breve","tag-festival-des-six-nations"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Les Bleuettes roulent sur les Anglaises et remportent le Festival des 6 Nations !<\/title>\n<meta name=\"description\" content=\"FESTIVAL DES SIX NATIONS F\u00c9MININ 2026 - Largement sup\u00e9rieures, les Bleuettes ont fait du petit bois avec les Anglaises et remportent la comp\u00e9tition.\u00a0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/les-bleuettes-roulent-sur-les-anglaises-et-remportent-le-festival-des-6-nations\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les Bleuettes roulent sur les Anglaises et remportent le Festival des 6 Nations !\" \/>\n<meta property=\"og:description\" content=\"FESTIVAL DES SIX NATIONS F\u00c9MININ 2026 - Largement sup\u00e9rieures, les Bleuettes ont fait du petit bois avec les Anglaises et remportent la comp\u00e9tition.\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/les-bleuettes-roulent-sur-les-anglaises-et-remportent-le-festival-des-6-nations\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/sebastien.gente\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-10T16:59:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/04\/Les-Bleuettes-roulent-sur-les-Anglaises-et-remportent-le-Festival-des-6-Nations-.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"S\u00e9bastien Gente\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Les Bleuettes roulent sur les Anglaises et remportent le Festival des 6 Nations !\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/globulo24\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-bleuettes-roulent-sur-les-anglaises-et-remportent-le-festival-des-6-nations\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-bleuettes-roulent-sur-les-anglaises-et-remportent-le-festival-des-6-nations\\\/\"},\"author\":{\"name\":\"S\u00e9bastien Gente\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/627966a6cde45dbd8c5e36ac85d783da\"},\"headline\":\"Les Bleuettes roulent sur les Anglaises et remportent le Festival des 6 Nations !\",\"datePublished\":\"2026-04-10T16:59:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-bleuettes-roulent-sur-les-anglaises-et-remportent-le-festival-des-6-nations\\\/\"},\"wordCount\":590,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-bleuettes-roulent-sur-les-anglaises-et-remportent-le-festival-des-6-nations\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Les-Bleuettes-roulent-sur-les-Anglaises-et-remportent-le-Festival-des-6-Nations-.png\",\"keywords\":[\"br\u00e8ve\",\"Festival des Six Nations\"],\"articleSection\":[\"Rugby \u00e0 XV\",\"Tournoi des 6 Nations\",\"XV de France\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-bleuettes-roulent-sur-les-anglaises-et-remportent-le-festival-des-6-nations\\\/#respond\"]}],\"copyrightYear\":\"2026\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-bleuettes-roulent-sur-les-anglaises-et-remportent-le-festival-des-6-nations\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-bleuettes-roulent-sur-les-anglaises-et-remportent-le-festival-des-6-nations\\\/\",\"name\":\"Les Bleuettes roulent sur les Anglaises et remportent le Festival des 6 Nations !\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-bleuettes-roulent-sur-les-anglaises-et-remportent-le-festival-des-6-nations\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-bleuettes-roulent-sur-les-anglaises-et-remportent-le-festival-des-6-nations\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Les-Bleuettes-roulent-sur-les-Anglaises-et-remportent-le-Festival-des-6-Nations-.png\",\"datePublished\":\"2026-04-10T16:59:37+00:00\",\"description\":\"FESTIVAL DES SIX NATIONS F\u00c9MININ 2026 - Largement sup\u00e9rieures, les Bleuettes ont fait du petit bois avec les Anglaises et remportent la comp\u00e9tition.\u00a0\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-bleuettes-roulent-sur-les-anglaises-et-remportent-le-festival-des-6-nations\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-bleuettes-roulent-sur-les-anglaises-et-remportent-le-festival-des-6-nations\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-bleuettes-roulent-sur-les-anglaises-et-remportent-le-festival-des-6-nations\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Les-Bleuettes-roulent-sur-les-Anglaises-et-remportent-le-Festival-des-6-Nations-.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Les-Bleuettes-roulent-sur-les-Anglaises-et-remportent-le-Festival-des-6-Nations-.png\",\"width\":1200,\"height\":674,\"caption\":\"Les Bleuettes roulent sur les Anglaises et remportent le Festival des 6 Nations !\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-bleuettes-roulent-sur-les-anglaises-et-remportent-le-festival-des-6-nations\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les Bleuettes roulent sur les Anglaises et remportent le Festival des 6 Nations !\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/627966a6cde45dbd8c5e36ac85d783da\",\"name\":\"S\u00e9bastien Gente\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"caption\":\"S\u00e9bastien Gente\"},\"description\":\"John Stockton, Gianni Bugno, Zinedine Zidane, Steffi Graf, Frode Andresen, St\u00e9phane Stoecklin, Davis Kamoga, Primoz Peterka, Werner Schlager et Aur\u00e9lien Rougerie. Point commun entre ces sportifs? Ils m'ont fait r\u00eaver et ont berc\u00e9 mon adolescence. Je suis un fondu de sports et j'essaie de retranscrire ma passion \u00e0 travers mes articles. Originaire du P\u00e9rigord, ma passion pour les Girondins, les Jaunards et les Jazzmen transpire dans mes \u00e9crits. \u00c0 Dicodusport depuis 2021, je d\u00e9niche les sports m\u00e9connus dans lesquels la France brille, et il y en a !\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/sebastien.gente\\\/\",\"https:\\\/\\\/www.instagram.com\\\/sebgente\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/sbastien-gente-a29583169\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/globulo24\",\"SebastienGente\"],\"worksFor\":\"S\u00e9bastien GENTE\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/sebastiengente\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Les Bleuettes roulent sur les Anglaises et remportent le Festival des 6 Nations !","description":"FESTIVAL DES SIX NATIONS F\u00c9MININ 2026 - Largement sup\u00e9rieures, les Bleuettes ont fait du petit bois avec les Anglaises et remportent la comp\u00e9tition.\u00a0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/les-bleuettes-roulent-sur-les-anglaises-et-remportent-le-festival-des-6-nations\/","og_locale":"fr_FR","og_type":"article","og_title":"Les Bleuettes roulent sur les Anglaises et remportent le Festival des 6 Nations !","og_description":"FESTIVAL DES SIX NATIONS F\u00c9MININ 2026 - Largement sup\u00e9rieures, les Bleuettes ont fait du petit bois avec les Anglaises et remportent la comp\u00e9tition.\u00a0","og_url":"https:\/\/dicodusport.fr\/blog\/les-bleuettes-roulent-sur-les-anglaises-et-remportent-le-festival-des-6-nations\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/sebastien.gente\/","article_published_time":"2026-04-10T16:59:37+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/04\/Les-Bleuettes-roulent-sur-les-Anglaises-et-remportent-le-Festival-des-6-Nations-.png","type":"image\/png"}],"author":"S\u00e9bastien Gente","twitter_card":"summary_large_image","twitter_title":"Les Bleuettes roulent sur les Anglaises et remportent le Festival des 6 Nations !","twitter_creator":"@https:\/\/twitter.com\/globulo24","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/les-bleuettes-roulent-sur-les-anglaises-et-remportent-le-festival-des-6-nations\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/les-bleuettes-roulent-sur-les-anglaises-et-remportent-le-festival-des-6-nations\/"},"author":{"name":"S\u00e9bastien Gente","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da"},"headline":"Les Bleuettes roulent sur les Anglaises et remportent le Festival des 6 Nations !","datePublished":"2026-04-10T16:59:37+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/les-bleuettes-roulent-sur-les-anglaises-et-remportent-le-festival-des-6-nations\/"},"wordCount":590,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/les-bleuettes-roulent-sur-les-anglaises-et-remportent-le-festival-des-6-nations\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/04\/Les-Bleuettes-roulent-sur-les-Anglaises-et-remportent-le-Festival-des-6-Nations-.png","keywords":["br\u00e8ve","Festival des Six Nations"],"articleSection":["Rugby \u00e0 XV","Tournoi des 6 Nations","XV de France"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/les-bleuettes-roulent-sur-les-anglaises-et-remportent-le-festival-des-6-nations\/#respond"]}],"copyrightYear":"2026","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/les-bleuettes-roulent-sur-les-anglaises-et-remportent-le-festival-des-6-nations\/","url":"https:\/\/dicodusport.fr\/blog\/les-bleuettes-roulent-sur-les-anglaises-et-remportent-le-festival-des-6-nations\/","name":"Les Bleuettes roulent sur les Anglaises et remportent le Festival des 6 Nations !","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/les-bleuettes-roulent-sur-les-anglaises-et-remportent-le-festival-des-6-nations\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/les-bleuettes-roulent-sur-les-anglaises-et-remportent-le-festival-des-6-nations\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/04\/Les-Bleuettes-roulent-sur-les-Anglaises-et-remportent-le-Festival-des-6-Nations-.png","datePublished":"2026-04-10T16:59:37+00:00","description":"FESTIVAL DES SIX NATIONS F\u00c9MININ 2026 - Largement sup\u00e9rieures, les Bleuettes ont fait du petit bois avec les Anglaises et remportent la comp\u00e9tition.\u00a0","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/les-bleuettes-roulent-sur-les-anglaises-et-remportent-le-festival-des-6-nations\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/les-bleuettes-roulent-sur-les-anglaises-et-remportent-le-festival-des-6-nations\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/les-bleuettes-roulent-sur-les-anglaises-et-remportent-le-festival-des-6-nations\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/04\/Les-Bleuettes-roulent-sur-les-Anglaises-et-remportent-le-Festival-des-6-Nations-.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/04\/Les-Bleuettes-roulent-sur-les-Anglaises-et-remportent-le-Festival-des-6-Nations-.png","width":1200,"height":674,"caption":"Les Bleuettes roulent sur les Anglaises et remportent le Festival des 6 Nations !"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/les-bleuettes-roulent-sur-les-anglaises-et-remportent-le-festival-des-6-nations\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Les Bleuettes roulent sur les Anglaises et remportent le Festival des 6 Nations !"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da","name":"S\u00e9bastien Gente","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","caption":"S\u00e9bastien Gente"},"description":"John Stockton, Gianni Bugno, Zinedine Zidane, Steffi Graf, Frode Andresen, St\u00e9phane Stoecklin, Davis Kamoga, Primoz Peterka, Werner Schlager et Aur\u00e9lien Rougerie. Point commun entre ces sportifs? Ils m'ont fait r\u00eaver et ont berc\u00e9 mon adolescence. Je suis un fondu de sports et j'essaie de retranscrire ma passion \u00e0 travers mes articles. Originaire du P\u00e9rigord, ma passion pour les Girondins, les Jaunards et les Jazzmen transpire dans mes \u00e9crits. \u00c0 Dicodusport depuis 2021, je d\u00e9niche les sports m\u00e9connus dans lesquels la France brille, et il y en a !","sameAs":["https:\/\/www.facebook.com\/sebastien.gente\/","https:\/\/www.instagram.com\/sebgente\/","https:\/\/www.linkedin.com\/in\/sbastien-gente-a29583169\/","https:\/\/x.com\/https:\/\/twitter.com\/globulo24","SebastienGente"],"worksFor":"S\u00e9bastien GENTE","url":"https:\/\/dicodusport.fr\/blog\/author\/sebastiengente\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/661816","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/59"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=661816"}],"version-history":[{"count":1,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/661816\/revisions"}],"predecessor-version":[{"id":661870,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/661816\/revisions\/661870"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/661857"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=661816"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=661816"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=661816"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}