{"id":661885,"date":"2026-04-10T20:02:09","date_gmt":"2026-04-10T18:02:09","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=661885&#038;preview=true&#038;preview_id=661885"},"modified":"2026-04-10T20:02:09","modified_gmt":"2026-04-10T18:02:09","slug":"christo-popov-et-toma-junior-popov-assurent-une-medaille-et-peuvent-rever-de-double-europeen","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/christo-popov-et-toma-junior-popov-assurent-une-medaille-et-peuvent-rever-de-double-europeen\/","title":{"rendered":"Christo Popov et Toma Junior Popov assurent une m\u00e9daille et peuvent r\u00eaver de doubl\u00e9 europ\u00e9en"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>CHAMPIONNATS D&rsquo;EUROPE DE BADMINTON 2026 &#8211; Sans trembler, Christo Popov et Toma Junior Popov rallient le dernier carr\u00e9 et peuvent viser le doubl\u00e9.<\/em><\/strong><\/p>\n<ul style=\"text-align: justify;\">\n<li><strong>\u00c0 ce sujet &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/championnats-deurope-de-badminton-2026-programme-resultats-et-tableau-des-medailles\/\">Championnats d\u2019Europe de badminton 2026 : programme, r\u00e9sultats et tableau des m\u00e9dailles<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Plus t\u00f4t dans la journ\u00e9e, <strong>Christo Popov<\/strong> et <strong>Toma Junior Popov<\/strong> <a href=\"https:\/\/dicodusport.fr\/blog\/trois-bleus-en-demi-finales-du-simple-aux-championnats-deurope-de-badminton-arnaud-merkle-soffre-alex-lanier\/\">avaient gagn\u00e9 chacun leur quart de finale en simple<\/a>, et pris rendez-vous pour un duel fratricide en demi-finales demain. Mais il fallait oublier temporairement cet enjeu : les deux fr\u00e8res \u00e9taient associ\u00e9s en quart de finale du double, pour tenter de prolonger la d\u00e9fense du titre acquis la saison derni\u00e8re.<\/p>\n<div class=\"vlp-link-container vlp-layout-article\"><a href=\"https:\/\/dicodusport.fr\/blog\/badminton-championnats-deurope-2025-toma-junior-popov-et-christo-popov-sacres-en-double\/\" class=\"vlp-link\" title=\"Badminton Championnats d&#039;Europe 2025 : Toma Junior Popov et Christo Popov sacr\u00e9s en double !\"><\/a><div class=\"vlp-layout-zone-side\"><div class=\"vlp-block-4 vlp-link-image\"><img loading=\"lazy\" decoding=\"async\" style=\"max-width: 792px;\" width=\"792\" height=\"445\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/04\/Badminton-Championnats-dEurope-2025-Toma-Junior-Popov-et-Christo-Popov-sacres-en-double-.png\" class=\"attachment-800x445 size-800x445\" alt=\"Badminton Championnats d&#039;Europe 2025 Toma Junior Popov et Christo Popov sacr\u00e9s en double !\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/04\/Badminton-Championnats-dEurope-2025-Toma-Junior-Popov-et-Christo-Popov-sacres-en-double-.png 1200w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/04\/Badminton-Championnats-dEurope-2025-Toma-Junior-Popov-et-Christo-Popov-sacres-en-double--300x169.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/04\/Badminton-Championnats-dEurope-2025-Toma-Junior-Popov-et-Christo-Popov-sacres-en-double--1024x575.png 1024w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/04\/Badminton-Championnats-dEurope-2025-Toma-Junior-Popov-et-Christo-Popov-sacres-en-double--768x431.png 768w\" sizes=\"auto, (max-width: 792px) 100vw, 792px\" \/><\/div><\/div><div class=\"vlp-layout-zone-main\"><div class=\"vlp-block-0 vlp-link-title\">Badminton Championnats d'Europe 2025 : Toma Junior Popov et Christo Popov sacr\u00e9s en double !<\/div><div class=\"vlp-block-1 vlp-link-summary\">CHAMPIONNATS D'EUROPE DE BADMINTON 2025 - Dans cette finale du double hommes 100% fran\u00e7aise, Toma Junior Popov et Christo Popov ont repouss\u00e9 \u00c9loi Adam et L\u00e9o Rossi pour aller chercher leur premier titre.\u00a0<\/div><div class=\"vlp-block-2 vlp-link-button\">Lire l'article<\/div><div class=\"vlp-block-3 vlp-link-url\">dicodusport.fr<\/div><\/div><\/div>\n<h2 style=\"text-align: justify;\">Les Bleus sont l\u00e0<\/h2>\n<p style=\"text-align: justify;\">Face \u00e0 eux, \u00e9galement deux fr\u00e8res : <strong>Ji\u0159\u00ed Kr\u00e1l<\/strong> et <strong>Ond\u0159ej Kr\u00e1l<\/strong>, deux adversaires largement \u00e0 la mesure des Bleus. Mais les Tch\u00e8ques vendaient ch\u00e8rement leur peau, perturbant le petit jeu habituellement impactant des Bleus, qui tentaient alors de passer en force. Un festival de smashs surpuissants, qui faisait exploser la d\u00e9fense tch\u00e8que, et provoquait une multitude de fautes directes. De quoi s&rsquo;\u00e9chapper et rafler en toute logique la premi\u00e8re manche.<\/p>\n<p style=\"text-align: justify;\">Les fr\u00e8res <strong>Kr\u00e1l<\/strong> n&rsquo;avaient n\u00e9anmoins pas dit leur dernier mot, et sortaient quelques amortis de g\u00e9nie pour rester au contact en d\u00e9but de deuxi\u00e8me set. Et ils for\u00e7aient les Bleus \u00e0 sortir le grand jeu, notamment en d\u00e9fense. Une couverture de terrain quatre \u00e9toiles, des attaques tranchantes pour faire c\u00e9der leurs rivaux, qui n&rsquo;auront clairement pas d\u00e9m\u00e9rit\u00e9.\u00a0<strong>Christo Popov<\/strong> et <strong>Toma Junior Popov\u00a0<\/strong>s&rsquo;imposent<strong> 21-15, 21-14<\/strong> et seront en demi-finales demain. La m\u00e9daille est assur\u00e9e, mais contre <strong>Alex Green<\/strong> et<strong> Zach Russ<\/strong>, qui ont tomb\u00e9 les favoris danois, les Bleus seront en pole pour une deuxi\u00e8me finale cons\u00e9cutive.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CHAMPIONNATS D&rsquo;EUROPE DE BADMINTON 2026 &#8211; Sans trembler, Christo Popov et Toma Junior Popov rallient le dernier carr\u00e9 et peuvent viser le doubl\u00e9.<\/p>\n","protected":false},"author":59,"featured_media":661888,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[13604],"tags":[16878,15850,22703,20080],"class_list":["post-661885","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-badminton","tag-breve","tag-championnats-deurope-de-badminton","tag-christo-popov","tag-toma-junior-popov"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Christo Popov et Toma Junior Popov assurent une m\u00e9daille et peuvent r\u00eaver de doubl\u00e9 europ\u00e9en<\/title>\n<meta name=\"description\" content=\"CHAMPIONNATS D&#039;EUROPE DE BADMINTON 2026 - Sans trembler, Christo Popov et Toma Junior Popov rallient le dernier carr\u00e9 et peuvent viser le doubl\u00e9.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/christo-popov-et-toma-junior-popov-assurent-une-medaille-et-peuvent-rever-de-double-europeen\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Christo Popov et Toma Junior Popov assurent une m\u00e9daille et peuvent r\u00eaver de doubl\u00e9 europ\u00e9en\" \/>\n<meta property=\"og:description\" content=\"CHAMPIONNATS D&#039;EUROPE DE BADMINTON 2026 - Sans trembler, Christo Popov et Toma Junior Popov rallient le dernier carr\u00e9 et peuvent viser le doubl\u00e9.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/christo-popov-et-toma-junior-popov-assurent-une-medaille-et-peuvent-rever-de-double-europeen\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/sebastien.gente\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-10T18:02:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/04\/Christo-Popov-et-Toma-Junior-Popov-assurent-une-medaille-et-peuvent-rever-de-double-europeen.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"S\u00e9bastien Gente\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Christo Popov et Toma Junior Popov assurent une m\u00e9daille et peuvent r\u00eaver de doubl\u00e9 europ\u00e9en\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/globulo24\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/christo-popov-et-toma-junior-popov-assurent-une-medaille-et-peuvent-rever-de-double-europeen\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/christo-popov-et-toma-junior-popov-assurent-une-medaille-et-peuvent-rever-de-double-europeen\/\"},\"author\":{\"name\":\"S\u00e9bastien Gente\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da\"},\"headline\":\"Christo Popov et Toma Junior Popov assurent une m\u00e9daille et peuvent r\u00eaver de doubl\u00e9 europ\u00e9en\",\"datePublished\":\"2026-04-10T18:02:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/christo-popov-et-toma-junior-popov-assurent-une-medaille-et-peuvent-rever-de-double-europeen\/\"},\"wordCount\":429,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/christo-popov-et-toma-junior-popov-assurent-une-medaille-et-peuvent-rever-de-double-europeen\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/04\/Christo-Popov-et-Toma-Junior-Popov-assurent-une-medaille-et-peuvent-rever-de-double-europeen.png\",\"keywords\":[\"br\u00e8ve\",\"Championnats d'Europe de badminton\",\"Christo Popov\",\"Toma Junior Popov\"],\"articleSection\":[\"Badminton\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/christo-popov-et-toma-junior-popov-assurent-une-medaille-et-peuvent-rever-de-double-europeen\/#respond\"]}],\"copyrightYear\":\"2026\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/christo-popov-et-toma-junior-popov-assurent-une-medaille-et-peuvent-rever-de-double-europeen\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/christo-popov-et-toma-junior-popov-assurent-une-medaille-et-peuvent-rever-de-double-europeen\/\",\"name\":\"Christo Popov et Toma Junior Popov assurent une m\u00e9daille et peuvent r\u00eaver de doubl\u00e9 europ\u00e9en\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/christo-popov-et-toma-junior-popov-assurent-une-medaille-et-peuvent-rever-de-double-europeen\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/christo-popov-et-toma-junior-popov-assurent-une-medaille-et-peuvent-rever-de-double-europeen\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/04\/Christo-Popov-et-Toma-Junior-Popov-assurent-une-medaille-et-peuvent-rever-de-double-europeen.png\",\"datePublished\":\"2026-04-10T18:02:09+00:00\",\"description\":\"CHAMPIONNATS D'EUROPE DE BADMINTON 2026 - Sans trembler, Christo Popov et Toma Junior Popov rallient le dernier carr\u00e9 et peuvent viser le doubl\u00e9.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/christo-popov-et-toma-junior-popov-assurent-une-medaille-et-peuvent-rever-de-double-europeen\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/christo-popov-et-toma-junior-popov-assurent-une-medaille-et-peuvent-rever-de-double-europeen\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/christo-popov-et-toma-junior-popov-assurent-une-medaille-et-peuvent-rever-de-double-europeen\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/04\/Christo-Popov-et-Toma-Junior-Popov-assurent-une-medaille-et-peuvent-rever-de-double-europeen.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/04\/Christo-Popov-et-Toma-Junior-Popov-assurent-une-medaille-et-peuvent-rever-de-double-europeen.png\",\"width\":1200,\"height\":674,\"caption\":\"Christo Popov et Toma Junior Popov assurent une m\u00e9daille et peuvent r\u00eaver de doubl\u00e9 europ\u00e9en\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/christo-popov-et-toma-junior-popov-assurent-une-medaille-et-peuvent-rever-de-double-europeen\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Christo Popov et Toma Junior Popov assurent une m\u00e9daille et peuvent r\u00eaver de doubl\u00e9 europ\u00e9en\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da\",\"name\":\"S\u00e9bastien Gente\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"caption\":\"S\u00e9bastien Gente\"},\"description\":\"John Stockton, Gianni Bugno, Zinedine Zidane, Steffi Graf, Frode Andresen, St\u00e9phane Stoecklin, Davis Kamoga, Primoz Peterka, Werner Schlager et Aur\u00e9lien Rougerie. Point commun entre ces sportifs? Ils m'ont fait r\u00eaver et ont berc\u00e9 mon adolescence. Je suis un fondu de sports et j'essaie de retranscrire ma passion \u00e0 travers mes articles. Originaire du P\u00e9rigord, ma passion pour les Girondins, les Jaunards et les Jazzmen transpire dans mes \u00e9crits. \u00c0 Dicodusport depuis 2021, je d\u00e9niche les sports m\u00e9connus dans lesquels la France brille, et il y en a !\",\"sameAs\":[\"https:\/\/www.facebook.com\/sebastien.gente\/\",\"https:\/\/www.instagram.com\/sebgente\/\",\"https:\/\/www.linkedin.com\/in\/sbastien-gente-a29583169\/\",\"https:\/\/x.com\/https:\/\/twitter.com\/globulo24\",\"SebastienGente\"],\"worksFor\":\"S\u00e9bastien GENTE\",\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/sebastiengente\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Christo Popov et Toma Junior Popov assurent une m\u00e9daille et peuvent r\u00eaver de doubl\u00e9 europ\u00e9en","description":"CHAMPIONNATS D'EUROPE DE BADMINTON 2026 - Sans trembler, Christo Popov et Toma Junior Popov rallient le dernier carr\u00e9 et peuvent viser le doubl\u00e9.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/christo-popov-et-toma-junior-popov-assurent-une-medaille-et-peuvent-rever-de-double-europeen\/","og_locale":"fr_FR","og_type":"article","og_title":"Christo Popov et Toma Junior Popov assurent une m\u00e9daille et peuvent r\u00eaver de doubl\u00e9 europ\u00e9en","og_description":"CHAMPIONNATS D'EUROPE DE BADMINTON 2026 - Sans trembler, Christo Popov et Toma Junior Popov rallient le dernier carr\u00e9 et peuvent viser le doubl\u00e9.","og_url":"https:\/\/dicodusport.fr\/blog\/christo-popov-et-toma-junior-popov-assurent-une-medaille-et-peuvent-rever-de-double-europeen\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/sebastien.gente\/","article_published_time":"2026-04-10T18:02:09+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/04\/Christo-Popov-et-Toma-Junior-Popov-assurent-une-medaille-et-peuvent-rever-de-double-europeen.png","type":"image\/png"}],"author":"S\u00e9bastien Gente","twitter_card":"summary_large_image","twitter_title":"Christo Popov et Toma Junior Popov assurent une m\u00e9daille et peuvent r\u00eaver de doubl\u00e9 europ\u00e9en","twitter_creator":"@https:\/\/twitter.com\/globulo24","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/christo-popov-et-toma-junior-popov-assurent-une-medaille-et-peuvent-rever-de-double-europeen\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/christo-popov-et-toma-junior-popov-assurent-une-medaille-et-peuvent-rever-de-double-europeen\/"},"author":{"name":"S\u00e9bastien Gente","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da"},"headline":"Christo Popov et Toma Junior Popov assurent une m\u00e9daille et peuvent r\u00eaver de doubl\u00e9 europ\u00e9en","datePublished":"2026-04-10T18:02:09+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/christo-popov-et-toma-junior-popov-assurent-une-medaille-et-peuvent-rever-de-double-europeen\/"},"wordCount":429,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/christo-popov-et-toma-junior-popov-assurent-une-medaille-et-peuvent-rever-de-double-europeen\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/04\/Christo-Popov-et-Toma-Junior-Popov-assurent-une-medaille-et-peuvent-rever-de-double-europeen.png","keywords":["br\u00e8ve","Championnats d'Europe de badminton","Christo Popov","Toma Junior Popov"],"articleSection":["Badminton"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/christo-popov-et-toma-junior-popov-assurent-une-medaille-et-peuvent-rever-de-double-europeen\/#respond"]}],"copyrightYear":"2026","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/christo-popov-et-toma-junior-popov-assurent-une-medaille-et-peuvent-rever-de-double-europeen\/","url":"https:\/\/dicodusport.fr\/blog\/christo-popov-et-toma-junior-popov-assurent-une-medaille-et-peuvent-rever-de-double-europeen\/","name":"Christo Popov et Toma Junior Popov assurent une m\u00e9daille et peuvent r\u00eaver de doubl\u00e9 europ\u00e9en","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/christo-popov-et-toma-junior-popov-assurent-une-medaille-et-peuvent-rever-de-double-europeen\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/christo-popov-et-toma-junior-popov-assurent-une-medaille-et-peuvent-rever-de-double-europeen\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/04\/Christo-Popov-et-Toma-Junior-Popov-assurent-une-medaille-et-peuvent-rever-de-double-europeen.png","datePublished":"2026-04-10T18:02:09+00:00","description":"CHAMPIONNATS D'EUROPE DE BADMINTON 2026 - Sans trembler, Christo Popov et Toma Junior Popov rallient le dernier carr\u00e9 et peuvent viser le doubl\u00e9.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/christo-popov-et-toma-junior-popov-assurent-une-medaille-et-peuvent-rever-de-double-europeen\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/christo-popov-et-toma-junior-popov-assurent-une-medaille-et-peuvent-rever-de-double-europeen\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/christo-popov-et-toma-junior-popov-assurent-une-medaille-et-peuvent-rever-de-double-europeen\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/04\/Christo-Popov-et-Toma-Junior-Popov-assurent-une-medaille-et-peuvent-rever-de-double-europeen.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/04\/Christo-Popov-et-Toma-Junior-Popov-assurent-une-medaille-et-peuvent-rever-de-double-europeen.png","width":1200,"height":674,"caption":"Christo Popov et Toma Junior Popov assurent une m\u00e9daille et peuvent r\u00eaver de doubl\u00e9 europ\u00e9en"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/christo-popov-et-toma-junior-popov-assurent-une-medaille-et-peuvent-rever-de-double-europeen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Christo Popov et Toma Junior Popov assurent une m\u00e9daille et peuvent r\u00eaver de doubl\u00e9 europ\u00e9en"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da","name":"S\u00e9bastien Gente","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","caption":"S\u00e9bastien Gente"},"description":"John Stockton, Gianni Bugno, Zinedine Zidane, Steffi Graf, Frode Andresen, St\u00e9phane Stoecklin, Davis Kamoga, Primoz Peterka, Werner Schlager et Aur\u00e9lien Rougerie. Point commun entre ces sportifs? Ils m'ont fait r\u00eaver et ont berc\u00e9 mon adolescence. Je suis un fondu de sports et j'essaie de retranscrire ma passion \u00e0 travers mes articles. Originaire du P\u00e9rigord, ma passion pour les Girondins, les Jaunards et les Jazzmen transpire dans mes \u00e9crits. \u00c0 Dicodusport depuis 2021, je d\u00e9niche les sports m\u00e9connus dans lesquels la France brille, et il y en a !","sameAs":["https:\/\/www.facebook.com\/sebastien.gente\/","https:\/\/www.instagram.com\/sebgente\/","https:\/\/www.linkedin.com\/in\/sbastien-gente-a29583169\/","https:\/\/x.com\/https:\/\/twitter.com\/globulo24","SebastienGente"],"worksFor":"S\u00e9bastien GENTE","url":"https:\/\/dicodusport.fr\/blog\/author\/sebastiengente\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/661885","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/59"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=661885"}],"version-history":[{"count":1,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/661885\/revisions"}],"predecessor-version":[{"id":661889,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/661885\/revisions\/661889"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/661888"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=661885"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=661885"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=661885"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}