{"id":661903,"date":"2026-04-10T22:51:31","date_gmt":"2026-04-10T20:51:31","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=661903&#038;preview=true&#038;preview_id=661903"},"modified":"2026-04-10T23:02:52","modified_gmt":"2026-04-10T21:02:52","slug":"defaite-logique-pour-lasvel-face-aux-serbes-de-letoile-rouge","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/defaite-logique-pour-lasvel-face-aux-serbes-de-letoile-rouge\/","title":{"rendered":"D\u00e9faite logique pour l\u2019ASVEL face aux Serbes de l&rsquo;\u00c9toile Rouge"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>EUROLIGUE 2025\/2026 &#8211; <\/em><em>Battue par l\u2019\u00c9toile Rouge (106-93), l\u2019ASVEL a pourtant montr\u00e9 du caract\u00e8re en revenant dans le match. Mais les Villeurbannais ont fini par c\u00e9der face \u00e0 l\u2019intensit\u00e9 et \u00e0 l\u2019adresse des Serbes.<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">\u00c0 l\u2019occasion de l\u2019avant-derni\u00e8re journ\u00e9e d\u2019Euroligue, <strong>l\u2019ASVEL<\/strong> recevait l\u2019<strong>\u00c9toile Rouge de Belgrade<\/strong>, avant de conclure sa saison face au <strong>Fenerbah\u00e7e<\/strong>. D\u00e9j\u00e0 assur\u00e9s de terminer derniers, les Villeurbannais affrontaient une \u00e9quipe serbe encore en lice pour une place en play-in.<\/p>\n<ul style=\"text-align: justify;\">\n<li style=\"text-align: justify;\"><strong>\u00c0 lire aussi \u2013 <a href=\"https:\/\/dicodusport.fr\/blog\/classement-actualise-euroligue-masculine-2025-2026\/\">Classement actualis\u00e9 EuroLigue masculine 2025-2026<\/a><\/strong><\/li>\n<\/ul>\n<h2 style=\"text-align: justify;\" data-section-id=\"1h3f12b\" data-start=\"83\" data-end=\"136\">L\u2019ASVEL r\u00e9siste puis craque<\/h2>\n<p style=\"text-align: justify;\" data-start=\"138\" data-end=\"402\">Si le jeu est parfois d\u00e9cousu, <strong>l\u2019ASVEL<\/strong> fait jeu \u00e9gal avec l\u2019<strong>\u00c9toile Rouge<\/strong> dans le premier quart-temps. Port\u00e9s par un bon <strong>Thomas Heurtel<\/strong> (9 points dans le premier quart-temps), les Villeurbannais tiennent le rythme et restent au contact \u00e0 l\u2019issue du premier acte (26-26).<\/p>\n<p style=\"text-align: justify;\" data-start=\"404\" data-end=\"883\">Mais le deuxi\u00e8me quart-temps tourne nettement en faveur des Serbes. Plus agressifs d\u00e9fensivement, les joueurs de l\u2019<strong>\u00c9toile Rouge<\/strong> imposent leur intensit\u00e9 et envoient rapidement <strong>l\u2019ASVEL<\/strong> dans la p\u00e9nalit\u00e9. L\u2019\u00e9cart se creuse progressivement, d\u2019autant que Villeurbanne cale offensivement, avec seulement 7 points inscrits en sept minutes. En face, l\u2019adresse ext\u00e9rieure fait la diff\u00e9rence, permettant aux visiteurs de rejoindre les vestiaires avec une avance confortable (55-43).<\/p>\n<h2 style=\"text-align: justify;\" data-section-id=\"rwwawj\" data-start=\"1845\" data-end=\"1912\"><span role=\"text\"><strong>Mais l\u2019ASVEL r\u00e9agit, puis finit par c\u00e9der dans le dernier quart-temps<\/strong><\/span><\/h2>\n<p style=\"text-align: justify;\" data-start=\"1914\" data-end=\"2367\"><strong>L\u2019ASVEL<\/strong> revient des vestiaires avec de meilleures intentions et hausse le ton d\u00e9fensivement. Bien emmen\u00e9s par <strong>Mbaye Ndiaye<\/strong>, les Villeurbannais multiplient les contres et se projettent rapidement en contre-attaque, port\u00e9s par l\u2019exp\u00e9rience d\u2019<strong>Edwin Jackson<\/strong> et de <strong>Braian Angola<\/strong>. L\u2019<strong>\u00c9toile Rouge<\/strong> est compl\u00e8tement \u00e9touff\u00e9e dans ce passage, ne marquant que 2 petits points en cinq minutes, ce qui permet \u00e0 l\u2019ASVEL de repasser devant (59-57).<\/p>\n<p style=\"text-align: justify;\" data-start=\"2369\" data-end=\"2589\">Mais les Serbes r\u00e9agissent en fin de troisi\u00e8me quart-temps. <strong>Moneke<\/strong> et <strong>Butler<\/strong> relancent leur \u00e9quipe avec des tirs prim\u00e9s pr\u00e9cieux, redonnant l\u2019avantage \u00e0 l\u2019\u00c9toile Rouge (71-74) avant les dix derni\u00e8res minutes.<\/p>\n<p style=\"text-align: justify;\" data-start=\"2591\" data-end=\"2984\">Le d\u00e9but du quatri\u00e8me quart-temps tourne toutefois \u00e0 l\u2019avantage des visiteurs. Plus physiques et plus agressifs, les joueurs de l\u2019\u00c9toile Rouge creusent rapidement un \u00e9cart de neuf points. <strong>Jordan Nwora<\/strong> se montre particuli\u00e8rement pr\u00e9cieux dans ce moment cl\u00e9. Malgr\u00e9 quelques tentatives de retour, l\u2019ASVEL ne parvient pas \u00e0 inverser la tendance. L\u2019\u00c9toile Rouge s\u2019impose finalement 106-93.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">L&rsquo;\u00c9toile Rouge a fait la diff\u00e9rence dans le dernier quart-temps.<\/p>\n<p>Merci l&rsquo;Astroballe pour cette superbe ambiance, on se revoit d\u00e8s dimanche face \u00e0 Saint-Quentin ! \ud83e\udef6 <a href=\"https:\/\/t.co\/cPqd9Kck3X\">pic.twitter.com\/cPqd9Kck3X<\/a><\/p>\n<p>\u2014 LDLC ASVEL (@LDLCASVEL) <a href=\"https:\/\/twitter.com\/LDLCASVEL\/status\/2042707604682445153?ref_src=twsrc%5Etfw\">April 10, 2026<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<ul style=\"text-align: justify;\">\n<li style=\"text-align: justify;\"><strong>\u00c0 lire aussi \u2013 <a href=\"https:\/\/dicodusport.fr\/blog\/calendrier-et-resultats-euroligue-masculine-2025-2026\/\">Calendrier et r\u00e9sultats EuroLigue masculine 2025-2026<\/a><\/strong><\/li>\n<\/ul>\n<div id=\"gtx-trans\" style=\"position: absolute; left: -14px; top: 40.9091px;\">\n<div class=\"gtx-trans-icon\" style=\"text-align: justify;\"><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Battue par l\u2019\u00c9toile Rouge (106-93), l\u2019ASVEL a pourtant montr\u00e9 du caract\u00e8re en revenant dans le match. Mais les Villeurbannais ont fini par c\u00e9der face \u00e0 l\u2019intensit\u00e9 et \u00e0 l\u2019adresse des Serbes.<\/p>\n","protected":false},"author":111,"featured_media":661949,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[47001],"tags":[32415,7864,16878,181],"class_list":["post-661903","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-euroligue","tag-actu","tag-asvel","tag-breve","tag-euroligue"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>D\u00e9faite logique pour l\u2019ASVEL face aux Serbes de l&#039;\u00c9toile Rouge<\/title>\n<meta name=\"description\" content=\"Battue par l\u2019\u00c9toile Rouge (106-93), l\u2019ASVEL a pourtant montr\u00e9 du caract\u00e8re en revenant dans le match. Mais les Villeurbannais ont fini par c\u00e9der face \u00e0 l\u2019intensit\u00e9 et \u00e0 l\u2019adresse des Serbes.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/defaite-logique-pour-lasvel-face-aux-serbes-de-letoile-rouge\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"D\u00e9faite logique pour l\u2019ASVEL face aux Serbes de l&#039;\u00c9toile Rouge\" \/>\n<meta property=\"og:description\" content=\"Battue par l\u2019\u00c9toile Rouge (106-93), l\u2019ASVEL a pourtant montr\u00e9 du caract\u00e8re en revenant dans le match. Mais les Villeurbannais ont fini par c\u00e9der face \u00e0 l\u2019intensit\u00e9 et \u00e0 l\u2019adresse des Serbes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/defaite-logique-pour-lasvel-face-aux-serbes-de-letoile-rouge\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-10T20:51:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-10T21:02:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/04\/Defaite-logique-pour-lASVEL-face-aux-Serbes-de-lEtoile-Rouge.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"L\u00e9o Derambure\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"D\u00e9faite logique pour l\u2019ASVEL face aux Serbes de l&#039;\u00c9toile Rouge\" \/>\n<meta name=\"twitter:creator\" content=\"@dicodusport\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/defaite-logique-pour-lasvel-face-aux-serbes-de-letoile-rouge\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/defaite-logique-pour-lasvel-face-aux-serbes-de-letoile-rouge\/\"},\"author\":{\"name\":\"L\u00e9o Derambure\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/93f03e222ed8da203c940d17ef257295\"},\"headline\":\"D\u00e9faite logique pour l\u2019ASVEL face aux Serbes de l&rsquo;\u00c9toile Rouge\",\"datePublished\":\"2026-04-10T20:51:31+00:00\",\"dateModified\":\"2026-04-10T21:02:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/defaite-logique-pour-lasvel-face-aux-serbes-de-letoile-rouge\/\"},\"wordCount\":464,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/defaite-logique-pour-lasvel-face-aux-serbes-de-letoile-rouge\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/04\/Defaite-logique-pour-lASVEL-face-aux-Serbes-de-lEtoile-Rouge.png\",\"keywords\":[\"actu\",\"ASVEL\",\"br\u00e8ve\",\"Euroligue\"],\"articleSection\":[\"EuroLigue\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/defaite-logique-pour-lasvel-face-aux-serbes-de-letoile-rouge\/#respond\"]}],\"copyrightYear\":\"2026\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/defaite-logique-pour-lasvel-face-aux-serbes-de-letoile-rouge\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/defaite-logique-pour-lasvel-face-aux-serbes-de-letoile-rouge\/\",\"name\":\"D\u00e9faite logique pour l\u2019ASVEL face aux Serbes de l'\u00c9toile Rouge\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/defaite-logique-pour-lasvel-face-aux-serbes-de-letoile-rouge\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/defaite-logique-pour-lasvel-face-aux-serbes-de-letoile-rouge\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/04\/Defaite-logique-pour-lASVEL-face-aux-Serbes-de-lEtoile-Rouge.png\",\"datePublished\":\"2026-04-10T20:51:31+00:00\",\"dateModified\":\"2026-04-10T21:02:52+00:00\",\"description\":\"Battue par l\u2019\u00c9toile Rouge (106-93), l\u2019ASVEL a pourtant montr\u00e9 du caract\u00e8re en revenant dans le match. Mais les Villeurbannais ont fini par c\u00e9der face \u00e0 l\u2019intensit\u00e9 et \u00e0 l\u2019adresse des Serbes.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/defaite-logique-pour-lasvel-face-aux-serbes-de-letoile-rouge\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/defaite-logique-pour-lasvel-face-aux-serbes-de-letoile-rouge\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/defaite-logique-pour-lasvel-face-aux-serbes-de-letoile-rouge\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/04\/Defaite-logique-pour-lASVEL-face-aux-Serbes-de-lEtoile-Rouge.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/04\/Defaite-logique-pour-lASVEL-face-aux-Serbes-de-lEtoile-Rouge.png\",\"width\":1200,\"height\":674,\"caption\":\"D\u00e9faite logique pour l\u2019ASVEL face aux Serbes de l'\u00c9toile Rouge\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/defaite-logique-pour-lasvel-face-aux-serbes-de-letoile-rouge\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"D\u00e9faite logique pour l\u2019ASVEL face aux Serbes de l&rsquo;\u00c9toile Rouge\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/93f03e222ed8da203c940d17ef257295\",\"name\":\"L\u00e9o Derambure\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Maillot-Dicodusport-Lele-150x150.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Maillot-Dicodusport-Lele-150x150.png\",\"caption\":\"L\u00e9o Derambure\"},\"description\":\"Passionn\u00e9 de sport depuis l\u2019enfance, j\u2019ai grandi au rythme des grands \u00e9v\u00e9nements comme les Jeux Olympiques, les championnats du monde d\u2019athl\u00e9tisme et de natation, ou encore le Tour de France sur France T\u00e9l\u00e9visions. Abonn\u00e9 au RC Lens depuis 2008, cette ferveur m\u2019a \u00e9t\u00e9 transmise d\u00e8s l\u2019\u00e2ge de 5 ans par mon grand-p\u00e8re et mon p\u00e8re. Avec Rafael Nadal ou encore Aruna Dindane comme idole, j\u2019ai toujours ressenti l\u2019envie de partager cette passion \u00e0 travers l\u2019\u00e9criture. Apr\u00e8s les Jeux Olympiques de Paris 2024, j\u2019ai franchi le pas en rejoignant l\u2019\u00e9quipe de r\u00e9daction de Dicodusport. Aujourd\u2019hui, je couvre le biathlon, le ski alpin ainsi que les rencontres des clubs fran\u00e7ais en comp\u00e9titions europ\u00e9ennes, avec l'envie de faire vivre chaque instant sportif et de transmettre ces \u00e9motions au lecteur, comme s\u2019il \u00e9tait au c\u0153ur de l\u2019\u00e9v\u00e9nement.\",\"worksFor\":\"L\u00e9o Derambure\",\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/leo-derambure\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"D\u00e9faite logique pour l\u2019ASVEL face aux Serbes de l'\u00c9toile Rouge","description":"Battue par l\u2019\u00c9toile Rouge (106-93), l\u2019ASVEL a pourtant montr\u00e9 du caract\u00e8re en revenant dans le match. Mais les Villeurbannais ont fini par c\u00e9der face \u00e0 l\u2019intensit\u00e9 et \u00e0 l\u2019adresse des Serbes.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/defaite-logique-pour-lasvel-face-aux-serbes-de-letoile-rouge\/","og_locale":"fr_FR","og_type":"article","og_title":"D\u00e9faite logique pour l\u2019ASVEL face aux Serbes de l'\u00c9toile Rouge","og_description":"Battue par l\u2019\u00c9toile Rouge (106-93), l\u2019ASVEL a pourtant montr\u00e9 du caract\u00e8re en revenant dans le match. Mais les Villeurbannais ont fini par c\u00e9der face \u00e0 l\u2019intensit\u00e9 et \u00e0 l\u2019adresse des Serbes.","og_url":"https:\/\/dicodusport.fr\/blog\/defaite-logique-pour-lasvel-face-aux-serbes-de-letoile-rouge\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2026-04-10T20:51:31+00:00","article_modified_time":"2026-04-10T21:02:52+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/04\/Defaite-logique-pour-lASVEL-face-aux-Serbes-de-lEtoile-Rouge.png","type":"image\/png"}],"author":"L\u00e9o Derambure","twitter_card":"summary_large_image","twitter_title":"D\u00e9faite logique pour l\u2019ASVEL face aux Serbes de l'\u00c9toile Rouge","twitter_creator":"@dicodusport","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/defaite-logique-pour-lasvel-face-aux-serbes-de-letoile-rouge\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/defaite-logique-pour-lasvel-face-aux-serbes-de-letoile-rouge\/"},"author":{"name":"L\u00e9o Derambure","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/93f03e222ed8da203c940d17ef257295"},"headline":"D\u00e9faite logique pour l\u2019ASVEL face aux Serbes de l&rsquo;\u00c9toile Rouge","datePublished":"2026-04-10T20:51:31+00:00","dateModified":"2026-04-10T21:02:52+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/defaite-logique-pour-lasvel-face-aux-serbes-de-letoile-rouge\/"},"wordCount":464,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/defaite-logique-pour-lasvel-face-aux-serbes-de-letoile-rouge\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/04\/Defaite-logique-pour-lASVEL-face-aux-Serbes-de-lEtoile-Rouge.png","keywords":["actu","ASVEL","br\u00e8ve","Euroligue"],"articleSection":["EuroLigue"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/defaite-logique-pour-lasvel-face-aux-serbes-de-letoile-rouge\/#respond"]}],"copyrightYear":"2026","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/defaite-logique-pour-lasvel-face-aux-serbes-de-letoile-rouge\/","url":"https:\/\/dicodusport.fr\/blog\/defaite-logique-pour-lasvel-face-aux-serbes-de-letoile-rouge\/","name":"D\u00e9faite logique pour l\u2019ASVEL face aux Serbes de l'\u00c9toile Rouge","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/defaite-logique-pour-lasvel-face-aux-serbes-de-letoile-rouge\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/defaite-logique-pour-lasvel-face-aux-serbes-de-letoile-rouge\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/04\/Defaite-logique-pour-lASVEL-face-aux-Serbes-de-lEtoile-Rouge.png","datePublished":"2026-04-10T20:51:31+00:00","dateModified":"2026-04-10T21:02:52+00:00","description":"Battue par l\u2019\u00c9toile Rouge (106-93), l\u2019ASVEL a pourtant montr\u00e9 du caract\u00e8re en revenant dans le match. Mais les Villeurbannais ont fini par c\u00e9der face \u00e0 l\u2019intensit\u00e9 et \u00e0 l\u2019adresse des Serbes.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/defaite-logique-pour-lasvel-face-aux-serbes-de-letoile-rouge\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/defaite-logique-pour-lasvel-face-aux-serbes-de-letoile-rouge\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/defaite-logique-pour-lasvel-face-aux-serbes-de-letoile-rouge\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/04\/Defaite-logique-pour-lASVEL-face-aux-Serbes-de-lEtoile-Rouge.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/04\/Defaite-logique-pour-lASVEL-face-aux-Serbes-de-lEtoile-Rouge.png","width":1200,"height":674,"caption":"D\u00e9faite logique pour l\u2019ASVEL face aux Serbes de l'\u00c9toile Rouge"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/defaite-logique-pour-lasvel-face-aux-serbes-de-letoile-rouge\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"D\u00e9faite logique pour l\u2019ASVEL face aux Serbes de l&rsquo;\u00c9toile Rouge"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/93f03e222ed8da203c940d17ef257295","name":"L\u00e9o Derambure","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Maillot-Dicodusport-Lele-150x150.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Maillot-Dicodusport-Lele-150x150.png","caption":"L\u00e9o Derambure"},"description":"Passionn\u00e9 de sport depuis l\u2019enfance, j\u2019ai grandi au rythme des grands \u00e9v\u00e9nements comme les Jeux Olympiques, les championnats du monde d\u2019athl\u00e9tisme et de natation, ou encore le Tour de France sur France T\u00e9l\u00e9visions. Abonn\u00e9 au RC Lens depuis 2008, cette ferveur m\u2019a \u00e9t\u00e9 transmise d\u00e8s l\u2019\u00e2ge de 5 ans par mon grand-p\u00e8re et mon p\u00e8re. Avec Rafael Nadal ou encore Aruna Dindane comme idole, j\u2019ai toujours ressenti l\u2019envie de partager cette passion \u00e0 travers l\u2019\u00e9criture. Apr\u00e8s les Jeux Olympiques de Paris 2024, j\u2019ai franchi le pas en rejoignant l\u2019\u00e9quipe de r\u00e9daction de Dicodusport. Aujourd\u2019hui, je couvre le biathlon, le ski alpin ainsi que les rencontres des clubs fran\u00e7ais en comp\u00e9titions europ\u00e9ennes, avec l'envie de faire vivre chaque instant sportif et de transmettre ces \u00e9motions au lecteur, comme s\u2019il \u00e9tait au c\u0153ur de l\u2019\u00e9v\u00e9nement.","worksFor":"L\u00e9o Derambure","url":"https:\/\/dicodusport.fr\/blog\/author\/leo-derambure\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/661903","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/111"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=661903"}],"version-history":[{"count":5,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/661903\/revisions"}],"predecessor-version":[{"id":661965,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/661903\/revisions\/661965"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/661949"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=661903"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=661903"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=661903"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}