{"id":662140,"date":"2026-04-11T19:55:27","date_gmt":"2026-04-11T17:55:27","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=662140&#038;preview=true&#038;preview_id=662140"},"modified":"2026-04-11T20:01:54","modified_gmt":"2026-04-11T18:01:54","slug":"les-bleuets-se-jouent-de-lirlande-et-triomphent-au-festival-six-nations-u18","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/les-bleuets-se-jouent-de-lirlande-et-triomphent-au-festival-six-nations-u18\/","title":{"rendered":"Les Bleuets se jouent de l&rsquo;Irlande et triomphent au Festival Six Nations U18"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>FESTIVAL DES SIX NATIONS U18 2026 \u2013 L&rsquo;\u00e9quipe de France U18 a r\u00e9alis\u00e9 un sans-faute en remportant son troisi\u00e8me match \u00e0 Vichy, face \u00e0 l&rsquo;Irlande, 43-29.\u00a0<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">Victorieux successivement de la <a href=\"https:\/\/dicodusport.fr\/blog\/les-bleuets-ecartent-non-sans-peine-la-georgie-pour-debuter-leur-festival-des-six-nations-2026\/\">G\u00e9orgie (49-22)<\/a>, puis du<a href=\"https:\/\/dicodusport.fr\/blog\/les-bleuets-viennent-a-bout-du-pays-de-galles-et-decrochent-un-deuxieme-succes-au-festival-des-six-nations-u18\/\"> Pays de Galles (33-31)<\/a>, l&rsquo;<strong>\u00e9quipe de France U18 masculine<\/strong> avait la possibilit\u00e9 de conclure son <strong>Festival des Six Nations U18<\/strong> comme son homologue f\u00e9minine : par la victoire finale. Pour cela, il fallait se d\u00e9faire d&rsquo;une <strong>Irlande<\/strong> \u00e9galement vainqueure de ses deux premiers matchs.<\/p>\n<div class=\"vlp-link-container vlp-layout-article\"><a href=\"https:\/\/dicodusport.fr\/blog\/les-bleuettes-roulent-sur-les-anglaises-et-remportent-le-festival-des-6-nations\/\" class=\"vlp-link\" title=\"Les Bleuettes roulent sur les Anglaises et remportent le Festival des 6 Nations !\"><\/a><div class=\"vlp-layout-zone-side\"><div class=\"vlp-block-4 vlp-link-image\"><img loading=\"lazy\" decoding=\"async\" style=\"max-width: 792px;\" width=\"792\" height=\"445\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/04\/Les-Bleuettes-roulent-sur-les-Anglaises-et-remportent-le-Festival-des-6-Nations-.png\" class=\"attachment-800x445 size-800x445\" alt=\"Les Bleuettes roulent sur les Anglaises et remportent le Festival des 6 Nations !\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/04\/Les-Bleuettes-roulent-sur-les-Anglaises-et-remportent-le-Festival-des-6-Nations-.png 1200w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/04\/Les-Bleuettes-roulent-sur-les-Anglaises-et-remportent-le-Festival-des-6-Nations--300x169.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/04\/Les-Bleuettes-roulent-sur-les-Anglaises-et-remportent-le-Festival-des-6-Nations--1024x575.png 1024w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/04\/Les-Bleuettes-roulent-sur-les-Anglaises-et-remportent-le-Festival-des-6-Nations--768x431.png 768w\" sizes=\"auto, (max-width: 792px) 100vw, 792px\" \/><\/div><\/div><div class=\"vlp-layout-zone-main\"><div class=\"vlp-block-0 vlp-link-title\">Les Bleuettes roulent sur les Anglaises et remportent le Festival des 6 Nations !<\/div><div class=\"vlp-block-1 vlp-link-summary\">FESTIVAL DES SIX NATIONS F\u00c9MININ 2026 - Largement sup\u00e9rieures, les Bleuettes ont fait du petit bois avec les Anglaises et remportent la comp\u00e9tition.\u00a0<\/div><div class=\"vlp-block-2 vlp-link-button\">Lire l'article<\/div><div class=\"vlp-block-3 vlp-link-url\">dicodusport.fr<\/div><\/div><\/div>\n<h2 style=\"text-align: justify;\">Les Bleuets dominent la premi\u00e8re p\u00e9riode<\/h2>\n<p style=\"text-align: justify;\">Dans un d\u00e9but de match plut\u00f4t d\u00e9sordonn\u00e9, les Bleuets ont gagn\u00e9 la bataille de l&rsquo;occupation, \u00e0 l&rsquo;image d&rsquo;un magnifique 50-22 qui a initi\u00e9 le premier essai. Suite \u00e0 une p\u00e9nalit\u00e9 rapidement jou\u00e9e, un super offload de <strong>Marius Audemar Ghion<\/strong> a permis \u00e0 <strong>Bixintxo Daguerre<\/strong> de faire mouche (7-0, 14\u00e8me). N\u00e9anmoins, la r\u00e9action irlandaise a \u00e9t\u00e9 imm\u00e9diate, via le capitaine <strong>Luke Coffey<\/strong>, qui remettait les compteurs \u00e0 z\u00e9ro (7-7, 17\u00e8me).<\/p>\n<p style=\"text-align: justify;\">Cela n&rsquo;a \u00e9t\u00e9 qu&rsquo;un simple contretemps puisque sur le renvoi suivant, les trois-quarts ont remont\u00e9 le terrain avant que <strong>Christian Mendes Tani<\/strong> finisse le boulot au ras (14-7, 20\u00e8me). <strong>Prince Tambo Fantcho<\/strong> aurait m\u00eame pu faire le break dans la foul\u00e9e si un en-avant n&rsquo;avait pas \u00e9t\u00e9 commis \u00e0 deux m\u00e8tres de l&#8217;embut. Mais en exer\u00e7ant une pression constante par des courses ou du jeu au pied bien senti, les Tricolores ont roul\u00e9 sur le premier acte. Et sur une \u00e9ni\u00e8me p\u00e9nalit\u00e9 jou\u00e9e rapidement, <strong>Tom Delalain<\/strong> a sign\u00e9 un troisi\u00e8me essai.<\/p>\n<p style=\"text-align: justify;\">Seul b\u00e9mol, le carton jaune conc\u00e9d\u00e9 par <strong>Cl\u00e9o Bard<\/strong> avant la pause, et qui a offert trois points aux Irlandais (21-7, 35\u00e8me).<\/p>\n<h2 style=\"text-align: justify;\">La France tient son avantage jusqu&rsquo;au bout<\/h2>\n<p style=\"text-align: justify;\">En d\u00e9pit de cette inf\u00e9riorit\u00e9, les Tricolores ont repris le second acte dans la m\u00eame lign\u00e9e. D\u00e8s leur premi\u00e8re offensive, la d\u00e9fense irlandaise a \u00e0 nouveau craqu\u00e9 sur une percussion ravageuse de <strong>Christian Mendes Tani<\/strong> (28-10, 39\u00e8me). Une fois le coup de massue encaiss\u00e9, l&rsquo;Irlande a enfin r\u00e9agi en provoquant un deuxi\u00e8me carton jaune. Puis, <strong>Matthew McCarthy<\/strong> a frapp\u00e9 pour rester dans le coup (28-17, 48\u00e8me).<\/p>\n<p style=\"text-align: justify;\">Mais comme en premi\u00e8re p\u00e9riode, un revirement parfaitement g\u00e9r\u00e9 a men\u00e9 \u00e0 un nouvel essai tricolore, sign\u00e9 par l&rsquo;entrant <strong>Valentin Bouju<\/strong> (35-17, 50\u00e8me). Un essai bienvenu \u00e9tant donn\u00e9 que dans la foul\u00e9e, ce diable de <strong>McCarthy<\/strong> a encore frapp\u00e9 (35-24, 52\u00e8me). Le match touchant \u00e0 sa fin, les Bleuets ont fait preuve de pragmatisme en prenant trois points pour capitaliser sur une folle chevauch\u00e9e de <strong>Louis Favrau<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Un choix judicieux au vu du sc\u00e9nario, une erreur d&rsquo;<strong>Elija Lozano<\/strong> offrant \u00e0 <strong>Finn Brennan<\/strong> un essai en coin, heureusement non transform\u00e9 (38-29, 64\u00e8me). Bouscul\u00e9s, les Bleuets ne se sont pas effondr\u00e9s, et ont r\u00e9sist\u00e9 aux derniers assauts irlandais, tout en se permettant m\u00eame d&rsquo;inscrire un ultime essai par l&rsquo;interm\u00e9diaire de <strong>Valentin Bouju<\/strong> encore ! Gr\u00e2ce \u00e0 ce succ\u00e8s spectaculaire <strong>43-29<\/strong>, la victoire finale a \u00e9t\u00e9 assur\u00e9e !<\/p>\n<p><span class=\"2WY4p1RkcFDgLUxBdVTzoJIn9bHNEvPZy3mMiAeOuK60l8G7rftwCSqaQh\"><iframe loading=\"lazy\" title=\"\ud83c\udfdf\ufe0f Festival des Six Nations U18 Masculin 2026 : \ud83c\uddeb\ud83c\uddf7\u2618\ufe0f France\/Irlande\" width=\"740\" height=\"555\" src=\"https:\/\/www.youtube.com\/embed\/sAwvuZbJvPQ?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/span><\/p>\n<div id=\"gtx-trans\" style=\"position: absolute; left: -14px; top: 40.9091px;\">\n<div class=\"gtx-trans-icon\" style=\"text-align: justify;\"><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>FESTIVAL DES SIX NATIONS U18 2026 \u2013 L&rsquo;\u00e9quipe de France U18 a r\u00e9alis\u00e9 un sans-faute en remportant son troisi\u00e8me match \u00e0 Vichy, face \u00e0 l&rsquo;Irlande, 43-29.\u00a0<\/p>\n","protected":false},"author":55,"featured_media":662165,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[9129],"tags":[16878,47462],"class_list":["post-662140","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rugby-a-xv","tag-breve","tag-festival-des-six-nations"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Les Bleuets se jouent de l&#039;Irlande et triomphent au Festival Six Nations U18<\/title>\n<meta name=\"description\" content=\"FESTIVAL DES SIX NATIONS U18 2026 \u2013 L&#039;\u00e9quipe de France U18 a r\u00e9alis\u00e9 un sans-faute en remportant son troisi\u00e8me match \u00e0 Vichy, face \u00e0 l&#039;Irlande, 43-29.\u00a0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/les-bleuets-se-jouent-de-lirlande-et-triomphent-au-festival-six-nations-u18\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les Bleuets se jouent de l&#039;Irlande et triomphent au Festival Six Nations U18\" \/>\n<meta property=\"og:description\" content=\"FESTIVAL DES SIX NATIONS U18 2026 \u2013 L&#039;\u00e9quipe de France U18 a r\u00e9alis\u00e9 un sans-faute en remportant son troisi\u00e8me match \u00e0 Vichy, face \u00e0 l&#039;Irlande, 43-29.\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/les-bleuets-se-jouent-de-lirlande-et-triomphent-au-festival-six-nations-u18\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-11T17:55:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-11T18:01:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/04\/Les-Bleuets-se-jouent-de-lIrlande-et-triomphent-au-Festival-Six-Nations-U18.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Maxime Cazenave\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Les Bleuets se jouent de l&#039;Irlande et triomphent au Festival Six Nations U18\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Maxime_Caze\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/les-bleuets-se-jouent-de-lirlande-et-triomphent-au-festival-six-nations-u18\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/les-bleuets-se-jouent-de-lirlande-et-triomphent-au-festival-six-nations-u18\/\"},\"author\":{\"name\":\"Maxime Cazenave\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0\"},\"headline\":\"Les Bleuets se jouent de l&rsquo;Irlande et triomphent au Festival Six Nations U18\",\"datePublished\":\"2026-04-11T17:55:27+00:00\",\"dateModified\":\"2026-04-11T18:01:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/les-bleuets-se-jouent-de-lirlande-et-triomphent-au-festival-six-nations-u18\/\"},\"wordCount\":644,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/les-bleuets-se-jouent-de-lirlande-et-triomphent-au-festival-six-nations-u18\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/04\/Les-Bleuets-se-jouent-de-lIrlande-et-triomphent-au-Festival-Six-Nations-U18.png\",\"keywords\":[\"br\u00e8ve\",\"Festival des Six Nations\"],\"articleSection\":[\"Rugby \u00e0 XV\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/les-bleuets-se-jouent-de-lirlande-et-triomphent-au-festival-six-nations-u18\/#respond\"]}],\"copyrightYear\":\"2026\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/les-bleuets-se-jouent-de-lirlande-et-triomphent-au-festival-six-nations-u18\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/les-bleuets-se-jouent-de-lirlande-et-triomphent-au-festival-six-nations-u18\/\",\"name\":\"Les Bleuets se jouent de l'Irlande et triomphent au Festival Six Nations U18\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/les-bleuets-se-jouent-de-lirlande-et-triomphent-au-festival-six-nations-u18\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/les-bleuets-se-jouent-de-lirlande-et-triomphent-au-festival-six-nations-u18\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/04\/Les-Bleuets-se-jouent-de-lIrlande-et-triomphent-au-Festival-Six-Nations-U18.png\",\"datePublished\":\"2026-04-11T17:55:27+00:00\",\"dateModified\":\"2026-04-11T18:01:54+00:00\",\"description\":\"FESTIVAL DES SIX NATIONS U18 2026 \u2013 L'\u00e9quipe de France U18 a r\u00e9alis\u00e9 un sans-faute en remportant son troisi\u00e8me match \u00e0 Vichy, face \u00e0 l'Irlande, 43-29.\u00a0\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/les-bleuets-se-jouent-de-lirlande-et-triomphent-au-festival-six-nations-u18\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/les-bleuets-se-jouent-de-lirlande-et-triomphent-au-festival-six-nations-u18\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/les-bleuets-se-jouent-de-lirlande-et-triomphent-au-festival-six-nations-u18\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/04\/Les-Bleuets-se-jouent-de-lIrlande-et-triomphent-au-Festival-Six-Nations-U18.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/04\/Les-Bleuets-se-jouent-de-lIrlande-et-triomphent-au-Festival-Six-Nations-U18.png\",\"width\":1200,\"height\":674,\"caption\":\"Les Bleuets se jouent de l'Irlande et triomphent au Festival Six Nations U18\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/les-bleuets-se-jouent-de-lirlande-et-triomphent-au-festival-six-nations-u18\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les Bleuets se jouent de l&rsquo;Irlande et triomphent au Festival Six Nations U18\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0\",\"name\":\"Maxime Cazenave\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg\",\"caption\":\"Maxime Cazenave\"},\"description\":\"Journaliste\/R\u00e9dacteur depuis 2012 - Berc\u00e9 par l\u2019amour des Girondins de Bordeaux, les \u00e9checs de Christophe Moreau sur le Tour de France sous l'\u00e8re Lance Armstrong et le fade-away l\u00e9tal de Dirk Nowitzki, ma passion d\u00e9vorante pour le sport a toujours \u00e9t\u00e9 un pan incontournable de ma vie. Transmettre ma passion \u00e0 l\u2019\u00e9crit a \u00e9t\u00e9 une transition naturelle. Suiveur assidu de basket et de hockey sur glace, je garde toujours un peu de place pour suivre le cyclisme, le football et le maximum de performances fran\u00e7aises.\",\"sameAs\":[\"https:\/\/x.com\/https:\/\/twitter.com\/Maxime_Caze\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/maximec\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Les Bleuets se jouent de l'Irlande et triomphent au Festival Six Nations U18","description":"FESTIVAL DES SIX NATIONS U18 2026 \u2013 L'\u00e9quipe de France U18 a r\u00e9alis\u00e9 un sans-faute en remportant son troisi\u00e8me match \u00e0 Vichy, face \u00e0 l'Irlande, 43-29.\u00a0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/les-bleuets-se-jouent-de-lirlande-et-triomphent-au-festival-six-nations-u18\/","og_locale":"fr_FR","og_type":"article","og_title":"Les Bleuets se jouent de l'Irlande et triomphent au Festival Six Nations U18","og_description":"FESTIVAL DES SIX NATIONS U18 2026 \u2013 L'\u00e9quipe de France U18 a r\u00e9alis\u00e9 un sans-faute en remportant son troisi\u00e8me match \u00e0 Vichy, face \u00e0 l'Irlande, 43-29.\u00a0","og_url":"https:\/\/dicodusport.fr\/blog\/les-bleuets-se-jouent-de-lirlande-et-triomphent-au-festival-six-nations-u18\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2026-04-11T17:55:27+00:00","article_modified_time":"2026-04-11T18:01:54+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/04\/Les-Bleuets-se-jouent-de-lIrlande-et-triomphent-au-Festival-Six-Nations-U18.png","type":"image\/png"}],"author":"Maxime Cazenave","twitter_card":"summary_large_image","twitter_title":"Les Bleuets se jouent de l'Irlande et triomphent au Festival Six Nations U18","twitter_creator":"@https:\/\/twitter.com\/Maxime_Caze","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/les-bleuets-se-jouent-de-lirlande-et-triomphent-au-festival-six-nations-u18\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/les-bleuets-se-jouent-de-lirlande-et-triomphent-au-festival-six-nations-u18\/"},"author":{"name":"Maxime Cazenave","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0"},"headline":"Les Bleuets se jouent de l&rsquo;Irlande et triomphent au Festival Six Nations U18","datePublished":"2026-04-11T17:55:27+00:00","dateModified":"2026-04-11T18:01:54+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/les-bleuets-se-jouent-de-lirlande-et-triomphent-au-festival-six-nations-u18\/"},"wordCount":644,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/les-bleuets-se-jouent-de-lirlande-et-triomphent-au-festival-six-nations-u18\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/04\/Les-Bleuets-se-jouent-de-lIrlande-et-triomphent-au-Festival-Six-Nations-U18.png","keywords":["br\u00e8ve","Festival des Six Nations"],"articleSection":["Rugby \u00e0 XV"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/les-bleuets-se-jouent-de-lirlande-et-triomphent-au-festival-six-nations-u18\/#respond"]}],"copyrightYear":"2026","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/les-bleuets-se-jouent-de-lirlande-et-triomphent-au-festival-six-nations-u18\/","url":"https:\/\/dicodusport.fr\/blog\/les-bleuets-se-jouent-de-lirlande-et-triomphent-au-festival-six-nations-u18\/","name":"Les Bleuets se jouent de l'Irlande et triomphent au Festival Six Nations U18","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/les-bleuets-se-jouent-de-lirlande-et-triomphent-au-festival-six-nations-u18\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/les-bleuets-se-jouent-de-lirlande-et-triomphent-au-festival-six-nations-u18\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/04\/Les-Bleuets-se-jouent-de-lIrlande-et-triomphent-au-Festival-Six-Nations-U18.png","datePublished":"2026-04-11T17:55:27+00:00","dateModified":"2026-04-11T18:01:54+00:00","description":"FESTIVAL DES SIX NATIONS U18 2026 \u2013 L'\u00e9quipe de France U18 a r\u00e9alis\u00e9 un sans-faute en remportant son troisi\u00e8me match \u00e0 Vichy, face \u00e0 l'Irlande, 43-29.\u00a0","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/les-bleuets-se-jouent-de-lirlande-et-triomphent-au-festival-six-nations-u18\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/les-bleuets-se-jouent-de-lirlande-et-triomphent-au-festival-six-nations-u18\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/les-bleuets-se-jouent-de-lirlande-et-triomphent-au-festival-six-nations-u18\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/04\/Les-Bleuets-se-jouent-de-lIrlande-et-triomphent-au-Festival-Six-Nations-U18.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/04\/Les-Bleuets-se-jouent-de-lIrlande-et-triomphent-au-Festival-Six-Nations-U18.png","width":1200,"height":674,"caption":"Les Bleuets se jouent de l'Irlande et triomphent au Festival Six Nations U18"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/les-bleuets-se-jouent-de-lirlande-et-triomphent-au-festival-six-nations-u18\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Les Bleuets se jouent de l&rsquo;Irlande et triomphent au Festival Six Nations U18"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0","name":"Maxime Cazenave","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg","caption":"Maxime Cazenave"},"description":"Journaliste\/R\u00e9dacteur depuis 2012 - Berc\u00e9 par l\u2019amour des Girondins de Bordeaux, les \u00e9checs de Christophe Moreau sur le Tour de France sous l'\u00e8re Lance Armstrong et le fade-away l\u00e9tal de Dirk Nowitzki, ma passion d\u00e9vorante pour le sport a toujours \u00e9t\u00e9 un pan incontournable de ma vie. Transmettre ma passion \u00e0 l\u2019\u00e9crit a \u00e9t\u00e9 une transition naturelle. Suiveur assidu de basket et de hockey sur glace, je garde toujours un peu de place pour suivre le cyclisme, le football et le maximum de performances fran\u00e7aises.","sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/Maxime_Caze"],"url":"https:\/\/dicodusport.fr\/blog\/author\/maximec\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/662140","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=662140"}],"version-history":[{"count":5,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/662140\/revisions"}],"predecessor-version":[{"id":662177,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/662140\/revisions\/662177"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/662165"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=662140"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=662140"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=662140"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}