{"id":662502,"date":"2026-04-12T21:48:37","date_gmt":"2026-04-12T19:48:37","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=662502&#038;preview=true&#038;preview_id=662502"},"modified":"2026-04-12T22:21:58","modified_gmt":"2026-04-12T20:21:58","slug":"les-bleues-chutent-apres-prolongation-face-a-la-hongrie-en-ouverture-du-mondial-d1a","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/les-bleues-chutent-apres-prolongation-face-a-la-hongrie-en-ouverture-du-mondial-d1a\/","title":{"rendered":"Les Bleues chutent apr\u00e8s prolongation face \u00e0 la Hongrie en ouverture du Mondial D1A"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>MONDIAL D1 F\u00c9MININ 2026 &#8211; Crucifi\u00e9e par un lancer magistral en prolongations, l&rsquo;\u00e9quipe de France s&rsquo;est inclin\u00e9e ce dimanche face \u00e0 la Hongrie, 3-2.\u00a0<\/em><\/strong><\/p>\n<ul>\n<li style=\"text-align: justify;\"><strong>\u00c0 lire aussi &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/ambitieuses-les-bleues-du-hockey-visent-la-montee-dans-un-mondial-d1a-plus-releve-que-jamais\/\">Ambitieuses, les Bleues du hockey visent la mont\u00e9e dans un Mondial D1A plus relev\u00e9 que jamais<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">La parenth\u00e8se des Jeux Olympiques d&rsquo;Hiver referm\u00e9e, l&rsquo;<strong>\u00e9quipe de France f\u00e9minine<\/strong> fait d\u00e9j\u00e0 face \u00e0 un objectif de taille cette semaine : remporter le titre, synonyme d&rsquo;accession \u00e0 l&rsquo;\u00c9lite, au <strong>Mondial D1A<\/strong> de <strong>Budapest<\/strong>. Oppos\u00e9es \u00e0 l&rsquo;h\u00f4te hongrois d&rsquo;entr\u00e9e, les Bleues faisaient face \u00e0 un premier gros test.<\/p>\n<h2 style=\"text-align: justify;\">Les Bleues multiplient les tirs, la Hongrie les occasions<\/h2>\n<p style=\"text-align: justify;\">Tout de suite bien rentr\u00e9es dans leur match, elles ont multipli\u00e9 les lancers sur la gardienne hongroise. N\u00e9anmoins, les meilleures occasions ont \u00e9t\u00e9 Hongroises. Sur des transitions mal g\u00e9r\u00e9es, <strong>Alice Philbert<\/strong> a ainsi sorti deux arr\u00eats d\u00e9cisifs dans les dix premi\u00e8res minutes. Au fil des minutes, la pression s&rsquo;est invers\u00e9e, et <strong>R\u00e9ka Dabasi<\/strong> a rapidement puni les largesses de la d\u00e9fense en profitant d&rsquo;un rebond laiss\u00e9 suite \u00e0 un tir \u00e0 bout portant de <strong>Madeline Leidt<\/strong> (0-1, 13\u00e8me).<\/p>\n<p style=\"text-align: justify;\">Dans la foul\u00e9e, les Bleues ont g\u00e2ch\u00e9 une premi\u00e8re sup\u00e9riorit\u00e9, et ont boucl\u00e9 ce premier tiers avec un seul but de retard. En d\u00e9pit d&rsquo;un avantage net au chapitre des tirs (16 \u00e0 6), c&rsquo;est bien la Hongrie qui a dispos\u00e9 des meilleures situations, souvent g\u00e2ch\u00e9es par des impr\u00e9cisions bienvenues.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"en\">The hosts score their first goal at the 2026 <a href=\"https:\/\/twitter.com\/hashtag\/WomensWorlds?src=hash&amp;ref_src=twsrc%5Etfw\">#WomensWorlds<\/a> 1A! \ud83d\udea8\ud83c\udded\ud83c\uddfa <a href=\"https:\/\/twitter.com\/hashtag\/IIHF?src=hash&amp;ref_src=twsrc%5Etfw\">#IIHF<\/a> <a href=\"https:\/\/twitter.com\/hockeyhungary?ref_src=twsrc%5Etfw\">@hockeyhungary<\/a> <a href=\"https:\/\/t.co\/ezpPPNsf0E\">pic.twitter.com\/ezpPPNsf0E<\/a><\/p>\n<p>\u2014 IIHF (@IIHFHockey) <a href=\"https:\/\/twitter.com\/IIHFHockey\/status\/2043388107383246970?ref_src=twsrc%5Etfw\">April 12, 2026<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 style=\"text-align: justify;\">L&rsquo;indiscipline, fardeau du deuxi\u00e8me tiers<\/h2>\n<p style=\"text-align: justify;\">Au retour des vestiaires, les Tricolores ont imm\u00e9diatement subi une grosse pression caus\u00e9e par une premi\u00e8re p\u00e9nalit\u00e9. Mais une fois l&rsquo;orage pass\u00e9, <strong>Estelle Duvin<\/strong> a remis les compteurs \u00e0 z\u00e9ro en remportant un duel offert par un oubli d\u00e9fensif des Magyares (1-1, 25\u00e8me). Dans la foul\u00e9e, les Bleues ont connu un vrai temps fort avec plusieurs occasions, dont un poteau de <strong>Chlo\u00e9 Aurard-Bushee<\/strong>.<\/p>\n<p style=\"text-align: justify;\">H\u00e9las, cet \u00e9lan a \u00e9t\u00e9 stopp\u00e9 par une inf\u00e9riorit\u00e9, punie imm\u00e9diatement par un lancer \u00e0 la bleue d&rsquo;<strong>Isabel Lippai<\/strong> (1-2, 32\u00e8me). Avant le deuxi\u00e8me entracte, les Tricolores ont d&rsquo;ailleurs \u00e9t\u00e9 min\u00e9es par une nouvelle inf\u00e9riorit\u00e9 \u00e0 g\u00e9rer, prolongeant la pression exerc\u00e9e par les Hongroises. Comme un symbole de cette pression constante, elles n&rsquo;ont tir\u00e9 qu&rsquo;\u00e0 4 reprises dans le deuxi\u00e8me tiers.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"en\">Estelle Duvin opens the scoring for France at the <a href=\"https:\/\/twitter.com\/hashtag\/WomensWorlds?src=hash&amp;ref_src=twsrc%5Etfw\">#WomensWorlds<\/a> 1A! \ud83c\uddeb\ud83c\uddf7\ud83c\udfd2<a href=\"https:\/\/twitter.com\/hashtag\/IIHF?src=hash&amp;ref_src=twsrc%5Etfw\">#IIHF<\/a> <a href=\"https:\/\/twitter.com\/Hockey_FRA?ref_src=twsrc%5Etfw\">@Hockey_FRA<\/a> <a href=\"https:\/\/t.co\/vwWUaPzNH1\">pic.twitter.com\/vwWUaPzNH1<\/a><\/p>\n<p>\u2014 IIHF (@IIHFHockey) <a href=\"https:\/\/twitter.com\/IIHFHockey\/status\/2043397626737967607?ref_src=twsrc%5Etfw\">April 12, 2026<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 style=\"text-align: justify;\">Emma Kreisz crucifie les Bleues en prolongation<\/h2>\n<p style=\"text-align: justify;\">Le d\u00e9but du dernier tiers a \u00e9t\u00e9 du m\u00eame acabit. Leurs difficult\u00e9s \u00e0 ressortir le puck ont permis aux Hongroises de porter le danger fr\u00e9quemment sur la cage d&rsquo;une <strong>Alice Philbert<\/strong> (24 arr\u00eats) r\u00e9guli\u00e8rement sollicit\u00e9e. Les d\u00e9bats se sont progressivement resserr\u00e9s, et les Bleues ont retrouv\u00e9 des situations \u00e0 l&rsquo;image d&rsquo;une grosse tentative de <strong>Duvin<\/strong>, ou d&rsquo;un tir fr\u00f4lant le poteau d&rsquo;<strong>Elina Zilliox<\/strong>. Dans le m\u00eame temps, la Hongrie a eu ses opportunit\u00e9s, mais l&rsquo;indiscipline a chang\u00e9 de camp \u00e0 dix minutes de la sir\u00e8ne.<\/p>\n<p style=\"text-align: justify;\">Coup sur coup, la Hongrie s&rsquo;est mise \u00e0 la faute, offrant quatre minutes quasi cons\u00e9cutives de sup\u00e9riorit\u00e9 ! \u00c0 moins de dix minutes de la sir\u00e8ne, la situation \u00e9tait id\u00e9ale. Si les Bleues n&rsquo;ont pas frapp\u00e9 durant cette longue s\u00e9quence \u00e0 5 contre 4, le travail de sape a \u00e9t\u00e9 r\u00e9compens\u00e9 une poign\u00e9e de secondes plus tard par un lancer soyeux de <strong>Chlo\u00e9 Aurard-Bushee<\/strong> (2-2, 55\u00e8me). Les deux \u00e9quipes ont alors d\u00fb se d\u00e9partager en prolongations.<\/p>\n<p style=\"text-align: justify;\">\u00c0 3 contre 3, les Hongroises ont \u00e9t\u00e9 un cran au-dessus. Ces derni\u00e8res se sont procur\u00e9es plusieurs occasions, jusqu&rsquo;\u00e0 ce qu&rsquo;<strong>Emma Kreisz<\/strong> d\u00e9coche un lancer imparable en pleine lucarne pour plier le match. Battue <strong>3-2<\/strong>, l&rsquo;\u00e9quipe de France quitte donc ce premier match avec un seul point au compteur. D\u00e8s lundi, la victoire sera obligatoire face \u00e0 la <strong>Norv\u00e8ge<\/strong> pour ne pas d\u00e9j\u00e0 voir la 1\u00e8re place s&rsquo;envoler.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"en\">Hungary takes their first game at home in overtime! \ud83c\udded\ud83c\uddfa\ud83d\udea8 <a href=\"https:\/\/twitter.com\/hashtag\/WomensWorlds?src=hash&amp;ref_src=twsrc%5Etfw\">#WomensWorlds<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/IIHF?src=hash&amp;ref_src=twsrc%5Etfw\">#IIHF<\/a> <a href=\"https:\/\/twitter.com\/hockeyhungary?ref_src=twsrc%5Etfw\">@hockeyhungary<\/a> <a href=\"https:\/\/t.co\/aY6IvB5SLT\">pic.twitter.com\/aY6IvB5SLT<\/a><\/p>\n<p>\u2014 IIHF (@IIHFHockey) <a href=\"https:\/\/twitter.com\/IIHFHockey\/status\/2043415635787493642?ref_src=twsrc%5Etfw\">April 12, 2026<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p>&nbsp;<\/p>\n<div id=\"gtx-trans\" style=\"position: absolute; left: -14px; top: 40.9091px;\">\n<div class=\"gtx-trans-icon\"><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>MONDIAL D1 F\u00c9MININ 2026 &#8211; Crucifi\u00e9e par un lancer magistral en prolongations, l&rsquo;\u00e9quipe de France s&rsquo;est inclin\u00e9e ce dimanche face \u00e0 la Hongrie, 3-2.\u00a0<\/p>\n","protected":false},"author":55,"featured_media":662540,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[10575],"tags":[44000,16878,379,22631],"class_list":["post-662502","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-hockey-sur-glace","tag-bleues-hockey","tag-breve","tag-hongrie","tag-mondial-d1a"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Les Bleues chutent apr\u00e8s prolongation face \u00e0 la Hongrie en ouverture du Mondial D1A<\/title>\n<meta name=\"description\" content=\"MONDIAL D1 F\u00c9MININ 2026 - Crucifi\u00e9e par un lancer magistral en prolongations, l&#039;\u00e9quipe de France s&#039;est inclin\u00e9e ce dimanche face \u00e0 la Hongrie, 3-2.\u00a0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/les-bleues-chutent-apres-prolongation-face-a-la-hongrie-en-ouverture-du-mondial-d1a\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les Bleues chutent apr\u00e8s prolongation face \u00e0 la Hongrie en ouverture du Mondial D1A\" \/>\n<meta property=\"og:description\" content=\"MONDIAL D1 F\u00c9MININ 2026 - Crucifi\u00e9e par un lancer magistral en prolongations, l&#039;\u00e9quipe de France s&#039;est inclin\u00e9e ce dimanche face \u00e0 la Hongrie, 3-2.\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/les-bleues-chutent-apres-prolongation-face-a-la-hongrie-en-ouverture-du-mondial-d1a\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-12T19:48:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-12T20:21:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/04\/Les-Bleues-chutent-apres-prolongation-face-a-la-Hongrie-en-ouverture-du-Mondial-D1A.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Maxime Cazenave\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Les Bleues chutent apr\u00e8s prolongation face \u00e0 la Hongrie en ouverture du Mondial D1A\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Maxime_Caze\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/les-bleues-chutent-apres-prolongation-face-a-la-hongrie-en-ouverture-du-mondial-d1a\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/les-bleues-chutent-apres-prolongation-face-a-la-hongrie-en-ouverture-du-mondial-d1a\/\"},\"author\":{\"name\":\"Maxime Cazenave\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0\"},\"headline\":\"Les Bleues chutent apr\u00e8s prolongation face \u00e0 la Hongrie en ouverture du Mondial D1A\",\"datePublished\":\"2026-04-12T19:48:37+00:00\",\"dateModified\":\"2026-04-12T20:21:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/les-bleues-chutent-apres-prolongation-face-a-la-hongrie-en-ouverture-du-mondial-d1a\/\"},\"wordCount\":745,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/les-bleues-chutent-apres-prolongation-face-a-la-hongrie-en-ouverture-du-mondial-d1a\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/04\/Les-Bleues-chutent-apres-prolongation-face-a-la-Hongrie-en-ouverture-du-Mondial-D1A.png\",\"keywords\":[\"Bleues hockey\",\"br\u00e8ve\",\"Hongrie\",\"Mondial D1A\"],\"articleSection\":[\"Hockey sur glace\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/les-bleues-chutent-apres-prolongation-face-a-la-hongrie-en-ouverture-du-mondial-d1a\/#respond\"]}],\"copyrightYear\":\"2026\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/les-bleues-chutent-apres-prolongation-face-a-la-hongrie-en-ouverture-du-mondial-d1a\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/les-bleues-chutent-apres-prolongation-face-a-la-hongrie-en-ouverture-du-mondial-d1a\/\",\"name\":\"Les Bleues chutent apr\u00e8s prolongation face \u00e0 la Hongrie en ouverture du Mondial D1A\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/les-bleues-chutent-apres-prolongation-face-a-la-hongrie-en-ouverture-du-mondial-d1a\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/les-bleues-chutent-apres-prolongation-face-a-la-hongrie-en-ouverture-du-mondial-d1a\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/04\/Les-Bleues-chutent-apres-prolongation-face-a-la-Hongrie-en-ouverture-du-Mondial-D1A.png\",\"datePublished\":\"2026-04-12T19:48:37+00:00\",\"dateModified\":\"2026-04-12T20:21:58+00:00\",\"description\":\"MONDIAL D1 F\u00c9MININ 2026 - Crucifi\u00e9e par un lancer magistral en prolongations, l'\u00e9quipe de France s'est inclin\u00e9e ce dimanche face \u00e0 la Hongrie, 3-2.\u00a0\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/les-bleues-chutent-apres-prolongation-face-a-la-hongrie-en-ouverture-du-mondial-d1a\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/les-bleues-chutent-apres-prolongation-face-a-la-hongrie-en-ouverture-du-mondial-d1a\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/les-bleues-chutent-apres-prolongation-face-a-la-hongrie-en-ouverture-du-mondial-d1a\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/04\/Les-Bleues-chutent-apres-prolongation-face-a-la-Hongrie-en-ouverture-du-Mondial-D1A.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/04\/Les-Bleues-chutent-apres-prolongation-face-a-la-Hongrie-en-ouverture-du-Mondial-D1A.png\",\"width\":1200,\"height\":674,\"caption\":\"Les Bleues chutent apr\u00e8s prolongation face \u00e0 la Hongrie en ouverture du Mondial D1A\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/les-bleues-chutent-apres-prolongation-face-a-la-hongrie-en-ouverture-du-mondial-d1a\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les Bleues chutent apr\u00e8s prolongation face \u00e0 la Hongrie en ouverture du Mondial D1A\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0\",\"name\":\"Maxime Cazenave\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg\",\"caption\":\"Maxime Cazenave\"},\"description\":\"Journaliste\/R\u00e9dacteur depuis 2012 - Berc\u00e9 par l\u2019amour des Girondins de Bordeaux, les \u00e9checs de Christophe Moreau sur le Tour de France sous l'\u00e8re Lance Armstrong et le fade-away l\u00e9tal de Dirk Nowitzki, ma passion d\u00e9vorante pour le sport a toujours \u00e9t\u00e9 un pan incontournable de ma vie. Transmettre ma passion \u00e0 l\u2019\u00e9crit a \u00e9t\u00e9 une transition naturelle. Suiveur assidu de basket et de hockey sur glace, je garde toujours un peu de place pour suivre le cyclisme, le football et le maximum de performances fran\u00e7aises.\",\"sameAs\":[\"https:\/\/x.com\/https:\/\/twitter.com\/Maxime_Caze\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/maximec\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Les Bleues chutent apr\u00e8s prolongation face \u00e0 la Hongrie en ouverture du Mondial D1A","description":"MONDIAL D1 F\u00c9MININ 2026 - Crucifi\u00e9e par un lancer magistral en prolongations, l'\u00e9quipe de France s'est inclin\u00e9e ce dimanche face \u00e0 la Hongrie, 3-2.\u00a0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/les-bleues-chutent-apres-prolongation-face-a-la-hongrie-en-ouverture-du-mondial-d1a\/","og_locale":"fr_FR","og_type":"article","og_title":"Les Bleues chutent apr\u00e8s prolongation face \u00e0 la Hongrie en ouverture du Mondial D1A","og_description":"MONDIAL D1 F\u00c9MININ 2026 - Crucifi\u00e9e par un lancer magistral en prolongations, l'\u00e9quipe de France s'est inclin\u00e9e ce dimanche face \u00e0 la Hongrie, 3-2.\u00a0","og_url":"https:\/\/dicodusport.fr\/blog\/les-bleues-chutent-apres-prolongation-face-a-la-hongrie-en-ouverture-du-mondial-d1a\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2026-04-12T19:48:37+00:00","article_modified_time":"2026-04-12T20:21:58+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/04\/Les-Bleues-chutent-apres-prolongation-face-a-la-Hongrie-en-ouverture-du-Mondial-D1A.png","type":"image\/png"}],"author":"Maxime Cazenave","twitter_card":"summary_large_image","twitter_title":"Les Bleues chutent apr\u00e8s prolongation face \u00e0 la Hongrie en ouverture du Mondial D1A","twitter_creator":"@https:\/\/twitter.com\/Maxime_Caze","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/les-bleues-chutent-apres-prolongation-face-a-la-hongrie-en-ouverture-du-mondial-d1a\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/les-bleues-chutent-apres-prolongation-face-a-la-hongrie-en-ouverture-du-mondial-d1a\/"},"author":{"name":"Maxime Cazenave","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0"},"headline":"Les Bleues chutent apr\u00e8s prolongation face \u00e0 la Hongrie en ouverture du Mondial D1A","datePublished":"2026-04-12T19:48:37+00:00","dateModified":"2026-04-12T20:21:58+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/les-bleues-chutent-apres-prolongation-face-a-la-hongrie-en-ouverture-du-mondial-d1a\/"},"wordCount":745,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/les-bleues-chutent-apres-prolongation-face-a-la-hongrie-en-ouverture-du-mondial-d1a\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/04\/Les-Bleues-chutent-apres-prolongation-face-a-la-Hongrie-en-ouverture-du-Mondial-D1A.png","keywords":["Bleues hockey","br\u00e8ve","Hongrie","Mondial D1A"],"articleSection":["Hockey sur glace"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/les-bleues-chutent-apres-prolongation-face-a-la-hongrie-en-ouverture-du-mondial-d1a\/#respond"]}],"copyrightYear":"2026","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/les-bleues-chutent-apres-prolongation-face-a-la-hongrie-en-ouverture-du-mondial-d1a\/","url":"https:\/\/dicodusport.fr\/blog\/les-bleues-chutent-apres-prolongation-face-a-la-hongrie-en-ouverture-du-mondial-d1a\/","name":"Les Bleues chutent apr\u00e8s prolongation face \u00e0 la Hongrie en ouverture du Mondial D1A","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/les-bleues-chutent-apres-prolongation-face-a-la-hongrie-en-ouverture-du-mondial-d1a\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/les-bleues-chutent-apres-prolongation-face-a-la-hongrie-en-ouverture-du-mondial-d1a\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/04\/Les-Bleues-chutent-apres-prolongation-face-a-la-Hongrie-en-ouverture-du-Mondial-D1A.png","datePublished":"2026-04-12T19:48:37+00:00","dateModified":"2026-04-12T20:21:58+00:00","description":"MONDIAL D1 F\u00c9MININ 2026 - Crucifi\u00e9e par un lancer magistral en prolongations, l'\u00e9quipe de France s'est inclin\u00e9e ce dimanche face \u00e0 la Hongrie, 3-2.\u00a0","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/les-bleues-chutent-apres-prolongation-face-a-la-hongrie-en-ouverture-du-mondial-d1a\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/les-bleues-chutent-apres-prolongation-face-a-la-hongrie-en-ouverture-du-mondial-d1a\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/les-bleues-chutent-apres-prolongation-face-a-la-hongrie-en-ouverture-du-mondial-d1a\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/04\/Les-Bleues-chutent-apres-prolongation-face-a-la-Hongrie-en-ouverture-du-Mondial-D1A.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/04\/Les-Bleues-chutent-apres-prolongation-face-a-la-Hongrie-en-ouverture-du-Mondial-D1A.png","width":1200,"height":674,"caption":"Les Bleues chutent apr\u00e8s prolongation face \u00e0 la Hongrie en ouverture du Mondial D1A"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/les-bleues-chutent-apres-prolongation-face-a-la-hongrie-en-ouverture-du-mondial-d1a\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Les Bleues chutent apr\u00e8s prolongation face \u00e0 la Hongrie en ouverture du Mondial D1A"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0","name":"Maxime Cazenave","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg","caption":"Maxime Cazenave"},"description":"Journaliste\/R\u00e9dacteur depuis 2012 - Berc\u00e9 par l\u2019amour des Girondins de Bordeaux, les \u00e9checs de Christophe Moreau sur le Tour de France sous l'\u00e8re Lance Armstrong et le fade-away l\u00e9tal de Dirk Nowitzki, ma passion d\u00e9vorante pour le sport a toujours \u00e9t\u00e9 un pan incontournable de ma vie. Transmettre ma passion \u00e0 l\u2019\u00e9crit a \u00e9t\u00e9 une transition naturelle. Suiveur assidu de basket et de hockey sur glace, je garde toujours un peu de place pour suivre le cyclisme, le football et le maximum de performances fran\u00e7aises.","sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/Maxime_Caze"],"url":"https:\/\/dicodusport.fr\/blog\/author\/maximec\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/662502","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=662502"}],"version-history":[{"count":5,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/662502\/revisions"}],"predecessor-version":[{"id":662555,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/662502\/revisions\/662555"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/662540"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=662502"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=662502"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=662502"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}