{"id":66387,"date":"2020-05-14T14:08:22","date_gmt":"2020-05-14T12:08:22","guid":{"rendered":"http:\/\/dicodusport.fr\/blog\/?p=66387"},"modified":"2020-05-14T14:11:10","modified_gmt":"2020-05-14T12:11:10","slug":"rouge-ou-mort-roman-peace-and-love","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/rouge-ou-mort-roman-peace-and-love\/","title":{"rendered":"\u00ab\u00a0Rouge ou mort\u00a0\u00bb, le roman Peace and Love"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><strong>De Borges \u00e0 Camus, de Blondin \u00e0 Mac Orlan, litt\u00e9rature et sport se nourrissent. Premier \u00e9pisode de notre s\u00e9rie, le roman que David Peace consacre \u00e0 Bill Shankly : \u00ab\u00a0Rouge ou mort\u00a0\u00bb. <\/strong><\/em><\/p>\n<h2 style=\"text-align: justify;\">\u00ab\u00a0Envoyer l&rsquo;adjoint\u00a0\u00bb<\/h2>\n<p style=\"text-align: justify;\">Qui a d\u00e9j\u00e0 jou\u00e9 \u00e0 <strong>Football Manager<\/strong> connait cette sensation. Choisir ses entra\u00eenements &#8211; le g\u00e9n\u00e9ral et les individuels, mettre des joueurs \u00e0 disposition de la r\u00e9serve, pr\u00e9parer son mercato, se rendre \u00e0 la conf\u00e9rence de presse d&rsquo;avant-match. S&rsquo;occuper du briefing tactique, confirmer la feuille de match, choisir les consignes individuelles, faire la causerie d&rsquo;avant-match et r\u00e9pondre aux questions sur le bord du terrain. Se rendre \u00e0 la conf\u00e9rence de presse d&rsquo;avant match, f\u00e9liciter un joueur pour sa prestation.<\/p>\n<p style=\"text-align: justify;\">La r\u00e9p\u00e9tition, in\u00e9luctable, d&rsquo;un quotidien qui trouble d&rsquo;abord, enivre ensuite, finit par lasser. Cette r\u00e9p\u00e9tition a toutefois des nuances selon qu&rsquo;on d\u00e9l\u00e8gue un peu, beaucoup ou pas du tout. Pourvu qu&rsquo;on soit un tant soit peu obsessionnel, cette r\u00e9p\u00e9tition s&rsquo;aggrave et grise. <strong>Football Manager<\/strong> est certes une simulation mais, par beaucoup, elle est d&rsquo;un r\u00e9alisme troublant. Alors, quand un obsessionnel de la litt\u00e9rature \u00e9crit sur un autre obsessionnel, cette fois du football, le rab\u00e2chage est \u00e9lev\u00e9 au rang de culte sacr\u00e9.<\/p>\n<h2 style=\"text-align: justify;\">M\u00e9duse morte<\/h2>\n<p style=\"text-align: justify;\">Quand <strong>Bill Shankly<\/strong> prend la t\u00eate du <strong>Liverpool FC<\/strong> en 1959, le club rouge de la Mersey est en deuxi\u00e8me division. Il est aussi structur\u00e9 et vert\u00e9br\u00e9 qu&rsquo;une m\u00e9duse morte. Stade v\u00e9tuste, centre d&rsquo;entrainement \u00e0 l&rsquo;avenant, <strong>Liverpool<\/strong> ne se distingue pas non plus par son staff aussi comp\u00e9tent et motiv\u00e9 qu&rsquo;un charcutier \u00e0 une r\u00e9union des v\u00e9gans anonymes. Gr\u00e2ce \u00e0 son travail acharn\u00e9, sa m\u00e9ticulosit\u00e9 et son obsession pour la perfection et la victoire, <strong>Bill Shankly<\/strong> r\u00e9ussira \u00e0 faire du <strong>LFC<\/strong> le meilleur club anglais de la p\u00e9riode et parmi les meilleurs d&rsquo;Europe. En 1974, apr\u00e8s 15 ans de r\u00e8gne, <strong>Bill Shankly<\/strong> jette l&rsquo;\u00e9ponge.<\/p>\n<p style=\"text-align: justify;\">1974, c&rsquo;est une obsession pour <strong>David Peace<\/strong>. Les meurtres au c\u0153ur de sa s\u00e9rie sur le tueur de Leeds. Leeds justement o\u00f9 <strong>Brian Clough<\/strong> a tenu 44 jours, le nom du roman qu&rsquo;il a consacr\u00e9 au manager. <strong>David Peace<\/strong> semble fascin\u00e9 par cette p\u00e9riode, comme par le Premier Ministre de l&rsquo;\u00e9poque, <strong>Harold Wilson<\/strong>. Un ami de <strong>Bill Shankly<\/strong>, \u00e7a tombe bien.<\/p>\n<h2 style=\"text-align: justify;\">\u00ab\u00a0Rouge ou mort\u00a0\u00bb, syncopes, r\u00e9p\u00e9titions<\/h2>\n<p style=\"text-align: justify;\">Dans <strong>\u00ab\u00a0Rouge ou mort\u00a0\u00bb<\/strong>,<strong> David Peace<\/strong> d\u00e9ploie une \u00e9criture obs\u00e9d\u00e9e par l&rsquo;exactitude et l&rsquo;exhaustivit\u00e9. Chaque entrainement, chaque match, chaque composition. Rien ne manque. Pour les fans hardcores de <strong>Liverpool<\/strong>, <strong>\u00ab\u00a0Rouge ou mort\u00a0\u00bb<\/strong> est une mine inesp\u00e9r\u00e9e de documentation. Surtout, les r\u00e9p\u00e9titions et les syncopes du style de <strong>David Peace<\/strong> rendent parfaitement ce qu&rsquo;\u00e9tait le quotidien de <strong>Bill Shankly<\/strong>. Le livre se r\u00e9v\u00e8le une ode \u00e0 tout un peuple du Nord de l&rsquo;Angleterre.<\/p>\n<p style=\"text-align: justify;\">Le Nord de l&rsquo;Angleterre, une autre obsession de <strong>David Peace<\/strong>. <strong>Bill Shankly<\/strong> ne pouvait pas na\u00eetre plus au Nord de l&rsquo;Angleterre qu&rsquo;\u00e0 Glenbuck (\u00c9cosse). Il repr\u00e9sente ce que l&rsquo;auteur voudrait statufier. Un homme modeste qui cr\u00e9e les tactiques de ses matchs chez lui gr\u00e2ce \u00e0 des couteaux et des fourchettes et r\u00e9pond aux lettres de supporters. Un entra\u00eeneur, sympathisant travailliste, qui met le m\u00e9rit\u00e9 au-dessus de toute valeur avec la solidarit\u00e9. Un leader enfin qui croit au collectif et met sur pied une \u00e9quipe sans star qui devra vaincre par sa coh\u00e9sion. <strong>Bill Shankly<\/strong> n&rsquo;\u00e9tait lui-m\u00eame pas un entra\u00eeneur star \u00e0 la <strong>Brian Clough<\/strong> mais la partie d&rsquo;un tout. Un homme qui a fait chanter le peuple des Reds dans la d\u00e9faite et lui a rendu sa fiert\u00e9.<\/p>\n<p style=\"text-align: justify;\">En r\u00e9sum\u00e9, <strong>\u00ab\u00a0Rouge ou Mort\u00a0\u00bb<\/strong> est un grand livre sur le football d&rsquo;abord. Un football qu&rsquo;on voit \u00e9voluer, muter avec un des entra\u00eeneurs les plus mythiques de l&rsquo;histoire du jeu. <strong>\u00ab\u00a0Rouge ou Mort\u00a0\u00bb<\/strong> est ensuite un grand livre sur le Nord de l&rsquo;Angleterre des ann\u00e9es 1960-1970. Une Angleterre en crise, aux prises avec une mutation qu&rsquo;elle aborde \u00e0 reculons. Enfin, peut-\u00eatre surtout, <strong>\u00ab\u00a0Rouge ou Mort\u00a0\u00bb<\/strong> est un grand livre d&rsquo;un grand auteur au style prot\u00e9iforme et enivrant.<\/p>\n<p><strong><em>JMPPMJ<br \/>\n<a href=\"https:\/\/twitter.com\/jmp_pmj\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2908\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-twitter-150x150.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>De Borges \u00e0 Camus, de Blondin \u00e0 Mac Orlan, litt\u00e9rature et sport se nourrissent. Premier \u00e9pisode de notre s\u00e9rie, le roman que David Peace consacre \u00e0 Bill Shankly : \u00ab\u00a0Rouge ou mort\u00a0\u00bb.<\/p>\n","protected":false},"author":40,"featured_media":66769,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[2301],"tags":[75,3120],"class_list":["post-66387","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-football","tag-football","tag-liverpool"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>&quot;Rouge ou mort&quot;, le roman Peace and Love - Dicodusport<\/title>\n<meta name=\"description\" content=\"De Borges \u00e0 Camus, de Blondin \u00e0 Mac Orlan, litt\u00e9rature et sport se nourissent. Premier \u00e9pisode de notre s\u00e9rie, le roman de David Peace : &quot;Rouge ou mort&quot;.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/rouge-ou-mort-roman-peace-and-love\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;Rouge ou mort&quot; : Voil\u00e0 LE grand livre sur Liverpool\" \/>\n<meta property=\"og:description\" content=\"De Borges \u00e0 Camus, de Blondin \u00e0 Mac Orlan, litt\u00e9rature et sport se nourissent. Premier \u00e9pisode de notre s\u00e9rie, le roman de David Peace : &quot;Rouge ou mort&quot;.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/rouge-ou-mort-roman-peace-and-love\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-14T12:08:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-05-14T12:11:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/05\/Rouge-ou-mort-le-roman-Peace-and-Love.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Jordane Mougenot-Pelletier\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"&quot;Rouge ou mort&quot; : Voil\u00e0 LE grand livre sur Liverpool\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/jmp_pmj\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/rouge-ou-mort-roman-peace-and-love\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/rouge-ou-mort-roman-peace-and-love\/\"},\"author\":{\"name\":\"Jordane Mougenot-Pelletier\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/20a73cde459581e727623fffec174040\"},\"headline\":\"\u00ab\u00a0Rouge ou mort\u00a0\u00bb, le roman Peace and Love\",\"datePublished\":\"2020-05-14T12:08:22+00:00\",\"dateModified\":\"2020-05-14T12:11:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/rouge-ou-mort-roman-peace-and-love\/\"},\"wordCount\":735,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/rouge-ou-mort-roman-peace-and-love\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/05\/Rouge-ou-mort-le-roman-Peace-and-Love.png\",\"keywords\":[\"Football\",\"Liverpool\"],\"articleSection\":[\"Football\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/rouge-ou-mort-roman-peace-and-love\/#respond\"]}],\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/rouge-ou-mort-roman-peace-and-love\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/rouge-ou-mort-roman-peace-and-love\/\",\"name\":\"\\\"Rouge ou mort\\\", le roman Peace and Love - Dicodusport\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/rouge-ou-mort-roman-peace-and-love\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/rouge-ou-mort-roman-peace-and-love\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/05\/Rouge-ou-mort-le-roman-Peace-and-Love.png\",\"datePublished\":\"2020-05-14T12:08:22+00:00\",\"dateModified\":\"2020-05-14T12:11:10+00:00\",\"description\":\"De Borges \u00e0 Camus, de Blondin \u00e0 Mac Orlan, litt\u00e9rature et sport se nourissent. Premier \u00e9pisode de notre s\u00e9rie, le roman de David Peace : \\\"Rouge ou mort\\\".\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/rouge-ou-mort-roman-peace-and-love\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/rouge-ou-mort-roman-peace-and-love\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/rouge-ou-mort-roman-peace-and-love\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/05\/Rouge-ou-mort-le-roman-Peace-and-Love.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/05\/Rouge-ou-mort-le-roman-Peace-and-Love.png\",\"width\":800,\"height\":445,\"caption\":\"\\\"Rouge ou mort\\\", le roman Peace and Love\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/rouge-ou-mort-roman-peace-and-love\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00ab\u00a0Rouge ou mort\u00a0\u00bb, le roman Peace and Love\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/20a73cde459581e727623fffec174040\",\"name\":\"Jordane Mougenot-Pelletier\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Jordane-MP-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Jordane-MP-150x150.jpg\",\"caption\":\"Jordane Mougenot-Pelletier\"},\"description\":\"Journaliste\/r\u00e9dacteur depuis mai 2018 - Dans mon sang coule \u00e0 la fois le feu des penne \u00e0 l'arrabiata et la glace du Grand Colombier. Amoureux des belles lettres et des Talking Heads, je supporte un club olympique. Int\u00e9ress\u00e9 par les relations qu'entretient le sport avec la soci\u00e9t\u00e9, je m'int\u00e9resse autant \u00e0 Marc C\u00e9cillon qu'\u00e0 Pep Guardiola, \u00e0 Tonya Harding qu'\u00e0 Philipp Roth. Enfant des 90's, on ne me fera pas croire qu'il y a eu plus beau \u00e0 voir depuis Zin\u00e9dine Zidane, Marco Pantani et Pete Sampras. La b\u00e9chamel est une invention du diable, la Super Ligue aussi.\",\"sameAs\":[\"https:\/\/x.com\/https:\/\/twitter.com\/jmp_pmj\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/jordane\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\"Rouge ou mort\", le roman Peace and Love - Dicodusport","description":"De Borges \u00e0 Camus, de Blondin \u00e0 Mac Orlan, litt\u00e9rature et sport se nourissent. Premier \u00e9pisode de notre s\u00e9rie, le roman de David Peace : \"Rouge ou mort\".","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/rouge-ou-mort-roman-peace-and-love\/","og_locale":"fr_FR","og_type":"article","og_title":"\"Rouge ou mort\" : Voil\u00e0 LE grand livre sur Liverpool","og_description":"De Borges \u00e0 Camus, de Blondin \u00e0 Mac Orlan, litt\u00e9rature et sport se nourissent. Premier \u00e9pisode de notre s\u00e9rie, le roman de David Peace : \"Rouge ou mort\".","og_url":"https:\/\/dicodusport.fr\/blog\/rouge-ou-mort-roman-peace-and-love\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2020-05-14T12:08:22+00:00","article_modified_time":"2020-05-14T12:11:10+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/05\/Rouge-ou-mort-le-roman-Peace-and-Love.png","type":"image\/png"}],"author":"Jordane Mougenot-Pelletier","twitter_card":"summary_large_image","twitter_title":"\"Rouge ou mort\" : Voil\u00e0 LE grand livre sur Liverpool","twitter_creator":"@https:\/\/twitter.com\/jmp_pmj","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/rouge-ou-mort-roman-peace-and-love\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/rouge-ou-mort-roman-peace-and-love\/"},"author":{"name":"Jordane Mougenot-Pelletier","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/20a73cde459581e727623fffec174040"},"headline":"\u00ab\u00a0Rouge ou mort\u00a0\u00bb, le roman Peace and Love","datePublished":"2020-05-14T12:08:22+00:00","dateModified":"2020-05-14T12:11:10+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/rouge-ou-mort-roman-peace-and-love\/"},"wordCount":735,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/rouge-ou-mort-roman-peace-and-love\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/05\/Rouge-ou-mort-le-roman-Peace-and-Love.png","keywords":["Football","Liverpool"],"articleSection":["Football"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/rouge-ou-mort-roman-peace-and-love\/#respond"]}],"copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/rouge-ou-mort-roman-peace-and-love\/","url":"https:\/\/dicodusport.fr\/blog\/rouge-ou-mort-roman-peace-and-love\/","name":"\"Rouge ou mort\", le roman Peace and Love - Dicodusport","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/rouge-ou-mort-roman-peace-and-love\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/rouge-ou-mort-roman-peace-and-love\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/05\/Rouge-ou-mort-le-roman-Peace-and-Love.png","datePublished":"2020-05-14T12:08:22+00:00","dateModified":"2020-05-14T12:11:10+00:00","description":"De Borges \u00e0 Camus, de Blondin \u00e0 Mac Orlan, litt\u00e9rature et sport se nourissent. Premier \u00e9pisode de notre s\u00e9rie, le roman de David Peace : \"Rouge ou mort\".","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/rouge-ou-mort-roman-peace-and-love\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/rouge-ou-mort-roman-peace-and-love\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/rouge-ou-mort-roman-peace-and-love\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/05\/Rouge-ou-mort-le-roman-Peace-and-Love.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/05\/Rouge-ou-mort-le-roman-Peace-and-Love.png","width":800,"height":445,"caption":"\"Rouge ou mort\", le roman Peace and Love"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/rouge-ou-mort-roman-peace-and-love\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"\u00ab\u00a0Rouge ou mort\u00a0\u00bb, le roman Peace and Love"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/20a73cde459581e727623fffec174040","name":"Jordane Mougenot-Pelletier","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Jordane-MP-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Jordane-MP-150x150.jpg","caption":"Jordane Mougenot-Pelletier"},"description":"Journaliste\/r\u00e9dacteur depuis mai 2018 - Dans mon sang coule \u00e0 la fois le feu des penne \u00e0 l'arrabiata et la glace du Grand Colombier. Amoureux des belles lettres et des Talking Heads, je supporte un club olympique. Int\u00e9ress\u00e9 par les relations qu'entretient le sport avec la soci\u00e9t\u00e9, je m'int\u00e9resse autant \u00e0 Marc C\u00e9cillon qu'\u00e0 Pep Guardiola, \u00e0 Tonya Harding qu'\u00e0 Philipp Roth. Enfant des 90's, on ne me fera pas croire qu'il y a eu plus beau \u00e0 voir depuis Zin\u00e9dine Zidane, Marco Pantani et Pete Sampras. La b\u00e9chamel est une invention du diable, la Super Ligue aussi.","sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/jmp_pmj"],"url":"https:\/\/dicodusport.fr\/blog\/author\/jordane\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/66387","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/40"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=66387"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/66387\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/66769"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=66387"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=66387"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=66387"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}