{"id":668227,"date":"2026-05-07T09:49:43","date_gmt":"2026-05-07T07:49:43","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=668227&#038;preview=true&#038;preview_id=668227"},"modified":"2026-05-07T09:58:59","modified_gmt":"2026-05-07T07:58:59","slug":"les-chiffres-marquants-de-la-qualification-du-psg-en-finale-de-la-ligue-des-champions","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/les-chiffres-marquants-de-la-qualification-du-psg-en-finale-de-la-ligue-des-champions\/","title":{"rendered":"Les chiffres marquants de la qualification du PSG en finale de la Ligue des Champions"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>FOOTBALL &#8211; Retour en chiffres, sur la deuxi\u00e8me qualification de rang du PSG en finale de la Ligue des Champions.<\/em><\/strong><\/p>\n<ul>\n<li><strong>\u00c0 ce sujet \u2013\u00a0<a href=\"https:\/\/dicodusport.fr\/blog\/ligue-des-champions-2025-2026-phase-finale-le-tableau-complet\/\">Ligue des Champions 2025-2026 Phase finale : Le tableau complet<\/a><\/strong><\/li>\n<\/ul>\n<h2 style=\"text-align: justify;\">2<\/h2>\n<p style=\"text-align: justify;\">En se qualifiant pour la deuxi\u00e8me ann\u00e9e cons\u00e9cutive pour la finale de la Ligue des Champions, le PSG devient le tout premier club fran\u00e7ais \u00e0 r\u00e9ussir cet exploit. Une performance cependant d\u00e9j\u00e0 r\u00e9alis\u00e9e par de nombreux clubs europ\u00e9ens auparavant. Preuve aussi d&rsquo;un certain retard pris historiquement par le football fran\u00e7ais. Une performance accomplie par le <strong>Real Madrid<\/strong>, <strong>Benfica Lisbonne<\/strong>, <strong>l\u2019Inter Milan<\/strong>, <strong>l\u2019Ajax Amsterdam<\/strong>, <strong>le Bayern Munich<\/strong>, <strong>Liverpool<\/strong>, <strong>Nottingham Forest<\/strong>, <strong>l\u2019AC Milan<\/strong>, <strong>la Juventus<\/strong>, <strong>Valence<\/strong> (deux fois finaliste malheureux) et <strong>Manchester United<\/strong>.<\/p>\n<h2 style=\"text-align: justify;\">2<\/h2>\n<p style=\"text-align: justify;\">Pour la deuxi\u00e8me fois de l&rsquo;histoire de la Ligue des Champions, la France aura un repr\u00e9sentant en finale des comp\u00e9titions masculine et f\u00e9minine. Comme en 2020, le PSG (chez les hommes) et l&rsquo;OL Lyonnes sont qualifi\u00e9s. En 2020, les Lyonnaises avaient remport\u00e9 la comp\u00e9tition, mais le PSG avait \u00e9chou\u00e9 en finale.<\/p>\n<p style=\"text-align: justify;\">Cette saison peut accoucher d&rsquo;une premi\u00e8re historique pour le football fran\u00e7ais. Si le RC Strasbourg se qualifie en finale de la Ligue Europa Conf\u00e9rence, la France pourrait avoir trois repr\u00e9sentants en finale europ\u00e9enne. Ce serait \u00e9galement une premi\u00e8re historique pour le football fran\u00e7ais.<\/p>\n<div class=\"vlp-link-container vlp-layout-article\"><a href=\"https:\/\/dicodusport.fr\/blog\/lol-lyonnes-rend-la-monnaie-a-arsenal-et-file-en-finale-de-la-ligue-des-champions\/\" class=\"vlp-link\" title=\"L\u2019OL Lyonnes rend la monnaie \u00e0 Arsenal et file en finale de la Ligue des Champions\"><\/a><div class=\"vlp-layout-zone-side\"><div class=\"vlp-block-4 vlp-link-image\"><img loading=\"lazy\" decoding=\"async\" style=\"max-width: 792px;\" width=\"792\" height=\"445\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/05\/LOL-Lyonnes-rend-la-monnaie-a-Arsenal-et-file-en-finale-de-la-Ligue-des-Champions.png\" class=\"attachment-800x445 size-800x445\" alt=\"L\u2019OL Lyonnes rend la monnaie \u00e0 Arsenal et file en finale de la Ligue des Champions\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/05\/LOL-Lyonnes-rend-la-monnaie-a-Arsenal-et-file-en-finale-de-la-Ligue-des-Champions.png 1200w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/05\/LOL-Lyonnes-rend-la-monnaie-a-Arsenal-et-file-en-finale-de-la-Ligue-des-Champions-300x169.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/05\/LOL-Lyonnes-rend-la-monnaie-a-Arsenal-et-file-en-finale-de-la-Ligue-des-Champions-1024x575.png 1024w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/05\/LOL-Lyonnes-rend-la-monnaie-a-Arsenal-et-file-en-finale-de-la-Ligue-des-Champions-768x431.png 768w\" sizes=\"auto, (max-width: 792px) 100vw, 792px\" \/><\/div><\/div><div class=\"vlp-layout-zone-main\"><div class=\"vlp-block-0 vlp-link-title\">L\u2019OL Lyonnes rend la monnaie \u00e0 Arsenal et file en finale de la Ligue des Champions<\/div><div class=\"vlp-block-1 vlp-link-summary\">Gr\u00e2ce \u00e0 un but de Jule Brand \u00e0 la fin du temps r\u00e9glementaire, l\u2019OL Lyonnes renverse Arsenal avec un succ\u00e8s 3-1 et rejoint pour la 12\u00e8me fois de son histoire la finale de la comp\u00e9tition europ\u00e9enne (4-3 cumul\u00e9).<\/div><div class=\"vlp-block-2 vlp-link-button\">Lire l'article<\/div><div class=\"vlp-block-3 vlp-link-url\">dicodusport.fr<\/div><\/div><\/div>\n<h2 style=\"text-align: justify;\">2.8<\/h2>\n<p style=\"text-align: justify;\">Comme le nombre de buts inscrits par match de Ligue des Champions par le PSG. Deuxi\u00e8me du classement derri\u00e8re le Bayern Munich (3.1). Le PSG reste \u00e9galement toujours prompt \u00e0 bien faire circuler le ballon. Les Parisiens sont aussi 2es sur le nombre de passes par match (612.9) ainsi qu&rsquo;en passes cl\u00e9s (13.2).<\/p>\n<h2 style=\"text-align: justify;\">3<\/h2>\n<p style=\"text-align: justify;\">Avec sa qualification en finale, le PSG est d\u00e9sormais 3e au classement UEFA des cinq derni\u00e8res saisons et double <strong>Liverpool<\/strong>, avec 131 points. Seuls le <strong>Bayern Munich<\/strong> (147 points) et le <strong>Real Madrid<\/strong> (144.5 points) devancent les Parisiens.<\/p>\n<p style=\"text-align: justify;\">\u00c0 noter qu&rsquo;avec 36.5 points, le PSG a d\u00e9j\u00e0 inscrit trois points de plus que la saison pass\u00e9e. Il est le club europ\u00e9en qui a marqu\u00e9 le plus de points sur les deux derni\u00e8res saisons.<\/p>\n<h2 style=\"text-align: justify;\">4<\/h2>\n<p style=\"text-align: justify;\">Toutes comp\u00e9titions confondues, ce n&rsquo;est que la 4e fois cette saison que le Bayern Munich ne s&rsquo;impose pas \u00e0 domicile. La deuxi\u00e8me fois de rang, apr\u00e8s son nul 3-3 contre Heidenheim en championnat.<\/p>\n<h2 style=\"text-align: justify;\">6<\/h2>\n<p style=\"text-align: justify;\">La finale de la Ligue des Champions sera la 6e confrontation officielle entre le PSG et Arsenal. Le bilan est l\u00e9g\u00e8rement favorable aux Parisiens, avec deux victoires, deux nuls et une d\u00e9faite. Les deux victoires ont \u00e9t\u00e9 obtenues la saison derni\u00e8re, lors de la demi-finale aller (1-0) et retour (2-1) de la Ligue des Champions, sur la route du premier sacre parisien. C&rsquo;est la 4e fois en 18 mois que les deux clubs se rencontrent.<\/p>\n<h2 style=\"text-align: justify;\">6<\/h2>\n<p style=\"text-align: justify;\">Le PSG reste sur six qualifications cons\u00e9cutives en Ligue des Champions contre des clubs anglais avant de retrouver Arsenal en finale. La derni\u00e8re \u00e9limination remonte \u00e0 la saison 2020-2021 en demi-finale de la comp\u00e9tition. Le parcours des Parisiens avait alors \u00e9t\u00e9 stopp\u00e9 par Manchester City.<\/p>\n<h2 style=\"text-align: justify;\">10<\/h2>\n<p style=\"text-align: justify;\">Comme le nombre de buts marqu\u00e9s par le G\u00e9orgien <strong>Khvicha Kvaratskhelia<\/strong>, meilleur buteur du PSG dans cette Ligue des Champions et 4e meilleur buteur de la comp\u00e9tition. Avec <strong>Achraf Hakimi<\/strong> et le Bavarois <strong>Micha\u00ebl Olise<\/strong>, ils sont \u00e9galement en t\u00eate du classement des passeurs d\u00e9cisifs, avec chacun six offrandes d\u00e9livr\u00e9es. Ce qui fait de \u00ab\u00a0Kvara\u00a0\u00bb le joueur le plus d\u00e9cisif de la comp\u00e9tition.<\/p>\n<h2 style=\"text-align: justify;\">60 %<\/h2>\n<p style=\"text-align: justify;\">En cinq demi-finales de Ligue des Champions, le PSG s&rsquo;est qualifi\u00e9 \u00e0 trois reprises pour la finale de la comp\u00e9tition. Lors des saisons 2019-2020, 2024-2025 et 2025-2026.<\/p>\n<h2 style=\"text-align: justify;\">108.5<\/h2>\n<p style=\"text-align: justify;\">Plaque tournante du PSG, <strong>Vitinha<\/strong> touche en moyenne 108.5 ballons par match depuis le d\u00e9but de la comp\u00e9tition. C&rsquo;est le deuxi\u00e8me total le plus \u00e9lev\u00e9 d&rsquo;un joueur dans cette Ligue des Champions. Mais le Portugais a beaucoup moins touch\u00e9 le ballon ce mercredi soir (45 ballons).<\/p>\n<h3>\u00c0 ce sujet<\/h3>\n<div class=\"vlp-link-container vlp-layout-article\"><a href=\"https:\/\/dicodusport.fr\/blog\/le-psg-retourne-en-finale-de-la-ligue-des-champions-apres-une-grande-bataille-contre-le-bayern\/\" class=\"vlp-link\" title=\"Le PSG retourne en finale de la Ligue des Champions apr\u00e8s une grande bataille contre le Bayern\"><\/a><div class=\"vlp-layout-zone-side\"><div class=\"vlp-block-4 vlp-link-image\"><img loading=\"lazy\" decoding=\"async\" style=\"max-width: 792px;\" width=\"792\" height=\"445\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/05\/Le-PSG-retourne-en-finale-de-la-Ligue-des-Champions-apres-une-grande-bataille-contre-le-Bayern.png\" class=\"attachment-800x445 size-800x445\" alt=\"Le PSG retourne en finale de la Ligue des Champions apr\u00e8s une grande bataille contre le Bayern\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/05\/Le-PSG-retourne-en-finale-de-la-Ligue-des-Champions-apres-une-grande-bataille-contre-le-Bayern.png 1200w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/05\/Le-PSG-retourne-en-finale-de-la-Ligue-des-Champions-apres-une-grande-bataille-contre-le-Bayern-300x169.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/05\/Le-PSG-retourne-en-finale-de-la-Ligue-des-Champions-apres-une-grande-bataille-contre-le-Bayern-1024x575.png 1024w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/05\/Le-PSG-retourne-en-finale-de-la-Ligue-des-Champions-apres-une-grande-bataille-contre-le-Bayern-768x431.png 768w\" sizes=\"auto, (max-width: 792px) 100vw, 792px\" \/><\/div><\/div><div class=\"vlp-layout-zone-main\"><div class=\"vlp-block-0 vlp-link-title\">Le PSG retourne en finale de la Ligue des Champions apr\u00e8s une grande bataille contre le Bayern<\/div><div class=\"vlp-block-1 vlp-link-summary\">LIGUE DES CHAMPIONS 2025-2026 \u2013 Avec un match nul 1-1 sur la pelouse du Bayern Munich, le PSG valide son billet pour la finale \u00e0 Budapest gr\u00e2ce \u00e0 son avance du match aller (6-5 en cumul\u00e9).<\/div><div class=\"vlp-block-2 vlp-link-button\">Lire l'article<\/div><div class=\"vlp-block-3 vlp-link-url\">dicodusport.fr<\/div><\/div><\/div>\n<div id=\"gtx-trans\" style=\"position: absolute; left: -14px; top: 40.9091px;\">\n<div class=\"gtx-trans-icon\"><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Retour en chiffres, sur la deuxi\u00e8me qualification de rang du PSG en finale de la Ligue des Champions.<\/p>\n","protected":false},"author":83,"featured_media":668231,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[47250],"tags":[32415,16878,74,75,419,1230,910],"class_list":["post-668227","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ligue-des-champions-de-football","tag-actu","tag-breve","tag-foot","tag-football","tag-ligue-des-champions","tag-paris-saint-germain","tag-psg"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Les chiffres marquants de la qualification du PSG en finale de la Ligue des Champions<\/title>\n<meta name=\"description\" content=\"Retour en chiffres, sur la deuxi\u00e8me qualification de rang du PSG en finale de la Ligue des Champions.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/les-chiffres-marquants-de-la-qualification-du-psg-en-finale-de-la-ligue-des-champions\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les chiffres marquants de la qualification du PSG en finale de la Ligue des Champions\" \/>\n<meta property=\"og:description\" content=\"Retour en chiffres, sur la deuxi\u00e8me qualification de rang du PSG en finale de la Ligue des Champions.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/les-chiffres-marquants-de-la-qualification-du-psg-en-finale-de-la-ligue-des-champions\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-07T07:49:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-07T07:58:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/05\/La-qualification-du-PSG-en-finale-de-la-Ligue-des-Champions-en-chiffres.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"680\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Etienne Goursaud\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Les chiffres marquants de la qualification du PSG en finale de la Ligue des Champions\" \/>\n<meta name=\"twitter:creator\" content=\"@dicodusport\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/les-chiffres-marquants-de-la-qualification-du-psg-en-finale-de-la-ligue-des-champions\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/les-chiffres-marquants-de-la-qualification-du-psg-en-finale-de-la-ligue-des-champions\/\"},\"author\":{\"name\":\"Etienne Goursaud\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/d603dd7da31fb2b46c82b9835a77ec13\"},\"headline\":\"Les chiffres marquants de la qualification du PSG en finale de la Ligue des Champions\",\"datePublished\":\"2026-05-07T07:49:43+00:00\",\"dateModified\":\"2026-05-07T07:58:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/les-chiffres-marquants-de-la-qualification-du-psg-en-finale-de-la-ligue-des-champions\/\"},\"wordCount\":878,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/les-chiffres-marquants-de-la-qualification-du-psg-en-finale-de-la-ligue-des-champions\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/05\/La-qualification-du-PSG-en-finale-de-la-Ligue-des-Champions-en-chiffres.png\",\"keywords\":[\"actu\",\"br\u00e8ve\",\"foot\",\"Football\",\"Ligue des champions\",\"Paris Saint-Germain\",\"PSG\"],\"articleSection\":[\"Ligue des Champions de football\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/les-chiffres-marquants-de-la-qualification-du-psg-en-finale-de-la-ligue-des-champions\/#respond\"]}],\"copyrightYear\":\"2026\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/les-chiffres-marquants-de-la-qualification-du-psg-en-finale-de-la-ligue-des-champions\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/les-chiffres-marquants-de-la-qualification-du-psg-en-finale-de-la-ligue-des-champions\/\",\"name\":\"Les chiffres marquants de la qualification du PSG en finale de la Ligue des Champions\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/les-chiffres-marquants-de-la-qualification-du-psg-en-finale-de-la-ligue-des-champions\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/les-chiffres-marquants-de-la-qualification-du-psg-en-finale-de-la-ligue-des-champions\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/05\/La-qualification-du-PSG-en-finale-de-la-Ligue-des-Champions-en-chiffres.png\",\"datePublished\":\"2026-05-07T07:49:43+00:00\",\"dateModified\":\"2026-05-07T07:58:59+00:00\",\"description\":\"Retour en chiffres, sur la deuxi\u00e8me qualification de rang du PSG en finale de la Ligue des Champions.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/les-chiffres-marquants-de-la-qualification-du-psg-en-finale-de-la-ligue-des-champions\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/les-chiffres-marquants-de-la-qualification-du-psg-en-finale-de-la-ligue-des-champions\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/les-chiffres-marquants-de-la-qualification-du-psg-en-finale-de-la-ligue-des-champions\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/05\/La-qualification-du-PSG-en-finale-de-la-Ligue-des-Champions-en-chiffres.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/05\/La-qualification-du-PSG-en-finale-de-la-Ligue-des-Champions-en-chiffres.png\",\"width\":1200,\"height\":680,\"caption\":\"La qualification du PSG en finale de la Ligue des Champions en chiffres\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/les-chiffres-marquants-de-la-qualification-du-psg-en-finale-de-la-ligue-des-champions\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les chiffres marquants de la qualification du PSG en finale de la Ligue des Champions\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/d603dd7da31fb2b46c82b9835a77ec13\",\"name\":\"Etienne Goursaud\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/410122264_10231602061736049_5565839791558026645_n-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/410122264_10231602061736049_5565839791558026645_n-150x150.jpg\",\"caption\":\"Etienne Goursaud\"},\"description\":\"Journaliste et amoureux de sport. Ancien footballeur reconverti athl\u00e8te quand ses muscles le laissent tranquille. \u00c9lev\u00e9 \u00e0 la sauce des exploits de Thomas Voeckler en 2004, du dernier essai de l\u00e9gende de Eunice Barber \u00e0 la longueur lors des championnats du monde d'athl\u00e9tisme de 2003 mais aussi Zidane, Omeyer et Titou Lamaison.\",\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/etienne-goursaud\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Les chiffres marquants de la qualification du PSG en finale de la Ligue des Champions","description":"Retour en chiffres, sur la deuxi\u00e8me qualification de rang du PSG en finale de la Ligue des Champions.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/les-chiffres-marquants-de-la-qualification-du-psg-en-finale-de-la-ligue-des-champions\/","og_locale":"fr_FR","og_type":"article","og_title":"Les chiffres marquants de la qualification du PSG en finale de la Ligue des Champions","og_description":"Retour en chiffres, sur la deuxi\u00e8me qualification de rang du PSG en finale de la Ligue des Champions.","og_url":"https:\/\/dicodusport.fr\/blog\/les-chiffres-marquants-de-la-qualification-du-psg-en-finale-de-la-ligue-des-champions\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2026-05-07T07:49:43+00:00","article_modified_time":"2026-05-07T07:58:59+00:00","og_image":[{"width":1200,"height":680,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/05\/La-qualification-du-PSG-en-finale-de-la-Ligue-des-Champions-en-chiffres.png","type":"image\/png"}],"author":"Etienne Goursaud","twitter_card":"summary_large_image","twitter_title":"Les chiffres marquants de la qualification du PSG en finale de la Ligue des Champions","twitter_creator":"@dicodusport","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/les-chiffres-marquants-de-la-qualification-du-psg-en-finale-de-la-ligue-des-champions\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/les-chiffres-marquants-de-la-qualification-du-psg-en-finale-de-la-ligue-des-champions\/"},"author":{"name":"Etienne Goursaud","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/d603dd7da31fb2b46c82b9835a77ec13"},"headline":"Les chiffres marquants de la qualification du PSG en finale de la Ligue des Champions","datePublished":"2026-05-07T07:49:43+00:00","dateModified":"2026-05-07T07:58:59+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/les-chiffres-marquants-de-la-qualification-du-psg-en-finale-de-la-ligue-des-champions\/"},"wordCount":878,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/les-chiffres-marquants-de-la-qualification-du-psg-en-finale-de-la-ligue-des-champions\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/05\/La-qualification-du-PSG-en-finale-de-la-Ligue-des-Champions-en-chiffres.png","keywords":["actu","br\u00e8ve","foot","Football","Ligue des champions","Paris Saint-Germain","PSG"],"articleSection":["Ligue des Champions de football"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/les-chiffres-marquants-de-la-qualification-du-psg-en-finale-de-la-ligue-des-champions\/#respond"]}],"copyrightYear":"2026","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/les-chiffres-marquants-de-la-qualification-du-psg-en-finale-de-la-ligue-des-champions\/","url":"https:\/\/dicodusport.fr\/blog\/les-chiffres-marquants-de-la-qualification-du-psg-en-finale-de-la-ligue-des-champions\/","name":"Les chiffres marquants de la qualification du PSG en finale de la Ligue des Champions","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/les-chiffres-marquants-de-la-qualification-du-psg-en-finale-de-la-ligue-des-champions\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/les-chiffres-marquants-de-la-qualification-du-psg-en-finale-de-la-ligue-des-champions\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/05\/La-qualification-du-PSG-en-finale-de-la-Ligue-des-Champions-en-chiffres.png","datePublished":"2026-05-07T07:49:43+00:00","dateModified":"2026-05-07T07:58:59+00:00","description":"Retour en chiffres, sur la deuxi\u00e8me qualification de rang du PSG en finale de la Ligue des Champions.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/les-chiffres-marquants-de-la-qualification-du-psg-en-finale-de-la-ligue-des-champions\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/les-chiffres-marquants-de-la-qualification-du-psg-en-finale-de-la-ligue-des-champions\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/les-chiffres-marquants-de-la-qualification-du-psg-en-finale-de-la-ligue-des-champions\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/05\/La-qualification-du-PSG-en-finale-de-la-Ligue-des-Champions-en-chiffres.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/05\/La-qualification-du-PSG-en-finale-de-la-Ligue-des-Champions-en-chiffres.png","width":1200,"height":680,"caption":"La qualification du PSG en finale de la Ligue des Champions en chiffres"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/les-chiffres-marquants-de-la-qualification-du-psg-en-finale-de-la-ligue-des-champions\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Les chiffres marquants de la qualification du PSG en finale de la Ligue des Champions"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/d603dd7da31fb2b46c82b9835a77ec13","name":"Etienne Goursaud","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/410122264_10231602061736049_5565839791558026645_n-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/410122264_10231602061736049_5565839791558026645_n-150x150.jpg","caption":"Etienne Goursaud"},"description":"Journaliste et amoureux de sport. Ancien footballeur reconverti athl\u00e8te quand ses muscles le laissent tranquille. \u00c9lev\u00e9 \u00e0 la sauce des exploits de Thomas Voeckler en 2004, du dernier essai de l\u00e9gende de Eunice Barber \u00e0 la longueur lors des championnats du monde d'athl\u00e9tisme de 2003 mais aussi Zidane, Omeyer et Titou Lamaison.","url":"https:\/\/dicodusport.fr\/blog\/author\/etienne-goursaud\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/668227","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/83"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=668227"}],"version-history":[{"count":4,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/668227\/revisions"}],"predecessor-version":[{"id":668240,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/668227\/revisions\/668240"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/668231"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=668227"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=668227"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=668227"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}