{"id":668358,"date":"2026-05-07T22:53:30","date_gmt":"2026-05-07T20:53:30","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=668358&#038;preview=true&#038;preview_id=668358"},"modified":"2026-05-07T22:58:19","modified_gmt":"2026-05-07T20:58:19","slug":"provence-rugby-efface-un-deficit-de-24-points-pour-scalper-vannes-leader-de-pro-d2","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/provence-rugby-efface-un-deficit-de-24-points-pour-scalper-vannes-leader-de-pro-d2\/","title":{"rendered":"Provence Rugby efface un d\u00e9ficit de 24 points pour scalper Vannes, leader de Pro D2"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>PRO D2 2025-2026 &#8211; Men\u00e9 de 24 points \u00e0 la pause, Provence Rugby a renvers\u00e9 la partie de mani\u00e8re spectaculaire pour s&rsquo;imposer face au leader Vannes, 34-24.<\/em><\/strong><\/p>\n<ul>\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet \u2013\u00a0<a href=\"https:\/\/dicodusport.fr\/blog\/classement-actualise-pro-d2-saison-2025-2026\/\">Le classement actualis\u00e9 de la Pro D2 (saison 2025-2026)<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">La 29\u00e8me et avant-derni\u00e8re journ\u00e9e de <strong>Pro D2<\/strong> d\u00e9butait par un match au sommet ce jeudi soir. 3\u00e8me et \u00e0 la lutte pour une place directe en demi-finale d&rsquo;accession, <strong>Provence Rugby<\/strong> accueillait le solide leader, <strong>Vannes<\/strong>. D\u00e9j\u00e0 assur\u00e9s de conserver leur place, les Bretons ne venaient pas en Provence pour faire de la figuration, mais bien pour pr\u00e9parer les barrages \u00e0 venir.<\/p>\n<h2 style=\"text-align: justify;\">En contr\u00f4le, Vannes ma\u00eetrise le premier acte<\/h2>\n<p style=\"text-align: justify;\">Les Vannetais l&rsquo;ont prouv\u00e9 imm\u00e9diatement en proposant une d\u00e9fense solide pour repousser <strong>Paul Cellio Zwiler<\/strong> en touche \u00e0 cinq m\u00e8tres de l&rsquo;en-but. De quoi lancer 20 premi\u00e8res minutes parfaitement ma\u00eetris\u00e9es face \u00e0 des Proven\u00e7aux maladroits et en grande difficult\u00e9 pour trouver de l&rsquo;avanc\u00e9e.<\/p>\n<p style=\"text-align: justify;\">D\u00e8s leur premier v\u00e9ritable lancement de jeu, les Bretons ont ainsi frapp\u00e9. Gr\u00e2ce \u00e0 une magnifique feinte de <strong>Thibaut Debaes<\/strong>, qui a d\u00e9chir\u00e9 le rideau d\u00e9fensif avant de d\u00e9livrer un caviar \u00e0 <strong>Eliott Roudil<\/strong> (0-7, 9\u00e8me). Puis, \u00e0 la suite d&rsquo;une m\u00eal\u00e9e \u00e0 cinq m\u00e8tres, deux passes ont suffi pour trouver <strong>Paul Surano<\/strong> en bord de touche (0-14, 20\u00e8me).<\/p>\n<p style=\"text-align: justify;\">S\u2019en sont alors suivies de longues minutes de possession st\u00e9rile en faveur des locaux, jusqu&rsquo;\u00e0 ce qu&rsquo;un turn-over m\u00e8ne \u00e0 un essai d&rsquo;<strong>Arthur Coville<\/strong>. H\u00e9las, la vid\u00e9o s&rsquo;en est m\u00eal\u00e9e et a annul\u00e9 l&rsquo;essai pour un contact \u00e0 la t\u00eate dans le camp proven\u00e7al, offrant une p\u00e9nalit\u00e9 aux Vannetais. R\u00e9sultat, le score est pass\u00e9 de 7-14 \u00e0 <strong>0-17<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Sonn\u00e9s, les Aixois ont m\u00eame pris l&rsquo;eau avant la pause sur un coup de filou de <strong>Santiago Medrano<\/strong>, qui a aplati sur la ligne un ballon \u00e9chapp\u00e9 des mains de Coville (0-24, 40\u00e8me) !<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">La vitesse de Surano, le timing de Roudil et la ruse de Medrano permettent au <a href=\"https:\/\/twitter.com\/RugbyClubVannes?ref_src=twsrc%5Etfw\">@RugbyClubVannes<\/a> de disposer d&rsquo;une confortable avance \u00e0 la pause \u23f1\ufe0f<a href=\"https:\/\/twitter.com\/hashtag\/PROD2?src=hash&amp;ref_src=twsrc%5Etfw\">#PROD2<\/a> <a href=\"https:\/\/t.co\/Uu3aoExgsp\">pic.twitter.com\/Uu3aoExgsp<\/a><\/p>\n<p>\u2014 Rugby PRO D2 (@rugbyprod2) <a href=\"https:\/\/twitter.com\/rugbyprod2\/status\/2052475967851888729?ref_src=twsrc%5Etfw\">May 7, 2026<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2>Vannes s&rsquo;\u00e9croule, Provence renverse tout<\/h2>\n<p style=\"text-align: justify;\">Une fois de retour sur le pr\u00e9, Provence a monopolis\u00e9 la gonfle, sans pour autant parvenir \u00e0 d\u00e9sorganiser imm\u00e9diatement la d\u00e9fense vannetaise. Finalement, c&rsquo;est sur une offensive d\u00e9brid\u00e9e et pleine de r\u00e9ussite, \u00e0 l&rsquo;image d&rsquo;une reprise de vol\u00e9e d\u00e9cisive de <strong>Vareiro<\/strong>, qu&rsquo;<strong>Adrien Lap\u00e8gue-Lafaye<\/strong> a pu d\u00e9bloquer le compteur aixois (7-24, 50\u00e8me).<\/p>\n<p style=\"text-align: justify;\">Puis, alors que le RCV avait repouss\u00e9 la pression pour recentrer le jeu au c\u0153ur du terrain, Lap\u00e8gue-Lafaye a de nouveau frapp\u00e9 apr\u00e8s une perc\u00e9e brutale de <strong>Setareki Bituniyata<\/strong> (14-24, 59\u00e8me).<\/p>\n<p style=\"text-align: justify;\">Sentant le vent tourner, les Aixois ont accentu\u00e9 leurs intentions en pilonnant une d\u00e9fense vannetaise devenue bien plus f\u00e9brile. Et ce sont les avants qui ont confirm\u00e9 ce renversement total de physionomie. <strong>Romain Latterrade<\/strong> a d&rsquo;abord r\u00e9compens\u00e9 une longue s\u00e9quence de domination au pr\u00e8s (21-24, 65\u00e8me), avant de se charger lui-m\u00eame de renverser le score sur un ballon port\u00e9 gagnant (28-24, 71\u00e8me) !<\/p>\n<p style=\"text-align: justify;\">Simple sparring-partner et totalement d\u00e9pass\u00e9 dans ce deuxi\u00e8me acte, le RCV ne r\u00e9agira jamais. Except\u00e9 \u00e0 la sir\u00e8ne par l&rsquo;interm\u00e9diaire de <strong>Paul Boudehent<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Mais entre-temps, <strong>Manuel Vareiro<\/strong> s&rsquo;\u00e9tait charg\u00e9 de plier l&rsquo;affaire en passant deux p\u00e9nalit\u00e9s. Men\u00e9 24-0 \u00e0 la pause, Provence Rugby a ainsi coll\u00e9 un cinglant <strong>34-7 au leader dans le deuxi\u00e8me acte<\/strong> pour finalement s&rsquo;imposer <strong>34-24<\/strong> ! Une victoire renversante qui permet aux Aixois de s&#8217;emparer de la 2\u00e8me place et de mettre la pression sur Colomiers.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">76&prime; : PRO 34 &#8211; 24 VAN. Vareiro de plus de 50 m\u00e8tres&#8230; encore ! La folie !<\/p>\n<p>\u2014 Provence Rugby \u26ab\ufe0f\ud83c\udfc9 (@ProvenceRugby) <a href=\"https:\/\/twitter.com\/ProvenceRugby\/status\/2052490199049941488?ref_src=twsrc%5Etfw\">May 7, 2026<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>PRO D2 2025-2026 &#8211; Men\u00e9 de 24 points \u00e0 la pause, Provence Rugby a renvers\u00e9 la partie de mani\u00e8re spectaculaire pour s&rsquo;imposer face au leader Vannes, 34-24.<\/p>\n","protected":false},"author":55,"featured_media":668396,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[47052],"tags":[16878,1839,10237,10224],"class_list":["post-668358","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-pro-d2","tag-breve","tag-pro-d2","tag-provence-rugby","tag-rc-vannes"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Provence Rugby efface un d\u00e9ficit de 24 points pour scalper Vannes, leader de Pro D2<\/title>\n<meta name=\"description\" content=\"PRO D2 2025-2026 - Men\u00e9 de 24 points \u00e0 la pause, Provence Rugby a renvers\u00e9 la partie de mani\u00e8re spectaculaire pour s&#039;imposer face au leader Vannes, 34-24.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/provence-rugby-efface-un-deficit-de-24-points-pour-scalper-vannes-leader-de-pro-d2\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Provence Rugby efface un d\u00e9ficit de 24 points pour scalper Vannes, leader de Pro D2\" \/>\n<meta property=\"og:description\" content=\"PRO D2 2025-2026 - Men\u00e9 de 24 points \u00e0 la pause, Provence Rugby a renvers\u00e9 la partie de mani\u00e8re spectaculaire pour s&#039;imposer face au leader Vannes, 34-24.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/provence-rugby-efface-un-deficit-de-24-points-pour-scalper-vannes-leader-de-pro-d2\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-07T20:53:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-07T20:58:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/05\/Provence-Rugby-efface-un-deficit-de-24-points-pour-scalper-Vannes-leader-de-Pro-D2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Maxime Cazenave\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Provence Rugby efface un d\u00e9ficit de 24 points pour scalper Vannes, leader de Pro D2\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Maxime_Caze\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/provence-rugby-efface-un-deficit-de-24-points-pour-scalper-vannes-leader-de-pro-d2\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/provence-rugby-efface-un-deficit-de-24-points-pour-scalper-vannes-leader-de-pro-d2\/\"},\"author\":{\"name\":\"Maxime Cazenave\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0\"},\"headline\":\"Provence Rugby efface un d\u00e9ficit de 24 points pour scalper Vannes, leader de Pro D2\",\"datePublished\":\"2026-05-07T20:53:30+00:00\",\"dateModified\":\"2026-05-07T20:58:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/provence-rugby-efface-un-deficit-de-24-points-pour-scalper-vannes-leader-de-pro-d2\/\"},\"wordCount\":665,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/provence-rugby-efface-un-deficit-de-24-points-pour-scalper-vannes-leader-de-pro-d2\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/05\/Provence-Rugby-efface-un-deficit-de-24-points-pour-scalper-Vannes-leader-de-Pro-D2.png\",\"keywords\":[\"br\u00e8ve\",\"Pro D2\",\"Provence Rugby\",\"RC Vannes\"],\"articleSection\":[\"Pro D2\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/provence-rugby-efface-un-deficit-de-24-points-pour-scalper-vannes-leader-de-pro-d2\/#respond\"]}],\"copyrightYear\":\"2026\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/provence-rugby-efface-un-deficit-de-24-points-pour-scalper-vannes-leader-de-pro-d2\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/provence-rugby-efface-un-deficit-de-24-points-pour-scalper-vannes-leader-de-pro-d2\/\",\"name\":\"Provence Rugby efface un d\u00e9ficit de 24 points pour scalper Vannes, leader de Pro D2\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/provence-rugby-efface-un-deficit-de-24-points-pour-scalper-vannes-leader-de-pro-d2\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/provence-rugby-efface-un-deficit-de-24-points-pour-scalper-vannes-leader-de-pro-d2\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/05\/Provence-Rugby-efface-un-deficit-de-24-points-pour-scalper-Vannes-leader-de-Pro-D2.png\",\"datePublished\":\"2026-05-07T20:53:30+00:00\",\"dateModified\":\"2026-05-07T20:58:19+00:00\",\"description\":\"PRO D2 2025-2026 - Men\u00e9 de 24 points \u00e0 la pause, Provence Rugby a renvers\u00e9 la partie de mani\u00e8re spectaculaire pour s'imposer face au leader Vannes, 34-24.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/provence-rugby-efface-un-deficit-de-24-points-pour-scalper-vannes-leader-de-pro-d2\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/provence-rugby-efface-un-deficit-de-24-points-pour-scalper-vannes-leader-de-pro-d2\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/provence-rugby-efface-un-deficit-de-24-points-pour-scalper-vannes-leader-de-pro-d2\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/05\/Provence-Rugby-efface-un-deficit-de-24-points-pour-scalper-Vannes-leader-de-Pro-D2.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/05\/Provence-Rugby-efface-un-deficit-de-24-points-pour-scalper-Vannes-leader-de-Pro-D2.png\",\"width\":1200,\"height\":674,\"caption\":\"Provence Rugby efface un d\u00e9ficit de 24 points pour scalper Vannes, leader de Pro D2\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/provence-rugby-efface-un-deficit-de-24-points-pour-scalper-vannes-leader-de-pro-d2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Provence Rugby efface un d\u00e9ficit de 24 points pour scalper Vannes, leader de Pro D2\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0\",\"name\":\"Maxime Cazenave\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg\",\"caption\":\"Maxime Cazenave\"},\"description\":\"Journaliste\/R\u00e9dacteur depuis 2012 - Berc\u00e9 par l\u2019amour des Girondins de Bordeaux, les \u00e9checs de Christophe Moreau sur le Tour de France sous l'\u00e8re Lance Armstrong et le fade-away l\u00e9tal de Dirk Nowitzki, ma passion d\u00e9vorante pour le sport a toujours \u00e9t\u00e9 un pan incontournable de ma vie. Transmettre ma passion \u00e0 l\u2019\u00e9crit a \u00e9t\u00e9 une transition naturelle. Suiveur assidu de basket et de hockey sur glace, je garde toujours un peu de place pour suivre le cyclisme, le football et le maximum de performances fran\u00e7aises.\",\"sameAs\":[\"https:\/\/x.com\/https:\/\/twitter.com\/Maxime_Caze\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/maximec\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Provence Rugby efface un d\u00e9ficit de 24 points pour scalper Vannes, leader de Pro D2","description":"PRO D2 2025-2026 - Men\u00e9 de 24 points \u00e0 la pause, Provence Rugby a renvers\u00e9 la partie de mani\u00e8re spectaculaire pour s'imposer face au leader Vannes, 34-24.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/provence-rugby-efface-un-deficit-de-24-points-pour-scalper-vannes-leader-de-pro-d2\/","og_locale":"fr_FR","og_type":"article","og_title":"Provence Rugby efface un d\u00e9ficit de 24 points pour scalper Vannes, leader de Pro D2","og_description":"PRO D2 2025-2026 - Men\u00e9 de 24 points \u00e0 la pause, Provence Rugby a renvers\u00e9 la partie de mani\u00e8re spectaculaire pour s'imposer face au leader Vannes, 34-24.","og_url":"https:\/\/dicodusport.fr\/blog\/provence-rugby-efface-un-deficit-de-24-points-pour-scalper-vannes-leader-de-pro-d2\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2026-05-07T20:53:30+00:00","article_modified_time":"2026-05-07T20:58:19+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/05\/Provence-Rugby-efface-un-deficit-de-24-points-pour-scalper-Vannes-leader-de-Pro-D2.png","type":"image\/png"}],"author":"Maxime Cazenave","twitter_card":"summary_large_image","twitter_title":"Provence Rugby efface un d\u00e9ficit de 24 points pour scalper Vannes, leader de Pro D2","twitter_creator":"@https:\/\/twitter.com\/Maxime_Caze","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/provence-rugby-efface-un-deficit-de-24-points-pour-scalper-vannes-leader-de-pro-d2\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/provence-rugby-efface-un-deficit-de-24-points-pour-scalper-vannes-leader-de-pro-d2\/"},"author":{"name":"Maxime Cazenave","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0"},"headline":"Provence Rugby efface un d\u00e9ficit de 24 points pour scalper Vannes, leader de Pro D2","datePublished":"2026-05-07T20:53:30+00:00","dateModified":"2026-05-07T20:58:19+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/provence-rugby-efface-un-deficit-de-24-points-pour-scalper-vannes-leader-de-pro-d2\/"},"wordCount":665,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/provence-rugby-efface-un-deficit-de-24-points-pour-scalper-vannes-leader-de-pro-d2\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/05\/Provence-Rugby-efface-un-deficit-de-24-points-pour-scalper-Vannes-leader-de-Pro-D2.png","keywords":["br\u00e8ve","Pro D2","Provence Rugby","RC Vannes"],"articleSection":["Pro D2"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/provence-rugby-efface-un-deficit-de-24-points-pour-scalper-vannes-leader-de-pro-d2\/#respond"]}],"copyrightYear":"2026","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/provence-rugby-efface-un-deficit-de-24-points-pour-scalper-vannes-leader-de-pro-d2\/","url":"https:\/\/dicodusport.fr\/blog\/provence-rugby-efface-un-deficit-de-24-points-pour-scalper-vannes-leader-de-pro-d2\/","name":"Provence Rugby efface un d\u00e9ficit de 24 points pour scalper Vannes, leader de Pro D2","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/provence-rugby-efface-un-deficit-de-24-points-pour-scalper-vannes-leader-de-pro-d2\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/provence-rugby-efface-un-deficit-de-24-points-pour-scalper-vannes-leader-de-pro-d2\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/05\/Provence-Rugby-efface-un-deficit-de-24-points-pour-scalper-Vannes-leader-de-Pro-D2.png","datePublished":"2026-05-07T20:53:30+00:00","dateModified":"2026-05-07T20:58:19+00:00","description":"PRO D2 2025-2026 - Men\u00e9 de 24 points \u00e0 la pause, Provence Rugby a renvers\u00e9 la partie de mani\u00e8re spectaculaire pour s'imposer face au leader Vannes, 34-24.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/provence-rugby-efface-un-deficit-de-24-points-pour-scalper-vannes-leader-de-pro-d2\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/provence-rugby-efface-un-deficit-de-24-points-pour-scalper-vannes-leader-de-pro-d2\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/provence-rugby-efface-un-deficit-de-24-points-pour-scalper-vannes-leader-de-pro-d2\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/05\/Provence-Rugby-efface-un-deficit-de-24-points-pour-scalper-Vannes-leader-de-Pro-D2.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/05\/Provence-Rugby-efface-un-deficit-de-24-points-pour-scalper-Vannes-leader-de-Pro-D2.png","width":1200,"height":674,"caption":"Provence Rugby efface un d\u00e9ficit de 24 points pour scalper Vannes, leader de Pro D2"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/provence-rugby-efface-un-deficit-de-24-points-pour-scalper-vannes-leader-de-pro-d2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Provence Rugby efface un d\u00e9ficit de 24 points pour scalper Vannes, leader de Pro D2"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0","name":"Maxime Cazenave","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg","caption":"Maxime Cazenave"},"description":"Journaliste\/R\u00e9dacteur depuis 2012 - Berc\u00e9 par l\u2019amour des Girondins de Bordeaux, les \u00e9checs de Christophe Moreau sur le Tour de France sous l'\u00e8re Lance Armstrong et le fade-away l\u00e9tal de Dirk Nowitzki, ma passion d\u00e9vorante pour le sport a toujours \u00e9t\u00e9 un pan incontournable de ma vie. Transmettre ma passion \u00e0 l\u2019\u00e9crit a \u00e9t\u00e9 une transition naturelle. Suiveur assidu de basket et de hockey sur glace, je garde toujours un peu de place pour suivre le cyclisme, le football et le maximum de performances fran\u00e7aises.","sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/Maxime_Caze"],"url":"https:\/\/dicodusport.fr\/blog\/author\/maximec\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/668358","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=668358"}],"version-history":[{"count":4,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/668358\/revisions"}],"predecessor-version":[{"id":668401,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/668358\/revisions\/668401"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/668396"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=668358"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=668358"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=668358"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}