{"id":668715,"date":"2026-05-09T19:08:17","date_gmt":"2026-05-09T17:08:17","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=668715&#038;preview=true&#038;preview_id=668715"},"modified":"2026-05-09T20:01:58","modified_gmt":"2026-05-09T18:01:58","slug":"les-bleues-dominent-largement-les-ecossaises-et-joueront-la-victoire-dans-le-six-nations-face-aux-anglaises","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/les-bleues-dominent-largement-les-ecossaises-et-joueront-la-victoire-dans-le-six-nations-face-aux-anglaises\/","title":{"rendered":"Les Bleues dominent largement les \u00c9cossaises et joueront la victoire dans le Six Nations face aux Anglaises"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>TOURNOI DES 6 NATIONS F\u00c9MININ 2026 &#8211; En multipliant les essais, les Fran\u00e7aises ont nettement domin\u00e9 les \u00c9cossaises (28-69) et restent en course pour le Grand Chelem.\u00a0<\/em><\/strong><\/p>\n<ul style=\"text-align: justify;\">\n<li><strong>\u00c0 ce sujet \u2013\u00a0<a href=\"https:\/\/dicodusport.fr\/blog\/tournoi-des-6-nations-feminin-2026-calendrier-resultats-et-classement-mis-a-jour\/\">Tournoi des 6 Nations F\u00e9minin 2026 : calendrier, r\u00e9sultats et classement mis \u00e0 jour<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Le Tournoi continue pour les Fran\u00e7aises avec une opposition face aux \u00c9cossaises aujourd\u2019hui. Invaincues jusque l\u00e0, les Bleues visent toujours le Grand Chelem, avant la probable finale contre leurs meilleures ennemies Anglaises.<\/p>\n<h2 style=\"text-align: justify;\">Le bonus offensif assur\u00e9 d\u00e8s la premi\u00e8re mi-temps<\/h2>\n<p style=\"text-align: justify;\">Le match d\u00e9marre, et les Tricolores n\u2019attendent pas longtemps pour lancer les hostilit\u00e9s. <strong>Arbez<\/strong> tape le coup d\u2019envoi, <strong>Champon<\/strong> r\u00e9cup\u00e8re, puis passe \u00e0 <strong>Feleu<\/strong> qui parvient \u00e0 aplatir en coin (0-5).<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">\ud83c\udfc9 <a href=\"https:\/\/twitter.com\/hashtag\/GuinnessW6N?src=hash&amp;ref_src=twsrc%5Etfw\">#GuinnessW6N<\/a> | \ud83c\uddeb\ud83c\uddf7 Le premier essai apr\u00e8s moins d&rsquo;une minute de jeu !<\/p>\n<p>La France lance parfaitement son match<\/p>\n<p>\ud83d\udcfa Suivez le match en direct : <a href=\"https:\/\/t.co\/2YyyGIAfdo\">https:\/\/t.co\/2YyyGIAfdo<\/a> <a href=\"https:\/\/t.co\/Yws3SiCCt1\">pic.twitter.com\/Yws3SiCCt1<\/a><\/p>\n<p>\u2014 francetvsport (@francetvsport) <a href=\"https:\/\/twitter.com\/francetvsport\/status\/2053132444103032877?ref_src=twsrc%5Etfw\">May 9, 2026<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p style=\"text-align: justify;\">Pourtant bien parties, les Bleues souffrent ensuite, notamment dans les mauls. La double sanction finit par tomber avec un essai \u00e9cossais sign\u00e9 <strong>Rachel Philipps<\/strong> (7-5), et un carton jaune contre <strong>Manae Feleu<\/strong>. Heureusement pour les Tricolores, <strong>Carla Arbez<\/strong> continue son excellent tournoi avec une superbe action. Dans l\u2019avanc\u00e9e, elle porte un petit coup de pied par-dessus qu\u2019elle r\u00e9cup\u00e8re avant d\u2019aplatir (7-12).<\/p>\n<p style=\"text-align: justify;\">Apr\u00e8s un ballon perdu par les Bleues, <strong>Bourdon-Sansus<\/strong> parvient \u00e0 le r\u00e9cup\u00e9rer. Le jeu tricolore se met en place, \u00e0 coup de <em>pick and go<\/em>. La d\u00e9fense \u00e9cossaise recule et finit par c\u00e9der sous la puissance de <strong>Soqeta<\/strong>, qui s\u2019offre un essai pour sa premi\u00e8re titularisation (7-19).<\/p>\n<div class=\"vlp-link-container vlp-layout-article\"><a href=\"https:\/\/dicodusport.fr\/blog\/les-notes-des-bleues-face-a-lecosse-champon-etincelante-brosseau-encore-secouee\/\" class=\"vlp-link\" title=\"Les notes des Bleues face \u00e0 l&#039;\u00c9cosse : Champon \u00e9tincelante, Brosseau encore secou\u00e9e\"><\/a><div class=\"vlp-layout-zone-side\"><div class=\"vlp-block-4 vlp-link-image\"><img loading=\"lazy\" decoding=\"async\" style=\"max-width: 785px;\" width=\"785\" height=\"445\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/05\/Les-notes-des-Bleues-face-a-lEcosse-Champon-etincelante-Brosseau-encore-secouee.png\" class=\"attachment-800x445 size-800x445\" alt=\"Les notes des Bleues face \u00e0 l&#039;\u00c9cosse : Champon \u00e9tincelante, Brosseau encore secou\u00e9e\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/05\/Les-notes-des-Bleues-face-a-lEcosse-Champon-etincelante-Brosseau-encore-secouee.png 1200w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/05\/Les-notes-des-Bleues-face-a-lEcosse-Champon-etincelante-Brosseau-encore-secouee-300x170.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/05\/Les-notes-des-Bleues-face-a-lEcosse-Champon-etincelante-Brosseau-encore-secouee-1024x580.png 1024w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/05\/Les-notes-des-Bleues-face-a-lEcosse-Champon-etincelante-Brosseau-encore-secouee-768x435.png 768w\" sizes=\"auto, (max-width: 785px) 100vw, 785px\" \/><\/div><\/div><div class=\"vlp-layout-zone-main\"><div class=\"vlp-block-0 vlp-link-title\">Les notes des Bleues face \u00e0 l'\u00c9cosse : Champon \u00e9tincelante, Brosseau encore secou\u00e9e<\/div><div class=\"vlp-block-1 vlp-link-summary\">D\u00e9couvrez les notes des Bleues face \u00e0 l'\u00c9cosse, dans le match de la 4e journ\u00e9e du Tournoi des 6 Nations f\u00e9minin remport\u00e9 par le XV de France (28-69).<\/div><div class=\"vlp-block-2 vlp-link-button\">Lire l'article<\/div><div class=\"vlp-block-3 vlp-link-url\">dicodusport.fr<\/div><\/div><\/div>\n<p style=\"text-align: justify;\">31\u00e8me minute de jeu et d\u00e9j\u00e0 l\u2019essai du bonus offensif pour les Bleues gr\u00e2ce au superbe travail de <strong>L\u00e9a Champon<\/strong> qui a feint\u00e9 la passe pour tromper la d\u00e9fense adverse (7-26). Malgr\u00e9 un niveau de jeu moyen, les \u00c9cossaises parviennent \u00e0 r\u00e9duire l\u2019\u00e9cart avant la mi-temps gr\u00e2ce au doubl\u00e9 de <strong>Philipps<\/strong>.<\/p>\n<p style=\"text-align: justify;\">\u00c0 la pause, les Fran\u00e7aises sont largement devant (14-31) suite au doubl\u00e9 de <strong>Champon<\/strong>. Les Bleues ont multipli\u00e9 les offensives, et sont parvenues \u00e0 quasiment toutes les concr\u00e9tiser.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">Une premi\u00e8re mi-temps riche en essais \u00e0 \u00c9dimbourg \ud83d\ude2e\u200d\ud83d\udca8<a href=\"https:\/\/twitter.com\/hashtag\/GreatnessW6N?src=hash&amp;ref_src=twsrc%5Etfw\">#GreatnessW6N<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/LovelyDayW6N?src=hash&amp;ref_src=twsrc%5Etfw\">#LovelyDayW6N<\/a> <a href=\"https:\/\/t.co\/9hLarOoG9c\">pic.twitter.com\/9hLarOoG9c<\/a><\/p>\n<p>\u2014 Guinness Women&rsquo;s Six Nations (@Womens6Nations) <a href=\"https:\/\/twitter.com\/Womens6Nations\/status\/2053144310170751125?ref_src=twsrc%5Etfw\">May 9, 2026<\/a><\/p><\/blockquote>\n<p style=\"text-align: justify;\"><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 style=\"text-align: justify;\">Une large victoire et direction la finale pour les Bleues<\/h2>\n<p style=\"text-align: justify;\">Aussit\u00f4t le coup de sifflet, les Tricolores repartent fort. Servie par <strong>Murie<\/strong>, <strong>Barrat<\/strong> inscrit un nouvel essai fran\u00e7ais (14-36). Les Fran\u00e7aises encha\u00eenent les opportunit\u00e9s mais peinent \u00e0 conclure \u00e0 cause de fautes de main r\u00e9p\u00e9t\u00e9es.<\/p>\n<p style=\"text-align: justify;\">En feu, les Bleues ajouteront 4 essais suppl\u00e9mentaires, dans les 20 derni\u00e8res minutes, sign\u00e9s <strong>Chambon<\/strong>, <strong>Murie<\/strong>, <strong>Deshaye<\/strong> et <strong>Mwayembe<\/strong>. En face, les \u00c9cossaises iront chercher le bonus offensif elles aussi, gr\u00e2ce \u00e0 <strong>Sutcliffe<\/strong>, mais s\u2019inclineront tr\u00e8s largement.<\/p>\n<p style=\"text-align: justify;\">Les Fran\u00e7aises s\u2019offrent une large victoire <strong>(69-28)<\/strong> et rejoignent les Anglaises pour disputer ce qui fera office de finale de ce tournoi 2026.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">4e match et 4e victoire bonifi\u00e9e pour les Bleues \ud83d\udcaa<\/p>\n<p>Rendez-vous dimanche 17 mai pour une FINALE contre l&rsquo;Angleterre \ud83d\udca5<a href=\"https:\/\/twitter.com\/hashtag\/GreatnessW6N?src=hash&amp;ref_src=twsrc%5Etfw\">#GreatnessW6N<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/LovelyDayW6N?src=hash&amp;ref_src=twsrc%5Etfw\">#LovelyDayW6N<\/a> <a href=\"https:\/\/t.co\/MPwUJUYdgv\">pic.twitter.com\/MPwUJUYdgv<\/a><\/p>\n<p>\u2014 Guinness Women&rsquo;s Six Nations (@Womens6Nations) <a href=\"https:\/\/twitter.com\/Womens6Nations\/status\/2053159822288195994?ref_src=twsrc%5Etfw\">May 9, 2026<\/a><\/p><\/blockquote>\n<p style=\"text-align: justify;\"><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h3>\u00c0 lire aussi<\/h3>\n<div class=\"vlp-link-container vlp-layout-article\"><a href=\"https:\/\/dicodusport.fr\/blog\/les-notes-des-bleues-face-a-lecosse-champon-etincelante-brosseau-encore-secouee\/\" class=\"vlp-link\" title=\"Les notes des Bleues face \u00e0 l&#039;\u00c9cosse : Champon \u00e9tincelante, Brosseau encore secou\u00e9e\"><\/a><div class=\"vlp-layout-zone-side\"><div class=\"vlp-block-4 vlp-link-image\"><img loading=\"lazy\" decoding=\"async\" style=\"max-width: 785px;\" width=\"785\" height=\"445\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/05\/Les-notes-des-Bleues-face-a-lEcosse-Champon-etincelante-Brosseau-encore-secouee.png\" class=\"attachment-800x445 size-800x445\" alt=\"Les notes des Bleues face \u00e0 l&#039;\u00c9cosse : Champon \u00e9tincelante, Brosseau encore secou\u00e9e\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/05\/Les-notes-des-Bleues-face-a-lEcosse-Champon-etincelante-Brosseau-encore-secouee.png 1200w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/05\/Les-notes-des-Bleues-face-a-lEcosse-Champon-etincelante-Brosseau-encore-secouee-300x170.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/05\/Les-notes-des-Bleues-face-a-lEcosse-Champon-etincelante-Brosseau-encore-secouee-1024x580.png 1024w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/05\/Les-notes-des-Bleues-face-a-lEcosse-Champon-etincelante-Brosseau-encore-secouee-768x435.png 768w\" sizes=\"auto, (max-width: 785px) 100vw, 785px\" \/><\/div><\/div><div class=\"vlp-layout-zone-main\"><div class=\"vlp-block-0 vlp-link-title\">Les notes des Bleues face \u00e0 l'\u00c9cosse : Champon \u00e9tincelante, Brosseau encore secou\u00e9e<\/div><div class=\"vlp-block-1 vlp-link-summary\">D\u00e9couvrez les notes des Bleues face \u00e0 l'\u00c9cosse, dans le match de la 4e journ\u00e9e du Tournoi des 6 Nations f\u00e9minin remport\u00e9 par le XV de France (28-69).<\/div><div class=\"vlp-block-2 vlp-link-button\">Lire l'article<\/div><div class=\"vlp-block-3 vlp-link-url\">dicodusport.fr<\/div><\/div><\/div>\n<div id=\"gtx-trans\" style=\"position: absolute; left: -14px; top: 40.9091px;\">\n<div class=\"gtx-trans-icon\" style=\"text-align: justify;\"><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>TOURNOI DES 6 NATIONS F\u00c9MININ 2026 &#8211; En multipliant les essais, les Fran\u00e7aises ont nettement domin\u00e9 les \u00c9cossaises (28-69) et restent en course pour le Grand Chelem.\u00a0<\/p>\n","protected":false},"author":89,"featured_media":669013,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[47048],"tags":[16878,1332,30,13,24,10602],"class_list":["post-668715","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tournoi-des-6-nations","tag-breve","tag-ecosse","tag-france","tag-rugby","tag-sport","tag-tournoi-des-6-nations-feminin"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Les Bleues dominent largement les \u00c9cossaises et joueront la victoire dans le Six Nations face aux Anglaises<\/title>\n<meta name=\"description\" content=\"TOURNOI DES 6 NATIONS F\u00c9MININ 2026 - En multipliant les essais, les Fran\u00e7aises ont nettement domin\u00e9 les \u00c9cossaises (28-69) et restent en course pour le Grand Chelem.\u00a0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/les-bleues-dominent-largement-les-ecossaises-et-joueront-la-victoire-dans-le-six-nations-face-aux-anglaises\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les Bleues dominent largement les \u00c9cossaises et joueront la victoire dans le Six Nations face aux Anglaises\" \/>\n<meta property=\"og:description\" content=\"TOURNOI DES 6 NATIONS F\u00c9MININ 2026 - En multipliant les essais, les Fran\u00e7aises ont nettement domin\u00e9 les \u00c9cossaises (28-69) et restent en course pour le Grand Chelem.\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/les-bleues-dominent-largement-les-ecossaises-et-joueront-la-victoire-dans-le-six-nations-face-aux-anglaises\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-09T17:08:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-09T18:01:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/05\/Les-Bleues-dominent-largement-les-Ecossaises-et-joueront-la-victoire-dans-le-Six-Nations-face-aux-Anglaises.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Louka Lesueur\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Les Bleues dominent largement les \u00c9cossaises et joueront la victoire dans le Six Nations face aux Anglaises\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/LNewsSF\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/les-bleues-dominent-largement-les-ecossaises-et-joueront-la-victoire-dans-le-six-nations-face-aux-anglaises\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/les-bleues-dominent-largement-les-ecossaises-et-joueront-la-victoire-dans-le-six-nations-face-aux-anglaises\/\"},\"author\":{\"name\":\"Louka Lesueur\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/54b6cdccebdfcd5a1036c594aecffc2a\"},\"headline\":\"Les Bleues dominent largement les \u00c9cossaises et joueront la victoire dans le Six Nations face aux Anglaises\",\"datePublished\":\"2026-05-09T17:08:17+00:00\",\"dateModified\":\"2026-05-09T18:01:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/les-bleues-dominent-largement-les-ecossaises-et-joueront-la-victoire-dans-le-six-nations-face-aux-anglaises\/\"},\"wordCount\":727,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/les-bleues-dominent-largement-les-ecossaises-et-joueront-la-victoire-dans-le-six-nations-face-aux-anglaises\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/05\/Les-Bleues-dominent-largement-les-Ecossaises-et-joueront-la-victoire-dans-le-Six-Nations-face-aux-Anglaises.png\",\"keywords\":[\"br\u00e8ve\",\"Ecosse\",\"France\",\"Rugby\",\"sport\",\"Tournoi des 6 Nations f\u00e9minin\"],\"articleSection\":[\"Tournoi des 6 Nations\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/les-bleues-dominent-largement-les-ecossaises-et-joueront-la-victoire-dans-le-six-nations-face-aux-anglaises\/#respond\"]}],\"copyrightYear\":\"2026\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/les-bleues-dominent-largement-les-ecossaises-et-joueront-la-victoire-dans-le-six-nations-face-aux-anglaises\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/les-bleues-dominent-largement-les-ecossaises-et-joueront-la-victoire-dans-le-six-nations-face-aux-anglaises\/\",\"name\":\"Les Bleues dominent largement les \u00c9cossaises et joueront la victoire dans le Six Nations face aux Anglaises\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/les-bleues-dominent-largement-les-ecossaises-et-joueront-la-victoire-dans-le-six-nations-face-aux-anglaises\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/les-bleues-dominent-largement-les-ecossaises-et-joueront-la-victoire-dans-le-six-nations-face-aux-anglaises\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/05\/Les-Bleues-dominent-largement-les-Ecossaises-et-joueront-la-victoire-dans-le-Six-Nations-face-aux-Anglaises.png\",\"datePublished\":\"2026-05-09T17:08:17+00:00\",\"dateModified\":\"2026-05-09T18:01:58+00:00\",\"description\":\"TOURNOI DES 6 NATIONS F\u00c9MININ 2026 - En multipliant les essais, les Fran\u00e7aises ont nettement domin\u00e9 les \u00c9cossaises (28-69) et restent en course pour le Grand Chelem.\u00a0\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/les-bleues-dominent-largement-les-ecossaises-et-joueront-la-victoire-dans-le-six-nations-face-aux-anglaises\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/les-bleues-dominent-largement-les-ecossaises-et-joueront-la-victoire-dans-le-six-nations-face-aux-anglaises\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/les-bleues-dominent-largement-les-ecossaises-et-joueront-la-victoire-dans-le-six-nations-face-aux-anglaises\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/05\/Les-Bleues-dominent-largement-les-Ecossaises-et-joueront-la-victoire-dans-le-Six-Nations-face-aux-Anglaises.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/05\/Les-Bleues-dominent-largement-les-Ecossaises-et-joueront-la-victoire-dans-le-Six-Nations-face-aux-Anglaises.png\",\"width\":1200,\"height\":674,\"caption\":\"Les Bleues dominent largement les \u00c9cossaises et joueront la victoire dans le Six Nations face aux Anglaises\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/les-bleues-dominent-largement-les-ecossaises-et-joueront-la-victoire-dans-le-six-nations-face-aux-anglaises\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les Bleues dominent largement les \u00c9cossaises et joueront la victoire dans le Six Nations face aux Anglaises\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/54b6cdccebdfcd5a1036c594aecffc2a\",\"name\":\"Louka Lesueur\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/09\/IMG_2783-150x150.jpeg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/09\/IMG_2783-150x150.jpeg\",\"caption\":\"Louka Lesueur\"},\"description\":\"Passionn\u00e9 depuis tout petit par les exploits de Bolt, Fourcade, Riner, Lavillenie, Wilkinson, Hirscher. Les \u00e9motions provoqu\u00e9es par le sport ont berc\u00e9 mon enfance et continuent de le faire aujourd'hui. C'est ainsi qu'il m'est arriv\u00e9 de pleurer devant la d\u00e9faite des Bleus face aux Blacks en 2011, ou encore devant le titre olympique de Florent Manaudou \u00e0 Londres. Bien loin de ce milieu professionnel, j'ai os\u00e9 tenter ma chance pour rejoindre l'\u00e9quipe de r\u00e9daction de Dicodusport, et depuis septembre 2023, je tente de retransmettre au mieux les exploits des athl\u00e8tes, tous sports confondus. Grand chauvin, c'est bel et bien sur les sportifs tricolores que je pr\u00e9f\u00e8re \u00e9crire.\",\"sameAs\":[\"https:\/\/x.com\/https:\/\/twitter.com\/LNewsSF\"],\"gender\":\"Homme\",\"worksFor\":\"Louka LESUEUR\",\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/louka-lesueur\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Les Bleues dominent largement les \u00c9cossaises et joueront la victoire dans le Six Nations face aux Anglaises","description":"TOURNOI DES 6 NATIONS F\u00c9MININ 2026 - En multipliant les essais, les Fran\u00e7aises ont nettement domin\u00e9 les \u00c9cossaises (28-69) et restent en course pour le Grand Chelem.\u00a0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/les-bleues-dominent-largement-les-ecossaises-et-joueront-la-victoire-dans-le-six-nations-face-aux-anglaises\/","og_locale":"fr_FR","og_type":"article","og_title":"Les Bleues dominent largement les \u00c9cossaises et joueront la victoire dans le Six Nations face aux Anglaises","og_description":"TOURNOI DES 6 NATIONS F\u00c9MININ 2026 - En multipliant les essais, les Fran\u00e7aises ont nettement domin\u00e9 les \u00c9cossaises (28-69) et restent en course pour le Grand Chelem.\u00a0","og_url":"https:\/\/dicodusport.fr\/blog\/les-bleues-dominent-largement-les-ecossaises-et-joueront-la-victoire-dans-le-six-nations-face-aux-anglaises\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2026-05-09T17:08:17+00:00","article_modified_time":"2026-05-09T18:01:58+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/05\/Les-Bleues-dominent-largement-les-Ecossaises-et-joueront-la-victoire-dans-le-Six-Nations-face-aux-Anglaises.png","type":"image\/png"}],"author":"Louka Lesueur","twitter_card":"summary_large_image","twitter_title":"Les Bleues dominent largement les \u00c9cossaises et joueront la victoire dans le Six Nations face aux Anglaises","twitter_creator":"@https:\/\/twitter.com\/LNewsSF","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/les-bleues-dominent-largement-les-ecossaises-et-joueront-la-victoire-dans-le-six-nations-face-aux-anglaises\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/les-bleues-dominent-largement-les-ecossaises-et-joueront-la-victoire-dans-le-six-nations-face-aux-anglaises\/"},"author":{"name":"Louka Lesueur","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/54b6cdccebdfcd5a1036c594aecffc2a"},"headline":"Les Bleues dominent largement les \u00c9cossaises et joueront la victoire dans le Six Nations face aux Anglaises","datePublished":"2026-05-09T17:08:17+00:00","dateModified":"2026-05-09T18:01:58+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/les-bleues-dominent-largement-les-ecossaises-et-joueront-la-victoire-dans-le-six-nations-face-aux-anglaises\/"},"wordCount":727,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/les-bleues-dominent-largement-les-ecossaises-et-joueront-la-victoire-dans-le-six-nations-face-aux-anglaises\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/05\/Les-Bleues-dominent-largement-les-Ecossaises-et-joueront-la-victoire-dans-le-Six-Nations-face-aux-Anglaises.png","keywords":["br\u00e8ve","Ecosse","France","Rugby","sport","Tournoi des 6 Nations f\u00e9minin"],"articleSection":["Tournoi des 6 Nations"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/les-bleues-dominent-largement-les-ecossaises-et-joueront-la-victoire-dans-le-six-nations-face-aux-anglaises\/#respond"]}],"copyrightYear":"2026","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/les-bleues-dominent-largement-les-ecossaises-et-joueront-la-victoire-dans-le-six-nations-face-aux-anglaises\/","url":"https:\/\/dicodusport.fr\/blog\/les-bleues-dominent-largement-les-ecossaises-et-joueront-la-victoire-dans-le-six-nations-face-aux-anglaises\/","name":"Les Bleues dominent largement les \u00c9cossaises et joueront la victoire dans le Six Nations face aux Anglaises","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/les-bleues-dominent-largement-les-ecossaises-et-joueront-la-victoire-dans-le-six-nations-face-aux-anglaises\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/les-bleues-dominent-largement-les-ecossaises-et-joueront-la-victoire-dans-le-six-nations-face-aux-anglaises\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/05\/Les-Bleues-dominent-largement-les-Ecossaises-et-joueront-la-victoire-dans-le-Six-Nations-face-aux-Anglaises.png","datePublished":"2026-05-09T17:08:17+00:00","dateModified":"2026-05-09T18:01:58+00:00","description":"TOURNOI DES 6 NATIONS F\u00c9MININ 2026 - En multipliant les essais, les Fran\u00e7aises ont nettement domin\u00e9 les \u00c9cossaises (28-69) et restent en course pour le Grand Chelem.\u00a0","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/les-bleues-dominent-largement-les-ecossaises-et-joueront-la-victoire-dans-le-six-nations-face-aux-anglaises\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/les-bleues-dominent-largement-les-ecossaises-et-joueront-la-victoire-dans-le-six-nations-face-aux-anglaises\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/les-bleues-dominent-largement-les-ecossaises-et-joueront-la-victoire-dans-le-six-nations-face-aux-anglaises\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/05\/Les-Bleues-dominent-largement-les-Ecossaises-et-joueront-la-victoire-dans-le-Six-Nations-face-aux-Anglaises.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/05\/Les-Bleues-dominent-largement-les-Ecossaises-et-joueront-la-victoire-dans-le-Six-Nations-face-aux-Anglaises.png","width":1200,"height":674,"caption":"Les Bleues dominent largement les \u00c9cossaises et joueront la victoire dans le Six Nations face aux Anglaises"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/les-bleues-dominent-largement-les-ecossaises-et-joueront-la-victoire-dans-le-six-nations-face-aux-anglaises\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Les Bleues dominent largement les \u00c9cossaises et joueront la victoire dans le Six Nations face aux Anglaises"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/54b6cdccebdfcd5a1036c594aecffc2a","name":"Louka Lesueur","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/09\/IMG_2783-150x150.jpeg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/09\/IMG_2783-150x150.jpeg","caption":"Louka Lesueur"},"description":"Passionn\u00e9 depuis tout petit par les exploits de Bolt, Fourcade, Riner, Lavillenie, Wilkinson, Hirscher. Les \u00e9motions provoqu\u00e9es par le sport ont berc\u00e9 mon enfance et continuent de le faire aujourd'hui. C'est ainsi qu'il m'est arriv\u00e9 de pleurer devant la d\u00e9faite des Bleus face aux Blacks en 2011, ou encore devant le titre olympique de Florent Manaudou \u00e0 Londres. Bien loin de ce milieu professionnel, j'ai os\u00e9 tenter ma chance pour rejoindre l'\u00e9quipe de r\u00e9daction de Dicodusport, et depuis septembre 2023, je tente de retransmettre au mieux les exploits des athl\u00e8tes, tous sports confondus. Grand chauvin, c'est bel et bien sur les sportifs tricolores que je pr\u00e9f\u00e8re \u00e9crire.","sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/LNewsSF"],"gender":"Homme","worksFor":"Louka LESUEUR","url":"https:\/\/dicodusport.fr\/blog\/author\/louka-lesueur\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/668715","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/89"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=668715"}],"version-history":[{"count":5,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/668715\/revisions"}],"predecessor-version":[{"id":669056,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/668715\/revisions\/669056"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/669013"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=668715"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=668715"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=668715"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}