{"id":669026,"date":"2026-05-09T19:45:36","date_gmt":"2026-05-09T17:45:36","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=669026&#038;preview=true&#038;preview_id=669026"},"modified":"2026-05-09T22:00:38","modified_gmt":"2026-05-09T20:00:38","slug":"blandine-lhirondel-triomphe-sur-la-transvulcania-et-bat-le-record-de-lepreuve","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/blandine-lhirondel-triomphe-sur-la-transvulcania-et-bat-le-record-de-lepreuve\/","title":{"rendered":"Blandine L&rsquo;Hirondel triomphe sur la Transvulcania et bat le record de l&rsquo;\u00e9preuve"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>TRAIL &#8211; Blandine L&rsquo;Hirondel a dompt\u00e9 les 75 km et 4240 m\u00e8tres de d\u00e9nivel\u00e9 positif et\u00a0remporte la Transvulcania 2026.<\/em><\/strong><\/p>\n<ul style=\"text-align: justify;\">\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/classement-transvulcania-2026-en-direct\/\">Classement Transvulcania 2026 en direct<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/dicodusport.fr\/blog\/margot-dajoux-je-suis-fiere-de-la-facon-dont-jai-couru-a-carhaix\/\">Dans son interview qu&rsquo;elle nous a accord\u00e9e il y a quelques semaines<\/a>, <strong>Margot Dajoux<\/strong> d\u00e9finissait <strong>Blandine L&rsquo;Hirondel<\/strong> comme l&rsquo;athl\u00e8te la plus polyvalente qu&rsquo;elle connaisse. Cette derni\u00e8re a encore frapp\u00e9 ce week-end. Dans les \u00eeles Canaries, elle a dompt\u00e9 la Transvulcania et ses 75 km et 4240 m\u00e8tres de d\u00e9nivel\u00e9 positif.<\/p>\n<h2 style=\"text-align: justify;\">Un \u00e9cart resserr\u00e9 sur sa poursuivante<\/h2>\n<p style=\"text-align: justify;\">La Fran\u00e7aise remporte une nouvelle victoire de prestige en ultra-trail, apr\u00e8s sa victoire dans la Diagonale des Fous. Malgr\u00e9 pr\u00e8s de 8 heures de course (7h43:47) elle a d\u00fb composer avec la r\u00e9sistance de l&rsquo;Australienne <strong>Lucy Bartholomew<\/strong>, qui ne conc\u00e8de que 5:39. Un \u00e9cart assez faible au vu du temps d&rsquo;effort, mais qui suffit \u00e0 la joie de la Fran\u00e7aise.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">La Transvulcania 2026 (75 km, 4 240 m D+) a couronn\u00e9 l&rsquo;Am\u00e9ricain David Sinclair, qui a par ailleurs battu le chrono de l&rsquo;\u00e9preuve, et la Fran\u00e7aise Blandine L&rsquo;Hirondel<br \/>\n\u27a1\ufe0f <a href=\"https:\/\/t.co\/rt1VOeV1ye\">https:\/\/t.co\/rt1VOeV1ye<\/a> <a href=\"https:\/\/t.co\/olyeoGyHMT\">pic.twitter.com\/olyeoGyHMT<\/a><\/p>\n<p>\u2014 L&rsquo;\u00c9quipe (@lequipe) <a href=\"https:\/\/twitter.com\/lequipe\/status\/2053119810934886587?ref_src=twsrc%5Etfw\">May 9, 2026<\/a><\/p><\/blockquote>\n<p style=\"text-align: justify;\"><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p style=\"text-align: justify;\">La Normande a cette capacit\u00e9 de switcher d&rsquo;efforts tr\u00e8s longs \u00e0 des efforts plus courts. Celle qui a d\u00e9j\u00e0 \u00e9t\u00e9 m\u00e9daill\u00e9e aux championnats de France de cross avait encore pris une place dans le Top 10 au mois de mars, lors du dernier rendez-vous national \u00e0 <strong>Carhaix<\/strong>. Une polyvalence qui inspire le respect. \u00c0 35 ans, la Fran\u00e7aise se constitue un sacr\u00e9 palmar\u00e8s en trail et en course de Montagne.<\/p>\n<div id=\"gtx-trans\" style=\"position: absolute; left: -14px; top: 40.9091px;\">\n<div class=\"gtx-trans-icon\" style=\"text-align: justify;\"><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>TRAIL &#8211; Blandine L&rsquo;Hirondel a dompt\u00e9 les 75 km et 4240 m\u00e8tres de d\u00e9nivel\u00e9 positif et\u00a0remporte la Transvulcania 2026.<\/p>\n","protected":false},"author":83,"featured_media":669044,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[8673],"tags":[16878,349,862],"class_list":["post-669026","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-trail","tag-breve","tag-course-a-pied","tag-trail"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Blandine L&#039;Hirondel triomphe sur la Transvulcania et bat le record de l&#039;\u00e9preuve<\/title>\n<meta name=\"description\" content=\"TRAIL - Blandine L&#039;Hirondel a dompt\u00e9 les 75 km et 4240 m\u00e8tres de d\u00e9nivel\u00e9 positif et\u00a0remporte la Transvulcania 2026.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/blandine-lhirondel-triomphe-sur-la-transvulcania-et-bat-le-record-de-lepreuve\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Blandine L&#039;Hirondel triomphe sur la Transvulcania et bat le record de l&#039;\u00e9preuve\" \/>\n<meta property=\"og:description\" content=\"TRAIL - Blandine L&#039;Hirondel a dompt\u00e9 les 75 km et 4240 m\u00e8tres de d\u00e9nivel\u00e9 positif et\u00a0remporte la Transvulcania 2026.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/blandine-lhirondel-triomphe-sur-la-transvulcania-et-bat-le-record-de-lepreuve\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-09T17:45:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-09T20:00:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/05\/Blandine-LHirondel-triomphe-sur-la-Transvulcania-et-bat-le-record-de-lepreuve.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Etienne Goursaud\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Blandine L&#039;Hirondel triomphe sur la Transvulcania et bat le record de l&#039;\u00e9preuve\" \/>\n<meta name=\"twitter:creator\" content=\"@dicodusport\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/blandine-lhirondel-triomphe-sur-la-transvulcania-et-bat-le-record-de-lepreuve\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/blandine-lhirondel-triomphe-sur-la-transvulcania-et-bat-le-record-de-lepreuve\/\"},\"author\":{\"name\":\"Etienne Goursaud\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/d603dd7da31fb2b46c82b9835a77ec13\"},\"headline\":\"Blandine L&rsquo;Hirondel triomphe sur la Transvulcania et bat le record de l&rsquo;\u00e9preuve\",\"datePublished\":\"2026-05-09T17:45:36+00:00\",\"dateModified\":\"2026-05-09T20:00:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/blandine-lhirondel-triomphe-sur-la-transvulcania-et-bat-le-record-de-lepreuve\/\"},\"wordCount\":285,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/blandine-lhirondel-triomphe-sur-la-transvulcania-et-bat-le-record-de-lepreuve\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/05\/Blandine-LHirondel-triomphe-sur-la-Transvulcania-et-bat-le-record-de-lepreuve.png\",\"keywords\":[\"br\u00e8ve\",\"Course \u00e0 pied\",\"trail\"],\"articleSection\":[\"Trail\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/blandine-lhirondel-triomphe-sur-la-transvulcania-et-bat-le-record-de-lepreuve\/#respond\"]}],\"copyrightYear\":\"2026\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/blandine-lhirondel-triomphe-sur-la-transvulcania-et-bat-le-record-de-lepreuve\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/blandine-lhirondel-triomphe-sur-la-transvulcania-et-bat-le-record-de-lepreuve\/\",\"name\":\"Blandine L'Hirondel triomphe sur la Transvulcania et bat le record de l'\u00e9preuve\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/blandine-lhirondel-triomphe-sur-la-transvulcania-et-bat-le-record-de-lepreuve\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/blandine-lhirondel-triomphe-sur-la-transvulcania-et-bat-le-record-de-lepreuve\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/05\/Blandine-LHirondel-triomphe-sur-la-Transvulcania-et-bat-le-record-de-lepreuve.png\",\"datePublished\":\"2026-05-09T17:45:36+00:00\",\"dateModified\":\"2026-05-09T20:00:38+00:00\",\"description\":\"TRAIL - Blandine L'Hirondel a dompt\u00e9 les 75 km et 4240 m\u00e8tres de d\u00e9nivel\u00e9 positif et\u00a0remporte la Transvulcania 2026.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/blandine-lhirondel-triomphe-sur-la-transvulcania-et-bat-le-record-de-lepreuve\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/blandine-lhirondel-triomphe-sur-la-transvulcania-et-bat-le-record-de-lepreuve\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/blandine-lhirondel-triomphe-sur-la-transvulcania-et-bat-le-record-de-lepreuve\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/05\/Blandine-LHirondel-triomphe-sur-la-Transvulcania-et-bat-le-record-de-lepreuve.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/05\/Blandine-LHirondel-triomphe-sur-la-Transvulcania-et-bat-le-record-de-lepreuve.png\",\"width\":1200,\"height\":674,\"caption\":\"Blandine L'Hirondel triomphe sur la Transvulcania et bat le record de l'\u00e9preuve\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/blandine-lhirondel-triomphe-sur-la-transvulcania-et-bat-le-record-de-lepreuve\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Blandine L&rsquo;Hirondel triomphe sur la Transvulcania et bat le record de l&rsquo;\u00e9preuve\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/d603dd7da31fb2b46c82b9835a77ec13\",\"name\":\"Etienne Goursaud\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/410122264_10231602061736049_5565839791558026645_n-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/410122264_10231602061736049_5565839791558026645_n-150x150.jpg\",\"caption\":\"Etienne Goursaud\"},\"description\":\"Journaliste et amoureux de sport. Ancien footballeur reconverti athl\u00e8te quand ses muscles le laissent tranquille. \u00c9lev\u00e9 \u00e0 la sauce des exploits de Thomas Voeckler en 2004, du dernier essai de l\u00e9gende de Eunice Barber \u00e0 la longueur lors des championnats du monde d'athl\u00e9tisme de 2003 mais aussi Zidane, Omeyer et Titou Lamaison.\",\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/etienne-goursaud\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Blandine L'Hirondel triomphe sur la Transvulcania et bat le record de l'\u00e9preuve","description":"TRAIL - Blandine L'Hirondel a dompt\u00e9 les 75 km et 4240 m\u00e8tres de d\u00e9nivel\u00e9 positif et\u00a0remporte la Transvulcania 2026.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/blandine-lhirondel-triomphe-sur-la-transvulcania-et-bat-le-record-de-lepreuve\/","og_locale":"fr_FR","og_type":"article","og_title":"Blandine L'Hirondel triomphe sur la Transvulcania et bat le record de l'\u00e9preuve","og_description":"TRAIL - Blandine L'Hirondel a dompt\u00e9 les 75 km et 4240 m\u00e8tres de d\u00e9nivel\u00e9 positif et\u00a0remporte la Transvulcania 2026.","og_url":"https:\/\/dicodusport.fr\/blog\/blandine-lhirondel-triomphe-sur-la-transvulcania-et-bat-le-record-de-lepreuve\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2026-05-09T17:45:36+00:00","article_modified_time":"2026-05-09T20:00:38+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/05\/Blandine-LHirondel-triomphe-sur-la-Transvulcania-et-bat-le-record-de-lepreuve.png","type":"image\/png"}],"author":"Etienne Goursaud","twitter_card":"summary_large_image","twitter_title":"Blandine L'Hirondel triomphe sur la Transvulcania et bat le record de l'\u00e9preuve","twitter_creator":"@dicodusport","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/blandine-lhirondel-triomphe-sur-la-transvulcania-et-bat-le-record-de-lepreuve\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/blandine-lhirondel-triomphe-sur-la-transvulcania-et-bat-le-record-de-lepreuve\/"},"author":{"name":"Etienne Goursaud","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/d603dd7da31fb2b46c82b9835a77ec13"},"headline":"Blandine L&rsquo;Hirondel triomphe sur la Transvulcania et bat le record de l&rsquo;\u00e9preuve","datePublished":"2026-05-09T17:45:36+00:00","dateModified":"2026-05-09T20:00:38+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/blandine-lhirondel-triomphe-sur-la-transvulcania-et-bat-le-record-de-lepreuve\/"},"wordCount":285,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/blandine-lhirondel-triomphe-sur-la-transvulcania-et-bat-le-record-de-lepreuve\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/05\/Blandine-LHirondel-triomphe-sur-la-Transvulcania-et-bat-le-record-de-lepreuve.png","keywords":["br\u00e8ve","Course \u00e0 pied","trail"],"articleSection":["Trail"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/blandine-lhirondel-triomphe-sur-la-transvulcania-et-bat-le-record-de-lepreuve\/#respond"]}],"copyrightYear":"2026","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/blandine-lhirondel-triomphe-sur-la-transvulcania-et-bat-le-record-de-lepreuve\/","url":"https:\/\/dicodusport.fr\/blog\/blandine-lhirondel-triomphe-sur-la-transvulcania-et-bat-le-record-de-lepreuve\/","name":"Blandine L'Hirondel triomphe sur la Transvulcania et bat le record de l'\u00e9preuve","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/blandine-lhirondel-triomphe-sur-la-transvulcania-et-bat-le-record-de-lepreuve\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/blandine-lhirondel-triomphe-sur-la-transvulcania-et-bat-le-record-de-lepreuve\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/05\/Blandine-LHirondel-triomphe-sur-la-Transvulcania-et-bat-le-record-de-lepreuve.png","datePublished":"2026-05-09T17:45:36+00:00","dateModified":"2026-05-09T20:00:38+00:00","description":"TRAIL - Blandine L'Hirondel a dompt\u00e9 les 75 km et 4240 m\u00e8tres de d\u00e9nivel\u00e9 positif et\u00a0remporte la Transvulcania 2026.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/blandine-lhirondel-triomphe-sur-la-transvulcania-et-bat-le-record-de-lepreuve\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/blandine-lhirondel-triomphe-sur-la-transvulcania-et-bat-le-record-de-lepreuve\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/blandine-lhirondel-triomphe-sur-la-transvulcania-et-bat-le-record-de-lepreuve\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/05\/Blandine-LHirondel-triomphe-sur-la-Transvulcania-et-bat-le-record-de-lepreuve.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/05\/Blandine-LHirondel-triomphe-sur-la-Transvulcania-et-bat-le-record-de-lepreuve.png","width":1200,"height":674,"caption":"Blandine L'Hirondel triomphe sur la Transvulcania et bat le record de l'\u00e9preuve"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/blandine-lhirondel-triomphe-sur-la-transvulcania-et-bat-le-record-de-lepreuve\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Blandine L&rsquo;Hirondel triomphe sur la Transvulcania et bat le record de l&rsquo;\u00e9preuve"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/d603dd7da31fb2b46c82b9835a77ec13","name":"Etienne Goursaud","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/410122264_10231602061736049_5565839791558026645_n-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/410122264_10231602061736049_5565839791558026645_n-150x150.jpg","caption":"Etienne Goursaud"},"description":"Journaliste et amoureux de sport. Ancien footballeur reconverti athl\u00e8te quand ses muscles le laissent tranquille. \u00c9lev\u00e9 \u00e0 la sauce des exploits de Thomas Voeckler en 2004, du dernier essai de l\u00e9gende de Eunice Barber \u00e0 la longueur lors des championnats du monde d'athl\u00e9tisme de 2003 mais aussi Zidane, Omeyer et Titou Lamaison.","url":"https:\/\/dicodusport.fr\/blog\/author\/etienne-goursaud\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/669026","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/83"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=669026"}],"version-history":[{"count":5,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/669026\/revisions"}],"predecessor-version":[{"id":669089,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/669026\/revisions\/669089"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/669044"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=669026"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=669026"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=669026"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}