{"id":669735,"date":"2026-05-13T15:30:30","date_gmt":"2026-05-13T13:30:30","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=669735&#038;preview=true&#038;preview_id=669735"},"modified":"2026-05-13T13:46:26","modified_gmt":"2026-05-13T11:46:26","slug":"5e-etape-du-tour-ditalie-2026-giro-classement-et-resultats","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/5e-etape-du-tour-ditalie-2026-giro-classement-et-resultats\/","title":{"rendered":"5e \u00e9tape du Tour d\u2019Italie 2026 (Giro) : Classement et r\u00e9sultats"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><strong>GIRO &#8211; Qui a gagn\u00e9 la 5e \u00e9tape du Tour d&rsquo;Italie 2026 \u00e0 Potenza (204 km) ? Retrouvez les r\u00e9sultats complets et le classement.<\/strong><\/em><\/p>\n<ul>\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet \u2013 <a href=\"https:\/\/dicodusport.fr\/blog\/giro-classement-general-tour-ditalie-2026-mis-a-jour\/\">Tour d\u2019Italie 2026 : le classement g\u00e9n\u00e9ral du Giro mis \u00e0 jour apr\u00e8s chaque \u00e9tape<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Le <strong>Tour d\u2019Italie 2026<\/strong> poursuit sa route dans le sud de la p\u00e9ninsule avec une 5e \u00e9tape nerveuse et pi\u00e9geuse entre les reliefs de Basilicate. Apr\u00e8s <a href=\"https:\/\/dicodusport.fr\/blog\/jhonatan-narvaez-redonne-le-sourire-a-uae-team-emirates-xrg-en-raflant-la-quatrieme-etape-du-tour-ditalie\/\">le succ\u00e8s de <strong>Jhonatan Narvaez<\/strong> \u00e0 Cosenza mardi<\/a>, les puncheurs et favoris du classement g\u00e9n\u00e9ral auront une nouvelle occasion de se mettre en \u00e9vidence sur un terrain accident\u00e9. <strong>D\u00e9couvrez le parcours, le profil et les favoris de la 5e \u00e9tape du Giro 2026<\/strong>.<\/p>\n<h2 style=\"text-align: justify;\"><strong>Un final explosif vers Potenza<\/strong><\/h2>\n<p style=\"text-align: justify;\">Cette cinqui\u00e8me journ\u00e9e proposera un parcours usant, sans v\u00e9ritable temps mort, avec une succession de mont\u00e9es et de descentes dans l\u2019arri\u00e8re-pays italien. D\u00e8s les premiers kilom\u00e8tres, le peloton devra composer avec un terrain casse-pattes qui pourrait favoriser les offensives lointaines.<\/p>\n<p style=\"text-align: justify;\">Mais tout devrait se jouer dans le final, avec l\u2019ascension de la <strong>Montagna Grande de Viggiano<\/strong>, principale difficult\u00e9 du jour. Cette mont\u00e9e irr\u00e9guli\u00e8re, plac\u00e9e dans les derniers kilom\u00e8tres, pourrait cr\u00e9er des \u00e9carts entre les leaders du classement g\u00e9n\u00e9ral. Les \u00e9quipiers des favoris devront contr\u00f4ler la course pour \u00e9viter les attaques de loin et placer leurs leaders dans les meilleures conditions.<\/p>\n<p style=\"text-align: justify;\">Le maillot rose <strong>Giulio Ciccone<\/strong> aura notamment fort \u00e0 faire pour d\u00e9fendre sa tunique face aux pr\u00e9tendants au g\u00e9n\u00e9ral, sur une arriv\u00e9e qui semble parfaitement adapt\u00e9e aux grimpeurs explosifs.<\/p>\n<div class=\"vlp-link-container vlp-layout-article\"><a href=\"https:\/\/dicodusport.fr\/blog\/5e-etape-tour-ditalie-2026-giro-decouvrez-le-parcours-detaille-et-le-profil-explosif-vers-potenza\/\" class=\"vlp-link\" title=\"5e \u00e9tape Tour d\u2019Italie 2026 (Giro) : d\u00e9couvrez le parcours d\u00e9taill\u00e9 et le profil explosif vers Potenza\"><\/a><div class=\"vlp-layout-zone-side\"><div class=\"vlp-block-4 vlp-link-image\"><img loading=\"lazy\" decoding=\"async\" style=\"max-width: 792px;\" width=\"792\" height=\"445\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/05\/5e-etape-Tour-dItalie-2026-Giro-decouvrez-le-parcours-detaille-et-le-profil-explosif-vers-Potenza.png\" class=\"attachment-800x445 size-800x445\" alt=\"5e \u00e9tape Tour d\u2019Italie 2026 (Giro) d\u00e9couvrez le parcours d\u00e9taill\u00e9 et le profil explosif vers Potenza\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/05\/5e-etape-Tour-dItalie-2026-Giro-decouvrez-le-parcours-detaille-et-le-profil-explosif-vers-Potenza.png 1200w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/05\/5e-etape-Tour-dItalie-2026-Giro-decouvrez-le-parcours-detaille-et-le-profil-explosif-vers-Potenza-300x169.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/05\/5e-etape-Tour-dItalie-2026-Giro-decouvrez-le-parcours-detaille-et-le-profil-explosif-vers-Potenza-1024x575.png 1024w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/05\/5e-etape-Tour-dItalie-2026-Giro-decouvrez-le-parcours-detaille-et-le-profil-explosif-vers-Potenza-768x431.png 768w\" sizes=\"auto, (max-width: 792px) 100vw, 792px\" \/><\/div><\/div><div class=\"vlp-layout-zone-main\"><div class=\"vlp-block-0 vlp-link-title\">5e \u00e9tape Tour d\u2019Italie 2026 (Giro) : d\u00e9couvrez le parcours d\u00e9taill\u00e9 et le profil explosif vers Potenza<\/div><div class=\"vlp-block-1 vlp-link-summary\">Suivez le d\u00e9tail du parcours et le profil de la 5\u00e8me \u00e9tape du Tour d'Italie 2026 vers Potenza : trac\u00e9, difficult\u00e9 et analyse du parcours.<\/div><div class=\"vlp-block-2 vlp-link-button\">Lire l'article<\/div><div class=\"vlp-block-3 vlp-link-url\">dicodusport.fr<\/div><\/div><\/div>\n<h2 style=\"text-align: justify;\"><strong>Narvaez, Vingegaard et Ciccone parmi les favoris<\/strong><\/h2>\n<p style=\"text-align: justify;\">La victoire de <strong>Jhonatan Narvaez<\/strong> lors de la 4e \u00e9tape a totalement relanc\u00e9 la dynamique de l\u2019\u00e9quipe UAE Team Emirates-XRG. L\u2019\u00c9quatorien appara\u00eet encore comme l\u2019un des grands favoris du jour gr\u00e2ce \u00e0 sa capacit\u00e9 \u00e0 r\u00e9p\u00e9ter les efforts sur des mont\u00e9es courtes et explosives.<\/p>\n<p style=\"text-align: justify;\">Du c\u00f4t\u00e9 des outsiders, <strong>Christian Scaroni<\/strong> pourrait profiter d\u2019un sc\u00e9nario mouvement\u00e9 pour tenter sa chance. Tr\u00e8s offensif depuis le d\u00e9but du Giro, l\u2019Italien poss\u00e8de le profil id\u00e9al pour ce type d\u2019\u00e9tape vallonn\u00e9e.<\/p>\n<p style=\"text-align: justify;\">Si les favoris du classement g\u00e9n\u00e9ral d\u00e9cident de se livrer bataille dans l\u2019ascension finale, alors <strong>Jonas Vingegaard<\/strong> pourrait frapper un grand coup. Le Danois devra toutefois surveiller <strong>Jan Christen<\/strong>, tr\u00e8s solide depuis le d\u00e9part, ainsi que <strong>Giulio Ciccone<\/strong>, qui voudra briller devant le public italien en conservant son maillot rose.<\/p>\n<ul>\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet \u2013\u00a0<a href=\"https:\/\/dicodusport.fr\/blog\/tour-ditalie-2026-le-parcours-complet-et-le-profil-des-21-etapes-du-giro\/\">Tour d\u2019Italie 2026 : le parcours complet et le profil des 21 \u00e9tapes du Giro<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\"><strong>Arriv\u00e9e pr\u00e9vue sur les coups de 18h<\/strong><strong>, heure fran\u00e7aise.\u00a0<\/strong><\/p>\n<ul>\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet \u2013\u00a0<a href=\"https:\/\/dicodusport.fr\/blog\/actualites\/cyclisme\/\">L\u2019actualit\u00e9 du cyclisme<\/a><\/strong><\/li>\n<\/ul>\n<h2 style=\"text-align: justify;\">Giro : Le classement et les r\u00e9sultats de la 5e \u00e9tape du Tour d&rsquo;Italie 2026<\/h2>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14px;\"><strong><em>Classement officiel mis \u00e0 jour \u00e0 l&rsquo;issue de l&rsquo;\u00e9tape.<\/em><\/strong><\/span><\/p>\n<div class=\"su-table su-table-alternate\">\n<table style=\"width: 800px;border-collapse: collapse\" border=\"1\">\n<tbody>\n<tr style=\"height: 24px\">\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 80px;vertical-align: middle\">\ud83c\udfc6<\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>COUREURS<\/strong><\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>TEMPS \/ \u00c9CART<\/strong><\/span><\/td>\n<\/tr>\n<tr style=\"height: 24px\">\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 80px;vertical-align: middle\"><strong><span class=\"su-label su-label-type-warning\">1.<\/span><\/strong><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">2.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">3.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">4.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">5.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">6.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">7.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">8.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">9.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">10.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">11.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">12.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">13.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">14.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">15.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">16.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">17.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">18.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">19.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">20.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<h3>\u00c0 ce sujet<\/h3>\n<ul>\n<li style=\"text-align: justify;\"><a href=\"https:\/\/www.procyclingstats.com\/race\/giro-d-italia\/2026\/stage-5\/result\"><strong>Le classement complet de la 5e \u00e9tape<\/strong><\/a><\/li>\n<\/ul>\n<div class=\"vlp-link-container vlp-layout-article\"><a href=\"https:\/\/dicodusport.fr\/blog\/mercato-cyclisme-2026-2027-le-tableau-des-transferts-mis-a-jour\/\" class=\"vlp-link\" title=\"Mercato Cyclisme 2026-2027 - Le tableau des transferts mis \u00e0 jour\"><\/a><div class=\"vlp-layout-zone-side\"><div class=\"vlp-block-4 vlp-link-image\"><img loading=\"lazy\" decoding=\"async\" style=\"max-width: 792px;\" width=\"792\" height=\"445\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/03\/Mercato-Cyclisme-2026-2027-Le-tableau-des-transferts-mis-a-jour.png\" class=\"attachment-800x445 size-800x445\" alt=\"Mercato Cyclisme 2026-2027 Le tableau des transferts mis \u00e0 jour\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/03\/Mercato-Cyclisme-2026-2027-Le-tableau-des-transferts-mis-a-jour.png 1200w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/03\/Mercato-Cyclisme-2026-2027-Le-tableau-des-transferts-mis-a-jour-300x169.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/03\/Mercato-Cyclisme-2026-2027-Le-tableau-des-transferts-mis-a-jour-1024x575.png 1024w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/03\/Mercato-Cyclisme-2026-2027-Le-tableau-des-transferts-mis-a-jour-768x431.png 768w\" sizes=\"auto, (max-width: 792px) 100vw, 792px\" \/><\/div><\/div><div class=\"vlp-layout-zone-main\"><div class=\"vlp-block-0 vlp-link-title\">Mercato Cyclisme 2026-2027 - Le tableau des transferts mis \u00e0 jour<\/div><div class=\"vlp-block-1 vlp-link-summary\">Mercato cyclisme 2026-2027 : retrouvez le tableau complet des transferts, prolongations et rumeurs du peloton. Tous les mouvements des \u00e9quipes WorldTeams et principales ProTeams en temps r\u00e9el.<\/div><div class=\"vlp-block-2 vlp-link-button\">Lire l'article<\/div><div class=\"vlp-block-3 vlp-link-url\">dicodusport.fr<\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>GIRO &#8211; Qui a gagn\u00e9 la 5e \u00e9tape du Tour d&rsquo;Italie 2026 \u00e0 Potenza (204 km) ? Retrouvez les r\u00e9sultats complets et le classement.<\/p>\n","protected":false},"author":4,"featured_media":669737,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[47041],"tags":[32415,16878,574,11197,2830,4722],"class_list":["post-669735","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tour-d-italie","tag-actu","tag-breve","tag-cyclisme","tag-cyclisme-sur-route","tag-giro","tag-tour-ditalie"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>5e \u00e9tape du Tour d\u2019Italie 2026 (Giro) : Classement et r\u00e9sultats<\/title>\n<meta name=\"description\" content=\"GIRO - Qui a gagn\u00e9 la 5e \u00e9tape du Tour d&#039;Italie 2026 \u00e0 Potenza (204 km) ? Retrouvez les r\u00e9sultats complets et le classement.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/5e-etape-du-tour-ditalie-2026-giro-classement-et-resultats\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Giro : Qui a gagn\u00e9 la 5e \u00e9tape du Tour d&#039;Italie 2026 ? Classement et r\u00e9sultats complets\" \/>\n<meta property=\"og:description\" content=\"GIRO - Qui a gagn\u00e9 la 5e \u00e9tape du Tour d&#039;Italie 2026 \u00e0 Potenza (204 km) ? Retrouvez les r\u00e9sultats complets et le classement.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/5e-etape-du-tour-ditalie-2026-giro-classement-et-resultats\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/florent.ostermann\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-13T13:30:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/05\/5e-etape-du-Tour-dItalie-2026-Giro-Classement-et-resultats.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Flo Ostermann\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Giro : Qui a gagn\u00e9 la 5e \u00e9tape du Tour d&#039;Italie 2026 ? Classement et r\u00e9sultats complets\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/FlOstermann\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/5e-etape-du-tour-ditalie-2026-giro-classement-et-resultats\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/5e-etape-du-tour-ditalie-2026-giro-classement-et-resultats\/\"},\"author\":{\"name\":\"Flo Ostermann\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a\"},\"headline\":\"5e \u00e9tape du Tour d\u2019Italie 2026 (Giro) : Classement et r\u00e9sultats\",\"datePublished\":\"2026-05-13T13:30:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/5e-etape-du-tour-ditalie-2026-giro-classement-et-resultats\/\"},\"wordCount\":722,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/5e-etape-du-tour-ditalie-2026-giro-classement-et-resultats\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/05\/5e-etape-du-Tour-dItalie-2026-Giro-Classement-et-resultats.png\",\"keywords\":[\"actu\",\"br\u00e8ve\",\"Cyclisme\",\"Cyclisme sur route\",\"Giro\",\"Tour d'Italie\"],\"articleSection\":[\"Tour d'Italie\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/5e-etape-du-tour-ditalie-2026-giro-classement-et-resultats\/#respond\"]}],\"copyrightYear\":\"2026\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/5e-etape-du-tour-ditalie-2026-giro-classement-et-resultats\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/5e-etape-du-tour-ditalie-2026-giro-classement-et-resultats\/\",\"name\":\"5e \u00e9tape du Tour d\u2019Italie 2026 (Giro) : Classement et r\u00e9sultats\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/5e-etape-du-tour-ditalie-2026-giro-classement-et-resultats\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/5e-etape-du-tour-ditalie-2026-giro-classement-et-resultats\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/05\/5e-etape-du-Tour-dItalie-2026-Giro-Classement-et-resultats.png\",\"datePublished\":\"2026-05-13T13:30:30+00:00\",\"description\":\"GIRO - Qui a gagn\u00e9 la 5e \u00e9tape du Tour d'Italie 2026 \u00e0 Potenza (204 km) ? Retrouvez les r\u00e9sultats complets et le classement.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/5e-etape-du-tour-ditalie-2026-giro-classement-et-resultats\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/5e-etape-du-tour-ditalie-2026-giro-classement-et-resultats\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/5e-etape-du-tour-ditalie-2026-giro-classement-et-resultats\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/05\/5e-etape-du-Tour-dItalie-2026-Giro-Classement-et-resultats.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/05\/5e-etape-du-Tour-dItalie-2026-Giro-Classement-et-resultats.png\",\"width\":1200,\"height\":674,\"caption\":\"5e \u00e9tape du Tour d\u2019Italie 2026 (Giro) Classement et r\u00e9sultats\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/5e-etape-du-tour-ditalie-2026-giro-classement-et-resultats\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"5e \u00e9tape du Tour d\u2019Italie 2026 (Giro) : Classement et r\u00e9sultats\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a\",\"name\":\"Flo Ostermann\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg\",\"caption\":\"Flo Ostermann\"},\"description\":\"Journaliste\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !\",\"sameAs\":[\"https:\/\/www.facebook.com\/florent.ostermann\",\"https:\/\/x.com\/https:\/\/twitter.com\/FlOstermann\",\"admin\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/flo\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"5e \u00e9tape du Tour d\u2019Italie 2026 (Giro) : Classement et r\u00e9sultats","description":"GIRO - Qui a gagn\u00e9 la 5e \u00e9tape du Tour d'Italie 2026 \u00e0 Potenza (204 km) ? Retrouvez les r\u00e9sultats complets et le classement.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/5e-etape-du-tour-ditalie-2026-giro-classement-et-resultats\/","og_locale":"fr_FR","og_type":"article","og_title":"Giro : Qui a gagn\u00e9 la 5e \u00e9tape du Tour d'Italie 2026 ? Classement et r\u00e9sultats complets","og_description":"GIRO - Qui a gagn\u00e9 la 5e \u00e9tape du Tour d'Italie 2026 \u00e0 Potenza (204 km) ? Retrouvez les r\u00e9sultats complets et le classement.","og_url":"https:\/\/dicodusport.fr\/blog\/5e-etape-du-tour-ditalie-2026-giro-classement-et-resultats\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/florent.ostermann","article_published_time":"2026-05-13T13:30:30+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/05\/5e-etape-du-Tour-dItalie-2026-Giro-Classement-et-resultats.png","type":"image\/png"}],"author":"Flo Ostermann","twitter_card":"summary_large_image","twitter_title":"Giro : Qui a gagn\u00e9 la 5e \u00e9tape du Tour d'Italie 2026 ? Classement et r\u00e9sultats complets","twitter_creator":"@https:\/\/twitter.com\/FlOstermann","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/5e-etape-du-tour-ditalie-2026-giro-classement-et-resultats\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/5e-etape-du-tour-ditalie-2026-giro-classement-et-resultats\/"},"author":{"name":"Flo Ostermann","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a"},"headline":"5e \u00e9tape du Tour d\u2019Italie 2026 (Giro) : Classement et r\u00e9sultats","datePublished":"2026-05-13T13:30:30+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/5e-etape-du-tour-ditalie-2026-giro-classement-et-resultats\/"},"wordCount":722,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/5e-etape-du-tour-ditalie-2026-giro-classement-et-resultats\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/05\/5e-etape-du-Tour-dItalie-2026-Giro-Classement-et-resultats.png","keywords":["actu","br\u00e8ve","Cyclisme","Cyclisme sur route","Giro","Tour d'Italie"],"articleSection":["Tour d'Italie"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/5e-etape-du-tour-ditalie-2026-giro-classement-et-resultats\/#respond"]}],"copyrightYear":"2026","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/5e-etape-du-tour-ditalie-2026-giro-classement-et-resultats\/","url":"https:\/\/dicodusport.fr\/blog\/5e-etape-du-tour-ditalie-2026-giro-classement-et-resultats\/","name":"5e \u00e9tape du Tour d\u2019Italie 2026 (Giro) : Classement et r\u00e9sultats","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/5e-etape-du-tour-ditalie-2026-giro-classement-et-resultats\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/5e-etape-du-tour-ditalie-2026-giro-classement-et-resultats\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/05\/5e-etape-du-Tour-dItalie-2026-Giro-Classement-et-resultats.png","datePublished":"2026-05-13T13:30:30+00:00","description":"GIRO - Qui a gagn\u00e9 la 5e \u00e9tape du Tour d'Italie 2026 \u00e0 Potenza (204 km) ? Retrouvez les r\u00e9sultats complets et le classement.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/5e-etape-du-tour-ditalie-2026-giro-classement-et-resultats\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/5e-etape-du-tour-ditalie-2026-giro-classement-et-resultats\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/5e-etape-du-tour-ditalie-2026-giro-classement-et-resultats\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/05\/5e-etape-du-Tour-dItalie-2026-Giro-Classement-et-resultats.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/05\/5e-etape-du-Tour-dItalie-2026-Giro-Classement-et-resultats.png","width":1200,"height":674,"caption":"5e \u00e9tape du Tour d\u2019Italie 2026 (Giro) Classement et r\u00e9sultats"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/5e-etape-du-tour-ditalie-2026-giro-classement-et-resultats\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"5e \u00e9tape du Tour d\u2019Italie 2026 (Giro) : Classement et r\u00e9sultats"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a","name":"Flo Ostermann","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","caption":"Flo Ostermann"},"description":"Journaliste\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !","sameAs":["https:\/\/www.facebook.com\/florent.ostermann","https:\/\/x.com\/https:\/\/twitter.com\/FlOstermann","admin"],"url":"https:\/\/dicodusport.fr\/blog\/author\/flo\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/669735","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=669735"}],"version-history":[{"count":2,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/669735\/revisions"}],"predecessor-version":[{"id":669738,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/669735\/revisions\/669738"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/669737"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=669735"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=669735"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=669735"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}