{"id":669743,"date":"2026-05-13T14:08:21","date_gmt":"2026-05-13T12:08:21","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=669743&#038;preview=true&#038;preview_id=669743"},"modified":"2026-05-13T14:08:21","modified_gmt":"2026-05-13T12:08:21","slug":"classement-general-tour-de-hongrie-2026-mis-a-jour","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/classement-general-tour-de-hongrie-2026-mis-a-jour\/","title":{"rendered":"Classement g\u00e9n\u00e9ral Tour de Hongrie 2026 mis \u00e0 jour"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><strong>Retrouvez le classement g\u00e9n\u00e9ral du Tour de Hongrie 2026 mis \u00e0 jour : position des favoris et \u00e9carts entre les leaders.<\/strong><\/em><\/p>\n<ul>\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet \u2013\u00a0<a href=\"https:\/\/dicodusport.fr\/blog\/tour-de-hongrie-2026-a-quelle-heure-et-sur-quelle-chaine-tv-regarder-la-course\/\">Tour de Hongrie 2026 : \u00e0 quelle heure et sur quelle cha\u00eene TV regarder la course ?<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Le <strong>Tour de Hongrie 2026<\/strong> se d\u00e9roule du 13 au 17 mai avec cinq \u00e9tapes au programme \u00e0 travers les routes hongroises. Entre arriv\u00e9es promises aux sprinteurs, finales vallonn\u00e9es et \u00e9tapes plus exigeantes pour les puncheurs, cette 47e \u00e9dition promet une bataille serr\u00e9e pour le <strong>classement g\u00e9n\u00e9ral du Tour de Hongrie 2026<\/strong>. Retrouvez le classement g\u00e9n\u00e9ral mis \u00e0 jour, les \u00e9carts entre les leaders et la position des principaux favoris de l\u2019\u00e9preuve.<\/p>\n<p style=\"text-align: justify;\">Le parcours devrait offrir plusieurs sc\u00e9narios diff\u00e9rents. Les deux premi\u00e8res \u00e9tapes semblent promises aux hommes rapides avec notamment un terrain favorable \u00e0 <strong>Tim Merlier<\/strong>. En revanche, les troisi\u00e8me, quatri\u00e8me et cinqui\u00e8me journ\u00e9es pourraient d\u00e9j\u00e0 cr\u00e9er des \u00e9carts avec des arriv\u00e9es plus exigeantes et plusieurs ascensions capables de faire exploser le peloton.<\/p>\n<div class=\"vlp-link-container vlp-layout-article\"><a href=\"https:\/\/dicodusport.fr\/blog\/tour-de-hongrie-2026-le-parcours-complet-et-le-profil-des-5-etapes\/\" class=\"vlp-link\" title=\"Tour de Hongrie 2026 : le parcours complet et le profil des 5 \u00e9tapes\"><\/a><div class=\"vlp-layout-zone-side\"><div class=\"vlp-block-4 vlp-link-image\"><img loading=\"lazy\" decoding=\"async\" style=\"max-width: 792px;\" width=\"792\" height=\"445\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/05\/Tour-de-Hongrie-2026-le-parcours-complet-et-le-profil-des-5-etapes.png\" class=\"attachment-800x445 size-800x445\" alt=\"\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/05\/Tour-de-Hongrie-2026-le-parcours-complet-et-le-profil-des-5-etapes.png 1200w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/05\/Tour-de-Hongrie-2026-le-parcours-complet-et-le-profil-des-5-etapes-300x169.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/05\/Tour-de-Hongrie-2026-le-parcours-complet-et-le-profil-des-5-etapes-1024x575.png 1024w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/05\/Tour-de-Hongrie-2026-le-parcours-complet-et-le-profil-des-5-etapes-768x431.png 768w\" sizes=\"auto, (max-width: 792px) 100vw, 792px\" \/><\/div><\/div><div class=\"vlp-layout-zone-main\"><div class=\"vlp-block-0 vlp-link-title\">Tour de Hongrie 2026 : le parcours complet et le profil des 5 \u00e9tapes<\/div><div class=\"vlp-block-1 vlp-link-summary\">D\u00e9couvrez le d\u00e9tail du parcours et le profil de la 47\u00e8me \u00e9dition du Tour de Hongrie : trac\u00e9 et difficult\u00e9s des \u00e9tapes, qui se d\u00e9roule du mercredi 13 au dimanche 17 mars 2026.<\/div><div class=\"vlp-block-2 vlp-link-button\">Lire l'article<\/div><div class=\"vlp-block-3 vlp-link-url\">dicodusport.fr<\/div><\/div><\/div>\n<h2 style=\"text-align: justify;\">Tour de Hongrie 2026 : les favoris du classement g\u00e9n\u00e9ral<\/h2>\n<p style=\"text-align: justify;\">Parmi les grands favoris de cette \u00e9dition, <a href=\"https:\/\/dicodusport.fr\/blog\/tag\/benoit-cosnefroy\/\"><strong>Beno\u00eet Cosnefroy<\/strong><\/a> appara\u00eet comme l\u2019un des hommes les plus attendus. Le Fran\u00e7ais arrive en confiance apr\u00e8s une campagne des classiques ardennaises r\u00e9ussie et pourrait profiter des arriv\u00e9es vallonn\u00e9es pour faire parler son explosivit\u00e9.<\/p>\n<p style=\"text-align: justify;\">La formation Jayco AlUla comptera \u00e9galement plusieurs cartes solides avec <strong>Luke Plapp<\/strong> et <strong>Paul Double<\/strong>. L\u2019Australien semble particuli\u00e8rement arm\u00e9 pour les \u00e9tapes les plus difficiles et pourrait faire la diff\u00e9rence dans les ascensions finales. Derri\u00e8re eux, des coureurs comme <strong>Jakob Omrzel<\/strong>, <strong>William Junior Lecerf<\/strong> ou encore <strong>Attila Valter<\/strong> auront aussi de belles ambitions pour le classement g\u00e9n\u00e9ral.<\/p>\n<ul>\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet \u2013\u00a0<a href=\"https:\/\/dicodusport.fr\/blog\/tour-de-hongrie-2026-les-favoris-et-la-liste-des-engages\/\">Tour de Hongrie 2026 : les favoris et la liste des engag\u00e9s<\/a><\/strong><\/li>\n<\/ul>\n<h2 style=\"text-align: justify;\">Un classement g\u00e9n\u00e9ral qui pourrait rester serr\u00e9 jusqu\u2019au bout<\/h2>\n<p style=\"text-align: justify;\">Avec seulement cinq \u00e9tapes et plusieurs profils tr\u00e8s diff\u00e9rents, le Tour de Hongrie 2026 pourrait se jouer \u00e0 quelques secondes. Les bonifications devraient avoir une importance majeure, notamment lors des arriv\u00e9es au sprint et des finals punchy. Les \u00e9carts risquent donc de rester faibles avant les deux derni\u00e8res \u00e9tapes, annonc\u00e9es comme les plus d\u00e9cisives pour la victoire finale.<\/p>\n<p style=\"text-align: justify;\">Cette \u00e9dition r\u00e9unit \u00e9galement plusieurs formations WorldTour et un plateau dense, ce qui devrait offrir une course nerveuse et ouverte jusqu\u2019\u00e0 l\u2019arriv\u00e9e finale \u00e0 Veszpr\u00e9m.<\/p>\n<ul>\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet \u2013\u00a0<a href=\"https:\/\/dicodusport.fr\/blog\/actualites\/cyclisme\/\">L\u2019actualit\u00e9 du cyclisme<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\"><strong>Retrouvez le top 10 du classement g\u00e9n\u00e9ral du Tour de Hongrie 2026 ci-dessous.<\/strong><\/p>\n<h2 style=\"text-align: justify;\">Le classement g\u00e9n\u00e9ral du Tour de Hongrie 2026 actualis\u00e9<\/h2>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14px;\"><strong><em>Classement g\u00e9n\u00e9ral officiel mis \u00e0 jour \u00e0 l\u2019issue de la 1re \u00e9tape.<\/em><\/strong><\/span><\/p>\n<div class=\"su-table su-table-alternate\">\n<table style=\"width: 800px;border-collapse: collapse\" border=\"1\">\n<tbody>\n<tr style=\"height: 24px\">\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 80px;vertical-align: middle\">\ud83c\udfc6<\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>COUREURS<\/strong><\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>TEMPS \/ \u00c9CART<\/strong><\/span><\/td>\n<\/tr>\n<tr style=\"height: 24px\">\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 80px;vertical-align: middle\"><strong><span class=\"su-label su-label-type-warning\">1.<\/span><\/strong><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">2.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">3.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">4.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">5.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">6.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">7.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">8.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">9.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">10.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">11.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">12.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">13.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">14.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">15.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">16.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">17.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">18.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">19.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">20.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<h3>\u00c0 ce sujet<\/h3>\n<ul>\n<li style=\"text-align: justify;\"><strong>Le classement g\u00e9n\u00e9ral complet (\u00e0 venir)<\/strong><\/li>\n<\/ul>\n<div class=\"vlp-link-container vlp-layout-article\"><a href=\"https:\/\/dicodusport.fr\/blog\/mercato-cyclisme-2026-2027-le-tableau-des-transferts-mis-a-jour\/\" class=\"vlp-link\" title=\"Mercato Cyclisme 2026-2027 - Le tableau des transferts mis \u00e0 jour\"><\/a><div class=\"vlp-layout-zone-side\"><div class=\"vlp-block-4 vlp-link-image\"><img loading=\"lazy\" decoding=\"async\" style=\"max-width: 792px;\" width=\"792\" height=\"445\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/03\/Mercato-Cyclisme-2026-2027-Le-tableau-des-transferts-mis-a-jour.png\" class=\"attachment-800x445 size-800x445\" alt=\"Mercato Cyclisme 2026-2027 Le tableau des transferts mis \u00e0 jour\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/03\/Mercato-Cyclisme-2026-2027-Le-tableau-des-transferts-mis-a-jour.png 1200w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/03\/Mercato-Cyclisme-2026-2027-Le-tableau-des-transferts-mis-a-jour-300x169.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/03\/Mercato-Cyclisme-2026-2027-Le-tableau-des-transferts-mis-a-jour-1024x575.png 1024w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/03\/Mercato-Cyclisme-2026-2027-Le-tableau-des-transferts-mis-a-jour-768x431.png 768w\" sizes=\"auto, (max-width: 792px) 100vw, 792px\" \/><\/div><\/div><div class=\"vlp-layout-zone-main\"><div class=\"vlp-block-0 vlp-link-title\">Mercato Cyclisme 2026-2027 - Le tableau des transferts mis \u00e0 jour<\/div><div class=\"vlp-block-1 vlp-link-summary\">Mercato cyclisme 2026-2027 : retrouvez le tableau complet des transferts, prolongations et rumeurs du peloton. Tous les mouvements des \u00e9quipes WorldTeams et principales ProTeams en temps r\u00e9el.<\/div><div class=\"vlp-block-2 vlp-link-button\">Lire l'article<\/div><div class=\"vlp-block-3 vlp-link-url\">dicodusport.fr<\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Retrouvez le classement g\u00e9n\u00e9ral du Tour de Hongrie 2026 mis \u00e0 jour : position des favoris et \u00e9carts entre les leaders.<\/p>\n","protected":false},"author":4,"featured_media":669747,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[46994],"tags":[32415,16878,574,11197,23414],"class_list":["post-669743","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cyclisme-sur-route","tag-actu","tag-breve","tag-cyclisme","tag-cyclisme-sur-route","tag-tour-de-hongrie"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Classement g\u00e9n\u00e9ral Tour de Hongrie 2026 mis \u00e0 jour<\/title>\n<meta name=\"description\" content=\"Retrouvez le classement g\u00e9n\u00e9ral du Tour de Hongrie 2026 mis \u00e0 jour : position des favoris et \u00e9carts entre les leaders.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/classement-general-tour-de-hongrie-2026-mis-a-jour\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Classement g\u00e9n\u00e9ral Tour de Hongrie 2026 mis \u00e0 jour\" \/>\n<meta property=\"og:description\" content=\"Retrouvez le classement g\u00e9n\u00e9ral du Tour de Hongrie 2026 mis \u00e0 jour : position des favoris et \u00e9carts entre les leaders.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/classement-general-tour-de-hongrie-2026-mis-a-jour\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/florent.ostermann\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-13T12:08:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/05\/Classement-general-Tour-de-Hongrie-2026-mis-a-jour.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Flo Ostermann\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/FlOstermann\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/classement-general-tour-de-hongrie-2026-mis-a-jour\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/classement-general-tour-de-hongrie-2026-mis-a-jour\/\"},\"author\":{\"name\":\"Flo Ostermann\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a\"},\"headline\":\"Classement g\u00e9n\u00e9ral Tour de Hongrie 2026 mis \u00e0 jour\",\"datePublished\":\"2026-05-13T12:08:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/classement-general-tour-de-hongrie-2026-mis-a-jour\/\"},\"wordCount\":678,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/classement-general-tour-de-hongrie-2026-mis-a-jour\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/05\/Classement-general-Tour-de-Hongrie-2026-mis-a-jour.png\",\"keywords\":[\"actu\",\"br\u00e8ve\",\"Cyclisme\",\"Cyclisme sur route\",\"Tour de Hongrie\"],\"articleSection\":[\"Cyclisme sur route\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/classement-general-tour-de-hongrie-2026-mis-a-jour\/#respond\"]}],\"copyrightYear\":\"2026\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/classement-general-tour-de-hongrie-2026-mis-a-jour\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/classement-general-tour-de-hongrie-2026-mis-a-jour\/\",\"name\":\"Classement g\u00e9n\u00e9ral Tour de Hongrie 2026 mis \u00e0 jour\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/classement-general-tour-de-hongrie-2026-mis-a-jour\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/classement-general-tour-de-hongrie-2026-mis-a-jour\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/05\/Classement-general-Tour-de-Hongrie-2026-mis-a-jour.png\",\"datePublished\":\"2026-05-13T12:08:21+00:00\",\"description\":\"Retrouvez le classement g\u00e9n\u00e9ral du Tour de Hongrie 2026 mis \u00e0 jour : position des favoris et \u00e9carts entre les leaders.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/classement-general-tour-de-hongrie-2026-mis-a-jour\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/classement-general-tour-de-hongrie-2026-mis-a-jour\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/classement-general-tour-de-hongrie-2026-mis-a-jour\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/05\/Classement-general-Tour-de-Hongrie-2026-mis-a-jour.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/05\/Classement-general-Tour-de-Hongrie-2026-mis-a-jour.png\",\"width\":1200,\"height\":674,\"caption\":\"Classement g\u00e9n\u00e9ral Tour de Hongrie 2026 mis \u00e0 jour\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/classement-general-tour-de-hongrie-2026-mis-a-jour\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Classement g\u00e9n\u00e9ral Tour de Hongrie 2026 mis \u00e0 jour\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a\",\"name\":\"Flo Ostermann\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg\",\"caption\":\"Flo Ostermann\"},\"description\":\"Journaliste\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !\",\"sameAs\":[\"https:\/\/www.facebook.com\/florent.ostermann\",\"https:\/\/x.com\/https:\/\/twitter.com\/FlOstermann\",\"admin\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/flo\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Classement g\u00e9n\u00e9ral Tour de Hongrie 2026 mis \u00e0 jour","description":"Retrouvez le classement g\u00e9n\u00e9ral du Tour de Hongrie 2026 mis \u00e0 jour : position des favoris et \u00e9carts entre les leaders.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/classement-general-tour-de-hongrie-2026-mis-a-jour\/","og_locale":"fr_FR","og_type":"article","og_title":"Classement g\u00e9n\u00e9ral Tour de Hongrie 2026 mis \u00e0 jour","og_description":"Retrouvez le classement g\u00e9n\u00e9ral du Tour de Hongrie 2026 mis \u00e0 jour : position des favoris et \u00e9carts entre les leaders.","og_url":"https:\/\/dicodusport.fr\/blog\/classement-general-tour-de-hongrie-2026-mis-a-jour\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/florent.ostermann","article_published_time":"2026-05-13T12:08:21+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/05\/Classement-general-Tour-de-Hongrie-2026-mis-a-jour.png","type":"image\/png"}],"author":"Flo Ostermann","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/FlOstermann","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/classement-general-tour-de-hongrie-2026-mis-a-jour\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/classement-general-tour-de-hongrie-2026-mis-a-jour\/"},"author":{"name":"Flo Ostermann","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a"},"headline":"Classement g\u00e9n\u00e9ral Tour de Hongrie 2026 mis \u00e0 jour","datePublished":"2026-05-13T12:08:21+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/classement-general-tour-de-hongrie-2026-mis-a-jour\/"},"wordCount":678,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/classement-general-tour-de-hongrie-2026-mis-a-jour\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/05\/Classement-general-Tour-de-Hongrie-2026-mis-a-jour.png","keywords":["actu","br\u00e8ve","Cyclisme","Cyclisme sur route","Tour de Hongrie"],"articleSection":["Cyclisme sur route"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/classement-general-tour-de-hongrie-2026-mis-a-jour\/#respond"]}],"copyrightYear":"2026","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/classement-general-tour-de-hongrie-2026-mis-a-jour\/","url":"https:\/\/dicodusport.fr\/blog\/classement-general-tour-de-hongrie-2026-mis-a-jour\/","name":"Classement g\u00e9n\u00e9ral Tour de Hongrie 2026 mis \u00e0 jour","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/classement-general-tour-de-hongrie-2026-mis-a-jour\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/classement-general-tour-de-hongrie-2026-mis-a-jour\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/05\/Classement-general-Tour-de-Hongrie-2026-mis-a-jour.png","datePublished":"2026-05-13T12:08:21+00:00","description":"Retrouvez le classement g\u00e9n\u00e9ral du Tour de Hongrie 2026 mis \u00e0 jour : position des favoris et \u00e9carts entre les leaders.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/classement-general-tour-de-hongrie-2026-mis-a-jour\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/classement-general-tour-de-hongrie-2026-mis-a-jour\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/classement-general-tour-de-hongrie-2026-mis-a-jour\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/05\/Classement-general-Tour-de-Hongrie-2026-mis-a-jour.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/05\/Classement-general-Tour-de-Hongrie-2026-mis-a-jour.png","width":1200,"height":674,"caption":"Classement g\u00e9n\u00e9ral Tour de Hongrie 2026 mis \u00e0 jour"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/classement-general-tour-de-hongrie-2026-mis-a-jour\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Classement g\u00e9n\u00e9ral Tour de Hongrie 2026 mis \u00e0 jour"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a","name":"Flo Ostermann","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","caption":"Flo Ostermann"},"description":"Journaliste\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !","sameAs":["https:\/\/www.facebook.com\/florent.ostermann","https:\/\/x.com\/https:\/\/twitter.com\/FlOstermann","admin"],"url":"https:\/\/dicodusport.fr\/blog\/author\/flo\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/669743","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=669743"}],"version-history":[{"count":1,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/669743\/revisions"}],"predecessor-version":[{"id":669746,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/669743\/revisions\/669746"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/669747"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=669743"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=669743"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=669743"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}