{"id":672364,"date":"2026-05-23T21:20:23","date_gmt":"2026-05-23T19:20:23","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=672364&#038;preview=true&#038;preview_id=672364"},"modified":"2026-05-23T22:30:20","modified_gmt":"2026-05-23T20:30:20","slug":"le-montpellier-hb-soffre-sa-quinzieme-coupe-de-france-en-dominant-nantes","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/le-montpellier-hb-soffre-sa-quinzieme-coupe-de-france-en-dominant-nantes\/","title":{"rendered":"Le Montpellier Handball s&rsquo;offre sa quinzi\u00e8me Coupe de France en dominant Nantes"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>COUPE DE FRANCE DE HANDBALL &#8211; Au terme d&rsquo;une finale monumentale, c&rsquo;est le Montpellier Handball qui triomphe, remportant ainsi son quinzi\u00e8me troph\u00e9e dans la comp\u00e9tition (27-24).<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Qui de Nantes, deuxi\u00e8me du championnat et triple vainqueur de la comp\u00e9tition, ou de Montpellier, quatorze fois champion et actuel troisi\u00e8me de Starligue, ajoutera une ligne \u00e0 son palmar\u00e8s ?<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Si, du c\u00f4t\u00e9 h\u00e9raultais, le groupe est au complet, du c\u00f4t\u00e9 du <\/span><strong>HBC Nantes<\/strong><span style=\"font-weight: 400;\">, le grand absent du soir se nomme <\/span><strong>Thibaud Briet<\/strong><span style=\"font-weight: 400;\">. En lice pour le titre de meilleur arri\u00e8re gauche et de meilleur d\u00e9fenseur du championnat, sa densit\u00e9 physique risque de manquer cruellement au H.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Quel d\u00e9but de match ! Avec six buts, dont quatre inscrits sur les ailes en moins de cinq minutes, les deux formations ne perdent pas de temps avant de s\u2019\u00e9changer des coups. En tribunes, les supporters des deux \u00e9quipes se r\u00e9pondent d\u2019un bout \u00e0 l\u2019autre du terrain. Le poids du public aura clairement son importance. <\/span><strong>Nantes<\/strong><span style=\"font-weight: 400;\"> subit dans ce premier quart d\u2019heure. Se mettant deux fois \u00e0 la faute en d\u00e9fense, <\/span><strong>Romain Lagarde<\/strong><span style=\"font-weight: 400;\"> offre deux penalties aux Montpelli\u00e9rains, qui prennent un petit avantage de deux buts (<\/span><strong>7-5, 9\u2019<\/strong><span style=\"font-weight: 400;\">).<\/span><\/p>\n<blockquote>\n<p style=\"text-align: justify;\"><em>Je ne suis pas content de ce qu&rsquo;on a produit. On a fait \u00e9norm\u00e9ment de fautes techniques, on a perdu \u00e9norm\u00e9ment de ballons, on s&rsquo;est trop pr\u00e9cipit\u00e9s.<\/em>\u00a0(Gr\u00e9gory Cojean, coach du HBC Nantes)<\/p>\n<\/blockquote>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Pour essayer de relancer la machine, <\/span><strong>Gr\u00e9gory Cojean<\/strong><span style=\"font-weight: 400;\"> effectue ses premi\u00e8res rotations en faisant entrer <\/span><strong>Julien Bos<\/strong><span style=\"font-weight: 400;\">, <\/span><strong>Rok Ovni\u010dek<\/strong><span style=\"font-weight: 400;\"> et <\/span><strong>Ian Tarrafeta<\/strong><span style=\"font-weight: 400;\">. Changement de plan en d\u00e9fense, avec un passage en 1-5, mais sans impact imm\u00e9diat. Pas le choix : le premier temps mort est pos\u00e9 c\u00f4t\u00e9 nantais, sous la bronca des supporters h\u00e9raultais. Dans le match des gardiens, avantage au portier du <\/span><strong>MHB<\/strong><span style=\"font-weight: 400;\">. Son homologue nantais, <\/span><strong>Ivan Pe\u0161i\u0107<\/strong><span style=\"font-weight: 400;\">, r\u00e9alise son premier arr\u00eat \u00e0 la 19\u2019 (<\/span><strong>13-9, 21\u2019<\/strong><span style=\"font-weight: 400;\">).<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Le jeu rapide montpelli\u00e9rain fait des ravages dans la d\u00e9fense nantaise, for\u00e7ant les Jaunes et Violets \u00e0 se mettre \u00e0 la faute et \u00e0 \u00e9coper d\u2019un quatri\u00e8me deux minutes en premi\u00e8re p\u00e9riode (<\/span><strong>16-12, 30\u2019<\/strong><span style=\"font-weight: 400;\">).<\/span><\/p>\n<h2 style=\"text-align: justify;\">R\u00e9mi Desbonnet scelle la rencontre<\/h2>\n<p style=\"text-align: justify;\"><strong>Nantes<\/strong><span style=\"font-weight: 400;\">, d\u00e9j\u00e0 mal embarqu\u00e9 dans cette rencontre, va voir rouge. Auteur d\u2019un coup au visage sur <\/span><strong>Rogerio Moraes<\/strong><span style=\"font-weight: 400;\">, <\/span><strong>Romain Lagarde<\/strong><span style=\"font-weight: 400;\"> \u00e9cope de son troisi\u00e8me deux minutes, synonyme d\u2019exclusion d\u00e9finitive. Un gros coup dur pour le secteur central nantais, d\u00e9sormais priv\u00e9 de deux joueurs (<\/span><strong>20-15, 37\u2019<\/strong><span style=\"font-weight: 400;\">). <\/span><strong>Noam L\u00e9opold<\/strong><span style=\"font-weight: 400;\"> a l\u2019occasion de ramener les siens \u00e0 -3, mais c\u2019est sans compter sur <\/span><strong>R\u00e9mi Desbonnet<\/strong><span style=\"font-weight: 400;\">, qui \u00e9c\u0153ure le jeune Suisse sur penalty.<\/span><\/p>\n<blockquote>\n<p style=\"text-align: justify;\"><em>On a perdu contre la meilleure \u00e9quipe aujourd&rsquo;hui. On fait trop de fautes et on rate des shoots importants \u00e0 la fin de la rencontre. Tout \u00e7a combin\u00e9, \u00e7a ne donne pas un tr\u00e8s bon r\u00e9sultat<\/em>. (Noam L\u00e9opold, ailier gauche du HBC Nantes)<\/p>\n<\/blockquote>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Pourtant bien dans son match, Montpellier se fait peur en attaque, perdant deux ballons puis venant buter sur le portier nantais, offrant ainsi une balle de -2 aux Nantais, qui n\u2019en demandaient pas tant. La finale est-elle relanc\u00e9e (<\/span><strong>21-18, 45\u2019<\/strong><span style=\"font-weight: 400;\">) ?<\/span><\/p>\n<blockquote>\n<p style=\"text-align: justify;\"><em>Franchement, je suis tr\u00e8s content. On n&rsquo;a pas \u00e9t\u00e9 happ\u00e9 par la pression, l&rsquo;ambiance de la rencontre. On a \u00e9t\u00e9 tr\u00e8s solides en d\u00e9fense tout au long du match. Tout n&rsquo;est pas parfait, mais 15, c&rsquo;est un chiffre presque rond, donc \u00e7a me va bien<\/em>. (Valentin Porte, arri\u00e8re droit du MHB)<\/p>\n<\/blockquote>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Si Nantes parvient \u00e0 rester en embuscade, oscillant entre -2 et -4, Montpellier reste ma\u00eetre de son destin. Les hommes d\u2019<\/span><strong>Erick Math\u00e9<\/strong><span style=\"font-weight: 400;\"> peuvent remercier leur portier, qui r\u00e9alise toujours l\u2019arr\u00eat parfait au bon moment. Et il le prouve encore en stoppant son troisi\u00e8me penalty de la rencontre, scellant d\u00e9finitivement l\u2019issue de cette finale. <\/span><strong>Montpellier<\/strong><span style=\"font-weight: 400;\"> remporte ainsi sa quinzi\u00e8me Coupe de France (<\/span><strong>27-24, score final<\/strong><span style=\"font-weight: 400;\">).<\/span><\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">[<a href=\"https:\/\/twitter.com\/hashtag\/CoupeDeFrance?src=hash&amp;ref_src=twsrc%5Etfw\">#CoupeDeFrance<\/a> &#8211; Finale]\n<p>\ud83c\udfc6 Montpellier remporte la COUPE DE FRANCE \ud83d\udd25 !<\/p>\n<p>1\u20e35\u20e3 C&rsquo;est le quinzi\u00e8me sacre dans cette comp\u00e9tition, le <a href=\"https:\/\/twitter.com\/mhbofficiel?ref_src=twsrc%5Etfw\">@mhbofficiel<\/a> conserve son titre !<\/p>\n<p>\ud83d\udd1a <a href=\"https:\/\/twitter.com\/mhbofficiel?ref_src=twsrc%5Etfw\">@mhbofficiel<\/a> \ud83c\udd9a <a href=\"https:\/\/twitter.com\/HBCNantes?ref_src=twsrc%5Etfw\">@HBCNantes<\/a> : 27-24 <a href=\"https:\/\/t.co\/Htbv0NK07I\">pic.twitter.com\/Htbv0NK07I<\/a><\/p>\n<p>\u2014 Montpellier Handball (@mhbofficiel) <a href=\"https:\/\/twitter.com\/mhbofficiel\/status\/2058268073279254803?ref_src=twsrc%5Etfw\">May 23, 2026<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>COUPE DE FRANCE DE HANDBALL &#8211; Au terme d&rsquo;une finale monumentale, c&rsquo;est le Montpellier Handball qui triomphe, remportant ainsi son quinzi\u00e8me troph\u00e9e dans la comp\u00e9tition (27-24).<\/p>\n","protected":false},"author":93,"featured_media":672473,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[2304],"tags":[16878,22930,405,2489,4933],"class_list":["post-672364","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-handball","tag-breve","tag-coupe-de-france-de-handball","tag-handball","tag-hbc-nantes","tag-mhb"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Le Montpellier Handball s&#039;offre sa quinzi\u00e8me Coupe de France en dominant Nantes<\/title>\n<meta name=\"description\" content=\"COUPE DE FRANCE DE HANDBALL - Au terme d&#039;une finale monumentale, c&#039;est le Montpellier Handball qui triomphe, remportant ainsi son quinzi\u00e8me troph\u00e9e dans la comp\u00e9tition (27-24).\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/le-montpellier-hb-soffre-sa-quinzieme-coupe-de-france-en-dominant-nantes\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le Montpellier Handball s&#039;offre sa quinzi\u00e8me Coupe de France en dominant Nantes\" \/>\n<meta property=\"og:description\" content=\"COUPE DE FRANCE DE HANDBALL - Au terme d&#039;une finale monumentale, c&#039;est le Montpellier Handball qui triomphe, remportant ainsi son quinzi\u00e8me troph\u00e9e dans la comp\u00e9tition (27-24).\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/le-montpellier-hb-soffre-sa-quinzieme-coupe-de-france-en-dominant-nantes\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-23T19:20:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-23T20:30:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/05\/Le-Montpellier-Handball-soffre-sa-quinzieme-Coupe-de-France-en-dominant-Nantes.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Th\u00e9o Alleaume\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Le Montpellier Handball s&#039;offre sa quinzi\u00e8me Coupe de France en dominant Nantes\" \/>\n<meta name=\"twitter:creator\" content=\"@dicodusport\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/le-montpellier-hb-soffre-sa-quinzieme-coupe-de-france-en-dominant-nantes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/le-montpellier-hb-soffre-sa-quinzieme-coupe-de-france-en-dominant-nantes\\\/\"},\"author\":{\"name\":\"Th\u00e9o Alleaume\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/dd5a6b44a2e07db91cdd73cfd7db2157\"},\"headline\":\"Le Montpellier Handball s&rsquo;offre sa quinzi\u00e8me Coupe de France en dominant Nantes\",\"datePublished\":\"2026-05-23T19:20:23+00:00\",\"dateModified\":\"2026-05-23T20:30:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/le-montpellier-hb-soffre-sa-quinzieme-coupe-de-france-en-dominant-nantes\\\/\"},\"wordCount\":720,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/le-montpellier-hb-soffre-sa-quinzieme-coupe-de-france-en-dominant-nantes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Le-Montpellier-Handball-soffre-sa-quinzieme-Coupe-de-France-en-dominant-Nantes.png\",\"keywords\":[\"br\u00e8ve\",\"coupe de france de handball\",\"Handball\",\"HBC Nantes\",\"MHB\"],\"articleSection\":[\"Handball\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/le-montpellier-hb-soffre-sa-quinzieme-coupe-de-france-en-dominant-nantes\\\/#respond\"]}],\"copyrightYear\":\"2026\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/le-montpellier-hb-soffre-sa-quinzieme-coupe-de-france-en-dominant-nantes\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/le-montpellier-hb-soffre-sa-quinzieme-coupe-de-france-en-dominant-nantes\\\/\",\"name\":\"Le Montpellier Handball s'offre sa quinzi\u00e8me Coupe de France en dominant Nantes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/le-montpellier-hb-soffre-sa-quinzieme-coupe-de-france-en-dominant-nantes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/le-montpellier-hb-soffre-sa-quinzieme-coupe-de-france-en-dominant-nantes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Le-Montpellier-Handball-soffre-sa-quinzieme-Coupe-de-France-en-dominant-Nantes.png\",\"datePublished\":\"2026-05-23T19:20:23+00:00\",\"dateModified\":\"2026-05-23T20:30:20+00:00\",\"description\":\"COUPE DE FRANCE DE HANDBALL - Au terme d'une finale monumentale, c'est le Montpellier Handball qui triomphe, remportant ainsi son quinzi\u00e8me troph\u00e9e dans la comp\u00e9tition (27-24).\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/le-montpellier-hb-soffre-sa-quinzieme-coupe-de-france-en-dominant-nantes\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/le-montpellier-hb-soffre-sa-quinzieme-coupe-de-france-en-dominant-nantes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/le-montpellier-hb-soffre-sa-quinzieme-coupe-de-france-en-dominant-nantes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Le-Montpellier-Handball-soffre-sa-quinzieme-Coupe-de-France-en-dominant-Nantes.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Le-Montpellier-Handball-soffre-sa-quinzieme-Coupe-de-France-en-dominant-Nantes.png\",\"width\":1200,\"height\":674,\"caption\":\"Le Montpellier Handball s'offre sa quinzi\u00e8me Coupe de France en dominant Nantes\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/le-montpellier-hb-soffre-sa-quinzieme-coupe-de-france-en-dominant-nantes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le Montpellier Handball s&rsquo;offre sa quinzi\u00e8me Coupe de France en dominant Nantes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/dd5a6b44a2e07db91cdd73cfd7db2157\",\"name\":\"Th\u00e9o Alleaume\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Maillot-Dicodusport-Toto-150x150.png\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Maillot-Dicodusport-Toto-150x150.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Maillot-Dicodusport-Toto-150x150.png\",\"caption\":\"Th\u00e9o Alleaume\"},\"description\":\"Chabal, Harinordoquy, Lamerat, Landin, Omeyer, Sterbik et bien d'autres sont mes idoles. \u00c0 d\u00e9faut d'\u00eatre sportif professionnel, j'\u00e9cris sur ceux qui me font vibrer.\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/theo-alleaume\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Le Montpellier Handball s'offre sa quinzi\u00e8me Coupe de France en dominant Nantes","description":"COUPE DE FRANCE DE HANDBALL - Au terme d'une finale monumentale, c'est le Montpellier Handball qui triomphe, remportant ainsi son quinzi\u00e8me troph\u00e9e dans la comp\u00e9tition (27-24).","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/le-montpellier-hb-soffre-sa-quinzieme-coupe-de-france-en-dominant-nantes\/","og_locale":"fr_FR","og_type":"article","og_title":"Le Montpellier Handball s'offre sa quinzi\u00e8me Coupe de France en dominant Nantes","og_description":"COUPE DE FRANCE DE HANDBALL - Au terme d'une finale monumentale, c'est le Montpellier Handball qui triomphe, remportant ainsi son quinzi\u00e8me troph\u00e9e dans la comp\u00e9tition (27-24).","og_url":"https:\/\/dicodusport.fr\/blog\/le-montpellier-hb-soffre-sa-quinzieme-coupe-de-france-en-dominant-nantes\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2026-05-23T19:20:23+00:00","article_modified_time":"2026-05-23T20:30:20+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/05\/Le-Montpellier-Handball-soffre-sa-quinzieme-Coupe-de-France-en-dominant-Nantes.png","type":"image\/png"}],"author":"Th\u00e9o Alleaume","twitter_card":"summary_large_image","twitter_title":"Le Montpellier Handball s'offre sa quinzi\u00e8me Coupe de France en dominant Nantes","twitter_creator":"@dicodusport","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/le-montpellier-hb-soffre-sa-quinzieme-coupe-de-france-en-dominant-nantes\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/le-montpellier-hb-soffre-sa-quinzieme-coupe-de-france-en-dominant-nantes\/"},"author":{"name":"Th\u00e9o Alleaume","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/dd5a6b44a2e07db91cdd73cfd7db2157"},"headline":"Le Montpellier Handball s&rsquo;offre sa quinzi\u00e8me Coupe de France en dominant Nantes","datePublished":"2026-05-23T19:20:23+00:00","dateModified":"2026-05-23T20:30:20+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/le-montpellier-hb-soffre-sa-quinzieme-coupe-de-france-en-dominant-nantes\/"},"wordCount":720,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/le-montpellier-hb-soffre-sa-quinzieme-coupe-de-france-en-dominant-nantes\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/05\/Le-Montpellier-Handball-soffre-sa-quinzieme-Coupe-de-France-en-dominant-Nantes.png","keywords":["br\u00e8ve","coupe de france de handball","Handball","HBC Nantes","MHB"],"articleSection":["Handball"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/le-montpellier-hb-soffre-sa-quinzieme-coupe-de-france-en-dominant-nantes\/#respond"]}],"copyrightYear":"2026","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/le-montpellier-hb-soffre-sa-quinzieme-coupe-de-france-en-dominant-nantes\/","url":"https:\/\/dicodusport.fr\/blog\/le-montpellier-hb-soffre-sa-quinzieme-coupe-de-france-en-dominant-nantes\/","name":"Le Montpellier Handball s'offre sa quinzi\u00e8me Coupe de France en dominant Nantes","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/le-montpellier-hb-soffre-sa-quinzieme-coupe-de-france-en-dominant-nantes\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/le-montpellier-hb-soffre-sa-quinzieme-coupe-de-france-en-dominant-nantes\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/05\/Le-Montpellier-Handball-soffre-sa-quinzieme-Coupe-de-France-en-dominant-Nantes.png","datePublished":"2026-05-23T19:20:23+00:00","dateModified":"2026-05-23T20:30:20+00:00","description":"COUPE DE FRANCE DE HANDBALL - Au terme d'une finale monumentale, c'est le Montpellier Handball qui triomphe, remportant ainsi son quinzi\u00e8me troph\u00e9e dans la comp\u00e9tition (27-24).","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/le-montpellier-hb-soffre-sa-quinzieme-coupe-de-france-en-dominant-nantes\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/le-montpellier-hb-soffre-sa-quinzieme-coupe-de-france-en-dominant-nantes\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/le-montpellier-hb-soffre-sa-quinzieme-coupe-de-france-en-dominant-nantes\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/05\/Le-Montpellier-Handball-soffre-sa-quinzieme-Coupe-de-France-en-dominant-Nantes.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/05\/Le-Montpellier-Handball-soffre-sa-quinzieme-Coupe-de-France-en-dominant-Nantes.png","width":1200,"height":674,"caption":"Le Montpellier Handball s'offre sa quinzi\u00e8me Coupe de France en dominant Nantes"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/le-montpellier-hb-soffre-sa-quinzieme-coupe-de-france-en-dominant-nantes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Le Montpellier Handball s&rsquo;offre sa quinzi\u00e8me Coupe de France en dominant Nantes"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/dd5a6b44a2e07db91cdd73cfd7db2157","name":"Th\u00e9o Alleaume","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Maillot-Dicodusport-Toto-150x150.png","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Maillot-Dicodusport-Toto-150x150.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Maillot-Dicodusport-Toto-150x150.png","caption":"Th\u00e9o Alleaume"},"description":"Chabal, Harinordoquy, Lamerat, Landin, Omeyer, Sterbik et bien d'autres sont mes idoles. \u00c0 d\u00e9faut d'\u00eatre sportif professionnel, j'\u00e9cris sur ceux qui me font vibrer.","url":"https:\/\/dicodusport.fr\/blog\/author\/theo-alleaume\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/672364","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/93"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=672364"}],"version-history":[{"count":5,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/672364\/revisions"}],"predecessor-version":[{"id":672479,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/672364\/revisions\/672479"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/672473"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=672364"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=672364"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=672364"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}