{"id":67278,"date":"2020-05-22T14:52:11","date_gmt":"2020-05-22T12:52:11","guid":{"rendered":"http:\/\/dicodusport.fr\/blog\/?p=67278&#038;preview=true&#038;preview_id=67278"},"modified":"2020-05-22T15:12:27","modified_gmt":"2020-05-22T13:12:27","slug":"le-super-sprint-un-atout-pour-le-biathlon-mondial","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/le-super-sprint-un-atout-pour-le-biathlon-mondial\/","title":{"rendered":"Le super sprint, un atout pour le biathlon mondial ?"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em><a href=\"https:\/\/dicodusport.fr\/blog\/actualites\/biathlon\/\" target=\"_blank\" rel=\"noopener noreferrer\">BIATHLON<\/a> &#8211; Test\u00e9 durant deux saisons en IBU Cup, le super sprint sera au programme de la Coupe du monde 2020-2021, lors de l&rsquo;\u00e9tape finale \u00e0 Oslo. Est-ce vraiment un nouvel atout pour le biathlon ?<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">Petit rappel des r\u00e8gles. Sur l&rsquo;\u00e9preuve du super sprint, les biathl\u00e8tes s\u2019\u00e9lancent pour une s\u00e9ance de qualification sur 3km avec un tir couch\u00e9 et un tir debout. Une balle de pioche est autoris\u00e9e, avec un tour de p\u00e9nalit\u00e9 de 75m en cas de faute suppl\u00e9mentaire. Les 30 meilleurs chronos sont qualifi\u00e9s pour la finale.<\/p>\n<p style=\"text-align: justify;\">Le d\u00e9part de la finale s\u2019effectue en mode <strong>mass-start<\/strong> avec les meilleurs biathl\u00e8tes de la qualification devant sur la grille de d\u00e9part. Tout ce beau monde pour 5km avec 4 tirs (couch\u00e9, couch\u00e9, debout et debout). Une balle de pioche est \u00e0 disposition sur chaque tir, avec l\u00e0 aussi, un tour de p\u00e9nalit\u00e9 de 75m en cas d\u2019erreur suppl\u00e9mentaire.<\/p>\n<p style=\"text-align: justify;\">La finale dure un peu moins de 15 minutes chez les hommes, et \u00e0 peine plus chez les femmes. Un format ultra-court, en somme. Alors, <strong>est-ce un atout pour le biathlon ?<\/strong> La r\u00e9ponse est surtout une question de point de vue.<\/p>\n<ul>\n<li style=\"text-align: justify;\"><strong>\u00c0 faire &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/quiz-biathlon-citez-les-40-derniers-champions-du-monde-2008-2020\/\" target=\"_blank\" rel=\"noopener noreferrer\">Quiz Biathlon : Citez les 40 derniers champions du monde (2008-2020)<\/a><\/strong><\/li>\n<\/ul>\n<h2 style=\"text-align: justify;\">Un \u00ab\u00a0produit spectaculaire\u00a0\u00bb, adapt\u00e9 \u00e0 la TV<\/h2>\n<p style=\"text-align: justify;\">Avec peu de ski et donc une course rapide agr\u00e9ment\u00e9e de quatre tirs, forc\u00e9ment, le spectacle est au rendez-vous du super sprint. Ajoutez \u00e0 cela un d\u00e9part group\u00e9 des 30 protagonistes en finale, et vous avez l\u00e0 une course qui attirera forc\u00e9ment les t\u00e9l\u00e9spectateurs. L&rsquo;<strong>IBU<\/strong> sait que la <strong>mass start<\/strong> est le format le plus vendeur, celui qui pla\u00eet le plus aux fans et le super sprint est un moyen de proposer une autre version de la course phare, avec de la confrontation directe. Pour les cha\u00eenes de TV, ce format en deux temps, et court, permet une meilleure rentabilit\u00e9.<\/p>\n<h2 style=\"text-align: justify;\">Sportivement, un int\u00e9r\u00eat limit\u00e9 ?<\/h2>\n<p style=\"text-align: justify;\">Le biathlon est la combinaison de deux sports : le tir et le ski de fond. Sur les courses programm\u00e9es jusqu&rsquo;ici, <strong>sprint<\/strong>, <strong>poursuite<\/strong>, <strong>individuel<\/strong> et <strong>mass start<\/strong>, l&rsquo;\u00e9quilibre entre les deux est quasi parfait. Avec seulement trois kilom\u00e8tres lors des qualifications et cinq en finale, le super sprint fait clairement pencher la balance du c\u00f4t\u00e9 du tir. Des boucles de seulement un kilom\u00e8tre qui ne permettent de faire aucune diff\u00e9rence \u00e0 ski. Le temps de partir et de revenir sur le pas de tir, la course se r\u00e9sume finalement presque \u00e0 un concours d&rsquo;adresse, plus qu&rsquo;\u00e0 du biathlon.<\/p>\n<h2 style=\"text-align: justify;\">Quentin Fillon Maillet dubitatif<\/h2>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/dicodusport.fr\/blog\/quentin-fillon-maillet-les-objectifs-seront-les-memes\/\" target=\"_blank\" rel=\"noopener noreferrer\">Dans nos colonnes<\/a>, <strong>Quentin Fillon Maillet<\/strong>, troisi\u00e8me des deux derni\u00e8res Coupes du monde, a expliqu\u00e9 que ce format ne l&rsquo;inspirait pas trop, m\u00eame s&rsquo;il attend de se faire son propre avis.<\/p>\n<blockquote>\n<p style=\"text-align: justify;\">C\u2019est une \u00e9preuve sur laquelle je n\u2019ai pas encore couru. J\u2019ai juste eu les retours d\u2019Antonin (Guigonnat) et Fabien (Claude) qui eux ont couru sur ce format en IBU Cup. Personnellement, je ne suis pas sp\u00e9cialement pour. Les premiers retours, justement, ne sont pas exceptionnels, le tir prenant une place trop importante avec le ski d\u00e9laiss\u00e9. Je pense qu\u2019il faut un compromis entre ski et tir. Apr\u00e8s, j\u2019ai envie de me faire mon propre avis.<\/p>\n<\/blockquote>\n<div class=\"dem-poll-shortcode\">\n<style id=\"democracy-poll\">.democracy:after{content:'';display:table;clear:both}.democracy ul li,.democracy ul{background:0 0;padding:0;margin:0}.democracy ul li:before{display:none}.democracy input[type=radio],.democracy input[type=checkbox]{margin:0;vertical-align:middle}.democracy input[type=radio]:focus,.democracy input[type=checkbox]:focus{outline:none}.democracy ul{list-style:none !important;border:none !important}.democracy ul li{list-style:none !important}input[type=submit].dem-button,a.dem-button,.dem-button{position:relative;display:inline-block;text-decoration:none;line-height:1;border:0;margin:0;padding:0;cursor:pointer;white-space:nowrap;-webkit-user-select:none;-moz-user-select:none;-ms-user-select:none;user-select:none}input[type=submit].dem-button:focus,a.dem-button:focus,.dem-button:focus{outline:none}input[type=submit].dem-button:disabled,a.dem-button:disabled,.dem-button:disabled{opacity:.6;cursor:not-allowed}a.dem-button:hover{text-decoration:none !important}.democracy{position:relative;margin:0 auto}.democracy input[type=radio],.democracy input[type=checkbox]{margin-right:.2em}.dem-screen{position:relative;line-height:1.3}.democracy ul.dem-vote{margin-bottom:1em}.democracy ul.dem-vote li{padding-bottom:0;margin-bottom:0}.democracy ul.dem-vote li>*{margin-bottom:.6em}.democracy ul.dem-answers li{padding-bottom:1em}.dem-answers .dem-label{margin-bottom:.2em;line-height:1.2}.dem-graph{position:relative;color:#555;color:rgba(0,0,0,.6);box-sizing:content-box;width:100%;display:table;height:1.2em;line-height:1.2em}.dem-fill{position:absolute;top:0;left:0;height:100%;background-color:#7cb4dd}.dem-voted-this .dem-fill{background-color:#ffc45a}.dem-votes-txt,.dem-percent-txt{position:relative;display:table-cell;padding-left:.3em;vertical-align:middle;font-size:90%}.dem-poll-info{padding-bottom:1em}.dem-poll-info:after{content:'';display:table;clear:both}.dem-poll-info>*{font-size:85%;display:block;float:right;clear:both;text-align:right;opacity:.7;line-height:1.3}.dem-vote label{float:none;display:block}.dem-results-link{display:inline-block;line-height:1;margin:.8em 1em}.dem-vote .dem-disabled{opacity:.5}.democracy .dem-bottom{padding-bottom:1em}.dem-bottom{text-align:center}.dem-bottom:after{content:'';display:table;clear:both}.dem-poll-title{display:block;margin-bottom:1.5em;margin-top:1.2em;font-size:120%}.dem-notice{z-index:10;position:absolute;top:0;border-radius:2px;width:100%;padding:1.5em 2em;text-align:center;background:rgba(247,241,212,.8);color:#6d6214}.dem-notice-close{position:absolute;top:0;right:0;padding:5px;cursor:pointer;line-height:.6;font-size:150%}.dem-notice-close:hover{color:#d26616}.dem-star{font-size:90%;vertical-align:baseline;padding-left:.3em;color:#ff4e00}.dem-poll-note{font-size:90%;padding:.5em;opacity:.8;line-height:1.3}.democracy .dem-copyright{position:absolute;bottom:-1em;right:0;text-decoration:none;border-bottom:0;color:#b2b2b2;opacity:.5;line-height:1}.democracy .dem-copyright:hover{opacity:1}.dem-add-answer{position:relative}.dem-add-answer>*{display:block}.dem-add-answer a{display:inline-block}input.dem-add-answer-txt{width:100%;box-sizing:border-box}.dem-add-answer-close{position:absolute;right:0;padding:0 .7em;cursor:pointer;color:#333}.dem-add-answer-close:hover{color:#ff2700}.dem-edit-link{display:block;position:absolute;top:0;right:0;line-height:1;text-decoration:none !important;border:none !important}.dem-edit-link svg{width:1.2em!important;fill:#6c6c6c}.dem-edit-link:hover svg{fill:#35a91d}.dem-loader{display:none;position:absolute;top:0;left:0;width:100%;height:100%}.dem-loader>*{display:table-cell;vertical-align:middle;text-align:center}.dem-loader svg{width:20%;max-width:100px;min-width:80px;margin-bottom:15%}.dem-loader [class^=dem-]{margin-bottom:15%!important}.dem__collapser{display:block;cursor:pointer;text-align:center;font-size:150%;line-height:1}.dem__collapser:hover{color:#f31;background:rgba(255,255,255,.3)}.dem__collapser.expanded{position:relative;height:1em}.dem__collapser.collapsed{position:absolute;top:0;bottom:0;right:0;left:0}.dem__collapser .arr{display:block;position:absolute;bottom:0;width:100%}.dem__collapser.collapsed .arr:before{content:\"\u25be\"}.dem__collapser.expanded .arr:before{content:\"\u25b4\"}.dem-poll-shortcode{margin-bottom:1.5em}.dem-archives .dem-elem-wrap{margin-bottom:2em;padding-bottom:20px;border-bottom:1px dashed rgba(0,0,0,.1)}.dem-archives .dem-archive-link{display:none}.dem-paging{text-align:center;margin:1.5em auto}.dem-paging>*{display:inline-block;padding:.3em .8em;border-radius:.2em;background:#e2e2e2;color:#333;text-decoration:none;text-transform:lowercase;user-select:none}.dem-paging>a{color:#333}.dem-paging>a:hover{background:#ccc;color:#333;text-decoration:none}.dem-paging .current{background:#656565;color:#fff}.dem-paging .dots{background:0 0}.democracy{border-color:#ccc;border:1px solid rgba(0,0,0,.1);background-color:#eee;background-color:rgba(0,0,0,.1);background-image:-webkit-linear-gradient(bottom,rgba(0,0,0,.05),transparent);background-image:linear-gradient(to top,rgba(0,0,0,.05),transparent);padding:1em;padding-bottom:.5em;margin-bottom:1em}.dem-poll-title{margin:0;font-size:115%;margin:-.9em;margin-bottom:1em;text-align:center;padding:1em;border-bottom:1px solid rgba(0,0,0,.1)}.dem-percent-txt,.dem-label-percent-txt{display:none}.dem-votes-txt-percent:before{content:'- ';display:inline}.dem-revote-button:before{content:'\u25c2 '}.dem-graph{background-color:rgba(255,255,255,.8)}.dem-results-link{margin-bottom:0}.dem__checkbox,.dem__radio{display:none !important}.dem__checkbox_label,.dem__radio_label{position:relative;box-sizing:content-box}.dem__checkbox_label .dem__spot{border-radius:3px}.dem__radio_label .dem__spot{border-radius:50%}.dem__checkbox_label .dem__spot,.dem__radio_label .dem__spot{position:relative;display:inline-block;vertical-align:baseline;width:.9em;height:.9em;margin-right:.3em;cursor:pointer;background:#fff;border:1px solid #ccc}.dem__checkbox_label .dem__spot:after{width:.9em;height:.32em;top:-.1em;left:.145em;border:.17em solid #333;border-top:none;border-right:none;-webkit-transform:rotate(-45deg);transform:rotate(-45deg);background:0 0}.dem__radio_label .dem__spot:after{width:.5em;height:.5em;border-radius:50%;top:50%;left:50%;-webkit-transform:translate(-50%,-50%);transform:translate(-50%,-50%);background:#333}.dem__checkbox_label .dem__spot:after,.dem__radio_label .dem__spot:after{content:'';position:absolute;opacity:0}.dem__checkbox_label:hover .dem__spot:after,.dem__radio_label:hover .dem__spot:after{opacity:.2}.dem__checkbox:checked+.dem__spot,.dem__radio:checked+.dem__spot{border-color:#999}.dem__checkbox:checked+.dem__spot:after,.dem__radio:checked+.dem__spot:after{opacity:1}.dem__checkbox:disabled+.dem__spot,.dem__radio:disabled+.dem__spot{opacity:.5}.dem__checkbox:not(:checked):disabled+.dem__spot:after,.dem__radio:not(:checked):disabled+.dem__spot:after{opacity:0}input[type=submit].dem-button,a.dem-button,.dem-button{font-size:90%;font-family:tahoma,arial,sans-serif;padding:.8em 1.6em !important;color:#fff;background:#61a9de;text-transform:uppercase}input[type=submit].dem-button:hover,a.dem-button:hover,.dem-button:hover{color:#fff;background:#3b8bc6}a.dem-button:visited{color:#fff}.dem-loader .fill{fill:#0248ed !important}.dem-loader .css-fill{background-color:#0248ed !important}.dem-loader .stroke{stroke:#0248ed !important}.dem-graph{background:#a5a5a5 !important}.dem-fill{background-color:#1c62ed !important}.dem-voted-this .dem-fill{background-color:#30a82a !important}.dem-graph{height:25px;line-height:25px}.dem-button{background-color:#f71339 !important}.dem-button{color:#efefef !important}.democracy{background-color:#fff;color:#000}.dem-poll-info{color:#000}.dem-votes-txt,.dem-percent-txt{color:#fff}<\/style>\n<div id=\"democracy-539\" class=\"democracy\" data-opts='{\"ajax_url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-admin\\\/admin-ajax.php\",\"pid\":539,\"max_answs\":0,\"answs_max_height\":\"-1\",\"anim_speed\":\"400\",\"line_anim_speed\":1500}' ><strong class=\"dem-poll-title\">Le Super Sprint, un atout pour le biathlon mondial ?<\/strong><div class=\"dem-screen voted\"><ul class=\"dem-answers\" data-voted-class=\"dem-voted-this\" data-voted-txt=\"(Votre vote)\">\n\t<li  class=\"dem-winner\" title=\"179 voix - 50% des votes\" data-aid=\"2515\">\n\t<div class=\"dem-label\">On essaie 1 saison et on en tire la conclusion<sup class=\"dem-star\" title=\"R\u00e9ponse ajout\u00e9 par un visiteur\">*<\/sup>  <span class=\"dem-label-percent-txt\">50%, 179 <span class=\"votxt\">voix<\/span><\/span><\/div>\n\t<div class=\"dem-graph\">\n\t\t<div class=\"dem-fill\" data-width=\"100%\"><\/div>\n\t\t<div class=\"dem-votes-txt\">\n\t\t\t<span class=\"dem-votes-txt-votes\">179 <span class=\"votxt\">voix<\/span><\/span>\n\t\t\t<span class=\"dem-votes-txt-percent\">50%<\/span>\n\t\t<\/div>\n\t\t<div class=\"dem-percent-txt\">179 voix - 50% des votes<\/div>\n\t<\/div>\n<\/li><li  title=\"148 voix - 41% des votes\" data-aid=\"2514\">\n\t<div class=\"dem-label\">Non  <span class=\"dem-label-percent-txt\">41%, 148 <span class=\"votxt\">voix<\/span><\/span><\/div>\n\t<div class=\"dem-graph\">\n\t\t<div class=\"dem-fill\" data-width=\"83%\"><\/div>\n\t\t<div class=\"dem-votes-txt\">\n\t\t\t<span class=\"dem-votes-txt-votes\">148 <span class=\"votxt\">voix<\/span><\/span>\n\t\t\t<span class=\"dem-votes-txt-percent\">41%<\/span>\n\t\t<\/div>\n\t\t<div class=\"dem-percent-txt\">148 voix - 41% des votes<\/div>\n\t<\/div>\n<\/li><li  title=\"32 voix - 9% des votes\" data-aid=\"2513\">\n\t<div class=\"dem-label\">Oui  <span class=\"dem-label-percent-txt\">9%, 32 <span class=\"votxt\">voix<\/span><\/span><\/div>\n\t<div class=\"dem-graph\">\n\t\t<div class=\"dem-fill\" data-width=\"18%\"><\/div>\n\t\t<div class=\"dem-votes-txt\">\n\t\t\t<span class=\"dem-votes-txt-votes\">32 <span class=\"votxt\">voix<\/span><\/span>\n\t\t\t<span class=\"dem-votes-txt-percent\">9%<\/span>\n\t\t<\/div>\n\t\t<div class=\"dem-percent-txt\">32 voix - 9% des votes<\/div>\n\t<\/div>\n<\/li>\n<\/ul>\n<div class=\"dem-bottom\">\n\t<div class=\"dem-poll-info\">\n\t\t<div class=\"dem-total-votes\">Total des votes : 359<\/div>\n\t\t\n\t\t<div class=\"dem-date\" title=\"D\u00e9but\">\n\t\t\t<span class=\"dem-begin-date\">22 mai 2020<\/span> - <span class=\"dem-end-date\" title=\"Fin\">12 ao\u00fbt 2021<\/span>\n\t\t<\/div>\n\t\t\n\t\t<div>Les votes sont clos<\/div>\n\t\t\n\t<\/div>\n\t\n<\/div><\/div><noscript>Poll Options are limited because JavaScript is disabled in your browser.<\/noscript><div class=\"dem-loader\"><div><style type=\"text\/css\">\n.dem-circle {\n  width:100%;\n  height:100%;\n  min-width:40px;\n  min-height:40px;\n  max-width:70px;\n  max-height:70px;\n\n  position: relative;\n  margin: 0 auto;\n}\n\n.double-bounce1, .double-bounce2 {\n  width: 100%;\n  height: 100%;\n  border-radius: 50%;\n  background-color: #226ec6;\n  opacity: 0.6;\n  position: absolute;\n  top: 0;\n  left: 0;\n  \n  -webkit-animation: bounce 2.0s infinite ease-in-out;\n  animation: bounce 2.0s infinite ease-in-out;\n}\n\n.double-bounce2 {\n  -webkit-animation-delay: -1.0s;\n  animation-delay: -1.0s;\n}\n\n@-webkit-keyframes bounce {\n  0%, 100% { -webkit-transform: scale(0.0) }\n  50% { -webkit-transform: scale(1.0) }\n}\n\n@keyframes bounce {\n  0%, 100% { \n    transform: scale(0.0);\n    -webkit-transform: scale(0.0);\n  } 50% { \n    transform: scale(1.0);\n    -webkit-transform: scale(1.0);\n  }\n}<\/style>\n\n<div class=\"dem-circle\">\n  <div class=\"double-bounce1 css-fill\"><\/div>\n  <div class=\"double-bounce2 css-fill\"><\/div>\n<\/div><\/div><\/div><\/div><!--democracy--><\/div>\n<ul>\n<li style=\"text-align: justify;\"><strong>\u00c0 faire &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/quiz-biathlon-citez-les-40-dernieres-championnes-du-monde-2008-2020\/\" target=\"_blank\" rel=\"noopener noreferrer\">Quiz Biathlon : Citez les 40 derni\u00e8res championnes du monde (2008-2020)<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\"><strong><em>Dicodusport<br \/>\n<a href=\"https:\/\/www.facebook.com\/dicodusport\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2909\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-facebook-150x150.png\" alt=\"\" width=\"40\" height=\"40\" \/><\/a><a href=\"https:\/\/twitter.com\/dicodusport\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2908\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-twitter-150x150.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>BIATHLON &#8211; Test\u00e9 durant deux saisons en IBU Cup, le super sprint sera au programme de la Coupe du monde 2020-2021, lors de l&rsquo;\u00e9tape finale \u00e0 Oslo. Est-ce vraiment un nouvel atout pour le biathlon ?<\/p>\n","protected":false},"author":1,"featured_media":67302,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[2426],"tags":[2427],"class_list":["post-67278","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-biathlon","tag-biathlon"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Le super sprint, un atout pour le biathlon mondial ?<\/title>\n<meta name=\"description\" content=\"BIATHLON - Test\u00e9 durant deux saisons en IBU Cup, le super sprint sera au programme de la Coupe du monde 2020-2021, lors de l&#039;\u00e9tape finale \u00e0 Oslo. Est-ce vraiment un nouvel atout pour le biathlon ?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/le-super-sprint-un-atout-pour-le-biathlon-mondial\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le super sprint, un atout pour le biathlon mondial ?\" \/>\n<meta property=\"og:description\" content=\"BIATHLON - Test\u00e9 durant deux saisons en IBU Cup, le super sprint sera au programme de la Coupe du monde 2020-2021, lors de l&#039;\u00e9tape finale \u00e0 Oslo. Est-ce vraiment un nouvel atout pour le biathlon ?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/le-super-sprint-un-atout-pour-le-biathlon-mondial\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-22T12:52:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-05-22T13:12:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/05\/Le-super-sprint-un-atout-pour-le-biathlon-mondial-.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicolas Jacquemard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Le super sprint, un atout pour le biathlon mondial ?\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Nico_Jacquemard\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/le-super-sprint-un-atout-pour-le-biathlon-mondial\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/le-super-sprint-un-atout-pour-le-biathlon-mondial\/\"},\"author\":{\"name\":\"Nicolas Jacquemard\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\"},\"headline\":\"Le super sprint, un atout pour le biathlon mondial ?\",\"datePublished\":\"2020-05-22T12:52:11+00:00\",\"dateModified\":\"2020-05-22T13:12:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/le-super-sprint-un-atout-pour-le-biathlon-mondial\/\"},\"wordCount\":584,\"commentCount\":2,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/le-super-sprint-un-atout-pour-le-biathlon-mondial\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/05\/Le-super-sprint-un-atout-pour-le-biathlon-mondial-.png\",\"keywords\":[\"Biathlon\"],\"articleSection\":[\"Biathlon\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/le-super-sprint-un-atout-pour-le-biathlon-mondial\/#respond\"]}],\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/le-super-sprint-un-atout-pour-le-biathlon-mondial\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/le-super-sprint-un-atout-pour-le-biathlon-mondial\/\",\"name\":\"Le super sprint, un atout pour le biathlon mondial ?\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/le-super-sprint-un-atout-pour-le-biathlon-mondial\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/le-super-sprint-un-atout-pour-le-biathlon-mondial\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/05\/Le-super-sprint-un-atout-pour-le-biathlon-mondial-.png\",\"datePublished\":\"2020-05-22T12:52:11+00:00\",\"dateModified\":\"2020-05-22T13:12:27+00:00\",\"description\":\"BIATHLON - Test\u00e9 durant deux saisons en IBU Cup, le super sprint sera au programme de la Coupe du monde 2020-2021, lors de l'\u00e9tape finale \u00e0 Oslo. Est-ce vraiment un nouvel atout pour le biathlon ?\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/le-super-sprint-un-atout-pour-le-biathlon-mondial\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/le-super-sprint-un-atout-pour-le-biathlon-mondial\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/le-super-sprint-un-atout-pour-le-biathlon-mondial\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/05\/Le-super-sprint-un-atout-pour-le-biathlon-mondial-.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/05\/Le-super-sprint-un-atout-pour-le-biathlon-mondial-.png\",\"width\":800,\"height\":445,\"caption\":\"Le super sprint, un atout pour le biathlon mondial ?\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/le-super-sprint-un-atout-pour-le-biathlon-mondial\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le super sprint, un atout pour le biathlon mondial ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\",\"name\":\"Nicolas Jacquemard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"caption\":\"Nicolas Jacquemard\"},\"description\":\"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.\",\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Le super sprint, un atout pour le biathlon mondial ?","description":"BIATHLON - Test\u00e9 durant deux saisons en IBU Cup, le super sprint sera au programme de la Coupe du monde 2020-2021, lors de l'\u00e9tape finale \u00e0 Oslo. Est-ce vraiment un nouvel atout pour le biathlon ?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/le-super-sprint-un-atout-pour-le-biathlon-mondial\/","og_locale":"fr_FR","og_type":"article","og_title":"Le super sprint, un atout pour le biathlon mondial ?","og_description":"BIATHLON - Test\u00e9 durant deux saisons en IBU Cup, le super sprint sera au programme de la Coupe du monde 2020-2021, lors de l'\u00e9tape finale \u00e0 Oslo. Est-ce vraiment un nouvel atout pour le biathlon ?","og_url":"https:\/\/dicodusport.fr\/blog\/le-super-sprint-un-atout-pour-le-biathlon-mondial\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2020-05-22T12:52:11+00:00","article_modified_time":"2020-05-22T13:12:27+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/05\/Le-super-sprint-un-atout-pour-le-biathlon-mondial-.png","type":"image\/png"}],"author":"Nicolas Jacquemard","twitter_card":"summary_large_image","twitter_title":"Le super sprint, un atout pour le biathlon mondial ?","twitter_creator":"@https:\/\/twitter.com\/Nico_Jacquemard","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/le-super-sprint-un-atout-pour-le-biathlon-mondial\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/le-super-sprint-un-atout-pour-le-biathlon-mondial\/"},"author":{"name":"Nicolas Jacquemard","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191"},"headline":"Le super sprint, un atout pour le biathlon mondial ?","datePublished":"2020-05-22T12:52:11+00:00","dateModified":"2020-05-22T13:12:27+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/le-super-sprint-un-atout-pour-le-biathlon-mondial\/"},"wordCount":584,"commentCount":2,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/le-super-sprint-un-atout-pour-le-biathlon-mondial\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/05\/Le-super-sprint-un-atout-pour-le-biathlon-mondial-.png","keywords":["Biathlon"],"articleSection":["Biathlon"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/le-super-sprint-un-atout-pour-le-biathlon-mondial\/#respond"]}],"copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/le-super-sprint-un-atout-pour-le-biathlon-mondial\/","url":"https:\/\/dicodusport.fr\/blog\/le-super-sprint-un-atout-pour-le-biathlon-mondial\/","name":"Le super sprint, un atout pour le biathlon mondial ?","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/le-super-sprint-un-atout-pour-le-biathlon-mondial\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/le-super-sprint-un-atout-pour-le-biathlon-mondial\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/05\/Le-super-sprint-un-atout-pour-le-biathlon-mondial-.png","datePublished":"2020-05-22T12:52:11+00:00","dateModified":"2020-05-22T13:12:27+00:00","description":"BIATHLON - Test\u00e9 durant deux saisons en IBU Cup, le super sprint sera au programme de la Coupe du monde 2020-2021, lors de l'\u00e9tape finale \u00e0 Oslo. Est-ce vraiment un nouvel atout pour le biathlon ?","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/le-super-sprint-un-atout-pour-le-biathlon-mondial\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/le-super-sprint-un-atout-pour-le-biathlon-mondial\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/le-super-sprint-un-atout-pour-le-biathlon-mondial\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/05\/Le-super-sprint-un-atout-pour-le-biathlon-mondial-.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/05\/Le-super-sprint-un-atout-pour-le-biathlon-mondial-.png","width":800,"height":445,"caption":"Le super sprint, un atout pour le biathlon mondial ?"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/le-super-sprint-un-atout-pour-le-biathlon-mondial\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Le super sprint, un atout pour le biathlon mondial ?"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191","name":"Nicolas Jacquemard","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","caption":"Nicolas Jacquemard"},"description":"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.","sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard"],"url":"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/67278","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=67278"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/67278\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/67302"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=67278"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=67278"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=67278"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}