{"id":675173,"date":"2026-06-02T17:59:48","date_gmt":"2026-06-02T15:59:48","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=675173&#038;preview=true&#038;preview_id=675173"},"modified":"2026-06-02T18:09:41","modified_gmt":"2026-06-02T16:09:41","slug":"deux-sur-deux-pour-les-bleus-vainqueurs-dans-la-douleur-face-a-porto-rico-en-coupe-du-monde-de-basket-3x3","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/deux-sur-deux-pour-les-bleus-vainqueurs-dans-la-douleur-face-a-porto-rico-en-coupe-du-monde-de-basket-3x3\/","title":{"rendered":"Deux sur deux pour les Bleus, vainqueurs dans la douleur face \u00e0 Porto Rico en Coupe du monde de basket 3&#215;3"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><strong>COUPE DU MONDE MASCULINE DE BASKET 3&#215;3 &#8211; Quelques heures apr\u00e8s avoir domin\u00e9 la Belgique d&rsquo;un point, l&rsquo;\u00e9quipe de France masculine a encha\u00een\u00e9 en s&rsquo;imposant au forceps face \u00e0 Porto Rico (18-16).\u00a0<\/strong><\/em><\/p>\n<p style=\"text-align: justify;\">Apr\u00e8s avoir arrach\u00e9 une victoire pr\u00e9cieuse et de justesse contre la <strong>Belgique<\/strong> plus t\u00f4t dans l&rsquo;apr\u00e8s-midi (21-20), l&rsquo;\u00e9quipe de France masculine de basket 3&#215;3 encha\u00eene d\u00e8s aujourd&rsquo;hui avec un deuxi\u00e8me gros test. Les <strong>Bleus<\/strong> ont rendez-vous avec <strong>Porto Rico<\/strong>, une \u00e9quipe redoutable et r\u00e9cente finaliste de la derni\u00e8re AmeriCup, pour tenter de confirmer leur bon d\u00e9but de tournoi.<\/p>\n<ul style=\"text-align: justify;\">\n<li><strong>\u00c0 ce sujet &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-masculine-de-basket-3x3-2026-calendrier-et-resultats\/\">Calendrier et r\u00e9sultats de la Coupe du monde masculine de basket 3&#215;3<\/a><\/strong><\/li>\n<\/ul>\n<h2 style=\"text-align: justify;\" data-path-to-node=\"2\">Un d\u00e9part s\u00e9rieux avant le r\u00e9veil de Porto Rico<\/h2>\n<p style=\"text-align: justify;\" data-path-to-node=\"3\">Les <strong>Bleus<\/strong> entament la rencontre de la meilleure des mani\u00e8res en r\u00e9citant parfaitement leur basket d\u00e8s les premi\u00e8res secondes. Appliqu\u00e9s, les Fran\u00e7ais r\u00e8glent la mire de loin et plantent rapidement deux tirs prim\u00e9s \u00e0 deux points. L&rsquo;entame de match des Tricolores est s\u00e9rieuse, notamment gr\u00e2ce au gros boulot d&rsquo;<strong>Emmanuel Monceau<\/strong> \u00e0 l&rsquo;int\u00e9rieur, qui p\u00e8se physiquement et g\u00eane \u00e9norm\u00e9ment les attaquants <strong>portoricains<\/strong>\u00a0dans la raquette.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">Alex Vialaret \ud835\ude59\ud835\ude64 \ud835\ude5e\ud835\ude69 \ud835\ude56\ud835\ude61\ud835\ude61 \u2728<\/p>\n<p>Suivez la rencontre en direct sur <a href=\"https:\/\/t.co\/dnO12lk1wG\">https:\/\/t.co\/dnO12lk1wG<\/a> \ud83d\udcfa <a href=\"https:\/\/x.com\/hashtag\/3x3WC?src=hash&amp;ref_src=twsrc%5Etfw\">#3x3WC<\/a> | <a href=\"https:\/\/x.com\/hashtag\/FRAPUR?src=hash&amp;ref_src=twsrc%5Etfw\">#FRAPUR<\/a> <a href=\"https:\/\/t.co\/iJLTzN7NwN\">pic.twitter.com\/iJLTzN7NwN<\/a><\/p>\n<p>\u2014 3&#215;3 FFBB (@3x3ffbb) <a href=\"https:\/\/x.com\/3x3ffbb\/status\/2061837289773277402?ref_src=twsrc%5Etfw\">June 2, 2026<\/a><\/p><\/blockquote>\n<p style=\"text-align: justify;\"><script async src=\"https:\/\/platform.x.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p style=\"text-align: justify;\" data-path-to-node=\"4\">Gr\u00e2ce \u00e0 cette assise d\u00e9fensive, l&rsquo;\u00e9cart oscille entre deux et quatre points d&rsquo;avance en faveur de la <strong>France<\/strong>, qui fait la course en t\u00eate durant les cinq premi\u00e8res minutes de cette partie. Alors que les <strong>Bleus<\/strong> ma\u00eetrisent leur sujet et m\u00e8nent logiquement (<b data-path-to-node=\"6\" data-index-in-node=\"96\">9-6<\/b>), le momentum change de camp. En panne d&rsquo;adresse et un peu plus passifs en d\u00e9fense, les <strong>Fran\u00e7ais<\/strong> subissent le r\u00e9veil des <strong>Portoricains<\/strong>. Port\u00e9s par leur vitesse de jeu, ils infligent un 5-0 de suite aux <strong>Bleus<\/strong> pour passer devant pour la toute premi\u00e8re fois du match. \u00a0N\u00e9anmoins, les Portoricains atteignent assez t\u00f4t la barre des 7 fautes d&rsquo;\u00e9quipe. D\u00e9sormais dans la p\u00e9nalit\u00e9, ils vont devoir limiter leurs contacts, ce qui pourrait avoir un impact sur la gestion de la seconde partie du match pour les attaquants fran\u00e7ais.<\/p>\n<h2 style=\"text-align: justify;\" data-path-to-node=\"4\">Une fin de match d\u00e9cousue et un dernier stop pour lib\u00e9rer les Bleus<\/h2>\n<p style=\"text-align: justify;\" data-path-to-node=\"3\">Dans le sillage de leur bonne entame, les <strong>Bleus<\/strong> affichent une grosse discipline collective, ils restent tr\u00e8s s\u00e9rieux en d\u00e9fense et, surtout, commettent tr\u00e8s peu de fautes par rapport \u00e0 leurs adversaires. Le score est serr\u00e9 (14-14) \u00e0 trois minutes de la fin du temps r\u00e9glementaire, montrant le caract\u00e8re pi\u00e9geux de cette rencontre. Gr\u00e2ce \u00e0 cette rigueur d\u00e9fensive, <strong>l\u2019\u00e9quipe de France<\/strong> parvient \u00e0 reprendre l\u2019avantage au tableau d&rsquo;affichage. Pour autant, les Fran\u00e7ais n\u2019arrivent pas \u00e0 faire le break d\u00e9finitif pour se mettre \u00e0 l&rsquo;abri. La tension monte d&rsquo;un cran, le jeu devient de plus en plus d\u00e9cousu sous la fatigue et l&rsquo;adresse fuit totalement les deux \u00e9quipes, les tirs ne rentrant plus du tout de part et d\u2019autre.<\/p>\n<p style=\"text-align: justify;\" data-path-to-node=\"6\">Dans cette fin de match o\u00f9 chaque possession vaut de l&rsquo;or, la d\u00e9livrance vient de la d\u00e9fense tricolore. Alors qu&rsquo;ils font la course en t\u00eate avec une courte avance, les Bleus s&rsquo;arrachent pour r\u00e9ussir un ultime stop d\u00e9fensif sur la derni\u00e8re tentative portoricaine. Cette solidit\u00e9 dans les derni\u00e8res secondes permet \u00e0 la <strong>France<\/strong> de s&rsquo;imposer sur le score serr\u00e9 de <b data-path-to-node=\"7\" data-index-in-node=\"97\">18-16<\/b>. Apr\u00e8s leur succ\u00e8s tout \u00e0 l&rsquo;heure face \u00e0 la <strong>Belgique<\/strong>, les Bleus signent un parfait deux sur deux aujourd&rsquo;hui et se placent id\u00e9alement dans cette phase de poules de la Coupe du monde.<\/p>\n<h3 data-path-to-node=\"6\">\u00c0 lire aussi<\/h3>\n<div class=\"vlp-link-container vlp-layout-article\"><a href=\"https:\/\/dicodusport.fr\/blog\/les-bleues-obtiennent-leur-premier-succes-a-la-coupe-du-monde-de-basket-3x3-face-a-la-lituanie\/\" class=\"vlp-link\" title=\"Les Bleues obtiennent leur premier succ\u00e8s \u00e0 la Coupe du monde de basket 3x3 face \u00e0 la Lituanie\"><\/a><div class=\"vlp-layout-zone-side\"><div class=\"vlp-block-4 vlp-link-image\"><img loading=\"lazy\" decoding=\"async\" style=\"max-width: 792px;\" width=\"792\" height=\"445\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/06\/Les-Bleues-obtiennent-leur-premier-succes-a-la-Coupe-du-monde-de-basket-3-3-face-a-la-Lituanie.png\" class=\"attachment-800x445 size-800x445\" alt=\"Les Bleues obtiennent leur premier succ\u00e8s \u00e0 la Coupe du monde de basket 3-3 face \u00e0 la Lituanie\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/06\/Les-Bleues-obtiennent-leur-premier-succes-a-la-Coupe-du-monde-de-basket-3-3-face-a-la-Lituanie.png 1200w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/06\/Les-Bleues-obtiennent-leur-premier-succes-a-la-Coupe-du-monde-de-basket-3-3-face-a-la-Lituanie-300x169.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/06\/Les-Bleues-obtiennent-leur-premier-succes-a-la-Coupe-du-monde-de-basket-3-3-face-a-la-Lituanie-1024x575.png 1024w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/06\/Les-Bleues-obtiennent-leur-premier-succes-a-la-Coupe-du-monde-de-basket-3-3-face-a-la-Lituanie-768x431.png 768w\" sizes=\"auto, (max-width: 792px) 100vw, 792px\" \/><\/div><\/div><div class=\"vlp-layout-zone-main\"><div class=\"vlp-block-0 vlp-link-title\">Les Bleues obtiennent leur premier succ\u00e8s \u00e0 la Coupe du monde de basket 3x3 face \u00e0 la Lituanie<\/div><div class=\"vlp-block-1 vlp-link-summary\">COUPE DU MONDE F\u00c9MININE DE BASKET 3X3 2026 - Les Bleues ont rebondi en ne faisant qu'une bouch\u00e9e de la Lituanie (21-12) ce mardi apr\u00e8s-midi.<\/div><div class=\"vlp-block-2 vlp-link-button\">Lire l'article<\/div><div class=\"vlp-block-3 vlp-link-url\">dicodusport.fr<\/div><\/div><\/div>\n<div id=\"gtx-trans\" style=\"position: absolute; left: -14px; top: 40.9091px;\">\n<div class=\"gtx-trans-icon\" style=\"text-align: justify;\"><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>COUPE DU MONDE MASCULINE DE BASKET 3&#215;3 &#8211; Quelques heures apr\u00e8s avoir domin\u00e9 la Belgique d&rsquo;un point, l&rsquo;\u00e9quipe de France masculine a encha\u00een\u00e9 en s&rsquo;imposant au forceps face \u00e0 Porto Rico (18-16).\u00a0<\/p>\n","protected":false},"author":111,"featured_media":675213,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[27116],"tags":[9140,16878,47550],"class_list":["post-675173","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-basket-ball-3x3","tag-basket-3x3","tag-breve","tag-coupe-du-monde-de-basket-3x3"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Deux sur deux pour les Bleus, vainqueurs dans la douleur face \u00e0 Porto Rico en Coupe du monde de basket 3x3<\/title>\n<meta name=\"description\" content=\"COUPE DU MONDE MASCULINE DE BASKET 3x3 - Quelques heures apr\u00e8s avoir domin\u00e9 la Belgique d&#039;un point, l&#039;\u00e9quipe de France masculine a encha\u00een\u00e9 en s&#039;imposant au forceps face \u00e0 Porto Rico (18-16).\u00a0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/deux-sur-deux-pour-les-bleus-vainqueurs-dans-la-douleur-face-a-porto-rico-en-coupe-du-monde-de-basket-3x3\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Deux sur deux pour les Bleus, vainqueurs dans la douleur face \u00e0 Porto Rico en Coupe du monde de basket 3x3\" \/>\n<meta property=\"og:description\" content=\"COUPE DU MONDE MASCULINE DE BASKET 3x3 - Quelques heures apr\u00e8s avoir domin\u00e9 la Belgique d&#039;un point, l&#039;\u00e9quipe de France masculine a encha\u00een\u00e9 en s&#039;imposant au forceps face \u00e0 Porto Rico (18-16).\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/deux-sur-deux-pour-les-bleus-vainqueurs-dans-la-douleur-face-a-porto-rico-en-coupe-du-monde-de-basket-3x3\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2026-06-02T15:59:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-02T16:09:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/06\/Deux-sur-deux-pour-les-Bleus-vainqueurs-dans-la-douleur-face-a-Porto-Rico-en-Coupe-du-monde-de-basket-3x3-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"L\u00e9o Derambure\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Deux sur deux pour les Bleus, vainqueurs dans la douleur face \u00e0 Porto Rico en Coupe du monde de basket 3x3\" \/>\n<meta name=\"twitter:creator\" content=\"@dicodusport\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/deux-sur-deux-pour-les-bleus-vainqueurs-dans-la-douleur-face-a-porto-rico-en-coupe-du-monde-de-basket-3x3\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/deux-sur-deux-pour-les-bleus-vainqueurs-dans-la-douleur-face-a-porto-rico-en-coupe-du-monde-de-basket-3x3\\\/\"},\"author\":{\"name\":\"L\u00e9o Derambure\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/93f03e222ed8da203c940d17ef257295\"},\"headline\":\"Deux sur deux pour les Bleus, vainqueurs dans la douleur face \u00e0 Porto Rico en Coupe du monde de basket 3&#215;3\",\"datePublished\":\"2026-06-02T15:59:48+00:00\",\"dateModified\":\"2026-06-02T16:09:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/deux-sur-deux-pour-les-bleus-vainqueurs-dans-la-douleur-face-a-porto-rico-en-coupe-du-monde-de-basket-3x3\\\/\"},\"wordCount\":767,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/deux-sur-deux-pour-les-bleus-vainqueurs-dans-la-douleur-face-a-porto-rico-en-coupe-du-monde-de-basket-3x3\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Deux-sur-deux-pour-les-Bleus-vainqueurs-dans-la-douleur-face-a-Porto-Rico-en-Coupe-du-monde-de-basket-3x3-1.png\",\"keywords\":[\"Basket 3x3\",\"br\u00e8ve\",\"Coupe du monde de basket 3x3\"],\"articleSection\":[\"Basket-ball 3x3\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/deux-sur-deux-pour-les-bleus-vainqueurs-dans-la-douleur-face-a-porto-rico-en-coupe-du-monde-de-basket-3x3\\\/#respond\"]}],\"copyrightYear\":\"2026\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/deux-sur-deux-pour-les-bleus-vainqueurs-dans-la-douleur-face-a-porto-rico-en-coupe-du-monde-de-basket-3x3\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/deux-sur-deux-pour-les-bleus-vainqueurs-dans-la-douleur-face-a-porto-rico-en-coupe-du-monde-de-basket-3x3\\\/\",\"name\":\"Deux sur deux pour les Bleus, vainqueurs dans la douleur face \u00e0 Porto Rico en Coupe du monde de basket 3x3\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/deux-sur-deux-pour-les-bleus-vainqueurs-dans-la-douleur-face-a-porto-rico-en-coupe-du-monde-de-basket-3x3\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/deux-sur-deux-pour-les-bleus-vainqueurs-dans-la-douleur-face-a-porto-rico-en-coupe-du-monde-de-basket-3x3\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Deux-sur-deux-pour-les-Bleus-vainqueurs-dans-la-douleur-face-a-Porto-Rico-en-Coupe-du-monde-de-basket-3x3-1.png\",\"datePublished\":\"2026-06-02T15:59:48+00:00\",\"dateModified\":\"2026-06-02T16:09:41+00:00\",\"description\":\"COUPE DU MONDE MASCULINE DE BASKET 3x3 - Quelques heures apr\u00e8s avoir domin\u00e9 la Belgique d'un point, l'\u00e9quipe de France masculine a encha\u00een\u00e9 en s'imposant au forceps face \u00e0 Porto Rico (18-16).\u00a0\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/deux-sur-deux-pour-les-bleus-vainqueurs-dans-la-douleur-face-a-porto-rico-en-coupe-du-monde-de-basket-3x3\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/deux-sur-deux-pour-les-bleus-vainqueurs-dans-la-douleur-face-a-porto-rico-en-coupe-du-monde-de-basket-3x3\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/deux-sur-deux-pour-les-bleus-vainqueurs-dans-la-douleur-face-a-porto-rico-en-coupe-du-monde-de-basket-3x3\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Deux-sur-deux-pour-les-Bleus-vainqueurs-dans-la-douleur-face-a-Porto-Rico-en-Coupe-du-monde-de-basket-3x3-1.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Deux-sur-deux-pour-les-Bleus-vainqueurs-dans-la-douleur-face-a-Porto-Rico-en-Coupe-du-monde-de-basket-3x3-1.png\",\"width\":1200,\"height\":674,\"caption\":\"Deux sur deux pour les Bleus, vainqueurs dans la douleur face \u00e0 Porto Rico en Coupe du monde de basket 3x3\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/deux-sur-deux-pour-les-bleus-vainqueurs-dans-la-douleur-face-a-porto-rico-en-coupe-du-monde-de-basket-3x3\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Deux sur deux pour les Bleus, vainqueurs dans la douleur face \u00e0 Porto Rico en Coupe du monde de basket 3&#215;3\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/93f03e222ed8da203c940d17ef257295\",\"name\":\"L\u00e9o Derambure\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Maillot-Dicodusport-Lele-150x150.png\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Maillot-Dicodusport-Lele-150x150.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Maillot-Dicodusport-Lele-150x150.png\",\"caption\":\"L\u00e9o Derambure\"},\"description\":\"Passionn\u00e9 de sport depuis l\u2019enfance, j\u2019ai grandi au rythme des grands \u00e9v\u00e9nements comme les Jeux Olympiques, les championnats du monde d\u2019athl\u00e9tisme et de natation, ou encore le Tour de France sur France T\u00e9l\u00e9visions. Abonn\u00e9 au RC Lens depuis 2008, cette ferveur m\u2019a \u00e9t\u00e9 transmise d\u00e8s l\u2019\u00e2ge de 5 ans par mon grand-p\u00e8re et mon p\u00e8re. Avec Rafael Nadal ou encore Aruna Dindane comme idole, j\u2019ai toujours ressenti l\u2019envie de partager cette passion \u00e0 travers l\u2019\u00e9criture. Apr\u00e8s les Jeux Olympiques de Paris 2024, j\u2019ai franchi le pas en rejoignant l\u2019\u00e9quipe de r\u00e9daction de Dicodusport. Aujourd\u2019hui, je couvre le biathlon, le ski alpin ainsi que les rencontres des clubs fran\u00e7ais en comp\u00e9titions europ\u00e9ennes, avec l'envie de faire vivre chaque instant sportif et de transmettre ces \u00e9motions au lecteur, comme s\u2019il \u00e9tait au c\u0153ur de l\u2019\u00e9v\u00e9nement.\",\"worksFor\":\"L\u00e9o Derambure\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/leo-derambure\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Deux sur deux pour les Bleus, vainqueurs dans la douleur face \u00e0 Porto Rico en Coupe du monde de basket 3x3","description":"COUPE DU MONDE MASCULINE DE BASKET 3x3 - Quelques heures apr\u00e8s avoir domin\u00e9 la Belgique d'un point, l'\u00e9quipe de France masculine a encha\u00een\u00e9 en s'imposant au forceps face \u00e0 Porto Rico (18-16).\u00a0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/deux-sur-deux-pour-les-bleus-vainqueurs-dans-la-douleur-face-a-porto-rico-en-coupe-du-monde-de-basket-3x3\/","og_locale":"fr_FR","og_type":"article","og_title":"Deux sur deux pour les Bleus, vainqueurs dans la douleur face \u00e0 Porto Rico en Coupe du monde de basket 3x3","og_description":"COUPE DU MONDE MASCULINE DE BASKET 3x3 - Quelques heures apr\u00e8s avoir domin\u00e9 la Belgique d'un point, l'\u00e9quipe de France masculine a encha\u00een\u00e9 en s'imposant au forceps face \u00e0 Porto Rico (18-16).\u00a0","og_url":"https:\/\/dicodusport.fr\/blog\/deux-sur-deux-pour-les-bleus-vainqueurs-dans-la-douleur-face-a-porto-rico-en-coupe-du-monde-de-basket-3x3\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2026-06-02T15:59:48+00:00","article_modified_time":"2026-06-02T16:09:41+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/06\/Deux-sur-deux-pour-les-Bleus-vainqueurs-dans-la-douleur-face-a-Porto-Rico-en-Coupe-du-monde-de-basket-3x3-1.png","type":"image\/png"}],"author":"L\u00e9o Derambure","twitter_card":"summary_large_image","twitter_title":"Deux sur deux pour les Bleus, vainqueurs dans la douleur face \u00e0 Porto Rico en Coupe du monde de basket 3x3","twitter_creator":"@dicodusport","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/deux-sur-deux-pour-les-bleus-vainqueurs-dans-la-douleur-face-a-porto-rico-en-coupe-du-monde-de-basket-3x3\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/deux-sur-deux-pour-les-bleus-vainqueurs-dans-la-douleur-face-a-porto-rico-en-coupe-du-monde-de-basket-3x3\/"},"author":{"name":"L\u00e9o Derambure","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/93f03e222ed8da203c940d17ef257295"},"headline":"Deux sur deux pour les Bleus, vainqueurs dans la douleur face \u00e0 Porto Rico en Coupe du monde de basket 3&#215;3","datePublished":"2026-06-02T15:59:48+00:00","dateModified":"2026-06-02T16:09:41+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/deux-sur-deux-pour-les-bleus-vainqueurs-dans-la-douleur-face-a-porto-rico-en-coupe-du-monde-de-basket-3x3\/"},"wordCount":767,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/deux-sur-deux-pour-les-bleus-vainqueurs-dans-la-douleur-face-a-porto-rico-en-coupe-du-monde-de-basket-3x3\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/06\/Deux-sur-deux-pour-les-Bleus-vainqueurs-dans-la-douleur-face-a-Porto-Rico-en-Coupe-du-monde-de-basket-3x3-1.png","keywords":["Basket 3x3","br\u00e8ve","Coupe du monde de basket 3x3"],"articleSection":["Basket-ball 3x3"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/deux-sur-deux-pour-les-bleus-vainqueurs-dans-la-douleur-face-a-porto-rico-en-coupe-du-monde-de-basket-3x3\/#respond"]}],"copyrightYear":"2026","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/deux-sur-deux-pour-les-bleus-vainqueurs-dans-la-douleur-face-a-porto-rico-en-coupe-du-monde-de-basket-3x3\/","url":"https:\/\/dicodusport.fr\/blog\/deux-sur-deux-pour-les-bleus-vainqueurs-dans-la-douleur-face-a-porto-rico-en-coupe-du-monde-de-basket-3x3\/","name":"Deux sur deux pour les Bleus, vainqueurs dans la douleur face \u00e0 Porto Rico en Coupe du monde de basket 3x3","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/deux-sur-deux-pour-les-bleus-vainqueurs-dans-la-douleur-face-a-porto-rico-en-coupe-du-monde-de-basket-3x3\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/deux-sur-deux-pour-les-bleus-vainqueurs-dans-la-douleur-face-a-porto-rico-en-coupe-du-monde-de-basket-3x3\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/06\/Deux-sur-deux-pour-les-Bleus-vainqueurs-dans-la-douleur-face-a-Porto-Rico-en-Coupe-du-monde-de-basket-3x3-1.png","datePublished":"2026-06-02T15:59:48+00:00","dateModified":"2026-06-02T16:09:41+00:00","description":"COUPE DU MONDE MASCULINE DE BASKET 3x3 - Quelques heures apr\u00e8s avoir domin\u00e9 la Belgique d'un point, l'\u00e9quipe de France masculine a encha\u00een\u00e9 en s'imposant au forceps face \u00e0 Porto Rico (18-16).\u00a0","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/deux-sur-deux-pour-les-bleus-vainqueurs-dans-la-douleur-face-a-porto-rico-en-coupe-du-monde-de-basket-3x3\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/deux-sur-deux-pour-les-bleus-vainqueurs-dans-la-douleur-face-a-porto-rico-en-coupe-du-monde-de-basket-3x3\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/deux-sur-deux-pour-les-bleus-vainqueurs-dans-la-douleur-face-a-porto-rico-en-coupe-du-monde-de-basket-3x3\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/06\/Deux-sur-deux-pour-les-Bleus-vainqueurs-dans-la-douleur-face-a-Porto-Rico-en-Coupe-du-monde-de-basket-3x3-1.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/06\/Deux-sur-deux-pour-les-Bleus-vainqueurs-dans-la-douleur-face-a-Porto-Rico-en-Coupe-du-monde-de-basket-3x3-1.png","width":1200,"height":674,"caption":"Deux sur deux pour les Bleus, vainqueurs dans la douleur face \u00e0 Porto Rico en Coupe du monde de basket 3x3"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/deux-sur-deux-pour-les-bleus-vainqueurs-dans-la-douleur-face-a-porto-rico-en-coupe-du-monde-de-basket-3x3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Deux sur deux pour les Bleus, vainqueurs dans la douleur face \u00e0 Porto Rico en Coupe du monde de basket 3&#215;3"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/93f03e222ed8da203c940d17ef257295","name":"L\u00e9o Derambure","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Maillot-Dicodusport-Lele-150x150.png","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Maillot-Dicodusport-Lele-150x150.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Maillot-Dicodusport-Lele-150x150.png","caption":"L\u00e9o Derambure"},"description":"Passionn\u00e9 de sport depuis l\u2019enfance, j\u2019ai grandi au rythme des grands \u00e9v\u00e9nements comme les Jeux Olympiques, les championnats du monde d\u2019athl\u00e9tisme et de natation, ou encore le Tour de France sur France T\u00e9l\u00e9visions. Abonn\u00e9 au RC Lens depuis 2008, cette ferveur m\u2019a \u00e9t\u00e9 transmise d\u00e8s l\u2019\u00e2ge de 5 ans par mon grand-p\u00e8re et mon p\u00e8re. Avec Rafael Nadal ou encore Aruna Dindane comme idole, j\u2019ai toujours ressenti l\u2019envie de partager cette passion \u00e0 travers l\u2019\u00e9criture. Apr\u00e8s les Jeux Olympiques de Paris 2024, j\u2019ai franchi le pas en rejoignant l\u2019\u00e9quipe de r\u00e9daction de Dicodusport. Aujourd\u2019hui, je couvre le biathlon, le ski alpin ainsi que les rencontres des clubs fran\u00e7ais en comp\u00e9titions europ\u00e9ennes, avec l'envie de faire vivre chaque instant sportif et de transmettre ces \u00e9motions au lecteur, comme s\u2019il \u00e9tait au c\u0153ur de l\u2019\u00e9v\u00e9nement.","worksFor":"L\u00e9o Derambure","url":"https:\/\/dicodusport.fr\/blog\/author\/leo-derambure\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/675173","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/111"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=675173"}],"version-history":[{"count":5,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/675173\/revisions"}],"predecessor-version":[{"id":675220,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/675173\/revisions\/675220"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/675213"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=675173"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=675173"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=675173"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}