{"id":67856,"date":"2020-05-30T12:58:58","date_gmt":"2020-05-30T10:58:58","guid":{"rendered":"http:\/\/dicodusport.fr\/blog\/?p=67856&#038;preview=true&#038;preview_id=67856"},"modified":"2020-05-30T13:06:00","modified_gmt":"2020-05-30T11:06:00","slug":"dopage-echantillons-tour-de-france-2017-vont-etre-reanalyses","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/dopage-echantillons-tour-de-france-2017-vont-etre-reanalyses\/","title":{"rendered":"Dopage : des \u00e9chantillons du Tour de France 2017 vont \u00eatre r\u00e9analys\u00e9s"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>CYCLISME &#8211; Dans le c<\/em><\/strong><strong><em>adre de l&rsquo;op\u00e9ration Aderlass, le <a href=\"https:\/\/www.nieuwsblad.be\/cnt\/dmf20200529_04976010\" target=\"_blank\" rel=\"noopener noreferrer\">Het Nieuwsblad<\/a> annonce que des \u00e9chantillons du Tour de France 2017 vont \u00eatre r\u00e9analys\u00e9s par la CADF (Fondation Antidopage du Cyclisme).<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">Amorc\u00e9e en f\u00e9vrier 2019, l&rsquo;<strong>op\u00e9ration Aderlass<\/strong> avait secou\u00e9 la plan\u00e8te sport. Cette derni\u00e8re a mis en exergue un r\u00e9seau organis\u00e9 de dopage sanguin, en Autriche mais aussi en Allemagne. Dans un premier temps, les sports d&rsquo;hiver \u00e9taient cibl\u00e9s, avant que le cyclisme ne soit lui aussi concern\u00e9. Parmi les coureurs impliqu\u00e9s, <a href=\"https:\/\/www.lequipe.fr\/Cyclisme-sur-route\/Actualites\/L-autrichien-georg-preidler-avoue-s-etre-dope\/994883\" target=\"_blank\" rel=\"noopener noreferrer\">le nom de l&rsquo;Autrichien <strong>Georg Preidler<\/strong><\/a>, membre de la formation <strong>Sunweb<\/strong> en 2017 puis co\u00e9quipier de <strong>Thibaut Pinot<\/strong> chez la <strong>Groupama-FDJ<\/strong>, jusqu&rsquo;\u00e0 son licenciement en mars 2019, avait \u00e9t\u00e9 \u00e9pingl\u00e9. Ce dernier avait alors avou\u00e9, quelques semaines apr\u00e8s le d\u00e9mant\u00e8lement du r\u00e9seau, avoir eu recours au dopage sanguin.<\/p>\n<h2 style=\"text-align: justify;\">Des \u00e9chantillons du Tour 2017 de nouveau analys\u00e9s<\/h2>\n<p style=\"text-align: justify;\">C&rsquo;est dans le cadre de cette <strong>op\u00e9ration Aderlass<\/strong> que des \u00e9chantillons datant du <strong>Tour 2017<\/strong> vont \u00eatre r\u00e9examin\u00e9s. Selon le <strong><em>Het Nieuwblad<\/em><\/strong>, la <strong>CADF<\/strong>, sur demande de l&rsquo;<strong>UCI<\/strong>, a pour objectif de d\u00e9tecter un produit <em>\u00ab d&rsquo;origine am\u00e9ricaine \u00bb<\/em>, ind\u00e9tectable il y a trois ans. \u00ab<em> Sur la base des informations obtenues, nous avons identifi\u00e9 les \u00e9chantillons pertinents et r\u00e9alis\u00e9 les premi\u00e8res analyses \u00bb, <\/em>a indiqu\u00e9 la <strong>Fondation Antidopage du Cyclisme<\/strong>. Toujours selon le quotidien belge, des t\u00e9moignages au cours de l&rsquo;<strong>op\u00e9ration Aderlass<\/strong> seraient \u00e0 l&rsquo;origine de ces nouvelles analyses. Affaire \u00e0 suive, d\u00e9sormais.<\/p>\n<p><strong><em>Dicodusport<br \/>\n<a href=\"https:\/\/www.facebook.com\/dicodusport\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2909\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-facebook-150x150.png\" alt=\"\" width=\"40\" height=\"40\" \/><\/a><a href=\"https:\/\/twitter.com\/dicodusport\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2908\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-twitter-150x150.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>CYCLISME &#8211; Dans le cadre de l&rsquo;affaire Aderlass, le Het Nieuwsblad annonce que des \u00e9chantillons du Tour de France 2017 vont \u00eatre r\u00e9analys\u00e9s par la CADF (Fondation Antidopage du Cyclisme).<\/p>\n","protected":false},"author":4,"featured_media":67857,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[2307],"tags":[2886],"class_list":["post-67856","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cyclisme","tag-dopage"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Dopage : des \u00e9chantillons du Tour de France 2017 vont \u00eatre r\u00e9analys\u00e9s<\/title>\n<meta name=\"description\" content=\"CYCLISME - Dans le cadre de l&#039;affaire Aderlass, le Het Nieuwsblad annonce que des \u00e9chantillons du Tour de France 2017 vont \u00eatre r\u00e9analys\u00e9s par la CADF.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/dopage-echantillons-tour-de-france-2017-vont-etre-reanalyses\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dopage : Des \u00e9chantillons du Tour de France 2017 vont \u00eatre r\u00e9analys\u00e9s\" \/>\n<meta property=\"og:description\" content=\"CYCLISME - Dans le cadre de l&#039;affaire Aderlass, le Het Nieuwsblad annonce que des \u00e9chantillons du Tour de France 2017 vont \u00eatre r\u00e9analys\u00e9s par la CADF.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/dopage-echantillons-tour-de-france-2017-vont-etre-reanalyses\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/florent.ostermann\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-30T10:58:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-05-30T11:06:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/05\/Dopage-Des-\u00e9chantillons-du-Tour-de-France-2017-vont-\u00eatre-r\u00e9analys\u00e9s.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Flo Ostermann\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Dopage : Des \u00e9chantillons du Tour de France 2017 vont \u00eatre r\u00e9analys\u00e9s\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/FlOstermann\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/dopage-echantillons-tour-de-france-2017-vont-etre-reanalyses\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/dopage-echantillons-tour-de-france-2017-vont-etre-reanalyses\/\"},\"author\":{\"name\":\"Flo Ostermann\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a\"},\"headline\":\"Dopage : des \u00e9chantillons du Tour de France 2017 vont \u00eatre r\u00e9analys\u00e9s\",\"datePublished\":\"2020-05-30T10:58:58+00:00\",\"dateModified\":\"2020-05-30T11:06:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/dopage-echantillons-tour-de-france-2017-vont-etre-reanalyses\/\"},\"wordCount\":270,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/dopage-echantillons-tour-de-france-2017-vont-etre-reanalyses\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/05\/Dopage-Des-\u00e9chantillons-du-Tour-de-France-2017-vont-\u00eatre-r\u00e9analys\u00e9s.png\",\"keywords\":[\"dopage\"],\"articleSection\":[\"Cyclisme\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/dopage-echantillons-tour-de-france-2017-vont-etre-reanalyses\/#respond\"]}],\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/dopage-echantillons-tour-de-france-2017-vont-etre-reanalyses\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/dopage-echantillons-tour-de-france-2017-vont-etre-reanalyses\/\",\"name\":\"Dopage : des \u00e9chantillons du Tour de France 2017 vont \u00eatre r\u00e9analys\u00e9s\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/dopage-echantillons-tour-de-france-2017-vont-etre-reanalyses\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/dopage-echantillons-tour-de-france-2017-vont-etre-reanalyses\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/05\/Dopage-Des-\u00e9chantillons-du-Tour-de-France-2017-vont-\u00eatre-r\u00e9analys\u00e9s.png\",\"datePublished\":\"2020-05-30T10:58:58+00:00\",\"dateModified\":\"2020-05-30T11:06:00+00:00\",\"description\":\"CYCLISME - Dans le cadre de l'affaire Aderlass, le Het Nieuwsblad annonce que des \u00e9chantillons du Tour de France 2017 vont \u00eatre r\u00e9analys\u00e9s par la CADF.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/dopage-echantillons-tour-de-france-2017-vont-etre-reanalyses\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/dopage-echantillons-tour-de-france-2017-vont-etre-reanalyses\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/dopage-echantillons-tour-de-france-2017-vont-etre-reanalyses\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/05\/Dopage-Des-\u00e9chantillons-du-Tour-de-France-2017-vont-\u00eatre-r\u00e9analys\u00e9s.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/05\/Dopage-Des-\u00e9chantillons-du-Tour-de-France-2017-vont-\u00eatre-r\u00e9analys\u00e9s.png\",\"width\":800,\"height\":445,\"caption\":\"Dopage - Des \u00e9chantillons du Tour de France 2017 vont \u00eatre r\u00e9analys\u00e9s\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/dopage-echantillons-tour-de-france-2017-vont-etre-reanalyses\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dopage : des \u00e9chantillons du Tour de France 2017 vont \u00eatre r\u00e9analys\u00e9s\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a\",\"name\":\"Flo Ostermann\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg\",\"caption\":\"Flo Ostermann\"},\"description\":\"Journaliste\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !\",\"sameAs\":[\"https:\/\/www.facebook.com\/florent.ostermann\",\"https:\/\/x.com\/https:\/\/twitter.com\/FlOstermann\",\"admin\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/flo\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Dopage : des \u00e9chantillons du Tour de France 2017 vont \u00eatre r\u00e9analys\u00e9s","description":"CYCLISME - Dans le cadre de l'affaire Aderlass, le Het Nieuwsblad annonce que des \u00e9chantillons du Tour de France 2017 vont \u00eatre r\u00e9analys\u00e9s par la CADF.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/dopage-echantillons-tour-de-france-2017-vont-etre-reanalyses\/","og_locale":"fr_FR","og_type":"article","og_title":"Dopage : Des \u00e9chantillons du Tour de France 2017 vont \u00eatre r\u00e9analys\u00e9s","og_description":"CYCLISME - Dans le cadre de l'affaire Aderlass, le Het Nieuwsblad annonce que des \u00e9chantillons du Tour de France 2017 vont \u00eatre r\u00e9analys\u00e9s par la CADF.","og_url":"https:\/\/dicodusport.fr\/blog\/dopage-echantillons-tour-de-france-2017-vont-etre-reanalyses\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/florent.ostermann","article_published_time":"2020-05-30T10:58:58+00:00","article_modified_time":"2020-05-30T11:06:00+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/05\/Dopage-Des-\u00e9chantillons-du-Tour-de-France-2017-vont-\u00eatre-r\u00e9analys\u00e9s.png","type":"image\/png"}],"author":"Flo Ostermann","twitter_card":"summary_large_image","twitter_title":"Dopage : Des \u00e9chantillons du Tour de France 2017 vont \u00eatre r\u00e9analys\u00e9s","twitter_creator":"@https:\/\/twitter.com\/FlOstermann","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/dopage-echantillons-tour-de-france-2017-vont-etre-reanalyses\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/dopage-echantillons-tour-de-france-2017-vont-etre-reanalyses\/"},"author":{"name":"Flo Ostermann","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a"},"headline":"Dopage : des \u00e9chantillons du Tour de France 2017 vont \u00eatre r\u00e9analys\u00e9s","datePublished":"2020-05-30T10:58:58+00:00","dateModified":"2020-05-30T11:06:00+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/dopage-echantillons-tour-de-france-2017-vont-etre-reanalyses\/"},"wordCount":270,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/dopage-echantillons-tour-de-france-2017-vont-etre-reanalyses\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/05\/Dopage-Des-\u00e9chantillons-du-Tour-de-France-2017-vont-\u00eatre-r\u00e9analys\u00e9s.png","keywords":["dopage"],"articleSection":["Cyclisme"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/dopage-echantillons-tour-de-france-2017-vont-etre-reanalyses\/#respond"]}],"copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/dopage-echantillons-tour-de-france-2017-vont-etre-reanalyses\/","url":"https:\/\/dicodusport.fr\/blog\/dopage-echantillons-tour-de-france-2017-vont-etre-reanalyses\/","name":"Dopage : des \u00e9chantillons du Tour de France 2017 vont \u00eatre r\u00e9analys\u00e9s","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/dopage-echantillons-tour-de-france-2017-vont-etre-reanalyses\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/dopage-echantillons-tour-de-france-2017-vont-etre-reanalyses\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/05\/Dopage-Des-\u00e9chantillons-du-Tour-de-France-2017-vont-\u00eatre-r\u00e9analys\u00e9s.png","datePublished":"2020-05-30T10:58:58+00:00","dateModified":"2020-05-30T11:06:00+00:00","description":"CYCLISME - Dans le cadre de l'affaire Aderlass, le Het Nieuwsblad annonce que des \u00e9chantillons du Tour de France 2017 vont \u00eatre r\u00e9analys\u00e9s par la CADF.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/dopage-echantillons-tour-de-france-2017-vont-etre-reanalyses\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/dopage-echantillons-tour-de-france-2017-vont-etre-reanalyses\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/dopage-echantillons-tour-de-france-2017-vont-etre-reanalyses\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/05\/Dopage-Des-\u00e9chantillons-du-Tour-de-France-2017-vont-\u00eatre-r\u00e9analys\u00e9s.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/05\/Dopage-Des-\u00e9chantillons-du-Tour-de-France-2017-vont-\u00eatre-r\u00e9analys\u00e9s.png","width":800,"height":445,"caption":"Dopage - Des \u00e9chantillons du Tour de France 2017 vont \u00eatre r\u00e9analys\u00e9s"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/dopage-echantillons-tour-de-france-2017-vont-etre-reanalyses\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Dopage : des \u00e9chantillons du Tour de France 2017 vont \u00eatre r\u00e9analys\u00e9s"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a","name":"Flo Ostermann","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","caption":"Flo Ostermann"},"description":"Journaliste\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !","sameAs":["https:\/\/www.facebook.com\/florent.ostermann","https:\/\/x.com\/https:\/\/twitter.com\/FlOstermann","admin"],"url":"https:\/\/dicodusport.fr\/blog\/author\/flo\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/67856","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=67856"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/67856\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/67857"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=67856"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=67856"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=67856"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}