{"id":679239,"date":"2026-06-15T10:00:16","date_gmt":"2026-06-15T08:00:16","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=679239&#038;preview=true&#038;preview_id=679239"},"modified":"2026-06-14T20:09:05","modified_gmt":"2026-06-14T18:09:05","slug":"tom-dolle-de-nouveau-sacre-champion-deurope-de-canoe-freestyle-en-finlande-quatre-medailles-pour-les-bleus","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/tom-dolle-de-nouveau-sacre-champion-deurope-de-canoe-freestyle-en-finlande-quatre-medailles-pour-les-bleus\/","title":{"rendered":"Tom Doll\u00e9 de nouveau sacr\u00e9 champion d&rsquo;Europe de cano\u00eb freestyle en Finlande, quatre m\u00e9dailles pour les Bleus"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>CHAMPIONNATS D&rsquo;EUROPE DE CANO\u00cb-KAYAK FREESTYLE 2026 &#8211; En Finlande, les Bleus ont rafl\u00e9 quatre m\u00e9dailles, dont un titre pour le champion du monde Tom Doll\u00e9.<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">L&rsquo;an dernier, <strong>Tom Doll\u00e9<\/strong> avait rafl\u00e9 son deuxi\u00e8me titre de champion du monde dans la discipline du cano\u00eb-kayak freestyle. Pas la plus populaire, pas la plus m\u00e9diatique, mais terriblement spectaculaire. L&rsquo;occasion \u00e9tait belle pour le Fran\u00e7ais de garnir son palmar\u00e8s lors des championnats d&rsquo;Europe la semaine pass\u00e9e en Finlande.<\/p>\n<ul style=\"text-align: justify;\">\n<li><strong>\u00c0 ce sujet &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/canoe-kayak-freestyle-tom-dolle-sacre-champion-du-monde-en-kayak\/\">Cano\u00eb-kayak Freestyle : Tom Doll\u00e9 sacr\u00e9 champion du monde en kayak !<\/a><\/strong><\/li>\n<\/ul>\n<h2 style=\"text-align: justify;\">Tom Doll\u00e9 de nouveau au sommet<\/h2>\n<p style=\"text-align: justify;\">Et l&rsquo;occasion a \u00e9t\u00e9 saisie. D\u00e8s les demi-finales en cano\u00eb, il a marqu\u00e9 les esprits : plus de 140 points d&rsquo;avance sur un autre Bleu, <strong>Abel Th\u00e9venet<\/strong>. Une d\u00e9monstration que l&rsquo;on esp\u00e9rait voir r\u00e9p\u00e9t\u00e9e en finale, o\u00f9, contrairement aux demies, seul le meilleur des trois runs \u00e9tait retenu. <strong>Tom Doll\u00e9<\/strong> allait livrer une performance extraordinaire, sanctionn\u00e9e d&rsquo;un score de 1128.33 points, quand le deuxi\u00e8me n&rsquo;allait pas faire mieux que 960 !<\/p>\n<blockquote class=\"instagram-media\" style=\"background: #FFF; border: 0; border-radius: 3px; box-shadow: 0 0 1px 0 rgba(0,0,0,0.5),0 1px 10px 0 rgba(0,0,0,0.15); margin: 1px; max-width: 540px; min-width: 326px; padding: 0; width: calc(100% - 2px);\" data-instgrm-captioned=\"\" data-instgrm-permalink=\"https:\/\/www.instagram.com\/p\/DZiKT7KD1sk\/?utm_source=ig_embed&amp;utm_campaign=loading\" data-instgrm-version=\"14\">\n<div style=\"padding: 16px;\">\n<p>&nbsp;<\/p>\n<div style=\"display: flex; flex-direction: row; align-items: center;\">\n<div style=\"background-color: #f4f4f4; border-radius: 50%; flex-grow: 0; height: 40px; margin-right: 14px; width: 40px;\"><\/div>\n<div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center;\">\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 100px;\"><\/div>\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; width: 60px;\"><\/div>\n<\/div>\n<\/div>\n<div style=\"padding: 19% 0;\"><\/div>\n<div style=\"display: block; height: 50px; margin: 0 auto 12px; width: 50px;\"><\/div>\n<div style=\"padding-top: 8px;\">\n<div style=\"color: #3897f0; font-family: Arial,sans-serif; font-size: 14px; font-style: normal; font-weight: 550; line-height: 18px;\">Voir cette publication sur Instagram<\/div>\n<\/div>\n<div style=\"padding: 12.5% 0;\"><\/div>\n<div style=\"display: flex; flex-direction: row; margin-bottom: 14px; align-items: center;\">\n<div>\n<div style=\"background-color: #f4f4f4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(0px) translateY(7px);\"><\/div>\n<div style=\"background-color: #f4f4f4; height: 12.5px; transform: rotate(-45deg) translateX(3px) translateY(1px); width: 12.5px; flex-grow: 0; margin-right: 14px; margin-left: 2px;\"><\/div>\n<div style=\"background-color: #f4f4f4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(9px) translateY(-18px);\"><\/div>\n<\/div>\n<div style=\"margin-left: 8px;\">\n<div style=\"background-color: #f4f4f4; border-radius: 50%; flex-grow: 0; height: 20px; width: 20px;\"><\/div>\n<div style=\"width: 0; height: 0; border-top: 2px solid transparent; border-left: 6px solid #f4f4f4; border-bottom: 2px solid transparent; transform: translateX(16px) translateY(-4px) rotate(30deg);\"><\/div>\n<\/div>\n<div style=\"margin-left: auto;\">\n<div style=\"width: 0px; border-top: 8px solid #F4F4F4; border-right: 8px solid transparent; transform: translateY(16px);\"><\/div>\n<div style=\"background-color: #f4f4f4; flex-grow: 0; height: 12px; width: 16px; transform: translateY(-4px);\"><\/div>\n<div style=\"width: 0; height: 0; border-top: 8px solid #F4F4F4; border-left: 8px solid transparent; transform: translateY(-4px) translateX(8px);\"><\/div>\n<\/div>\n<\/div>\n<div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center; margin-bottom: 24px;\">\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 224px;\"><\/div>\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; width: 144px;\"><\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<p style=\"color: #c9c8cd; font-family: Arial,sans-serif; font-size: 14px; line-height: 17px; margin-bottom: 0; margin-top: 8px; overflow: hidden; padding: 8px 0 7px; text-align: center; text-overflow: ellipsis; white-space: nowrap;\"><a style=\"color: #c9c8cd; font-family: Arial,sans-serif; font-size: 14px; font-style: normal; font-weight: normal; line-height: 17px; text-decoration: none;\" href=\"https:\/\/www.instagram.com\/p\/DZiKT7KD1sk\/?utm_source=ig_embed&amp;utm_campaign=loading\" target=\"_blank\" rel=\"noopener\">Une publication partag\u00e9e par Paddle Europe (@paddle.europe)<\/a><\/p>\n<\/div>\n<\/blockquote>\n<p style=\"text-align: justify;\"><script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><\/p>\n<p style=\"text-align: justify;\">Le deuxi\u00e8me \u00e9tait encore <strong>Abel Th\u00e9venet<\/strong>, qui offrait un doubl\u00e9 aux Bleus. Un doubl\u00e9 qui \u00e9chappait malheureusement \u00e0 <strong>Tom Doll\u00e9<\/strong> : sur l&rsquo;\u00e9preuve de kayak, malgr\u00e9 trois runs de tr\u00e8s haut niveau, il n&rsquo;allait pas renverser l&rsquo;un des grands noms de la discipline, <strong>Tomasz Czaplicki<\/strong>. N\u00e9anmoins, il se parait d&rsquo;argent, et devenait ainsi le seul double m\u00e9daill\u00e9 de la comp\u00e9tition. Avec en prime la rel\u00e8ve pr\u00e9sente c\u00f4t\u00e9 fran\u00e7ais : Arthur Genovese s&rsquo;offrait lui aussi l&rsquo;argent chez les juniors en kayak, agr\u00e9mentant un bilan tricolore de qualit\u00e9.<\/p>\n<p style=\"text-align: justify;\">Un titre et trois m\u00e9dailles d&rsquo;argent pour les Bleus, une \u00e9dition r\u00e9ussie, sans nul doute. Pour <strong>Tom Doll\u00e9<\/strong>, c&rsquo;est d\u00e9j\u00e0 le troisi\u00e8me titre europ\u00e9en en carri\u00e8re (+1 chez les juniors), et donc deux titres mondiaux, cano\u00eb et kayak confondus. Un des leaders mondiaux de la discipline, sans nul doute.<\/p>\n<h2 style=\"text-align: justify;\">Les m\u00e9dailles fran\u00e7aises<\/h2>\n<p style=\"text-align: justify;\">Or : Tom Doll\u00e9 (cano\u00eb)<\/p>\n<p style=\"text-align: justify;\">Argent : Abel Th\u00e9venet (cano\u00eb), Tom Doll\u00e9 (kayak), Arthur Genovese (kayak juniors)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CHAMPIONNATS D&rsquo;EUROPE DE CANO\u00cb-KAYAK FREESTYLE 2026 &#8211; En Finlande, les Bleus ont rafl\u00e9 quatre m\u00e9dailles, dont un titre pour le champion du monde Tom Doll\u00e9.<\/p>\n","protected":false},"author":59,"featured_media":679246,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[10458],"tags":[16878,47125],"class_list":["post-679239","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-canoe-kayak","tag-breve","tag-canoe-kayak-freestyle"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Tom Doll\u00e9 de nouveau sacr\u00e9 champion d&#039;Europe de cano\u00eb freestyle en Finlande, quatre m\u00e9dailles pour les Bleus<\/title>\n<meta name=\"description\" content=\"CHAMPIONNATS D&#039;EUROPE DE CANO\u00cb-KAYAK FREESTYLE 2026 - En Finlande, les Bleus ont rafl\u00e9 quatre m\u00e9dailles, dont un titre pour le champion du monde Tom Doll\u00e9.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/tom-dolle-de-nouveau-sacre-champion-deurope-de-canoe-freestyle-en-finlande-quatre-medailles-pour-les-bleus\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tom Doll\u00e9 de nouveau sacr\u00e9 champion d&#039;Europe de cano\u00eb freestyle en Finlande, quatre m\u00e9dailles pour les Bleus\" \/>\n<meta property=\"og:description\" content=\"CHAMPIONNATS D&#039;EUROPE DE CANO\u00cb-KAYAK FREESTYLE 2026 - En Finlande, les Bleus ont rafl\u00e9 quatre m\u00e9dailles, dont un titre pour le champion du monde Tom Doll\u00e9.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/tom-dolle-de-nouveau-sacre-champion-deurope-de-canoe-freestyle-en-finlande-quatre-medailles-pour-les-bleus\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/sebastien.gente\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-06-15T08:00:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/06\/Tom-Dolle-de-nouveau-sacre-champion-dEurope-de-canoe-freestyle-en-Finlande-quatre-medailles-pour-les-Bleus.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"S\u00e9bastien Gente\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Tom Doll\u00e9 de nouveau sacr\u00e9 champion d&#039;Europe de cano\u00eb freestyle en Finlande, quatre m\u00e9dailles pour les Bleus\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/globulo24\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/tom-dolle-de-nouveau-sacre-champion-deurope-de-canoe-freestyle-en-finlande-quatre-medailles-pour-les-bleus\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/tom-dolle-de-nouveau-sacre-champion-deurope-de-canoe-freestyle-en-finlande-quatre-medailles-pour-les-bleus\\\/\"},\"author\":{\"name\":\"S\u00e9bastien Gente\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/627966a6cde45dbd8c5e36ac85d783da\"},\"headline\":\"Tom Doll\u00e9 de nouveau sacr\u00e9 champion d&rsquo;Europe de cano\u00eb freestyle en Finlande, quatre m\u00e9dailles pour les Bleus\",\"datePublished\":\"2026-06-15T08:00:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/tom-dolle-de-nouveau-sacre-champion-deurope-de-canoe-freestyle-en-finlande-quatre-medailles-pour-les-bleus\\\/\"},\"wordCount\":397,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/tom-dolle-de-nouveau-sacre-champion-deurope-de-canoe-freestyle-en-finlande-quatre-medailles-pour-les-bleus\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Tom-Dolle-de-nouveau-sacre-champion-dEurope-de-canoe-freestyle-en-Finlande-quatre-medailles-pour-les-Bleus.png\",\"keywords\":[\"br\u00e8ve\",\"Cano\u00eb-kayak freestyle\"],\"articleSection\":[\"Cano\u00eb-Kayak\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/tom-dolle-de-nouveau-sacre-champion-deurope-de-canoe-freestyle-en-finlande-quatre-medailles-pour-les-bleus\\\/#respond\"]}],\"copyrightYear\":\"2026\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/tom-dolle-de-nouveau-sacre-champion-deurope-de-canoe-freestyle-en-finlande-quatre-medailles-pour-les-bleus\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/tom-dolle-de-nouveau-sacre-champion-deurope-de-canoe-freestyle-en-finlande-quatre-medailles-pour-les-bleus\\\/\",\"name\":\"Tom Doll\u00e9 de nouveau sacr\u00e9 champion d'Europe de cano\u00eb freestyle en Finlande, quatre m\u00e9dailles pour les Bleus\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/tom-dolle-de-nouveau-sacre-champion-deurope-de-canoe-freestyle-en-finlande-quatre-medailles-pour-les-bleus\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/tom-dolle-de-nouveau-sacre-champion-deurope-de-canoe-freestyle-en-finlande-quatre-medailles-pour-les-bleus\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Tom-Dolle-de-nouveau-sacre-champion-dEurope-de-canoe-freestyle-en-Finlande-quatre-medailles-pour-les-Bleus.png\",\"datePublished\":\"2026-06-15T08:00:16+00:00\",\"description\":\"CHAMPIONNATS D'EUROPE DE CANO\u00cb-KAYAK FREESTYLE 2026 - En Finlande, les Bleus ont rafl\u00e9 quatre m\u00e9dailles, dont un titre pour le champion du monde Tom Doll\u00e9.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/tom-dolle-de-nouveau-sacre-champion-deurope-de-canoe-freestyle-en-finlande-quatre-medailles-pour-les-bleus\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/tom-dolle-de-nouveau-sacre-champion-deurope-de-canoe-freestyle-en-finlande-quatre-medailles-pour-les-bleus\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/tom-dolle-de-nouveau-sacre-champion-deurope-de-canoe-freestyle-en-finlande-quatre-medailles-pour-les-bleus\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Tom-Dolle-de-nouveau-sacre-champion-dEurope-de-canoe-freestyle-en-Finlande-quatre-medailles-pour-les-Bleus.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Tom-Dolle-de-nouveau-sacre-champion-dEurope-de-canoe-freestyle-en-Finlande-quatre-medailles-pour-les-Bleus.png\",\"width\":1200,\"height\":674,\"caption\":\"Tom Doll\u00e9 de nouveau sacr\u00e9 champion d'Europe de cano\u00eb freestyle en Finlande, quatre m\u00e9dailles pour les Bleus\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/tom-dolle-de-nouveau-sacre-champion-deurope-de-canoe-freestyle-en-finlande-quatre-medailles-pour-les-bleus\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tom Doll\u00e9 de nouveau sacr\u00e9 champion d&rsquo;Europe de cano\u00eb freestyle en Finlande, quatre m\u00e9dailles pour les Bleus\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/627966a6cde45dbd8c5e36ac85d783da\",\"name\":\"S\u00e9bastien Gente\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"caption\":\"S\u00e9bastien Gente\"},\"description\":\"John Stockton, Gianni Bugno, Zinedine Zidane, Steffi Graf, Frode Andresen, St\u00e9phane Stoecklin, Davis Kamoga, Primoz Peterka, Werner Schlager et Aur\u00e9lien Rougerie. Point commun entre ces sportifs? Ils m'ont fait r\u00eaver et ont berc\u00e9 mon adolescence. Je suis un fondu de sports et j'essaie de retranscrire ma passion \u00e0 travers mes articles. Originaire du P\u00e9rigord, ma passion pour les Girondins, les Jaunards et les Jazzmen transpire dans mes \u00e9crits. \u00c0 Dicodusport depuis 2021, je d\u00e9niche les sports m\u00e9connus dans lesquels la France brille, et il y en a !\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/sebastien.gente\\\/\",\"https:\\\/\\\/www.instagram.com\\\/sebgente\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/sbastien-gente-a29583169\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/globulo24\",\"SebastienGente\"],\"worksFor\":\"S\u00e9bastien GENTE\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/sebastiengente\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Tom Doll\u00e9 de nouveau sacr\u00e9 champion d'Europe de cano\u00eb freestyle en Finlande, quatre m\u00e9dailles pour les Bleus","description":"CHAMPIONNATS D'EUROPE DE CANO\u00cb-KAYAK FREESTYLE 2026 - En Finlande, les Bleus ont rafl\u00e9 quatre m\u00e9dailles, dont un titre pour le champion du monde Tom Doll\u00e9.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/tom-dolle-de-nouveau-sacre-champion-deurope-de-canoe-freestyle-en-finlande-quatre-medailles-pour-les-bleus\/","og_locale":"fr_FR","og_type":"article","og_title":"Tom Doll\u00e9 de nouveau sacr\u00e9 champion d'Europe de cano\u00eb freestyle en Finlande, quatre m\u00e9dailles pour les Bleus","og_description":"CHAMPIONNATS D'EUROPE DE CANO\u00cb-KAYAK FREESTYLE 2026 - En Finlande, les Bleus ont rafl\u00e9 quatre m\u00e9dailles, dont un titre pour le champion du monde Tom Doll\u00e9.","og_url":"https:\/\/dicodusport.fr\/blog\/tom-dolle-de-nouveau-sacre-champion-deurope-de-canoe-freestyle-en-finlande-quatre-medailles-pour-les-bleus\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/sebastien.gente\/","article_published_time":"2026-06-15T08:00:16+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/06\/Tom-Dolle-de-nouveau-sacre-champion-dEurope-de-canoe-freestyle-en-Finlande-quatre-medailles-pour-les-Bleus.png","type":"image\/png"}],"author":"S\u00e9bastien Gente","twitter_card":"summary_large_image","twitter_title":"Tom Doll\u00e9 de nouveau sacr\u00e9 champion d'Europe de cano\u00eb freestyle en Finlande, quatre m\u00e9dailles pour les Bleus","twitter_creator":"@https:\/\/twitter.com\/globulo24","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/tom-dolle-de-nouveau-sacre-champion-deurope-de-canoe-freestyle-en-finlande-quatre-medailles-pour-les-bleus\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/tom-dolle-de-nouveau-sacre-champion-deurope-de-canoe-freestyle-en-finlande-quatre-medailles-pour-les-bleus\/"},"author":{"name":"S\u00e9bastien Gente","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da"},"headline":"Tom Doll\u00e9 de nouveau sacr\u00e9 champion d&rsquo;Europe de cano\u00eb freestyle en Finlande, quatre m\u00e9dailles pour les Bleus","datePublished":"2026-06-15T08:00:16+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/tom-dolle-de-nouveau-sacre-champion-deurope-de-canoe-freestyle-en-finlande-quatre-medailles-pour-les-bleus\/"},"wordCount":397,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/tom-dolle-de-nouveau-sacre-champion-deurope-de-canoe-freestyle-en-finlande-quatre-medailles-pour-les-bleus\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/06\/Tom-Dolle-de-nouveau-sacre-champion-dEurope-de-canoe-freestyle-en-Finlande-quatre-medailles-pour-les-Bleus.png","keywords":["br\u00e8ve","Cano\u00eb-kayak freestyle"],"articleSection":["Cano\u00eb-Kayak"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/tom-dolle-de-nouveau-sacre-champion-deurope-de-canoe-freestyle-en-finlande-quatre-medailles-pour-les-bleus\/#respond"]}],"copyrightYear":"2026","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/tom-dolle-de-nouveau-sacre-champion-deurope-de-canoe-freestyle-en-finlande-quatre-medailles-pour-les-bleus\/","url":"https:\/\/dicodusport.fr\/blog\/tom-dolle-de-nouveau-sacre-champion-deurope-de-canoe-freestyle-en-finlande-quatre-medailles-pour-les-bleus\/","name":"Tom Doll\u00e9 de nouveau sacr\u00e9 champion d'Europe de cano\u00eb freestyle en Finlande, quatre m\u00e9dailles pour les Bleus","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/tom-dolle-de-nouveau-sacre-champion-deurope-de-canoe-freestyle-en-finlande-quatre-medailles-pour-les-bleus\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/tom-dolle-de-nouveau-sacre-champion-deurope-de-canoe-freestyle-en-finlande-quatre-medailles-pour-les-bleus\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/06\/Tom-Dolle-de-nouveau-sacre-champion-dEurope-de-canoe-freestyle-en-Finlande-quatre-medailles-pour-les-Bleus.png","datePublished":"2026-06-15T08:00:16+00:00","description":"CHAMPIONNATS D'EUROPE DE CANO\u00cb-KAYAK FREESTYLE 2026 - En Finlande, les Bleus ont rafl\u00e9 quatre m\u00e9dailles, dont un titre pour le champion du monde Tom Doll\u00e9.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/tom-dolle-de-nouveau-sacre-champion-deurope-de-canoe-freestyle-en-finlande-quatre-medailles-pour-les-bleus\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/tom-dolle-de-nouveau-sacre-champion-deurope-de-canoe-freestyle-en-finlande-quatre-medailles-pour-les-bleus\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/tom-dolle-de-nouveau-sacre-champion-deurope-de-canoe-freestyle-en-finlande-quatre-medailles-pour-les-bleus\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/06\/Tom-Dolle-de-nouveau-sacre-champion-dEurope-de-canoe-freestyle-en-Finlande-quatre-medailles-pour-les-Bleus.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/06\/Tom-Dolle-de-nouveau-sacre-champion-dEurope-de-canoe-freestyle-en-Finlande-quatre-medailles-pour-les-Bleus.png","width":1200,"height":674,"caption":"Tom Doll\u00e9 de nouveau sacr\u00e9 champion d'Europe de cano\u00eb freestyle en Finlande, quatre m\u00e9dailles pour les Bleus"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/tom-dolle-de-nouveau-sacre-champion-deurope-de-canoe-freestyle-en-finlande-quatre-medailles-pour-les-bleus\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Tom Doll\u00e9 de nouveau sacr\u00e9 champion d&rsquo;Europe de cano\u00eb freestyle en Finlande, quatre m\u00e9dailles pour les Bleus"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da","name":"S\u00e9bastien Gente","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","caption":"S\u00e9bastien Gente"},"description":"John Stockton, Gianni Bugno, Zinedine Zidane, Steffi Graf, Frode Andresen, St\u00e9phane Stoecklin, Davis Kamoga, Primoz Peterka, Werner Schlager et Aur\u00e9lien Rougerie. Point commun entre ces sportifs? Ils m'ont fait r\u00eaver et ont berc\u00e9 mon adolescence. Je suis un fondu de sports et j'essaie de retranscrire ma passion \u00e0 travers mes articles. Originaire du P\u00e9rigord, ma passion pour les Girondins, les Jaunards et les Jazzmen transpire dans mes \u00e9crits. \u00c0 Dicodusport depuis 2021, je d\u00e9niche les sports m\u00e9connus dans lesquels la France brille, et il y en a !","sameAs":["https:\/\/www.facebook.com\/sebastien.gente\/","https:\/\/www.instagram.com\/sebgente\/","https:\/\/www.linkedin.com\/in\/sbastien-gente-a29583169\/","https:\/\/x.com\/https:\/\/twitter.com\/globulo24","SebastienGente"],"worksFor":"S\u00e9bastien GENTE","url":"https:\/\/dicodusport.fr\/blog\/author\/sebastiengente\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/679239","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/59"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=679239"}],"version-history":[{"count":1,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/679239\/revisions"}],"predecessor-version":[{"id":679258,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/679239\/revisions\/679258"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/679246"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=679239"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=679239"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=679239"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}