{"id":681169,"date":"2026-06-20T17:35:11","date_gmt":"2026-06-20T15:35:11","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=681169&#038;preview=true&#038;preview_id=681169"},"modified":"2026-06-20T22:08:01","modified_gmt":"2026-06-20T20:08:01","slug":"tadej-pogacar-sadjuge-le-contre-la-montre-de-la-4e-etape-du-tour-de-suisse-dun-cheveu-devant-mathieu-van-der-poel","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/tadej-pogacar-sadjuge-le-contre-la-montre-de-la-4e-etape-du-tour-de-suisse-dun-cheveu-devant-mathieu-van-der-poel\/","title":{"rendered":"Tadej Poga\u010dar s&rsquo;adjuge le contre-la-montre de la 4e \u00e9tape du Tour de Suisse d&rsquo;un cheveu devant Mathieu van der Poel"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><strong>TOUR DE SUISSE 2026 &#8211; Tadej Poga\u010dar s&rsquo;adjuge le contre-la-montre de la 4e \u00e9tape pour une seconde devant Mathieu van der Poel et conforte son maillot jaune.<\/strong><\/em><\/p>\n<p style=\"text-align: justify;\">Avant le terrible Col de la Croix \u00e0 escalader deux fois demain, l&rsquo;occasion \u00e9tait id\u00e9ale pour les leaders de commencer \u00e0 dessiner les contours du classement g\u00e9n\u00e9ral avec ce contre-la-montre trac\u00e9 autour d&rsquo;Aarburg. Du moins pour les accessits, puisque pour la premi\u00e8re place, <strong>Tadej Poga\u010dar<\/strong> a d&rsquo;ores et d\u00e9j\u00e0 tu\u00e9 le suspense depuis son r\u00e9cital lors de la premi\u00e8re \u00e9tape.<\/p>\n<ul style=\"text-align: justify;\">\n<li><strong>\u00c0 ce sujet \u2013 <a href=\"https:\/\/dicodusport.fr\/blog\/tour-de-suisse-2026-decouvrez-le-parcours-complet-et-le-profil-des-5-etapes\/\">Tour de Suisse 2026 : d\u00e9couvrez le parcours complet et le profil des 5 \u00e9tapes<\/a><\/strong><\/li>\n<\/ul>\n<h2 style=\"text-align: justify;\">Wellens et Van der Poel donnent le ton<\/h2>\n<p style=\"text-align: justify;\">Tout d&rsquo;abord, les sp\u00e9cialistes de l&rsquo;exercice ont anim\u00e9 le haut du classement, avec notamment les UAE Team Emirates &#8211; XRG <strong>Nils Politt<\/strong> et surtout <strong>Tim Wellens<\/strong>, qui ont tour \u00e0 tour d\u00e9tenu le meilleur temps. Puis, le N\u00e9erlandais <strong>Mathieu van der Poel<\/strong> a d\u00e9cid\u00e9 de r\u00e9aliser son chrono \u00e0 fond, ce qui n&rsquo;est pas toujours le cas, loin s&rsquo;en faut. Cela lui a permis de s&#8217;emparer du meilleur temps provisoire \u00e0 plus de 53 km\/h de moyenne sur les 24 kilom\u00e8tres du parcours.<\/p>\n<ul style=\"text-align: justify;\">\n<li><strong>\u00c0 ce sujet \u2013 <a href=\"https:\/\/dicodusport.fr\/blog\/4e-etape-tour-de-suisse-2026-classement-et-resultats-du-contre-la-montre\/\">4\u00e8me \u00e9tape Tour de Suisse 2026 : Classement et r\u00e9sultats<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Beaucoup d&rsquo;outsiders sont venus buter sur le temps du coureur d&rsquo;Alpecin &#8211; Premier Tech. Successivement, <strong>Felix Grossschartner<\/strong> et <strong>Brandon McNulty<\/strong> (UAE Team Emirates XRG), <strong>Tobias Foss<\/strong> (Netcompany INEOS), <a href=\"https:\/\/dicodusport.fr\/blog\/mondiaux-cyclisme-2022-tobias-foss-sacre-champion-du-monde-du-contre-la-montre\/\">ancien champion du monde de la discipline<\/a>, ou encore <strong>Primo\u017e Rogli\u010d<\/strong> et <strong>Finn Fisher-Black<\/strong> (Red Bull &#8211; Bora &#8211; Hansgrohe) se sont tous cass\u00e9 les dents sur ce meilleur temps.<\/p>\n<h2 style=\"text-align: justify;\">Mathias Vacek et Tadej Poga\u010dar, seuls \u00e0 soutenir la comparaison<\/h2>\n<p style=\"text-align: justify;\">Ensuite, les leaders du classement g\u00e9n\u00e9ral sont entr\u00e9s en piste. On a rapidement compris que <strong>Richard Carapaz<\/strong> (EF Education &#8211; EasyPost) et <strong>Andrea Bagioli<\/strong> (Lidl-Trek), install\u00e9s sur le podium provisoire du classement g\u00e9n\u00e9ral, allaient perdre du terrain au regard de leurs capacit\u00e9s dans l&rsquo;exercice. Finalement, seuls <strong>Mathias Vacek<\/strong> (Lidl-Trek) et le leader incontest\u00e9 <strong>Tadej Poga\u010dar<\/strong> semblaient en mesure d&rsquo;aller d\u00e9tr\u00f4ner <strong>Mathieu van der Poel<\/strong>.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">Un final totalement fou sur le Tour de Suisse ! Tadej Poga\u010dar remporte le contre-la-montre du jour pour seulement une petite seconde d&rsquo;avance sur Mathieu van der Poel, qui y a cru jusqu&rsquo;au bout !<\/p>\n<p>Le Slov\u00e8ne est vraiment imbattable. \ud83c\uddf8\ud83c\uddee <a href=\"https:\/\/t.co\/ufBRss99yR\">pic.twitter.com\/ufBRss99yR<\/a><\/p>\n<p>\u2014 la chaine L&rsquo;\u00c9quipe (@lachainelequipe) <a href=\"https:\/\/x.com\/lachainelequipe\/status\/2068356458895360102?ref_src=twsrc%5Etfw\">June 20, 2026<\/a><\/p><\/blockquote>\n<p style=\"text-align: justify;\"><script async src=\"https:\/\/platform.x.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p style=\"text-align: justify;\">Malheureusement pour lui, le Tch\u00e8que a l\u00e9g\u00e8rement craqu\u00e9 dans la seconde partie du trac\u00e9, mais r\u00e9alisait tout de m\u00eame une excellente op\u00e9ration. Quant \u00e0 l&rsquo;ogre slov\u00e8ne, il le devan\u00e7ait finalement d&rsquo;un rien, \u00e0 peine trois dixi\u00e8mes de seconde, pour s&rsquo;adjuger une nouvelle victoire de prestige. Au classement g\u00e9n\u00e9ral, <strong>Richard Carapaz<\/strong> est parvenu \u00e0 conserver sa position. <strong>Andrea Bagioli<\/strong> est d\u00e9pass\u00e9 par <strong>Mathias Vacek<\/strong>, tandis que <strong>Tobias Foss<\/strong> (cinqui\u00e8me) et <strong>Primo\u017e Rogli\u010d<\/strong> (neuvi\u00e8me) font leur entr\u00e9e dans le top 10. Mais tout reste \u00e0 faire pour le podium final avec l&rsquo;\u00e9tape reine de demain.<\/p>\n<ul style=\"text-align: justify;\">\n<li><strong>\u00c0 ce sujet \u2013 <a href=\"https:\/\/dicodusport.fr\/blog\/classement-general-du-tour-de-suisse-2026-actualise\/\">Classement g\u00e9n\u00e9ral du Tour de Suisse 2026 actualis\u00e9<\/a><\/strong><\/li>\n<\/ul>\n<h3 style=\"text-align: justify;\">\u00c0 lire aussi<\/h3>\n<ul>\n<li style=\"text-align: justify;\"><strong>\u00c0 voir aussi &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/mercato-cyclisme-2026-2027-le-tableau-des-transferts-mis-a-jour\/\">Mercato Cyclisme 2026-2027 \u2013 Le tableau des transferts mis \u00e0 jour<\/a><\/strong><\/li>\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet \u2013\u00a0<a href=\"https:\/\/dicodusport.fr\/blog\/tour-de-suisse-2026-les-favoris-et-la-liste-des-engages\/\">Tour de Suisse 2026 : les favoris et la liste des engag\u00e9s<\/a><\/strong><\/li>\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet \u2013\u00a0<a href=\"https:\/\/dicodusport.fr\/blog\/tour-de-suisse-2026-en-direct-a-quelle-heure-et-sur-quelle-chaine-tv-suivre-la-course\/\">Tour de Suisse 2026 en direct : \u00e0 quelle heure et sur quelle cha\u00eene TV suivre la course ?<\/a><\/strong><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>TOUR DE SUISSE 2026 &#8211; Tadej Poga\u010dar s&rsquo;adjuge le contre-la-montre de la 4e \u00e9tape pour une seconde sur Mathieu van der Poel et conforte son maillot jaune.<\/p>\n","protected":false},"author":92,"featured_media":681304,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[46994],"tags":[32415,16878,574,11197,8106],"class_list":["post-681169","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cyclisme-sur-route","tag-actu","tag-breve","tag-cyclisme","tag-cyclisme-sur-route","tag-tour-de-suisse"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Tadej Poga\u010dar s&#039;adjuge le contre-la-montre de la 4e \u00e9tape du Tour de Suisse d&#039;un cheveu devant Mathieu van der Poel<\/title>\n<meta name=\"description\" content=\"TOUR DE SUISSE 2026 - Tadej Poga\u010dar s&#039;adjuge le contre-la-montre de la 4e \u00e9tape pour une seconde sur Mathieu van der Poel et conforte son maillot jaune.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/tadej-pogacar-sadjuge-le-contre-la-montre-de-la-4e-etape-du-tour-de-suisse-dun-cheveu-devant-mathieu-van-der-poel\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tadej Poga\u010dar s&#039;adjuge le contre-la-montre de la 4e \u00e9tape du Tour de Suisse d&#039;un cheveu devant Mathieu van der Poel\" \/>\n<meta property=\"og:description\" content=\"TOUR DE SUISSE 2026 - Tadej Poga\u010dar s&#039;adjuge le contre-la-montre de la 4e \u00e9tape pour une seconde sur Mathieu van der Poel et conforte son maillot jaune.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/tadej-pogacar-sadjuge-le-contre-la-montre-de-la-4e-etape-du-tour-de-suisse-dun-cheveu-devant-mathieu-van-der-poel\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2026-06-20T15:35:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-20T20:08:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/06\/Tadej-Pogacar-sadjuge-le-contre-la-montre-de-la-4e-etape-du-Tour-de-Suisse-dun-cheveu-devant-Mathieu-van-der-Poel-1-1024x575.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"575\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Olivier Dobiezynski\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/x.com\/Olivier_Matros\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/tadej-pogacar-sadjuge-le-contre-la-montre-de-la-4e-etape-du-tour-de-suisse-dun-cheveu-devant-mathieu-van-der-poel\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/tadej-pogacar-sadjuge-le-contre-la-montre-de-la-4e-etape-du-tour-de-suisse-dun-cheveu-devant-mathieu-van-der-poel\\\/\"},\"author\":{\"name\":\"Olivier Dobiezynski\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/fe500246414ca17ddf0c0312d7a792cc\"},\"headline\":\"Tadej Poga\u010dar s&rsquo;adjuge le contre-la-montre de la 4e \u00e9tape du Tour de Suisse d&rsquo;un cheveu devant Mathieu van der Poel\",\"datePublished\":\"2026-06-20T15:35:11+00:00\",\"dateModified\":\"2026-06-20T20:08:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/tadej-pogacar-sadjuge-le-contre-la-montre-de-la-4e-etape-du-tour-de-suisse-dun-cheveu-devant-mathieu-van-der-poel\\\/\"},\"wordCount\":606,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/tadej-pogacar-sadjuge-le-contre-la-montre-de-la-4e-etape-du-tour-de-suisse-dun-cheveu-devant-mathieu-van-der-poel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Tadej-Pogacar-sadjuge-le-contre-la-montre-de-la-4e-etape-du-Tour-de-Suisse-dun-cheveu-devant-Mathieu-van-der-Poel-1.png\",\"keywords\":[\"actu\",\"br\u00e8ve\",\"Cyclisme\",\"Cyclisme sur route\",\"Tour de Suisse\"],\"articleSection\":[\"Cyclisme sur route\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/tadej-pogacar-sadjuge-le-contre-la-montre-de-la-4e-etape-du-tour-de-suisse-dun-cheveu-devant-mathieu-van-der-poel\\\/#respond\"]}],\"copyrightYear\":\"2026\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/tadej-pogacar-sadjuge-le-contre-la-montre-de-la-4e-etape-du-tour-de-suisse-dun-cheveu-devant-mathieu-van-der-poel\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/tadej-pogacar-sadjuge-le-contre-la-montre-de-la-4e-etape-du-tour-de-suisse-dun-cheveu-devant-mathieu-van-der-poel\\\/\",\"name\":\"Tadej Poga\u010dar s'adjuge le contre-la-montre de la 4e \u00e9tape du Tour de Suisse d'un cheveu devant Mathieu van der Poel\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/tadej-pogacar-sadjuge-le-contre-la-montre-de-la-4e-etape-du-tour-de-suisse-dun-cheveu-devant-mathieu-van-der-poel\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/tadej-pogacar-sadjuge-le-contre-la-montre-de-la-4e-etape-du-tour-de-suisse-dun-cheveu-devant-mathieu-van-der-poel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Tadej-Pogacar-sadjuge-le-contre-la-montre-de-la-4e-etape-du-Tour-de-Suisse-dun-cheveu-devant-Mathieu-van-der-Poel-1.png\",\"datePublished\":\"2026-06-20T15:35:11+00:00\",\"dateModified\":\"2026-06-20T20:08:01+00:00\",\"description\":\"TOUR DE SUISSE 2026 - Tadej Poga\u010dar s'adjuge le contre-la-montre de la 4e \u00e9tape pour une seconde sur Mathieu van der Poel et conforte son maillot jaune.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/tadej-pogacar-sadjuge-le-contre-la-montre-de-la-4e-etape-du-tour-de-suisse-dun-cheveu-devant-mathieu-van-der-poel\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/tadej-pogacar-sadjuge-le-contre-la-montre-de-la-4e-etape-du-tour-de-suisse-dun-cheveu-devant-mathieu-van-der-poel\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/tadej-pogacar-sadjuge-le-contre-la-montre-de-la-4e-etape-du-tour-de-suisse-dun-cheveu-devant-mathieu-van-der-poel\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Tadej-Pogacar-sadjuge-le-contre-la-montre-de-la-4e-etape-du-Tour-de-Suisse-dun-cheveu-devant-Mathieu-van-der-Poel-1.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Tadej-Pogacar-sadjuge-le-contre-la-montre-de-la-4e-etape-du-Tour-de-Suisse-dun-cheveu-devant-Mathieu-van-der-Poel-1.png\",\"width\":1200,\"height\":674,\"caption\":\"Tadej Poga\u010dar s'adjuge le contre-la-montre de la 4e \u00e9tape du Tour de Suisse d'un cheveu devant Mathieu van der Poel\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/tadej-pogacar-sadjuge-le-contre-la-montre-de-la-4e-etape-du-tour-de-suisse-dun-cheveu-devant-mathieu-van-der-poel\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tadej Poga\u010dar s&rsquo;adjuge le contre-la-montre de la 4e \u00e9tape du Tour de Suisse d&rsquo;un cheveu devant Mathieu van der Poel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/fe500246414ca17ddf0c0312d7a792cc\",\"name\":\"Olivier Dobiezynski\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/5be8fe8d-9962-4f1e-ad06-d6f9dee30e6d-150x150.jpg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/5be8fe8d-9962-4f1e-ad06-d6f9dee30e6d-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/5be8fe8d-9962-4f1e-ad06-d6f9dee30e6d-150x150.jpg\",\"caption\":\"Olivier Dobiezynski\"},\"description\":\"Depuis le milieu des ann\u00e9es 90, la passion du cyclisme m'anime. Mes h\u00e9ros s'appellent Luc Leblanc, Piotr Ugrumov, Paolo Savoldelli, Peter Sagan et bien \u00e9videmment Romain Bardet. R\u00e9dacteur depuis 2023, je suis ici pour partager cet amour de la Petite Reine. Vous pourrez me lire \u00e9galement sur du trail, du ski de fond et tout autre sujet susceptible d'\u00e9veiller ma curiosit\u00e9 sportive.\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/https:\\\/\\\/x.com\\\/Olivier_Matros\"],\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/olivier-gh\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Tadej Poga\u010dar s'adjuge le contre-la-montre de la 4e \u00e9tape du Tour de Suisse d'un cheveu devant Mathieu van der Poel","description":"TOUR DE SUISSE 2026 - Tadej Poga\u010dar s'adjuge le contre-la-montre de la 4e \u00e9tape pour une seconde sur Mathieu van der Poel et conforte son maillot jaune.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/tadej-pogacar-sadjuge-le-contre-la-montre-de-la-4e-etape-du-tour-de-suisse-dun-cheveu-devant-mathieu-van-der-poel\/","og_locale":"fr_FR","og_type":"article","og_title":"Tadej Poga\u010dar s'adjuge le contre-la-montre de la 4e \u00e9tape du Tour de Suisse d'un cheveu devant Mathieu van der Poel","og_description":"TOUR DE SUISSE 2026 - Tadej Poga\u010dar s'adjuge le contre-la-montre de la 4e \u00e9tape pour une seconde sur Mathieu van der Poel et conforte son maillot jaune.","og_url":"https:\/\/dicodusport.fr\/blog\/tadej-pogacar-sadjuge-le-contre-la-montre-de-la-4e-etape-du-tour-de-suisse-dun-cheveu-devant-mathieu-van-der-poel\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2026-06-20T15:35:11+00:00","article_modified_time":"2026-06-20T20:08:01+00:00","og_image":[{"width":1024,"height":575,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/06\/Tadej-Pogacar-sadjuge-le-contre-la-montre-de-la-4e-etape-du-Tour-de-Suisse-dun-cheveu-devant-Mathieu-van-der-Poel-1-1024x575.png","type":"image\/png"}],"author":"Olivier Dobiezynski","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/x.com\/Olivier_Matros","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/tadej-pogacar-sadjuge-le-contre-la-montre-de-la-4e-etape-du-tour-de-suisse-dun-cheveu-devant-mathieu-van-der-poel\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/tadej-pogacar-sadjuge-le-contre-la-montre-de-la-4e-etape-du-tour-de-suisse-dun-cheveu-devant-mathieu-van-der-poel\/"},"author":{"name":"Olivier Dobiezynski","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/fe500246414ca17ddf0c0312d7a792cc"},"headline":"Tadej Poga\u010dar s&rsquo;adjuge le contre-la-montre de la 4e \u00e9tape du Tour de Suisse d&rsquo;un cheveu devant Mathieu van der Poel","datePublished":"2026-06-20T15:35:11+00:00","dateModified":"2026-06-20T20:08:01+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/tadej-pogacar-sadjuge-le-contre-la-montre-de-la-4e-etape-du-tour-de-suisse-dun-cheveu-devant-mathieu-van-der-poel\/"},"wordCount":606,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/tadej-pogacar-sadjuge-le-contre-la-montre-de-la-4e-etape-du-tour-de-suisse-dun-cheveu-devant-mathieu-van-der-poel\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/06\/Tadej-Pogacar-sadjuge-le-contre-la-montre-de-la-4e-etape-du-Tour-de-Suisse-dun-cheveu-devant-Mathieu-van-der-Poel-1.png","keywords":["actu","br\u00e8ve","Cyclisme","Cyclisme sur route","Tour de Suisse"],"articleSection":["Cyclisme sur route"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/tadej-pogacar-sadjuge-le-contre-la-montre-de-la-4e-etape-du-tour-de-suisse-dun-cheveu-devant-mathieu-van-der-poel\/#respond"]}],"copyrightYear":"2026","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/tadej-pogacar-sadjuge-le-contre-la-montre-de-la-4e-etape-du-tour-de-suisse-dun-cheveu-devant-mathieu-van-der-poel\/","url":"https:\/\/dicodusport.fr\/blog\/tadej-pogacar-sadjuge-le-contre-la-montre-de-la-4e-etape-du-tour-de-suisse-dun-cheveu-devant-mathieu-van-der-poel\/","name":"Tadej Poga\u010dar s'adjuge le contre-la-montre de la 4e \u00e9tape du Tour de Suisse d'un cheveu devant Mathieu van der Poel","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/tadej-pogacar-sadjuge-le-contre-la-montre-de-la-4e-etape-du-tour-de-suisse-dun-cheveu-devant-mathieu-van-der-poel\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/tadej-pogacar-sadjuge-le-contre-la-montre-de-la-4e-etape-du-tour-de-suisse-dun-cheveu-devant-mathieu-van-der-poel\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/06\/Tadej-Pogacar-sadjuge-le-contre-la-montre-de-la-4e-etape-du-Tour-de-Suisse-dun-cheveu-devant-Mathieu-van-der-Poel-1.png","datePublished":"2026-06-20T15:35:11+00:00","dateModified":"2026-06-20T20:08:01+00:00","description":"TOUR DE SUISSE 2026 - Tadej Poga\u010dar s'adjuge le contre-la-montre de la 4e \u00e9tape pour une seconde sur Mathieu van der Poel et conforte son maillot jaune.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/tadej-pogacar-sadjuge-le-contre-la-montre-de-la-4e-etape-du-tour-de-suisse-dun-cheveu-devant-mathieu-van-der-poel\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/tadej-pogacar-sadjuge-le-contre-la-montre-de-la-4e-etape-du-tour-de-suisse-dun-cheveu-devant-mathieu-van-der-poel\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/tadej-pogacar-sadjuge-le-contre-la-montre-de-la-4e-etape-du-tour-de-suisse-dun-cheveu-devant-mathieu-van-der-poel\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/06\/Tadej-Pogacar-sadjuge-le-contre-la-montre-de-la-4e-etape-du-Tour-de-Suisse-dun-cheveu-devant-Mathieu-van-der-Poel-1.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/06\/Tadej-Pogacar-sadjuge-le-contre-la-montre-de-la-4e-etape-du-Tour-de-Suisse-dun-cheveu-devant-Mathieu-van-der-Poel-1.png","width":1200,"height":674,"caption":"Tadej Poga\u010dar s'adjuge le contre-la-montre de la 4e \u00e9tape du Tour de Suisse d'un cheveu devant Mathieu van der Poel"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/tadej-pogacar-sadjuge-le-contre-la-montre-de-la-4e-etape-du-tour-de-suisse-dun-cheveu-devant-mathieu-van-der-poel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Tadej Poga\u010dar s&rsquo;adjuge le contre-la-montre de la 4e \u00e9tape du Tour de Suisse d&rsquo;un cheveu devant Mathieu van der Poel"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/fe500246414ca17ddf0c0312d7a792cc","name":"Olivier Dobiezynski","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/09\/5be8fe8d-9962-4f1e-ad06-d6f9dee30e6d-150x150.jpg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/09\/5be8fe8d-9962-4f1e-ad06-d6f9dee30e6d-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/09\/5be8fe8d-9962-4f1e-ad06-d6f9dee30e6d-150x150.jpg","caption":"Olivier Dobiezynski"},"description":"Depuis le milieu des ann\u00e9es 90, la passion du cyclisme m'anime. Mes h\u00e9ros s'appellent Luc Leblanc, Piotr Ugrumov, Paolo Savoldelli, Peter Sagan et bien \u00e9videmment Romain Bardet. R\u00e9dacteur depuis 2023, je suis ici pour partager cet amour de la Petite Reine. Vous pourrez me lire \u00e9galement sur du trail, du ski de fond et tout autre sujet susceptible d'\u00e9veiller ma curiosit\u00e9 sportive.","sameAs":["https:\/\/x.com\/https:\/\/x.com\/Olivier_Matros"],"url":"https:\/\/dicodusport.fr\/blog\/author\/olivier-gh\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/681169","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/92"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=681169"}],"version-history":[{"count":5,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/681169\/revisions"}],"predecessor-version":[{"id":681379,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/681169\/revisions\/681379"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/681304"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=681169"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=681169"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=681169"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}