{"id":681326,"date":"2026-06-20T23:09:41","date_gmt":"2026-06-20T21:09:41","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=681326&#038;preview=true&#038;preview_id=681326"},"modified":"2026-06-20T23:36:03","modified_gmt":"2026-06-20T21:36:03","slug":"top-14-montpellier-domine-le-stade-francais-et-rejoint-toulouse-en-finale","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/top-14-montpellier-domine-le-stade-francais-et-rejoint-toulouse-en-finale\/","title":{"rendered":"Top 14 : Montpellier domine le Stade Fran\u00e7ais et rejoint Toulouse en finale"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>TOP 14 2025\/2026 &#8211; Dominant physiquement dans un choc cadenass\u00e9 au <strong>Stade V\u00e9lodrome<\/strong>, Montpellier a logiquement \u00e9cart\u00e9 des Parisiens impuissants (25-15) pour s&rsquo;offrir une finale de <strong>Top 14<\/strong> face \u00e0 <strong>Toulouse<\/strong>.<\/em><\/strong><\/p>\n<ul>\n<li><strong>\u00c0 ce sujet \u2013 <a href=\"https:\/\/dicodusport.fr\/blog\/phase-finale-top-14-2025-2026-tableau-programme-et-resultats-mis-a-jour\/\">Phase finale Top 14 2025-2026 : tableau, programme et r\u00e9sultats mis \u00e0 jour<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Les demi-finales du <strong>Top 14 2025\/2026<\/strong> se poursuivent \u00e0 <strong>Marseille<\/strong> avec le choc entre le <strong>Stade Fran\u00e7ais<\/strong> et le <strong>Montpellier H\u00e9rault Rugby<\/strong> au <strong>Stade V\u00e9lodrome<\/strong>. Qualifi\u00e9s d&rsquo;office apr\u00e8s leur grosse saison r\u00e9guli\u00e8re, les H\u00e9raultais s&rsquo;avancent guid\u00e9s par leur jeune capitaine <strong>Lenni Nouchi<\/strong> et l&rsquo;arri\u00e8re <strong>Tom Banks<\/strong>.<\/p>\n<p style=\"text-align: justify;\">En face, les Parisiens ont d\u00fb passer par un barrage de haut vol face \u00e0 <strong>La Rochelle<\/strong>, marqu\u00e9 par le tripl\u00e9 de <strong>Romain Briatte<\/strong>, reconduit en troisi\u00e8me ligne, tandis que <strong>Paul Alo-Emile<\/strong> d\u00e9bute au poste de pilier droit. L&rsquo;enjeu est historique pour les deux clubs : le <strong>Stade Fran\u00e7ais<\/strong> vise sa premi\u00e8re finale depuis son sacre de 2015, alors que <strong>Montpellier<\/strong> court apr\u00e8s son premier rendez-vous au <strong>Stade de France<\/strong> depuis son titre de 2022.<\/p>\n<p style=\"text-align: justify;\">D\u00e8s le coup d\u2019envoi, ce sont les Montpelli\u00e9rains qui mettent la pression et du jeu dans le camp adverse. \u00c0 la suite d&rsquo;une premi\u00e8re faute parisienne \u00e0 35 m\u00e8tres, <strong>Domingo Miotti<\/strong> profite de cette occasion pour inscrire les trois premiers points de son \u00e9quipe sur p\u00e9nalit\u00e9 (3-0, 2e). Mais la r\u00e9action parisienne est rapide. Gr\u00e2ce \u00e0 un jeu fluide emmen\u00e9 par <strong>L\u00e9o Carbonel<\/strong> et <strong>L\u00e9o Barr\u00e9<\/strong>, l&rsquo;ouvreur permet aux siens de recoller au score sur une p\u00e9nalit\u00e9 aux 22 m\u00e8tres (3-3, 7e).<\/p>\n<h2>L&rsquo;\u00e9clair de Tom Banks lance les hostilit\u00e9s<\/h2>\n<p style=\"text-align: justify;\">Les premiers points dans le jeu sont finalement inscrits par <strong>Montpellier<\/strong>. \u00c0 la suite d\u2019un tr\u00e8s bon mouvement initi\u00e9 par <strong>Domingo Miotti<\/strong>, <strong>Tom Banks<\/strong> est trouv\u00e9 dans l\u2019intervalle sur une passe apr\u00e8s contact. Profitant d\u2019un boulevard, l\u2019arri\u00e8re australien inscrit le premier essai du match (10-3, 11e).<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">LE MAGNIFIQUE ESSAI DE BANKS AU MICRO \ud83c\udf99\ufe0f<\/p>\n<p>Les Montpelli\u00e9rains inscrivent le premier essai de cette demi-finale \ud83e\udd29<a href=\"https:\/\/x.com\/hashtag\/MHRSF?src=hash&amp;ref_src=twsrc%5Etfw\">#MHRSF<\/a> <a href=\"https:\/\/t.co\/xDYnuAnAG9\">pic.twitter.com\/xDYnuAnAG9<\/a><\/p>\n<p>\u2014 CANAL+ Rugby (@CanalplusRugby) <a href=\"https:\/\/x.com\/CanalplusRugby\/status\/2068414428442149365?ref_src=twsrc%5Etfw\">June 20, 2026<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.x.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p style=\"text-align: justify;\">La r\u00e9action parisienne est imm\u00e9diate. En quelques minutes, les Stadistes inscrivent deux essais coup sur coup, leur permettant de passer devant. Tout d\u2019abord, sur une bonne combinaison en sortie de touche, le jeu de passes entre <strong>Noah Nene<\/strong>, <strong>Yoan Tanga<\/strong> puis <strong>Kerr-Barlow<\/strong> s&rsquo;av\u00e8re ultra efficace pour envoyer le demi de m\u00eal\u00e9e \u00e0 l\u2019essai. Puis, dans la foul\u00e9e, dans les 22 m\u00e8tres c\u00f4t\u00e9 gauche, sur un coup de pied rasant de <strong>Jeremy Ward<\/strong>, <strong>Peniasi Dakuwaqa<\/strong> parvient \u00e0 ramasser le ballon pour inscrire en coin le deuxi\u00e8me essai de <strong>Paris<\/strong> apr\u00e8s 15 minutes de jeu (10-15, 16e).<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">Dakuwaqa sort les cannes pour conclure la magnifique action collective des Parisiens \ud83d\ude2e\u200d\ud83d\udca8<a href=\"https:\/\/x.com\/hashtag\/MHRSFP?src=hash&amp;ref_src=twsrc%5Etfw\">#MHRSFP<\/a> <a href=\"https:\/\/t.co\/LogJN2bWCV\">pic.twitter.com\/LogJN2bWCV<\/a><\/p>\n<p>\u2014 CANAL+ Rugby (@CanalplusRugby) <a href=\"https:\/\/x.com\/CanalplusRugby\/status\/2068435911835107669?ref_src=twsrc%5Etfw\">June 20, 2026<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.x.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p style=\"text-align: justify;\">Mais l\u2019indiscipline des <strong>Soldats Roses<\/strong> permet aux H\u00e9raultais de reprendre l\u2019avantage une dizaine de minutes plus tard. Sur deux p\u00e9nalit\u00e9s \u00e0 40 m\u00e8tres, <strong>Domingo Miotti<\/strong> r\u00e9ussit \u00e0 remettre son \u00e9quipe devant en l&rsquo;espace de cinq minutes (16-15, 22e et 27e). Alors que les Montpelli\u00e9rains reprennent la main sur le match, le <strong>Stade Fran\u00e7ais<\/strong> est r\u00e9duit \u00e0 14. Sur un ruck, <strong>Paul Alo-Emile<\/strong> vient d\u00e9blayer dangereusement au niveau de l&rsquo;articulation de <strong>Billy Vunipola<\/strong>, \u00e9copant d\u2019un carton jaune (33e). Dans une premi\u00e8re p\u00e9riode devenue de plus en plus brouillonne apr\u00e8s 20 minutes tr\u00e8s intenses, le score en reste \u00e0 16-15 \u00e0 la pause.<\/p>\n<ul>\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/les-notes-de-montpellier-stade-francais-domingo-miotti-en-metronome-paul-alo-emile-en-souffrance\/\">Les notes de Montpellier-Stade Fran\u00e7ais : Domingo Miotti en m\u00e9tronome, Paul Alo-Emile en souffrance<\/a><\/strong><\/li>\n<\/ul>\n<h2 style=\"text-align: justify;\">Le MHR dicte sa loi physiquement<\/h2>\n<p style=\"text-align: justify;\">Au retour des vestiaires, le jeu reste brouillon face \u00e0 des d\u00e9fenses solides. <strong>Domingo Miotti<\/strong> profite d\u2019une nouvelle p\u00e9nalit\u00e9 en faveur du <strong>MHR<\/strong> pour poursuivre son sans-faute et ajouter trois points au compteur (19-15, 44e). Dans un contexte marqu\u00e9 par de nombreuses fautes de main, le principal affrontement devient purement physique.<\/p>\n<p style=\"text-align: justify;\">C&rsquo;est notamment le cas en m\u00eal\u00e9e ferm\u00e9e, o\u00f9 les Montpelli\u00e9rains parviennent \u00e0 r\u00e9cup\u00e9rer plusieurs p\u00e9nalit\u00e9s cruciales. C\u2019est pourtant sur une phase de touche que les H\u00e9raultais profitent \u00e0 nouveau de l\u2019indiscipline parisienne : aux 22 m\u00e8tres, <strong>Domingo Miotti<\/strong> ajuste sa cible et permet \u00e0 son \u00e9quipe de prendre sept points d\u2019avance (22-15, 54e).<\/p>\n<p style=\"text-align: justify;\">Signe du manque de ma\u00eetrise des deux formations, sur une passe rat\u00e9e d&rsquo;<strong>Ali Price<\/strong> au milieu du terrain, <strong>L\u00e9o Carbonel<\/strong> tape au pied \u00e0 deux reprises pour s\u2019approcher de l\u2019en-but adverse. <strong>Joe Marchant<\/strong> parvient \u00e0 se saisir du ballon et \u00e0 glisser dans l\u2019en-but, mais le cuir n\u2019est pas aplati gr\u00e2ce au retour salvateur de <strong>Donovan Taofifenua<\/strong> (67e).<\/p>\n<p style=\"text-align: justify;\">Alors que le <strong>Stade Fran\u00e7ais<\/strong> continue de courir apr\u00e8s le ballon, le <strong>MHR<\/strong> parvient d\u00e9finitivement \u00e0 faire le break. \u00c0 moins de dix minutes de la fin, <strong>L\u00e9o Coly<\/strong> prend le relais face aux perches et inscrit une nouvelle p\u00e9nalit\u00e9 (25-15, 72e). Tandis que <strong>Montpellier<\/strong> inscrit neuf points pr\u00e9cieux en seconde p\u00e9riode, les Parisiens restent muets depuis l\u2019essai de <strong>Peniasi Dakuwaqa<\/strong> \u00e0 la 16e minute, illustrant leur totale impuissance offensive lors de ce second acte. Deuxi\u00e8me de la phase r\u00e9guli\u00e8re, le <strong>Montpellier H\u00e9rault Rugby<\/strong> valide son billet et rejoint le leader toulousain pour une finale explosive.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">MONTPELLIER REJOINT TOULOUSE EN FINALE \ud83e\udd2f<\/p>\n<p>Apr\u00e8s un match accroch\u00e9, les Montpelli\u00e9rains ont su se montrer disciplin\u00e9s et d\u00e9crocher leur billet pour le Stade de France \ud83d\udca5<a href=\"https:\/\/x.com\/hashtag\/MHRSFP?src=hash&amp;ref_src=twsrc%5Etfw\">#MHRSFP<\/a> <a href=\"https:\/\/t.co\/x9ctNsuZ3P\">pic.twitter.com\/x9ctNsuZ3P<\/a><\/p>\n<p>\u2014 CANAL+ Rugby (@CanalplusRugby) <a href=\"https:\/\/x.com\/CanalplusRugby\/status\/2068441203373211763?ref_src=twsrc%5Etfw\">June 20, 2026<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.x.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<div id=\"gtx-trans\" style=\"position: absolute; left: -14px; top: 40.9091px;\">\n<div class=\"gtx-trans-icon\"><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Montpellier a domin\u00e9 le Stade Fran\u00e7ais (25-15) en demi-finale du Top 14 2025-2026. Le MHR retrouvera Toulouse en finale pour un choc tr\u00e8s attendu.<\/p>\n","protected":false},"author":110,"featured_media":681396,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[47050],"tags":[32415,16878,5056,24,5088,111],"class_list":["post-681326","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-top-14","tag-actu","tag-breve","tag-montpellier-herault-rugby","tag-sport","tag-stade-francais-paris","tag-top-14"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Top 14 : Montpellier domine le Stade Fran\u00e7ais et rejoint Toulouse en finale<\/title>\n<meta name=\"description\" content=\"Montpellier a domin\u00e9 le Stade Fran\u00e7ais (25-15) en demi-finale du Top 14 2025-2026. Le MHR retrouvera Toulouse en finale pour un choc tr\u00e8s attendu.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/top-14-montpellier-domine-le-stade-francais-et-rejoint-toulouse-en-finale\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Montpellier d\u00e9fiera Toulouse en finale du Top 14 apr\u00e8s sa victoire face au Stade Fran\u00e7ais\" \/>\n<meta property=\"og:description\" content=\"Montpellier a domin\u00e9 le Stade Fran\u00e7ais (25-15) en demi-finale du Top 14 2025-2026. Le MHR retrouvera Toulouse en finale pour un choc tr\u00e8s attendu.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/top-14-montpellier-domine-le-stade-francais-et-rejoint-toulouse-en-finale\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2026-06-20T21:09:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-20T21:36:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/06\/Top-14-Montpellier-domine-le-Stade-Francais-et-rejoint-Toulouse-en-finale.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Malo Clement\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Montpellier d\u00e9fiera Toulouse en finale du Top 14 apr\u00e8s sa victoire face au Stade Fran\u00e7ais\" \/>\n<meta name=\"twitter:creator\" content=\"@dicodusport\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/top-14-montpellier-domine-le-stade-francais-et-rejoint-toulouse-en-finale\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/top-14-montpellier-domine-le-stade-francais-et-rejoint-toulouse-en-finale\\\/\"},\"author\":{\"name\":\"Malo Clement\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/c28883329a45cc92814310316945b3ce\"},\"headline\":\"Top 14 : Montpellier domine le Stade Fran\u00e7ais et rejoint Toulouse en finale\",\"datePublished\":\"2026-06-20T21:09:41+00:00\",\"dateModified\":\"2026-06-20T21:36:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/top-14-montpellier-domine-le-stade-francais-et-rejoint-toulouse-en-finale\\\/\"},\"wordCount\":950,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/top-14-montpellier-domine-le-stade-francais-et-rejoint-toulouse-en-finale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Top-14-Montpellier-domine-le-Stade-Francais-et-rejoint-Toulouse-en-finale.png\",\"keywords\":[\"actu\",\"br\u00e8ve\",\"Montpellier H\u00e9rault rugby\",\"sport\",\"Stade Fran\u00e7ais Paris\",\"Top 14\"],\"articleSection\":[\"Top 14\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/top-14-montpellier-domine-le-stade-francais-et-rejoint-toulouse-en-finale\\\/#respond\"]}],\"copyrightYear\":\"2026\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/top-14-montpellier-domine-le-stade-francais-et-rejoint-toulouse-en-finale\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/top-14-montpellier-domine-le-stade-francais-et-rejoint-toulouse-en-finale\\\/\",\"name\":\"Top 14 : Montpellier domine le Stade Fran\u00e7ais et rejoint Toulouse en finale\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/top-14-montpellier-domine-le-stade-francais-et-rejoint-toulouse-en-finale\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/top-14-montpellier-domine-le-stade-francais-et-rejoint-toulouse-en-finale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Top-14-Montpellier-domine-le-Stade-Francais-et-rejoint-Toulouse-en-finale.png\",\"datePublished\":\"2026-06-20T21:09:41+00:00\",\"dateModified\":\"2026-06-20T21:36:03+00:00\",\"description\":\"Montpellier a domin\u00e9 le Stade Fran\u00e7ais (25-15) en demi-finale du Top 14 2025-2026. Le MHR retrouvera Toulouse en finale pour un choc tr\u00e8s attendu.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/top-14-montpellier-domine-le-stade-francais-et-rejoint-toulouse-en-finale\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/top-14-montpellier-domine-le-stade-francais-et-rejoint-toulouse-en-finale\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/top-14-montpellier-domine-le-stade-francais-et-rejoint-toulouse-en-finale\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Top-14-Montpellier-domine-le-Stade-Francais-et-rejoint-Toulouse-en-finale.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Top-14-Montpellier-domine-le-Stade-Francais-et-rejoint-Toulouse-en-finale.png\",\"width\":1200,\"height\":674,\"caption\":\"Top 14 Montpellier domine le Stade Fran\u00e7ais et rejoint Toulouse en finale\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/top-14-montpellier-domine-le-stade-francais-et-rejoint-toulouse-en-finale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Top 14 : Montpellier domine le Stade Fran\u00e7ais et rejoint Toulouse en finale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/c28883329a45cc92814310316945b3ce\",\"name\":\"Malo Clement\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Maillot-Dicodusport-Malo-150x150.png\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Maillot-Dicodusport-Malo-150x150.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Maillot-Dicodusport-Malo-150x150.png\",\"caption\":\"Malo Clement\"},\"description\":\"Fan de sport depuis mes 10 ans, mes premiers souvenirs de stade sont le Racing M\u00e9tro 92 \u00e0 Yves du Manoir, le XV de France et le PSG de Nen\u00ea. Celui d\u2019Ibra, Lucas, Cavani et Verratti m\u2019ont d\u00e9finitivement emport\u00e9 dans le football, au d\u00e9sarroi de ma famille. Entre les finales perdues de Champions Cup et les m\u00e9saventures en Ligue des Champions, j\u2019ai eu le nez fin. Au-del\u00e0 de mes clubs franciliens, je m\u2019int\u00e9resse au sport en g\u00e9n\u00e9ral et principalement \u00e0 la d\u00e9couverte de jeunes sportifs. Cela a commenc\u00e9 par Football Manager et j'ai repris \u00e7a avec les sports automobiles. Depuis 2020, mes dimanches apr\u00e8s-midi sont occup\u00e9s par Julien F\u00e9breau et la Formule 1. L\u2019endurance, la F2, la F3 et les autres championnats compl\u00e8tent mes week-ends. J\u2019ai rejoint Dicodusport en novembre 2024 et je suis ravi d\u2019\u00eatre le cadet de la r\u00e9daction.\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/clement-malo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Top 14 : Montpellier domine le Stade Fran\u00e7ais et rejoint Toulouse en finale","description":"Montpellier a domin\u00e9 le Stade Fran\u00e7ais (25-15) en demi-finale du Top 14 2025-2026. Le MHR retrouvera Toulouse en finale pour un choc tr\u00e8s attendu.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/top-14-montpellier-domine-le-stade-francais-et-rejoint-toulouse-en-finale\/","og_locale":"fr_FR","og_type":"article","og_title":"Montpellier d\u00e9fiera Toulouse en finale du Top 14 apr\u00e8s sa victoire face au Stade Fran\u00e7ais","og_description":"Montpellier a domin\u00e9 le Stade Fran\u00e7ais (25-15) en demi-finale du Top 14 2025-2026. Le MHR retrouvera Toulouse en finale pour un choc tr\u00e8s attendu.","og_url":"https:\/\/dicodusport.fr\/blog\/top-14-montpellier-domine-le-stade-francais-et-rejoint-toulouse-en-finale\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2026-06-20T21:09:41+00:00","article_modified_time":"2026-06-20T21:36:03+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/06\/Top-14-Montpellier-domine-le-Stade-Francais-et-rejoint-Toulouse-en-finale.png","type":"image\/png"}],"author":"Malo Clement","twitter_card":"summary_large_image","twitter_title":"Montpellier d\u00e9fiera Toulouse en finale du Top 14 apr\u00e8s sa victoire face au Stade Fran\u00e7ais","twitter_creator":"@dicodusport","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/top-14-montpellier-domine-le-stade-francais-et-rejoint-toulouse-en-finale\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/top-14-montpellier-domine-le-stade-francais-et-rejoint-toulouse-en-finale\/"},"author":{"name":"Malo Clement","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/c28883329a45cc92814310316945b3ce"},"headline":"Top 14 : Montpellier domine le Stade Fran\u00e7ais et rejoint Toulouse en finale","datePublished":"2026-06-20T21:09:41+00:00","dateModified":"2026-06-20T21:36:03+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/top-14-montpellier-domine-le-stade-francais-et-rejoint-toulouse-en-finale\/"},"wordCount":950,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/top-14-montpellier-domine-le-stade-francais-et-rejoint-toulouse-en-finale\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/06\/Top-14-Montpellier-domine-le-Stade-Francais-et-rejoint-Toulouse-en-finale.png","keywords":["actu","br\u00e8ve","Montpellier H\u00e9rault rugby","sport","Stade Fran\u00e7ais Paris","Top 14"],"articleSection":["Top 14"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/top-14-montpellier-domine-le-stade-francais-et-rejoint-toulouse-en-finale\/#respond"]}],"copyrightYear":"2026","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/top-14-montpellier-domine-le-stade-francais-et-rejoint-toulouse-en-finale\/","url":"https:\/\/dicodusport.fr\/blog\/top-14-montpellier-domine-le-stade-francais-et-rejoint-toulouse-en-finale\/","name":"Top 14 : Montpellier domine le Stade Fran\u00e7ais et rejoint Toulouse en finale","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/top-14-montpellier-domine-le-stade-francais-et-rejoint-toulouse-en-finale\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/top-14-montpellier-domine-le-stade-francais-et-rejoint-toulouse-en-finale\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/06\/Top-14-Montpellier-domine-le-Stade-Francais-et-rejoint-Toulouse-en-finale.png","datePublished":"2026-06-20T21:09:41+00:00","dateModified":"2026-06-20T21:36:03+00:00","description":"Montpellier a domin\u00e9 le Stade Fran\u00e7ais (25-15) en demi-finale du Top 14 2025-2026. Le MHR retrouvera Toulouse en finale pour un choc tr\u00e8s attendu.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/top-14-montpellier-domine-le-stade-francais-et-rejoint-toulouse-en-finale\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/top-14-montpellier-domine-le-stade-francais-et-rejoint-toulouse-en-finale\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/top-14-montpellier-domine-le-stade-francais-et-rejoint-toulouse-en-finale\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/06\/Top-14-Montpellier-domine-le-Stade-Francais-et-rejoint-Toulouse-en-finale.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/06\/Top-14-Montpellier-domine-le-Stade-Francais-et-rejoint-Toulouse-en-finale.png","width":1200,"height":674,"caption":"Top 14 Montpellier domine le Stade Fran\u00e7ais et rejoint Toulouse en finale"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/top-14-montpellier-domine-le-stade-francais-et-rejoint-toulouse-en-finale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Top 14 : Montpellier domine le Stade Fran\u00e7ais et rejoint Toulouse en finale"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/c28883329a45cc92814310316945b3ce","name":"Malo Clement","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Maillot-Dicodusport-Malo-150x150.png","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Maillot-Dicodusport-Malo-150x150.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Maillot-Dicodusport-Malo-150x150.png","caption":"Malo Clement"},"description":"Fan de sport depuis mes 10 ans, mes premiers souvenirs de stade sont le Racing M\u00e9tro 92 \u00e0 Yves du Manoir, le XV de France et le PSG de Nen\u00ea. Celui d\u2019Ibra, Lucas, Cavani et Verratti m\u2019ont d\u00e9finitivement emport\u00e9 dans le football, au d\u00e9sarroi de ma famille. Entre les finales perdues de Champions Cup et les m\u00e9saventures en Ligue des Champions, j\u2019ai eu le nez fin. Au-del\u00e0 de mes clubs franciliens, je m\u2019int\u00e9resse au sport en g\u00e9n\u00e9ral et principalement \u00e0 la d\u00e9couverte de jeunes sportifs. Cela a commenc\u00e9 par Football Manager et j'ai repris \u00e7a avec les sports automobiles. Depuis 2020, mes dimanches apr\u00e8s-midi sont occup\u00e9s par Julien F\u00e9breau et la Formule 1. L\u2019endurance, la F2, la F3 et les autres championnats compl\u00e8tent mes week-ends. J\u2019ai rejoint Dicodusport en novembre 2024 et je suis ravi d\u2019\u00eatre le cadet de la r\u00e9daction.","url":"https:\/\/dicodusport.fr\/blog\/author\/clement-malo\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/681326","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/110"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=681326"}],"version-history":[{"count":5,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/681326\/revisions"}],"predecessor-version":[{"id":681412,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/681326\/revisions\/681412"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/681396"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=681326"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=681326"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=681326"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}