{"id":681666,"date":"2026-06-21T21:50:56","date_gmt":"2026-06-21T19:50:56","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=681666&#038;preview=true&#038;preview_id=681666"},"modified":"2026-06-21T22:26:30","modified_gmt":"2026-06-21T20:26:30","slug":"etrilles-en-finale-par-litalie-les-bleus-du-fleuret-restent-vice-champions-deurope","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/etrilles-en-finale-par-litalie-les-bleus-du-fleuret-restent-vice-champions-deurope\/","title":{"rendered":"\u00c9trill\u00e9s en finale par l&rsquo;Italie, les Bleus du fleuret restent vice-champions d&rsquo;Europe"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>CHAMPIONNATS D&rsquo;EUROPE D&rsquo;ESCRIME 2026 &#8211; Apr\u00e8s deux victoires solides, les Bleus du fleuret ont \u00e9t\u00e9 \u00e9crabouill\u00e9s par l&rsquo;Italie en finale, et se contentent de l&rsquo;argent.<\/em><\/strong><\/p>\n<ul style=\"text-align: justify;\">\n<li><strong>\u00c0 ce sujet \u2013\u00a0<a href=\"https:\/\/dicodusport.fr\/blog\/calendrier-et-resultats-championnats-deurope-descrime-2026\/\">Calendrier et r\u00e9sultats Championnats d\u2019Europe d\u2019escrime 2026<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Depuis 2019, jamais l&rsquo;\u00e9quipe de France n&rsquo;a manqu\u00e9 d&rsquo;aller en finale des championnats d&rsquo;Europe, avec en point d&rsquo;orgue ses titres en 2019 et en 2024. Cette fois, <a href=\"https:\/\/dicodusport.fr\/blog\/escrime-championnats-deurope-2025-anas-anane-prend-largent-au-fleuret\/\">le vice-champion d&rsquo;Europe 2025<\/a> <strong>Anas Anane<\/strong>, <a href=\"https:\/\/dicodusport.fr\/blog\/escrime-championnats-du-monde-2025-maxime-pauty-fleuret-ouvre-le-compteur-tricolore-avec-du-bronze\/\">l&rsquo;ancien m\u00e9daill\u00e9 mondial<\/a> <strong>Maxime Pauty<\/strong>, <strong>Alexandre Sido<\/strong> et bien \u00e9videmment <a href=\"https:\/\/dicodusport.fr\/blog\/rafael-savin-remporte-le-premier-titre-europeen-du-fleuret-hommes-francais-depuis-30-ans\/\">le tout frais champion d&rsquo;Europe<\/a> <strong>Rafael Savin<\/strong> entendaient bien faire de m\u00eame, avec le titre en ligne de mire<\/p>\n<h2 style=\"text-align: justify;\">Finale bien terne malgr\u00e9 Pauty<\/h2>\n<p style=\"text-align: justify;\">Avec une entr\u00e9e en piste en quarts de finale, la m\u00e9daille \u00e9tait \u00e0 port\u00e9e de mains. Et encore plus apr\u00e8s une victoire ais\u00e9e contre l&rsquo;Espagne, avec notamment un premier gros relais de <strong>Maxime Pauty<\/strong> pour lancer les Bleus sur la voie du succ\u00e8s. N\u00e9anmoins, la demi-finale s&rsquo;annon\u00e7ait plus relev\u00e9e contre l&rsquo;Allemagne, mais alors que la France menait <strong>30-27<\/strong> au deux tiers du match, l&rsquo;acc\u00e9l\u00e9ration allait \u00eatre foudroyante, <strong>Anas Anane<\/strong> et <strong>Pauty<\/strong> concluant chacun par un <strong>5-0<\/strong> pour une victoire <strong>45-30<\/strong> et une place en finale.<\/p>\n<p style=\"text-align: justify;\">Face \u00e0 eux, leurs meilleurs ennemis : les Italiens, champions du monde et vice-champions olympiques en titre. Le match commen\u00e7ait bien mal : les Bleus \u00e9taient men\u00e9s 15-7 apr\u00e8s trois relais. Mais <strong>Pauty<\/strong>, encore lui, sortait une prestation exceptionnelle et collait un <strong>13-4<\/strong> \u00e0 <strong>Tommaso Marini<\/strong>, soit le champion du monde 2023 !<\/p>\n<ul>\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet \u2013 <a href=\"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-escrime-championnats-deurope-2026\/\" target=\"_blank\" rel=\"noopener\">Tableau des m\u00e9dailles Championnats d\u2019Europe d\u2019escrime 2026<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Mais cela allait \u00eatre le chant du cygne. Menant<strong> 20-19<\/strong>, les Bleus allaient sombrer corps et \u00e2mes. Au point de ne plus inscrire que deux touches jusqu&rsquo;\u00e0 la fin du match. Le relais de Pauty \u00e9tait donc un \u00e9piph\u00e9nom\u00e8ne et compterait pour 13 des 22 points fran\u00e7ais. Une fin en eau de boudin, mais encore une fois, les Bleus du fleuret sont la deuxi\u00e8me force europ\u00e9enne, sans nul doute.<\/p>\n<h3>\u00c0 lire aussi<\/h3>\n<div class=\"vlp-link-container vlp-layout-article\"><a href=\"https:\/\/dicodusport.fr\/blog\/les-bleues-de-lepee-triomphent-de-la-hongrie-et-redeviennent-championnes-deurope-par-equipes\/\" class=\"vlp-link\" title=\"Les Bleues de l&#039;\u00e9p\u00e9e triomphent de la Hongrie et redeviennent championnes d&#039;Europe par \u00e9quipes !\"><\/a><div class=\"vlp-layout-zone-side\"><div class=\"vlp-block-4 vlp-link-image\"><img loading=\"lazy\" decoding=\"async\" style=\"max-width: 792px;\" width=\"792\" height=\"445\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/06\/Les-Bleues-de-lepee-triomphent-de-la-Hongrie-et-redeviennent-championnes-dEurope-par-equipes-1-1.png\" class=\"attachment-800x445 size-800x445\" alt=\"Les Bleues de l&#039;\u00e9p\u00e9e triomphent de la Hongrie et redeviennent championnes d&#039;Europe par \u00e9quipes !\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/06\/Les-Bleues-de-lepee-triomphent-de-la-Hongrie-et-redeviennent-championnes-dEurope-par-equipes-1-1.png 1200w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/06\/Les-Bleues-de-lepee-triomphent-de-la-Hongrie-et-redeviennent-championnes-dEurope-par-equipes-1-1-300x169.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/06\/Les-Bleues-de-lepee-triomphent-de-la-Hongrie-et-redeviennent-championnes-dEurope-par-equipes-1-1-1024x575.png 1024w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/06\/Les-Bleues-de-lepee-triomphent-de-la-Hongrie-et-redeviennent-championnes-dEurope-par-equipes-1-1-768x431.png 768w\" sizes=\"auto, (max-width: 792px) 100vw, 792px\" \/><\/div><\/div><div class=\"vlp-layout-zone-main\"><div class=\"vlp-block-0 vlp-link-title\">Les Bleues de l'\u00e9p\u00e9e triomphent de la Hongrie et redeviennent championnes d'Europe par \u00e9quipes !<\/div><div class=\"vlp-block-1 vlp-link-summary\">CHAMPIONNATS D'EUROPE D'ESCRIME 2026 - Trois ans apr\u00e8s, les Bleues de l'\u00e9p\u00e9e retrouvent l'or europ\u00e9en apr\u00e8s une finale disput\u00e9e contre la Hongrie.\u00a0<\/div><div class=\"vlp-block-2 vlp-link-button\">Lire l'article<\/div><div class=\"vlp-block-3 vlp-link-url\">dicodusport.fr<\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>CHAMPIONNATS D&rsquo;EUROPE D&rsquo;ESCRIME 2026 &#8211; Apr\u00e8s deux victoires solides, les Bleus du fleuret ont \u00e9t\u00e9 \u00e9crabouill\u00e9s par l&rsquo;Italie en finale, et se contentent de l&rsquo;argent.<\/p>\n","protected":false},"author":59,"featured_media":681770,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[9251],"tags":[16878,47062,23855],"class_list":["post-681666","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-escrime","tag-breve","tag-championnats-deurope-descrime","tag-escrime-francaise"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u00c9trill\u00e9s en finale par l&#039;Italie, les Bleus du fleuret restent vice-champions d&#039;Europe<\/title>\n<meta name=\"description\" content=\"CHAMPIONNATS D&#039;EUROPE D&#039;ESCRIME 2026 - Apr\u00e8s deux victoires solides, les Bleus du fleuret ont \u00e9t\u00e9 \u00e9crabouill\u00e9s par l&#039;Italie en finale, et se contentent de l&#039;argent.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/etrilles-en-finale-par-litalie-les-bleus-du-fleuret-restent-vice-champions-deurope\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00c9trill\u00e9s en finale par l&#039;Italie, les Bleus du fleuret restent vice-champions d&#039;Europe\" \/>\n<meta property=\"og:description\" content=\"CHAMPIONNATS D&#039;EUROPE D&#039;ESCRIME 2026 - Apr\u00e8s deux victoires solides, les Bleus du fleuret ont \u00e9t\u00e9 \u00e9crabouill\u00e9s par l&#039;Italie en finale, et se contentent de l&#039;argent.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/etrilles-en-finale-par-litalie-les-bleus-du-fleuret-restent-vice-champions-deurope\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/sebastien.gente\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-06-21T19:50:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-21T20:26:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/06\/Etrilles-en-finale-par-lItalie-les-Bleus-du-fleuret-restent-vice-champions-dEurope-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"S\u00e9bastien Gente\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"\u00c9trill\u00e9s en finale par l&#039;Italie, les Bleus du fleuret restent vice-champions d&#039;Europe\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/globulo24\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/etrilles-en-finale-par-litalie-les-bleus-du-fleuret-restent-vice-champions-deurope\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/etrilles-en-finale-par-litalie-les-bleus-du-fleuret-restent-vice-champions-deurope\\\/\"},\"author\":{\"name\":\"S\u00e9bastien Gente\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/627966a6cde45dbd8c5e36ac85d783da\"},\"headline\":\"\u00c9trill\u00e9s en finale par l&rsquo;Italie, les Bleus du fleuret restent vice-champions d&rsquo;Europe\",\"datePublished\":\"2026-06-21T19:50:56+00:00\",\"dateModified\":\"2026-06-21T20:26:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/etrilles-en-finale-par-litalie-les-bleus-du-fleuret-restent-vice-champions-deurope\\\/\"},\"wordCount\":457,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/etrilles-en-finale-par-litalie-les-bleus-du-fleuret-restent-vice-champions-deurope\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Etrilles-en-finale-par-lItalie-les-Bleus-du-fleuret-restent-vice-champions-dEurope-1.png\",\"keywords\":[\"br\u00e8ve\",\"championnats d'Europe d'escrime\",\"Escrime fran\u00e7aise\"],\"articleSection\":[\"Escrime\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/etrilles-en-finale-par-litalie-les-bleus-du-fleuret-restent-vice-champions-deurope\\\/#respond\"]}],\"copyrightYear\":\"2026\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/etrilles-en-finale-par-litalie-les-bleus-du-fleuret-restent-vice-champions-deurope\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/etrilles-en-finale-par-litalie-les-bleus-du-fleuret-restent-vice-champions-deurope\\\/\",\"name\":\"\u00c9trill\u00e9s en finale par l'Italie, les Bleus du fleuret restent vice-champions d'Europe\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/etrilles-en-finale-par-litalie-les-bleus-du-fleuret-restent-vice-champions-deurope\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/etrilles-en-finale-par-litalie-les-bleus-du-fleuret-restent-vice-champions-deurope\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Etrilles-en-finale-par-lItalie-les-Bleus-du-fleuret-restent-vice-champions-dEurope-1.png\",\"datePublished\":\"2026-06-21T19:50:56+00:00\",\"dateModified\":\"2026-06-21T20:26:30+00:00\",\"description\":\"CHAMPIONNATS D'EUROPE D'ESCRIME 2026 - Apr\u00e8s deux victoires solides, les Bleus du fleuret ont \u00e9t\u00e9 \u00e9crabouill\u00e9s par l'Italie en finale, et se contentent de l'argent.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/etrilles-en-finale-par-litalie-les-bleus-du-fleuret-restent-vice-champions-deurope\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/etrilles-en-finale-par-litalie-les-bleus-du-fleuret-restent-vice-champions-deurope\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/etrilles-en-finale-par-litalie-les-bleus-du-fleuret-restent-vice-champions-deurope\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Etrilles-en-finale-par-lItalie-les-Bleus-du-fleuret-restent-vice-champions-dEurope-1.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Etrilles-en-finale-par-lItalie-les-Bleus-du-fleuret-restent-vice-champions-dEurope-1.png\",\"width\":1200,\"height\":674,\"caption\":\"\u00c9trill\u00e9s en finale par l'Italie, les Bleus du fleuret restent vice-champions d'Europe\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/etrilles-en-finale-par-litalie-les-bleus-du-fleuret-restent-vice-champions-deurope\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00c9trill\u00e9s en finale par l&rsquo;Italie, les Bleus du fleuret restent vice-champions d&rsquo;Europe\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/627966a6cde45dbd8c5e36ac85d783da\",\"name\":\"S\u00e9bastien Gente\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"caption\":\"S\u00e9bastien Gente\"},\"description\":\"John Stockton, Gianni Bugno, Zinedine Zidane, Steffi Graf, Frode Andresen, St\u00e9phane Stoecklin, Davis Kamoga, Primoz Peterka, Werner Schlager et Aur\u00e9lien Rougerie. Point commun entre ces sportifs? Ils m'ont fait r\u00eaver et ont berc\u00e9 mon adolescence. Je suis un fondu de sports et j'essaie de retranscrire ma passion \u00e0 travers mes articles. Originaire du P\u00e9rigord, ma passion pour les Girondins, les Jaunards et les Jazzmen transpire dans mes \u00e9crits. \u00c0 Dicodusport depuis 2021, je d\u00e9niche les sports m\u00e9connus dans lesquels la France brille, et il y en a !\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/sebastien.gente\\\/\",\"https:\\\/\\\/www.instagram.com\\\/sebgente\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/sbastien-gente-a29583169\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/globulo24\",\"SebastienGente\"],\"worksFor\":\"S\u00e9bastien GENTE\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/sebastiengente\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u00c9trill\u00e9s en finale par l'Italie, les Bleus du fleuret restent vice-champions d'Europe","description":"CHAMPIONNATS D'EUROPE D'ESCRIME 2026 - Apr\u00e8s deux victoires solides, les Bleus du fleuret ont \u00e9t\u00e9 \u00e9crabouill\u00e9s par l'Italie en finale, et se contentent de l'argent.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/etrilles-en-finale-par-litalie-les-bleus-du-fleuret-restent-vice-champions-deurope\/","og_locale":"fr_FR","og_type":"article","og_title":"\u00c9trill\u00e9s en finale par l'Italie, les Bleus du fleuret restent vice-champions d'Europe","og_description":"CHAMPIONNATS D'EUROPE D'ESCRIME 2026 - Apr\u00e8s deux victoires solides, les Bleus du fleuret ont \u00e9t\u00e9 \u00e9crabouill\u00e9s par l'Italie en finale, et se contentent de l'argent.","og_url":"https:\/\/dicodusport.fr\/blog\/etrilles-en-finale-par-litalie-les-bleus-du-fleuret-restent-vice-champions-deurope\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/sebastien.gente\/","article_published_time":"2026-06-21T19:50:56+00:00","article_modified_time":"2026-06-21T20:26:30+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/06\/Etrilles-en-finale-par-lItalie-les-Bleus-du-fleuret-restent-vice-champions-dEurope-1.png","type":"image\/png"}],"author":"S\u00e9bastien Gente","twitter_card":"summary_large_image","twitter_title":"\u00c9trill\u00e9s en finale par l'Italie, les Bleus du fleuret restent vice-champions d'Europe","twitter_creator":"@https:\/\/twitter.com\/globulo24","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/etrilles-en-finale-par-litalie-les-bleus-du-fleuret-restent-vice-champions-deurope\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/etrilles-en-finale-par-litalie-les-bleus-du-fleuret-restent-vice-champions-deurope\/"},"author":{"name":"S\u00e9bastien Gente","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da"},"headline":"\u00c9trill\u00e9s en finale par l&rsquo;Italie, les Bleus du fleuret restent vice-champions d&rsquo;Europe","datePublished":"2026-06-21T19:50:56+00:00","dateModified":"2026-06-21T20:26:30+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/etrilles-en-finale-par-litalie-les-bleus-du-fleuret-restent-vice-champions-deurope\/"},"wordCount":457,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/etrilles-en-finale-par-litalie-les-bleus-du-fleuret-restent-vice-champions-deurope\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/06\/Etrilles-en-finale-par-lItalie-les-Bleus-du-fleuret-restent-vice-champions-dEurope-1.png","keywords":["br\u00e8ve","championnats d'Europe d'escrime","Escrime fran\u00e7aise"],"articleSection":["Escrime"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/etrilles-en-finale-par-litalie-les-bleus-du-fleuret-restent-vice-champions-deurope\/#respond"]}],"copyrightYear":"2026","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/etrilles-en-finale-par-litalie-les-bleus-du-fleuret-restent-vice-champions-deurope\/","url":"https:\/\/dicodusport.fr\/blog\/etrilles-en-finale-par-litalie-les-bleus-du-fleuret-restent-vice-champions-deurope\/","name":"\u00c9trill\u00e9s en finale par l'Italie, les Bleus du fleuret restent vice-champions d'Europe","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/etrilles-en-finale-par-litalie-les-bleus-du-fleuret-restent-vice-champions-deurope\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/etrilles-en-finale-par-litalie-les-bleus-du-fleuret-restent-vice-champions-deurope\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/06\/Etrilles-en-finale-par-lItalie-les-Bleus-du-fleuret-restent-vice-champions-dEurope-1.png","datePublished":"2026-06-21T19:50:56+00:00","dateModified":"2026-06-21T20:26:30+00:00","description":"CHAMPIONNATS D'EUROPE D'ESCRIME 2026 - Apr\u00e8s deux victoires solides, les Bleus du fleuret ont \u00e9t\u00e9 \u00e9crabouill\u00e9s par l'Italie en finale, et se contentent de l'argent.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/etrilles-en-finale-par-litalie-les-bleus-du-fleuret-restent-vice-champions-deurope\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/etrilles-en-finale-par-litalie-les-bleus-du-fleuret-restent-vice-champions-deurope\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/etrilles-en-finale-par-litalie-les-bleus-du-fleuret-restent-vice-champions-deurope\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/06\/Etrilles-en-finale-par-lItalie-les-Bleus-du-fleuret-restent-vice-champions-dEurope-1.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/06\/Etrilles-en-finale-par-lItalie-les-Bleus-du-fleuret-restent-vice-champions-dEurope-1.png","width":1200,"height":674,"caption":"\u00c9trill\u00e9s en finale par l'Italie, les Bleus du fleuret restent vice-champions d'Europe"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/etrilles-en-finale-par-litalie-les-bleus-du-fleuret-restent-vice-champions-deurope\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"\u00c9trill\u00e9s en finale par l&rsquo;Italie, les Bleus du fleuret restent vice-champions d&rsquo;Europe"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da","name":"S\u00e9bastien Gente","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","caption":"S\u00e9bastien Gente"},"description":"John Stockton, Gianni Bugno, Zinedine Zidane, Steffi Graf, Frode Andresen, St\u00e9phane Stoecklin, Davis Kamoga, Primoz Peterka, Werner Schlager et Aur\u00e9lien Rougerie. Point commun entre ces sportifs? Ils m'ont fait r\u00eaver et ont berc\u00e9 mon adolescence. Je suis un fondu de sports et j'essaie de retranscrire ma passion \u00e0 travers mes articles. Originaire du P\u00e9rigord, ma passion pour les Girondins, les Jaunards et les Jazzmen transpire dans mes \u00e9crits. \u00c0 Dicodusport depuis 2021, je d\u00e9niche les sports m\u00e9connus dans lesquels la France brille, et il y en a !","sameAs":["https:\/\/www.facebook.com\/sebastien.gente\/","https:\/\/www.instagram.com\/sebgente\/","https:\/\/www.linkedin.com\/in\/sbastien-gente-a29583169\/","https:\/\/x.com\/https:\/\/twitter.com\/globulo24","SebastienGente"],"worksFor":"S\u00e9bastien GENTE","url":"https:\/\/dicodusport.fr\/blog\/author\/sebastiengente\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/681666","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/59"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=681666"}],"version-history":[{"count":2,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/681666\/revisions"}],"predecessor-version":[{"id":681771,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/681666\/revisions\/681771"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/681770"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=681666"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=681666"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=681666"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}