{"id":682494,"date":"2026-06-26T19:53:32","date_gmt":"2026-06-26T17:53:32","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=682494&#038;preview=true&#038;preview_id=682494"},"modified":"2026-06-26T19:54:19","modified_gmt":"2026-06-26T17:54:19","slug":"norvege-france-la-compo-probable-des-bleus","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/norvege-france-la-compo-probable-des-bleus\/","title":{"rendered":"Norv\u00e8ge-France : la compo officielle des Bleus"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>COUPE DU MONDE DE FOOTBALL 2026 &#8211; D\u00e9couvrez les compositions officielles du match du groupe I entre la Norv\u00e8ge et la France.<\/em><\/strong><\/p>\n<ul style=\"text-align: justify;\">\n<li><strong>\u00c0 ce sujet \u2013 <a href=\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-2026-groupe-i-calendrier-classement-et-resultats\/\">Coupe du monde 2026 \u2013 Groupe I : calendrier, classement et r\u00e9sultats<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">La <a href=\"https:\/\/dicodusport.fr\/blog\/france-coupe-du-monde-2026-liste-calendrier-joueurs-a-suivre-ambitions-tout-savoir-sur-les-bleus\/\"><strong>France<\/strong><\/a> et la <a href=\"https:\/\/dicodusport.fr\/blog\/norvege-coupe-du-monde-2026-liste-calendrier-joueurs-a-suivre-ambitions-tout-savoir-sur-les-drillos\/\"><strong>Norv\u00e8ge<\/strong><\/a> ont remport\u00e9 leurs deux premiers matchs de poule, et cette derni\u00e8re rencontre sera donc d\u00e9cisive pour la premi\u00e8re place du groupe. \u00c0 noter que <strong>Didier Deschamps<\/strong> ne sera pas pr\u00e9sent pour cette rencontre, puisqu&rsquo;il a d\u00fb retourner en France \u00e0 la suite d&rsquo;un deuil.<\/p>\n<ul style=\"text-align: justify;\">\n<li><strong>\u00c0 ce sujet \u2013 <a href=\"https:\/\/dicodusport.fr\/blog\/les-enseignements-de-france-irak-la-meteo-star-du-match-100e-rugissante-pour-mbappe\/\">Les enseignements de France-Irak : la m\u00e9t\u00e9o star du match, 100e rugissante pour Mbapp\u00e9<\/a><\/strong><\/li>\n<\/ul>\n<h2 style=\"text-align: justify;\">Rayan Cherki pas titulaire<\/h2>\n<p style=\"text-align: justify;\">Le staff des <strong>Bleus<\/strong> pouvait \u00e9ventuellement de nouveau modifier son animation offensive dans le couloir gauche. Apr\u00e8s <strong>D\u00e9sir\u00e9 Dou\u00e9<\/strong> face au S\u00e9n\u00e9gal et <strong>Bradley Barcola<\/strong> face \u00e0 l&rsquo;Irak, <strong>Rayan Cherki<\/strong> \u00e9tait pressenti pour d\u00e9buter \u00e0 ce poste. Mais c&rsquo;est finalement D\u00e9sir\u00e9 Dou\u00e9, comme au premier match, qui sera\u00a0associ\u00e9 \u00e0 <strong>Ousmane Demb\u00e9l\u00e9<\/strong> et <strong>Michael Olise<\/strong>, en soutien de <strong>Kylian Mbapp\u00e9<\/strong>.<\/p>\n<p style=\"text-align: justify;\">En d\u00e9fense, <strong>Th\u00e9o Hernandez<\/strong> va effectuer son retour dans le couloir gauche \u00e0 la place de <strong>Lucas Digne<\/strong>. Comme annonc\u00e9 en conf\u00e9rence de presse, William Saliba est m\u00e9nag\u00e9 pour ce match et remplac\u00e9 par <strong>Maxence Lacroix<\/strong>. Au milieu de terrain, <strong>Manu Kon\u00e9<\/strong> est de nouveau pr\u00e9f\u00e9r\u00e9 \u00e0 <strong>Aur\u00e9lien Tchouam\u00e9ni<\/strong>. \u00c0 noter que la Norv\u00e8ge fait largement tourner, <strong>Erling Haaland<\/strong> \u00e9tant notamment sur le banc.<\/p>\n<h2 style=\"text-align: justify;\">Les compositions officielles de Norv\u00e8ge vs France<\/h2>\n<p style=\"text-align: justify;\"><b>Norv\u00e8ge <\/b>: Selvik; Aursnes, \u00d6stigard, Falchener, Bj\u00f6rkan; Aasgaard, Berg, Thorsvtedt; Bobb, Strand Larsen, Schjelderup<\/p>\n<p style=\"text-align: justify;\"><strong>France<\/strong> : Maignan ; Kound\u00e9, Upamecano, Lacroix, Th\u00e9o Hernandez; Kon\u00e9, Tchouam\u00e9ni; Demb\u00e9l\u00e9, Olise, Dou\u00e9; Mbapp\u00e9<\/p>\n<ul>\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet \u2013\u00a0<a href=\"https:\/\/dicodusport.fr\/blog\/16es-de-finale-coupe-du-monde-2026-toutes-les-affiches-le-programme-et-les-dates\/\">16es de finale Coupe du monde 2026 : toutes les affiches, le programme et les dates<\/a><\/strong><\/li>\n<\/ul>\n<h3 style=\"text-align: justify;\">\u00c0 lire aussi<\/h3>\n<ul>\n<li style=\"text-align: justify;\"><strong><a href=\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-2026-les-criteres-qui-departagent-les-equipes-a-egalite\/\">Coupe du monde 2026 : les crit\u00e8res qui d\u00e9partagent les \u00e9quipes \u00e0 \u00e9galit\u00e9<\/a><\/strong><\/li>\n<li style=\"text-align: justify;\"><strong><a href=\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-2026-quelles-sont-les-nouvelles-regles-mises-en-place-par-la-fifa\/\">Coupe du monde 2026 : quelles sont les nouvelles r\u00e8gles mises en place par la FIFA ?<\/a><\/strong><\/li>\n<li style=\"text-align: justify;\"><strong><a href=\"https:\/\/dicodusport.fr\/blog\/?p=677509\">Coupe du monde 2026 : d\u00e9couvrez la signification et l\u2019origine des surnoms des 48 s\u00e9lections<\/a><\/strong><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>COUPE DU MONDE DE FOOTBALL 2026 &#8211; D\u00e9couvrez les compositions officielles du match du groupe I entre la Norv\u00e8ge et la France.<\/p>\n","protected":false},"author":1,"featured_media":683326,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[47043],"tags":[16878,6966,75,1345],"class_list":["post-682494","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coupe-du-monde-de-football","tag-breve","tag-equipe-de-france-de-football","tag-football","tag-norvege"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Norv\u00e8ge-France : la compo officielle des Bleus<\/title>\n<meta name=\"description\" content=\"COUPE DU MONDE DE FOOTBALL 2026 - D\u00e9couvrez les compositions officielles du match du groupe I entre la Norv\u00e8ge et la France.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/norvege-france-la-compo-probable-des-bleus\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Norv\u00e8ge-France : la compo officielle des Bleus\" \/>\n<meta property=\"og:description\" content=\"COUPE DU MONDE DE FOOTBALL 2026 - D\u00e9couvrez les compositions officielles du match du groupe I entre la Norv\u00e8ge et la France.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/norvege-france-la-compo-probable-des-bleus\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2026-06-26T17:53:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-26T17:54:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/06\/Norvege-France-la-compo-officielle-des-Bleus.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicolas Jacquemard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Nico_Jacquemard\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/norvege-france-la-compo-probable-des-bleus\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/norvege-france-la-compo-probable-des-bleus\\\/\"},\"author\":{\"name\":\"Nicolas Jacquemard\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/55dcb50ad410894e431ed812bbb70191\"},\"headline\":\"Norv\u00e8ge-France : la compo officielle des Bleus\",\"datePublished\":\"2026-06-26T17:53:32+00:00\",\"dateModified\":\"2026-06-26T17:54:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/norvege-france-la-compo-probable-des-bleus\\\/\"},\"wordCount\":352,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/norvege-france-la-compo-probable-des-bleus\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Norvege-France-la-compo-officielle-des-Bleus.png\",\"keywords\":[\"br\u00e8ve\",\"Equipe de France de football\",\"Football\",\"Norv\u00e8ge\"],\"articleSection\":[\"Coupe du monde de football\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/norvege-france-la-compo-probable-des-bleus\\\/#respond\"]}],\"copyrightYear\":\"2026\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/norvege-france-la-compo-probable-des-bleus\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/norvege-france-la-compo-probable-des-bleus\\\/\",\"name\":\"Norv\u00e8ge-France : la compo officielle des Bleus\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/norvege-france-la-compo-probable-des-bleus\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/norvege-france-la-compo-probable-des-bleus\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Norvege-France-la-compo-officielle-des-Bleus.png\",\"datePublished\":\"2026-06-26T17:53:32+00:00\",\"dateModified\":\"2026-06-26T17:54:19+00:00\",\"description\":\"COUPE DU MONDE DE FOOTBALL 2026 - D\u00e9couvrez les compositions officielles du match du groupe I entre la Norv\u00e8ge et la France.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/norvege-france-la-compo-probable-des-bleus\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/norvege-france-la-compo-probable-des-bleus\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/norvege-france-la-compo-probable-des-bleus\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Norvege-France-la-compo-officielle-des-Bleus.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Norvege-France-la-compo-officielle-des-Bleus.png\",\"width\":1200,\"height\":674,\"caption\":\"Norv\u00e8ge-France la compo officielle des Bleus\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/norvege-france-la-compo-probable-des-bleus\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Norv\u00e8ge-France : la compo officielle des Bleus\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/55dcb50ad410894e431ed812bbb70191\",\"name\":\"Nicolas Jacquemard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"caption\":\"Nicolas Jacquemard\"},\"description\":\"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/Nico_Jacquemard\"],\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/dicodusport\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Norv\u00e8ge-France : la compo officielle des Bleus","description":"COUPE DU MONDE DE FOOTBALL 2026 - D\u00e9couvrez les compositions officielles du match du groupe I entre la Norv\u00e8ge et la France.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/norvege-france-la-compo-probable-des-bleus\/","og_locale":"fr_FR","og_type":"article","og_title":"Norv\u00e8ge-France : la compo officielle des Bleus","og_description":"COUPE DU MONDE DE FOOTBALL 2026 - D\u00e9couvrez les compositions officielles du match du groupe I entre la Norv\u00e8ge et la France.","og_url":"https:\/\/dicodusport.fr\/blog\/norvege-france-la-compo-probable-des-bleus\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2026-06-26T17:53:32+00:00","article_modified_time":"2026-06-26T17:54:19+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/06\/Norvege-France-la-compo-officielle-des-Bleus.png","type":"image\/png"}],"author":"Nicolas Jacquemard","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/Nico_Jacquemard","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/norvege-france-la-compo-probable-des-bleus\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/norvege-france-la-compo-probable-des-bleus\/"},"author":{"name":"Nicolas Jacquemard","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191"},"headline":"Norv\u00e8ge-France : la compo officielle des Bleus","datePublished":"2026-06-26T17:53:32+00:00","dateModified":"2026-06-26T17:54:19+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/norvege-france-la-compo-probable-des-bleus\/"},"wordCount":352,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/norvege-france-la-compo-probable-des-bleus\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/06\/Norvege-France-la-compo-officielle-des-Bleus.png","keywords":["br\u00e8ve","Equipe de France de football","Football","Norv\u00e8ge"],"articleSection":["Coupe du monde de football"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/norvege-france-la-compo-probable-des-bleus\/#respond"]}],"copyrightYear":"2026","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/norvege-france-la-compo-probable-des-bleus\/","url":"https:\/\/dicodusport.fr\/blog\/norvege-france-la-compo-probable-des-bleus\/","name":"Norv\u00e8ge-France : la compo officielle des Bleus","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/norvege-france-la-compo-probable-des-bleus\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/norvege-france-la-compo-probable-des-bleus\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/06\/Norvege-France-la-compo-officielle-des-Bleus.png","datePublished":"2026-06-26T17:53:32+00:00","dateModified":"2026-06-26T17:54:19+00:00","description":"COUPE DU MONDE DE FOOTBALL 2026 - D\u00e9couvrez les compositions officielles du match du groupe I entre la Norv\u00e8ge et la France.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/norvege-france-la-compo-probable-des-bleus\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/norvege-france-la-compo-probable-des-bleus\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/norvege-france-la-compo-probable-des-bleus\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/06\/Norvege-France-la-compo-officielle-des-Bleus.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/06\/Norvege-France-la-compo-officielle-des-Bleus.png","width":1200,"height":674,"caption":"Norv\u00e8ge-France la compo officielle des Bleus"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/norvege-france-la-compo-probable-des-bleus\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Norv\u00e8ge-France : la compo officielle des Bleus"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191","name":"Nicolas Jacquemard","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","caption":"Nicolas Jacquemard"},"description":"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.","sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard"],"url":"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/682494","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=682494"}],"version-history":[{"count":5,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/682494\/revisions"}],"predecessor-version":[{"id":683327,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/682494\/revisions\/683327"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/683326"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=682494"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=682494"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=682494"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}