{"id":682672,"date":"2026-06-25T08:30:45","date_gmt":"2026-06-25T06:30:45","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=682672&#038;preview=true&#038;preview_id=682672"},"modified":"2026-06-25T09:35:58","modified_gmt":"2026-06-25T07:35:58","slug":"la-surprise-narcisse-ngoy-seul-francais-selectionne-a-la-draft-nba-2026","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/la-surprise-narcisse-ngoy-seul-francais-selectionne-a-la-draft-nba-2026\/","title":{"rendered":"La surprise Narcisse Ngoy, seul Fran\u00e7ais s\u00e9lectionn\u00e9 \u00e0 la Draft NBA 2026"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>DRAFT NBA 2026 &#8211; S\u00e9lectionn\u00e9 en 57e position par les Hawks, puis envoy\u00e9 aux Clippers, Narcisse Ngoy est le seul Fran\u00e7ais rep\u00each\u00e9 cette ann\u00e9e.<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">Les s\u00e9ries sont faites pour \u00eatre bris\u00e9es. Depuis 2015, la France avait toujours eu au moins un joueur s\u00e9lectionn\u00e9 lors de la <strong>Draft NBA<\/strong>. Mais avec les retraits de <strong>Noa Koukou-Heugue<\/strong> et <strong>Adam Atamna<\/strong>, qui \u00e9taient les deux seuls potentiellement rep\u00eachables, le clan tricolore semblait se diriger vers une ann\u00e9e blanche.<\/p>\n<div class=\"vlp-link-container vlp-layout-article\"><a href=\"https:\/\/dicodusport.fr\/blog\/pille-par-la-ncaa-le-basket-francais-impuissant-face-a-lexode-massif-de-ses-jeunes-talents\/\" class=\"vlp-link\" title=\"Pill\u00e9 par la NCAA, le basket fran\u00e7ais impuissant face \u00e0 l&#039;exode massif de ses jeunes talents\"><\/a><div class=\"vlp-layout-zone-side\"><div class=\"vlp-block-4 vlp-link-image\"><img loading=\"lazy\" decoding=\"async\" style=\"max-width: 792px;\" width=\"792\" height=\"445\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/04\/Pille-par-la-NCAA-le-basket-francais-impuissant-face-a-lexode-massif-de-ces-jeunes-talents.png\" class=\"attachment-800x445 size-800x445\" alt=\"Pill\u00e9 par la NCAA, le basket fran\u00e7ais impuissant face \u00e0 l&#039;exode massif de ses jeunes talents\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/04\/Pille-par-la-NCAA-le-basket-francais-impuissant-face-a-lexode-massif-de-ces-jeunes-talents.png 1200w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/04\/Pille-par-la-NCAA-le-basket-francais-impuissant-face-a-lexode-massif-de-ces-jeunes-talents-300x169.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/04\/Pille-par-la-NCAA-le-basket-francais-impuissant-face-a-lexode-massif-de-ces-jeunes-talents-1024x575.png 1024w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/04\/Pille-par-la-NCAA-le-basket-francais-impuissant-face-a-lexode-massif-de-ces-jeunes-talents-768x431.png 768w\" sizes=\"auto, (max-width: 792px) 100vw, 792px\" \/><\/div><\/div><div class=\"vlp-layout-zone-main\"><div class=\"vlp-block-0 vlp-link-title\">Pill\u00e9 par la NCAA, le basket fran\u00e7ais impuissant face \u00e0 l'exode massif de ses jeunes talents<\/div><div class=\"vlp-block-1 vlp-link-summary\">NCAA \u2013 D\u00e9j\u00e0 massif l\u2019ann\u00e9e derni\u00e8re, l\u2019exil des talents tricolores en NCAA ne fait que s\u2019acc\u00e9l\u00e9rer \u00e0 un rythme affolant.<\/div><div class=\"vlp-block-2 vlp-link-button\">Lire l'article<\/div><div class=\"vlp-block-3 vlp-link-url\">dicodusport.fr<\/div><\/div><\/div>\n<h2 style=\"text-align: justify;\">Narcisse Ngoy dans le giron des Clippers<\/h2>\n<p style=\"text-align: justify;\">N\u00e9anmoins, au bout de la nuit, alors que le <strong>2e tour<\/strong> touchait \u00e0 sa fin, les <strong>Atlanta Hawks<\/strong> ont cr\u00e9\u00e9 la surprise en appelant le nom de <strong>Narcisse Ngoy<\/strong> en <strong>57e position<\/strong>. La surprise \u00e9tait totale puisque le pivot de <strong>Poitiers<\/strong> ne s&rsquo;\u00e9tait pas pr\u00e9sent\u00e9 \u00e0 la Draft et s&rsquo;\u00e9tait d\u00e9j\u00e0 engag\u00e9 en <strong>NCAA<\/strong> avec <strong>Auburn<\/strong> il y a plusieurs semaines. Dans la foul\u00e9e, ses droits ont \u00e9t\u00e9 transf\u00e9r\u00e9s aux <strong>Los Angeles Clippers<\/strong>.<\/p>\n<p style=\"text-align: justify;\">La s\u00e9rie du basket fran\u00e7ais se poursuit donc, m\u00eame si l&rsquo;on ne devrait pas voir Ngoy d\u00e9barquer en Californie d\u00e8s la saison prochaine. Le pivot tricolore peut toutefois d\u00e9sormais nourrir l&rsquo;ambition d&rsquo;\u00e9voluer un jour dans la grande ligue. Avec <strong>9,8 points et 11,6 rebonds de moyenne en Pro B<\/strong> cette saison, il a franchi un cap inattendu au fil des mois. D\u00e9sormais dans le giron d&rsquo;une franchise NBA, il va tenter de poursuivre sa progression sur les parquets universitaires am\u00e9ricains.<\/p>\n<p style=\"text-align: justify;\">Dans les faits, le chemin reste encore long, et les joueurs fran\u00e7ais rep\u00each\u00e9s en fin de <strong>2e tour<\/strong> ont rarement r\u00e9ussi \u00e0 s&rsquo;installer durablement en NBA. \u00c0 <strong>22 ans<\/strong>, cette s\u00e9lection repr\u00e9sente n\u00e9anmoins une belle r\u00e9compense pour les progr\u00e8s accomplis ces derniers mois.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"en\">With the 57th pick of the NBA Draft the <a href=\"https:\/\/x.com\/ATLHawks?ref_src=twsrc%5Etfw\">@ATLHawks<\/a> select Narcisse Ngoy!<\/p>\n<p>The 2026 NBA Draft is LIVE on ESPN. <a href=\"https:\/\/t.co\/jvVoB2P8O1\">pic.twitter.com\/jvVoB2P8O1<\/a><\/p>\n<p>\u2014 NBA (@NBA) <a href=\"https:\/\/x.com\/NBA\/status\/2069971187547988308?ref_src=twsrc%5Etfw\">June 25, 2026<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.x.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<div id=\"gtx-trans\" style=\"position: absolute; left: -14px; top: 40.9091px;\">\n<div class=\"gtx-trans-icon\"><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>DRAFT NBA 2026 &#8211; S\u00e9lectionn\u00e9 en 57\u00e8me position par les Hawks, puis envoy\u00e9 aux Clippers, Narcisse Ngoy a \u00e9t\u00e9 le seul fran\u00e7ais rep\u00each\u00e9 cette ann\u00e9e.<\/p>\n","protected":false},"author":55,"featured_media":682673,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[10533],"tags":[16878,12557,12826,179],"class_list":["post-682672","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nba","tag-breve","tag-draft-nba","tag-francais-nba","tag-nba"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>La surprise Narcisse Ngoy, seul Fran\u00e7ais s\u00e9lectionn\u00e9 \u00e0 la Draft NBA 2026<\/title>\n<meta name=\"description\" content=\"DRAFT NBA 2026 - S\u00e9lectionn\u00e9 en 57\u00e8me position par les Hawks, puis envoy\u00e9 aux Clippers, Narcisse Ngoy a \u00e9t\u00e9 le seul fran\u00e7ais rep\u00each\u00e9 cette ann\u00e9e.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/la-surprise-narcisse-ngoy-seul-francais-selectionne-a-la-draft-nba-2026\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La surprise Narcisse Ngoy, seul Fran\u00e7ais s\u00e9lectionn\u00e9 \u00e0 la Draft NBA 2026\" \/>\n<meta property=\"og:description\" content=\"DRAFT NBA 2026 - S\u00e9lectionn\u00e9 en 57\u00e8me position par les Hawks, puis envoy\u00e9 aux Clippers, Narcisse Ngoy a \u00e9t\u00e9 le seul fran\u00e7ais rep\u00each\u00e9 cette ann\u00e9e.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/la-surprise-narcisse-ngoy-seul-francais-selectionne-a-la-draft-nba-2026\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2026-06-25T06:30:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-25T07:35:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/06\/La-surprise-Narcisse-Ngoy-seul-Francais-selectionne-a-la-Draft-NBA-2026.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Maxime Cazenave\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"La surprise Narcisse Ngoy, seul Fran\u00e7ais s\u00e9lectionn\u00e9 \u00e0 la Draft NBA 2026\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Maxime_Caze\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/la-surprise-narcisse-ngoy-seul-francais-selectionne-a-la-draft-nba-2026\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/la-surprise-narcisse-ngoy-seul-francais-selectionne-a-la-draft-nba-2026\\\/\"},\"author\":{\"name\":\"Maxime Cazenave\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/37def232098a7a5cbab3974a3690abb0\"},\"headline\":\"La surprise Narcisse Ngoy, seul Fran\u00e7ais s\u00e9lectionn\u00e9 \u00e0 la Draft NBA 2026\",\"datePublished\":\"2026-06-25T06:30:45+00:00\",\"dateModified\":\"2026-06-25T07:35:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/la-surprise-narcisse-ngoy-seul-francais-selectionne-a-la-draft-nba-2026\\\/\"},\"wordCount\":447,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/la-surprise-narcisse-ngoy-seul-francais-selectionne-a-la-draft-nba-2026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/La-surprise-Narcisse-Ngoy-seul-Francais-selectionne-a-la-Draft-NBA-2026.png\",\"keywords\":[\"br\u00e8ve\",\"Draft NBA\",\"Fran\u00e7ais NBA\",\"NBA\"],\"articleSection\":[\"NBA\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/la-surprise-narcisse-ngoy-seul-francais-selectionne-a-la-draft-nba-2026\\\/#respond\"]}],\"copyrightYear\":\"2026\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/la-surprise-narcisse-ngoy-seul-francais-selectionne-a-la-draft-nba-2026\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/la-surprise-narcisse-ngoy-seul-francais-selectionne-a-la-draft-nba-2026\\\/\",\"name\":\"La surprise Narcisse Ngoy, seul Fran\u00e7ais s\u00e9lectionn\u00e9 \u00e0 la Draft NBA 2026\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/la-surprise-narcisse-ngoy-seul-francais-selectionne-a-la-draft-nba-2026\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/la-surprise-narcisse-ngoy-seul-francais-selectionne-a-la-draft-nba-2026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/La-surprise-Narcisse-Ngoy-seul-Francais-selectionne-a-la-Draft-NBA-2026.png\",\"datePublished\":\"2026-06-25T06:30:45+00:00\",\"dateModified\":\"2026-06-25T07:35:58+00:00\",\"description\":\"DRAFT NBA 2026 - S\u00e9lectionn\u00e9 en 57\u00e8me position par les Hawks, puis envoy\u00e9 aux Clippers, Narcisse Ngoy a \u00e9t\u00e9 le seul fran\u00e7ais rep\u00each\u00e9 cette ann\u00e9e.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/la-surprise-narcisse-ngoy-seul-francais-selectionne-a-la-draft-nba-2026\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/la-surprise-narcisse-ngoy-seul-francais-selectionne-a-la-draft-nba-2026\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/la-surprise-narcisse-ngoy-seul-francais-selectionne-a-la-draft-nba-2026\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/La-surprise-Narcisse-Ngoy-seul-Francais-selectionne-a-la-Draft-NBA-2026.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/La-surprise-Narcisse-Ngoy-seul-Francais-selectionne-a-la-Draft-NBA-2026.png\",\"width\":1200,\"height\":674,\"caption\":\"La surprise Narcisse Ngoy, seul Fran\u00e7ais s\u00e9lectionn\u00e9 \u00e0 la Draft NBA 2026\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/la-surprise-narcisse-ngoy-seul-francais-selectionne-a-la-draft-nba-2026\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La surprise Narcisse Ngoy, seul Fran\u00e7ais s\u00e9lectionn\u00e9 \u00e0 la Draft NBA 2026\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/37def232098a7a5cbab3974a3690abb0\",\"name\":\"Maxime Cazenave\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Maxime-Cazenave-150x150.jpg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Maxime-Cazenave-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Maxime-Cazenave-150x150.jpg\",\"caption\":\"Maxime Cazenave\"},\"description\":\"Journaliste\\\/R\u00e9dacteur depuis 2012 - Berc\u00e9 par l\u2019amour des Girondins de Bordeaux, les \u00e9checs de Christophe Moreau sur le Tour de France sous l'\u00e8re Lance Armstrong et le fade-away l\u00e9tal de Dirk Nowitzki, ma passion d\u00e9vorante pour le sport a toujours \u00e9t\u00e9 un pan incontournable de ma vie. Transmettre ma passion \u00e0 l\u2019\u00e9crit a \u00e9t\u00e9 une transition naturelle. Suiveur assidu de basket et de hockey sur glace, je garde toujours un peu de place pour suivre le cyclisme, le football et le maximum de performances fran\u00e7aises.\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/Maxime_Caze\"],\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/maximec\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"La surprise Narcisse Ngoy, seul Fran\u00e7ais s\u00e9lectionn\u00e9 \u00e0 la Draft NBA 2026","description":"DRAFT NBA 2026 - S\u00e9lectionn\u00e9 en 57\u00e8me position par les Hawks, puis envoy\u00e9 aux Clippers, Narcisse Ngoy a \u00e9t\u00e9 le seul fran\u00e7ais rep\u00each\u00e9 cette ann\u00e9e.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/la-surprise-narcisse-ngoy-seul-francais-selectionne-a-la-draft-nba-2026\/","og_locale":"fr_FR","og_type":"article","og_title":"La surprise Narcisse Ngoy, seul Fran\u00e7ais s\u00e9lectionn\u00e9 \u00e0 la Draft NBA 2026","og_description":"DRAFT NBA 2026 - S\u00e9lectionn\u00e9 en 57\u00e8me position par les Hawks, puis envoy\u00e9 aux Clippers, Narcisse Ngoy a \u00e9t\u00e9 le seul fran\u00e7ais rep\u00each\u00e9 cette ann\u00e9e.","og_url":"https:\/\/dicodusport.fr\/blog\/la-surprise-narcisse-ngoy-seul-francais-selectionne-a-la-draft-nba-2026\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2026-06-25T06:30:45+00:00","article_modified_time":"2026-06-25T07:35:58+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/06\/La-surprise-Narcisse-Ngoy-seul-Francais-selectionne-a-la-Draft-NBA-2026.png","type":"image\/png"}],"author":"Maxime Cazenave","twitter_card":"summary_large_image","twitter_title":"La surprise Narcisse Ngoy, seul Fran\u00e7ais s\u00e9lectionn\u00e9 \u00e0 la Draft NBA 2026","twitter_creator":"@https:\/\/twitter.com\/Maxime_Caze","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/la-surprise-narcisse-ngoy-seul-francais-selectionne-a-la-draft-nba-2026\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/la-surprise-narcisse-ngoy-seul-francais-selectionne-a-la-draft-nba-2026\/"},"author":{"name":"Maxime Cazenave","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0"},"headline":"La surprise Narcisse Ngoy, seul Fran\u00e7ais s\u00e9lectionn\u00e9 \u00e0 la Draft NBA 2026","datePublished":"2026-06-25T06:30:45+00:00","dateModified":"2026-06-25T07:35:58+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/la-surprise-narcisse-ngoy-seul-francais-selectionne-a-la-draft-nba-2026\/"},"wordCount":447,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/la-surprise-narcisse-ngoy-seul-francais-selectionne-a-la-draft-nba-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/06\/La-surprise-Narcisse-Ngoy-seul-Francais-selectionne-a-la-Draft-NBA-2026.png","keywords":["br\u00e8ve","Draft NBA","Fran\u00e7ais NBA","NBA"],"articleSection":["NBA"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/la-surprise-narcisse-ngoy-seul-francais-selectionne-a-la-draft-nba-2026\/#respond"]}],"copyrightYear":"2026","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/la-surprise-narcisse-ngoy-seul-francais-selectionne-a-la-draft-nba-2026\/","url":"https:\/\/dicodusport.fr\/blog\/la-surprise-narcisse-ngoy-seul-francais-selectionne-a-la-draft-nba-2026\/","name":"La surprise Narcisse Ngoy, seul Fran\u00e7ais s\u00e9lectionn\u00e9 \u00e0 la Draft NBA 2026","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/la-surprise-narcisse-ngoy-seul-francais-selectionne-a-la-draft-nba-2026\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/la-surprise-narcisse-ngoy-seul-francais-selectionne-a-la-draft-nba-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/06\/La-surprise-Narcisse-Ngoy-seul-Francais-selectionne-a-la-Draft-NBA-2026.png","datePublished":"2026-06-25T06:30:45+00:00","dateModified":"2026-06-25T07:35:58+00:00","description":"DRAFT NBA 2026 - S\u00e9lectionn\u00e9 en 57\u00e8me position par les Hawks, puis envoy\u00e9 aux Clippers, Narcisse Ngoy a \u00e9t\u00e9 le seul fran\u00e7ais rep\u00each\u00e9 cette ann\u00e9e.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/la-surprise-narcisse-ngoy-seul-francais-selectionne-a-la-draft-nba-2026\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/la-surprise-narcisse-ngoy-seul-francais-selectionne-a-la-draft-nba-2026\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/la-surprise-narcisse-ngoy-seul-francais-selectionne-a-la-draft-nba-2026\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/06\/La-surprise-Narcisse-Ngoy-seul-Francais-selectionne-a-la-Draft-NBA-2026.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/06\/La-surprise-Narcisse-Ngoy-seul-Francais-selectionne-a-la-Draft-NBA-2026.png","width":1200,"height":674,"caption":"La surprise Narcisse Ngoy, seul Fran\u00e7ais s\u00e9lectionn\u00e9 \u00e0 la Draft NBA 2026"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/la-surprise-narcisse-ngoy-seul-francais-selectionne-a-la-draft-nba-2026\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"La surprise Narcisse Ngoy, seul Fran\u00e7ais s\u00e9lectionn\u00e9 \u00e0 la Draft NBA 2026"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0","name":"Maxime Cazenave","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg","caption":"Maxime Cazenave"},"description":"Journaliste\/R\u00e9dacteur depuis 2012 - Berc\u00e9 par l\u2019amour des Girondins de Bordeaux, les \u00e9checs de Christophe Moreau sur le Tour de France sous l'\u00e8re Lance Armstrong et le fade-away l\u00e9tal de Dirk Nowitzki, ma passion d\u00e9vorante pour le sport a toujours \u00e9t\u00e9 un pan incontournable de ma vie. Transmettre ma passion \u00e0 l\u2019\u00e9crit a \u00e9t\u00e9 une transition naturelle. Suiveur assidu de basket et de hockey sur glace, je garde toujours un peu de place pour suivre le cyclisme, le football et le maximum de performances fran\u00e7aises.","sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/Maxime_Caze"],"url":"https:\/\/dicodusport.fr\/blog\/author\/maximec\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/682672","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=682672"}],"version-history":[{"count":2,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/682672\/revisions"}],"predecessor-version":[{"id":682701,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/682672\/revisions\/682701"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/682673"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=682672"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=682672"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=682672"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}