{"id":68831,"date":"2020-06-13T15:08:04","date_gmt":"2020-06-13T13:08:04","guid":{"rendered":"http:\/\/dicodusport.fr\/blog\/?p=68831&#038;preview=true&#038;preview_id=68831"},"modified":"2021-05-11T17:03:16","modified_gmt":"2021-05-11T15:03:16","slug":"nrl-pronostic-pour-st-george-illawarra-dragons-cronulla-sharks","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/nrl-pronostic-pour-st-george-illawarra-dragons-cronulla-sharks\/","title":{"rendered":"NRL : notre pronostic pour St George Illawarra Dragons &#8211; Cronulla Sharks"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><b><a href=\"https:\/\/treizemondial.fr\/calendrier-resultats-nrl\/\" target=\"_blank\" rel=\"noopener noreferrer\">NRL<\/a> &#8211; Pour le compte de la 5\u00e8me journ\u00e9e, les Dragons de St George re\u00e7oivent les Sharks de Cronulla. Notre pronostic.<\/b><\/em><\/p>\n<h2 style=\"text-align: justify;\"><span style=\"font-family: -apple-system, BlinkMacSystemFont, 'Segoe UI', Roboto, Oxygen-Sans, Ubuntu, Cantarell, 'Helvetica Neue', sans-serif;\">St George Illawarra Dragons &#8211; Cronulla Sharks : Samedi 13 juin, 11h35<\/span><\/h2>\n<p style=\"text-align: justify;\">Les Dragons peuvent-ils tomber plus bas ? Pas s\u00fbr, tant leurs deux premi\u00e8res performances depuis la reprise ont \u00e9t\u00e9 catastrophiques avec seulement deux points marqu\u00e9s contre des \u00e9quipes qui ne joueront pourtant pas la qualification. Malgr\u00e9 tout, l&rsquo;entra\u00eeneur reste en place et devra composer avec de nouveaux absents, Brayden Wiliame, l&rsquo;ancien Dragons Catalans, et Korbin Sims.<\/p>\n<p style=\"text-align: justify;\">En face, les Sharks restent sur un succ\u00e8s face aux Cowboys malgr\u00e9 une prestation moyenne. Si Andrew Fifita est de retour et fera du bien devant, Matt Moylan ne pourra lui tenir sa place \u00e0 l&rsquo;arri\u00e8re. M\u00eame s&rsquo;ils ne peuvent pas creuser plus, les Dragons semblent partir de trop loin pour renouer avec un succ\u00e8s. <strong>On part sur une victoire des Sharks.<\/strong><\/p>\n<table style=\"width: 100%;\">\n<tbody>\n<tr style=\"height: 16px;\">\n<td style=\"background-color: #404040; width: 70%; text-align: left; border-color: #ededed;\"><span style=\"font-size: 12px; color: #ffffff;\">Dimanche 14 juin, 10h30<br \/>\n<\/span><\/td>\n<td style=\"background-color: #525252; width: 10%; border-color: #ededed; text-align: center;\"><span style=\"font-size: 12px; color: #ffffff;\">1<\/span><\/td>\n<td style=\"background-color: #525252; width: 10%; border-color: #ededed; text-align: center;\"><span style=\"font-size: 12px; color: #ffffff;\">N<\/span><\/td>\n<td style=\"background-color: #525252; width: 10%; border-color: #ededed; text-align: center;\"><span style=\"font-size: 12px; color: #ffffff;\">2<\/span><\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"background-color: #ffffff; text-align: justify; border-color: #ededed; vertical-align: middle;\"><strong>St George Illawarra Dragons &#8211; Cronulla Sharks<br \/>\n<\/strong><\/td>\n<td style=\"background-color: #ffffff; border-color: #ededed; vertical-align: middle; text-align: center;\"><span style=\"font-size: 10px;\"><a href=\"https:\/\/www.winamax.fr\/paris-sportifs\/match\/prelive\/22085575?banid=33423\" class=\"su-button su-button-style-flat\" style=\"color:#FFFFFF;background-color:#b10e12;border-color:#8e0c0f;border-radius:5px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#FFFFFF;padding:0px 16px;font-size:13px;line-height:26px;border-color:#c9575a;border-radius:5px;text-shadow:none\"> 2.80<\/span><\/a><\/span><\/td>\n<td style=\"background-color: #ffffff; border-color: #ededed; vertical-align: middle; text-align: center;\"><span style=\"font-size: 10px;\"><a href=\"https:\/\/www.winamax.fr\/paris-sportifs\/match\/prelive\/22085575?banid=33423\" class=\"su-button su-button-style-flat\" style=\"color:#FFFFFF;background-color:#b10e12;border-color:#8e0c0f;border-radius:5px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#FFFFFF;padding:0px 16px;font-size:13px;line-height:26px;border-color:#c9575a;border-radius:5px;text-shadow:none\"> 25<\/span><\/a><\/span><\/td>\n<td style=\"background-color: #ffffff; border-color: #ededed; vertical-align: middle; text-align: center;\"><span style=\"font-size: 10px;\"><a href=\"https:\/\/www.winamax.fr\/paris-sportifs\/match\/prelive\/22085575?banid=33423\" class=\"su-button su-button-style-flat\" style=\"color:#FFFFFF;background-color:#0057ae;border-color:#00468c;border-radius:5px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#FFFFFF;padding:0px 16px;font-size:13px;line-height:26px;border-color:#4d8ac7;border-radius:5px;text-shadow:none\"> 1.48<\/span><\/a><\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p style=\"text-align: justify;\"><span style=\"font-family: -apple-system, BlinkMacSystemFont, 'Segoe UI', Roboto, Oxygen-Sans, Ubuntu, Cantarell, 'Helvetica Neue', sans-serif; font-size: 16px;\">Tentez votre chance en misant jusqu\u2019\u00e0 100\u20ac gr\u00e2ce \u00e0 votre\u00a0<\/span><a style=\"font-family: -apple-system, BlinkMacSystemFont, 'Segoe UI', Roboto, Oxygen-Sans, Ubuntu, Cantarell, 'Helvetica Neue', sans-serif; font-size: 16px;\" href=\"https:\/\/www.winamax.fr\/landing\/landing_leads.php?ldg=1er-pari-rembourse&amp;banid=33423\" target=\"_blank\" rel=\"noopener noreferrer\">premier pari rembours\u00e9<\/a><span style=\"font-family: -apple-system, BlinkMacSystemFont, 'Segoe UI', Roboto, Oxygen-Sans, Ubuntu, Cantarell, 'Helvetica Neue', sans-serif; font-size: 16px;\">.<\/span><\/p>\n<ul style=\"text-align: justify;\">\n<li style=\"text-align: justify;\"><strong>\u00c0 lire aussi &#8211; <a href=\"https:\/\/treizemondial.fr\/nos-pronostics-pour-la-5eme-journee-de-nrl-2020\/\" target=\"_blank\" rel=\"noopener noreferrer\">NRL &#8211; 5\u00e8me round : les pronostics de Treize Mondial<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\"><strong><em>Dicodusport<br \/>\n<a href=\"https:\/\/www.facebook.com\/dicodusport\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2909\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-facebook-150x150.png\" sizes=\"auto, (max-width: 40px) 100vw, 40px\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-facebook-150x150.png 150w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-facebook-300x300.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-facebook.png 400w\" alt=\"\" width=\"40\" height=\"40\" \/><\/a><a href=\"https:\/\/twitter.com\/dicodusport\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2908\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-twitter-150x150.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>NRL &#8211; Pour le compte de la 5\u00e8me journ\u00e9e, les Dragons de St George re\u00e7oivent les Sharks de Cronulla. Notre pronostic.<\/p>\n","protected":false},"author":1,"featured_media":68834,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[9128],"tags":[5690,4146,2978],"class_list":["post-68831","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rugby-a-xiii","tag-dragons","tag-nrl","tag-sharks"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>NRL : notre pronostic pour St George Illawarra Dragons - Cronulla Sharks - Dicodusport<\/title>\n<meta name=\"description\" content=\"PRONOSTICS NRL - Pour le compte de la 5\u00e8me journ\u00e9e, les Dragons de St George re\u00e7oivent les Sharks de Cronulla. Notre prono.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/nrl-pronostic-pour-st-george-illawarra-dragons-cronulla-sharks\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"NRL : notre pronostic pour St George Illawarra Dragons - Cronulla Sharks\" \/>\n<meta property=\"og:description\" content=\"PRONOSTICS NRL - Pour le compte de la 5\u00e8me journ\u00e9e, les Dragons de St George re\u00e7oivent les Sharks de Cronulla. Notre prono.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/nrl-pronostic-pour-st-george-illawarra-dragons-cronulla-sharks\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-13T13:08:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-05-11T15:03:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/NRL-notre-pronostic-pour-Dragons-Sharks.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"670\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicolas Jacquemard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"NRL : notre pronostic pour St George Illawarra Dragons - Cronulla Sharks\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Nico_Jacquemard\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/nrl-pronostic-pour-st-george-illawarra-dragons-cronulla-sharks\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/nrl-pronostic-pour-st-george-illawarra-dragons-cronulla-sharks\\\/\"},\"author\":{\"name\":\"Nicolas Jacquemard\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/55dcb50ad410894e431ed812bbb70191\"},\"headline\":\"NRL : notre pronostic pour St George Illawarra Dragons &#8211; Cronulla Sharks\",\"datePublished\":\"2020-06-13T13:08:04+00:00\",\"dateModified\":\"2021-05-11T15:03:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/nrl-pronostic-pour-st-george-illawarra-dragons-cronulla-sharks\\\/\"},\"wordCount\":273,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/nrl-pronostic-pour-st-george-illawarra-dragons-cronulla-sharks\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/NRL-notre-pronostic-pour-Dragons-Sharks.png\",\"keywords\":[\"Dragons\",\"NRL\",\"sharks\"],\"articleSection\":[\"Rugby \u00e0 XIII\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/nrl-pronostic-pour-st-george-illawarra-dragons-cronulla-sharks\\\/#respond\"]}],\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/nrl-pronostic-pour-st-george-illawarra-dragons-cronulla-sharks\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/nrl-pronostic-pour-st-george-illawarra-dragons-cronulla-sharks\\\/\",\"name\":\"NRL : notre pronostic pour St George Illawarra Dragons - Cronulla Sharks - Dicodusport\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/nrl-pronostic-pour-st-george-illawarra-dragons-cronulla-sharks\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/nrl-pronostic-pour-st-george-illawarra-dragons-cronulla-sharks\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/NRL-notre-pronostic-pour-Dragons-Sharks.png\",\"datePublished\":\"2020-06-13T13:08:04+00:00\",\"dateModified\":\"2021-05-11T15:03:16+00:00\",\"description\":\"PRONOSTICS NRL - Pour le compte de la 5\u00e8me journ\u00e9e, les Dragons de St George re\u00e7oivent les Sharks de Cronulla. Notre prono.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/nrl-pronostic-pour-st-george-illawarra-dragons-cronulla-sharks\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/nrl-pronostic-pour-st-george-illawarra-dragons-cronulla-sharks\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/nrl-pronostic-pour-st-george-illawarra-dragons-cronulla-sharks\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/NRL-notre-pronostic-pour-Dragons-Sharks.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/NRL-notre-pronostic-pour-Dragons-Sharks.png\",\"width\":1200,\"height\":670,\"caption\":\"NRL : notre pronostic pour St George Illawarra Dragons - Cronulla Sharks\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/nrl-pronostic-pour-st-george-illawarra-dragons-cronulla-sharks\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"NRL : notre pronostic pour St George Illawarra Dragons &#8211; Cronulla Sharks\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/55dcb50ad410894e431ed812bbb70191\",\"name\":\"Nicolas Jacquemard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"caption\":\"Nicolas Jacquemard\"},\"description\":\"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/Nico_Jacquemard\"],\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/dicodusport\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"NRL : notre pronostic pour St George Illawarra Dragons - Cronulla Sharks - Dicodusport","description":"PRONOSTICS NRL - Pour le compte de la 5\u00e8me journ\u00e9e, les Dragons de St George re\u00e7oivent les Sharks de Cronulla. Notre prono.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/nrl-pronostic-pour-st-george-illawarra-dragons-cronulla-sharks\/","og_locale":"fr_FR","og_type":"article","og_title":"NRL : notre pronostic pour St George Illawarra Dragons - Cronulla Sharks","og_description":"PRONOSTICS NRL - Pour le compte de la 5\u00e8me journ\u00e9e, les Dragons de St George re\u00e7oivent les Sharks de Cronulla. Notre prono.","og_url":"https:\/\/dicodusport.fr\/blog\/nrl-pronostic-pour-st-george-illawarra-dragons-cronulla-sharks\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2020-06-13T13:08:04+00:00","article_modified_time":"2021-05-11T15:03:16+00:00","og_image":[{"width":1200,"height":670,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/NRL-notre-pronostic-pour-Dragons-Sharks.png","type":"image\/png"}],"author":"Nicolas Jacquemard","twitter_card":"summary_large_image","twitter_title":"NRL : notre pronostic pour St George Illawarra Dragons - Cronulla Sharks","twitter_creator":"@https:\/\/twitter.com\/Nico_Jacquemard","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/nrl-pronostic-pour-st-george-illawarra-dragons-cronulla-sharks\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/nrl-pronostic-pour-st-george-illawarra-dragons-cronulla-sharks\/"},"author":{"name":"Nicolas Jacquemard","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191"},"headline":"NRL : notre pronostic pour St George Illawarra Dragons &#8211; Cronulla Sharks","datePublished":"2020-06-13T13:08:04+00:00","dateModified":"2021-05-11T15:03:16+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/nrl-pronostic-pour-st-george-illawarra-dragons-cronulla-sharks\/"},"wordCount":273,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/nrl-pronostic-pour-st-george-illawarra-dragons-cronulla-sharks\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/NRL-notre-pronostic-pour-Dragons-Sharks.png","keywords":["Dragons","NRL","sharks"],"articleSection":["Rugby \u00e0 XIII"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/nrl-pronostic-pour-st-george-illawarra-dragons-cronulla-sharks\/#respond"]}],"copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/nrl-pronostic-pour-st-george-illawarra-dragons-cronulla-sharks\/","url":"https:\/\/dicodusport.fr\/blog\/nrl-pronostic-pour-st-george-illawarra-dragons-cronulla-sharks\/","name":"NRL : notre pronostic pour St George Illawarra Dragons - Cronulla Sharks - Dicodusport","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/nrl-pronostic-pour-st-george-illawarra-dragons-cronulla-sharks\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/nrl-pronostic-pour-st-george-illawarra-dragons-cronulla-sharks\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/NRL-notre-pronostic-pour-Dragons-Sharks.png","datePublished":"2020-06-13T13:08:04+00:00","dateModified":"2021-05-11T15:03:16+00:00","description":"PRONOSTICS NRL - Pour le compte de la 5\u00e8me journ\u00e9e, les Dragons de St George re\u00e7oivent les Sharks de Cronulla. Notre prono.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/nrl-pronostic-pour-st-george-illawarra-dragons-cronulla-sharks\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/nrl-pronostic-pour-st-george-illawarra-dragons-cronulla-sharks\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/nrl-pronostic-pour-st-george-illawarra-dragons-cronulla-sharks\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/NRL-notre-pronostic-pour-Dragons-Sharks.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/NRL-notre-pronostic-pour-Dragons-Sharks.png","width":1200,"height":670,"caption":"NRL : notre pronostic pour St George Illawarra Dragons - Cronulla Sharks"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/nrl-pronostic-pour-st-george-illawarra-dragons-cronulla-sharks\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"NRL : notre pronostic pour St George Illawarra Dragons &#8211; Cronulla Sharks"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191","name":"Nicolas Jacquemard","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","caption":"Nicolas Jacquemard"},"description":"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.","sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard"],"url":"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/68831","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=68831"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/68831\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/68834"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=68831"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=68831"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=68831"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}