{"id":688562,"date":"2026-07-15T13:59:02","date_gmt":"2026-07-15T11:59:02","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=688562&#038;preview=true&#038;preview_id=688562"},"modified":"2026-07-15T13:59:02","modified_gmt":"2026-07-15T11:59:02","slug":"les-bleuets-du-volley-dominent-la-belgique-et-seront-au-rendez-vous-des-demi-finales-de-leuro-u18","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/les-bleuets-du-volley-dominent-la-belgique-et-seront-au-rendez-vous-des-demi-finales-de-leuro-u18\/","title":{"rendered":"Les Bleuets du volley dominent la Belgique et seront au rendez-vous des demi-finales de l&rsquo;Euro U18"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>EURO U18 MASCULIN DE VOLLEYBALL 2026 &#8211; Les Bleus ont termin\u00e9 le travail contre la Belgique, et peuvent maintenant se projeter vers le carr\u00e9 final.<\/em><\/strong><\/p>\n<ul style=\"text-align: justify;\">\n<li><strong>\u00c0 ce sujet &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/calendrier-et-resultats-championnat-deurope-masculin-de-volley-ball-u18-2026\/\">Calendrier et r\u00e9sultats Championnat d\u2019Europe masculin de volley-ball U18 2026<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">La bonne nouvelle \u00e9tait tomb\u00e9e hier soir : \u00e0 la fin de l&rsquo;avant-derni\u00e8re journ\u00e9e de la phase de poules, <strong>l&rsquo;\u00e9quipe de France U18 gar\u00e7ons de volleyball<\/strong> \u00e9tait certaine de voir le dernier carr\u00e9 de son championnat d&rsquo;Europe. Restait un dernier match contre la Belgique, histoire de r\u00e9p\u00e9ter les gammes, et surtout de mettre la pression sur la Bulgarie pour d\u00e9crocher la premi\u00e8re place du groupe.<\/p>\n<ul style=\"text-align: justify;\">\n<li><strong>\u00c0 ce sujet &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/les-bleuets-du-volley-dominent-la-roumanie-et-se-rapprochent-des-demi-finales-de-leuro-u18\/\">Les Bleuets du volley dominent la Roumanie et se rapprochent des demi-finales de l\u2019Euro U18<\/a><\/strong><\/li>\n<\/ul>\n<h2 style=\"text-align: justify;\">\u00c0 deux matchs de l&rsquo;or<\/h2>\n<p style=\"text-align: justify;\">L&rsquo;occasion de faire tourner, et notamment de mettre \u00e0 l&rsquo;\u00e9preuve <strong>Lilian Julien<\/strong> et<strong> Yanis Marion<\/strong>, pas toujours tr\u00e8s utilis\u00e9s depuis le d\u00e9but de la comp\u00e9tition, mais qui ont r\u00e9pondu pr\u00e9sent, surtout le deuxi\u00e8me avec ses 15 points. Mais surtout, le block fran\u00e7ais a fait \u00e9talage de sa force, venant sanctionner une prestation globalement solide, a fortiori dans les deux premiers sets.<\/p>\n<p style=\"text-align: justify;\">Dans le troisi\u00e8me, en revanche, les Bleuets ont d\u00fb cravacher. Mis sous pression, ils ont sauv\u00e9 pas moins de trois balles de set pour an\u00e9antir le baroud d&rsquo;honneur des Belges, qui allaient quoi qu&rsquo;il arriver quitter la comp\u00e9tition, ne pouvant plus passer en demi-finale. Une mission r\u00e9ussie sous l&rsquo;\u00e9gide du duo <strong>Antonin Bonnard &#8211; Jaden Ebagne Yon<\/strong>, et une victoire <strong>25-21, 25-19, 29-27<\/strong>. Ce sera la Pologne, l&rsquo;Italie ou la Slov\u00e9nie en demi-finales, quoi qu&rsquo;il arrive un choc donc, mais une belle occasion de prouver que l&rsquo;\u00e9quipe de France peut d\u00e9fendre son titre !<\/p>\n","protected":false},"excerpt":{"rendered":"<p>EURO U18 MASCULIN DE VOLLEYBALL 2026 &#8211; Les Bleus ont termin\u00e9 le travail contre la Belgique, et peuvent maintenant se projeter vers le carr\u00e9 final.<\/p>\n","protected":false},"author":59,"featured_media":688569,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[8369],"tags":[16878,24835],"class_list":["post-688562","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-volley-ball","tag-breve","tag-championnat-deurope-masculin-de-volley-ball-u18"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Les Bleuets du volley dominent la Belgique et seront au rendez-vous des demi-finales de l&#039;Euro U18<\/title>\n<meta name=\"description\" content=\"EURO U18 MASCULIN DE VOLLEYBALL 2026 - Les Bleus ont termin\u00e9 le travail contre la Belgique, et peuvent maintenant se projeter vers le carr\u00e9 final.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/les-bleuets-du-volley-dominent-la-belgique-et-seront-au-rendez-vous-des-demi-finales-de-leuro-u18\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les Bleuets du volley dominent la Belgique et seront au rendez-vous des demi-finales de l&#039;Euro U18\" \/>\n<meta property=\"og:description\" content=\"EURO U18 MASCULIN DE VOLLEYBALL 2026 - Les Bleus ont termin\u00e9 le travail contre la Belgique, et peuvent maintenant se projeter vers le carr\u00e9 final.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/les-bleuets-du-volley-dominent-la-belgique-et-seront-au-rendez-vous-des-demi-finales-de-leuro-u18\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/sebastien.gente\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-15T11:59:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/07\/Les-Bleuets-du-volley-dominent-la-Belgique-et-seront-au-rendez-vous-des-demi-finales-de-lEuro-U18.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"S\u00e9bastien Gente\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Les Bleuets du volley dominent la Belgique et seront au rendez-vous des demi-finales de l&#039;Euro U18\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/globulo24\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-bleuets-du-volley-dominent-la-belgique-et-seront-au-rendez-vous-des-demi-finales-de-leuro-u18\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-bleuets-du-volley-dominent-la-belgique-et-seront-au-rendez-vous-des-demi-finales-de-leuro-u18\\\/\"},\"author\":{\"name\":\"S\u00e9bastien Gente\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/627966a6cde45dbd8c5e36ac85d783da\"},\"headline\":\"Les Bleuets du volley dominent la Belgique et seront au rendez-vous des demi-finales de l&rsquo;Euro U18\",\"datePublished\":\"2026-07-15T11:59:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-bleuets-du-volley-dominent-la-belgique-et-seront-au-rendez-vous-des-demi-finales-de-leuro-u18\\\/\"},\"wordCount\":327,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-bleuets-du-volley-dominent-la-belgique-et-seront-au-rendez-vous-des-demi-finales-de-leuro-u18\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/Les-Bleuets-du-volley-dominent-la-Belgique-et-seront-au-rendez-vous-des-demi-finales-de-lEuro-U18.png\",\"keywords\":[\"br\u00e8ve\",\"Championnat d'Europe masculin de volley-ball U18\"],\"articleSection\":[\"Volley-Ball\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-bleuets-du-volley-dominent-la-belgique-et-seront-au-rendez-vous-des-demi-finales-de-leuro-u18\\\/#respond\"]}],\"copyrightYear\":\"2026\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-bleuets-du-volley-dominent-la-belgique-et-seront-au-rendez-vous-des-demi-finales-de-leuro-u18\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-bleuets-du-volley-dominent-la-belgique-et-seront-au-rendez-vous-des-demi-finales-de-leuro-u18\\\/\",\"name\":\"Les Bleuets du volley dominent la Belgique et seront au rendez-vous des demi-finales de l'Euro U18\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-bleuets-du-volley-dominent-la-belgique-et-seront-au-rendez-vous-des-demi-finales-de-leuro-u18\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-bleuets-du-volley-dominent-la-belgique-et-seront-au-rendez-vous-des-demi-finales-de-leuro-u18\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/Les-Bleuets-du-volley-dominent-la-Belgique-et-seront-au-rendez-vous-des-demi-finales-de-lEuro-U18.png\",\"datePublished\":\"2026-07-15T11:59:02+00:00\",\"description\":\"EURO U18 MASCULIN DE VOLLEYBALL 2026 - Les Bleus ont termin\u00e9 le travail contre la Belgique, et peuvent maintenant se projeter vers le carr\u00e9 final.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-bleuets-du-volley-dominent-la-belgique-et-seront-au-rendez-vous-des-demi-finales-de-leuro-u18\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-bleuets-du-volley-dominent-la-belgique-et-seront-au-rendez-vous-des-demi-finales-de-leuro-u18\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-bleuets-du-volley-dominent-la-belgique-et-seront-au-rendez-vous-des-demi-finales-de-leuro-u18\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/Les-Bleuets-du-volley-dominent-la-Belgique-et-seront-au-rendez-vous-des-demi-finales-de-lEuro-U18.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/Les-Bleuets-du-volley-dominent-la-Belgique-et-seront-au-rendez-vous-des-demi-finales-de-lEuro-U18.png\",\"width\":1200,\"height\":674,\"caption\":\"Les Bleuets du volley dominent la Belgique et seront au rendez-vous des demi-finales de l'Euro U18\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-bleuets-du-volley-dominent-la-belgique-et-seront-au-rendez-vous-des-demi-finales-de-leuro-u18\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les Bleuets du volley dominent la Belgique et seront au rendez-vous des demi-finales de l&rsquo;Euro U18\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/627966a6cde45dbd8c5e36ac85d783da\",\"name\":\"S\u00e9bastien Gente\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"caption\":\"S\u00e9bastien Gente\"},\"description\":\"John Stockton, Gianni Bugno, Zinedine Zidane, Steffi Graf, Frode Andresen, St\u00e9phane Stoecklin, Davis Kamoga, Primoz Peterka, Werner Schlager et Aur\u00e9lien Rougerie. Point commun entre ces sportifs? Ils m'ont fait r\u00eaver et ont berc\u00e9 mon adolescence. Je suis un fondu de sports et j'essaie de retranscrire ma passion \u00e0 travers mes articles. Originaire du P\u00e9rigord, ma passion pour les Girondins, les Jaunards et les Jazzmen transpire dans mes \u00e9crits. \u00c0 Dicodusport depuis 2021, je d\u00e9niche les sports m\u00e9connus dans lesquels la France brille, et il y en a !\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/sebastien.gente\\\/\",\"https:\\\/\\\/www.instagram.com\\\/sebgente\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/sbastien-gente-a29583169\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/globulo24\",\"SebastienGente\"],\"worksFor\":\"S\u00e9bastien GENTE\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/sebastiengente\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Les Bleuets du volley dominent la Belgique et seront au rendez-vous des demi-finales de l'Euro U18","description":"EURO U18 MASCULIN DE VOLLEYBALL 2026 - Les Bleus ont termin\u00e9 le travail contre la Belgique, et peuvent maintenant se projeter vers le carr\u00e9 final.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/les-bleuets-du-volley-dominent-la-belgique-et-seront-au-rendez-vous-des-demi-finales-de-leuro-u18\/","og_locale":"fr_FR","og_type":"article","og_title":"Les Bleuets du volley dominent la Belgique et seront au rendez-vous des demi-finales de l'Euro U18","og_description":"EURO U18 MASCULIN DE VOLLEYBALL 2026 - Les Bleus ont termin\u00e9 le travail contre la Belgique, et peuvent maintenant se projeter vers le carr\u00e9 final.","og_url":"https:\/\/dicodusport.fr\/blog\/les-bleuets-du-volley-dominent-la-belgique-et-seront-au-rendez-vous-des-demi-finales-de-leuro-u18\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/sebastien.gente\/","article_published_time":"2026-07-15T11:59:02+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/07\/Les-Bleuets-du-volley-dominent-la-Belgique-et-seront-au-rendez-vous-des-demi-finales-de-lEuro-U18.png","type":"image\/png"}],"author":"S\u00e9bastien Gente","twitter_card":"summary_large_image","twitter_title":"Les Bleuets du volley dominent la Belgique et seront au rendez-vous des demi-finales de l'Euro U18","twitter_creator":"@https:\/\/twitter.com\/globulo24","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/les-bleuets-du-volley-dominent-la-belgique-et-seront-au-rendez-vous-des-demi-finales-de-leuro-u18\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/les-bleuets-du-volley-dominent-la-belgique-et-seront-au-rendez-vous-des-demi-finales-de-leuro-u18\/"},"author":{"name":"S\u00e9bastien Gente","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da"},"headline":"Les Bleuets du volley dominent la Belgique et seront au rendez-vous des demi-finales de l&rsquo;Euro U18","datePublished":"2026-07-15T11:59:02+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/les-bleuets-du-volley-dominent-la-belgique-et-seront-au-rendez-vous-des-demi-finales-de-leuro-u18\/"},"wordCount":327,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/les-bleuets-du-volley-dominent-la-belgique-et-seront-au-rendez-vous-des-demi-finales-de-leuro-u18\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/07\/Les-Bleuets-du-volley-dominent-la-Belgique-et-seront-au-rendez-vous-des-demi-finales-de-lEuro-U18.png","keywords":["br\u00e8ve","Championnat d'Europe masculin de volley-ball U18"],"articleSection":["Volley-Ball"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/les-bleuets-du-volley-dominent-la-belgique-et-seront-au-rendez-vous-des-demi-finales-de-leuro-u18\/#respond"]}],"copyrightYear":"2026","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/les-bleuets-du-volley-dominent-la-belgique-et-seront-au-rendez-vous-des-demi-finales-de-leuro-u18\/","url":"https:\/\/dicodusport.fr\/blog\/les-bleuets-du-volley-dominent-la-belgique-et-seront-au-rendez-vous-des-demi-finales-de-leuro-u18\/","name":"Les Bleuets du volley dominent la Belgique et seront au rendez-vous des demi-finales de l'Euro U18","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/les-bleuets-du-volley-dominent-la-belgique-et-seront-au-rendez-vous-des-demi-finales-de-leuro-u18\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/les-bleuets-du-volley-dominent-la-belgique-et-seront-au-rendez-vous-des-demi-finales-de-leuro-u18\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/07\/Les-Bleuets-du-volley-dominent-la-Belgique-et-seront-au-rendez-vous-des-demi-finales-de-lEuro-U18.png","datePublished":"2026-07-15T11:59:02+00:00","description":"EURO U18 MASCULIN DE VOLLEYBALL 2026 - Les Bleus ont termin\u00e9 le travail contre la Belgique, et peuvent maintenant se projeter vers le carr\u00e9 final.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/les-bleuets-du-volley-dominent-la-belgique-et-seront-au-rendez-vous-des-demi-finales-de-leuro-u18\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/les-bleuets-du-volley-dominent-la-belgique-et-seront-au-rendez-vous-des-demi-finales-de-leuro-u18\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/les-bleuets-du-volley-dominent-la-belgique-et-seront-au-rendez-vous-des-demi-finales-de-leuro-u18\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/07\/Les-Bleuets-du-volley-dominent-la-Belgique-et-seront-au-rendez-vous-des-demi-finales-de-lEuro-U18.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/07\/Les-Bleuets-du-volley-dominent-la-Belgique-et-seront-au-rendez-vous-des-demi-finales-de-lEuro-U18.png","width":1200,"height":674,"caption":"Les Bleuets du volley dominent la Belgique et seront au rendez-vous des demi-finales de l'Euro U18"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/les-bleuets-du-volley-dominent-la-belgique-et-seront-au-rendez-vous-des-demi-finales-de-leuro-u18\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Les Bleuets du volley dominent la Belgique et seront au rendez-vous des demi-finales de l&rsquo;Euro U18"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da","name":"S\u00e9bastien Gente","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","caption":"S\u00e9bastien Gente"},"description":"John Stockton, Gianni Bugno, Zinedine Zidane, Steffi Graf, Frode Andresen, St\u00e9phane Stoecklin, Davis Kamoga, Primoz Peterka, Werner Schlager et Aur\u00e9lien Rougerie. Point commun entre ces sportifs? Ils m'ont fait r\u00eaver et ont berc\u00e9 mon adolescence. Je suis un fondu de sports et j'essaie de retranscrire ma passion \u00e0 travers mes articles. Originaire du P\u00e9rigord, ma passion pour les Girondins, les Jaunards et les Jazzmen transpire dans mes \u00e9crits. \u00c0 Dicodusport depuis 2021, je d\u00e9niche les sports m\u00e9connus dans lesquels la France brille, et il y en a !","sameAs":["https:\/\/www.facebook.com\/sebastien.gente\/","https:\/\/www.instagram.com\/sebgente\/","https:\/\/www.linkedin.com\/in\/sbastien-gente-a29583169\/","https:\/\/x.com\/https:\/\/twitter.com\/globulo24","SebastienGente"],"worksFor":"S\u00e9bastien GENTE","url":"https:\/\/dicodusport.fr\/blog\/author\/sebastiengente\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/688562","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/59"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=688562"}],"version-history":[{"count":1,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/688562\/revisions"}],"predecessor-version":[{"id":688571,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/688562\/revisions\/688571"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/688569"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=688562"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=688562"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=688562"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}