{"id":688607,"date":"2026-07-15T23:05:01","date_gmt":"2026-07-15T21:05:01","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=688607&#038;preview=true&#038;preview_id=688607"},"modified":"2026-07-15T23:20:34","modified_gmt":"2026-07-15T21:20:34","slug":"les-tops-et-flops-dangleterre-argentine-insubmersible-albiceleste-les-three-lions-ont-trop-joue-avec-le-feu","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/les-tops-et-flops-dangleterre-argentine-insubmersible-albiceleste-les-three-lions-ont-trop-joue-avec-le-feu\/","title":{"rendered":"Les tops et flops d&rsquo;Angleterre-Argentine : insubmersible Albiceleste, les Three Lions ont trop jou\u00e9 avec le feu"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>COUPE DU MONDE DE FOOTBALL 2026 &#8211; Men\u00e9s jusqu&rsquo;\u00e0 la 84\u00e8me minute, les Argentins sont parvenus \u00e0 renverser les Anglais (2-0) pour rejoindre la grande finale. D\u00e9couvrez les tops et les flops de ce match.\u00a0<\/em><\/strong><\/p>\n<ul style=\"text-align: justify;\">\n<li><strong>\u00c0 ce sujet \u2013\u00a0<a href=\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-2026-phase-finale-tableau-complet-et-resultats\/\">Coupe du monde 2026 Phase finale \u2013 Tableau complet et r\u00e9sultats<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Apr\u00e8s la d\u00e9faite des Bleus face aux Espagnols, la seconde demi-finale avait lieu ce soir entre les Anglais et les Argentins. Cette rencontre a offert une rencontre d\u00e9cousue, qui a finalement vu l&rsquo;Argentine s&rsquo;imposer deux buts \u00e0 z\u00e9ro.<\/p>\n<ul style=\"text-align: justify;\">\n<li><strong>\u00c0 ce sujet \u2013\u00a0<a href=\"https:\/\/dicodusport.fr\/blog\/les-enseignements-de-france-espagne-le-naufrage-de-lucas-digne-la-roja-bete-noire-des-bleus\/\">Les enseignements de France-Espagne : le naufrage de Lucas Digne, la Roja b\u00eate noire des Bleus<\/a><\/strong><\/li>\n<\/ul>\n<h2 style=\"text-align: justify;\">Les tops<\/h2>\n<h3 style=\"text-align: justify;\">L\u2019Albiceste renversante<\/h3>\n<p style=\"text-align: justify;\">Les Argentins ont fait preuve ce soir d\u2019une r\u00e9silience et d\u2019une combativit\u00e9 impressionnantes pour recoller au score. \u00c0 5 minutes du temps r\u00e9glementaire, ils \u00e9taient encore men\u00e9s mais \u00e0 force d&rsquo;encha\u00eener les offensives, ils ont renvers\u00e9 le match dans les derniers instants pour s\u2019offrir une deuxi\u00e8me finale cons\u00e9cutive. Ils ont paru inarr\u00eatables, et ont litt\u00e9ralement \u00e9touff\u00e9 leurs adversaires, s\u2019offrant une victoire amplement m\u00e9rit\u00e9e.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">LAUTARO MART\u00cdNEZ MARQUE DANS LES ARR\u00caTS DE JEU ! \u26bd\ufe0f Sur un centre magique de Lionel Messi, l&rsquo;attaquant argentin place une t\u00eate imparable et fait basculer cette demi-finale ! L&rsquo;Argentine se dirige vers la finale de la Coupe du Monde. \ud83c\udde6\ud83c\uddf7<br \/>\nSuivez le match <a href=\"https:\/\/t.co\/5OZyqM4p0X\">https:\/\/t.co\/5OZyqM4p0X<\/a> sur\u2026 <a href=\"https:\/\/t.co\/Dzk5Qd0x4U\">pic.twitter.com\/Dzk5Qd0x4U<\/a><\/p>\n<p>\u2014 M6 &#8211; Coupe du Monde de la FIFA 2026\u2122 (@M6) <a href=\"https:\/\/x.com\/M6\/status\/2077497735331147891?ref_src=twsrc%5Etfw\">July 15, 2026<\/a><\/p><\/blockquote>\n<p style=\"text-align: justify;\"><script async src=\"https:\/\/platform.x.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h3 style=\"text-align: justify;\">\u00c0 39 ans, Lionel Messi est toujours aussi solide<\/h3>\n<p style=\"text-align: justify;\">Que dire de Lionel Messi ? Est-il le meilleur joueur de l&rsquo;histoire, est-il plus fort que Cristiano Ronaldo ? Tant de questions auxquelles personne ne tombera jamais d&rsquo;accord, mais le moins que l&rsquo;on puisse dire, c&rsquo;est qu&rsquo;il a encore impressionn\u00e9 ce soir. Dans une premi\u00e8re p\u00e9riode tr\u00e8s faible, il a su se d\u00e9marquer en offrant des dribbles remarquables. Mais c&rsquo;est surtout en fin de match qu&rsquo;il a subjugu\u00e9 le monde du foot avec ses deux passes d\u00e9cisives. Sans \u00eatre le buteur, il parvient tout de m\u00eame \u00e0 se montrer sur les deux buts de son \u00e9quipe, montrant qu&rsquo;il est toujours l\u00e0, parmi les meilleurs du monde \u00e0 presque 40 ans.<\/p>\n<h3 style=\"text-align: justify;\"><strong>Une affiche de finale all\u00e9chante<\/strong><\/h3>\n<p style=\"text-align: justify;\">Avec cette victoire, l\u2019Albiceleste rejoint la Roja en finale et cela promet une superbe finale. Deux \u00e9quipes offensives, qui \u00e9taient cit\u00e9es parmi les favorites et qui ont plus que r\u00e9pondu pr\u00e9sentes sur cette Coupe du monde. En tant que supporter fran\u00e7ais, nous r\u00eavions d\u2019une autre affiche, mais il faut reconna\u00eetre que cette rencontre sonne comme une logique implacable.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"en\">The final is set: \ud83c\uddea\ud83c\uddf8\ud83c\udd9a\ud83c\udde6\ud83c\uddf7<a href=\"https:\/\/x.com\/hashtag\/FIFAWorldCup?src=hash&amp;ref_src=twsrc%5Etfw\">#FIFAWorldCup<\/a> <a href=\"https:\/\/t.co\/KNZ3lX6YLV\">pic.twitter.com\/KNZ3lX6YLV<\/a><\/p>\n<p>\u2014 FIFA World Cup (@FIFAWorldCup) <a href=\"https:\/\/x.com\/FIFAWorldCup\/status\/2077499809326309545?ref_src=twsrc%5Etfw\">July 15, 2026<\/a><\/p><\/blockquote>\n<p style=\"text-align: justify;\"><script async src=\"https:\/\/platform.x.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 style=\"text-align: justify;\">Les flops<\/h2>\n<h3 style=\"text-align: justify;\"><strong>Une premi\u00e8re p\u00e9riode tr\u00e8s pauvre<\/strong><\/h3>\n<p style=\"text-align: justify;\">Il fallait \u00eatre imaginatif pour trouver de quoi s\u2019occuper durant cette premi\u00e8re p\u00e9riode. Les deux \u00e9quipes n\u2019ont pas propos\u00e9 grand-chose, si ce n\u2019est des fautes, des fautes et encore des fautes pour porter le total \u00e0 20. \u00c0 plusieurs reprises, les joueurs se sont livr\u00e9s des batailles plus proches du MMA que du football. Et concernant les occasions ? Trois tirs, dont un seul cadr\u00e9, montrant bien la pauvret\u00e9 offensive de ces 45 premi\u00e8res minutes.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">Faute sur Messi et les esprits s\u2019\u00e9chauffent entre les deux \u00e9quipes ! Le match est d\u00e9j\u00e0 sous tr\u00e8s haute tension \ud83d\udd25<\/p>\n<p>Suivez le match <a href=\"https:\/\/t.co\/5OZyqM4p0X\">https:\/\/t.co\/5OZyqM4p0X<\/a> sur M6 et M6+<a href=\"https:\/\/x.com\/hashtag\/CDM2026?src=hash&amp;ref_src=twsrc%5Etfw\">#CDM2026<\/a> <a href=\"https:\/\/x.com\/hashtag\/FIFAWorldCup?src=hash&amp;ref_src=twsrc%5Etfw\">#FIFAWorldCup<\/a> <a href=\"https:\/\/x.com\/hashtag\/ANGARG?src=hash&amp;ref_src=twsrc%5Etfw\">#ANGARG<\/a> <a href=\"https:\/\/t.co\/3Z0C1ZV1qd\">pic.twitter.com\/3Z0C1ZV1qd<\/a><\/p>\n<p>\u2014 M6 &#8211; Coupe du Monde de la FIFA 2026\u2122 (@M6) <a href=\"https:\/\/x.com\/M6\/status\/2077478510851997824?ref_src=twsrc%5Etfw\">July 15, 2026<\/a><\/p><\/blockquote>\n<p style=\"text-align: justify;\"><script async src=\"https:\/\/platform.x.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 style=\"text-align: justify;\"><strong>Les choix de Tuchel discutables<\/strong><\/h2>\n<p style=\"text-align: justify;\">Tactiquement, les choix de <strong>Thomas Tuchel<\/strong> auront \u00e9t\u00e9 tr\u00e8s critiquables. Alors que son \u00e9quipe venait de marquer (55\u2019), le s\u00e9lectionneur de l\u2019\u00e9quipe d\u2019Angleterre a d\u00e9cid\u00e9 d\u2019encha\u00eener les changements pour faire rentrer uniquement des d\u00e9fenseurs. Mais finalement, \u00e0 la 85\u1d49 minute, les Argentins finissent par briser ce mur anglais, us\u00e9 \u00e0 d\u00e9fendre depuis pr\u00e8s de 30 minutes. Est-ce que se tourner vers une strat\u00e9gie d\u00e9fensive quand son \u00e9quipe dominait \u00e9tait intelligent ? Chacun se fera son opinion, mais le second but encaiss\u00e9 par les Anglais dans le temps additionnel vient sous-entendre la bonne r\u00e9ponse.<\/p>\n<div id=\"gtx-trans\" style=\"position: absolute; left: -14px; top: 40.9091px;\">\n<div class=\"gtx-trans-icon\" style=\"text-align: justify;\"><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>COUPE DU MONDE DE FOOTBALL 2026 &#8211; Men\u00e9s jusqu&rsquo;\u00e0 la 84\u00e8me minute, les Argentins sont parvenus \u00e0 renverser les Anglais (2-0) pour rejoindre la grande finale. D\u00e9couvrez les tops et les flops de ce match.\u00a0<\/p>\n","protected":false},"author":89,"featured_media":688764,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[47043],"tags":[51,4209,16878,47003,75,24],"class_list":["post-688607","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coupe-du-monde-de-football","tag-angleterre","tag-argentine","tag-breve","tag-coupe-du-monde-2026","tag-football","tag-sport"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Les tops et flops d&#039;Angleterre-Argentine : insubmersible Albiceleste, les Three Lions ont trop jou\u00e9 avec le feu<\/title>\n<meta name=\"description\" content=\"COUPE DU MONDE DE FOOTBALL 2026 - Men\u00e9s jusqu&#039;\u00e0 la 84\u00e8me minute, les Argentins sont parvenus \u00e0 renverser les Anglais (2-0) pour rejoindre la grande finale. D\u00e9couvrez les tops et les flops de ce match.\u00a0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/les-tops-et-flops-dangleterre-argentine-insubmersible-albiceleste-les-three-lions-ont-trop-joue-avec-le-feu\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les tops et flops d&#039;Angleterre-Argentine : insubmersible Albiceleste, les Three Lions ont trop jou\u00e9 avec le feu\" \/>\n<meta property=\"og:description\" content=\"COUPE DU MONDE DE FOOTBALL 2026 - Men\u00e9s jusqu&#039;\u00e0 la 84\u00e8me minute, les Argentins sont parvenus \u00e0 renverser les Anglais (2-0) pour rejoindre la grande finale. D\u00e9couvrez les tops et les flops de ce match.\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/les-tops-et-flops-dangleterre-argentine-insubmersible-albiceleste-les-three-lions-ont-trop-joue-avec-le-feu\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-15T21:05:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-15T21:20:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/07\/Les-tops-et-flops-dAngleterre-Argentine-insubmersible-Albiceleste-les-Three-Lions-ont-trop-joue-avec-le-feu-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Louka Lesueur\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Les tops et flops d&#039;Angleterre-Argentine : insubmersible Albiceleste, les Three Lions ont trop jou\u00e9 avec le feu\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/LNewsSF\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-tops-et-flops-dangleterre-argentine-insubmersible-albiceleste-les-three-lions-ont-trop-joue-avec-le-feu\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-tops-et-flops-dangleterre-argentine-insubmersible-albiceleste-les-three-lions-ont-trop-joue-avec-le-feu\\\/\"},\"author\":{\"name\":\"Louka Lesueur\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/54b6cdccebdfcd5a1036c594aecffc2a\"},\"headline\":\"Les tops et flops d&rsquo;Angleterre-Argentine : insubmersible Albiceleste, les Three Lions ont trop jou\u00e9 avec le feu\",\"datePublished\":\"2026-07-15T21:05:01+00:00\",\"dateModified\":\"2026-07-15T21:20:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-tops-et-flops-dangleterre-argentine-insubmersible-albiceleste-les-three-lions-ont-trop-joue-avec-le-feu\\\/\"},\"wordCount\":735,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-tops-et-flops-dangleterre-argentine-insubmersible-albiceleste-les-three-lions-ont-trop-joue-avec-le-feu\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/Les-tops-et-flops-dAngleterre-Argentine-insubmersible-Albiceleste-les-Three-Lions-ont-trop-joue-avec-le-feu-1.png\",\"keywords\":[\"Angleterre\",\"Argentine\",\"br\u00e8ve\",\"Coupe du monde 2026\",\"Football\",\"sport\"],\"articleSection\":[\"Coupe du monde de football\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-tops-et-flops-dangleterre-argentine-insubmersible-albiceleste-les-three-lions-ont-trop-joue-avec-le-feu\\\/#respond\"]}],\"copyrightYear\":\"2026\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-tops-et-flops-dangleterre-argentine-insubmersible-albiceleste-les-three-lions-ont-trop-joue-avec-le-feu\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-tops-et-flops-dangleterre-argentine-insubmersible-albiceleste-les-three-lions-ont-trop-joue-avec-le-feu\\\/\",\"name\":\"Les tops et flops d'Angleterre-Argentine : insubmersible Albiceleste, les Three Lions ont trop jou\u00e9 avec le feu\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-tops-et-flops-dangleterre-argentine-insubmersible-albiceleste-les-three-lions-ont-trop-joue-avec-le-feu\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-tops-et-flops-dangleterre-argentine-insubmersible-albiceleste-les-three-lions-ont-trop-joue-avec-le-feu\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/Les-tops-et-flops-dAngleterre-Argentine-insubmersible-Albiceleste-les-Three-Lions-ont-trop-joue-avec-le-feu-1.png\",\"datePublished\":\"2026-07-15T21:05:01+00:00\",\"dateModified\":\"2026-07-15T21:20:34+00:00\",\"description\":\"COUPE DU MONDE DE FOOTBALL 2026 - Men\u00e9s jusqu'\u00e0 la 84\u00e8me minute, les Argentins sont parvenus \u00e0 renverser les Anglais (2-0) pour rejoindre la grande finale. D\u00e9couvrez les tops et les flops de ce match.\u00a0\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-tops-et-flops-dangleterre-argentine-insubmersible-albiceleste-les-three-lions-ont-trop-joue-avec-le-feu\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-tops-et-flops-dangleterre-argentine-insubmersible-albiceleste-les-three-lions-ont-trop-joue-avec-le-feu\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-tops-et-flops-dangleterre-argentine-insubmersible-albiceleste-les-three-lions-ont-trop-joue-avec-le-feu\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/Les-tops-et-flops-dAngleterre-Argentine-insubmersible-Albiceleste-les-Three-Lions-ont-trop-joue-avec-le-feu-1.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/Les-tops-et-flops-dAngleterre-Argentine-insubmersible-Albiceleste-les-Three-Lions-ont-trop-joue-avec-le-feu-1.png\",\"width\":1200,\"height\":674,\"caption\":\"Les tops et flops d'Angleterre-Argentine insubmersible Albiceleste, les Three Lions ont trop jou\u00e9 avec le feu\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-tops-et-flops-dangleterre-argentine-insubmersible-albiceleste-les-three-lions-ont-trop-joue-avec-le-feu\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les tops et flops d&rsquo;Angleterre-Argentine : insubmersible Albiceleste, les Three Lions ont trop jou\u00e9 avec le feu\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/54b6cdccebdfcd5a1036c594aecffc2a\",\"name\":\"Louka Lesueur\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/IMG_2783-150x150.jpeg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/IMG_2783-150x150.jpeg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/IMG_2783-150x150.jpeg\",\"caption\":\"Louka Lesueur\"},\"description\":\"Passionn\u00e9 depuis tout petit par les exploits de Bolt, Fourcade, Riner, Lavillenie, Wilkinson, Hirscher. Les \u00e9motions provoqu\u00e9es par le sport ont berc\u00e9 mon enfance et continuent de le faire aujourd'hui. C'est ainsi qu'il m'est arriv\u00e9 de pleurer devant la d\u00e9faite des Bleus face aux Blacks en 2011, ou encore devant le titre olympique de Florent Manaudou \u00e0 Londres. Bien loin de ce milieu professionnel, j'ai os\u00e9 tenter ma chance pour rejoindre l'\u00e9quipe de r\u00e9daction de Dicodusport, et depuis septembre 2023, je tente de retransmettre au mieux les exploits des athl\u00e8tes, tous sports confondus. Grand chauvin, c'est bel et bien sur les sportifs tricolores que je pr\u00e9f\u00e8re \u00e9crire.\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/LNewsSF\"],\"gender\":\"Homme\",\"worksFor\":\"Louka LESUEUR\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/louka-lesueur\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Les tops et flops d'Angleterre-Argentine : insubmersible Albiceleste, les Three Lions ont trop jou\u00e9 avec le feu","description":"COUPE DU MONDE DE FOOTBALL 2026 - Men\u00e9s jusqu'\u00e0 la 84\u00e8me minute, les Argentins sont parvenus \u00e0 renverser les Anglais (2-0) pour rejoindre la grande finale. D\u00e9couvrez les tops et les flops de ce match.\u00a0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/les-tops-et-flops-dangleterre-argentine-insubmersible-albiceleste-les-three-lions-ont-trop-joue-avec-le-feu\/","og_locale":"fr_FR","og_type":"article","og_title":"Les tops et flops d'Angleterre-Argentine : insubmersible Albiceleste, les Three Lions ont trop jou\u00e9 avec le feu","og_description":"COUPE DU MONDE DE FOOTBALL 2026 - Men\u00e9s jusqu'\u00e0 la 84\u00e8me minute, les Argentins sont parvenus \u00e0 renverser les Anglais (2-0) pour rejoindre la grande finale. D\u00e9couvrez les tops et les flops de ce match.\u00a0","og_url":"https:\/\/dicodusport.fr\/blog\/les-tops-et-flops-dangleterre-argentine-insubmersible-albiceleste-les-three-lions-ont-trop-joue-avec-le-feu\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2026-07-15T21:05:01+00:00","article_modified_time":"2026-07-15T21:20:34+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/07\/Les-tops-et-flops-dAngleterre-Argentine-insubmersible-Albiceleste-les-Three-Lions-ont-trop-joue-avec-le-feu-1.png","type":"image\/png"}],"author":"Louka Lesueur","twitter_card":"summary_large_image","twitter_title":"Les tops et flops d'Angleterre-Argentine : insubmersible Albiceleste, les Three Lions ont trop jou\u00e9 avec le feu","twitter_creator":"@https:\/\/twitter.com\/LNewsSF","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/les-tops-et-flops-dangleterre-argentine-insubmersible-albiceleste-les-three-lions-ont-trop-joue-avec-le-feu\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/les-tops-et-flops-dangleterre-argentine-insubmersible-albiceleste-les-three-lions-ont-trop-joue-avec-le-feu\/"},"author":{"name":"Louka Lesueur","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/54b6cdccebdfcd5a1036c594aecffc2a"},"headline":"Les tops et flops d&rsquo;Angleterre-Argentine : insubmersible Albiceleste, les Three Lions ont trop jou\u00e9 avec le feu","datePublished":"2026-07-15T21:05:01+00:00","dateModified":"2026-07-15T21:20:34+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/les-tops-et-flops-dangleterre-argentine-insubmersible-albiceleste-les-three-lions-ont-trop-joue-avec-le-feu\/"},"wordCount":735,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/les-tops-et-flops-dangleterre-argentine-insubmersible-albiceleste-les-three-lions-ont-trop-joue-avec-le-feu\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/07\/Les-tops-et-flops-dAngleterre-Argentine-insubmersible-Albiceleste-les-Three-Lions-ont-trop-joue-avec-le-feu-1.png","keywords":["Angleterre","Argentine","br\u00e8ve","Coupe du monde 2026","Football","sport"],"articleSection":["Coupe du monde de football"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/les-tops-et-flops-dangleterre-argentine-insubmersible-albiceleste-les-three-lions-ont-trop-joue-avec-le-feu\/#respond"]}],"copyrightYear":"2026","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/les-tops-et-flops-dangleterre-argentine-insubmersible-albiceleste-les-three-lions-ont-trop-joue-avec-le-feu\/","url":"https:\/\/dicodusport.fr\/blog\/les-tops-et-flops-dangleterre-argentine-insubmersible-albiceleste-les-three-lions-ont-trop-joue-avec-le-feu\/","name":"Les tops et flops d'Angleterre-Argentine : insubmersible Albiceleste, les Three Lions ont trop jou\u00e9 avec le feu","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/les-tops-et-flops-dangleterre-argentine-insubmersible-albiceleste-les-three-lions-ont-trop-joue-avec-le-feu\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/les-tops-et-flops-dangleterre-argentine-insubmersible-albiceleste-les-three-lions-ont-trop-joue-avec-le-feu\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/07\/Les-tops-et-flops-dAngleterre-Argentine-insubmersible-Albiceleste-les-Three-Lions-ont-trop-joue-avec-le-feu-1.png","datePublished":"2026-07-15T21:05:01+00:00","dateModified":"2026-07-15T21:20:34+00:00","description":"COUPE DU MONDE DE FOOTBALL 2026 - Men\u00e9s jusqu'\u00e0 la 84\u00e8me minute, les Argentins sont parvenus \u00e0 renverser les Anglais (2-0) pour rejoindre la grande finale. D\u00e9couvrez les tops et les flops de ce match.\u00a0","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/les-tops-et-flops-dangleterre-argentine-insubmersible-albiceleste-les-three-lions-ont-trop-joue-avec-le-feu\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/les-tops-et-flops-dangleterre-argentine-insubmersible-albiceleste-les-three-lions-ont-trop-joue-avec-le-feu\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/les-tops-et-flops-dangleterre-argentine-insubmersible-albiceleste-les-three-lions-ont-trop-joue-avec-le-feu\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/07\/Les-tops-et-flops-dAngleterre-Argentine-insubmersible-Albiceleste-les-Three-Lions-ont-trop-joue-avec-le-feu-1.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/07\/Les-tops-et-flops-dAngleterre-Argentine-insubmersible-Albiceleste-les-Three-Lions-ont-trop-joue-avec-le-feu-1.png","width":1200,"height":674,"caption":"Les tops et flops d'Angleterre-Argentine insubmersible Albiceleste, les Three Lions ont trop jou\u00e9 avec le feu"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/les-tops-et-flops-dangleterre-argentine-insubmersible-albiceleste-les-three-lions-ont-trop-joue-avec-le-feu\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Les tops et flops d&rsquo;Angleterre-Argentine : insubmersible Albiceleste, les Three Lions ont trop jou\u00e9 avec le feu"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/54b6cdccebdfcd5a1036c594aecffc2a","name":"Louka Lesueur","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/09\/IMG_2783-150x150.jpeg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/09\/IMG_2783-150x150.jpeg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/09\/IMG_2783-150x150.jpeg","caption":"Louka Lesueur"},"description":"Passionn\u00e9 depuis tout petit par les exploits de Bolt, Fourcade, Riner, Lavillenie, Wilkinson, Hirscher. Les \u00e9motions provoqu\u00e9es par le sport ont berc\u00e9 mon enfance et continuent de le faire aujourd'hui. C'est ainsi qu'il m'est arriv\u00e9 de pleurer devant la d\u00e9faite des Bleus face aux Blacks en 2011, ou encore devant le titre olympique de Florent Manaudou \u00e0 Londres. Bien loin de ce milieu professionnel, j'ai os\u00e9 tenter ma chance pour rejoindre l'\u00e9quipe de r\u00e9daction de Dicodusport, et depuis septembre 2023, je tente de retransmettre au mieux les exploits des athl\u00e8tes, tous sports confondus. Grand chauvin, c'est bel et bien sur les sportifs tricolores que je pr\u00e9f\u00e8re \u00e9crire.","sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/LNewsSF"],"gender":"Homme","worksFor":"Louka LESUEUR","url":"https:\/\/dicodusport.fr\/blog\/author\/louka-lesueur\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/688607","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/89"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=688607"}],"version-history":[{"count":5,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/688607\/revisions"}],"predecessor-version":[{"id":688769,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/688607\/revisions\/688769"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/688764"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=688607"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=688607"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=688607"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}