{"id":688611,"date":"2026-07-15T18:12:46","date_gmt":"2026-07-15T16:12:46","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=688611&#038;preview=true&#038;preview_id=688611"},"modified":"2026-07-15T18:12:46","modified_gmt":"2026-07-15T16:12:46","slug":"tour-de-france-2026-peut-on-vraiment-recuperer-pendant-une-etape-de-plaine","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/tour-de-france-2026-peut-on-vraiment-recuperer-pendant-une-etape-de-plaine\/","title":{"rendered":"Tour de France 2026 : peut-on vraiment r\u00e9cup\u00e9rer pendant une \u00e9tape de plaine ?"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>TOUR DE FRANCE 2026 &#8211; Ce d\u00e9but de Tour de France 2026 est particuli\u00e8rement intense pour les coureurs. Sur presque toutes les \u00e9tapes, le peloton roule \u00e0 bloc, sans v\u00e9ritable r\u00e9pit. \u00c0 l\u2019exception, peut-\u00eatre, des \u00e9tapes de plaine o\u00f9 les coureurs semblent pouvoir souffler un peu. Mais est-ce vraiment le cas ?<\/em><\/strong><\/p>\n<ul>\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet \u2013 <a href=\"https:\/\/dicodusport.fr\/blog\/tour-de-france-2026-classement-general\/\">Tour de France 2026 : classement g\u00e9n\u00e9ral, maillot jaune, \u00e9carts et Top 10 actualis\u00e9s<\/a><\/strong><\/li>\n<\/ul>\n<h2 align=\"justify\">47 km\/h de moyenne en plaine : peut-on vraiment r\u00e9cup\u00e9rer ?<\/h2>\n<p align=\"justify\"><strong>47,4 km\/h<\/strong>. Voici la vitesse moyenne enregistr\u00e9e sur les quatre \u00e9tapes conclues par un sprint massif depuis le d\u00e9part du Tour. Si vous \u00eates cycliste \u2014 et plus encore si vous ne l\u2019\u00eates pas \u2014 vous vous dites sans doute qu\u2019il est impossible de r\u00e9cup\u00e9rer \u00e0 une telle allure, m\u00eame avec le meilleur v\u00e9lo du monde.<\/p>\n<p align=\"justify\">Ce serait pourtant sous-estimer l&rsquo;importance du <em>drafting<\/em>, autrement dit l&rsquo;aspiration. Cet anglicisme d\u00e9signe le fait de rouler \u00e0 l&rsquo;abri du vent derri\u00e8re d&rsquo;autres coureurs, ou, selon l&rsquo;expression bien connue du peloton, d&rsquo;\u00eatre \u00ab au chaud dans les roues \u00bb.<\/p>\n<div class=\"vlp-link-container vlp-layout-article\"><a href=\"https:\/\/dicodusport.fr\/blog\/en-filou-soren-waerenskjold-remporte-la-11e-etape-du-tour-de-france-a-nevers\/\" class=\"vlp-link\" title=\"En filou, Soren Waerenskjold remporte la 11e \u00e9tape du Tour de France \u00e0 Nevers !\"><\/a><div class=\"vlp-layout-zone-side\"><div class=\"vlp-block-4 vlp-link-image\"><img loading=\"lazy\" decoding=\"async\" style=\"max-width: 792px;\" width=\"792\" height=\"445\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/07\/En-filou-Soren-Waerenskjold-remporte-la-11e-etape-du-Tour-de-France-a-Nevers-1.png\" class=\"attachment-800x445 size-800x445\" alt=\"En filou, Soren Waerenskjold remporte la 11e \u00e9tape du Tour de France \u00e0 Nevers ! (1)\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/07\/En-filou-Soren-Waerenskjold-remporte-la-11e-etape-du-Tour-de-France-a-Nevers-1.png 1200w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/07\/En-filou-Soren-Waerenskjold-remporte-la-11e-etape-du-Tour-de-France-a-Nevers-1-300x169.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/07\/En-filou-Soren-Waerenskjold-remporte-la-11e-etape-du-Tour-de-France-a-Nevers-1-1024x575.png 1024w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/07\/En-filou-Soren-Waerenskjold-remporte-la-11e-etape-du-Tour-de-France-a-Nevers-1-768x431.png 768w\" sizes=\"auto, (max-width: 792px) 100vw, 792px\" \/><\/div><\/div><div class=\"vlp-layout-zone-main\"><div class=\"vlp-block-0 vlp-link-title\">En filou, Soren Waerenskjold remporte la 11e \u00e9tape du Tour de France \u00e0 Nevers !<\/div><div class=\"vlp-block-1 vlp-link-summary\">TOUR DE FRANCE 2026 - S\u00f8ren Waerenskjold (Uno-X Mobility) a gagn\u00e9 au sprint la 11\u00e8me \u00e9tape du Tour de France 2026 entre Vichy et Nevers.\u00a0<\/div><div class=\"vlp-block-2 vlp-link-button\">Lire l'article<\/div><div class=\"vlp-block-3 vlp-link-url\">dicodusport.fr<\/div><\/div><\/div>\n<p align=\"justify\">Selon une \u00e9tude men\u00e9e par le N\u00e9erlandais <a href=\"https:\/\/www.cyclist.co.uk\/news\/peloton-drafting-even-more-efficient-than-we-first-thought-new-study-finds\"><strong>Bert Blocken<\/strong><\/a>, un coureur plac\u00e9 au c\u0153ur d&rsquo;un peloton compact ne subit que 5 \u00e0 10 % de la r\u00e9sistance de l&rsquo;air encaiss\u00e9e par un coureur isol\u00e9 roulant \u00e0 la m\u00eame vitesse. Dans un peloton r\u00e9el, moins homog\u00e8ne qu&rsquo;en laboratoire, ces valeurs seraient l\u00e9g\u00e8rement sup\u00e9rieures, mais le gain a\u00e9rodynamique reste consid\u00e9rable.<\/p>\n<p align=\"justify\">Le revers de la m\u00e9daille ? Rester dans les roues n&rsquo;est jamais totalement <em>\u00ab gratuit \u00bb<\/em>. Il faut constamment se battre pour conserver sa position, freiner, relancer et subir l&rsquo;effet accord\u00e9on. M\u00eame si l&rsquo;avantage a\u00e9rodynamique est \u00e9norme, la d\u00e9pense \u00e9nerg\u00e9tique et surtout la vigilance restent bien r\u00e9elles.<\/p>\n<ul>\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet \u2013 <a href=\"https:\/\/dicodusport.fr\/blog\/tour-de-france-2026-parcours-complet-profil-et-presentation-detaillee-des-21-etapes\/\">Tour de France 2026 : parcours complet, profil et pr\u00e9sentation d\u00e9taill\u00e9e des 21 \u00e9tapes<\/a><\/strong><\/li>\n<\/ul>\n<h2 style=\"text-align: justify;\" align=\"justify\">Des v\u00e9los toujours plus rapides gr\u00e2ce aux progr\u00e8s technologiques<\/h2>\n<p align=\"justify\">Depuis le d\u00e9but des ann\u00e9es 2000 et l&rsquo;apparition des v\u00e9los a\u00e9rodynamiques, les \u00e9volutions technologiques ont \u00e9t\u00e9 spectaculaires. Ann\u00e9e apr\u00e8s ann\u00e9e, les machines se sont perfectionn\u00e9es gr\u00e2ce aux essais en soufflerie, qui permettent de mesurer avec pr\u00e9cision leur rendement a\u00e9rodynamique.<\/p>\n<p align=\"justify\">Aujourd&rsquo;hui, toutes les \u00e9quipes utilisent des v\u00e9los en carbone, avec c\u00e2blerie enti\u00e8rement int\u00e9gr\u00e9e et roues \u00e0 haut rendement. \u00c0 cela s&rsquo;ajoutent les fameux gains marginaux : bidons profil\u00e9s, pneus sp\u00e9cifiques, casques optimis\u00e9s ou encore combinaisons toujours plus travaill\u00e9es pour les \u00e9tapes rapides.<\/p>\n<p align=\"justify\">Le mat\u00e9riel a consid\u00e9rablement \u00e9volu\u00e9, avec des proc\u00e9d\u00e9s de conception qui feraient presque rougir Airbus ou Dassault. Mais il ne faut pas oublier un \u00e9l\u00e9ment essentiel : pr\u00e8s de <strong>70 % de la tra\u00een\u00e9e a\u00e9rodynamique provient du corps du coureur<\/strong>, et non du v\u00e9lo. Le mat\u00e9riel permet de rouler plus vite \u00e0 puissance \u00e9gale, mais la position et la morphologie restent d\u00e9terminantes.<\/p>\n<ul>\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet \u2013\u00a0<a href=\"https:\/\/dicodusport.fr\/blog\/le-classement-et-les-resultats-de-la-11e-etape-du-tour-de-france-2026-remportee-par-soren-waerenskjold\/\">Le classement et les r\u00e9sultats de la 11e \u00e9tape du Tour de France 2026, remport\u00e9e par Soren Waerenskjold<\/a><\/strong><\/li>\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet \u2013 <a href=\"https:\/\/dicodusport.fr\/blog\/rythme-infernal-waerenskjold-alaphilippe-les-4-enseignements-de-la-11e-etape-du-tour-de-france-2026\/\">Rythme infernal, Waerenskjold, Alaphilippe\u2026 les 4 enseignements de la 11e \u00e9tape du Tour de France 2026<\/a><\/strong><\/li>\n<\/ul>\n<h2 style=\"text-align: justify;\" align=\"justify\">Les coureurs peuvent-ils vraiment r\u00e9cup\u00e9rer pendant une \u00e9tape de plaine ?<\/h2>\n<p align=\"justify\">Pour r\u00e9pondre \u00e0 cette question, prenons un exemple concret : <strong>Joris Delbove<\/strong>.<\/p>\n<p align=\"justify\">Le Fran\u00e7ais est l&rsquo;un des rares coureurs du peloton \u00e0 publier r\u00e9guli\u00e8rement ses donn\u00e9es de puissance et de fr\u00e9quence cardiaque, au grand plaisir des observateurs. Lors de la 7e \u00e9tape, conclue \u00e0 Bordeaux, le coureur de <strong>TotalEnergies<\/strong> a pass\u00e9 l&rsquo;int\u00e9gralit\u00e9 de la journ\u00e9e au sein du peloton. Sa fr\u00e9quence cardiaque moyenne s&rsquo;est \u00e9lev\u00e9e \u00e0 <strong>118 battements par minute<\/strong>, soit une intensit\u00e9 correspondant \u00e0 un effort d&rsquo;endurance pour un coureur professionnel.<\/p>\n<p align=\"justify\">Bien s\u00fbr, le rythme s&rsquo;est nettement acc\u00e9l\u00e9r\u00e9 dans les 30 derniers kilom\u00e8tres, o\u00f9 il a d\u00fb fournir un effort plus important pour rester bien plac\u00e9. Mais il ne s&rsquo;agissait pas d&rsquo;un effort maximal, loin de l\u00e0.<\/p>\n<p align=\"justify\">La r\u00e9ponse est donc oui : il est possible de r\u00e9cup\u00e9rer, au moins partiellement, lors d&rsquo;une \u00e9tape de plaine. Ou, plus pr\u00e9cis\u00e9ment, d&rsquo;y d\u00e9penser beaucoup moins d&rsquo;\u00e9nergie que lors des journ\u00e9es de montagne, o\u00f9 les longues ascensions r\u00e9duisent fortement les b\u00e9n\u00e9fices du <em>drafting<\/em> et rendent les efforts bien plus co\u00fbteux.<\/p>\n<h3 style=\"text-align: justify;\">Le classement des autres maillots distinctifs<\/h3>\n<ul style=\"text-align: justify;\">\n<li><a href=\"https:\/\/dicodusport.fr\/blog\/classement-par-points-tour-de-france-2026-le-maillot-vert-actualise-apres-chaque-etape\/\"><strong>Classement du maillot vert<\/strong><\/a><\/li>\n<li><a href=\"https:\/\/dicodusport.fr\/blog\/classement-de-la-montagne-tour-de-france-2026-le-maillot-a-pois-actualise-apres-chaque-etape\/\"><strong>Classement du maillot \u00e0 pois<\/strong><\/a><\/li>\n<li><a href=\"https:\/\/dicodusport.fr\/blog\/classement-du-meilleur-jeune-tour-de-france-2026-le-maillot-blanc-actualise-apres-chaque-etape\/\"><strong>Classement du maillot blanc<\/strong><\/a><\/li>\n<\/ul>\n<div id=\"gtx-trans\" style=\"position: absolute; left: -14px; top: 40.9091px;\">\n<div class=\"gtx-trans-icon\"><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Peut-on vraiment r\u00e9cup\u00e9rer pendant une \u00e9tape de plaine du Tour de France ? Entre aspiration, mat\u00e9riel et donn\u00e9es de Joris Delbove, d\u00e9cryptage d&rsquo;un mythe du peloton.<\/p>\n","protected":false},"author":131,"featured_media":688668,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[46995],"tags":[32415,16878,574,11197,1262],"class_list":["post-688611","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tour-de-france","tag-actu","tag-breve","tag-cyclisme","tag-cyclisme-sur-route","tag-tour-de-france"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Tour de France 2026 : peut-on vraiment r\u00e9cup\u00e9rer pendant une \u00e9tape de plaine ?<\/title>\n<meta name=\"description\" content=\"Peut-on vraiment r\u00e9cup\u00e9rer pendant une \u00e9tape de plaine du Tour de France ? Entre aspiration, mat\u00e9riel et donn\u00e9es de Joris Delbove, d\u00e9cryptage d&#039;un mythe du peloton.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/tour-de-france-2026-peut-on-vraiment-recuperer-pendant-une-etape-de-plaine\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tour de France 2026 : peut-on vraiment r\u00e9cup\u00e9rer pendant une \u00e9tape de plaine ?\" \/>\n<meta property=\"og:description\" content=\"Peut-on vraiment r\u00e9cup\u00e9rer pendant une \u00e9tape de plaine du Tour de France ? Entre aspiration, mat\u00e9riel et donn\u00e9es de Joris Delbove, d\u00e9cryptage d&#039;un mythe du peloton.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/tour-de-france-2026-peut-on-vraiment-recuperer-pendant-une-etape-de-plaine\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-15T16:12:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/07\/Tour-de-France-2026-peut-on-vraiment-recuperer-pendant-une-etape-de-plaine-.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicolas Grasser\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Tour de France 2026 : peut-on vraiment r\u00e9cup\u00e9rer pendant une \u00e9tape de plaine ?\" \/>\n<meta name=\"twitter:creator\" content=\"@dicodusport\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/tour-de-france-2026-peut-on-vraiment-recuperer-pendant-une-etape-de-plaine\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/tour-de-france-2026-peut-on-vraiment-recuperer-pendant-une-etape-de-plaine\\\/\"},\"author\":{\"name\":\"Nicolas Grasser\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/a173469c5b5aa34cf42cfa11482c966d\"},\"headline\":\"Tour de France 2026 : peut-on vraiment r\u00e9cup\u00e9rer pendant une \u00e9tape de plaine ?\",\"datePublished\":\"2026-07-15T16:12:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/tour-de-france-2026-peut-on-vraiment-recuperer-pendant-une-etape-de-plaine\\\/\"},\"wordCount\":867,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/tour-de-france-2026-peut-on-vraiment-recuperer-pendant-une-etape-de-plaine\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/Tour-de-France-2026-peut-on-vraiment-recuperer-pendant-une-etape-de-plaine-.png\",\"keywords\":[\"actu\",\"br\u00e8ve\",\"Cyclisme\",\"Cyclisme sur route\",\"Tour de France\"],\"articleSection\":[\"Tour de France\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/tour-de-france-2026-peut-on-vraiment-recuperer-pendant-une-etape-de-plaine\\\/#respond\"]}],\"copyrightYear\":\"2026\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/tour-de-france-2026-peut-on-vraiment-recuperer-pendant-une-etape-de-plaine\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/tour-de-france-2026-peut-on-vraiment-recuperer-pendant-une-etape-de-plaine\\\/\",\"name\":\"Tour de France 2026 : peut-on vraiment r\u00e9cup\u00e9rer pendant une \u00e9tape de plaine ?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/tour-de-france-2026-peut-on-vraiment-recuperer-pendant-une-etape-de-plaine\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/tour-de-france-2026-peut-on-vraiment-recuperer-pendant-une-etape-de-plaine\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/Tour-de-France-2026-peut-on-vraiment-recuperer-pendant-une-etape-de-plaine-.png\",\"datePublished\":\"2026-07-15T16:12:46+00:00\",\"description\":\"Peut-on vraiment r\u00e9cup\u00e9rer pendant une \u00e9tape de plaine du Tour de France ? Entre aspiration, mat\u00e9riel et donn\u00e9es de Joris Delbove, d\u00e9cryptage d'un mythe du peloton.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/tour-de-france-2026-peut-on-vraiment-recuperer-pendant-une-etape-de-plaine\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/tour-de-france-2026-peut-on-vraiment-recuperer-pendant-une-etape-de-plaine\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/tour-de-france-2026-peut-on-vraiment-recuperer-pendant-une-etape-de-plaine\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/Tour-de-France-2026-peut-on-vraiment-recuperer-pendant-une-etape-de-plaine-.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/Tour-de-France-2026-peut-on-vraiment-recuperer-pendant-une-etape-de-plaine-.png\",\"width\":1200,\"height\":674,\"caption\":\"Tour de France 2026 peut-on vraiment r\u00e9cup\u00e9rer pendant une \u00e9tape de plaine\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/tour-de-france-2026-peut-on-vraiment-recuperer-pendant-une-etape-de-plaine\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tour de France 2026 : peut-on vraiment r\u00e9cup\u00e9rer pendant une \u00e9tape de plaine ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/a173469c5b5aa34cf42cfa11482c966d\",\"name\":\"Nicolas Grasser\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE-150x150.png\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE-150x150.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE-150x150.png\",\"caption\":\"Nicolas Grasser\"},\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/nicolas-grasser\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Tour de France 2026 : peut-on vraiment r\u00e9cup\u00e9rer pendant une \u00e9tape de plaine ?","description":"Peut-on vraiment r\u00e9cup\u00e9rer pendant une \u00e9tape de plaine du Tour de France ? Entre aspiration, mat\u00e9riel et donn\u00e9es de Joris Delbove, d\u00e9cryptage d'un mythe du peloton.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/tour-de-france-2026-peut-on-vraiment-recuperer-pendant-une-etape-de-plaine\/","og_locale":"fr_FR","og_type":"article","og_title":"Tour de France 2026 : peut-on vraiment r\u00e9cup\u00e9rer pendant une \u00e9tape de plaine ?","og_description":"Peut-on vraiment r\u00e9cup\u00e9rer pendant une \u00e9tape de plaine du Tour de France ? Entre aspiration, mat\u00e9riel et donn\u00e9es de Joris Delbove, d\u00e9cryptage d'un mythe du peloton.","og_url":"https:\/\/dicodusport.fr\/blog\/tour-de-france-2026-peut-on-vraiment-recuperer-pendant-une-etape-de-plaine\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2026-07-15T16:12:46+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/07\/Tour-de-France-2026-peut-on-vraiment-recuperer-pendant-une-etape-de-plaine-.png","type":"image\/png"}],"author":"Nicolas Grasser","twitter_card":"summary_large_image","twitter_title":"Tour de France 2026 : peut-on vraiment r\u00e9cup\u00e9rer pendant une \u00e9tape de plaine ?","twitter_creator":"@dicodusport","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/tour-de-france-2026-peut-on-vraiment-recuperer-pendant-une-etape-de-plaine\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/tour-de-france-2026-peut-on-vraiment-recuperer-pendant-une-etape-de-plaine\/"},"author":{"name":"Nicolas Grasser","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/a173469c5b5aa34cf42cfa11482c966d"},"headline":"Tour de France 2026 : peut-on vraiment r\u00e9cup\u00e9rer pendant une \u00e9tape de plaine ?","datePublished":"2026-07-15T16:12:46+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/tour-de-france-2026-peut-on-vraiment-recuperer-pendant-une-etape-de-plaine\/"},"wordCount":867,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/tour-de-france-2026-peut-on-vraiment-recuperer-pendant-une-etape-de-plaine\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/07\/Tour-de-France-2026-peut-on-vraiment-recuperer-pendant-une-etape-de-plaine-.png","keywords":["actu","br\u00e8ve","Cyclisme","Cyclisme sur route","Tour de France"],"articleSection":["Tour de France"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/tour-de-france-2026-peut-on-vraiment-recuperer-pendant-une-etape-de-plaine\/#respond"]}],"copyrightYear":"2026","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/tour-de-france-2026-peut-on-vraiment-recuperer-pendant-une-etape-de-plaine\/","url":"https:\/\/dicodusport.fr\/blog\/tour-de-france-2026-peut-on-vraiment-recuperer-pendant-une-etape-de-plaine\/","name":"Tour de France 2026 : peut-on vraiment r\u00e9cup\u00e9rer pendant une \u00e9tape de plaine ?","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/tour-de-france-2026-peut-on-vraiment-recuperer-pendant-une-etape-de-plaine\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/tour-de-france-2026-peut-on-vraiment-recuperer-pendant-une-etape-de-plaine\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/07\/Tour-de-France-2026-peut-on-vraiment-recuperer-pendant-une-etape-de-plaine-.png","datePublished":"2026-07-15T16:12:46+00:00","description":"Peut-on vraiment r\u00e9cup\u00e9rer pendant une \u00e9tape de plaine du Tour de France ? Entre aspiration, mat\u00e9riel et donn\u00e9es de Joris Delbove, d\u00e9cryptage d'un mythe du peloton.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/tour-de-france-2026-peut-on-vraiment-recuperer-pendant-une-etape-de-plaine\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/tour-de-france-2026-peut-on-vraiment-recuperer-pendant-une-etape-de-plaine\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/tour-de-france-2026-peut-on-vraiment-recuperer-pendant-une-etape-de-plaine\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/07\/Tour-de-France-2026-peut-on-vraiment-recuperer-pendant-une-etape-de-plaine-.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/07\/Tour-de-France-2026-peut-on-vraiment-recuperer-pendant-une-etape-de-plaine-.png","width":1200,"height":674,"caption":"Tour de France 2026 peut-on vraiment r\u00e9cup\u00e9rer pendant une \u00e9tape de plaine"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/tour-de-france-2026-peut-on-vraiment-recuperer-pendant-une-etape-de-plaine\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Tour de France 2026 : peut-on vraiment r\u00e9cup\u00e9rer pendant une \u00e9tape de plaine ?"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/a173469c5b5aa34cf42cfa11482c966d","name":"Nicolas Grasser","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE-150x150.png","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE-150x150.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE-150x150.png","caption":"Nicolas Grasser"},"url":"https:\/\/dicodusport.fr\/blog\/author\/nicolas-grasser\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/688611","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/131"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=688611"}],"version-history":[{"count":5,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/688611\/revisions"}],"predecessor-version":[{"id":688666,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/688611\/revisions\/688666"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/688668"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=688611"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=688611"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=688611"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}