{"id":68964,"date":"2020-06-15T19:12:01","date_gmt":"2020-06-15T17:12:01","guid":{"rendered":"http:\/\/dicodusport.fr\/blog\/?p=68964&#038;preview=true&#038;preview_id=68964"},"modified":"2021-05-11T17:03:14","modified_gmt":"2021-05-11T15:03:14","slug":"football-bundesliga-pronostic-pour-werder-breme-bayern-munich","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/football-bundesliga-pronostic-pour-werder-breme-bayern-munich\/","title":{"rendered":"Football &#8211; Bundesliga : notre pronostic pour Werder Br\u00eame &#8211; Bayern Munich"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><b>BUNDESLIGA &#8211; Pour le compte de la 32\u00e8me journ\u00e9e, le Bayern Munich se d\u00e9place sur la pelouse du Werder Br\u00eame. Notre pronostic.<\/b><br \/>\n<\/em><\/p>\n<h2 style=\"text-align: justify;\"><span style=\"font-family: -apple-system, BlinkMacSystemFont, 'Segoe UI', Roboto, Oxygen-Sans, Ubuntu, Cantarell, 'Helvetica Neue', sans-serif;\">Werder Br\u00eame &#8211; Bayern Munich : Mardi 16 juin, 20h30<\/span><\/h2>\n<p style=\"text-align: justify;\">Match \u00e0 enjeu pour les deux \u00e9quipes, mais pas le m\u00eame. Le Werder de Br\u00eame est toujours \u00e0 la lutte pour le maintien et si la situation semblait d\u00e9sesp\u00e9r\u00e9e au moment de la reprise, c&rsquo;est un peu moins vrai maintenant. Prendre des points contre le Bayern serait utile dans cette course, mais les Bavarois peuvent \u00eatre titr\u00e9s sur ce match. Et sur la forme du moment, on ne voit pas bien comment la pire \u00e9quipe de la saison \u00e0 domicile, m\u00eame au bord du pr\u00e9cipice, pourra \u00e9viter cela. Suspendu lors du dernier match, Robert Lewandowski fait son retour. <strong>On part sur une victoire du Bayern avec un but de son avant-centre polonais.<\/strong><\/p>\n<table style=\"width: 800px;\">\n<tbody>\n<tr style=\"height: 16px;\">\n<td style=\"border-color: #ffffff; background-color: #404040; width: 500px; vertical-align: middle;\"><span style=\"font-size: 12px; color: #ffffff;\">Mardi 16 juin, 20h30<\/span><\/td>\n<td style=\"border-color: #ffffff; background-color: #525252; text-align: center; width: 300px;\"><span style=\"font-size: 12px; color: #ffffff;\">Le joueur marque et son \u00e9quipe gagne\u00a0<\/span><\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"border-color: #ffffff; background-color: #ffffff; text-align: justify; width: 500px;\"><span style=\"font-size: 14px; color: #000000;\"><strong>Robert Lewandowski\/Bayern Munich<\/strong><\/span><\/td>\n<td style=\"border-color: #ffffff; background-color: #ffffff; text-align: center; width: 300px;\"><span style=\"font-size: 10px;\"><a href=\"https:\/\/www.winamax.fr\/paris-sportifs\/match\/prelive\/21971407?banid=33431\" class=\"su-button su-button-style-flat\" style=\"color:#FFFFFF;background-color:#b10e12;border-color:#8e0c0f;border-radius:5px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#FFFFFF;padding:0px 16px;font-size:13px;line-height:26px;border-color:#c9575a;border-radius:5px;text-shadow:none\"> 1.42<\/span><\/a><\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p style=\"text-align: justify;\"><span style=\"font-family: -apple-system, BlinkMacSystemFont, 'Segoe UI', Roboto, Oxygen-Sans, Ubuntu, Cantarell, 'Helvetica Neue', sans-serif; font-size: 16px;\">Tentez votre chance en misant jusqu\u2019\u00e0 100\u20ac gr\u00e2ce \u00e0 votre <\/span><a style=\"font-family: -apple-system, BlinkMacSystemFont, 'Segoe UI', Roboto, Oxygen-Sans, Ubuntu, Cantarell, 'Helvetica Neue', sans-serif; font-size: 16px;\" href=\"https:\/\/www.winamax.fr\/landing\/landing_leads.php?ldg=1er-pari-rembourse&amp;banid=33423\" target=\"_blank\" rel=\"noopener noreferrer\">premier pari rembours\u00e9<\/a><span style=\"font-family: -apple-system, BlinkMacSystemFont, 'Segoe UI', Roboto, Oxygen-Sans, Ubuntu, Cantarell, 'Helvetica Neue', sans-serif; font-size: 16px;\">.<\/span><\/p>\n<p style=\"text-align: justify;\"><strong><em>Dicodusport<br \/>\n<a href=\"https:\/\/www.facebook.com\/dicodusport\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2909\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-facebook-150x150.png\" sizes=\"auto, (max-width: 40px) 100vw, 40px\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-facebook-150x150.png 150w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-facebook-300x300.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-facebook.png 400w\" alt=\"\" width=\"40\" height=\"40\" \/><\/a><a href=\"https:\/\/twitter.com\/dicodusport\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2908\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-twitter-150x150.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>BUNDESLIGA &#8211; Pour le compte de la 32\u00e8me journ\u00e9e, le Bayern Munich se d\u00e9place sur la pelouse du Werder Br\u00eame. Notre pronostic.<\/p>\n","protected":false},"author":1,"featured_media":68981,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[2301],"tags":[4484,7173,75,4949,10758],"class_list":["post-68964","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-football","tag-bayern-munich","tag-bundesliga","tag-football","tag-pronostics","tag-werder-breme"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Football - Bundesliga : notre pronostic pour Werder Br\u00eame - Bayern Munich - Dicodusport<\/title>\n<meta name=\"description\" content=\"BUNDESLIGA - Pour le compte de la 32\u00e8me journ\u00e9e, le Bayern Munich se d\u00e9place sur la pelouse du Werder Br\u00eame. Notre pronostic.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/football-bundesliga-pronostic-pour-werder-breme-bayern-munich\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bundesliga : notre pronostic pour Werder Br\u00eame - Bayern Munich\" \/>\n<meta property=\"og:description\" content=\"BUNDESLIGA - Pour le compte de la 32\u00e8me journ\u00e9e, le Bayern Munich se d\u00e9place sur la pelouse du Werder Br\u00eame. Notre pronostic.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/football-bundesliga-pronostic-pour-werder-breme-bayern-munich\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-15T17:12:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-05-11T15:03:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/Football-Bundesliga-Notre-pronostic-pour-Werder-Br\u00eame-Bayern-Munich.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicolas Jacquemard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Bundesliga : notre pronostic pour Werder Br\u00eame - Bayern Munich\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Nico_Jacquemard\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/football-bundesliga-pronostic-pour-werder-breme-bayern-munich\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/football-bundesliga-pronostic-pour-werder-breme-bayern-munich\/\"},\"author\":{\"name\":\"Nicolas Jacquemard\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\"},\"headline\":\"Football &#8211; Bundesliga : notre pronostic pour Werder Br\u00eame &#8211; Bayern Munich\",\"datePublished\":\"2020-06-15T17:12:01+00:00\",\"dateModified\":\"2021-05-11T15:03:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/football-bundesliga-pronostic-pour-werder-breme-bayern-munich\/\"},\"wordCount\":213,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/football-bundesliga-pronostic-pour-werder-breme-bayern-munich\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/Football-Bundesliga-Notre-pronostic-pour-Werder-Br\u00eame-Bayern-Munich.png\",\"keywords\":[\"Bayern Munich\",\"Bundesliga\",\"Football\",\"Pronostics\",\"Werder Br\u00eame\"],\"articleSection\":[\"Football\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/football-bundesliga-pronostic-pour-werder-breme-bayern-munich\/#respond\"]}],\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/football-bundesliga-pronostic-pour-werder-breme-bayern-munich\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/football-bundesliga-pronostic-pour-werder-breme-bayern-munich\/\",\"name\":\"Football - Bundesliga : notre pronostic pour Werder Br\u00eame - Bayern Munich - Dicodusport\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/football-bundesliga-pronostic-pour-werder-breme-bayern-munich\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/football-bundesliga-pronostic-pour-werder-breme-bayern-munich\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/Football-Bundesliga-Notre-pronostic-pour-Werder-Br\u00eame-Bayern-Munich.png\",\"datePublished\":\"2020-06-15T17:12:01+00:00\",\"dateModified\":\"2021-05-11T15:03:14+00:00\",\"description\":\"BUNDESLIGA - Pour le compte de la 32\u00e8me journ\u00e9e, le Bayern Munich se d\u00e9place sur la pelouse du Werder Br\u00eame. Notre pronostic.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/football-bundesliga-pronostic-pour-werder-breme-bayern-munich\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/football-bundesliga-pronostic-pour-werder-breme-bayern-munich\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/football-bundesliga-pronostic-pour-werder-breme-bayern-munich\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/Football-Bundesliga-Notre-pronostic-pour-Werder-Br\u00eame-Bayern-Munich.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/Football-Bundesliga-Notre-pronostic-pour-Werder-Br\u00eame-Bayern-Munich.png\",\"width\":800,\"height\":445,\"caption\":\"Football - Bundesliga : notre pronostic pour Werder Br\u00eame - Bayern Munich\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/football-bundesliga-pronostic-pour-werder-breme-bayern-munich\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Football &#8211; Bundesliga : notre pronostic pour Werder Br\u00eame &#8211; Bayern Munich\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\",\"name\":\"Nicolas Jacquemard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"caption\":\"Nicolas Jacquemard\"},\"description\":\"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.\",\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Football - Bundesliga : notre pronostic pour Werder Br\u00eame - Bayern Munich - Dicodusport","description":"BUNDESLIGA - Pour le compte de la 32\u00e8me journ\u00e9e, le Bayern Munich se d\u00e9place sur la pelouse du Werder Br\u00eame. Notre pronostic.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/football-bundesliga-pronostic-pour-werder-breme-bayern-munich\/","og_locale":"fr_FR","og_type":"article","og_title":"Bundesliga : notre pronostic pour Werder Br\u00eame - Bayern Munich","og_description":"BUNDESLIGA - Pour le compte de la 32\u00e8me journ\u00e9e, le Bayern Munich se d\u00e9place sur la pelouse du Werder Br\u00eame. Notre pronostic.","og_url":"https:\/\/dicodusport.fr\/blog\/football-bundesliga-pronostic-pour-werder-breme-bayern-munich\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2020-06-15T17:12:01+00:00","article_modified_time":"2021-05-11T15:03:14+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/Football-Bundesliga-Notre-pronostic-pour-Werder-Br\u00eame-Bayern-Munich.png","type":"image\/png"}],"author":"Nicolas Jacquemard","twitter_card":"summary_large_image","twitter_title":"Bundesliga : notre pronostic pour Werder Br\u00eame - Bayern Munich","twitter_creator":"@https:\/\/twitter.com\/Nico_Jacquemard","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/football-bundesliga-pronostic-pour-werder-breme-bayern-munich\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/football-bundesliga-pronostic-pour-werder-breme-bayern-munich\/"},"author":{"name":"Nicolas Jacquemard","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191"},"headline":"Football &#8211; Bundesliga : notre pronostic pour Werder Br\u00eame &#8211; Bayern Munich","datePublished":"2020-06-15T17:12:01+00:00","dateModified":"2021-05-11T15:03:14+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/football-bundesliga-pronostic-pour-werder-breme-bayern-munich\/"},"wordCount":213,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/football-bundesliga-pronostic-pour-werder-breme-bayern-munich\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/Football-Bundesliga-Notre-pronostic-pour-Werder-Br\u00eame-Bayern-Munich.png","keywords":["Bayern Munich","Bundesliga","Football","Pronostics","Werder Br\u00eame"],"articleSection":["Football"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/football-bundesliga-pronostic-pour-werder-breme-bayern-munich\/#respond"]}],"copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/football-bundesliga-pronostic-pour-werder-breme-bayern-munich\/","url":"https:\/\/dicodusport.fr\/blog\/football-bundesliga-pronostic-pour-werder-breme-bayern-munich\/","name":"Football - Bundesliga : notre pronostic pour Werder Br\u00eame - Bayern Munich - Dicodusport","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/football-bundesliga-pronostic-pour-werder-breme-bayern-munich\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/football-bundesliga-pronostic-pour-werder-breme-bayern-munich\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/Football-Bundesliga-Notre-pronostic-pour-Werder-Br\u00eame-Bayern-Munich.png","datePublished":"2020-06-15T17:12:01+00:00","dateModified":"2021-05-11T15:03:14+00:00","description":"BUNDESLIGA - Pour le compte de la 32\u00e8me journ\u00e9e, le Bayern Munich se d\u00e9place sur la pelouse du Werder Br\u00eame. Notre pronostic.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/football-bundesliga-pronostic-pour-werder-breme-bayern-munich\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/football-bundesliga-pronostic-pour-werder-breme-bayern-munich\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/football-bundesliga-pronostic-pour-werder-breme-bayern-munich\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/Football-Bundesliga-Notre-pronostic-pour-Werder-Br\u00eame-Bayern-Munich.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/Football-Bundesliga-Notre-pronostic-pour-Werder-Br\u00eame-Bayern-Munich.png","width":800,"height":445,"caption":"Football - Bundesliga : notre pronostic pour Werder Br\u00eame - Bayern Munich"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/football-bundesliga-pronostic-pour-werder-breme-bayern-munich\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Football &#8211; Bundesliga : notre pronostic pour Werder Br\u00eame &#8211; Bayern Munich"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191","name":"Nicolas Jacquemard","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","caption":"Nicolas Jacquemard"},"description":"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.","sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard"],"url":"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/68964","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=68964"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/68964\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/68981"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=68964"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=68964"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=68964"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}