{"id":71093,"date":"2020-07-08T14:59:45","date_gmt":"2020-07-08T12:59:45","guid":{"rendered":"http:\/\/dicodusport.fr\/blog\/?p=71093&#038;preview=true&#038;preview_id=71093"},"modified":"2020-07-08T15:08:18","modified_gmt":"2020-07-08T13:08:18","slug":"top-14-pro-d2-lnr-annonce-grandes-dates-saison-2020-2021","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/top-14-pro-d2-lnr-annonce-grandes-dates-saison-2020-2021\/","title":{"rendered":"Top 14 &#8211; Pro D2 : La LNR annonce les grandes dates de la saison 2020-2021"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>RUGBY &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/top-14-ffr-rejette-calendrier\/\" target=\"_blank\" rel=\"noopener noreferrer\">Apr\u00e8s l&rsquo;avoir dans un premier temps repouss\u00e9<\/a>, la F\u00e9d\u00e9ration Fran\u00e7aise de Rugby a finalement valid\u00e9 le calendrier de la Ligue Nationale de Rugby pour la saison 2020-2021 de Top 14 et Pro D2.\u00a0<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">La premi\u00e8re journ\u00e9e de Top 14 et Pro D2 aura lieu du <strong>3 au 5 septembre<\/strong>. La finale de Pro D2 se d\u00e9roulera le <strong>dimanche 6 juin<\/strong> tandis que celle de Top 14 se disputera le <strong>samedi 26 juin<\/strong>. Pour le moment, les dates des matchs du XV de France pour la tourn\u00e9e d&rsquo;automne ne figurent pas sur le calendrier.<\/p>\n<h2 style=\"text-align: justify;\">Le calendrier complet<\/h2>\n<div id=\"attachment_71100\" style=\"width: 2294px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/07\/Top-14-Pro-D2-Les-grandes-dates-de-la-saison-2020-2021.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-71100\" class=\"size-full wp-image-71100\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/07\/Top-14-Pro-D2-Les-grandes-dates-de-la-saison-2020-2021.jpg\" alt=\"\" width=\"2284\" height=\"1216\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/07\/Top-14-Pro-D2-Les-grandes-dates-de-la-saison-2020-2021.jpg 2284w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/07\/Top-14-Pro-D2-Les-grandes-dates-de-la-saison-2020-2021-300x160.jpg 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/07\/Top-14-Pro-D2-Les-grandes-dates-de-la-saison-2020-2021-1024x545.jpg 1024w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/07\/Top-14-Pro-D2-Les-grandes-dates-de-la-saison-2020-2021-768x409.jpg 768w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/07\/Top-14-Pro-D2-Les-grandes-dates-de-la-saison-2020-2021-1536x818.jpg 1536w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/07\/Top-14-Pro-D2-Les-grandes-dates-de-la-saison-2020-2021-2048x1090.jpg 2048w\" sizes=\"auto, (max-width: 2284px) 100vw, 2284px\" \/><\/a><p id=\"caption-attachment-71100\" class=\"wp-caption-text\">Top 14 &#8211; Pro D2 : les grandes dates de la saison 2020-2021 &#8211; LNR<\/p><\/div>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">Suite \u00e0 l\u2019adoption par le Comit\u00e9 Directeur de la LNR le 1er Juillet, le Comit\u00e9 Directeur de la FFR a approuv\u00e9 le calendrier des championnats de TOP 14, de PRO D2 et de l\u2019IN EXTENSO SUPERSEVENS pour la saison 2020-2021.<\/p>\n<p>Le communiqu\u00e9 &#x1f4c4;&#x27a1;&#xfe0f; <a href=\"https:\/\/t.co\/dnjcx82mYp\">https:\/\/t.co\/dnjcx82mYp<\/a><\/p>\n[1\/2] <a href=\"https:\/\/t.co\/0qAzCViws2\">pic.twitter.com\/0qAzCViws2<\/a><\/p>\n<p>\u2014 Ligue Nationale de Rugby (@LNRofficiel) <a href=\"https:\/\/twitter.com\/LNRofficiel\/status\/1280818094626258944?ref_src=twsrc%5Etfw\">July 8, 2020<\/a><\/p><\/blockquote>\n<p style=\"text-align: justify;\"><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p style=\"text-align: justify;\"><strong><em>Dicodusport<br \/>\n<a href=\"https:\/\/www.facebook.com\/dicodusport\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2909\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-facebook-150x150.png\" alt=\"\" width=\"40\" height=\"40\" \/><\/a><a href=\"https:\/\/twitter.com\/dicodusport\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2908\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-twitter-150x150.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>RUGBY &#8211; Apr\u00e8s l&rsquo;avoir dans un premier temps repouss\u00e9, la F\u00e9d\u00e9ration Fran\u00e7aise de Rugby a finalement valid\u00e9 le calendrier de la Ligue Nationale de Rugby pour la saison 2020-2021 de Top 14 et Pro D2.\u00a0<\/p>\n","protected":false},"author":1,"featured_media":71101,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[9129],"tags":[1839,111],"class_list":["post-71093","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rugby-a-xv","tag-pro-d2","tag-top-14"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Top 14 - Pro D2 : La LNR annonce les grandes dates de la saison 2020-2021<\/title>\n<meta name=\"description\" content=\"RUGBY - La F\u00e9d\u00e9ration Fran\u00e7aise de Rugby a finalement valid\u00e9 le calendrier de la Ligue Nationale de Rugby pour la saison 2020-2021 de Top 14 et Pro D2.\u00a0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/top-14-pro-d2-lnr-annonce-grandes-dates-saison-2020-2021\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Top 14 - Pro D2 : les grandes dates de la saison 2020-2021\" \/>\n<meta property=\"og:description\" content=\"RUGBY - La F\u00e9d\u00e9ration Fran\u00e7aise de Rugby a finalement valid\u00e9 le calendrier de la Ligue Nationale de Rugby pour la saison 2020-2021 de Top 14 et Pro D2.\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/top-14-pro-d2-lnr-annonce-grandes-dates-saison-2020-2021\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-08T12:59:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-07-08T13:08:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/07\/Top-14-Pro-D2-Les-grandes-dates-de-la-saison-2020-2021.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicolas Jacquemard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Top 14 - Pro D2 : les grandes dates de la saison 2020-2021\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Nico_Jacquemard\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/top-14-pro-d2-lnr-annonce-grandes-dates-saison-2020-2021\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/top-14-pro-d2-lnr-annonce-grandes-dates-saison-2020-2021\\\/\"},\"author\":{\"name\":\"Nicolas Jacquemard\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/55dcb50ad410894e431ed812bbb70191\"},\"headline\":\"Top 14 &#8211; Pro D2 : La LNR annonce les grandes dates de la saison 2020-2021\",\"datePublished\":\"2020-07-08T12:59:45+00:00\",\"dateModified\":\"2020-07-08T13:08:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/top-14-pro-d2-lnr-annonce-grandes-dates-saison-2020-2021\\\/\"},\"wordCount\":200,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/top-14-pro-d2-lnr-annonce-grandes-dates-saison-2020-2021\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/Top-14-Pro-D2-Les-grandes-dates-de-la-saison-2020-2021.png\",\"keywords\":[\"Pro D2\",\"Top 14\"],\"articleSection\":[\"Rugby \u00e0 XV\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/top-14-pro-d2-lnr-annonce-grandes-dates-saison-2020-2021\\\/#respond\"]}],\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/top-14-pro-d2-lnr-annonce-grandes-dates-saison-2020-2021\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/top-14-pro-d2-lnr-annonce-grandes-dates-saison-2020-2021\\\/\",\"name\":\"Top 14 - Pro D2 : La LNR annonce les grandes dates de la saison 2020-2021\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/top-14-pro-d2-lnr-annonce-grandes-dates-saison-2020-2021\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/top-14-pro-d2-lnr-annonce-grandes-dates-saison-2020-2021\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/Top-14-Pro-D2-Les-grandes-dates-de-la-saison-2020-2021.png\",\"datePublished\":\"2020-07-08T12:59:45+00:00\",\"dateModified\":\"2020-07-08T13:08:18+00:00\",\"description\":\"RUGBY - La F\u00e9d\u00e9ration Fran\u00e7aise de Rugby a finalement valid\u00e9 le calendrier de la Ligue Nationale de Rugby pour la saison 2020-2021 de Top 14 et Pro D2.\u00a0\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/top-14-pro-d2-lnr-annonce-grandes-dates-saison-2020-2021\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/top-14-pro-d2-lnr-annonce-grandes-dates-saison-2020-2021\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/top-14-pro-d2-lnr-annonce-grandes-dates-saison-2020-2021\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/Top-14-Pro-D2-Les-grandes-dates-de-la-saison-2020-2021.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/Top-14-Pro-D2-Les-grandes-dates-de-la-saison-2020-2021.png\",\"width\":800,\"height\":445,\"caption\":\"Top 14 - Pro D2 : les grandes dates de la saison 2020-2021\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/top-14-pro-d2-lnr-annonce-grandes-dates-saison-2020-2021\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Top 14 &#8211; Pro D2 : La LNR annonce les grandes dates de la saison 2020-2021\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/55dcb50ad410894e431ed812bbb70191\",\"name\":\"Nicolas Jacquemard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"caption\":\"Nicolas Jacquemard\"},\"description\":\"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/Nico_Jacquemard\"],\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/dicodusport\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Top 14 - Pro D2 : La LNR annonce les grandes dates de la saison 2020-2021","description":"RUGBY - La F\u00e9d\u00e9ration Fran\u00e7aise de Rugby a finalement valid\u00e9 le calendrier de la Ligue Nationale de Rugby pour la saison 2020-2021 de Top 14 et Pro D2.\u00a0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/top-14-pro-d2-lnr-annonce-grandes-dates-saison-2020-2021\/","og_locale":"fr_FR","og_type":"article","og_title":"Top 14 - Pro D2 : les grandes dates de la saison 2020-2021","og_description":"RUGBY - La F\u00e9d\u00e9ration Fran\u00e7aise de Rugby a finalement valid\u00e9 le calendrier de la Ligue Nationale de Rugby pour la saison 2020-2021 de Top 14 et Pro D2.\u00a0","og_url":"https:\/\/dicodusport.fr\/blog\/top-14-pro-d2-lnr-annonce-grandes-dates-saison-2020-2021\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2020-07-08T12:59:45+00:00","article_modified_time":"2020-07-08T13:08:18+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/07\/Top-14-Pro-D2-Les-grandes-dates-de-la-saison-2020-2021.png","type":"image\/png"}],"author":"Nicolas Jacquemard","twitter_card":"summary_large_image","twitter_title":"Top 14 - Pro D2 : les grandes dates de la saison 2020-2021","twitter_creator":"@https:\/\/twitter.com\/Nico_Jacquemard","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/top-14-pro-d2-lnr-annonce-grandes-dates-saison-2020-2021\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/top-14-pro-d2-lnr-annonce-grandes-dates-saison-2020-2021\/"},"author":{"name":"Nicolas Jacquemard","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191"},"headline":"Top 14 &#8211; Pro D2 : La LNR annonce les grandes dates de la saison 2020-2021","datePublished":"2020-07-08T12:59:45+00:00","dateModified":"2020-07-08T13:08:18+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/top-14-pro-d2-lnr-annonce-grandes-dates-saison-2020-2021\/"},"wordCount":200,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/top-14-pro-d2-lnr-annonce-grandes-dates-saison-2020-2021\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/07\/Top-14-Pro-D2-Les-grandes-dates-de-la-saison-2020-2021.png","keywords":["Pro D2","Top 14"],"articleSection":["Rugby \u00e0 XV"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/top-14-pro-d2-lnr-annonce-grandes-dates-saison-2020-2021\/#respond"]}],"copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/top-14-pro-d2-lnr-annonce-grandes-dates-saison-2020-2021\/","url":"https:\/\/dicodusport.fr\/blog\/top-14-pro-d2-lnr-annonce-grandes-dates-saison-2020-2021\/","name":"Top 14 - Pro D2 : La LNR annonce les grandes dates de la saison 2020-2021","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/top-14-pro-d2-lnr-annonce-grandes-dates-saison-2020-2021\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/top-14-pro-d2-lnr-annonce-grandes-dates-saison-2020-2021\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/07\/Top-14-Pro-D2-Les-grandes-dates-de-la-saison-2020-2021.png","datePublished":"2020-07-08T12:59:45+00:00","dateModified":"2020-07-08T13:08:18+00:00","description":"RUGBY - La F\u00e9d\u00e9ration Fran\u00e7aise de Rugby a finalement valid\u00e9 le calendrier de la Ligue Nationale de Rugby pour la saison 2020-2021 de Top 14 et Pro D2.\u00a0","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/top-14-pro-d2-lnr-annonce-grandes-dates-saison-2020-2021\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/top-14-pro-d2-lnr-annonce-grandes-dates-saison-2020-2021\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/top-14-pro-d2-lnr-annonce-grandes-dates-saison-2020-2021\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/07\/Top-14-Pro-D2-Les-grandes-dates-de-la-saison-2020-2021.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/07\/Top-14-Pro-D2-Les-grandes-dates-de-la-saison-2020-2021.png","width":800,"height":445,"caption":"Top 14 - Pro D2 : les grandes dates de la saison 2020-2021"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/top-14-pro-d2-lnr-annonce-grandes-dates-saison-2020-2021\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Top 14 &#8211; Pro D2 : La LNR annonce les grandes dates de la saison 2020-2021"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191","name":"Nicolas Jacquemard","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","caption":"Nicolas Jacquemard"},"description":"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.","sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard"],"url":"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/71093","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=71093"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/71093\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/71101"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=71093"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=71093"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=71093"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}