{"id":72177,"date":"2020-07-21T14:31:46","date_gmt":"2020-07-21T12:31:46","guid":{"rendered":"http:\/\/dicodusport.fr\/blog\/?p=72177&#038;preview=true&#038;preview_id=72177"},"modified":"2020-07-21T18:26:55","modified_gmt":"2020-07-21T16:26:55","slug":"beziers-emiratis-de-nouveau-en-piste","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/beziers-emiratis-de-nouveau-en-piste\/","title":{"rendered":"B\u00e9ziers : Les \u00c9miratis de nouveau en piste !"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>RUGBY &#8211; Apr\u00e8s avoir annonc\u00e9 <a href=\"https:\/\/dicodusport.fr\/blog\/beziers-investisseurs-emirati-lachent-affaire\/\" target=\"_blank\" rel=\"noopener noreferrer\">l&rsquo;abandon du projet de rachat du club de B\u00e9ziers<\/a>, les \u00c9miratis seraient finalement de nouveau dans le jeu concernant l&rsquo;ASBH. Selon le <a href=\"https:\/\/www.midi-olympique.fr\/2020\/07\/21\/exclusif-beziers-les-emiratis-reviennent-dans-le-danse-le-feuilleton-rebondit-8988365.php\" target=\"_blank\" rel=\"noopener noreferrer\">Midi Olympique<\/a>, une porte serait ouverte pour que la soci\u00e9t\u00e9 SOTACO International, soci\u00e9t\u00e9 des investisseurs \u00e9miratis, devienne actionnaire de la SASP ASBH.<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">On ne s&rsquo;y attendait pas. Pas maintenant en tout cas. Mais ce mardi, le <em>Midi Olympique<\/em> r\u00e9v\u00e8le que les investisseurs \u00e9miratis seraient de nouveau dans le coup pour investir au sein de l&rsquo;ASBH. <strong>Louis-Pierre Angelotti<\/strong> et <strong>Pierre-Olivier Valaize<\/strong> ayant jet\u00e9 l&rsquo;\u00e9ponge, il ne reste plus que <strong>C\u00e9dric Bistu\u00e9<\/strong> aux commandes du navire biterrois. <a href=\"https:\/\/dicodusport.fr\/blog\/beziers-recoit-avis-favorable-dnacg-reste-pro-d2\/\" target=\"_blank\" rel=\"noopener noreferrer\">Maintenue en Pro D2 par la DNACG<\/a>, l&rsquo;<strong>ASBH<\/strong> doit d\u00e9sormais assurer ses arri\u00e8res en deuxi\u00e8me division, avant de voir plus grand. Avec les investisseurs du Golfe ?<\/p>\n<h2 style=\"text-align: justify;\">Une visio-conf\u00e9rence avec Robert M\u00e9nard<\/h2>\n<p style=\"text-align: justify;\">Ce lundi, le <em>Midol<\/em> rapporte que le maire de la ville de <a href=\"https:\/\/dicodusport.fr\/blog\/tag\/beziers\/\" target=\"_blank\" rel=\"noopener noreferrer\">B\u00e9ziers<\/a>, <strong>Robert M\u00e9nard<\/strong>, a r\u00e9uni en visio-conf\u00e9rence tous les acteurs du projet initial de rachat. De celle-ci ressortirait la possibilit\u00e9 pour les investisseurs de miser plusieurs millions d&rsquo;euros dans la <strong>SASP ASBH<\/strong>, et ce d\u00e8s le mois de septembre. Une hypoth\u00e8se \u00e0 laquelle <strong>C\u00e9dric Bistu\u00e9<\/strong> ne dit pas non. Cit\u00e9e par le Midi Olympique, une source proche du dossier justifie cette d\u00e9marche.<\/p>\n<blockquote>\n<p style=\"text-align: justify;\">Ce serait le moyen de mettre un pied dans le club sans passer par une autre guerre st\u00e9rile et, pourquoi pas, d&rsquo;y apporter un regain de vitalit\u00e9 avant de vraiment prendre les choses en mains.<\/p>\n<\/blockquote>\n<p style=\"text-align: justify;\">Une premi\u00e8re \u00e9tape donc, avant une possible main mise compl\u00e8te de l\u2019institution biterroise pour <strong>SOTACO International<\/strong> et <strong>Samir Ben Romdhane<\/strong> ? Si les dirigeants actuels et les investisseurs \u00e9miratis sont pr\u00eats \u00e0 travailler main dans la main, reste \u00e0 savoir si <strong>Ren\u00e9 Bouscatel<\/strong>, annonc\u00e9 comme le futur pr\u00e9sident, sera bien de la partie. Le feuilleton de l&rsquo;\u00e9t\u00e9 n&rsquo;a pas fini de nous tenir en haleine.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">&#x1f6a8; INFO MIDI OLYMPIQUE &#x1f6a8;Cette semaine, plusieurs r\u00e9unions sont pr\u00e9vues en Biterre afin de savoir si les investisseurs des \u00c9mirats, qui viennent d&rsquo;\u00e9chouer dans leur projet de rachat de l&rsquo;ASBH, pourraient \u00e0 court terme en devenir les actionnaires.<a href=\"https:\/\/t.co\/ImaVShFOJQ\">https:\/\/t.co\/ImaVShFOJQ<\/a><\/p>\n<p>\u2014 Midi Olympique (@midi_olympique) <a href=\"https:\/\/twitter.com\/midi_olympique\/status\/1285542835866017793?ref_src=twsrc%5Etfw\">July 21, 2020<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p><strong><em>Dicodusport<br \/>\n<a href=\"https:\/\/www.facebook.com\/dicodusport\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2909\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-facebook-150x150.png\" alt=\"\" width=\"40\" height=\"40\" \/><\/a><a href=\"https:\/\/twitter.com\/dicodusport\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2908\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-twitter-150x150.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>RUGBY &#8211; Apr\u00e8s avoir annonc\u00e9 l&rsquo;abandon du projet de rachat de B\u00e9ziers, les \u00c9miratis seraient finalement de nouveau dans le jeu concernant l&rsquo;ASBH. Selon le Midi Olympique, une porte serait ouverte pour que la soci\u00e9t\u00e9 SOTACO International, soci\u00e9t\u00e9 des investisseurs \u00e9miratis, devienne actionnaire de la SASP ASBH.<\/p>\n","protected":false},"author":4,"featured_media":72178,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[9129],"tags":[10966,4514,1839],"class_list":["post-72177","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rugby-a-xv","tag-asbh","tag-beziers","tag-pro-d2"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>B\u00e9ziers : Les \u00c9miratis de nouveau en piste !<\/title>\n<meta name=\"description\" content=\"RUGBY - Apr\u00e8s avoir annonc\u00e9 l&#039;abandon du projet de rachat de B\u00e9ziers, les \u00c9miratis seraient finalement de nouveau dans le jeu concernant l&#039;ASBH.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/beziers-emiratis-de-nouveau-en-piste\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"B\u00e9ziers : Les \u00c9miratis de nouveau en piste !\" \/>\n<meta property=\"og:description\" content=\"RUGBY - Apr\u00e8s avoir annonc\u00e9 l&#039;abandon du projet de rachat de B\u00e9ziers, les \u00c9miratis seraient finalement de nouveau dans le jeu concernant l&#039;ASBH.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/beziers-emiratis-de-nouveau-en-piste\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/florent.ostermann\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-21T12:31:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-07-21T16:26:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/07\/B\u00e9ziers-Les-\u00c9miratis-de-nouveau-en-piste.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Flo Ostermann\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"B\u00e9ziers : Les \u00c9miratis de nouveau en piste !\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/FlOstermann\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/beziers-emiratis-de-nouveau-en-piste\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/beziers-emiratis-de-nouveau-en-piste\\\/\"},\"author\":{\"name\":\"Flo Ostermann\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/cb02af4c173ce4a653b55e9baf388d4a\"},\"headline\":\"B\u00e9ziers : Les \u00c9miratis de nouveau en piste !\",\"datePublished\":\"2020-07-21T12:31:46+00:00\",\"dateModified\":\"2020-07-21T16:26:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/beziers-emiratis-de-nouveau-en-piste\\\/\"},\"wordCount\":404,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/beziers-emiratis-de-nouveau-en-piste\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/B\u00e9ziers-Les-\u00c9miratis-de-nouveau-en-piste.png\",\"keywords\":[\"ASBH\",\"b\u00e9ziers\",\"Pro D2\"],\"articleSection\":[\"Rugby \u00e0 XV\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/beziers-emiratis-de-nouveau-en-piste\\\/#respond\"]}],\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/beziers-emiratis-de-nouveau-en-piste\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/beziers-emiratis-de-nouveau-en-piste\\\/\",\"name\":\"B\u00e9ziers : Les \u00c9miratis de nouveau en piste !\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/beziers-emiratis-de-nouveau-en-piste\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/beziers-emiratis-de-nouveau-en-piste\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/B\u00e9ziers-Les-\u00c9miratis-de-nouveau-en-piste.png\",\"datePublished\":\"2020-07-21T12:31:46+00:00\",\"dateModified\":\"2020-07-21T16:26:55+00:00\",\"description\":\"RUGBY - Apr\u00e8s avoir annonc\u00e9 l'abandon du projet de rachat de B\u00e9ziers, les \u00c9miratis seraient finalement de nouveau dans le jeu concernant l'ASBH.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/beziers-emiratis-de-nouveau-en-piste\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/beziers-emiratis-de-nouveau-en-piste\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/beziers-emiratis-de-nouveau-en-piste\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/B\u00e9ziers-Les-\u00c9miratis-de-nouveau-en-piste.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/B\u00e9ziers-Les-\u00c9miratis-de-nouveau-en-piste.png\",\"width\":800,\"height\":445,\"caption\":\"B\u00e9ziers : Les \u00c9miratis de nouveau en piste !\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/beziers-emiratis-de-nouveau-en-piste\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"B\u00e9ziers : Les \u00c9miratis de nouveau en piste !\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/cb02af4c173ce4a653b55e9baf388d4a\",\"name\":\"Flo Ostermann\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Flo-Ostermann-150x150.jpg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Flo-Ostermann-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Flo-Ostermann-150x150.jpg\",\"caption\":\"Flo Ostermann\"},\"description\":\"Journaliste\\\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/florent.ostermann\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/FlOstermann\",\"admin\"],\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/flo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"B\u00e9ziers : Les \u00c9miratis de nouveau en piste !","description":"RUGBY - Apr\u00e8s avoir annonc\u00e9 l'abandon du projet de rachat de B\u00e9ziers, les \u00c9miratis seraient finalement de nouveau dans le jeu concernant l'ASBH.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/beziers-emiratis-de-nouveau-en-piste\/","og_locale":"fr_FR","og_type":"article","og_title":"B\u00e9ziers : Les \u00c9miratis de nouveau en piste !","og_description":"RUGBY - Apr\u00e8s avoir annonc\u00e9 l'abandon du projet de rachat de B\u00e9ziers, les \u00c9miratis seraient finalement de nouveau dans le jeu concernant l'ASBH.","og_url":"https:\/\/dicodusport.fr\/blog\/beziers-emiratis-de-nouveau-en-piste\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/florent.ostermann","article_published_time":"2020-07-21T12:31:46+00:00","article_modified_time":"2020-07-21T16:26:55+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/07\/B\u00e9ziers-Les-\u00c9miratis-de-nouveau-en-piste.png","type":"image\/png"}],"author":"Flo Ostermann","twitter_card":"summary_large_image","twitter_title":"B\u00e9ziers : Les \u00c9miratis de nouveau en piste !","twitter_creator":"@https:\/\/twitter.com\/FlOstermann","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/beziers-emiratis-de-nouveau-en-piste\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/beziers-emiratis-de-nouveau-en-piste\/"},"author":{"name":"Flo Ostermann","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a"},"headline":"B\u00e9ziers : Les \u00c9miratis de nouveau en piste !","datePublished":"2020-07-21T12:31:46+00:00","dateModified":"2020-07-21T16:26:55+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/beziers-emiratis-de-nouveau-en-piste\/"},"wordCount":404,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/beziers-emiratis-de-nouveau-en-piste\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/07\/B\u00e9ziers-Les-\u00c9miratis-de-nouveau-en-piste.png","keywords":["ASBH","b\u00e9ziers","Pro D2"],"articleSection":["Rugby \u00e0 XV"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/beziers-emiratis-de-nouveau-en-piste\/#respond"]}],"copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/beziers-emiratis-de-nouveau-en-piste\/","url":"https:\/\/dicodusport.fr\/blog\/beziers-emiratis-de-nouveau-en-piste\/","name":"B\u00e9ziers : Les \u00c9miratis de nouveau en piste !","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/beziers-emiratis-de-nouveau-en-piste\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/beziers-emiratis-de-nouveau-en-piste\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/07\/B\u00e9ziers-Les-\u00c9miratis-de-nouveau-en-piste.png","datePublished":"2020-07-21T12:31:46+00:00","dateModified":"2020-07-21T16:26:55+00:00","description":"RUGBY - Apr\u00e8s avoir annonc\u00e9 l'abandon du projet de rachat de B\u00e9ziers, les \u00c9miratis seraient finalement de nouveau dans le jeu concernant l'ASBH.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/beziers-emiratis-de-nouveau-en-piste\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/beziers-emiratis-de-nouveau-en-piste\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/beziers-emiratis-de-nouveau-en-piste\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/07\/B\u00e9ziers-Les-\u00c9miratis-de-nouveau-en-piste.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/07\/B\u00e9ziers-Les-\u00c9miratis-de-nouveau-en-piste.png","width":800,"height":445,"caption":"B\u00e9ziers : Les \u00c9miratis de nouveau en piste !"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/beziers-emiratis-de-nouveau-en-piste\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"B\u00e9ziers : Les \u00c9miratis de nouveau en piste !"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a","name":"Flo Ostermann","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","caption":"Flo Ostermann"},"description":"Journaliste\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !","sameAs":["https:\/\/www.facebook.com\/florent.ostermann","https:\/\/x.com\/https:\/\/twitter.com\/FlOstermann","admin"],"url":"https:\/\/dicodusport.fr\/blog\/author\/flo\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/72177","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=72177"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/72177\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/72178"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=72177"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=72177"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=72177"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}