{"id":72300,"date":"2020-07-22T20:01:01","date_gmt":"2020-07-22T18:01:01","guid":{"rendered":"http:\/\/dicodusport.fr\/blog\/?p=72300&#038;preview=true&#038;preview_id=72300"},"modified":"2020-07-22T20:05:59","modified_gmt":"2020-07-22T18:05:59","slug":"dopage-georg-preidler-ecope-peine-un-an-de-prison","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/dopage-georg-preidler-ecope-peine-un-an-de-prison\/","title":{"rendered":"Dopage : Georg Preidler \u00e9cope d&rsquo;une peine d&rsquo;un an de prison avec sursis"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><b>CYCLISME &#8211; Le tribunal r\u00e9gional d&rsquo;Innsbruck a tranch\u00e9. Georg Preidler a \u00e9t\u00e9 condamn\u00e9 \u00e0 un an de prison avec sursis et d&rsquo;une amende de 2880 euros. L&rsquo;ancien coureur de la Sunweb et de la Groupama-FDJ \u00e9tait impliqu\u00e9 dans l&rsquo;affaire Aderlass, immense scandale de dopage d\u00e9mantel\u00e9 d\u00e9but 2019.<\/b><\/em><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.lequipe.fr\/Cyclisme-sur-route\/Actualites\/Dopage-quatre-ans-de-suspension-pour-georg-preidler-et-stefan-denifl\/1034255\" target=\"_blank\" rel=\"noopener noreferrer\">D\u00e9j\u00e0 condamn\u00e9 \u00e0 quatre ans de suspension<\/a> par la Commission Juridique de l&rsquo;Organisation Antidopage Autrichienne (\u00d6ADR), <strong>Georg Preidler<\/strong> conna\u00eet \u00e9galement sa sanction p\u00e9nale. Le tribunal r\u00e9gional d&rsquo;Innsbruck a condamn\u00e9 l&rsquo;ancien coureur autrichien \u00e0 un an de prison avec sursis. Avec en prime, une amende de 2880 euros. <strong>Preidler<\/strong>, 30 ans, avait admis s&rsquo;\u00eatre dop\u00e9 d\u00e8s 2018. La justice autrichienne, elle, l&rsquo;a reconnu coupable d&rsquo;avoir utilis\u00e9 des hormones de croissance d\u00e8s 2017, et d&rsquo;avoir tromp\u00e9 ses partenaires commerciaux et sportifs, dont la formation <strong>Groupama-FDJ<\/strong>.<\/p>\n<h2 style=\"text-align: justify;\">Aderlass, un r\u00e9seau organis\u00e9<\/h2>\n<p style=\"text-align: justify;\">Pour rappel, l&rsquo;affaire <strong><a href=\"https:\/\/dicodusport.fr\/blog\/dopage-echantillons-tour-de-france-2017-vont-etre-reanalyses\/\" target=\"_blank\" rel=\"noopener noreferrer\">Aderlass<\/a><\/strong> a \u00e9clat\u00e9 au tout d\u00e9but de l&rsquo;ann\u00e9e 2019. Celle-ci implique une vingtaine de sportifs europ\u00e9ens dans le cadre d&rsquo;un vaste syst\u00e8me de dopage sanguin. Dans un premier temps, les sports d&rsquo;hiver sont cibl\u00e9s. Peu de temps apr\u00e8s le d\u00e9mant\u00e8lement, le cyclisme est alors touch\u00e9 \u00e0 son tour. Outre <strong>Georg Preidler<\/strong>, <strong>Stefan Denifl<\/strong>, ex-coureur d&rsquo;IAM et de la Trek-Segafredo, a \u00e9galement \u00e9t\u00e9 condamn\u00e9 \u00e0 quatre ans de suspension.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"en\">Georg Preidler spared jail after admitting involvement in Operation Aderlass blood doping ring | <a href=\"https:\/\/t.co\/iHZZJwzy5E\">https:\/\/t.co\/iHZZJwzy5E<\/a> <a href=\"https:\/\/t.co\/3aSnFBbUUg\">pic.twitter.com\/3aSnFBbUUg<\/a><\/p>\n<p>\u2014 Cycling Weekly (@cyclingweekly) <a href=\"https:\/\/twitter.com\/cyclingweekly\/status\/1285936418951495680?ref_src=twsrc%5Etfw\">July 22, 2020<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p><strong><em>Dicodusport<br \/>\n<a href=\"https:\/\/www.facebook.com\/dicodusport\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2909\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-facebook-150x150.png\" alt=\"\" width=\"40\" height=\"40\" \/><\/a><a href=\"https:\/\/twitter.com\/dicodusport\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2908\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-twitter-150x150.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>CYCLISME &#8211; Le tribunal r\u00e9gional d&rsquo;Innsbruck a tranch\u00e9. L&rsquo;ancien cycliste autrichien Georg Preidler a \u00e9t\u00e9 condamn\u00e9 \u00e0 un an de prison avec sursis et d&rsquo;une amende de 2880 euros. L&rsquo;ancien coureur de la Sunweb et de la Groupama-FDJ \u00e9tait impliqu\u00e9 dans l&rsquo;affaire Aderlass, immense scandale de dopage en Autriche d\u00e9mantel\u00e9\u00a0d\u00e9but 2019.<\/p>\n","protected":false},"author":4,"featured_media":72305,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[2307],"tags":[574,2886],"class_list":["post-72300","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cyclisme","tag-cyclisme","tag-dopage"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Dopage : Georg Preidler \u00e9cope d&#039;une peine d&#039;un an de prison avec sursis<\/title>\n<meta name=\"description\" content=\"CYCLISME - Le tribunal r\u00e9gional d&#039;Innsbruck a tranch\u00e9. L&#039;ancien cycliste autrichien Georg Preidler a \u00e9t\u00e9 condamn\u00e9 \u00e0 un an de prison avec sursis et d&#039;une amende de 2880 euros.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/dopage-georg-preidler-ecope-peine-un-an-de-prison\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dopage : Georg Preidler \u00e9cope d&#039;une peine d&#039;un an de prison avec sursis\" \/>\n<meta property=\"og:description\" content=\"CYCLISME - Le tribunal r\u00e9gional d&#039;Innsbruck a tranch\u00e9. L&#039;ancien cycliste autrichien Georg Preidler a \u00e9t\u00e9 condamn\u00e9 \u00e0 un an de prison avec sursis et d&#039;une amende de 2880 euros.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/dopage-georg-preidler-ecope-peine-un-an-de-prison\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/florent.ostermann\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-22T18:01:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-07-22T18:05:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/07\/Dopage-Georg-Preidler-\u00e9cope-dune-peine-dun-an-de-prison-avec-sursis.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Flo Ostermann\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Dopage : Georg Preidler \u00e9cope d&#039;une peine d&#039;un an de prison avec sursis\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/FlOstermann\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/dopage-georg-preidler-ecope-peine-un-an-de-prison\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/dopage-georg-preidler-ecope-peine-un-an-de-prison\/\"},\"author\":{\"name\":\"Flo Ostermann\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a\"},\"headline\":\"Dopage : Georg Preidler \u00e9cope d&rsquo;une peine d&rsquo;un an de prison avec sursis\",\"datePublished\":\"2020-07-22T18:01:01+00:00\",\"dateModified\":\"2020-07-22T18:05:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/dopage-georg-preidler-ecope-peine-un-an-de-prison\/\"},\"wordCount\":268,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/dopage-georg-preidler-ecope-peine-un-an-de-prison\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/07\/Dopage-Georg-Preidler-\u00e9cope-dune-peine-dun-an-de-prison-avec-sursis.png\",\"keywords\":[\"Cyclisme\",\"dopage\"],\"articleSection\":[\"Cyclisme\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/dopage-georg-preidler-ecope-peine-un-an-de-prison\/#respond\"]}],\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/dopage-georg-preidler-ecope-peine-un-an-de-prison\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/dopage-georg-preidler-ecope-peine-un-an-de-prison\/\",\"name\":\"Dopage : Georg Preidler \u00e9cope d'une peine d'un an de prison avec sursis\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/dopage-georg-preidler-ecope-peine-un-an-de-prison\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/dopage-georg-preidler-ecope-peine-un-an-de-prison\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/07\/Dopage-Georg-Preidler-\u00e9cope-dune-peine-dun-an-de-prison-avec-sursis.png\",\"datePublished\":\"2020-07-22T18:01:01+00:00\",\"dateModified\":\"2020-07-22T18:05:59+00:00\",\"description\":\"CYCLISME - Le tribunal r\u00e9gional d'Innsbruck a tranch\u00e9. L'ancien cycliste autrichien Georg Preidler a \u00e9t\u00e9 condamn\u00e9 \u00e0 un an de prison avec sursis et d'une amende de 2880 euros.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/dopage-georg-preidler-ecope-peine-un-an-de-prison\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/dopage-georg-preidler-ecope-peine-un-an-de-prison\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/dopage-georg-preidler-ecope-peine-un-an-de-prison\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/07\/Dopage-Georg-Preidler-\u00e9cope-dune-peine-dun-an-de-prison-avec-sursis.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/07\/Dopage-Georg-Preidler-\u00e9cope-dune-peine-dun-an-de-prison-avec-sursis.png\",\"width\":800,\"height\":445,\"caption\":\"Dopage : Georg Preidler \u00e9cope d'une peine d'un an de prison avec sursis\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/dopage-georg-preidler-ecope-peine-un-an-de-prison\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dopage : Georg Preidler \u00e9cope d&rsquo;une peine d&rsquo;un an de prison avec sursis\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a\",\"name\":\"Flo Ostermann\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg\",\"caption\":\"Flo Ostermann\"},\"description\":\"Journaliste\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !\",\"sameAs\":[\"https:\/\/www.facebook.com\/florent.ostermann\",\"https:\/\/x.com\/https:\/\/twitter.com\/FlOstermann\",\"admin\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/flo\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Dopage : Georg Preidler \u00e9cope d'une peine d'un an de prison avec sursis","description":"CYCLISME - Le tribunal r\u00e9gional d'Innsbruck a tranch\u00e9. L'ancien cycliste autrichien Georg Preidler a \u00e9t\u00e9 condamn\u00e9 \u00e0 un an de prison avec sursis et d'une amende de 2880 euros.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/dopage-georg-preidler-ecope-peine-un-an-de-prison\/","og_locale":"fr_FR","og_type":"article","og_title":"Dopage : Georg Preidler \u00e9cope d'une peine d'un an de prison avec sursis","og_description":"CYCLISME - Le tribunal r\u00e9gional d'Innsbruck a tranch\u00e9. L'ancien cycliste autrichien Georg Preidler a \u00e9t\u00e9 condamn\u00e9 \u00e0 un an de prison avec sursis et d'une amende de 2880 euros.","og_url":"https:\/\/dicodusport.fr\/blog\/dopage-georg-preidler-ecope-peine-un-an-de-prison\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/florent.ostermann","article_published_time":"2020-07-22T18:01:01+00:00","article_modified_time":"2020-07-22T18:05:59+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/07\/Dopage-Georg-Preidler-\u00e9cope-dune-peine-dun-an-de-prison-avec-sursis.png","type":"image\/png"}],"author":"Flo Ostermann","twitter_card":"summary_large_image","twitter_title":"Dopage : Georg Preidler \u00e9cope d'une peine d'un an de prison avec sursis","twitter_creator":"@https:\/\/twitter.com\/FlOstermann","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/dopage-georg-preidler-ecope-peine-un-an-de-prison\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/dopage-georg-preidler-ecope-peine-un-an-de-prison\/"},"author":{"name":"Flo Ostermann","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a"},"headline":"Dopage : Georg Preidler \u00e9cope d&rsquo;une peine d&rsquo;un an de prison avec sursis","datePublished":"2020-07-22T18:01:01+00:00","dateModified":"2020-07-22T18:05:59+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/dopage-georg-preidler-ecope-peine-un-an-de-prison\/"},"wordCount":268,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/dopage-georg-preidler-ecope-peine-un-an-de-prison\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/07\/Dopage-Georg-Preidler-\u00e9cope-dune-peine-dun-an-de-prison-avec-sursis.png","keywords":["Cyclisme","dopage"],"articleSection":["Cyclisme"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/dopage-georg-preidler-ecope-peine-un-an-de-prison\/#respond"]}],"copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/dopage-georg-preidler-ecope-peine-un-an-de-prison\/","url":"https:\/\/dicodusport.fr\/blog\/dopage-georg-preidler-ecope-peine-un-an-de-prison\/","name":"Dopage : Georg Preidler \u00e9cope d'une peine d'un an de prison avec sursis","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/dopage-georg-preidler-ecope-peine-un-an-de-prison\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/dopage-georg-preidler-ecope-peine-un-an-de-prison\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/07\/Dopage-Georg-Preidler-\u00e9cope-dune-peine-dun-an-de-prison-avec-sursis.png","datePublished":"2020-07-22T18:01:01+00:00","dateModified":"2020-07-22T18:05:59+00:00","description":"CYCLISME - Le tribunal r\u00e9gional d'Innsbruck a tranch\u00e9. L'ancien cycliste autrichien Georg Preidler a \u00e9t\u00e9 condamn\u00e9 \u00e0 un an de prison avec sursis et d'une amende de 2880 euros.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/dopage-georg-preidler-ecope-peine-un-an-de-prison\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/dopage-georg-preidler-ecope-peine-un-an-de-prison\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/dopage-georg-preidler-ecope-peine-un-an-de-prison\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/07\/Dopage-Georg-Preidler-\u00e9cope-dune-peine-dun-an-de-prison-avec-sursis.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/07\/Dopage-Georg-Preidler-\u00e9cope-dune-peine-dun-an-de-prison-avec-sursis.png","width":800,"height":445,"caption":"Dopage : Georg Preidler \u00e9cope d'une peine d'un an de prison avec sursis"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/dopage-georg-preidler-ecope-peine-un-an-de-prison\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Dopage : Georg Preidler \u00e9cope d&rsquo;une peine d&rsquo;un an de prison avec sursis"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a","name":"Flo Ostermann","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","caption":"Flo Ostermann"},"description":"Journaliste\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !","sameAs":["https:\/\/www.facebook.com\/florent.ostermann","https:\/\/x.com\/https:\/\/twitter.com\/FlOstermann","admin"],"url":"https:\/\/dicodusport.fr\/blog\/author\/flo\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/72300","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=72300"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/72300\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/72305"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=72300"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=72300"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=72300"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}