{"id":74151,"date":"2020-08-13T10:10:00","date_gmt":"2020-08-13T08:10:00","guid":{"rendered":"http:\/\/dicodusport.fr\/blog\/?p=74151&#038;preview=true&#038;preview_id=74151"},"modified":"2020-08-13T10:22:26","modified_gmt":"2020-08-13T08:22:26","slug":"thomas-voeckler-nos-meilleurs-grimpeurs-y-pensaient-depuis-un-an-et-revaient-d-etre-champions-du-monde","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/thomas-voeckler-nos-meilleurs-grimpeurs-y-pensaient-depuis-un-an-et-revaient-d-etre-champions-du-monde\/","title":{"rendered":"Thomas Voeckler : \u00ab Nos meilleurs grimpeurs y pensaient depuis un an et r\u00eavaient d&rsquo;\u00eatre champions du monde \u00bb"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><strong>CYCLISME &#8211; Dans des propos \u00e0 l&rsquo;AFP repris par <a href=\"https:\/\/www.lequipe.fr\/Cyclisme-sur-route\/Actualites\/L-annulation-des-mondiaux-en-suisse-est-une-grosse-desillusion-pour-thomas-voeckler\/1160499\" target=\"_blank\" rel=\"noopener noreferrer\">L&rsquo;\u00c9quipe<\/a>, Thomas Voeckler revient sur <a href=\"https:\/\/dicodusport.fr\/blog\/cyclisme-mondiaux-sur-route-n-auront-pas-lieu-aigle-martigny\/\" target=\"_blank\" rel=\"noopener noreferrer\">l&rsquo;annulation des Mondiaux sur route \u00e0 Aigle-Martigny (Suisse)<\/a>, annonc\u00e9e par l&rsquo;UCI.\u00a0<\/strong><\/em><\/p>\n<p style=\"text-align: justify;\">O\u00f9 auront lieu les <strong>championnats du monde de cyclisme sur route 2020<\/strong>,\u00a0et sur quel type de parcours ? Pour le moment, aucune information ne filtre sur un possible plan de secours. L&rsquo;Union Cycliste Internationale tente en effet de trouver une solution \u00e0 quelques semaines de l&rsquo;\u00e9v\u00e9nement. <strong>Thomas Voeckler<\/strong>, s\u00e9lectionneur de l&rsquo;\u00e9quipe de France, est revenu sur cette annulation. Avec beaucoup de d\u00e9ception.<\/p>\n<blockquote>\n<p style=\"text-align: justify;\">C&rsquo;est un an de travail avec la f\u00e9d\u00e9ration sur la logistique, la pr\u00e9paration. Tout \u00e7a a \u00e9t\u00e9 balay\u00e9 en une journ\u00e9e. Nos meilleurs grimpeurs y pensaient depuis un an et r\u00eavaient d&rsquo;\u00eatre champions du monde. On ne va pas chipoter, s&rsquo;ils arrivent \u00e0 trouver un parcours pour grimpeurs, ce sera tr\u00e8s bien.<\/p>\n<\/blockquote>\n<p style=\"text-align: justify;\">Les Mondiaux \u00e9tant pr\u00e9vus du 20 au 27 septembre, l&rsquo;<strong>UCI<\/strong> a un peu plus d&rsquo;un mois pour trouver un nouveau lieu pour organiser sa comp\u00e9tition. Sous peine d&rsquo;une annulation d\u00e9finitive pour 2020.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">Cyclisme: annulation des Mondiaux en Suisse, une \u00ab\u00a0grosse d\u00e9sillusion\u00a0\u00bb pour Thomas Voeckler <a href=\"https:\/\/t.co\/NrXiEKBEa0\">https:\/\/t.co\/NrXiEKBEa0<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/AFP?src=hash&amp;ref_src=twsrc%5Etfw\">#AFP<\/a> <a href=\"https:\/\/t.co\/AcmLehrT1I\">pic.twitter.com\/AcmLehrT1I<\/a><\/p>\n<p>\u2014 AFP Sports (@AFPSport) <a href=\"https:\/\/twitter.com\/AFPSport\/status\/1293614477334716417?ref_src=twsrc%5Etfw\">August 12, 2020<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p><strong><em>Dicodusport<br \/>\n<a href=\"https:\/\/www.facebook.com\/dicodusport\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2909\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-facebook-150x150.png\" alt=\"\" width=\"40\" height=\"40\" \/><\/a><a href=\"https:\/\/twitter.com\/dicodusport\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2908\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-twitter-150x150.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>CYCLISME &#8211; Dans des propos \u00e0 l&rsquo;AFP repris par L&rsquo;\u00c9quipe, Thomas Voeckler revient sur l&rsquo;annulation des Mondiaux sur route \u00e0 Aigle-Martigny (Suisse), annonc\u00e9e par l&rsquo;UCI.\u00a0<\/p>\n","protected":false},"author":1,"featured_media":74164,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[2307],"tags":[574,5218],"class_list":["post-74151","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cyclisme","tag-cyclisme","tag-thomas-voeckler"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Thomas Voeckler : \u00ab Nos meilleurs grimpeurs y pensaient depuis un an et r\u00eavaient d&#039;\u00eatre champions du monde \u00bb<\/title>\n<meta name=\"description\" content=\"CYCLISME - Dans des propos \u00e0 l&#039;AFP repris par L&#039;\u00c9quipe, Thomas Voeckler revient sur l&#039;annulation des Mondiaux sur route \u00e0 Aigle-Martigny.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/thomas-voeckler-nos-meilleurs-grimpeurs-y-pensaient-depuis-un-an-et-revaient-d-etre-champions-du-monde\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Thomas Voeckler : \u00ab Nos meilleurs grimpeurs pensaient aux Mondiaux depuis un an \u00bb\" \/>\n<meta property=\"og:description\" content=\"CYCLISME - Dans des propos \u00e0 l&#039;AFP repris par L&#039;\u00c9quipe, Thomas Voeckler revient sur l&#039;annulation des Mondiaux sur route \u00e0 Aigle-Martigny.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/thomas-voeckler-nos-meilleurs-grimpeurs-y-pensaient-depuis-un-an-et-revaient-d-etre-champions-du-monde\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2020-08-13T08:10:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-08-13T08:22:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/08\/Thomas-Voeckler-Nos-meilleurs-grimpeurs-y-pensaient-depuis-un-an-et-r\u00eavaient-d\u00eatre-champions-du-monde.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicolas Jacquemard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Thomas Voeckler : \u00ab Nos meilleurs grimpeurs pensaient aux Mondiaux depuis un an \u00bb\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Nico_Jacquemard\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/thomas-voeckler-nos-meilleurs-grimpeurs-y-pensaient-depuis-un-an-et-revaient-d-etre-champions-du-monde\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/thomas-voeckler-nos-meilleurs-grimpeurs-y-pensaient-depuis-un-an-et-revaient-d-etre-champions-du-monde\/\"},\"author\":{\"name\":\"Nicolas Jacquemard\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\"},\"headline\":\"Thomas Voeckler : \u00ab Nos meilleurs grimpeurs y pensaient depuis un an et r\u00eavaient d&rsquo;\u00eatre champions du monde \u00bb\",\"datePublished\":\"2020-08-13T08:10:00+00:00\",\"dateModified\":\"2020-08-13T08:22:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/thomas-voeckler-nos-meilleurs-grimpeurs-y-pensaient-depuis-un-an-et-revaient-d-etre-champions-du-monde\/\"},\"wordCount\":235,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/thomas-voeckler-nos-meilleurs-grimpeurs-y-pensaient-depuis-un-an-et-revaient-d-etre-champions-du-monde\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/08\/Thomas-Voeckler-Nos-meilleurs-grimpeurs-y-pensaient-depuis-un-an-et-r\u00eavaient-d\u00eatre-champions-du-monde.png\",\"keywords\":[\"Cyclisme\",\"Thomas Voeckler\"],\"articleSection\":[\"Cyclisme\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/thomas-voeckler-nos-meilleurs-grimpeurs-y-pensaient-depuis-un-an-et-revaient-d-etre-champions-du-monde\/#respond\"]}],\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/thomas-voeckler-nos-meilleurs-grimpeurs-y-pensaient-depuis-un-an-et-revaient-d-etre-champions-du-monde\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/thomas-voeckler-nos-meilleurs-grimpeurs-y-pensaient-depuis-un-an-et-revaient-d-etre-champions-du-monde\/\",\"name\":\"Thomas Voeckler : \u00ab Nos meilleurs grimpeurs y pensaient depuis un an et r\u00eavaient d'\u00eatre champions du monde \u00bb\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/thomas-voeckler-nos-meilleurs-grimpeurs-y-pensaient-depuis-un-an-et-revaient-d-etre-champions-du-monde\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/thomas-voeckler-nos-meilleurs-grimpeurs-y-pensaient-depuis-un-an-et-revaient-d-etre-champions-du-monde\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/08\/Thomas-Voeckler-Nos-meilleurs-grimpeurs-y-pensaient-depuis-un-an-et-r\u00eavaient-d\u00eatre-champions-du-monde.png\",\"datePublished\":\"2020-08-13T08:10:00+00:00\",\"dateModified\":\"2020-08-13T08:22:26+00:00\",\"description\":\"CYCLISME - Dans des propos \u00e0 l'AFP repris par L'\u00c9quipe, Thomas Voeckler revient sur l'annulation des Mondiaux sur route \u00e0 Aigle-Martigny.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/thomas-voeckler-nos-meilleurs-grimpeurs-y-pensaient-depuis-un-an-et-revaient-d-etre-champions-du-monde\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/thomas-voeckler-nos-meilleurs-grimpeurs-y-pensaient-depuis-un-an-et-revaient-d-etre-champions-du-monde\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/thomas-voeckler-nos-meilleurs-grimpeurs-y-pensaient-depuis-un-an-et-revaient-d-etre-champions-du-monde\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/08\/Thomas-Voeckler-Nos-meilleurs-grimpeurs-y-pensaient-depuis-un-an-et-r\u00eavaient-d\u00eatre-champions-du-monde.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/08\/Thomas-Voeckler-Nos-meilleurs-grimpeurs-y-pensaient-depuis-un-an-et-r\u00eavaient-d\u00eatre-champions-du-monde.png\",\"width\":800,\"height\":445,\"caption\":\"Thomas Voeckler : Sur ce type de circuit, Julian \u00e9tait notre meilleure carte\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/thomas-voeckler-nos-meilleurs-grimpeurs-y-pensaient-depuis-un-an-et-revaient-d-etre-champions-du-monde\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Thomas Voeckler : \u00ab Nos meilleurs grimpeurs y pensaient depuis un an et r\u00eavaient d&rsquo;\u00eatre champions du monde \u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\",\"name\":\"Nicolas Jacquemard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"caption\":\"Nicolas Jacquemard\"},\"description\":\"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.\",\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Thomas Voeckler : \u00ab Nos meilleurs grimpeurs y pensaient depuis un an et r\u00eavaient d'\u00eatre champions du monde \u00bb","description":"CYCLISME - Dans des propos \u00e0 l'AFP repris par L'\u00c9quipe, Thomas Voeckler revient sur l'annulation des Mondiaux sur route \u00e0 Aigle-Martigny.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/thomas-voeckler-nos-meilleurs-grimpeurs-y-pensaient-depuis-un-an-et-revaient-d-etre-champions-du-monde\/","og_locale":"fr_FR","og_type":"article","og_title":"Thomas Voeckler : \u00ab Nos meilleurs grimpeurs pensaient aux Mondiaux depuis un an \u00bb","og_description":"CYCLISME - Dans des propos \u00e0 l'AFP repris par L'\u00c9quipe, Thomas Voeckler revient sur l'annulation des Mondiaux sur route \u00e0 Aigle-Martigny.","og_url":"https:\/\/dicodusport.fr\/blog\/thomas-voeckler-nos-meilleurs-grimpeurs-y-pensaient-depuis-un-an-et-revaient-d-etre-champions-du-monde\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2020-08-13T08:10:00+00:00","article_modified_time":"2020-08-13T08:22:26+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/08\/Thomas-Voeckler-Nos-meilleurs-grimpeurs-y-pensaient-depuis-un-an-et-r\u00eavaient-d\u00eatre-champions-du-monde.png","type":"image\/png"}],"author":"Nicolas Jacquemard","twitter_card":"summary_large_image","twitter_title":"Thomas Voeckler : \u00ab Nos meilleurs grimpeurs pensaient aux Mondiaux depuis un an \u00bb","twitter_creator":"@https:\/\/twitter.com\/Nico_Jacquemard","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/thomas-voeckler-nos-meilleurs-grimpeurs-y-pensaient-depuis-un-an-et-revaient-d-etre-champions-du-monde\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/thomas-voeckler-nos-meilleurs-grimpeurs-y-pensaient-depuis-un-an-et-revaient-d-etre-champions-du-monde\/"},"author":{"name":"Nicolas Jacquemard","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191"},"headline":"Thomas Voeckler : \u00ab Nos meilleurs grimpeurs y pensaient depuis un an et r\u00eavaient d&rsquo;\u00eatre champions du monde \u00bb","datePublished":"2020-08-13T08:10:00+00:00","dateModified":"2020-08-13T08:22:26+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/thomas-voeckler-nos-meilleurs-grimpeurs-y-pensaient-depuis-un-an-et-revaient-d-etre-champions-du-monde\/"},"wordCount":235,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/thomas-voeckler-nos-meilleurs-grimpeurs-y-pensaient-depuis-un-an-et-revaient-d-etre-champions-du-monde\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/08\/Thomas-Voeckler-Nos-meilleurs-grimpeurs-y-pensaient-depuis-un-an-et-r\u00eavaient-d\u00eatre-champions-du-monde.png","keywords":["Cyclisme","Thomas Voeckler"],"articleSection":["Cyclisme"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/thomas-voeckler-nos-meilleurs-grimpeurs-y-pensaient-depuis-un-an-et-revaient-d-etre-champions-du-monde\/#respond"]}],"copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/thomas-voeckler-nos-meilleurs-grimpeurs-y-pensaient-depuis-un-an-et-revaient-d-etre-champions-du-monde\/","url":"https:\/\/dicodusport.fr\/blog\/thomas-voeckler-nos-meilleurs-grimpeurs-y-pensaient-depuis-un-an-et-revaient-d-etre-champions-du-monde\/","name":"Thomas Voeckler : \u00ab Nos meilleurs grimpeurs y pensaient depuis un an et r\u00eavaient d'\u00eatre champions du monde \u00bb","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/thomas-voeckler-nos-meilleurs-grimpeurs-y-pensaient-depuis-un-an-et-revaient-d-etre-champions-du-monde\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/thomas-voeckler-nos-meilleurs-grimpeurs-y-pensaient-depuis-un-an-et-revaient-d-etre-champions-du-monde\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/08\/Thomas-Voeckler-Nos-meilleurs-grimpeurs-y-pensaient-depuis-un-an-et-r\u00eavaient-d\u00eatre-champions-du-monde.png","datePublished":"2020-08-13T08:10:00+00:00","dateModified":"2020-08-13T08:22:26+00:00","description":"CYCLISME - Dans des propos \u00e0 l'AFP repris par L'\u00c9quipe, Thomas Voeckler revient sur l'annulation des Mondiaux sur route \u00e0 Aigle-Martigny.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/thomas-voeckler-nos-meilleurs-grimpeurs-y-pensaient-depuis-un-an-et-revaient-d-etre-champions-du-monde\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/thomas-voeckler-nos-meilleurs-grimpeurs-y-pensaient-depuis-un-an-et-revaient-d-etre-champions-du-monde\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/thomas-voeckler-nos-meilleurs-grimpeurs-y-pensaient-depuis-un-an-et-revaient-d-etre-champions-du-monde\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/08\/Thomas-Voeckler-Nos-meilleurs-grimpeurs-y-pensaient-depuis-un-an-et-r\u00eavaient-d\u00eatre-champions-du-monde.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/08\/Thomas-Voeckler-Nos-meilleurs-grimpeurs-y-pensaient-depuis-un-an-et-r\u00eavaient-d\u00eatre-champions-du-monde.png","width":800,"height":445,"caption":"Thomas Voeckler : Sur ce type de circuit, Julian \u00e9tait notre meilleure carte"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/thomas-voeckler-nos-meilleurs-grimpeurs-y-pensaient-depuis-un-an-et-revaient-d-etre-champions-du-monde\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Thomas Voeckler : \u00ab Nos meilleurs grimpeurs y pensaient depuis un an et r\u00eavaient d&rsquo;\u00eatre champions du monde \u00bb"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191","name":"Nicolas Jacquemard","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","caption":"Nicolas Jacquemard"},"description":"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.","sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard"],"url":"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/74151","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=74151"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/74151\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/74164"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=74151"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=74151"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=74151"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}