{"id":75189,"date":"2020-08-22T16:15:05","date_gmt":"2020-08-22T14:15:05","guid":{"rendered":"http:\/\/dicodusport.fr\/blog\/?p=75189&#038;preview=true&#038;preview_id=75189"},"modified":"2021-05-11T17:10:24","modified_gmt":"2021-05-11T15:10:24","slug":"nrl-pronostic-pour-newcastle-knights-north-queensland-cowboys","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/nrl-pronostic-pour-newcastle-knights-north-queensland-cowboys\/","title":{"rendered":"NRL : notre pronostic pour Newcastle Knights &#8211; North Queensland Cowboys"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>NRL &#8211; Les Newcastle Knights re\u00e7oivent les North Queensland Cowboys pour cl\u00f4turer la 15\u00e8me journ\u00e9e. Notre pronostic pour cette rencontre.<\/em><\/strong><\/p>\n<h2 style=\"text-align: justify;\"><span style=\"font-family: -apple-system, BlinkMacSystemFont, 'Segoe UI', Roboto, Oxygen-Sans, Ubuntu, Cantarell, 'Helvetica Neue', sans-serif;\">Newcastle Knights &#8211; North Queensland Cowboys : Dimanche 23 ao\u00fbt, 8h05<\/span><\/h2>\n<p style=\"text-align: justify;\">Les Knights restent sur une prestation moyenne face aux Sea Eagles, mais la victoire est au bout gr\u00e2ce notamment \u00e0 leur star Kalyn Ponga. Newcastle continue d&rsquo;alterner des bonnes performances et des moins bonnes mais gagne malgr\u00e9 tout, ce qui n&rsquo;\u00e9tait pas le cas avant.<\/p>\n<p style=\"text-align: justify;\">De leur c\u00f4t\u00e9, les Cowboys pourront avoir des regrets sur leur derni\u00e8re d\u00e9faite face aux Rabbitohs. Apr\u00e8s avoir men\u00e9 \u00e0 quelques minutes de la fin du match, une erreur de Feldt leur a co\u00fbt\u00e9 la victoire. Newcastle, battu par le North Queensland il y a quelques semaines, a une revanche \u00e0 prendre et des points \u00e0 aller chercher pour assurer une bonne place au classement. <strong>Victoire des Knights.<\/strong><\/p>\n<table style=\"width: 100%;\">\n<tbody>\n<tr style=\"height: 16px;\">\n<td style=\"background-color: #404040; width: 70%; text-align: left; border-color: #ededed;\"><span style=\"font-size: 12px; color: #ffffff;\">Dimanche 23 ao\u00fbt, 08h05<br \/>\n<\/span><\/td>\n<td style=\"background-color: #525252; width: 10%; border-color: #ededed; text-align: center;\"><span style=\"font-size: 12px; color: #ffffff;\">1<\/span><\/td>\n<td style=\"background-color: #525252; width: 10%; border-color: #ededed; text-align: center;\"><span style=\"font-size: 12px; color: #ffffff;\">N<\/span><\/td>\n<td style=\"background-color: #525252; width: 10%; border-color: #ededed; text-align: center;\"><span style=\"font-size: 12px; color: #ffffff;\">2<\/span><\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"background-color: #ffffff; text-align: justify; border-color: #ededed; vertical-align: middle;\"><strong>Newcastle Knights &#8211; North Queensland Cowboys<br \/>\n<\/strong><\/td>\n<td style=\"background-color: #ffffff; border-color: #ededed; vertical-align: middle; text-align: center;\"><span style=\"font-size: 10px;\"><a href=\"https:\/\/www.winamax.fr\/paris-sportifs\/match\/prelive\/22085735?banid=33423\" class=\"su-button su-button-style-flat\" style=\"color:#FFFFFF;background-color:#0057ae;border-color:#00468c;border-radius:5px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#FFFFFF;padding:0px 16px;font-size:13px;line-height:26px;border-color:#4d8ac7;border-radius:5px;text-shadow:none\"> 1.30<\/span><\/a><\/span><\/td>\n<td style=\"background-color: #ffffff; border-color: #ededed; vertical-align: middle; text-align: center;\"><span style=\"font-size: 10px;\"><a href=\"https:\/\/www.winamax.fr\/paris-sportifs\/match\/prelive\/22085735?banid=33423\" class=\"su-button su-button-style-flat\" style=\"color:#FFFFFF;background-color:#b10e12;border-color:#8e0c0f;border-radius:5px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#FFFFFF;padding:0px 16px;font-size:13px;line-height:26px;border-color:#c9575a;border-radius:5px;text-shadow:none\"> 28<\/span><\/a><\/span><\/td>\n<td style=\"background-color: #ffffff; border-color: #ededed; vertical-align: middle; text-align: center;\"><span style=\"font-size: 10px;\"><a href=\"https:\/\/www.winamax.fr\/paris-sportifs\/match\/prelive\/22085735?banid=33423\" class=\"su-button su-button-style-flat\" style=\"color:#FFFFFF;background-color:#b10e12;border-color:#8e0c0f;border-radius:5px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#FFFFFF;padding:0px 16px;font-size:13px;line-height:26px;border-color:#c9575a;border-radius:5px;text-shadow:none\"> 3.75<\/span><\/a><\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p style=\"text-align: justify;\"><span style=\"font-family: -apple-system, BlinkMacSystemFont, 'Segoe UI', Roboto, Oxygen-Sans, Ubuntu, Cantarell, 'Helvetica Neue', sans-serif; font-size: 16px;\">Tentez votre chance en misant jusqu\u2019\u00e0 100\u20ac gr\u00e2ce \u00e0 votre\u00a0<\/span><a style=\"font-family: -apple-system, BlinkMacSystemFont, 'Segoe UI', Roboto, Oxygen-Sans, Ubuntu, Cantarell, 'Helvetica Neue', sans-serif; font-size: 16px;\" href=\"https:\/\/www.winamax.fr\/landing\/landing_leads.php?ldg=1er-pari-rembourse&amp;banid=33423\" target=\"_blank\" rel=\"noopener noreferrer\">premier pari rembours\u00e9<\/a><span style=\"font-family: -apple-system, BlinkMacSystemFont, 'Segoe UI', Roboto, Oxygen-Sans, Ubuntu, Cantarell, 'Helvetica Neue', sans-serif; font-size: 16px;\">.<\/span><\/p>\n<ul style=\"text-align: justify;\">\n<li style=\"text-align: justify;\"><strong>\u00c0 lire aussi &#8211; <a href=\"https:\/\/treizemondial.fr\/nos-pronostics-pour-la-15eme-journee-de-nrl-2020\/\" target=\"_blank\" rel=\"noopener noreferrer\">NRL &#8211; 15\u00e8me round : les pronostics de Treize Mondial<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\"><strong><em>Dicodusport<br \/>\n<a href=\"https:\/\/www.facebook.com\/dicodusport\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2909\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-facebook-150x150.png\" sizes=\"auto, (max-width: 40px) 100vw, 40px\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-facebook-150x150.png 150w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-facebook-300x300.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-facebook.png 400w\" alt=\"\" width=\"40\" height=\"40\" \/><\/a><a href=\"https:\/\/twitter.com\/dicodusport\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2908\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-twitter-150x150.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>NRL &#8211; Les Newcastle Knights re\u00e7oivent les North Queensland Cowboys pour cl\u00f4turer la 15\u00e8me journ\u00e9e. Notre pronostic pour cette rencontre.<\/p>\n","protected":false},"author":1,"featured_media":75229,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[9128],"tags":[11025,10916,4146],"class_list":["post-75189","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rugby-a-xiii","tag-cowboys","tag-knights","tag-nrl"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>NRL : notre pronostic pour Newcastle Knights - North Queensland Cowboys - Dicodusport<\/title>\n<meta name=\"description\" content=\"NRL - Les Newcastle Knights re\u00e7oivent les North Queensland Cowboys pour cl\u00f4turer la 15\u00e8me journ\u00e9e. Notre pronostic pour cette rencontre.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/nrl-pronostic-pour-newcastle-knights-north-queensland-cowboys\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"NRL : notre pronostic pour Newcastle Knights - North Queensland Cowboys\" \/>\n<meta property=\"og:description\" content=\"NRL - Les Newcastle Knights re\u00e7oivent les North Queensland Cowboys pour cl\u00f4turer la 15\u00e8me journ\u00e9e. Notre pronostic pour cette rencontre.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/nrl-pronostic-pour-newcastle-knights-north-queensland-cowboys\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2020-08-22T14:15:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-05-11T15:10:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/08\/NRL-Notre-pronostic-pour-Newcastle-Knights-North-Queensland-Cowboys.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"670\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicolas Jacquemard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"NRL : notre pronostic pour Newcastle Knights - North Queensland Cowboys\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Nico_Jacquemard\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/nrl-pronostic-pour-newcastle-knights-north-queensland-cowboys\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/nrl-pronostic-pour-newcastle-knights-north-queensland-cowboys\\\/\"},\"author\":{\"name\":\"Nicolas Jacquemard\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/55dcb50ad410894e431ed812bbb70191\"},\"headline\":\"NRL : notre pronostic pour Newcastle Knights &#8211; North Queensland Cowboys\",\"datePublished\":\"2020-08-22T14:15:05+00:00\",\"dateModified\":\"2021-05-11T15:10:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/nrl-pronostic-pour-newcastle-knights-north-queensland-cowboys\\\/\"},\"wordCount\":261,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/nrl-pronostic-pour-newcastle-knights-north-queensland-cowboys\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/NRL-Notre-pronostic-pour-Newcastle-Knights-North-Queensland-Cowboys.png\",\"keywords\":[\"Cowboys\",\"Knights\",\"NRL\"],\"articleSection\":[\"Rugby \u00e0 XIII\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/nrl-pronostic-pour-newcastle-knights-north-queensland-cowboys\\\/#respond\"]}],\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/nrl-pronostic-pour-newcastle-knights-north-queensland-cowboys\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/nrl-pronostic-pour-newcastle-knights-north-queensland-cowboys\\\/\",\"name\":\"NRL : notre pronostic pour Newcastle Knights - North Queensland Cowboys - Dicodusport\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/nrl-pronostic-pour-newcastle-knights-north-queensland-cowboys\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/nrl-pronostic-pour-newcastle-knights-north-queensland-cowboys\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/NRL-Notre-pronostic-pour-Newcastle-Knights-North-Queensland-Cowboys.png\",\"datePublished\":\"2020-08-22T14:15:05+00:00\",\"dateModified\":\"2021-05-11T15:10:24+00:00\",\"description\":\"NRL - Les Newcastle Knights re\u00e7oivent les North Queensland Cowboys pour cl\u00f4turer la 15\u00e8me journ\u00e9e. Notre pronostic pour cette rencontre.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/nrl-pronostic-pour-newcastle-knights-north-queensland-cowboys\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/nrl-pronostic-pour-newcastle-knights-north-queensland-cowboys\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/nrl-pronostic-pour-newcastle-knights-north-queensland-cowboys\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/NRL-Notre-pronostic-pour-Newcastle-Knights-North-Queensland-Cowboys.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/NRL-Notre-pronostic-pour-Newcastle-Knights-North-Queensland-Cowboys.png\",\"width\":1200,\"height\":670,\"caption\":\"NRL - Notre pronostic pour Newcastle Knights - North Queensland Cowboys\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/nrl-pronostic-pour-newcastle-knights-north-queensland-cowboys\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"NRL : notre pronostic pour Newcastle Knights &#8211; North Queensland Cowboys\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/55dcb50ad410894e431ed812bbb70191\",\"name\":\"Nicolas Jacquemard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"caption\":\"Nicolas Jacquemard\"},\"description\":\"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/Nico_Jacquemard\"],\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/dicodusport\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"NRL : notre pronostic pour Newcastle Knights - North Queensland Cowboys - Dicodusport","description":"NRL - Les Newcastle Knights re\u00e7oivent les North Queensland Cowboys pour cl\u00f4turer la 15\u00e8me journ\u00e9e. Notre pronostic pour cette rencontre.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/nrl-pronostic-pour-newcastle-knights-north-queensland-cowboys\/","og_locale":"fr_FR","og_type":"article","og_title":"NRL : notre pronostic pour Newcastle Knights - North Queensland Cowboys","og_description":"NRL - Les Newcastle Knights re\u00e7oivent les North Queensland Cowboys pour cl\u00f4turer la 15\u00e8me journ\u00e9e. Notre pronostic pour cette rencontre.","og_url":"https:\/\/dicodusport.fr\/blog\/nrl-pronostic-pour-newcastle-knights-north-queensland-cowboys\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2020-08-22T14:15:05+00:00","article_modified_time":"2021-05-11T15:10:24+00:00","og_image":[{"width":1200,"height":670,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/08\/NRL-Notre-pronostic-pour-Newcastle-Knights-North-Queensland-Cowboys.png","type":"image\/png"}],"author":"Nicolas Jacquemard","twitter_card":"summary_large_image","twitter_title":"NRL : notre pronostic pour Newcastle Knights - North Queensland Cowboys","twitter_creator":"@https:\/\/twitter.com\/Nico_Jacquemard","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/nrl-pronostic-pour-newcastle-knights-north-queensland-cowboys\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/nrl-pronostic-pour-newcastle-knights-north-queensland-cowboys\/"},"author":{"name":"Nicolas Jacquemard","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191"},"headline":"NRL : notre pronostic pour Newcastle Knights &#8211; North Queensland Cowboys","datePublished":"2020-08-22T14:15:05+00:00","dateModified":"2021-05-11T15:10:24+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/nrl-pronostic-pour-newcastle-knights-north-queensland-cowboys\/"},"wordCount":261,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/nrl-pronostic-pour-newcastle-knights-north-queensland-cowboys\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/08\/NRL-Notre-pronostic-pour-Newcastle-Knights-North-Queensland-Cowboys.png","keywords":["Cowboys","Knights","NRL"],"articleSection":["Rugby \u00e0 XIII"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/nrl-pronostic-pour-newcastle-knights-north-queensland-cowboys\/#respond"]}],"copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/nrl-pronostic-pour-newcastle-knights-north-queensland-cowboys\/","url":"https:\/\/dicodusport.fr\/blog\/nrl-pronostic-pour-newcastle-knights-north-queensland-cowboys\/","name":"NRL : notre pronostic pour Newcastle Knights - North Queensland Cowboys - Dicodusport","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/nrl-pronostic-pour-newcastle-knights-north-queensland-cowboys\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/nrl-pronostic-pour-newcastle-knights-north-queensland-cowboys\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/08\/NRL-Notre-pronostic-pour-Newcastle-Knights-North-Queensland-Cowboys.png","datePublished":"2020-08-22T14:15:05+00:00","dateModified":"2021-05-11T15:10:24+00:00","description":"NRL - Les Newcastle Knights re\u00e7oivent les North Queensland Cowboys pour cl\u00f4turer la 15\u00e8me journ\u00e9e. Notre pronostic pour cette rencontre.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/nrl-pronostic-pour-newcastle-knights-north-queensland-cowboys\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/nrl-pronostic-pour-newcastle-knights-north-queensland-cowboys\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/nrl-pronostic-pour-newcastle-knights-north-queensland-cowboys\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/08\/NRL-Notre-pronostic-pour-Newcastle-Knights-North-Queensland-Cowboys.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/08\/NRL-Notre-pronostic-pour-Newcastle-Knights-North-Queensland-Cowboys.png","width":1200,"height":670,"caption":"NRL - Notre pronostic pour Newcastle Knights - North Queensland Cowboys"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/nrl-pronostic-pour-newcastle-knights-north-queensland-cowboys\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"NRL : notre pronostic pour Newcastle Knights &#8211; North Queensland Cowboys"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191","name":"Nicolas Jacquemard","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","caption":"Nicolas Jacquemard"},"description":"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.","sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard"],"url":"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/75189","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=75189"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/75189\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/75229"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=75189"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=75189"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=75189"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}