{"id":75887,"date":"2020-09-08T05:10:13","date_gmt":"2020-09-08T03:10:13","guid":{"rendered":"http:\/\/dicodusport.fr\/blog\/?p=75887&#038;preview=true&#038;preview_id=75887"},"modified":"2020-09-13T00:14:13","modified_gmt":"2020-09-12T22:14:13","slug":"us-open-2020-le-tableau-dames","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/us-open-2020-le-tableau-dames\/","title":{"rendered":"US Open 2020 : le tableau dames"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><b>La particuli\u00e8re 140e \u00e9dition du tournoi de l\u2019US Open 2020 se d\u00e9roulera du 31 ao\u00fbt au 13 septembre. Qui succ\u00e9dera\u00a0\u00e0 Bianca Andreescu qui ne sera pas l\u00e0 pour d\u00e9fendre sa couronne ?<\/b><\/em><\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/dicodusport.fr\/blog\/us-open-naomi-osaka-renverse-victoria-azarenka-en-finale\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Naomi Osaka s&rsquo;est impos\u00e9e 1-6 6-3 6-3 en finale face \u00e0 Victoria Azarenka.<\/strong><\/a><\/p>\n<p>La liste des absentes est longue avec pas moins de <strong>27 forfaits<\/strong> dont <strong>6 membres du Top 10<\/strong> ! Seront notamment absentes la tenante du titre <strong>Bianca Andreescu<\/strong> (n\u00b06) qui estime ne pas avoir pu se pr\u00e9parer correctement en raison de la pand\u00e9mie, la num\u00e9ro 1 mondiale <strong>Ashleigh Barty<\/strong>, <strong>Simona Halep<\/strong> (n\u00b02), <strong>Elina Svitolina<\/strong> (n\u00b05), <strong>Kiki Bertens<\/strong> (n\u00b07) et <strong>Belinda Bencic<\/strong> (n\u00b08). Vainqueur du tournoi de Palerme, la Fran\u00e7aise <a href=\"http:\/\/dicodusport.fr\/blog\/palerme-deuxieme-titre-wta-pour-fiona-ferro\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Fiona Ferro<\/strong><\/a> ne sera pas de la partie. Touch\u00e9e \u00e0 une c\u00f4te, elle avait d\u00e9clar\u00e9 forfait pour le tournoi de Prague.<\/p>\n<p style=\"text-align: justify;\">Avec tous ces forfaits, on pourrait voir pour la quatri\u00e8me ann\u00e9e cons\u00e9cutive une joueuse sacr\u00e9e sur un Grand Chelem pour la premi\u00e8re fois. Mais elles sont \u00e9galement nombreuses \u00e0 vouloir ajouter une nouvelle ligne \u00e0 leur palmar\u00e8s.<\/p>\n<p style=\"text-align: justify;\">\u00c7a ne sera pas encore cette ann\u00e9e pour la t\u00eate de s\u00e9rie n\u00b01 <strong>Karolina Pliskova<\/strong> qui r\u00eave de gagner son premier tournoi du Grand Chelem. Si elle a facilement dispos\u00e9 d&rsquo;Anhelina Kalinina (6-4 6-0), elle n&rsquo;a rien pu faire face \u00e0 Caroline Garcia au deuxi\u00e8me tour.<\/p>\n<p>Vainqueur de l&rsquo;Open d&rsquo;Australie, <strong>Sofia Kenin<\/strong> ne remportera pas son deuxi\u00e8me majeur \u00e0 domicile cette ann\u00e9e. Victorieuse face \u00e0 Yanina Wickmayer, Leylah Fernandez puis face \u00e0 Ons Jabeur, elle a c\u00e9d\u00e9 face \u00e0 Elise Mertens en deux sets secs 3-6 3-6.<\/p>\n<p style=\"text-align: justify;\">Le tableau s&rsquo;est d\u00e9gag\u00e9 pour la laur\u00e9ate 2018 <strong>Naomi Osaka<\/strong> qui a eu besoin de 3 sets (6-2 5-7 6-2) pour se d\u00e9faire de sa compatriote Misaki Doi mais qui n&rsquo;a pas perdu de temps face \u00e0 Giorgi (6-1 6-2). Au troisi\u00e8me tour elle a battu Kostyuk 6-3 6-7[4] 6-2 et Kontavait en huiti\u00e8mes : 6-3 6-4. En quart de finale, elle a battu <strong>Shelby Rogers<\/strong>, tombeuse de Kvitova et l&rsquo;Am\u00e9ricaine Brady en demi-finale.<\/p>\n<p style=\"text-align: justify;\"><strong>Serena Williams<\/strong> vise toujours le record de Margaret Court mais elle n&rsquo;est plus la joueuse ultra-dominante d&rsquo;antan et elle devra s&#8217;employer pour remporter un <strong>7e US Open<\/strong>. Elle a bien d\u00e9but\u00e9 face \u00e0 sa compatriote Kristie Ahn (7-5 6-3) puis face \u00e0 Gasparyan (6-2 6-4). Elle a fait le dos rond face \u00e0 Sloane Stephens pour finalement s&rsquo;imposer 2-6 6-2 6-2 au troisi\u00e8me tour. Elle a pris sa revanche face \u00e0 Sakkari qui l&rsquo;avait \u00e9limin\u00e9e en huiti\u00e8mes de finale \u00e0 Cincinnati. : 6-3 6-7[6] 6-3. Nouveau combat remport\u00e9 en quart de finale en trois sets face \u00e0 Pironkova. Elle a craqu\u00e9 en demi-finale face \u00e0 Azarenka 6-1 3-6 3-6.<\/p>\n<p style=\"text-align: justify;\"><strong>Kim Clijsters<\/strong> qui a re\u00e7u une wild-card s&rsquo;est inclin\u00e9e au premier tour en trois sets face \u00e0 la Russe Ekaterina Alexandrova, t\u00eate de s\u00e9rie n\u00b021 6-3 5-7 1-6.<\/p>\n<h2 style=\"text-align: justify;\">Le tirage des Fran\u00e7aises<\/h2>\n<p style=\"text-align: justify;\"><strong>Aliz\u00e9 Cornet<\/strong> s&rsquo;est impos\u00e9e face \u00e0 Lauren Davis 6-3 1-6 6-0 puis Ysaline Bonaventure (7-6[4] 6-3) qui avait fait tomber Zhang. Derni\u00e8re rescap\u00e9e Fran\u00e7aise, elle a poursuivi son aventure gr\u00e2ce \u00e0 l&rsquo;abandon sur blessure de Madison Keys, alors que la Fran\u00e7aise menait 7-6[4] 3-2. Apr\u00e8s 2h53 et malgr\u00e9 une combativit\u00e9 exemplaire, la Fran\u00e7aise s&rsquo;est inclin\u00e9e 4-6 7-6[5] 3-6 face \u00e0 Pironkova, tombeuse de Muguruza et Vekic.<\/p>\n<p style=\"text-align: justify;\">Pour son retour en Grand Chelem, <strong>Oc\u00e9ane Dodin<\/strong> s&rsquo;est inclin\u00e9e 6-7[1] 4-6 face \u00e0 la t\u00eate de s\u00e9rie n\u00b05 Aryna Sabalenka.<\/p>\n<p style=\"text-align: justify;\">Alors qu&rsquo;elle menait 6-1 6-1 et qu&rsquo;elle a eu 4 balles de match, Kristina<strong> Mladenovic<\/strong> s&rsquo;est inclin\u00e9e au deuxi\u00e8me tour face \u00e0 Gracheva (6-1 6-7[2] 0-6).<\/p>\n<p style=\"text-align: justify;\"><strong>Caroline Garcia<\/strong> s&rsquo;est impos\u00e9e 6-3 6-2 face \u00e0 Jasmine Paolini et a \u00e9t\u00e9 incroyable face \u00e0 la n\u00b03 mondiale, t\u00eate de s\u00e9rie n\u00b01 Karolina Pliskova : victoire 6-1 7-6[2]. Elle n&rsquo;a malheureusement pas confirm\u00e9 face \u00e0 l&rsquo;Am\u00e9ricaine Brady : d\u00e9faite 3-6 3-6.<\/p>\n<p><strong><a href=\"https:\/\/www.usopen.org\/en_US\/draws\/index.html?event=WS\" target=\"_blank\" rel=\"noopener noreferrer\">Le tableau complet<\/a><\/strong><\/p>\n<p><strong><em>Arlette<br \/>\n<a href=\"https:\/\/twitter.com\/Shiclette94\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2908\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-twitter-150x150.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La particuli\u00e8re 140e \u00e9dition du tournoi de l\u2019US Open 2020 se d\u00e9roulera du 31 ao\u00fbt au 13 septembre. Qui succ\u00e9dera \u00e0 Bianca Andreescu qui ne sera pas l\u00e0 pour d\u00e9fendre sa couronne ?<\/p>\n","protected":false},"author":12,"featured_media":75889,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[2302],"tags":[8567,8571,1463,137],"class_list":["post-75887","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tennis","tag-flushing-meadows","tag-simple-dames-us-open","tag-us-open","tag-wta"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>US Open 2020 : le tableau dames<\/title>\n<meta name=\"description\" content=\"La particuli\u00e8re 140e \u00e9dition du tournoi de l\u2019US Open 2020 se d\u00e9roulera du 31 ao\u00fbt au 13 septembre. Qui succ\u00e9dera \u00e0 Bianca Andreescu ?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/us-open-2020-le-tableau-dames\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"US Open 2020 : le tableau dames\" \/>\n<meta property=\"og:description\" content=\"La particuli\u00e8re 140e \u00e9dition du tournoi de l\u2019US Open 2020 se d\u00e9roulera du 31 ao\u00fbt au 13 septembre. Qui succ\u00e9dera \u00e0 Bianca Andreescu ?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/us-open-2020-le-tableau-dames\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-08T03:10:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-09-12T22:14:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/08\/c_NaomiCincyServe.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Arlette Yeye\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"US Open 2020 : le tableau dames\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Shiclette94\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/us-open-2020-le-tableau-dames\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/us-open-2020-le-tableau-dames\/\"},\"author\":{\"name\":\"Arlette Yeye\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cce96fa88785bd8573e3d43078ac8c79\"},\"headline\":\"US Open 2020 : le tableau dames\",\"datePublished\":\"2020-09-08T03:10:13+00:00\",\"dateModified\":\"2020-09-12T22:14:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/us-open-2020-le-tableau-dames\/\"},\"wordCount\":683,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/us-open-2020-le-tableau-dames\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/08\/c_NaomiCincyServe.jpg\",\"keywords\":[\"Flushing Meadows\",\"simple dames US Open\",\"US Open\",\"wta\"],\"articleSection\":[\"Tennis\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/us-open-2020-le-tableau-dames\/#respond\"]}],\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/us-open-2020-le-tableau-dames\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/us-open-2020-le-tableau-dames\/\",\"name\":\"US Open 2020 : le tableau dames\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/us-open-2020-le-tableau-dames\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/us-open-2020-le-tableau-dames\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/08\/c_NaomiCincyServe.jpg\",\"datePublished\":\"2020-09-08T03:10:13+00:00\",\"dateModified\":\"2020-09-12T22:14:13+00:00\",\"description\":\"La particuli\u00e8re 140e \u00e9dition du tournoi de l\u2019US Open 2020 se d\u00e9roulera du 31 ao\u00fbt au 13 septembre. Qui succ\u00e9dera \u00e0 Bianca Andreescu ?\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/us-open-2020-le-tableau-dames\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/us-open-2020-le-tableau-dames\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/us-open-2020-le-tableau-dames\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/08\/c_NaomiCincyServe.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/08\/c_NaomiCincyServe.jpg\",\"width\":800,\"height\":440},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/us-open-2020-le-tableau-dames\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"US Open 2020 : le tableau dames\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cce96fa88785bd8573e3d43078ac8c79\",\"name\":\"Arlette Yeye\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/dca4a6239e6d708e46c45d60e160de6c?s=96&d=wp_user_avatar&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/dca4a6239e6d708e46c45d60e160de6c?s=96&d=wp_user_avatar&r=g\",\"caption\":\"Arlette Yeye\"},\"description\":\"Journaliste\/r\u00e9dactrice depuis septembre 2015 - Supportrice de Chelsea, j'ai pour sports de pr\u00e9dilection le handball, l'athl\u00e9tisme et le tennis. Si je tweete plus vite que mon ombre, vous pouvez aussi me retrouver les week-ends sur les playgrounds de Bruxelles pour un petit foot ou basket entre potes. Parcourir la France, l'Europe et plus si affinit\u00e9s pour suivre mes sportifs pr\u00e9f\u00e9r\u00e9s ? Mon kif ! Et c'est avec plaisir que je partage les r\u00e9sultats des sports populaires mais \u00e9galement plus confidentiels pour Dicodusport.\",\"sameAs\":[\"https:\/\/x.com\/https:\/\/twitter.com\/Shiclette94\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/arlette\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"US Open 2020 : le tableau dames","description":"La particuli\u00e8re 140e \u00e9dition du tournoi de l\u2019US Open 2020 se d\u00e9roulera du 31 ao\u00fbt au 13 septembre. Qui succ\u00e9dera \u00e0 Bianca Andreescu ?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/us-open-2020-le-tableau-dames\/","og_locale":"fr_FR","og_type":"article","og_title":"US Open 2020 : le tableau dames","og_description":"La particuli\u00e8re 140e \u00e9dition du tournoi de l\u2019US Open 2020 se d\u00e9roulera du 31 ao\u00fbt au 13 septembre. Qui succ\u00e9dera \u00e0 Bianca Andreescu ?","og_url":"https:\/\/dicodusport.fr\/blog\/us-open-2020-le-tableau-dames\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2020-09-08T03:10:13+00:00","article_modified_time":"2020-09-12T22:14:13+00:00","og_image":[{"width":800,"height":440,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/08\/c_NaomiCincyServe.jpg","type":"image\/jpeg"}],"author":"Arlette Yeye","twitter_card":"summary_large_image","twitter_title":"US Open 2020 : le tableau dames","twitter_creator":"@https:\/\/twitter.com\/Shiclette94","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/us-open-2020-le-tableau-dames\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/us-open-2020-le-tableau-dames\/"},"author":{"name":"Arlette Yeye","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cce96fa88785bd8573e3d43078ac8c79"},"headline":"US Open 2020 : le tableau dames","datePublished":"2020-09-08T03:10:13+00:00","dateModified":"2020-09-12T22:14:13+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/us-open-2020-le-tableau-dames\/"},"wordCount":683,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/us-open-2020-le-tableau-dames\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/08\/c_NaomiCincyServe.jpg","keywords":["Flushing Meadows","simple dames US Open","US Open","wta"],"articleSection":["Tennis"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/us-open-2020-le-tableau-dames\/#respond"]}],"copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/us-open-2020-le-tableau-dames\/","url":"https:\/\/dicodusport.fr\/blog\/us-open-2020-le-tableau-dames\/","name":"US Open 2020 : le tableau dames","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/us-open-2020-le-tableau-dames\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/us-open-2020-le-tableau-dames\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/08\/c_NaomiCincyServe.jpg","datePublished":"2020-09-08T03:10:13+00:00","dateModified":"2020-09-12T22:14:13+00:00","description":"La particuli\u00e8re 140e \u00e9dition du tournoi de l\u2019US Open 2020 se d\u00e9roulera du 31 ao\u00fbt au 13 septembre. Qui succ\u00e9dera \u00e0 Bianca Andreescu ?","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/us-open-2020-le-tableau-dames\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/us-open-2020-le-tableau-dames\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/us-open-2020-le-tableau-dames\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/08\/c_NaomiCincyServe.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/08\/c_NaomiCincyServe.jpg","width":800,"height":440},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/us-open-2020-le-tableau-dames\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"US Open 2020 : le tableau dames"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cce96fa88785bd8573e3d43078ac8c79","name":"Arlette Yeye","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/dca4a6239e6d708e46c45d60e160de6c?s=96&d=wp_user_avatar&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/dca4a6239e6d708e46c45d60e160de6c?s=96&d=wp_user_avatar&r=g","caption":"Arlette Yeye"},"description":"Journaliste\/r\u00e9dactrice depuis septembre 2015 - Supportrice de Chelsea, j'ai pour sports de pr\u00e9dilection le handball, l'athl\u00e9tisme et le tennis. Si je tweete plus vite que mon ombre, vous pouvez aussi me retrouver les week-ends sur les playgrounds de Bruxelles pour un petit foot ou basket entre potes. Parcourir la France, l'Europe et plus si affinit\u00e9s pour suivre mes sportifs pr\u00e9f\u00e9r\u00e9s ? Mon kif ! Et c'est avec plaisir que je partage les r\u00e9sultats des sports populaires mais \u00e9galement plus confidentiels pour Dicodusport.","sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/Shiclette94"],"url":"https:\/\/dicodusport.fr\/blog\/author\/arlette\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/75887","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=75887"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/75887\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/75889"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=75887"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=75887"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=75887"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}