{"id":78742,"date":"2020-09-18T08:48:21","date_gmt":"2020-09-18T06:48:21","guid":{"rendered":"http:\/\/dicodusport.fr\/blog\/?p=78742&#038;preview=true&#038;preview_id=78742"},"modified":"2020-09-18T08:57:17","modified_gmt":"2020-09-18T06:57:17","slug":"objectif-atteint-pour-la-motion-de-censure-au-fc-barcelone","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/objectif-atteint-pour-la-motion-de-censure-au-fc-barcelone\/","title":{"rendered":"Objectif atteint pour la motion de censure au FC Barcelone"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>FOOTBALL &#8211; Port\u00e9e par Jordi Farr\u00e9, socio, entrepreneur catalan et candidat aux prochaines \u00e9lections \u00e0 la pr\u00e9sidentielle du FC Barcelona, la motion de censure a recueilli 20731 signatures, un record dans l&rsquo;histoire du club.<br \/>\n<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">D\u00e9pos\u00e9e il y \u00e0 14 jours, la motion de censure devait atteindre aujourd&rsquo;hui le nombre de 16521 signatures pour \u00eatre recevable. Avec un tel r\u00e9sultat, et plus de 20000 signatures, la motion a \u00e9tabli un record dans l&rsquo;histoire du club catalan et ouvre d\u00e9sormais la voie \u00e0 une destitution du pr\u00e9sident <strong>Bartomeu<\/strong> et son \u00e9quipe, et permet d&rsquo;avancer les nouvelles \u00e9lections. Largement rejet\u00e9e, l&rsquo;\u00e9quipe en place n&rsquo;a pas arrang\u00e9 son cas avec l&rsquo;humiliation subie en Champions League et la gestion des vell\u00e9it\u00e9s de d\u00e9part de la star <strong>Lionel Messi<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Le club, qui a accus\u00e9 r\u00e9ception de la motion, vient d&rsquo;activer l&rsquo;article 55.4. Le club a d\u00e9sormais 10 jours pour constituer un groupe de travail constitu\u00e9 de 2 membres de la direction actuelle, des 2 premiers signataires de la motion et d&rsquo;un repr\u00e9sentant de la f\u00e9d\u00e9ration catalane de football. Une fois constitu\u00e9, cet organe devra v\u00e9rifier que la demande correspond aux r\u00e8gles auxquelles elle est soumise et, sp\u00e9cialement, qu&rsquo;elle a obtenu le nombre suffisant de vote de socios. La Table pourra invalider les supports qui ne sont pas assez document\u00e9s et r\u00e9aliser des contr\u00f4les afin de v\u00e9rifier leur authenticit\u00e9.<\/p>\n<h2 style=\"text-align: justify;\">Et ensuite ?<\/h2>\n<p style=\"text-align: justify;\">Si tout ce qui est demand\u00e9 est correct, la demande sera accept\u00e9e et il sera demand\u00e9 au Comit\u00e9 de Direction de convoquer, dans un d\u00e9lai allant de dix \u00e0 vingt jours, des \u00e9lections. Si elle n&rsquo;est pas accept\u00e9e, le vote de censure sera refus\u00e9. Une fois accept\u00e9e, le club doit organiser un r\u00e9f\u00e9rendum afin de demander aux socios la tenue de nouvelles \u00e9lections.<\/p>\n<p style=\"text-align: justify;\">Le pr\u00e9sident <strong>Bartomeu<\/strong> peut d&rsquo;ores et d\u00e9j\u00e0 d\u00e9missionner et laisser place imm\u00e9diatement \u00e0 des \u00e9lections anticip\u00e9es. <strong>Jordi Farr\u00e9<\/strong> s&rsquo;est dit d&rsquo;ailleurs plut\u00f4t confiant \u00e0 ce sujet. Mais il est fort probable que le pr\u00e9sident en place s&rsquo;accroche, les divers faits ces derniers mois ne l&rsquo;ont pas fait vaciller et il pourrait m\u00eame affronter les autres pr\u00e9tendants pour, pourquoi pas, \u00eatre confort\u00e9 \u00e0 son poste.<\/p>\n<p style=\"text-align: justify;\">Ses adversaires sont aujourd&rsquo;hui <strong>Jordi Farr\u00e9<\/strong> et <strong>Victor Font<\/strong>, candidats d\u00e9clar\u00e9s \u00e0 la pr\u00e9sidence, mais un maintien des deux hommes au scrutin pourrait compliquer le vote et certains pourraient m\u00eame revenir sur le devant de la sc\u00e8ne, comme l&rsquo;ancien pr\u00e9sident <strong>Joan Laporta<\/strong>. Alors que <a href=\"https:\/\/dicodusport.fr\/blog\/lionel-messi-reste-finalement-au-barca\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Messi<\/strong> s&rsquo;est r\u00e9solu \u00e0 rester au Bar\u00e7a<\/a> et que la pr\u00e9-saison bat son plein, la situation du club est loin d&rsquo;\u00eatre stabilis\u00e9e, et promet d&rsquo;\u00eatre intense en ce d\u00e9but de saison.<strong><em><br \/>\n<\/em><\/strong><\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"ca\">&#x1f4aa; POD\u00cdEM&#x2757;<br \/>\n&#x1f525; VOL\u00cdEM&#x2757;<br \/>\n&#x2705; HO HEM FET&#x2757;<\/p>\n<p>&#x1f6a8; 20.731 SIGNATURES &#x1f6a8;<\/p>\n<p>GR\u00c0CIES VOLUNTARIS!<br \/>\nGR\u00c0CIES SOCIS I S\u00d2CIES!<br \/>\nG-R-\u00c0-C-I-E-S!<a href=\"https:\/\/twitter.com\/hashtag\/MesQueUnaMocio?src=hash&amp;ref_src=twsrc%5Etfw\">#MesQueUnaMocio<\/a>, una oportunitat per tornar a ser M\u00e9s que un Club <a href=\"https:\/\/t.co\/r2MkUSH5iT\">pic.twitter.com\/r2MkUSH5iT<\/a><\/p>\n<p>\u2014 Plataforma M\u00e9s que una Moci\u00f3 (@MesQueUnaMocio) <a href=\"https:\/\/twitter.com\/MesQueUnaMocio\/status\/1306622431046569986?ref_src=twsrc%5Etfw\">September 17, 2020<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p><strong><em>Dicodusport<br \/>\n<a href=\"https:\/\/www.facebook.com\/dicodusport\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2909\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-facebook-150x150.png\" alt=\"\" width=\"40\" height=\"40\" \/><\/a><a href=\"https:\/\/twitter.com\/dicodusport\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2908\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-twitter-150x150.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>FOOTBALL &#8211; Port\u00e9e par Jordi Farr\u00e9, socio, entrepreneur catalan et candidat aux prochaines \u00e9lections \u00e0 la pr\u00e9sidentielle du FC Barcelona, la motion de censure a recueilli 20731 signatures, un record dans l&rsquo;histoire du club.<\/p>\n","protected":false},"author":1,"featured_media":78749,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[2301],"tags":[912,2101,4203,75],"class_list":["post-78742","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-football","tag-barca","tag-barcelone","tag-fc-barcelone","tag-football"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Objectif atteint pour la motion de censure au FC Barcelone<\/title>\n<meta name=\"description\" content=\"FOOTBALL - Port\u00e9e par Jordi Farr\u00e9, socio, entrepreneur catalan et candidat aux prochaines \u00e9lections \u00e0 la pr\u00e9sidentielle du FC Barcelona, la motion de censure a recueilli 20731 signatures, un record dans l&#039;histoire du club.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/objectif-atteint-pour-la-motion-de-censure-au-fc-barcelone\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Objectif atteint pour la motion de censure au FC Barcelone\" \/>\n<meta property=\"og:description\" content=\"FOOTBALL - Port\u00e9e par Jordi Farr\u00e9, socio, entrepreneur catalan et candidat aux prochaines \u00e9lections \u00e0 la pr\u00e9sidentielle du FC Barcelona, la motion de censure a recueilli 20731 signatures, un record dans l&#039;histoire du club.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/objectif-atteint-pour-la-motion-de-censure-au-fc-barcelone\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-18T06:48:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-09-18T06:57:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/09\/Josep-Maria-Bartomeu.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicolas Jacquemard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Objectif atteint pour la motion de censure au FC Barcelone\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Nico_Jacquemard\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/objectif-atteint-pour-la-motion-de-censure-au-fc-barcelone\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/objectif-atteint-pour-la-motion-de-censure-au-fc-barcelone\/\"},\"author\":{\"name\":\"Nicolas Jacquemard\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\"},\"headline\":\"Objectif atteint pour la motion de censure au FC Barcelone\",\"datePublished\":\"2020-09-18T06:48:21+00:00\",\"dateModified\":\"2020-09-18T06:57:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/objectif-atteint-pour-la-motion-de-censure-au-fc-barcelone\/\"},\"wordCount\":551,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/objectif-atteint-pour-la-motion-de-censure-au-fc-barcelone\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/09\/Josep-Maria-Bartomeu.png\",\"keywords\":[\"bar\u00e7a\",\"barcelone\",\"FC Barcelone\",\"Football\"],\"articleSection\":[\"Football\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/objectif-atteint-pour-la-motion-de-censure-au-fc-barcelone\/#respond\"]}],\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/objectif-atteint-pour-la-motion-de-censure-au-fc-barcelone\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/objectif-atteint-pour-la-motion-de-censure-au-fc-barcelone\/\",\"name\":\"Objectif atteint pour la motion de censure au FC Barcelone\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/objectif-atteint-pour-la-motion-de-censure-au-fc-barcelone\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/objectif-atteint-pour-la-motion-de-censure-au-fc-barcelone\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/09\/Josep-Maria-Bartomeu.png\",\"datePublished\":\"2020-09-18T06:48:21+00:00\",\"dateModified\":\"2020-09-18T06:57:17+00:00\",\"description\":\"FOOTBALL - Port\u00e9e par Jordi Farr\u00e9, socio, entrepreneur catalan et candidat aux prochaines \u00e9lections \u00e0 la pr\u00e9sidentielle du FC Barcelona, la motion de censure a recueilli 20731 signatures, un record dans l'histoire du club.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/objectif-atteint-pour-la-motion-de-censure-au-fc-barcelone\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/objectif-atteint-pour-la-motion-de-censure-au-fc-barcelone\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/objectif-atteint-pour-la-motion-de-censure-au-fc-barcelone\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/09\/Josep-Maria-Bartomeu.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/09\/Josep-Maria-Bartomeu.png\",\"width\":800,\"height\":445,\"caption\":\"Objectif atteint pour la motion de censure au FC Barcelone\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/objectif-atteint-pour-la-motion-de-censure-au-fc-barcelone\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Objectif atteint pour la motion de censure au FC Barcelone\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\",\"name\":\"Nicolas Jacquemard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"caption\":\"Nicolas Jacquemard\"},\"description\":\"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.\",\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Objectif atteint pour la motion de censure au FC Barcelone","description":"FOOTBALL - Port\u00e9e par Jordi Farr\u00e9, socio, entrepreneur catalan et candidat aux prochaines \u00e9lections \u00e0 la pr\u00e9sidentielle du FC Barcelona, la motion de censure a recueilli 20731 signatures, un record dans l'histoire du club.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/objectif-atteint-pour-la-motion-de-censure-au-fc-barcelone\/","og_locale":"fr_FR","og_type":"article","og_title":"Objectif atteint pour la motion de censure au FC Barcelone","og_description":"FOOTBALL - Port\u00e9e par Jordi Farr\u00e9, socio, entrepreneur catalan et candidat aux prochaines \u00e9lections \u00e0 la pr\u00e9sidentielle du FC Barcelona, la motion de censure a recueilli 20731 signatures, un record dans l'histoire du club.","og_url":"https:\/\/dicodusport.fr\/blog\/objectif-atteint-pour-la-motion-de-censure-au-fc-barcelone\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2020-09-18T06:48:21+00:00","article_modified_time":"2020-09-18T06:57:17+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/09\/Josep-Maria-Bartomeu.png","type":"image\/png"}],"author":"Nicolas Jacquemard","twitter_card":"summary_large_image","twitter_title":"Objectif atteint pour la motion de censure au FC Barcelone","twitter_creator":"@https:\/\/twitter.com\/Nico_Jacquemard","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/objectif-atteint-pour-la-motion-de-censure-au-fc-barcelone\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/objectif-atteint-pour-la-motion-de-censure-au-fc-barcelone\/"},"author":{"name":"Nicolas Jacquemard","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191"},"headline":"Objectif atteint pour la motion de censure au FC Barcelone","datePublished":"2020-09-18T06:48:21+00:00","dateModified":"2020-09-18T06:57:17+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/objectif-atteint-pour-la-motion-de-censure-au-fc-barcelone\/"},"wordCount":551,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/objectif-atteint-pour-la-motion-de-censure-au-fc-barcelone\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/09\/Josep-Maria-Bartomeu.png","keywords":["bar\u00e7a","barcelone","FC Barcelone","Football"],"articleSection":["Football"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/objectif-atteint-pour-la-motion-de-censure-au-fc-barcelone\/#respond"]}],"copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/objectif-atteint-pour-la-motion-de-censure-au-fc-barcelone\/","url":"https:\/\/dicodusport.fr\/blog\/objectif-atteint-pour-la-motion-de-censure-au-fc-barcelone\/","name":"Objectif atteint pour la motion de censure au FC Barcelone","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/objectif-atteint-pour-la-motion-de-censure-au-fc-barcelone\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/objectif-atteint-pour-la-motion-de-censure-au-fc-barcelone\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/09\/Josep-Maria-Bartomeu.png","datePublished":"2020-09-18T06:48:21+00:00","dateModified":"2020-09-18T06:57:17+00:00","description":"FOOTBALL - Port\u00e9e par Jordi Farr\u00e9, socio, entrepreneur catalan et candidat aux prochaines \u00e9lections \u00e0 la pr\u00e9sidentielle du FC Barcelona, la motion de censure a recueilli 20731 signatures, un record dans l'histoire du club.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/objectif-atteint-pour-la-motion-de-censure-au-fc-barcelone\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/objectif-atteint-pour-la-motion-de-censure-au-fc-barcelone\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/objectif-atteint-pour-la-motion-de-censure-au-fc-barcelone\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/09\/Josep-Maria-Bartomeu.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/09\/Josep-Maria-Bartomeu.png","width":800,"height":445,"caption":"Objectif atteint pour la motion de censure au FC Barcelone"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/objectif-atteint-pour-la-motion-de-censure-au-fc-barcelone\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Objectif atteint pour la motion de censure au FC Barcelone"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191","name":"Nicolas Jacquemard","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","caption":"Nicolas Jacquemard"},"description":"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.","sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard"],"url":"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/78742","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=78742"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/78742\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/78749"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=78742"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=78742"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=78742"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}