{"id":80461,"date":"2020-09-30T21:10:05","date_gmt":"2020-09-30T19:10:05","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=80461&#038;preview=true&#038;preview_id=80461"},"modified":"2020-10-01T07:49:23","modified_gmt":"2020-10-01T05:49:23","slug":"roland-garros-2020-le-programme-des-matchs-du-jeudi-1er-octobre","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/roland-garros-2020-le-programme-des-matchs-du-jeudi-1er-octobre\/","title":{"rendered":"Roland-Garros 2020 : le programme des matchs du Jeudi 1er octobre"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><b><a href=\"https:\/\/dicodusport.fr\/blog\/actualites\/tennis\/roland-garros-2020\/\" target=\"_blank\" rel=\"noopener noreferrer\">ROLAND-GARROS 2020<\/a> &#8211; Roland-Garros a d\u00e9marr\u00e9 dimanche pour deux semaines de comp\u00e9tition \u00e0 une p\u00e9riode inhabituelle. Voici le programme des matchs de simple du jeudi 1er octobre.\u00a0<\/b><\/em><\/p>\n<h2 style=\"text-align: justify;\">Court Philippe-Chatrier (D\u00e8s 11 h)<\/h2>\n<p style=\"text-align: justify;\">Jelena Ostapenko (LET) &#8211; Karolina Pliskova (RTC\/n\u00b0 2)<br \/>\nAna Bogdan (Rou) &#8211; Sofia Kenin (USA\/n\u00b0 4)<br \/>\nNovak Djokovic (SER\/n\u00b0 1) &#8211; Ricardas Berankis (LIT)<br \/>\nPablo Cuevas (URU) &#8211; Stefanos Tsisipas (GRE\/n\u00b0 5)<\/p>\n<h2 style=\"text-align: justify;\">Court Suzanne-Lenglen (D\u00e8s 11 h)<\/h2>\n<p style=\"text-align: justify;\">Denis Shapovalov (CAN\/n\u00b0 9) &#8211; Roberto Carballes Baena (ESP)<br \/>\nKristyna Pliskova (RTC) &#8211; Garbine Muguruza (ESP\/n\u00b0 11)<br \/>\nLloyd Harris (AFS) &#8211; Matteo Berrettini (ITA\/n\u00b0 7)<br \/>\nElena Rybakina (KAZ\/n\u00b0 14) &#8211; <strong>Fiona Ferro (FRA)<\/strong><\/p>\n<h2 style=\"text-align: justify;\">Court Simonne-Mathieu (D\u00e8s 11 h)<\/h2>\n<p style=\"text-align: justify;\">Petra Kvitova (RTC\/n\u00b0 7) &#8211; Jasmine Paolini (ITA)<br \/>\nAndrej Martin (SVQ) &#8211; Grigor Dimitrov (BUL\/n\u00b0 18)<br \/>\n<strong>Aliz\u00e9 Cornet (FRA)<\/strong> &#8211; Shuai Zhang (CHN)<br \/>\nAlejandro Davidovich Fokina (ESP) &#8211; Andrey Rublev (RUS\/n\u00b0 13)<\/p>\n<h2 style=\"text-align: justify;\">Court n\u00b04 (D\u00e8s 11 h)<\/h2>\n<p style=\"text-align: justify;\">Marcos Giron (USA) &#8211; Thiago Monteiro (BRE)<br \/>\nPatricia Maria Tig (ROU) &#8211; Christina McHale (USA)<\/p>\n<h2 style=\"text-align: justify;\">Court n\u00b05<\/h2>\n<p style=\"text-align: justify;\">Polona Hercog (SVN) &#8211; Leylah Annie Fernandez (CAN)<br \/>\nIrina Maria Bara (ROU) &#8211; Alison Van Uytvanck (BEL)<\/p>\n<h2 style=\"text-align: justify;\">Court n\u00b07 (D\u00e8s 11 h)<\/h2>\n<p style=\"text-align: justify;\">Clara Tauson (DAN) &#8211; Danielle Collins (USA)<br \/>\nAryna Sabalenka (BLR\/n\u00b0 8) &#8211; Daria Kasatkina (RUS)<br \/>\nGuido Pella (ARG) &#8211; Pablo Carre\u00f1o Busta (ESP\/n\u00b0 17)<\/p>\n<h2 style=\"text-align: justify;\">Court n\u00b09 (D\u00e8s 11 h)<\/h2>\n<p style=\"text-align: justify;\">Cristian Garin (CHI\/n\u00b0 20) &#8211; Marc Polmans (AUS)<br \/>\nNao Hibino (JAP) &#8211; Ons Jabeur (TUN\/n\u00b0 30)<\/p>\n<h2 style=\"text-align: justify;\">Court n\u00b010<\/h2>\n<p style=\"text-align: justify;\">Nikola Milojevic (SER) &#8211; Aljaz Bedene (SVN)<\/p>\n<h2 style=\"text-align: justify;\">Court n\u00b011<\/h2>\n<p style=\"text-align: justify;\">Tennys Sandgren (USA) &#8211; Daniel Galan (COL)<\/p>\n<h2 style=\"text-align: justify;\">Court n\u00b012 (D\u00e8s 11 h)<\/h2>\n<p style=\"text-align: justify;\">Marton Fucsovics (HON) &#8211; Albert Ramos-Vinolas (ESP)<br \/>\nSloane Stephens (USA\/n\u00b0 29) &#8211; Paula Badosa (ESP)<br \/>\nPetra Martic (CRO\/n\u00b0 13) &#8211; Veronika Kudermetova (RUS)<\/p>\n<h2 style=\"text-align: justify;\">Court n\u00b013<\/h2>\n<p style=\"text-align: justify;\">Jan-Lennard Struff (ALL\/n\u00b0 30) &#8211; Daniel Altmaier (ALL)<br \/>\nLaura Siegemund (ALL) &#8211; Julia Goerges (ALL)<\/p>\n<h2 style=\"text-align: justify;\">Court n\u00b014 (D\u00e8s 11 h)<\/h2>\n<p style=\"text-align: justify;\">Jiri Vesely ( CZE) &#8211; Karen Khachanov (RUS\/n\u00b0 15)<br \/>\nKaja Juvan (SLO) &#8211; <strong>Clara Burel (FRA)<\/strong><br \/>\nRoberto Bautista Agut (ESP\/n\u00b0 10) &#8211; Attila Balazs (HON)<\/p>\n<p style=\"text-align: justify;\"><strong><em>Dicodusport<br \/>\n<a href=\"https:\/\/www.facebook.com\/dicodusport\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2909\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-facebook-150x150.png\" alt=\"\" width=\"40\" height=\"40\" \/><\/a><a href=\"https:\/\/twitter.com\/dicodusport\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2908\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-twitter-150x150.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>ROLAND-GARROS 2020 &#8211; Roland-Garros a d\u00e9marr\u00e9 dimanche pour deux semaines de comp\u00e9tition \u00e0 une p\u00e9riode inhabituelle. Voici le programme des matchs de simple du jeudi 1er octobre.\u00a0<\/p>\n","protected":false},"author":1,"featured_media":80308,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[47090],"tags":[159],"class_list":["post-80461","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-roland-garros","tag-roland-garros"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Roland-Garros 2020 : le programme des matchs du Jeudi 1er octobre<\/title>\n<meta name=\"description\" content=\"ROLAND-GARROS 2020 - Roland-Garros a d\u00e9marr\u00e9 dimanche pour deux semaines de comp\u00e9tition. Voici le programme des matchs du jeudi 1er octobre.\u00a0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/roland-garros-2020-le-programme-des-matchs-du-jeudi-1er-octobre\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Roland-Garros 2020 : le programme des matchs du Jeudi 1er octobre\" \/>\n<meta property=\"og:description\" content=\"ROLAND-GARROS 2020 - Roland-Garros a d\u00e9marr\u00e9 dimanche pour deux semaines de comp\u00e9tition. Voici le programme des matchs du jeudi 1er octobre.\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/roland-garros-2020-le-programme-des-matchs-du-jeudi-1er-octobre\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-30T19:10:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-10-01T05:49:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/09\/Programme-Roland-Garros-1-octobre.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"670\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicolas Jacquemard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Roland-Garros 2020 : le programme des matchs du Jeudi 1er octobre\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Nico_Jacquemard\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/roland-garros-2020-le-programme-des-matchs-du-jeudi-1er-octobre\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/roland-garros-2020-le-programme-des-matchs-du-jeudi-1er-octobre\\\/\"},\"author\":{\"name\":\"Nicolas Jacquemard\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/55dcb50ad410894e431ed812bbb70191\"},\"headline\":\"Roland-Garros 2020 : le programme des matchs du Jeudi 1er octobre\",\"datePublished\":\"2020-09-30T19:10:05+00:00\",\"dateModified\":\"2020-10-01T05:49:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/roland-garros-2020-le-programme-des-matchs-du-jeudi-1er-octobre\\\/\"},\"wordCount\":332,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/roland-garros-2020-le-programme-des-matchs-du-jeudi-1er-octobre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/Programme-Roland-Garros-1-octobre.png\",\"keywords\":[\"Roland-Garros\"],\"articleSection\":[\"Roland-Garros\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/roland-garros-2020-le-programme-des-matchs-du-jeudi-1er-octobre\\\/#respond\"]}],\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/roland-garros-2020-le-programme-des-matchs-du-jeudi-1er-octobre\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/roland-garros-2020-le-programme-des-matchs-du-jeudi-1er-octobre\\\/\",\"name\":\"Roland-Garros 2020 : le programme des matchs du Jeudi 1er octobre\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/roland-garros-2020-le-programme-des-matchs-du-jeudi-1er-octobre\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/roland-garros-2020-le-programme-des-matchs-du-jeudi-1er-octobre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/Programme-Roland-Garros-1-octobre.png\",\"datePublished\":\"2020-09-30T19:10:05+00:00\",\"dateModified\":\"2020-10-01T05:49:23+00:00\",\"description\":\"ROLAND-GARROS 2020 - Roland-Garros a d\u00e9marr\u00e9 dimanche pour deux semaines de comp\u00e9tition. Voici le programme des matchs du jeudi 1er octobre.\u00a0\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/roland-garros-2020-le-programme-des-matchs-du-jeudi-1er-octobre\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/roland-garros-2020-le-programme-des-matchs-du-jeudi-1er-octobre\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/roland-garros-2020-le-programme-des-matchs-du-jeudi-1er-octobre\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/Programme-Roland-Garros-1-octobre.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/Programme-Roland-Garros-1-octobre.png\",\"width\":1200,\"height\":670},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/roland-garros-2020-le-programme-des-matchs-du-jeudi-1er-octobre\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Roland-Garros 2020 : le programme des matchs du Jeudi 1er octobre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/55dcb50ad410894e431ed812bbb70191\",\"name\":\"Nicolas Jacquemard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"caption\":\"Nicolas Jacquemard\"},\"description\":\"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/Nico_Jacquemard\"],\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/dicodusport\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Roland-Garros 2020 : le programme des matchs du Jeudi 1er octobre","description":"ROLAND-GARROS 2020 - Roland-Garros a d\u00e9marr\u00e9 dimanche pour deux semaines de comp\u00e9tition. Voici le programme des matchs du jeudi 1er octobre.\u00a0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/roland-garros-2020-le-programme-des-matchs-du-jeudi-1er-octobre\/","og_locale":"fr_FR","og_type":"article","og_title":"Roland-Garros 2020 : le programme des matchs du Jeudi 1er octobre","og_description":"ROLAND-GARROS 2020 - Roland-Garros a d\u00e9marr\u00e9 dimanche pour deux semaines de comp\u00e9tition. Voici le programme des matchs du jeudi 1er octobre.\u00a0","og_url":"https:\/\/dicodusport.fr\/blog\/roland-garros-2020-le-programme-des-matchs-du-jeudi-1er-octobre\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2020-09-30T19:10:05+00:00","article_modified_time":"2020-10-01T05:49:23+00:00","og_image":[{"width":1200,"height":670,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/09\/Programme-Roland-Garros-1-octobre.png","type":"image\/png"}],"author":"Nicolas Jacquemard","twitter_card":"summary_large_image","twitter_title":"Roland-Garros 2020 : le programme des matchs du Jeudi 1er octobre","twitter_creator":"@https:\/\/twitter.com\/Nico_Jacquemard","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/roland-garros-2020-le-programme-des-matchs-du-jeudi-1er-octobre\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/roland-garros-2020-le-programme-des-matchs-du-jeudi-1er-octobre\/"},"author":{"name":"Nicolas Jacquemard","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191"},"headline":"Roland-Garros 2020 : le programme des matchs du Jeudi 1er octobre","datePublished":"2020-09-30T19:10:05+00:00","dateModified":"2020-10-01T05:49:23+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/roland-garros-2020-le-programme-des-matchs-du-jeudi-1er-octobre\/"},"wordCount":332,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/roland-garros-2020-le-programme-des-matchs-du-jeudi-1er-octobre\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/09\/Programme-Roland-Garros-1-octobre.png","keywords":["Roland-Garros"],"articleSection":["Roland-Garros"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/roland-garros-2020-le-programme-des-matchs-du-jeudi-1er-octobre\/#respond"]}],"copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/roland-garros-2020-le-programme-des-matchs-du-jeudi-1er-octobre\/","url":"https:\/\/dicodusport.fr\/blog\/roland-garros-2020-le-programme-des-matchs-du-jeudi-1er-octobre\/","name":"Roland-Garros 2020 : le programme des matchs du Jeudi 1er octobre","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/roland-garros-2020-le-programme-des-matchs-du-jeudi-1er-octobre\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/roland-garros-2020-le-programme-des-matchs-du-jeudi-1er-octobre\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/09\/Programme-Roland-Garros-1-octobre.png","datePublished":"2020-09-30T19:10:05+00:00","dateModified":"2020-10-01T05:49:23+00:00","description":"ROLAND-GARROS 2020 - Roland-Garros a d\u00e9marr\u00e9 dimanche pour deux semaines de comp\u00e9tition. Voici le programme des matchs du jeudi 1er octobre.\u00a0","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/roland-garros-2020-le-programme-des-matchs-du-jeudi-1er-octobre\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/roland-garros-2020-le-programme-des-matchs-du-jeudi-1er-octobre\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/roland-garros-2020-le-programme-des-matchs-du-jeudi-1er-octobre\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/09\/Programme-Roland-Garros-1-octobre.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/09\/Programme-Roland-Garros-1-octobre.png","width":1200,"height":670},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/roland-garros-2020-le-programme-des-matchs-du-jeudi-1er-octobre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Roland-Garros 2020 : le programme des matchs du Jeudi 1er octobre"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191","name":"Nicolas Jacquemard","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","caption":"Nicolas Jacquemard"},"description":"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.","sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard"],"url":"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/80461","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=80461"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/80461\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/80308"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=80461"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=80461"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=80461"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}